{"id":77431,"date":"2017-08-16T16:52:39","date_gmt":"2017-08-16T16:52:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/16\/charlottesville-en-france\/"},"modified":"2017-08-16T16:52:39","modified_gmt":"2017-08-16T16:52:39","slug":"charlottesville-en-france","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/16\/charlottesville-en-france\/","title":{"rendered":"Charlottesville-en-France"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Charlottesville-en-France<\/h2>\n<\/p>\n<p><p>16 ao&ucirc;t 2017 &ndash; Tout d&rsquo;abord, il ne faut pas s&rsquo;y tromper : le nom Charlottesville n&rsquo;a rien de fran\u00e7ais, sinon du mot \u00ab\u00a0ville\u00a0\u00bb qui lui est donn\u00e9 en r\u00e9f\u00e9rence \u00e0 la ma&icirc;trise internationale de la langue fran\u00e7aise au XVIII\u00e8me si\u00e8cle. Ce nom fut donn\u00e9 \u00e0 <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Charlottesville\">cette petite ville<\/a> (43.000 habitants aujourd&rsquo;hui) fond\u00e9e en 1762, en l&rsquo;honneur de la femme du roi George III, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Charlotte_de_Mecklembourg-Strelitz\">Sophie-Charlotte<\/a> de Mecklembourg-Strelitz venue d&rsquo;une des multitudes de principaut\u00e9s et de royaumes de l&rsquo;ancien saint-Empire et du futur <em>Reich<\/em> ; ainsi reine d&rsquo;Angleterre de 1761 \u00e0 1818, grand caract\u00e8re d&rsquo;une tr\u00e8s-grande amie des arts (\u00e9l\u00e8ve de Bach, admir\u00e9e par Mozart), remarquable botaniste, favorisant l&rsquo;\u00e9ducation avanc\u00e9e des femmes dont celle de ses filles, pesant d&rsquo;un poids politique grandissant \u00e0 mesure que son mari sombrait dans la maladie (sans doute une maniaco-d\u00e9pression s\u00e9v\u00e8re).<\/p>\n<\/p>\n<p><p>Tout cela para&icirc;trait idyllique au premier abord, de m\u00eame que la ville dont la petitesse rend d&rsquo;autant plus attachant l&rsquo;int\u00e9r\u00eat qu&rsquo;elle a toujours port\u00e9 \u00e0 la culture, notamment sous l&rsquo;impulsion de Jefferson au d\u00e9part. Tout cela n&rsquo;est pas idyllique et s&rsquo;efface devant les \u00e9v\u00e9nements de vendredi et de samedi, non qu&rsquo;ils soient dramatiques et exceptionnellement sanglants, mais parce que je crois <strong>qu&rsquo;on doit les juger si significativement exemplaires de leur temps<\/strong>. Je ne m&rsquo;attache ici qu&rsquo;\u00e0 un seul aspect, path\u00e9tique, catastrophique, qui est la mise en \u00e9vidence d&rsquo;un fait central, une fois de plus mais cette fois de fa\u00e7on tr\u00e8s spectaculaire, <strong>je dirais symboliquement tr\u00e8s \u00e9clairante avec les r\u00e9f\u00e9rences \u00e0 l&rsquo;histoire des USA<\/strong> comme on le voit dans l&rsquo;un des deux textes de <em>The Federalist <\/em>adjoints \u00e0 l&rsquo;<em>Ouverture Libre<\/em> de ce <a href=\"http:\/\/www.dedefensa.org\/article\/nouvelles-de-charlottesville\">15 ao&ucirc;t 2017<\/a>.<\/p>\n<\/p>\n<p><p>(Je veux dire par l\u00e0 qu&rsquo;\u00e0 lire ce texte, effectivement, appara&icirc;t d&rsquo;un pur point de vue intellectuel et culturel l&rsquo;acte par des violences obsc\u00e8nes de haine et d&rsquo;hyst\u00e9rie de la profanation directe ou symbolique de deux des plus grandes figures de l&rsquo;histoire des USA, qui contrastent avec la foule d&rsquo;inf\u00e2me crapules et de corrompus notoires dont elle est peupl\u00e9e. Je veux parler, on s&rsquo;en doute je l&rsquo;esp\u00e8re, de Thomas Jefferson et du <a href=\"http:\/\/www.dedefensa.org\/article\/la-liquidation-de-robert-e-lee\">G\u00e9n\u00e9ral Robert E. Lee<\/a>.)<\/p>\n<\/p>\n<p><p>Ce \u00ab\u00a0seul aspect, path\u00e9tique, catastrophique\u00a0\u00bb qui m&rsquo;importe ici, c&rsquo;est une \u00e9clatante confirmation par les symboles les plus hauts et les violences les plus basses, salu\u00e9s par la corruption des psychologies et la soumission au simulacre du Syst\u00e8me de la plupart des commentateurs ; confirmation de l&rsquo;ignominie que constitue <strong>la trahison de la gauche dissidente US par rapport au devoir imp\u00e9ratif que lui impose la situation pr\u00e9sente, c&rsquo;est-\u00e0-dire la lutte contre la Grande Crise G\u00e9n\u00e9rale d&rsquo;effondrement du Syst\u00e8me<\/strong>. La chose est rapidement mais clairement mise en \u00e9vidente par Denise C. McAllister, dans l&rsquo;un des deux textes du <em>Federalist<\/em> cit\u00e9s. Reprenant l&rsquo;historique de l&rsquo;<em>Antifa<\/em> aux USA, McAllister note :<\/p>\n<\/p>\n<p><p>&laquo; <em>Dans les ann\u00e9es 2000, sur l&rsquo;internet qui encourageait le dialogue transatlantique, quelques activistes am\u00e9ricains adopt\u00e8rent l&rsquo;\u00e9tiquettes d&rsquo;Antifa<\/em> [anti-fascistes]. <em>Mais m\u00eame du c\u00f4t\u00e9 de la gauche militante, le mouvement \u00ab\u00a0Antifa\u00a0\u00bb \u00e9tait rel\u00e9gu\u00e9 \u00e0 l&rsquo;arri\u00e8re-plan. Pour beaucoup d&rsquo;activistes de gauche durant les ann\u00e9es Clinton, Bush et Obama, <strong>le capitalisme global d\u00e9r\u00e9gul\u00e9 semblait un danger bien plus grand que le fascisme.<\/strong><\/em>.. &raquo; Dans un autre texte (du <a href=\"http:\/\/thefederalist.com\/2017\/08\/09\/anti-trumpers-need-fire-real-enemy-instead-conservatives\/\">9 ao&ucirc;t 2017<\/a>), la m\u00eame McAllister observe, se faisant critique du changement qui s&rsquo;est amorc\u00e9 en 2014-2015 (avec Trump), o&ugrave; une part importante de la \u00ab\u00a0gauche dissidente\u00a0\u00bb et antiSyst\u00e8me a rejoint l&rsquo;<em>Antifa<\/em> pour plonger dans l&rsquo;id\u00e9ologie de l&rsquo;ultragauche qui semble comme un de ces simulacres sans tain fascinant les esprits en tranquillisant les consciences ; on remarque l&rsquo;usage du mot \u00ab\u00a0d\u00e9construire\u00a0\u00bb&#8230; :<\/p>\n<\/p>\n<p><p>&laquo; <em>Le v\u00e9ritable danger est cette id\u00e9ologie du gauchisme<\/em> [notre ultragauche, rameutant le centre-gauche humaniste et droitdel&rsquo;hommiste, les libertaires-globalistes et les marxistes utopistes] <em>qui cherche \u00e0 <strong>d\u00e9construire<\/strong> notre nation et \u00e0 d\u00e9truire tout ce qui menace ses id\u00e9aux utopiques<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est une question des plus essentielles qui est ainsi r\u00e9sum\u00e9e, qui appara&icirc;t \u00e9galement d&rsquo;une fa\u00e7on tr\u00e8s significative en France, laquelle devrait se sentir concern\u00e9e par l&rsquo;attaque qui est faite contre le pass\u00e9 historique des USA parce qu&rsquo;elle-m\u00eame (la France) y a jou\u00e9 un r\u00f4le essentiel. J&rsquo;ai abord\u00e9 \u00e0 plusieurs reprises cette \u00ab\u00a0question essentielle\u00a0\u00bb \u00e0 propos d&rsquo;un personnage politique qui est \u00e0 lui seul la quintessence contradictoire de ce renversement dont parle McAllister. Il s&rsquo;agit de M\u00e9lenchon, dont on a l&rsquo;impression \u00e0 divers moments qu&rsquo;il est l&rsquo;homme politique fran\u00e7ais le plus apte \u00e0 comprendre l&rsquo;ampleur catastrophique de notre Grande Crise G\u00e9n\u00e9rale g\u00e9n\u00e9r\u00e9e par le Syst\u00e8me (en gros, &laquo; <em>le capitalisme global d\u00e9r\u00e9gul\u00e9 <\/em>&raquo; dont parle McAllister), et <strong>qui sombre d&rsquo;une fa\u00e7on absolument catastrophique le moment d&rsquo;apr\u00e8s dans la vitup\u00e9ration <em>Antifa<\/em>-\u00e0-la-fran\u00e7aise<\/strong>, sans le moindre souci de la contradiction, de l&rsquo;\u00e9norme indignit\u00e9 d&rsquo;ainsi gaspiller une vision lucide de la catastrophe dans un emprisonnement de l&rsquo;id\u00e9ologisation la plus basse, et \u00e9ventuellement avec la dose d&rsquo;hyst\u00e9rie qu&rsquo;il faut.<\/p>\n<\/p>\n<p><p>Il y a quinze ans, il y a dix ans, il y a presque cinq ans encore, tout ce qu&rsquo;il y avait de \u00ab\u00a0dissident\u00a0\u00bb antiSyst\u00e8me, de droite comme de gauche, &ndash; comme si ces \u00e9tiquettes pouvaient encore avoir un sens, se disait-on alors, &ndash; se retrouvaient contre la guerre en Irak, contre Wall Street et l&rsquo;UE \u00e0 l&rsquo;automne 2008, contre la relance de la guerre en Afghanistan, l&rsquo;assassinat par les drones et l&rsquo;omnipr\u00e9sente NSA lors de la premi\u00e8re moiti\u00e9 du r\u00e8gne de Sa-Saintet\u00e9 Obama. Parall\u00e8lement et sans que nous le v&icirc;mes venir d&rsquo;abord pour ce qu&rsquo;il \u00e9tait, un vent nouveau, produit remarquable de la modernit\u00e9 extr\u00eamement avanc\u00e9e des ann\u00e9es 1930, se leva \u00e0 propos d&rsquo;Assad, puis de l&rsquo;Ukraine (et de Poutine pour toutes les saisons et toutes les raisons), et enfin devint temp\u00eate folle avec le cas-Trump une fois que l&rsquo;escroc Hillary n&rsquo;eut trouv\u00e9 (il y a un an) rien d&rsquo;autre que les simulacres id\u00e9ologiques que l&rsquo;on agite aujourd&rsquo;hui, <em>Antifa <\/em>compris, pour grappiller quelques semaines de plus de l&rsquo;apparence de sa vertu politique. <strong>Leur \u00ab\u00a0dissidence\u00a0\u00bb antiSyst\u00e8me vola en \u00e9clats pour laisser place au \u00ab\u00a0combat contre le fascisme\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>En France, nous avons le m\u00eame sch\u00e9ma, &ndash; je veux dire pour le \u00ab\u00a0combat contre le fascisme\u00a0\u00bb, &ndash; mais simplement selon une \u00e9volution diff\u00e9rente. La chanson est connue car la France n&rsquo;a jamais vraiment d\u00e9sert\u00e9 ses fantasmes-<em>Antifa. <\/em>L&rsquo;hyst\u00e9rie est telle dans tous ces cas qu&rsquo;un dilemme s&rsquo;impose aussit\u00f4t pour l&rsquo;enqu\u00eateur qui entend y comprendre quelque chose : <strong>est-ce la d\u00e9mence qui rend stupide ou la sottise qui rend fou ? Dans tous les cas, on a les deux, d\u00e9mence et sottise<\/strong>.<\/p>\n<\/p>\n<p><p>Mais la chose ne s&rsquo;arr\u00eate pas l\u00e0. Les <em>Antifa<\/em> qui pr\u00e9f\u00e8rent la lutte contre le fascisme qui \u00e9videmment n&rsquo;existe pas dans la lutte antiSyst\u00e8me, introduisent non moins \u00e9videmment <strong>une dimension qui est qualifi\u00e9e par le mot \u00ab\u00a0d\u00e9construire\u00a0\u00bb qu&#8217;emploie McAllister<\/strong>, qui nous est si familier.  Du coup, leur bataille contre le fascisme n&rsquo;est plus si sotte qu&rsquo;elle y para&icirc;t, m\u00eame si l&rsquo;on peut faire l&rsquo;hypoth\u00e8se que la d\u00e9mence subsiste, sous forme d&rsquo;un emprisonnement diabolique qui les entra&icirc;ne dans l&rsquo;inversion d&rsquo;eux-m\u00eames. La lutte contre le fascisme se d\u00e9cline \u00e9galement et \u00e9videmment sur le mode universel de l&rsquo;antiracisme, avec tout ce que cela suppose dans le chef de la postmodernit\u00e9. Elle \u00e9clot dans la radicalit\u00e9 la plus extr\u00eame que l&rsquo;on conna&icirc;t aux USA depuis une petite ann\u00e9e, allant jusqu&rsquo;\u00e0 l&rsquo;exigence d&rsquo;un \u00ab\u00a0holocauste des Blancs\u00a0\u00bb chez les plus imaginatifs, ou encore, selon le mot de Michael Moore, <strong>jusqu&rsquo;\u00e0 l&rsquo;\u00e9radication des trois si\u00e8cles de \u00ab\u00a0supr\u00e9macisme blanc\u00a0\u00bb aux USA<\/strong>.<\/p>\n<\/p>\n<p><p>(\u00ab\u00a0Holocauste des Blancs\u00a0\u00bb, certes la chose a d\u00e9j\u00e0 \u00e9t\u00e9 dite, et chez nombre de progressistes-lib\u00e9raux blancs aux USA, au point qu&rsquo;on se demanderait pourquoi ils ne passent pas \u00e0 l&rsquo;acte le plus simplement et le plus droitement du monde pour lancer leur programme en lui faisant \u00ab\u00a0don de leur personne\u00a0\u00bb, &ndash; en se tirant une balle dans la t\u00eate, fa\u00e7on-NKVD ou mani\u00e8re-SS c&rsquo;est selon, puisque blanc de peau en v\u00e9rit\u00e9 ?)<\/p>\n<\/p>\n<p><p>La d\u00e9marche rejoint elle aussi ce qui se passe en France, dans d&rsquo;autres conditions mais \u00e9margeant au m\u00eame esprit. Voici la chose parfaitement r\u00e9sum\u00e9e par Alain Finkielkraut r\u00e9agissant lors de l&rsquo;\u00e9mission <em>Historiquement Show<\/em> du <a href=\"http:\/\/www.histoire.fr\/actualit\u00e9s\/historiquement-show-sp\u00e9cial-alain-finkielkraut\">11 ao&ucirc;t 2017<\/a> \u00e0 la parution du gros ouvrage qui fait grand bruit, dit <em>Histoire Mondiale de la France<\/em>, qu&rsquo;il d\u00e9finit comme &laquo; <em>une imposture, qui se pr\u00e9sente comme une somme \u00e9rudite alors qu&rsquo;il s&rsquo;agit d&rsquo;une entreprise id\u00e9ologique de part en part<\/em> &raquo;. Il s&rsquo;agit bien d&rsquo;une d\u00e9marche de n\u00e9antissement de la France, qui &laquo; <em>vide la France de toute identit\u00e9 m\u00eame narrative. La France n&rsquo;est plus qu&rsquo;une succession d&rsquo;al\u00e9as<\/em> [&#8230;] [La France est devenue]<em> un espace vide, sans qualit\u00e9, qui accueille la diversit\u00e9 en tant que telle, ce qui veut dire que nulle ant\u00e9riorit\u00e9 ne saurait pr\u00e9valoir et que nulle hi\u00e9rarchie n&rsquo;est autoris\u00e9e \u00e0 s&rsquo;exercer <\/em>[&#8230;] <strong><em>Nous ne sommes plus rien<\/em> [&#8230;] <em>et cette renonciation \u00e0 soi de la France aujourd&rsquo;hui me plonge dans la stupeur et dans une sorte de d\u00e9sespoir<\/em><\/strong>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Finkielkraut, que l&rsquo;on voit d&rsquo;ici avec ses gestes enfi\u00e9vr\u00e9s et contenus et sa diction si pr\u00e9cise et press\u00e9e, nous conte avec au d\u00e9part une sorte de sourire incr\u00e9dule, comment l&rsquo;un des collaborateurs de cette &oelig;uvre de collaboration (voir <em>Antifa<\/em>, au sens p\u00e9tainiste du terme) d\u00e9montre que le tr\u00e8s-grand philosophe fran\u00e7ais Descartes, tout simplement, &laquo; <em>n&rsquo;a absolument rien \u00e0 voir avec la France. Ce qui a fait de lui un grand philosophe, c&rsquo;est sa mobilit\u00e9, son errance, ses voyages. Il ne doit rien \u00e0 la France, tout \u00e0 l&rsquo;exil ; il n&rsquo;appartient pas \u00e0 la France, il appartient au monde&#8230; &raquo;<\/em>.<\/p>\n<\/p>\n<p><p>L&rsquo;<em>Histoire Mondiale de la France<\/em>, qui entend ainsi nous prot\u00e9ger de \u00ab\u00a0la lep\u00e9nisation des esprits\u00a0\u00bb, <strong>du &laquo; <em>nationalisme renaissant en supprimant la nation<\/em> &raquo;<\/strong>, est \u00e9videmment <em>Antifa <\/em>au m\u00eame titre que le cogneur qui vient matraquer les grotesques pseudo-Nazis en esp\u00e9rant qu&rsquo;ainsi Robert E. Lee, Thomas Jefferson &#038; Cie sombreront d\u00e9finitivement dans les latrines largement ouvertes de la non-histoire. Il se manifeste de cette fa\u00e7on, dans l&rsquo;esprit de la chose, une indisputable convergence entre les USA et la France, montrant combien <strong>les deux pays historiquement li\u00e9s par tant d&rsquo;occurrences restent proches l&rsquo;un de l&rsquo;autre<\/strong>, pour nos beaux jours d&rsquo;aujourd&rsquo;hui apr\u00e8s les occurrences historiques, <strong>dans les plus basses entreprises possibles<\/strong>. Le constat est, par-dessus tout cela, et consid\u00e9rant ce travail de d\u00e9construction et de n\u00e9antissement du pass\u00e9, que la gauche devenue <em>Antifa <\/em>s&rsquo;est ainsi institu\u00e9e comme la premi\u00e8re collaboratrice, dans le sens p\u00e9tainiste (suite) de la chose, du Syst\u00e8me dans son &oelig;uvre totalitaire de destruction du monde. <strong>Le basculement est complet, total, absolument accompli par rapport \u00e0 ces jours de la dissidence antiSyst\u00e8me que je rappelai plus haut<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>Quoi qu&rsquo;il en soit, il se trouve que, pour mon compte, <strong>je ne me plains pas vraiment<\/strong> de cette \u00e9volution. L&rsquo;effet principal est, en effet, qu&rsquo;en m\u00eame temps que la gauche devenait <em>Antifa<\/em> et <strong>se d\u00e9couvrait comme collaboratrice directe<\/strong> du Syst\u00e8me, ce m\u00eame Syst\u00e8me <strong>sortait de l&rsquo;ombre, notamment sous sa forme de <em>Deep State<\/em> aux USA<\/strong> de la fa\u00e7on qu&rsquo;on a tent\u00e9e de d\u00e9crire <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-le-moment-glasnostdu-systeme\">le 14 ao&ucirc;t 2017<\/a>.<\/p>\n<\/p>\n<p><p>Cela signifie que toutes les cartes sont ouvertes, bien lisibles et, comme l&rsquo;on dit, \u00e9tal\u00e9es sur la table&#8230; Nous avons devant les yeux <strong>l&rsquo;op\u00e9rationnalisation \u00e0 ciel ouvert d&rsquo;un concept<\/strong> qui est \u00e0 l&rsquo;&oelig;uvre depuis longtemps, mais souterrainement ; sa mise \u00e0 jour doit nous r\u00e9jouir car <strong>ainsi savons-nous d\u00e9sormais qu&rsquo;il est bien ce que nous soup\u00e7onnions qu&rsquo;il est<\/strong>. Les arguments attentistes pour ne pas trop dramatiser la situation et \u00e9carter la n\u00e9cessit\u00e9 de la r\u00e9sistance et du combat n&rsquo;ont plus cours. <strong>Bienvenu, Armageddon<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>De mon point de vue, ceci viendra de plus en plus vite, ce fait que l&rsquo;on va pouvoir et que l&rsquo;on va devoir se compter \u00e0 propos du r\u00f4le que chacun joue par rapport \u00e0 cette entreprise de destruction du monde que conduit le Syst\u00e8me. J&rsquo;en serais m\u00eame \u00e0 soup\u00e7onner que cette haine d\u00e9mente et cette d\u00e9mence haineuse que l&rsquo;on constate aux USA, qui est si proche d&rsquo;une sorte d&rsquo;hyst\u00e9rie, d&rsquo;une esp\u00e8ce de crise de nerfs sans fin \u00e0 l&rsquo;\u00e9chelle globale des progressistes-soci\u00e9taux, qui est si proche de la n\u00e9cessit\u00e9 de tr\u00e8s vite consulter et d&rsquo;envisager un s\u00e9jour au calme de la maison de repos psychiatrique du coin, &ndash; <strong>je soup\u00e7onne fortement que tout cela provient du fait que m\u00eame les plus sots d&rsquo;entre eux, et encore plus pour ceux qui le sont moins, commencent \u00e0 se douter de quelque chose<\/strong>. Il ne s&rsquo;agit pas de Trump mais du pi\u00e8ge o&ugrave; ils se sont mis, en se d\u00e9cha&icirc;nant comme ils font contre Trump, de se retrouver <strong>employ\u00e9s, serviteurs et collaborateurs du <em>Deep State<\/em>, alias le Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p>Bient\u00f4t, il leur faudra constater et mesurer dans quelle entreprise affreuse ils se sont engag\u00e9s au nom d&rsquo;une fugace satisfaction d&rsquo;avoir un simulacre de vertu de leur c\u00f4t\u00e9 et, par le biais d&rsquo;une fantasmagorie compl\u00e8te conceptualis\u00e9e sous la forme de slogans, d&rsquo;avoir combattu des lubies qui font le jeu du Syst\u00e8me et l&rsquo;exacerbe dans le d\u00e9cha&icirc;nement de sa surpuissance&#8230; La surpuissance du Syst\u00e8me devenant comme l&rsquo;on sait autodestruction, <strong>cela pourrait valoir pour eux comme cela vaut pour le Syst\u00e8me<\/strong>.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlottesville-en-France 16 ao&ucirc;t 2017 &ndash; Tout d&rsquo;abord, il ne faut pas s&rsquo;y tromper : le nom Charlottesville n&rsquo;a rien de fran\u00e7ais, sinon du mot \u00ab\u00a0ville\u00a0\u00bb qui lui est donn\u00e9 en r\u00e9f\u00e9rence \u00e0 la ma&icirc;trise internationale de la langue fran\u00e7aise au XVIII\u00e8me si\u00e8cle. Ce nom fut donn\u00e9 \u00e0 cette petite ville (43.000 habitants aujourd&rsquo;hui) fond\u00e9e en&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[13154,7918,13281,2631,7153,2604,4743,2674,2687,3518,4880,3006,2622,7540,13282,3851,3973,3425,13280],"class_list":["post-77431","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-antifa","tag-blancs","tag-charlottesville","tag-de","tag-deep","tag-des","tag-descartes","tag-finkielkraut","tag-france","tag-histoire","tag-holocauste","tag-jefferson","tag-la","tag-lee","tag-mcallister","tag-mondiale","tag-state","tag-supremacisme","tag-trum"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77431"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77431\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}