{"id":77432,"date":"2017-08-17T09:10:54","date_gmt":"2017-08-17T09:10:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/17\/la-loi-dessans-papiers\/"},"modified":"2017-08-17T09:10:54","modified_gmt":"2017-08-17T09:10:54","slug":"la-loi-dessans-papiers","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/17\/la-loi-dessans-papiers\/","title":{"rendered":"La loi des\u00a0sans-papiers"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">La loi des sans-papiers<\/h2>\n<\/p>\n<blockquote>\n<p><p><em>Nous profitons des r\u00e9cents d\u00e9ferlements de migrants ill\u00e9gaux en terres qu\u00e9b\u00e9coises afin de poursuivre une r\u00e9flexion amorc\u00e9e il y a quelques ann\u00e9es et qui \u00e9tait rest\u00e9e en plan. Les puissances atlantistes s&rsquo;acharnent \u00e0 d\u00e9membrer nos \u00e9tats afin de pouvoir reconfigurer la Polis, c&rsquo;est-\u00e0-dire tout le modus vivendi qui constitue la charpente d&rsquo;un &laquo; vivre ensemble &raquo; qui est tout sauf une p\u00e9tition de principe. Puisque la &laquo; paix sociale &raquo; n&rsquo;est pas la r\u00e9sultante d&rsquo;une compromission forc\u00e9e mais bien la sommation de l&rsquo;histoire nationale. &Agrave; l&rsquo;heure des &laquo; Invasions barbares &raquo;, il y a p\u00e9ril en la demeure !<\/em><\/p>\n<\/p>\n<\/blockquote>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">L&rsquo;identit\u00e9 permet de communiquer avec autrui<\/h3>\n<\/p>\n<p><p>Le dialogue n&rsquo;est possible qu&rsquo;\u00e0 partir de l&rsquo;alt\u00e9rit\u00e9, c&rsquo;est-\u00e0-dire cette diff\u00e9rence qui marque les limites constitutives de la rencontre avec les autres. C&rsquo;est en \u00e9rigeant des FRONTI&Egrave;RES que l&rsquo;on pose les jalons de notre identit\u00e9, de la constitution de notre \u00eatre collectif. La fronti\u00e8re &ndash; R\u00e9gis Debray l&rsquo;a parfaitement bien expliqu\u00e9 sans son OPUS intitul\u00e9 <em>&Eacute;loge des fronti\u00e8res<\/em> &ndash; c&rsquo;est, d&rsquo;abord et avant tout, la s\u00e9gr\u00e9gation op\u00e9r\u00e9e par le langage afin d&rsquo;\u00eatre en mesure de se distancier des choses et des hommes. Nommer l&rsquo;univers qui nous entoure permet d&rsquo;\u00e9riger des <em>bornes<\/em> salutaires qui agiront comme les marqueurs de notre identit\u00e9 et, partant, repr\u00e9sentent une forme de cartographie de cette cit\u00e9 qui regroupe nos semblables.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">B\u00e2tir un milieu de vie<\/h3>\n<\/p>\n<p><p>M\u00eame les marchandises finissent leur course quelque part afin de s&rsquo;int\u00e9grer \u00e0 la petite famille des objets domestiques d&rsquo;une maisonn\u00e9e. La domesticit\u00e9 &ndash; <em>DOMUS<\/em> &ndash; c&rsquo;est ce qui distingue un milieu de vie et participe \u00e0 son enrichissement au gr\u00e9 d&rsquo;une patiente acclimatation. La domesticit\u00e9 comporte ses lieux communs, ses r\u00e8gles, son modus vivendi, son environnement et sa soci\u00e9t\u00e9 respective; tout ce qui participe \u00e0 la vie familiale requiert une part d&rsquo;inviolabilit\u00e9 et de protection. C&rsquo;est l&rsquo;intimit\u00e9 du foyer &ndash; <em>o\u00efka <\/em>chez les anciens Grecs &ndash; qui fera en sorte qu&rsquo;Ulysse finisse par trouver les forces n\u00e9cessaires afin d&rsquo;\u00eatre en mesure de retourner parmi les siens. La maison familiale c&rsquo;est le n&oelig;ud de notre m\u00e9moire intime, c&rsquo;est le r\u00e9ceptacle d&rsquo;une tradition filiale qui fonde toute la charpente de nos futures entreprises et qui repr\u00e9sente une r\u00e9f\u00e9rence insurpassable pour quiconque n&rsquo;a pas \u00e9t\u00e9 compl\u00e8tement d\u00e9racin\u00e9.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le viol de la cit\u00e9<\/h3>\n<\/p>\n<p><p>&laquo; <em>Montr\u00e9al, ville sanctuaire pour les migrants <\/em>&raquo; s&rsquo;apparente \u00e0 un slogan politique qui d\u00e9cline un programme particuli\u00e8rement d\u00e9l\u00e9t\u00e8re, toxique. En effet, le Maire de Montr\u00e9al s&rsquo;arroge le droit d&rsquo;ouvrir un canal privil\u00e9gi\u00e9 afin de permettre \u00e0 de puissantes organisations mondialistes de faire converger des milliers de migrants au c&oelig;ur de la m\u00e9tropole d&rsquo;un Qu\u00e9bec qui est litt\u00e9ralement viol\u00e9 en toute impunit\u00e9. Chemin faisant, Montr\u00e9al devient le <em>Cheval de Troie <\/em>qui permettra \u00e0 toutes les <em>Open Society<\/em> &ndash; soci\u00e9t\u00e9 \u00e9cran cr\u00e9\u00e9e par George Soros &ndash; de ce monde de venir phagocyter les pr\u00e9rogatives r\u00e9galiennes de la cit\u00e9. En d&rsquo;autres termes, les habitants de Montr\u00e9al &ndash; et le gouvernement du Qu\u00e9bec &ndash; devront consacrer des sommes exorbitantes pour que des int\u00e9r\u00eats financiers \u00e9trangers puissent organiser des camps d&rsquo;accueil pour migrants qui se transformeront en &hellip; camps de travail \u00e9ventuellement. Il ne restera plus qu&rsquo;\u00e0 utiliser ce nouveau <em>pipeline \u00e0 migrants<\/em> afin de pourvoir aux emplois subalternes des services d\u00e9di\u00e9s au confort de l&rsquo;hyperclasse et des touristes en goguette. &Agrave; moyen terme, il n&rsquo;y aura plus aucun francophone (de souche) \u00e0 Montr\u00e9al, ce qui permettra de faire de l&rsquo;ancienne m\u00e9tropole du Qu\u00e9bec une <em>ville franche<\/em> au service de l&rsquo;oligarchie mondialiste et de proc\u00e9der, de facto, \u00e0 la partition de cette <em>Nouvelle-France<\/em> qui r\u00e9sistait toujours au rouleau compresseur de l&rsquo;<em>Empire<\/em>.<\/p>\n<\/p>\n<p><p>Le Maire de Montr\u00e9al contrevient &ndash; c&rsquo;est le cas de le dire &ndash; aux capacit\u00e9s r\u00e9galiennes des paliers sup\u00e9rieurs de gouvernement de r\u00e9guler l&rsquo;immigration de masse. Toute cette approche &ndash; qui n&rsquo;est pas l&rsquo;apanage de la m\u00e9tropole qu\u00e9b\u00e9coise &ndash; a \u00e9t\u00e9 mise en place par les puissants r\u00e9seaux du tandem Clinton-Soros afin de paralyser les politiques du gouvernement Trump en mati\u00e8re de politique migratoire. Montr\u00e9al rejoint, ainsi, le peloton des <em>villes franches <\/em>qui ont d\u00e9cid\u00e9 d&rsquo;outrepasser les pouvoirs sup\u00e9rieurs en mati\u00e8re d&rsquo;immigration en agissant de leur propre chef, comme si elles \u00e9taient des <em>cit\u00e9-\u00e9tats&shy; <\/em>de la Renaissance. Et, dans un contexte o&ugrave; une nouvelle crise financi\u00e8re menace de frapper l&rsquo;Am\u00e9rique du Nord de plein fouet, il va de soi que toute cette politique de sabotage des tissus urbains risque de provoquer une dislocation de la cit\u00e9 pour que nos milieux de vie se transforment en m\u00e9tastases incurables. &Agrave; terme, c&rsquo;est la souverainet\u00e9 des \u00e9tats qui est vis\u00e9e, ce qui facilitera le parach\u00e8vement des grands trait\u00e9s de libre-\u00e9change et laissera aux multinationales toute la latitude voulue pour gouverner.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le grand remplacement<\/h3>\n<\/p>\n<p><p>Les qu\u00e9b\u00e9cois regardent, m\u00e9dus\u00e9s, leur propre m\u00e9tropole se d\u00e9sagr\u00e9ger alors que des ressources publiques consid\u00e9rables sont pomp\u00e9es afin d&rsquo;acc\u00e9l\u00e9rer le processus. Il s&rsquo;agit d&rsquo;un &laquo; suicide assist\u00e9 &raquo; de tr\u00e8s grande ampleur et le spectre des mesures qui nous sont impos\u00e9es par l&rsquo;oligarchie mondialiste nous force \u00e0 pr\u00e9ciser les termes de notre r\u00e9flexion.<\/p>\n<\/p>\n<p><p>Cette acc\u00e9l\u00e9ration soudaine du flux migratoires profitera, bien entendu, au Parti lib\u00e9ral du Qu\u00e9bec qui pourra compter sur accroissement de son bassin d&rsquo;\u00e9lecteurs potentiels. Outre qu&rsquo;elle fera baisser les conditions de vie des travailleurs, cette politique n\u00e9ocoloniale aura pour effet de disloquer nos milieux de vie, de solliciter \u00e0 outrance les finances d&rsquo;un \u00e9tat \u00e0 bout de souffle et de contribuer \u00e0 de faire du Grand Montr\u00e9al m\u00e9tropolitain un v\u00e9ritable protectorat \u00e9tranger. Le Qu\u00e9bec devrait, \u00e0 br\u00e8ve \u00e9ch\u00e9ance, \u00eatre coup\u00e9 en deux. Et, le poison faisant effet, l&rsquo;an\u00e9antissement de notre nation sera r\u00e9alis\u00e9 pour le plus grand bonheur des architectes d&rsquo;un <em>multiculturalisme <\/em>au service de l&rsquo;oligarchie financi\u00e8re internationale.<\/p>\n<\/p>\n<p><p>La <em>Consultation sur la discrimination syst\u00e9mique et le racisme<\/em>, mise de l&rsquo;avant par le gouvernement Couillard, repr\u00e9sente la clef de voute au chapitre de l&rsquo;ing\u00e9nierie sociale et permettra de mettre en place un dispositif qui agira comme un puissant adjuvant afin de disqualifier tous les patriotes qui s&rsquo;aviseraient de remettre en cause cette abominable gabegie. Il n&rsquo;y a qu&rsquo;\u00e0 voir toute l&rsquo;entreprise de concertation qui se tisse entre le minist\u00e8re f\u00e9d\u00e9ral du Patrimoine et le gouvernement du Qu\u00e9bec pour comprendre que la bourgeoisie compradore d\u00e9sire acc\u00e9l\u00e9rer le tempo afin d&rsquo;en finir avec la dissidence &hellip; avant la tenue des prochaines \u00e9lections provinciales.<\/p>\n<\/p>\n<p><h4>Patrice-Hans Perrier<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La loi des sans-papiers Nous profitons des r\u00e9cents d\u00e9ferlements de migrants ill\u00e9gaux en terres qu\u00e9b\u00e9coises afin de poursuivre une r\u00e9flexion amorc\u00e9e il y a quelques ann\u00e9es et qui \u00e9tait rest\u00e9e en plan. Les puissances atlantistes s&rsquo;acharnent \u00e0 d\u00e9membrer nos \u00e9tats afin de pouvoir reconfigurer la Polis, c&rsquo;est-\u00e0-dire tout le modus vivendi qui constitue la charpente&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3708,13283,2957,12744,13212,12532,2958],"class_list":["post-77432","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-canada","tag-deferlement","tag-grand","tag-migrants","tag-montreal","tag-quebec","tag-remplacement"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77432"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77432\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}