{"id":77434,"date":"2017-08-17T16:51:33","date_gmt":"2017-08-17T16:51:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/17\/paroles-et-paradoxes-dantifa-usa\/"},"modified":"2017-08-17T16:51:33","modified_gmt":"2017-08-17T16:51:33","slug":"paroles-et-paradoxes-dantifa-usa","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/17\/paroles-et-paradoxes-dantifa-usa\/","title":{"rendered":"Paroles et paradoxes d&rsquo;<em>Antifa<\/em>-USA"},"content":{"rendered":"<p><h3 class=\"subtitleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Paroles et paradoxes d&rsquo;<em>Antifa<\/em>-USA<\/h3>\n<\/p>\n<p><p>17 ao&ucirc;t 2017 &ndash; D\u00e9cid\u00e9ment, <strong>une seule formule<\/strong> que nous citons souvent depuis une ou deux semaines \u00e9crase aujourd&rsquo;hui toutes les autres pour d\u00e9crire la situation, c&rsquo;est-\u00e0-dire comme <strong>essentielle <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> : \u00ab\u00a0la r\u00e9f\u00e9rence n&rsquo;est plus le Syst\u00e8me mais le d\u00e9sordre\u00a0\u00bb<\/strong>. Cela nous conduit \u00e0 devoir chaque jour modifier l&rsquo;orientation de la perception de la situation, &ndash; aux USA, au fait, &ndash; par cons\u00e9quent de d\u00e9velopper des observations qui semblent le contraire de celles qui ont pr\u00e9c\u00e9d\u00e9 et qui le sont effectivement d&rsquo;un point de vue op\u00e9rationnel imm\u00e9diat, auxquelles pourtant il nous appartient de donner une coh\u00e9rence ; car finalement, sur l&rsquo;essentiel, tout finit par <strong>se mettre en place pour \u00e9clairer d&rsquo;une lumi\u00e8re triomphale l&rsquo;avancement de la catastrophe<\/strong>.<\/p>\n<\/p>\n<p><p>On v\u00e9rifie cet \u00e9tat de chose, aujourd&rsquo;hui encore, en citant ce texte d&rsquo;un tr\u00e8s haut int\u00e9r\u00eat documentaire de Peter Hasson, du <em>Daily Caller<\/em>, du <a href=\"http:\/\/dailycaller.com\/2017\/08\/16\/in-their-own-words-the-radical-political-goals-of-anti-fascists\/\">16 ao&ucirc;t 2017<\/a>. Le titre serait &laquo; <em>Selon leurs propres mots : les buts politiques radicaux des \u00ab\u00a0Anti-fascistes\u00a0\u00bb<\/em> &raquo; (\u00ab\u00a0<em>In Their Own Words: The Radical Political Goals Of &lsquo;Anti-Fascists&rsquo;<\/em>\u00ab\u00a0). Il s&rsquo;agit des activistes<em> Antifa <\/em>(-USA), comme on les nomme, dont on va voir qu&rsquo;il faut bien les distinguer d&rsquo;une fa\u00e7on sp\u00e9cifique, justement en \u00e9cartant l&rsquo;\u00e9tiquette fourre-tout d'\u00a0\u00bbantifascistes\u00a0\u00bb, auberge espagnole de tous les ph\u00e9nom\u00e8nes contradictoires suscit\u00e9s par cette situation, dans le champ de l&rsquo;antitrumpisme pris dans son acceptation la plus large. Ainsi, lorsque l&rsquo;un et l&rsquo;autre membres d&rsquo;<em>Antifa<\/em>-USA repr\u00e9sentant tel et tel groupes disent qu&rsquo;ils veulent rendre ce pays (les USA) \u00ab\u00a0ingouvernable\u00a0\u00bb ; qu&rsquo;ils ne sont pas int\u00e9ress\u00e9 par la \u00ab\u00a0protection de l&rsquo;actuel syst\u00e8me politique US\u00a0\u00bb (Washington D.C.) mais qu&rsquo;au contraire \u00ab\u00a0ils veulent le d\u00e9truire\u00a0\u00bb ; qu&rsquo;ils veulent \u00ab\u00a0supprimer le Pentagone et consacrer le budget de guerre \u00e0 aider les pauvres et les groupes opprim\u00e9s\u00a0\u00bb ; qu&rsquo;ils veulent d\u00e9truire le capitalisme et qu&rsquo;ils sont aux c\u00f4t\u00e9s du Nord-Cor\u00e9en Kim et du V\u00e9n\u00e9zu\u00e9lien Maduro contre les pressions militaires du Pentagone, etc., &ndash; ils n&rsquo;\u00e9noncent certainement pas des objectifs extr\u00eamement diff\u00e9rents de ceux que <strong>doit approuver et favoriser tactiquement un antiSyst\u00e8me cons\u00e9quent par rapport \u00e0 la strat\u00e9gie de destruction du Syst\u00e8me<\/strong>.<\/p>\n<\/p>\n<p><p>Dans ce cas, les <em>Antifa<\/em>-USA ne se situent nullement dans l&rsquo;antitrumpisme qu&rsquo;orchestre le <em>Deep State<\/em>, selon la conception que nous avons des effets du gouvernement (ou du non-gouvernement) de Trump et de l&rsquo;opposition que dresse contre lui le <em>Deep State<\/em>, mais d&rsquo;une fa\u00e7on si diff\u00e9rente que c&rsquo;en est le contraire, dans une opposition compl\u00e8te \u00e0 la presseSyst\u00e8me, aux d\u00e9mocrates US, au <em>Deep State<\/em>, lesquels se disent tous \u00ab\u00a0antifascistes\u00a0\u00bb de la plus grande ardeur possible, exactement comme BHL se dit \u00ab\u00a0antifasciste\u00a0\u00bb en France. <strong>Les <em>Antifa<\/em>-USA devraient se douter de quelque chose<\/strong> lorsqu&rsquo;ils constatent que les membres d&rsquo;un <em>panel<\/em> choisi de grands patrons du capitalisme r\u00e9unis par Trump dans le <em>Strategy &#038; Policy Forum <\/em>mis en place pour conseiller le pr\u00e9sident ont commenc\u00e9 \u00e0 d\u00e9missionner les uns apr\u00e8s les autres par pur \u00ab\u00a0antifascisme\u00a0\u00bb, pour protester contre le r\u00f4le (?) de Trump dans les \u00e9v\u00e9nements de Charlottesville, avant que <a href=\"http:\/\/www.zerohedge.com\/news\/2017-08-16\/trump-reportedly-verge-disbanding-strategic-policy-council\">Trump ne liquide<\/a> ce rassemblement de conseillers-CEO d\u00e9cid\u00e9ment incroyablement vertueux type-antifascistes, et donc plus aptes \u00e0 donner des conseils sur l&rsquo;antifascisme que sur la bonne marche des affaires&#8230; Car ces purs produits et dirigeants du capitalisme monstrueux que les <em>Antifa<\/em>-USA veulent d\u00e9truire se disent effectivement \u00ab\u00a0antifa\u00a0\u00bb comme les <em>Antifa<\/em>-USA eux-m\u00eames !<\/p>\n<\/p>\n<p><p>(Pour paraphraser en le pastichant la phrase de <a href=\"http:\/\/www.dedefensa.org\/article\/charlottesville-en-france\">Finkielkraut<\/a> [en mai 68, \u00ab\u00a0on avait le fascisme facile\u00a0\u00bb, c&rsquo;est-\u00e0-dire l&rsquo;accusation de \u00ab\u00a0fascistes\u00a0\u00bb facile], on dirait qu&rsquo;<strong>aujourd&rsquo;hui \u00ab\u00a0on a l&rsquo;antifascisme encore plus facile\u00a0\u00bb. <\/strong>Ainsi en revenons-nous \u00e0 cette id\u00e9e de l&rsquo;auberge espagnole vue plus haut.)<\/p>\n<\/p>\n<p><p>L&rsquo;antitrumpisme institutionnel (Syst\u00e8me) de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb et le gouvernement de Trump ont <strong>ceci en commun qu&rsquo;ils participent \u00e0 l&rsquo;entretien du d\u00e9sordre au moins autant que les <em>Antifa<\/em>-USA<\/strong>, ce qui n&rsquo;est pas peu dire ; ou bien sont-ce les <em>Antifa<\/em>-USA qui se perdent eux-m\u00eames dans le d\u00e9sordre qui les concernent tous et ne voient rien des v\u00e9ritables effets et cons\u00e9quences de leurs actions&#8230; Qu&rsquo;importe, <strong>tout le monde aujourd&rsquo;hui, aux USA, dans l&rsquo;ar\u00e8ne politique, tout le monde alimente le d\u00e9sordre<\/strong>, &ndash; puisqu&rsquo;en effet, \u00e0 c\u00f4t\u00e9 de tous ses adversaires qui agissent contre lui en semant le d\u00e9sordre, Trump lui-m\u00eame riposte en ajoutant son d\u00e9sordre \u00e0 ceux de ses divers adversaires.<\/p>\n<\/p>\n<blockquote>\n<p><p>Quant aux rapports de ces groupes <em>Antifa<\/em>-USA et des \u00ab\u00a0antifascistes\u00a0\u00bb de <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-la-tragedie-bouffe\">trag\u00e9die-bouffe<\/a> de la composante lib\u00e9rale-chic des progressistes-soci\u00e9taux, <strong>il est extr\u00eamement difficile de savoir qui est \u00ab\u00a0l&rsquo;idiot utile\u00a0\u00bb de l&rsquo;autre. Notre hypoth\u00e8se serait bien que les <em>Antifa<\/em>-USA sont \u00ab\u00a0les idiots utiles du Syst\u00e8me\u00a0\u00bb, <\/strong>mais dans un sens qui, en alimentant \u00e9videmment sa surpuissance, travaille d\u00e9sormais dans un contexte o&ugrave; cette surpuissance est directement transmut\u00e9e en autodestruction, <strong>laquelle est le but n\u00e9cessaire que doit favoriser tout antiSyst\u00e8me&#8230; Ils sont par cons\u00e9quent les \u00ab\u00a0idiots utiles\u00a0\u00bb de l&rsquo;antiSyst\u00e8me !<\/strong><\/p>\n<\/p>\n<\/blockquote>\n<p><p>Voici quelques extraits du texte Peter Hasson, du <em>Daily Caller<\/em>, du <a href=\"http:\/\/dailycaller.com\/2017\/08\/16\/in-their-own-words-the-radical-political-goals-of-anti-fascists\/\">16 ao&ucirc;t 2017<\/a> : &laquo; <em>In the days since violent clashes at a white nationalist rally in Charlottesville culminated in a neo-Nazi sympathizer driving his car into a crowd of counter-protesters, journalists have mainstreamed the self-described \u00ab\u00a0anti-fascists\u00a0\u00bb (or \u00ab\u00a0antifa\u00a0\u00bb) at the rally &mdash; largely ignoring their involvement in the escalating political violence in this country. Many establishment political figures insisted the far-left actors <a href=\"http:\/\/dailycaller.com\/2017\/08\/16\/major-figures-work-to-mainstream-violent-antifa-protesters\/\">were just like American soldiers on D-Day<\/a>. But these \u00ab\u00a0anti-fascists'\u00a0\u00bb  own statements show they&rsquo;re nothing like American soldiers on D-Day. <\/em><em>They aren&rsquo;t interested in protecting America&rsquo;s system of government, according to their own statements &mdash; they&rsquo;re interested in destroying it<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>From the very start of the Trump administration, far-left actors declared their intention to use massive demonstrations to disrupt the American political process as much as possible. A common mantra among far-left groups beginning shortly before the inauguration: make America \u00ab\u00a0ungovernable.\u00a0\u00bb \u00ab\u00a0We need to make this country ungovernable,\u00a0\u00bb <a href=\"http:\/\/dailycaller.com\/2017\/02\/06\/in-their-own-words-anti-trump-resistance-leaders-say-they-want-to-make-america-ungovernable\/\">declared<\/a> a female leader for Refuse Fascism shortly after the inauguration. <\/em><em>\u00ab\u00a0We need to do what the German people should have done when Hitler was elected.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Refuse Fascism was a driving force behind the violent, politically motivated riots in Berkeley. Right-wing provocateur Milo Yiannopoulos &mdash; who at the time was an editor at pro-Trump website Breitbart &mdash; was scheduled to speak at the University of California&rsquo;s Berkeley campus. He was forced to cancel the speech after mobs of protesters started fires, assaulted bystanders and pepper sprayed suspected Trump supporters as part of an <a href=\"http:\/\/dailycaller.com\/2017\/02\/01\/inferno-milo-speech-cancelled-after-rioters-set-campus-ablaze\/\">organized effort to shut down the speech<\/a>. Refuse Fascism was among the left-wing groups advertising the Charlottesville rally and <a href=\"https:\/\/refusefascism.org\/2017\/08\/08\/white-supremacists-plan-august-12-rally-in-charlottesville-join-in-saying-nonewkkk\/\">urged confrontation<\/a> with the white nationalists: \u00ab\u00a0Drive them OUT of Charlottesville and out of power!\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Refuse Fascism was far from the only left-wing fringe group at Charlottesville. One anarchist group that was at Charlottesville, CrimethInc, holds that anarchism is necessary to destroy white supremacy, which the group says cannot be fully extinguished in a democracy. \u00ab\u00a0Anarchism is one of the most thoroughgoing forms of opposition to fascism, in that it entails opposition to hierarchy itself. Virtually every framework that countenances hierarchy, be it democracy or &lsquo;national liberation,&rsquo; enables old power imbalances like white supremacy and patriarchy to remain in place, hidden within the legitimacy of the prevailing structures,\u00a0\u00bb the the group explains<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>They similarly want to destroy law enforcement and capitalists. \u00ab\u00a0We must identify the forces underlying their laws and their order&mdash;white supremacy, patriarchy, policing, capitalism, and the state. We have to work together to keep ourselves safe and reimagine the world without them,\u00a0\u00bb the group states in an article, which was reposted on popular antifa website <a href=\"https:\/\/itsgoingdown.org\/author\/crimethinc-ex-workers-collective\/\">It&rsquo;s Going Down<\/a><\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Another far-left group at Charlottesville last weekend: the Workers World Party, a group of Marxist-Leninist revolutionaries who have declared their support for Kim Jong Un&rsquo;s murderous dictatorship in North Korea. Workers World&rsquo;s publication has consistently published <a href=\"http:\/\/www.workers.org\/2017\/05\/31\/venezuela-resists-u-s-sabotage\/\">propaganda-like<\/a> screeds supporting Venezuela&rsquo;s murderous regime. The communist group \u00ab\u00a0sent many of its members to Charlottesville, Va., to beat back the Nazis and Klan who marched there,\u00a0\u00bb according to a <a href=\"http:\/\/www.workers.org\/2017\/08\/14\/charlottesville-watershed-in-the-united-struggle-against-fascism\/\">post<\/a> recapping the group&rsquo;s participation in the weekend&rsquo;s violence<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>The Daily Caller News Foundation <a href=\"http:\/\/dailycaller.com\/2017\/08\/16\/brutal-examples-of-violence-that-occurred-by-both-sides-in-charlottesville-video\/\">confirmed<\/a> Workers World&rsquo;s presence at the Charlottesville rally. <\/em><em>The group <a href=\"http:\/\/www.workers.org\/2017\/08\/15\/freedom-fighters-topple-white-supremacy-statue\/\">took credit<\/a><\/em><em> for organizing the vandals who toppled a city-owned confederate statue in Durham, North Carolina this week. Workers&rsquo; World&rsquo;s stated <a href=\"http:\/\/www.workers.org\/wwp\/what-is-wwp-2\/\">goals<\/a><\/em><em> are classic Marxism, including igniting an international socialist revolution and \u00ab\u00a0the shutdown of the Pentagon and the use of the war budget\u00a0\u00bb &mdash; that is, the funding for the Department of Defense &mdash; \u00ab\u00a0to improve the lives of the working class and especially the oppressed peoples.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p><em>&raquo; While Workers World is currently fighting (literally) with white nationalists, the group is opposed to all in the \u00ab\u00a0ruling establishment\u00a0\u00bb who the group explains hide \u00ab\u00a0behind a veil of &lsquo;democracy&rsquo; and &lsquo;human rights.'\u00a0\u00bb \u00ab\u00a0Those in the ruling establishment who see their reputation in tatters are appalled by what happened <\/em>[<em>at Charlottesville<\/em>]<em>, but not for the right reasons,\u00a0\u00bb read a Workers World <\/em><em><a href=\"http:\/\/www.workers.org\/2017\/08\/14\/charlottesville-watershed-in-the-united-struggle-against-fascism\/\">post<\/a><\/em><em> after Charlottesville. \u00ab\u00a0They want to continue to exploit and dominate most of the world, but behind a veil of &lsquo;democracy&rsquo; and &lsquo;human rights.&rsquo; The people are showing by their actions that only by taking the fight for justice into their own hands, with no confidence in the organs of state power, can they make progress.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Bien entendu, cette occurrence tactique qu&rsquo;on d\u00e9couvre chez les <em>Antifa<\/em>-USA n&rsquo;implique nullement un accord g\u00e9n\u00e9ral sur leur activisme. Dans ce cas, nous dirions, nous, que le d\u00e9sordre qu&rsquo;ils entendent cr\u00e9er ne rencontre leurs conceptions que pour les plonger eux-m\u00eames dans le d\u00e9sordre caract\u00e9ristique de ces gauchismes qui constituent autant de fruits de la d\u00e9cadence incertaine de la belle floraison marxiste et marxiste-l\u00e9niniste qui a \u00e9clair\u00e9 le monde au long du XX\u00e8me si\u00e8cle.<\/p>\n<\/p>\n<p><p>C&rsquo;est d&rsquo;ailleurs un signe excellent de l&rsquo;\u00e9volution de la situation US, parce que c&rsquo;est un puissant moteur d&rsquo;accroissement de la confusion des genres (politiques, certes) dans des alliances confuses (du c\u00f4t\u00e9 des antitrumpistes) et une incompr\u00e9hension compl\u00e8te du ph\u00e9nom\u00e8ne politique que constitue l&rsquo;\u00e9lection de Trump. Non seulement Trump est un semeur de d\u00e9sordre par lui-m\u00eame mais il l&rsquo;est \u00e9galement, et fort bellement, d&rsquo;une fa\u00e7on indirecte, par les \u00e9tranges coalitions qu&rsquo;il suscite contre lui, et la haine extraordinaire qui aveugle et nourrit les susdites coalitions, comme <strong>enivr\u00e9es par l'\u00a0\u00bbantifascisme\u00a0\u00bb et l'\u00a0\u00bbantiracisme\u00a0\u00bb devenus autant d&rsquo;alcools irr\u00e9sistibles pour ces braves petites \u00e2mes si vertueuses<\/strong>&#8230;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Chasse aux statues, \u00ab\u00a0chasse aux sorci\u00e8res\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>La <em>doxa <\/em>des antitrumpistes, des s\u00e9nateurs d\u00e9mocrates parfum\u00e9s et cravat\u00e9s aux <em>Antifa<\/em>-USA d\u00e9penaill\u00e9s, est la notion du \u00ab\u00a0supr\u00e9macisme blanc\u00a0\u00bb mari\u00e9e \u00e0 la diabolisation du Sud de la Guerre de S\u00e9cession, en une sorte d&rsquo;habillage dialectique de la pens\u00e9e antiraciste devenue folle. Le \u00ab\u00a0supr\u00e9macisme blanc\u00a0\u00bb est dans le cadre actuel des USA super-r\u00e9glement\u00e9, r\u00e9duit \u00e0 sa plus simple expression, oblig\u00e9 de se grimer et de ce fait enti\u00e8rement tourn\u00e9 vers le communautarisme soci\u00e9tal plut\u00f4t color\u00e9 (les LGTBQ, les Africains-Am\u00e9ricains, etc.) ; c&rsquo;est-\u00e0-dire que la lutte contre lui se constitue en un concept certes destructeur et d\u00e9constructeur, <strong>mais un concept absurde pour une action politique constructive et conqu\u00e9rante<\/strong> parce qu&rsquo;il n&rsquo;a aucune signification politique sp\u00e9cifique sinon de mettre en \u00e9vidence les contraintes oppressives de ce cadre communautariste-soci\u00e9tal, <strong>donc de sugg\u00e9rer la n\u00e9cessit\u00e9 de la d\u00e9construction de ce cadre<\/strong>.<\/p>\n<\/p>\n<p><p>Le seul v\u00e9ritable supr\u00e9macisme qui ait aujourd&rsquo;hui une marque historique r\u00e9elle, passant par l&rsquo;influence, la conqu\u00eate, la manipulation, etc., <strong>c&rsquo;est le \u00ab\u00a0supr\u00e9macisme anglo-saxon\u00a0\u00bb auquel des non-Blancs (Obama par exemple) ont largement contribu\u00e9<\/strong> ; ce supr\u00e9macisme est l&rsquo;organisateur depuis des lustres de la globalisation, et plac\u00e9 d\u00e9sormais devant la contradiction interne du monstre qu&rsquo;il a enfant\u00e9, et <strong>qui d\u00e9vore toutes les souverainet\u00e9s, y compris celles des nations anglo-saxonnes<\/strong>.<\/p>\n<\/p>\n<p><p>Les antitrumpistes, alli\u00e9s incongrus des <em>Antifa<\/em>-USA, sont essentiellement comptables de ce \u00ab\u00a0supr\u00e9macisme anglo-saxon\u00a0\u00bb tandis que Trump chercherait en th\u00e9orie, si l&rsquo;on s&rsquo;attache \u00e0 ce qu&rsquo;il reste de coh\u00e9rent dans son discours, \u00e0 s&rsquo;y opposer <strong>selon la doctrine <em>America-First<\/em> devenant par un curieux retour des choses une r\u00e9sistance am\u00e9ricaine au supr\u00e9macisme anglo-saxon mut\u00e9 en globalisation<\/strong>. Si les <em>Antifa<\/em>-USA \u00e9taient coh\u00e9rents dans leur opposition au \u00ab\u00a0supr\u00e9macisme\u00a0\u00bb, ils devraient soutenir le programme <em>American-Firster <\/em>de Trump et les intentions affich\u00e9es du terrifiant Steven Bannon de \u00ab\u00a0d\u00e9truire la bureaucratie\u00a0\u00bb de Washington D.C. Bien entendu, tout cela n&rsquo;a aucune coh\u00e9rence, aucune coh\u00e9sion, et ne fournit aucune indication politique de quelque ordre que ce soit, <strong>sinon l&rsquo;omnipr\u00e9sence du d\u00e9sordre et la confusion qui s&rsquo;ensuit<\/strong>.<\/p>\n<\/p>\n<p><p>Un point d&rsquo;une extr\u00eame importance apparu \u00e0 Charlottesville, et qui \u00e9tait en relatif sommeil depuis un ou deux ans, c&rsquo;est l&rsquo;attaque symbolique contre le Sud de la Guerre de S\u00e9cession et sa diabolisation au travers de la destruction de statues et de signes comm\u00e9moratifs. Cette dynamique a \u00e9t\u00e9 d\u00e9clench\u00e9e il y a quelques ann\u00e9es, dans le climat instaur\u00e9 par l&rsquo;administration Obama, mais elle n&rsquo;avait pas pris <strong>l&rsquo;ampleur symbolique absolument stup\u00e9fiante de surpuissance qu&rsquo;elle a acquise en quelques jours depuis <a href=\"http:\/\/www.dedefensa.org\/article\/nouvelles-de-charlottesville\">Charlottesville<\/a><\/strong>. Les <em>Antifa<\/em>-USA adoptent compl\u00e8tement, tout comme la coalition antitrumpiste au rythme du progressisme-soci\u00e9tal, la th\u00e8se de la diabolisation du Sud au nom de l&rsquo;antiracisme, c&rsquo;est-\u00e0-dire de l&rsquo;esclavage. Bien entendu, comme tout ce qui supporte aujourd&rsquo;hui les grands mouvements soi-disant politique de la postmodernit\u00e9, cette th\u00e8se, &ndash; o&ugrave; Poutine et la Russie ne peuvent malheureusement pas \u00eatre impliqu\u00e9s malgr\u00e9 les forts soup\u00e7ons qui continuent \u00e0 r\u00f4der, &ndash;  est tr\u00e8s fortement, tr\u00e8s infiniment faussaire, dans nombre de cas elle est pure r\u00e9\u00e9criture de l&rsquo;histoire, pure <em>narrative<\/em> fournissant un sc\u00e9nario au <em>Lincoln <\/em>de Spielberg, si vous voulez. <strong>Elle doit \u00eatre vue comme un simulacre justifiant le d\u00e9cha&icirc;nement antitrumpiste au nom d&rsquo;une logique certes assez indigne mais qui fait l&rsquo;affaire pour le Syst\u00e8me<\/strong>&#8230; Et ainsi, sur ce point, les <em>Antifa<\/em>-USA se trouvent compl\u00e8tement, absolument en phase avec le Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Le probl\u00e8me est qu&rsquo;ils (les antitrumpistes et les <em>Antifa<\/em>-USA) \u00e9rigent en d\u00e9bat national la phase la plus d\u00e9licate et la plus douloureuse, et aussi la plus irr\u00e9solue et la plus contestable de l&rsquo;histoire des &Eacute;tats-Unis ; et qu&rsquo;au-del\u00e0, selon la logique d&rsquo;enroulement du pass\u00e9 de la repentance de l&rsquo;esclavagisme et les outrances extraordinaires de la d\u00e9nonciation du \u00ab\u00a0supr\u00e9macisme\u00a0\u00bb, ils mettent en question la structure historique m\u00eame des USA <strong>en remontant aux origines<\/strong>. Lorsque Trump avertit les journalistes partisans \u00e9videmment de l&rsquo;agitation antitrumpiste et soutiens assez irresponsables (de leur point de vue) des <em>Antifa<\/em>-USA, cela dans <a href=\"https:\/\/www.infowars.com\/trumps-press-conference-leaves-reporters-shaken-rattled\/\">une de ses meilleures<\/a> conf\u00e9rences de presse, mardi, que <a href=\"https:\/\/www.lewrockwell.com\/lrc-blog\/attention-snowflakes-please-melt-completely\/\">m\u00eame des libertariens<\/a> portant bien peu trumpistes ont applaudi, il leur dit en se r\u00e9f\u00e9rant <strong>\u00e0 la chasse aux statues des g\u00e9n\u00e9raux sudistes, sorte de \u00ab\u00a0chasse aux sorci\u00e8res\u00a0\u00bb de la postmodernit\u00e9 en plein symbolisme<\/strong> :<\/p>\n<\/p>\n<p><p>&laquo; <strong><em>Vous \u00eates en train de changer l&rsquo;histoire, vous \u00eates en train de changer notre culture<\/em><\/strong><em>&#8230; George Washington \u00e9tait un propri\u00e9taire d&rsquo;esclaves. &Eacute;tait-il un propri\u00e9taire d&rsquo;esclaves, oui ou non ? Alors, faut-il liquider la statue de George Washington ? Allons-nous abattre les statues de George Washington ? Et Thomas Jefferson ? &#8230; Est-ce qu&rsquo;on va d\u00e9molir ses statues ? Parce que, hein, c&rsquo;\u00e9tait un propri\u00e9taire d&rsquo;esclaves. <strong>Alors, va-t-on d\u00e9molir ses statues ?<\/strong><\/em> &raquo;<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Oui !\u00a0\u00bb s&#8217;empresse-t-on de r\u00e9pondre dans l&rsquo;un ou l&rsquo;autre point de la coalition \u00ab\u00a0arc-en-ciel\u00a0\u00bb des antitrumpistes, comme le fait  <a href=\"https:\/\/www.infowars.com\/trump-predicted-it-chicago-pastor-wants-george-washington-statue-removed\/\">un pr\u00e9dicateur fameux de Chicago<\/a> \u00e0 propos d&rsquo;un des parcs de la ville (<em>out <\/em>les statues de George Washington et d&rsquo;Andrew Jackson, &ndash; on l&rsquo;avait oubli\u00e9, celui-l\u00e0), ou <a href=\"https:\/\/www.infowars.com\/ending-white-supremacy-requires-erasure-of-washington-and-jefferson-says-antifa-supporter\/\">le candidat vice-pr\u00e9sident des <em>Greens<\/em><\/a> (<em>out <\/em>George Washington et Thomas Jefferson)&#8230; Et Scott Greer, du <em>Daily Caller<\/em>, <a href=\"http:\/\/dailycaller.com\/2017\/08\/15\/its-time-to-blow-up-mount-rushmore\/\">sugg\u00e8re sarcastiquement<\/a> qu&rsquo;on liquide le Mount Rushmore, cette montagne de granit o&ugrave; sont sculpt\u00e9s les visages immenses de quatre pr\u00e9sidents (Washington, Jefferson, Lincoln et Theodore Roosevelt) dans les chevelures desquels on peut trouver tous les poux du supr\u00e9macisme blanc qu&rsquo;on veut, &ndash; une petite bombe nucl\u00e9aire ferait l&rsquo;affaire pour la montagne, tandis que l&rsquo;on prendra soin de br&ucirc;ler toutes les copies de <em>La Mort aux trousses<\/em> d&rsquo;Hitchcock, film \u00e0 la gloire du supr\u00e9macisme du granit&#8230; M\u00eame <a href=\"https:\/\/www.infowars.com\/joint-statement-from-george-bush-senior-and-jr-says-exactly-what-trump-said\/\">les Bush p\u00e8re et fils<\/a> commencent \u00e0 s&rsquo;inqui\u00e9ter de cette folie.<\/p>\n<\/p>\n<p><p>L&rsquo;affaire est claire, dans le cadre de l&rsquo;extr\u00eame excentricit\u00e9 et l&rsquo;extr\u00e9misme de son exploitation de communication propre \u00e0 la situation US. Elle rejoint, pour les USA, ce que PhG reprenait dans son <em><a href=\"http:\/\/www.dedefensa.org\/article\/charlottesville-en-france\">Journal-dde.crisis d&rsquo;hier<\/a><\/em> \u00e0 propos de la douloureuse stupeur et du d\u00e9sespoir d&rsquo;Alain Finkielkraut commentant le livre sur <em>L&rsquo;histoire mondiale de la France<\/em>, qui &laquo; <em>vide la France de toute identit\u00e9 m\u00eame narrative. La France n&rsquo;est plus qu&rsquo;une succession d&rsquo;al\u00e9as<\/em> [&#8230;] [La France est devenue]<em> un espace vide, sans qualit\u00e9, qui accueille la diversit\u00e9 en tant que telle, ce qui veut dire que nulle ant\u00e9riorit\u00e9 ne saurait pr\u00e9valoir et que nulle hi\u00e9rarchie n&rsquo;est autoris\u00e9e \u00e0 s&rsquo;exercer <\/em>[&#8230;] <strong><em>Nous ne sommes plus rien<\/em> [&#8230;] <em>et cette renonciation \u00e0 soi de la France aujourd&rsquo;hui me plonge dans la stupeur et dans une sorte de d\u00e9sespoir<\/em><\/strong>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Ainsi se trouve-t-on au c&oelig;ur du tourbillon des paradoxes que nous r\u00e9serve la Grande Crise d&rsquo;effondrement du Syst\u00e8me&#8230; On ne peut que se ranger au c\u00f4t\u00e9 de Finkielkraut lorsqu&rsquo;il parle de la France parce que la France occupe une position si particuli\u00e8re compl\u00e8tement ancr\u00e9e dans l&rsquo;Histoire et qui contient tous les germes n\u00e9cessaires \u00e0 l&rsquo;antiSyst\u00e8me, et donc que sa sauvegarde est <strong>quelque chose qui doit \u00eatre tent\u00e9e<\/strong>. Lorsqu&rsquo;on en sollicite l&rsquo;analogie pour les USA, et suivant en cela notre logique constante de critique de l&rsquo;action d\u00e9mentielle des antitrumpistes, on est conduit \u00e0 observer que ces m\u00eames antitrumpistes, <em>Antifa<\/em>-USA en t\u00eate, se trouvent emport\u00e9s par <strong>une dynamique qui menace d&rsquo;\u00e9branler toute la structure de l&rsquo;am\u00e9ricanisme dans le chef de son socle historique<\/strong>, c&rsquo;est-\u00e0-dire d&rsquo;accompagner la formidable action de la surpuissance du Syst\u00e8me vers la destruction de ce qui op\u00e9rationnalise cette surpuissance, <strong>achevant la transmutation de la surpuissance en autodestruction<\/strong>. Ainsi l&rsquo;effondrement des USA est-il <strong>quelque chose qu&rsquo;il faut encourager<\/strong>.<\/p>\n<\/p>\n<p><p>Il est \u00e9vident que les <em>Antifa<\/em>-USA esp\u00e8rent cet effondrement, sur lequel ils b\u00e2tiront un monde meilleur (&laquo; <em>to reimagine the world without them<\/em> &raquo;), et il faut appr\u00e9cier l&rsquo;effort fourni dans l&rsquo;ent\u00eatement de l&rsquo;espoir et la poursuite de l&rsquo;utopie. Il reste qu&rsquo;on est tr\u00e8s vite conduit \u00e0 douter de la possibilit\u00e9 d&rsquo;une r\u00e9ussite de leur simple \u00ab\u00a0r\u00e9-imagination\u00a0\u00bb tant l&rsquo;\u00e9branlement tellurique qui menace les USA <strong>est immense et sur le point de d\u00e9cha&icirc;ner des forces consid\u00e9rables<\/strong>, tant eux-m\u00eames (les <em>Antifa<\/em>-USA) sont le plus souvent manipul\u00e9s par les \u00e9v\u00e9nements, sinon par l&rsquo;un ou l&rsquo;autre agent du FBI infiltr\u00e9, et donc <strong>disposant de forces d\u00e9risoires et totalement incertaines qui vont rapidement se trouver sous le feu de ripostes impr\u00e9visibles<\/strong>. Ils n&rsquo;ont pour eux aucun de ces socles qui forgent les traditions, puisqu&rsquo;ils sont occup\u00e9s \u00e0 les d\u00e9truire ; ils n&rsquo;ont comme lettres de cr\u00e9dit qu&rsquo;une suite impressionnante d&rsquo;\u00e9checs historiques et comme \u00ab\u00a0compagnons de route\u00a0\u00bb des groupes qui vont dans tous les sens et la cohorte des politiciens corrompus de Washington emport\u00e9s dans le flot de haine antitrumpiste dont on cherche encore \u00e0 comprendre la cause profonde.<\/p>\n<\/p>\n<blockquote>\n<p><p>.. Car, jusqu&rsquo;ici, et sans d\u00e9semparer, se pose cette m\u00eame lancinante question de savoir <strong>comment l&rsquo;ensemble des choses<\/strong>, &ndash; p\u00eale-m\u00eale, les <em>Antifa<\/em>-USA, \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, le <em>Deep State<\/em> et le Syst\u00e8me, &ndash; <strong>s&rsquo;est-il laiss\u00e9 emporter dans cette dynamique d\u00e9mente qui est en train de d\u00e9truire la puissante architecture de l&rsquo;am\u00e9ricanisme jusqu&rsquo;\u00e0 une sorte de 1789-hollywoodien <\/strong>? D\u00e9terrera-t-on bient\u00f4t les ossements des <em>Founding Fathers <\/em>pour les jeter aux quatre vents comme firent les r\u00e9volutionnaires de la Terreur en 1793 \u00e0 Saint-Denis, des restes des \u00ab\u00a0quarante rois qui ont fait la France\u00a0\u00bb ? <strong>Il n&rsquo;y a que le Diable<\/strong> pour commettre, au bout de son entreprise semblant irr\u00e9sistible de destruction du monde, une de ces sottises \u00ab\u00a0qui sont sa marque\u00a0\u00bb, qui compromettent brutalement toute la validit\u00e9 de l&rsquo;ouvrage.<\/p>\n<\/p>\n<p><p>&#8230; &laquo; <em>On dit m\u00eame que le diable, quand il veut, est fort bon th\u00e9ologien ; il est vrai, pourtant, qu&rsquo;il ne peut s&#8217;emp\u00eacher de laisser \u00e9chapper toujours quelque sottise, <strong>qui est comme sa signature<\/strong><\/em>. &raquo; (Ren\u00e9 Gu\u00e9non)<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Paroles et paradoxes d&rsquo;Antifa-USA 17 ao&ucirc;t 2017 &ndash; D\u00e9cid\u00e9ment, une seule formule que nous citons souvent depuis une ou deux semaines \u00e9crase aujourd&rsquo;hui toutes les autres pour d\u00e9crire la situation, c&rsquo;est-\u00e0-dire comme essentielle v\u00e9rit\u00e9-de-situation : \u00ab\u00a0la r\u00e9f\u00e9rence n&rsquo;est plus le Syst\u00e8me mais le d\u00e9sordre\u00a0\u00bb. Cela nous conduit \u00e0 devoir chaque jour modifier l&rsquo;orientation de la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[13154,13284,13281,2631,7153,5932,6115,11069,9772,2645,3006,7540,11961,2949,3973,3248],"class_list":["post-77434","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-antifa","tag-antitrumpisme","tag-charlottesville","tag-de","tag-deep","tag-diable","tag-fathers","tag-founding","tag-guenon","tag-guerre","tag-jefferson","tag-lee","tag-rushmore","tag-secession","tag-state","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77434"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77434\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}