{"id":77440,"date":"2017-08-20T09:34:29","date_gmt":"2017-08-20T09:34:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/20\/dun-temps-lautre\/"},"modified":"2017-08-20T09:34:29","modified_gmt":"2017-08-20T09:34:29","slug":"dun-temps-lautre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/20\/dun-temps-lautre\/","title":{"rendered":"D&rsquo;un temps l&rsquo;autre&#8230;"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">D&rsquo;un temps l&rsquo;autre&#8230;<\/h2>\n<\/p>\n<p><p>20 ao&ucirc;t 2017 &ndash; Au gr\u00e9 du programme de la cha&icirc;ne <em>Histoire<\/em>, que j&rsquo;appr\u00e9cie comme une compagne de bonne compagnie dans les programmes catastrophiques de t\u00e9l\u00e9vision, je tombe sur un de ces documentaires tr\u00e8s classiques, sans gu\u00e8re d&rsquo;originalit\u00e9, tr\u00e8s-politiquement correct, mais qui a le simple pouvoir d&rsquo;\u00e9veiller en moi des souvenirs pr\u00e9cis et bien documet\u00e9s. Il s&rsquo;agit d&rsquo;une revue classique des \u00e9v\u00e9nements des ann\u00e9es 1970 (<em>The Seventies<\/em>). Je regardai la chose en passant, sans trop y penser, parce que j&rsquo;en avais fort peu \u00e0 retenir et, sans doute me disais-je, rien \u00e0 en penser.<\/p>\n<\/p>\n<p><p>Il se trouve tout de m\u00eame que, durant ces ann\u00e9es-l\u00e0, j&rsquo;\u00e9tais d\u00e9j\u00e0 bien install\u00e9 dans le m\u00e9tier et je suivais, pour le quotidien o&ugrave; je travaillais, les affaires \u00e9trang\u00e8res et particuli\u00e8rement les USA. Ce n&rsquo;est pas une r\u00e9v\u00e9lation mais cela explique que, si hier je regardais vaguement ce documentaire sans beaucoup d&rsquo;\u00e2me et une attention \u00e0 mesure, par contre je retrouvais des impressions, des jugements, des appr\u00e9ciations et des sentiments anciens mais pr\u00e9cis \u00e0 propos de ces \u00e9v\u00e9nements, essentiellement aux USA. Je r\u00e9alisai soudain, &ndash; curieux comme les jugements g\u00e9n\u00e9raux mais bien enrichis se forment ou se retrouvent en fulgurance, &ndash; combien cette \u00e9poque <strong>\u00e9tait extraordinairement agit\u00e9e, parcourue d&rsquo;\u00e9v\u00e9nements d&rsquo;une rare puissance et d&rsquo;une extr\u00eame violence, et notamment, et particuli\u00e8rement, pour la situation int\u00e9rieure des USA<\/strong>. Toute la d\u00e9cennie est comme \u00e7a, jusqu&rsquo;au naufrage du pauvre Carter et de son \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/le-discours-du-malaise\">Discours du Malaise<\/a>\u00ab\u00a0, que j&rsquo;ai rappel\u00e9 r\u00e9cemment.<\/p>\n<\/p>\n<p><p>Il y avait tout, des troubles publics et un terrorisme divers, puissant et meurtrier dans les premi\u00e8res ann\u00e9es de la d\u00e9cennie : la fusillade du campus de Kent University avec plusieurs morts chez les \u00e9tudiants, les <em>Weather Underground<\/em> qui fabriquaient des bombes et les faisaient sauter \u00e0 New York ou \u00e0 Washington, les <em>Black Panters<\/em>, que le FBI pourchassait avec une f\u00e9rocit\u00e9 impitoyable et sans le moindre respect des lois, l&rsquo;enl\u00e8vement de Patricia Hearst devenant elle-m\u00eame une terroriste dans une occurrence extr\u00eame du \u00ab\u00a0syndrome de Stockholm\u00a0\u00bb o&ugrave; la victime d&rsquo;un enl\u00e8vement ou d&rsquo;une prise d&rsquo;otages finit par \u00e9pouser la cause de ses ravisseurs&#8230; <\/p>\n<\/p>\n<p><p>(Tout cela, bien entendu, sur l&rsquo;arri\u00e8re-plan ext\u00e9rieur d&rsquo;un terrorisme en pleine expansion, aussi bien du fait des Palestiniens que du fait de divers groupes clandestins plus ou moins manipul\u00e9s [plut\u00f4t plus que moins, certes], en Allemagne et en Italie surtout, avec la \u00ab\u00a0strat\u00e9gie de la tension\u00a0\u00bb des \u00ab\u00a0ann\u00e9es de plomb\u00a0\u00bb se terminant dans la trag\u00e9die de l&rsquo;enl\u00e8vement d&rsquo;Aldo Moro&#8230; Curieuse occurrence l\u00e0 aussi : Moro, enlev\u00e9 le jour de la mort de mon beau-p\u00e8re, le 19 mars 1978, et retrouv\u00e9 le jour de la mort du beau-p\u00e8re de ma future deuxi\u00e8me \u00e9pouse, le 9 mai, deux hommes que nous adorions chacun de notre c\u00f4t\u00e9, elle et moi&#8230; C&rsquo;est aussi pourquoi j&rsquo;ai toujours ressenti avec plus de force encore cette affaire Moro comme une v\u00e9ritable, une terrible trag\u00e9die qui marqua symboliquement ma vie personnelle elle-m\u00eame.)<\/p>\n<\/p>\n<p><p>Les <em>Seventies <\/em>aux USA, c&rsquo;\u00e9taient aussi le Watergate bien entendu, la d\u00e9mission de Nixon, la chute de Saigon apr\u00e8s les \u00e9pisodes de guerre du Cambodge, de 1972 au Vietnam et la \u00ab\u00a0paix\u00a0\u00bb du d\u00e9but 1973 avec le funambulesque Kissinger qui se payait fin 1973 la moiti\u00e9 d&rsquo;un Prix Nobel de la Paix, la CIA pass\u00e9e au scalpel et d\u00e9chiquet\u00e9e en 1974-1975 par un Congr\u00e8s qui \u00e9tait bien loin de ces assembl\u00e9es-croupions, hallucin\u00e9es et robotis\u00e9es qu&rsquo;il est devenu, l&rsquo;\u00e9lection de Carter dans une ambiance de tr\u00e8s grand d\u00e9sarroi national, enfin les derniers avatars jusqu&rsquo;\u00e0 la prise d&rsquo;otages de T\u00e9h\u00e9ran apr\u00e8s la seconde crise p\u00e9troli\u00e8re, la premi\u00e8re d&rsquo;octobre 1973 marquant selon moi et sans nul doute <strong>le point-<em>Om\u00e9ga<\/em> de la d\u00e9stabilisation du monde ouvrant la Grande Crise qui vient jusqu&rsquo;\u00e0 nous<\/strong>.<\/p>\n<\/p>\n<p><p>Voil\u00e0 tout ce qui repassait dans mon esprit, et bien entendu avec la question simple, sinon simpliste qui vient par automatisme aujourd&rsquo;hui \u00e0 l&rsquo;esprit : \u00ab\u00a0Allons allons, nous et moi surtout qui crions \u00e0 la crise des crises des USA, nous rendons-nous donc compte \u00e0 quel point les \u00e9v\u00e9nements int\u00e9rieurs US de cette p\u00e9riode, apr\u00e8s les troubles des ann\u00e9es 1960 qui n&rsquo;\u00e9tait pas mal non plus, <strong>valent bien largement, sinon bien au-del\u00e0 en gravit\u00e9, en intensit\u00e9, ceux que nous connaissons aujourd&rsquo;hui <\/strong>?\u00a0\u00bb Cela semble \u00e9vident jusqu&rsquo;\u00e0 \u00eatre l&rsquo;\u00e9vidence, et cela devrait logiquement temp\u00e9rer d&rsquo;autant le jugement catastrophique d&rsquo;aujourd&rsquo;hui, quant \u00e0 la gravit\u00e9 et \u00e0 l&rsquo;intensit\u00e9 des \u00e9v\u00e9nements. La r\u00e9ponse \u00e0 cette question serait donc positive, les \u00e9v\u00e9nements de ces ann\u00e9es-l\u00e0 valent bien sinon surpassent en gravit\u00e9 ceux que l&rsquo;on conna&icirc;t aujourd&rsquo;hui&#8230;<\/p>\n<\/p>\n<blockquote>\n<p><p>Et l\u00e0, un instant pour souffler, et pour encha&icirc;ner aussit\u00f4t : <strong>eh bien non, pas du tout, au contraire la r\u00e9ponse est bien n\u00e9gative, absolument n\u00e9gative !<\/strong> Il n&rsquo;y a aucune comparaison possible, je veux dire que ce n&rsquo;est pas le m\u00eame univers, ce n&rsquo;est pas la m\u00eame essence des choses. Au bout du compte, ma r\u00e9ponse est cat\u00e9gorique et les \u00e9v\u00e9nements du temps pr\u00e9sent, sans aucun rapportavec les <em>Seventies<\/em>, <strong>sont infiniment plus graves jusqu&rsquo;\u00e0 \u00eatre absolument d\u00e9cisifs, quelque chose de compl\u00e8tement d\u00e9finitif comme entre un moment d&rsquo;agitation particuli\u00e8re qui secoue le navire et le moment du Jugement dernier<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Dans les <em>Seventies <\/em>apr\u00e8s les <em>Sixties<\/em>, l&rsquo;impression \u00e9tait celle d&rsquo;attaques puissantes et diverses port\u00e9es contre des structures de gouvernement et d&rsquo;autorit\u00e9 dont la solidarit\u00e9 et m\u00eame la l\u00e9gitimit\u00e9 encore existante restaient av\u00e9r\u00e9es et n&rsquo;\u00e9taient nullement mises en cause sur le fond. M\u00eame ceux qui contestaient le gouvernement le faisaient en rebelles, <strong>c&rsquo;est-\u00e0-dire contestant certes sa l\u00e9gitimit\u00e9, mais cette l\u00e9gitimit\u00e9 existant n\u00e9cessairemen<\/strong>t. Les structures existaient, fermement en place, et si elles \u00e9taient endommag\u00e9es sans nul doute elles subsistaient et les dommages semblaient pouvoir \u00eatre r\u00e9par\u00e9es. (Reagan se posa en Grand R\u00e9parateur et tout le monde y crut.) Personne parmi les commentateurs et observateurs courants, y compris parmi les adversaires du syst\u00e8me, &ndash; lequel \u00e9tait \u00e9crit alors sans majuscule et n&rsquo;aurait certainement pas engendr\u00e9 l&rsquo;hypoth\u00e8se d&rsquo;un antisyst\u00e8me, encore moins de l&rsquo;antiSyst\u00e8me, &ndash; <strong>absolument personne n&rsquo;aurait song\u00e9 \u00e0 s&rsquo;interroger sur l&rsquo;existence m\u00eame du pays<\/strong>. Ce n&rsquo;\u00e9tait pas une question taboue, <strong>c&rsquo;\u00e9tait une interrogation sans fondement, <em>irrelevant<\/em><\/strong><em>.<\/em>.. Jusqu&rsquo;au contraire, m\u00eame : combien, \u00e0 propos du Watergate notamment, qui constituait pourtant une crise constitutionnelle de premi\u00e8re importance, ne s&rsquo;exclamaient-ils pas que la crise avait d&rsquo;abord d\u00e9montr\u00e9 la solidit\u00e9, la validit\u00e9, que dis-je, la vertu du syst\u00e8me de gouvernement qui avait r\u00e9sist\u00e9 \u00e0 la temp\u00eate avec quelle assurance et quelle \u00e9l\u00e9gance !<\/p>\n<\/p>\n<p><p>Selon une vision spatiale de la chose, je dirais que le syst\u00e8me tenait un territoire horizontal tr\u00e8s organis\u00e9 au milieu duquel il tr\u00f4nait solidement, et si des attaques nombreuses se d\u00e9roulaient sur le territoire alentour dans la profondeur, dont certaines tr\u00e8s puissantes qui p\u00e9n\u00e9traient tr\u00e8s profond\u00e9ment et marquaient des contestations sp\u00e9cifiques, parfois tr\u00e8s violentes, finalement rien ne changeait vraiment de l&rsquo;essentiel de l&rsquo;architecture centrale. <strong>La structure restait en place comme un roc sur lequel les temp\u00eates venaient se briser et \u00e0 nul moment on ne voyait que le syst\u00e8me de l&rsquo;am\u00e9ricanisme p&ucirc;t \u00eatre menac\u00e9<\/strong>. Seul et d&rsquo;une fa\u00e7on assez significative qui conduit \u00e0 lui reconna&icirc;tre une r\u00e9elle capacit\u00e9 de visionnaire, le \u00ab\u00a0Discours du Malaise\u00a0\u00bb de Carter envisageait une autre sorte de trouble que l&rsquo;on ignorait alors et qui s&rsquo;impose aujourd&rsquo;hui comme le commentaire pr\u00e9monitoire de ce que nous connaissons aujourd&rsquo;hui. (C&rsquo;est une preuve de cet aspect visionnaire reconnu, comme c&rsquo;est logique, bien apr\u00e8s le d\u00e9roulement de la chose, que l&rsquo;on en soit venu \u00e0 parler du \u00ab\u00a0Discours du Malaise\u00a0\u00bb alors que le discours ne portait pas ce nom lorsqu&rsquo;il fut prononc\u00e9 ; signe de son aspect visionnaire, un discours de 1979 fait pour 2017&#8230;)<\/p>\n<\/p>\n<p><p>Aujourd&rsquo;hui, les contestations et les violences sont diff\u00e9rentes, beaucoup moins dures et brutales mais terriblement marquantes du point de vue psychologique, grandies d\u00e9mesur\u00e9ment par l&rsquo;\u00e9cho de la communication. Aucune attaque ne peut s&rsquo;\u00e9quivaloir en intensit\u00e9 \u00e0 celles que nous conn&ucirc;mes dans les <em>Seventies <\/em>apr\u00e8s les <em>Sixties<\/em>, <strong>mais cela n&rsquo;importe pas car la psychologie a sa propre perception qui est catastrophique irr\u00e9m\u00e9diablement<\/strong>. Le ph\u00e9nom\u00e8ne principal est l&rsquo;extraordinaire fragilit\u00e9 per\u00e7ue par la psychologie, qui marque la structure centrale, qui ne se d\u00e9structure pas mais qui, dans l&rsquo;\u00e9tape ultime beaucoup plus grave, est <strong>en \u00e9tat constant et acc\u00e9l\u00e9r\u00e9 de dissolution<\/strong>. Les temp\u00eates qui l&rsquo;assaillent sont beaucoup moins violentes mais obtiennent des r\u00e9sultats sans commune mesure <strong>parce qu&rsquo;elles s&rsquo;attaquent \u00e0 la consistance devenue sablonneuse de la structure centrale<\/strong>.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est pas le processus d&rsquo;une <em>House of Cards<\/em> qui peut s&rsquo;\u00e9crouler d&rsquo;un coup, c&rsquo;est celui d&rsquo;un ch\u00e2teau de sable qui se dissout \u00e0 une vitesse acc\u00e9l\u00e9r\u00e9e. Tout le monde qui pr\u00eate attention au ph\u00e9nom\u00e8ne sent et constate cela : <strong>nous sommes pass\u00e9 du territoire solide des terres fermes et des roches dures comme du granit aux \u00e9difices friables construits sur des sables mouvants et qui se d\u00e9font de l&rsquo;int\u00e9rieur<\/strong>. Le tissu social n&rsquo;agit pas selon des formations structur\u00e9es elles-m\u00eames et frappant dur mais finalement ais\u00e9ment identifiables et donc contr\u00f4lables, mais selon des mar\u00e9es irr\u00e9sistibles et insaisissables qui minent la texture devenue infiniment fragile, toujours avec cet \u00e9l\u00e9ment du rythme infernal de la communication qui ne cesse d&rsquo;affaiblir les psychologies \u00e0 mesure de la friabilit\u00e9 de la structure devenue ch\u00e2teau de sable, et agit sur la perception dans ce sens. Ainsi n&rsquo;est-il nul besoin d&rsquo;\u00e9v\u00e9nements extr\u00eamement brutaux pour qu&rsquo;observateurs et commentateurs \u00e9voquent \u00e0 chaque instant, aussit\u00f4t, et participant ainsi au d\u00e9litement g\u00e9n\u00e9ral, une \u00ab\u00a0<a href=\"http:\/\/www.zerohedge.com\/news\/2017-08-19\/hugh-smith-we-need-social-revolution\">seconde r\u00e9volution<\/a>\u00ab\u00a0, une \u00ab\u00a0<a href=\"http:\/\/buchanan.org\/blog\/americas-second-civil-war-127520\">seconde<\/a> <a href=\"http:\/\/www.breitbart.com\/video\/2017\/08\/18\/rush-limbaugh-cusp-second-civil-war\/\">guerre civile<\/a>\u00a0\u00bb ou une \u00ab\u00a0<a href=\"http:\/\/www.zerohedge.com\/news\/2017-08-18\/retired-green-beret-warns-domestic-destabilization-underway\">Civil War<\/a>\u00ab\u00a0, et plus g\u00e9n\u00e9ralement \u00ab\u00a0<a href=\"http:\/\/theduran.com\/the-death-of-a-nation\/\">la fin d&rsquo;une nation<\/a>\u00a0\u00bb sans autre forme de proc\u00e8s, avec pour toutes ces choses le r\u00e9sultat qu&rsquo;on devine, avec un naturel qui sollicite l&rsquo;\u00e9vidence elle-m\u00eame, avec la psychologie qui, dans cette \u00e9poque o&ugrave; la r\u00e9alit\u00e9 s&rsquo;est dissoute comme du sable, impose sa propre perception d&rsquo;une dissolution du syst\u00e8me de l&rsquo;am\u00e9ricanisme et de ses structures se transformant en ruines d&rsquo;elles-m\u00eames comme le ch\u00e2teau de sable min\u00e9 par les mar\u00e9es, qui se succ\u00e8dent de plus en plus vite, dont l&rsquo;effet est de plus en plus rapide.<\/p>\n<\/p>\n<blockquote>\n<p><p>Ainsi en est-il de la Grande Crise d&rsquo;effondrement du Syst\u00e8me : <strong>la dissolution et l&rsquo;effritement plus que l&rsquo;effondrement<\/strong>, insaisissable, incontr\u00f4lable, d\u00e9j\u00e0 si avanc\u00e9e et proche du terme. <strong>Nous sommes si loin de l&rsquo;univers des <em>Sixties-Seventies<\/em><\/strong>&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>J&rsquo;ajouterais en conclusion ceci qui constitue pour moi un constant sujet de stup\u00e9faction m\u00eame si j&rsquo;en connais bien la raison. Dans les <em>Sixties-Seventies<\/em>, nous \u00e9tions tous, dans le monde entier, t\u00e9moins directs et absolument concern\u00e9s, angoiss\u00e9s ou satisfaits, de ce que nous croyions \u00eatre l&rsquo;agonie de l&rsquo;Am\u00e9rique et qui ne le fut pas finalement. Aujourd&rsquo;hui, il y a <strong>cette extraordinaire ignorance, m\u00e9lange d&rsquo;indiff\u00e9rence et de d\u00e9sint\u00e9r\u00eat pour parvenir \u00e0 distinguer cette <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> de la dissolution de l&rsquo;Am\u00e9rique<\/strong> qu&rsquo;on peut ais\u00e9ment d\u00e9couvrir dans la prolif\u00e9ration extraordinaire de la communication. Ce complet isolement de chacun de nous dans un individualisme qui se satisfait de l&rsquo;univers factice du simulacre rassurant que nous offre la grossi\u00e8re propagande de l&rsquo;<em>entertainment <\/em>et de la philosophie de l&rsquo;optimisme, fait de nous des spectateurs qui regardent sans voir et se r\u00e9jouissent par automatisme de la seule satisfaction de l&rsquo;instant de ce qui n&rsquo;est m\u00eame pas la caverne de Platon, qui est tout juste le simulacre en carton-p\u00e2te de la caverne de Platon. <strong>\u00ab\u00a0Bling-bling\u00a0\u00bb fait le commentateur et les applaudissements ordonn\u00e9s par l&rsquo;affichage automatique \u00e9clatent<\/strong>. <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D&rsquo;un temps l&rsquo;autre&#8230; 20 ao&ucirc;t 2017 &ndash; Au gr\u00e9 du programme de la cha&icirc;ne Histoire, que j&rsquo;appr\u00e9cie comme une compagne de bonne compagnie dans les programmes catastrophiques de t\u00e9l\u00e9vision, je tombe sur un de ces documentaires tr\u00e8s classiques, sans gu\u00e8re d&rsquo;originalit\u00e9, tr\u00e8s-politiquement correct, mais qui a le simple pouvoir d&rsquo;\u00e9veiller en moi des souvenirs pr\u00e9cis&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[9009,8596,3104,2631,4119,9442,13294,3965,13295,7114,1267,2626],"class_list":["post-77440","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-caverne","tag-chateau","tag-cia","tag-de","tag-platon","tag-sable","tag-seventies","tag-simulacre","tag-sixties","tag-structure","tag-terrorisme","tag-watergate"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77440"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77440\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}