{"id":77458,"date":"2017-08-30T15:21:54","date_gmt":"2017-08-30T15:21:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/30\/harvey-le-deluge-et-les-pompes-de-la-flotus\/"},"modified":"2017-08-30T15:21:54","modified_gmt":"2017-08-30T15:21:54","slug":"harvey-le-deluge-et-les-pompes-de-la-flotus","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/08\/30\/harvey-le-deluge-et-les-pompes-de-la-flotus\/","title":{"rendered":"<em>Harvey<\/em>-le-D\u00e9luge et les pompes de la FLOTUS"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>Harvey<\/em>-le-D\u00e9luge et les pompes de la FLOTUS<\/h2>\n<\/p>\n<p><p>30 ao&ucirc;t 2017 &ndash; L&rsquo;impitoyable <em>Harvey<\/em>, le cyclone qui a d\u00e9vast\u00e9 et continue \u00e0 d\u00e9vaster la ville de Houston sous des flots d&rsquo;inondations qui semblent le D\u00e9luge lui-m\u00eame, est l&rsquo;occasion, une fois de plus, de mesurer encore plus haut et toujours en phase d&rsquo;acc\u00e9l\u00e9ration le degr\u00e9 de folie affectant tant de citoyens de la grande R\u00e9publique ; tous ceux-l\u00e0 dont nous parlons sur ce site et dont je vous parle \u00e0 l&rsquo;instant, frapp\u00e9s des spasmes orgasmo-maniaques du <a href=\"http:\/\/www.dedefensa.org\/article\/ptsd-trump-pathologie-de-dc-la-folle\">FTSD-Trump<\/a> transmu\u00e9s op\u00e9rationnellement en une haine qui a elle aussi des allures bibliques.<\/p>\n<\/p>\n<p><p>Le fait simple de cet \u00e9pisode est qu&rsquo;il n&rsquo;y a pas seulement ceci que des millions de m\u00e8tres cubes d&rsquo;eau sont en train de d\u00e9truire une ville de plus de 2 millions d&rsquo;habitants. (Perspectives du fric que tout cela va co&ucirc;ter, prospective tr\u00e8s am\u00e9ricaniste : <em>Harvey<\/em>, s&rsquo;il consent \u00e0 s&rsquo;arr\u00eater dans quatre-cinq jours, devrait co&ucirc;ter selon certaines estimations \u00ab\u00a0r\u00e9alistes\u00a0\u00bb par rapport \u00e0 l&rsquo;optimisme officiel entre $500 et $1.000 milliards au Texas. Je crois qu&rsquo;on est en train de laisser <em>Katrina <\/em>loin derri\u00e8re, &ndash; d&rsquo;autant plus que <em>Harvey <\/em>a lanc\u00e9 un tentacule <a href=\"http:\/\/www.zerohedge.com\/news\/2017-08-30\/harvey-makes-2nd-landfall-western-louisiana-after-pummeling-texas-50-inches-rain\">vers la Louisiane<\/a> o&ugrave; l&rsquo;on craint justement une r\u00e9plique de<em> Katrina<\/em>.) Mais non, il y a aussi, et il y a eu d&rsquo;abord sinon essentiellement pour certains pendant au moins une journ\u00e9e, les pompes (les chaussures) de Melania Trump, la FLOTUS (<em>First Lady of the United States<\/em>).<\/p>\n<\/p>\n<p><p>Plusieurs articles incr\u00e9dules sur cette \u00ab\u00a0affaire\u00a0\u00bb, devant un constat de plus en plus lourd au fil des heures en marge du d\u00e9placement du couple Trump \u00e0 Houston. Tr\u00e8s vite pendant la journ\u00e9e d&rsquo;hier, le flot des tweets-citoyens a de plus en plus d\u00e9laiss\u00e9 les cons\u00e9quences en cours de <em>Harvey <\/em>pour le cas de la FLOTUS. D&rsquo;abord arriv\u00e9e et mont\u00e9e dans <em>Air Force One<\/em> certes avec une paire de chaussures d\u00e9nonc\u00e9e comme un peu trop chic et sexy pour la trag\u00e9die de Houston malgr\u00e9 l&rsquo;\u00e9quipement \u00ab\u00a0op\u00e9rationnel\u00a0\u00bb (blouson kaki, pantalons noirs, lunettes de soleil type <em>Ray-Ban<\/em>) ; ensuite occup\u00e9e pendant le voyage jusqu&rsquo;\u00e0 Houston \u00e0 changer de v\u00eatements (plus l\u00e9gers pour la temp\u00e9rature mais toujours aussi \u00ab\u00a0op\u00e9rationnels\u00a0\u00bb) et de chaussures pour des \u00ab\u00a0tennis\u00a0\u00bb de sport un peu plus appropri\u00e9es quoiqu&rsquo;un peu trop blanches pour les rues mar\u00e9cageuses de la capitale texane. Melania Trump a tout faux, et c&rsquo;est bien la preuve qu&rsquo;elle est l&rsquo;\u00e9pouse incons\u00e9quente, arrogante et insensible aux souffrances des gens d&rsquo;un fasciste-raciste notoire venu se repa&icirc;tre du spectacle de la noyade in\u00e9galitaire des Africains-Am\u00e9ricains de Houston qui coulent plus vite que les blancs supr\u00e9maciste \u00e7a c&rsquo;est s&ucirc;r, et cibl\u00e9s par <em>Harvey<\/em>-le-d\u00e9luge, lui-m\u00eame aussit\u00f4t soup\u00e7onn\u00e9 des m\u00eames tares. Nous sommes au royaume d&rsquo;une sorte de d\u00e9cha&icirc;nement d&rsquo;un fantasme constant qui a trouv\u00e9, l&rsquo;espace d&rsquo;une journ\u00e9e, un \u00e9l\u00e9ment d\u00e9risoire de plus o&ugrave; fixer sa puissance et sa fureur de haine.<\/p>\n<\/p>\n<p><p>Puisqu&rsquo;il faut bien traiter s\u00e9rieusement le probl\u00e8me, puisqu&rsquo;il y a l\u00e0 ampleur nationale dans une puissance d&rsquo;ampleur mondiale, j&rsquo;y sacrifie comme le fait <em>The Federalist<\/em>, le 29 ao&ucirc;t, sous la plume de Britt McHenry, et sous ce titre-l\u00e0 : &laquo;<em> Si vous \u00eates plus pr\u00e9occup\u00e9s par les chaussures de Melania que par les victimes de Harvey, c&rsquo;est vous qui \u00eates le probl\u00e8me.<\/em> &raquo; Je vous mets quelques phrases en un anglo-am\u00e9ricain pas trop difficile \u00e0 comprendre, d&rsquo;autant que le sens appara&icirc;t \u00e9vident, et d&rsquo;ailleurs r\u00e9sum\u00e9 par cette derni\u00e8re phrase (la conclusion) qui dit : &laquo; <em>Aussi enfantin et insignifiant que cela soit, les adversaires de Trump trouveront toujours quelque chose jusqu&rsquo;au plus minuscule pour ridiculiser<\/em> [Trump]<em> ou l&rsquo;attaquer alors que notre pays est en train d&rsquo;affronter une tr\u00e8s grave catastrophe qui devrait susciter son unit\u00e9. <\/em>&raquo;&#8230;<\/p>\n<\/p>\n<p><p>Extraits de l&rsquo;article&#8230; &laquo; <em>Instead of focusing on our first lady choosing to accompany her husband to a state dealing with utter wreckage, cynics chose to fixate on her choice of fashion because \u00ab\u00a0optics.\u00a0\u00bb Newsflash: If you align with a public perception that&rsquo;s more concerned with a woman&rsquo;s shoes instead of the hundreds of thousands who are forced to abandon their flooded homes, then you&rsquo;re part of the problem. Quite simply, you belong to the divisive, accusatory political witch-hunt aimed at tearing the social seams of this country apart.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Furthermore, the people criticizing FLOTUS for her \u00ab\u00a0elitist\u00a0\u00bb attire are the same people who lambast President Trump for not being \u00ab\u00a0presidential\u00a0\u00bb enough. I&rsquo;m not here to argue with every instance that particular point of view has been vocalized. But if the supposed informality of Trump&rsquo;s appearance and colloquial speech is a source of ire, it&rsquo;s hypocritical to get bothered by our first lady&rsquo;s immaculate, polished appearance. Shouldn&rsquo;t she be \u00ab\u00a0presidential\u00a0\u00bb enough for you?<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; &#8230;<em>Like most things when it comes to the quick-to-judge extremists of the Left, the outrage was for nothing. No matter what the presidential family does or happens to wear, it&rsquo;s never going to be good enough for the staunch Left. <\/em><em>As inappropriate and juvenile as it is, Trump combatants will always find something miniscule to ridicule or attack despite our country facing much larger issues that require unity<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>On dira que le sujet est bien d\u00e9risoire et insignifiant et l&rsquo;on n&rsquo;aura pas tort, sans nul doute, tout en n&rsquo;ayant pas tout \u00e0 fait raison. <strong>C&rsquo;est justement parce qu&rsquo;il est d\u00e9risoire qu&rsquo;il est important et donc nullement insignifiant en raison de la place qui lui est accord\u00e9e <\/strong>&hellip; Certes, faire d&rsquo;une telle question d&rsquo;un style de chaussure ou de telle sorte de v\u00eatements par ailleurs adapt\u00e9s aux circonstances, l&rsquo;objet d&rsquo;une campagne de tweets aussi consid\u00e9rable que celle qui concerne les victimes de <em>Harvey <\/em>qui continue \u00e0 l&rsquo;instant \u00e0 \u00eatre en plein d\u00e9veloppement, <strong>voil\u00e0 qui n&rsquo;est nullement insignifiant<\/strong>.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est pas tant la critique qui est remarquable d&rsquo;ailleurs, car l&rsquo;on trouve souvent de ces petites pol\u00e9miques pour animer nos pauvres esprits toujours ardents \u00e0 tenter de prouver leur libre-arbitre et leur ind\u00e9pendance de penser, <strong>que cette critique-l\u00e0, dans ce moment-l\u00e0, dans les circonstances g\u00e9n\u00e9rales qu&rsquo;on sait<\/strong>. Que le d\u00e9risoire soit hauss\u00e9 \u00e0 un niveau si important alors que se d\u00e9veloppe cette \u00e9norme catastrophe naturelle, justement alors que les personnes vis\u00e9es vont sur place pour observer les conditions de cette catastrophe, alors qu&rsquo;il y a ce contexte crisique de la \u00ab\u00a0guerre civile de communication\u00a0\u00bb qu&rsquo;on conna&icirc;t depuis d\u00e9sormais plus d&rsquo;un an du d\u00e9cha&icirc;nement de haine contre Trump &#038; Cie, voil\u00e0 qui est loin d&rsquo;\u00eatre insignifiant. Cela implique que <strong>rien, absolument rien n&rsquo;arr\u00eate ce d\u00e9ferlement diluvien de haine, un <em>Harvey <\/em>de la haine, que soul\u00e8vent Trump et tout ce qui approche Trump<\/strong>.<\/p>\n<\/p>\n<p><p>Il y avait eu tr\u00e8s vite une pol\u00e9mique lors de <em>Katrina<\/em>, en Septembre 2005, mais il s&rsquo;agissait de la fa\u00e7on d&rsquo;organiser les secours, de l&rsquo;efficacit\u00e9 de l&rsquo;agence f\u00e9d\u00e9rale FEMA, critiqu\u00e9e par de nombreuses voix, de la n\u00e9cessit\u00e9 de faire intervenir des forces militaires \u00e0 sa place, Garde Nationale, US Army, etc. <strong><a href=\"http:\/\/www.dedefensa.org\/article\/militarisation-usa-le-dod-maitre-du-jeu\">Ces pol\u00e9miques<\/a> d\u00e9rivaient directement <a href=\"http:\/\/www.dedefensa.org\/article\/militarisation-usa-la-qdr-katrina\">des conditions de la catastrophe<\/a><\/strong> et, m\u00eame si elles pouvaient appara&icirc;tre comme un \u00e9l\u00e9ment de division du fait d&rsquo;appr\u00e9ciations diff\u00e9rentes sinon partisanes entre centres de pouvoir concurrents, elles n&rsquo;en concernaient pas moins <strong>les conditions d&rsquo;une action g\u00e9n\u00e9rale face \u00e0 la catastrophe<\/strong>. Le cas d&rsquo;aujourd&rsquo;hui (d&rsquo;hier) est compl\u00e8tement diff\u00e9rent : il fait passer la pol\u00e9mique \u00e0 la haine d&rsquo;un personnage politique et de son entourage, sans aucun rapport avec les conditions de la catastrophe. On passe du domaine de la pol\u00e9mique politique \u00e0 partir d&rsquo;\u00e9v\u00e9nements r\u00e9els \u00e0 celui du comportement des psychologies, quels que soit l&rsquo;\u00e9v\u00e9nement et sa r\u00e9alit\u00e9.<\/p>\n<\/p>\n<blockquote>\n<p><p>Loin de moi l&rsquo;id\u00e9e de prendre la d\u00e9fense, ni de Trump ni des pompes de la FLOTUS, justement parce qu&rsquo;il ne s&rsquo;agit pas du tout de cette question, de ce probl\u00e8me, de cette interrogation, de ce parti pris, de cet \u00ab\u00a0engagement\u00a0\u00bb, etc., &ndash; <strong>vraiment rien de semblable, en aucune fa\u00e7on<\/strong>. L&rsquo;int\u00e9r\u00eat est bien dans <strong>cette pr\u00e9gnance collective d&rsquo;une psychologie<\/strong> d&rsquo;un segment entier de la population am\u00e9ricaniste, <strong>anim\u00e9e par la puissance quasi fascinatoire du courant progressiste-soci\u00e9tal<\/strong>, non pas comme \u00e9l\u00e9ment d&rsquo;une opinion publique et d&rsquo;un jugement politique, &ndash; m\u00eame si ce courant peut par ailleurs \u00eatre jug\u00e9 et appr\u00e9ci\u00e9 comme tel, &ndash; <strong>mais comme une drogue absolument, qui aveugle sur tout \u00e0 propos de ce qui n&rsquo;est pas un argument en sa faveur, et qui retourne tout en rien d&rsquo;autre qu&rsquo;un argument en sa faveur<\/strong>. Il s&rsquo;agit de quelque chose qui est un monde en soi, constitutif de soi et avec sa logique propre, qui ne r\u00e9pond qu&rsquo;\u00e0 ses seuls caract\u00e8res propres, qui se domine et s&rsquo;ordonne en tant que tel et qui, dans l&rsquo;esprit de ceux qui en sont affect\u00e9s, domine et ordonne tout le reste comme si tout le reste n&rsquo;existait pas en tant que tel.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Je me rends bien compte que je ne fais que poursuivre l&rsquo;observation d&rsquo;un ph\u00e9nom\u00e8ne dont l&rsquo;originalit\u00e9, la puissance et la dur\u00e9e, et d&rsquo;une certaine fa\u00e7on la nouveaut\u00e9 par sa radicalit\u00e9 absolue et sa vitesse d&rsquo;intervention, sont maintenant bien identifi\u00e9e. Mais cette identification doit justement conduire \u00e0 une attention renouvel\u00e9e, <strong>car nous ne savons rien des cons\u00e9quences de cette chose si compl\u00e8tement sans pr\u00e9c\u00e9dent <\/strong>dans les diverses circonstances o&ugrave; elle se d\u00e9veloppe. Nous ne savons pas o&ugrave; tout cela peut mener et nous mener, nous savons seulement de plus en plus assur\u00e9ment que l&rsquo;outil central de la bataille est psychologique et que la communication y tient donc le r\u00f4le d&rsquo;outil principal, et que tout cela, consid\u00e9r\u00e9e la hauteur de l&rsquo;enjeu qui n&rsquo;est rien moins que le destin des &Eacute;tats-Unis d&rsquo;Am\u00e9rique, est d&rsquo;une importance si consid\u00e9rable. Ainsi, je ne m&rsquo;avancerais pas tant que cela en observant que les cons\u00e9quences psychologiques, c&rsquo;est-\u00e0-dire politiques, de <em>Harvey<\/em>, parall\u00e8lement \u00e0 l&rsquo;\u00e9tendue et au gigantisme de la catastrophe, pourraient \u00eatre tr\u00e8s importantes, <strong>bien plus importantes que celles de <em>Katrina<\/em><\/strong> qui a constitu\u00e9 en 2005 un \u00e9norme \u00e9branlement des structures politiques des USA, mais aussi et encore plus fortement consid\u00e9r\u00e9es sur le long terme, <strong>des structures psychologiques justement<\/strong>.<\/p>\n<\/p>\n<p><p>Ainsi en est-il, par cons\u00e9quent, du sort qu&rsquo;il faut faire aux chaussures de la FLOTUS, dont, par ailleurs, l&rsquo;\u00e9l\u00e9gance et l&rsquo;allure ont, l\u00e0 aussi d&rsquo;une fa\u00e7on r\u00e9v\u00e9latrice, constitu\u00e9 un argument de plus pour la sombre haine qui s&rsquo;est ainsi d\u00e9cha&icirc;n\u00e9e. Il est assur\u00e9, \u00e0 mon sens, <strong>que se joue une partie qui nous d\u00e9passe, qui utilise les \u00eatres et les attributs des \u00eatres \u00e0 sa fa\u00e7on, et dans un sens que nous ne pouvons ni imaginer ni pr\u00e9voir<\/strong>. <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Harvey-le-D\u00e9luge et les pompes de la FLOTUS 30 ao&ucirc;t 2017 &ndash; L&rsquo;impitoyable Harvey, le cyclone qui a d\u00e9vast\u00e9 et continue \u00e0 d\u00e9vaster la ville de Houston sous des flots d&rsquo;inondations qui semblent le D\u00e9luge lui-m\u00eame, est l&rsquo;occasion, une fois de plus, de mesurer encore plus haut et toujours en phase d&rsquo;acc\u00e9l\u00e9ration le degr\u00e9 de folie&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[12379,12662,3602,5516,1368,13334,3099,2639],"class_list":["post-77458","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-chaussures","tag-flotus","tag-haine","tag-houston","tag-katrina","tag-melanie","tag-psychologie","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77458"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77458\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}