{"id":77486,"date":"2017-09-13T10:03:43","date_gmt":"2017-09-13T10:03:43","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/09\/13\/le-climate-change-etdedefensaorg\/"},"modified":"2017-09-13T10:03:43","modified_gmt":"2017-09-13T10:03:43","slug":"le-climate-change-etdedefensaorg","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/09\/13\/le-climate-change-etdedefensaorg\/","title":{"rendered":"Le <em>climate change <\/em>et\u00a0<em>dedefensa.org<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le <em>climate change <\/em>et <em>dedefensa.org<\/em><\/h2>\n<\/p>\n<p><p>13 septembre 2017 &ndash; Justement venu en ces temps d&rsquo;ouragans particuli\u00e8rement catastrophiques, <a href=\"http:\/\/www.dedefensa.org\/article\/voici-comment-votre-monde-pourrait-prendre-fin\">un article de ce jour<\/a> pourrait faire croire \u00e0 des obtus vraiment tr\u00e8s-courts que la publication de cet article incite \u00e0 penser qu&rsquo;il refl\u00e8te la position de <em>dedefensa.org<\/em> sur la question de la \u00ab\u00a0crise climatique\u00a0\u00bb, et la mienne par cons\u00e9quent. La r\u00e9ponse est n\u00e9gative mais <strong>le probl\u00e8me, dans notre cas, est int\u00e9ressant : \u00ab\u00a0Au fait, qu&rsquo;est-ce qu&rsquo;ils pensent, \u00e0 <em>dedefensa.org<\/em> ?\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>Ce genre de supputations m&rsquo;a donn\u00e9 l&rsquo;id\u00e9e de sugg\u00e9rer une r\u00e9ponse, c&rsquo;est-\u00e0-dire de la retrouver puisqu&rsquo;elle se trouve enfouie dans les archives fort nombreuses du site (12.821 articles \u00e0 ce jour). C&rsquo;est en reprenant des parties d&rsquo;un texte publi\u00e9 le <a href=\"http:\/\/www.dedefensa.org\/article\/inconnaissance-et-climat-derrida-deleuze-cie-1\">10 ao&ucirc;t 2011<\/a> et intitul\u00e9 &laquo; <em>Inconnaissance et climat, \u00ab\u00a0Derrida, Deleuze &#038; Cie\u00a0\u00bb<\/em> &raquo; qu&rsquo;on peut effectivement disposer de cette r\u00e9ponse. Le th\u00e8me n&rsquo;en est pas exactement le climat et sa crise mais plut\u00f4t ce que nous nommons, dans le jargon <em>dde.org<\/em>, dans l'\u00a0\u00bbarsenal dialectique\u00a0\u00bb du site (la rubrique <em>Glossaire.dde<\/em>), &ndash; l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-linconnaissance\">inconnaissance<\/a>.<\/p>\n<\/p>\n<p><p>En 2011, le th\u00e8me de la \u00ab\u00a0crise climatique\u00a0\u00bb \u00e9tait d&rsquo;actualit\u00e9, il l&rsquo;\u00e9tait depuis plusieurs ann\u00e9es, et aujourd&rsquo;hui il l&rsquo;est toujours et m\u00eame plus que jamais. Le th\u00e8me, bien entendu<strong> c&rsquo;est une pol\u00e9mique \u00e0 fortes couleurs d&rsquo;id\u00e9ologisation, entre les partisans de la th\u00e8se du d\u00e9r\u00e8glement climatique du fait de l&rsquo;action humaine et les climatosceptiques qui s&rsquo;opposent \u00e0 cette th\u00e8se<\/strong>. Les ouragans r\u00e9cents et toujours en cours ont \u00e9t\u00e9 plus que jamais l&rsquo;occasion d&rsquo;un nouveau paroxysme de cette pol\u00e9mique qui est assez int\u00e9ressante parce qu&rsquo;elle est <strong>suffisamment confuse pour qu&rsquo;on trouve des pro-Syst\u00e8me et des antiSyst\u00e8me des deux c\u00f4t\u00e9s<\/strong> (\u00ab\u00a0pro-Syst\u00e8me et antiSyst\u00e8me\u00a0\u00bb, et sachant ce que ces choses veulent dire, &ndash; ma classification essentielle, universelle des positions dans cette guerre terrible et en cours, et m\u00eame ma classification exclusive). La vigueur de la chose est telle qu&rsquo;aux USA, o&ugrave; l&rsquo;on vient d\u00e9j\u00e0 de s&rsquo;\u00e9triper \u00e0 ce propos avec le retrait des USA de l&rsquo;Accord de Paris sur la limitation des \u00e9missions de CO2, on pol\u00e9mique en ce moment m\u00eame du c\u00f4t\u00e9 anti-Trump\/progressistes-soci\u00e9taux autour de l&rsquo;id\u00e9e assez nouvelle et tr\u00e8s <em>sexy <\/em>qu&rsquo;il faudrait <strong>inculper et condamner les climatosceptiques [ex-<s>eurosceptiques<\/s><\/strong><strong>]<\/strong>. (The Washington <em>Times<\/em> du <a href=\"http:\/\/www.washingtontimes.com\/news\/2017\/sep\/11\/climate-change-activists-want-punishment-for-skept\/\">12 septembre 2017<\/a> : &laquo; \u00ab\u00a0<em>Climate change denial should be a crime,\u00a0\u00bb declared the Sept. 1 headline in the Outline. Mark Hertsgaard argued in a Sept. 7 article in the Nation, titled \u00ab\u00a0Climate Denialism Is Literally Killing Us,\u00a0\u00bb that \u00ab\u00a0murder is murder\u00a0\u00bb and \u00ab\u00a0we should punish it as such.\u00a0\u00bb<\/em> &raquo;)<\/p>\n<\/p>\n<p><p>Bien, revenons-en \u00e0 cet article. Au d\u00e9part, il y a des r\u00e9flexions d&rsquo;un lecteur, non pas directement sur la crise climatique mais bien sur le concept d&rsquo;inconnaissance et sur la position de <em>dedefensa.org<\/em> \u00e0 cet \u00e9gard, qui le rapprocherait, selon ce lecteur, des th\u00e8ses des d\u00e9constructeurs du type Deleuze &#038; Derrida. Le th\u00e8me g\u00e9n\u00e9ral est notre\/mon refus (d&rsquo;autant que le texte est \u00e9crit \u00e0 la premi\u00e8re personne-PhG) de chercher disons ce que nous voudrions \u00eatre la v\u00e9rit\u00e9 dans certaines pol\u00e9miques, et cela au nom du principe d&rsquo;inconnaissance. L\u00e0-dessus, dans le cours du texte, vient se glisser <strong>comme exemple d\u00e9monstratif suppl\u00e9mentaire de cette position<\/strong>, le cas de la pol\u00e9mique sur le climat, et mon d\u00e9sint\u00e9r\u00eat complet de r\u00e9pondre \u00e0 cette question portant sur la pol\u00e9mique elle-m\u00eame : \u00ab\u00a0Qui a raison, des climatosceptiques ou des autres ?\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Je ne vais pas reprendre tout le texte, qui peut \u00eatre consult\u00e9 dans nos archives, en suivant l&rsquo;URL <a href=\"http:\/\/www.dedefensa.org\/article\/inconnaissance-et-climat-derrida-deleuze-cie-1\">d\u00e9j\u00e0 r\u00e9f\u00e9renc\u00e9<\/a>. Je vais en prendre quelques extraits, notamment la premi\u00e8re partie introductive sur l&rsquo;inconnaissance pour ceux qui sont d\u00e9j\u00e0 \u00e9puis\u00e9 \u00e0 l&rsquo;id\u00e9e de la longueur <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-linconnaissance\">du texte sur ce sujet<\/a> dans <em>Glossaire.dde<\/em> ; et puis, dans le reste, ce qui a trait au climat&#8230; Je pense en effet qu&rsquo;on comprend mal sinon pas du tout la position exprim\u00e9e sur la question du climat, &ndash; <strong>\u00e0 la relecture, j&rsquo;y adh\u00e8re aujourd&rsquo;hui autant que j&rsquo;y adh\u00e9rai \u00e0 l&rsquo;\u00e9t\u00e9 2011 quand je l&rsquo;ai \u00e9crite<\/strong>, &ndash; si l&rsquo;on n&rsquo;a pas lu l&rsquo;introduction sur l&rsquo;inconnaissance&#8230;<\/p>\n<\/p>\n<p><p>_______________________<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&raquo; Inconnaissance et climat&#8230;<\/h2>\n<\/p>\n<p><p>&raquo; Voici donc mes r\u00e9ponses [au lecteur] <em>GEO<\/em> transform\u00e9es en une sorte de manifeste g\u00e9n\u00e9ral. On y trouvera une certaine vigueur parce que le sujet le m\u00e9rite, qui est une approche de notre position par rapport \u00e0 la crise \u00e0 la lumi\u00e8re de trois th\u00e8mes diff\u00e9rents. Il (le sujet de la chose) est tout simplement fondamental et, pour mon compte, participe \u00e0 son heure au r\u00e8glement de l&rsquo;existence, de l&rsquo;orientation et des ambitions de ce site. Toutes les pr\u00e9cisions \u00e0 cet \u00e9gard, y compris sous une forme appuy\u00e9e, sont bonnes pour permettre au lecteur de mieux se situer par rapport \u00e0 <em>dedefensa.org<\/em>, en fonction de la lecture qu&rsquo;il fera de cet article. Il se d\u00e9cidera alors en connaissance de cause.<\/p>\n<\/p>\n<p><p>&raquo; Je suis \u00e0 peu pr\u00e8s l&rsquo;ordre des sujets abord\u00e9s par <em>GEO<\/em> dans son intervention, sous forme de trois \u00ab\u00a0rubriques\u00a0\u00bb : la question de l&rsquo;inconnaissance (d\u00e9finition, usage et utilit\u00e9, etc.) ; la question de l'\u00a0\u00bbultramodernisme\u00a0\u00bb de <em>dedefensa.org<\/em> (et de moi-m\u00eame, par cons\u00e9quent) ; la question de la pol\u00e9mique sur le climat. Mais ce classement est pour la facilit\u00e9, et l&rsquo;on verra que la r\u00e9flexion, venue de l&rsquo;inconnaissance qui n&rsquo;est attach\u00e9 \u00e0 aucune chapelle de la \u00ab\u00a0connaissance\u00a0\u00bb terrestre, sait prendre ses aises quand cela lui importe. Bref, il s&rsquo;agit bien d&rsquo;un texte d&rsquo;une port\u00e9e g\u00e9n\u00e9rale, et qui doit \u00eatre pris comme tel par les lecteurs.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">&raquo; 1). L&rsquo;inconnaissance est \u00ab\u00a0antimoderne\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>&raquo; L&rsquo;inconnaissance est une posture intellectuelle fix\u00e9e et non un maniement quelconque de quelque r\u00e9alit\u00e9 que ce soit. Son avantage absolument fondamental est d&rsquo;\u00eatre <strong>en dehors<\/strong> du Syst\u00e8me, pour \u00e9viter l&#8217;emprisonnement par le Syst\u00e8me, c&rsquo;est-\u00e0-dire l&#8217;emprisonnement dans un espace mental, une conception, une pens\u00e9e d\u00e9sert\u00e9es par la v\u00e9rit\u00e9. L&rsquo;inconnaissance est le refus d&rsquo;une \u00ab\u00a0connaissance\u00a0\u00bb o&ugrave; l&rsquo;objet de cette connaissance lie le sujet recherchant cette connaissance \u00e0 lui-m\u00eame [cet objet], jusqu&rsquo;\u00e0 la d\u00e9formation et, dans les conditions pr\u00e9sentes, \u00e0 la subversion ; dans le cas de la \u00ab\u00a0connaissance\u00a0\u00bb du Syst\u00e8me, qui est ce qui m&rsquo;importe, et la seule chose \u00e0 la fois possible et s\u00e9rieuse aujourd&rsquo;hui, je serais ainsi irr\u00e9m\u00e9diablement li\u00e9 \u00e0 ce que j&rsquo;estime \u00eatre le Mal, et sans aucune chance de pouvoir r\u00e9sister efficacement \u00e0 cause de sa surpuissance. Le refus de <strong>cette<\/strong> connaissance se fait au profit du savoir, qui contient ou re\u00e7oit des connaissances ma&icirc;tris\u00e9es, qui dispose de l&rsquo;exp\u00e9rience et, par-dessus tout, qui est \u00e9clair\u00e9 par l&rsquo;intuition (l&rsquo;intuition haute) ; et, gr\u00e2ce \u00e0 cela, pr\u00e9servant toute l&rsquo;ind\u00e9pendance et l&rsquo;autonomie du sujet et assurant sa position en dehors.<\/p>\n<\/p>\n<p><p>&raquo; Effectivement, l&rsquo;essentiel dans l&rsquo;inconnaissance est que le savoir permet de se situer en dehors du Syst\u00e8me, au contraire de la connaissance. Le fait de vouloir se situer en dehors du Syst\u00e8me pr\u00e9suppose le jugement (qui est le mien) que la v\u00e9rit\u00e9 a d\u00e9sert\u00e9 le monde puisque le monde est devenu le Syst\u00e8me et que le Syst\u00e8me est par d\u00e9finition, pour moi, antinomique \u00e0 la v\u00e9rit\u00e9, ou, plus substantiellement, qu&rsquo;il est la non-v\u00e9rit\u00e9 puisqu&rsquo;il est, comme je l&rsquo;affirme, repr\u00e9sentation <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\">du Mal<\/a> sinon <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-mal-i\">le Mal<\/a> lui-m\u00eame. En me tenant en dehors, appuy\u00e9 sur mon savoir, je peux esp\u00e9rer retrouver la v\u00e9rit\u00e9 et lutter contre le Syst\u00e8me, situation impossible dans le cas de la connaissance o&ugrave; je suis en dedans le Syst\u00e8me. Il n&rsquo;est <strong>nulle part<\/strong> question d'\u00a0\u00bbignorance\u00a0\u00bb dans tout cela, cette absence \u00e9tant contenue par ailleurs absolument dans la d\u00e9finition du concept, &ndash; \u00ab\u00a0inconnaissance\u00a0\u00bb signifiant \u00ab\u00a0<strong>ni<\/strong> ignorance, ni connaissance\u00a0\u00bb. (S&rsquo;il est question d&rsquo;appr\u00e9cier qualitativement, &ndash; justement, &ndash; la question de la connaissance, je dirais \u00e9videmment que l&rsquo;inconnaissance refuse la \u00ab\u00a0connaissance\u00a0\u00bb quantitative au profit de la connaissance qualitative, d\u00e9termin\u00e9e gr\u00e2ce \u00e0 l&rsquo;existence des autres composants du savoir situ\u00e9s hors du Syst\u00e8me, dont le couronnement que constitue l&rsquo;intuition haute.)<\/p>\n<\/p>\n<p><p>&raquo; Il me semble bien contestable de d\u00e9finir cela comme \u00ab\u00a0une s\u00e9curit\u00e9\u00a0\u00bb (puisqu&rsquo;il est question dans les remarques cit\u00e9es de notre lecteur de \u00ab\u00a0fausse s\u00e9curit\u00e9\u00a0\u00bb pour caract\u00e9riser l&rsquo;inconnaissance), alors que je parle, moi, d&rsquo;un socle solide o&ugrave; s&rsquo;appuyer, pour r\u00e9sister, et r\u00e9sister avec tant de force qu&rsquo;on puisse passer d&rsquo;une posture d\u00e9fensive \u00e0 une posture offensive (c&rsquo;est dans le texte extrait de <em>dde.crisis<\/em>). La r\u00e9sistance, ce n&rsquo;est pas une \u00ab\u00a0s\u00e9curit\u00e9\u00a0\u00bb. Ceux qui d\u00e9battent dans la basse-cour (<em>dito<\/em>, le Syst\u00e8me), en pleine \u00ab\u00a0connaissance\u00a0\u00bb et \u00ab\u00a0v\u00e9rit\u00e9 scientifique\u00a0\u00bb para&icirc;t-il, sont bien plus \u00ab\u00a0en s\u00e9curit\u00e9\u00a0\u00bb ; ils sont ministres, experts, publicitaires, grands chefs de grandes entreprises, habitu\u00e9s de Davos en janvier de chaque ann\u00e9e, ou alors ils sont en vacances. Une \u00ab\u00a0s\u00e9curit\u00e9\u00a0\u00bb, l&rsquo;inconnaissance ? Qu&rsquo;on vienne \u00e0 ma place, et on go&ucirc;tera le sentiment de \u00ab\u00a0s\u00e9curit\u00e9\u00a0\u00bb que l&rsquo;on y trouve. La r\u00e9sistance, une \u00ab\u00a0s\u00e9curit\u00e9\u00a0\u00bb ? Cela, sur le sens des mots, c&rsquo;est du Derrida, Deleuze &#038; Cie. (Voir plus loin.)<\/p>\n<\/p>\n<p><p>&raquo; S&rsquo;il fallait donner une r\u00e9f\u00e9rence psychopolitique concr\u00e8te \u00e0 l&rsquo;inconnaissance, je dirais qu&rsquo;elle fait partie du domaine des \u00ab\u00a0antimodernes\u00a0\u00bb, bien <a href=\"http:\/\/www.dedefensa.org\/article-notre_raison_d_etre_extrait_de_la_rubrique_de_defensa_de_defensa_volume_20_n20_du_10_juillet_2005_21_07_2005.html?admin=1\">connu<\/a> par ici. La phrase fondamentale de l&rsquo;antimoderne, les lecteurs de ce site le savent, c&rsquo;est &laquo;<em>Celui qui peut dire \u00ab\u00a0nous modernes\u00a0\u00bb tout en d\u00e9non\u00e7ant le moderne<\/em>&raquo;. L&rsquo;inconnaissance peut dire \u00ab\u00a0je connais le Syst\u00e8me par mon savoir et je refuse de m&rsquo;y compromettre sous pr\u00e9texte de &lsquo;connaissance&rsquo;, pour pouvoir mieux le combattre et le d\u00e9noncer\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&raquo; Ce qui encha&icirc;ne bien entendu sur ce qui suit&hellip;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">&raquo; 2). Derrida, Deleuze &#038; Cie<\/h3>\n<\/p>\n<p><p>&raquo; Bien entendu, il va de soi que je ne suis pas \u00ab\u00a0aussi ultramoderne\u00a0\u00bb qu&rsquo;un type-Derrida (et je dirais plut\u00f4t, pour aller au plus radical et au plus \u00ab\u00a0habit\u00e9\u00a0\u00bb \u00e0 mon avis, et avis venu des bonnes lectures : qu&rsquo;un \u00ab\u00a0type-Deleuze\u00a0\u00bb). Tout cela, ce jugement \u00e0 l&#8217;emporte-pi\u00e8ce d&rsquo;\u00eatre \u00ab\u00a0ultramoderne\u00a0\u00bb, excusez-moi, est un peu gratuit, un peu d\u00e9risoire, &ndash; un peu, comment dirais-je, &ndash; c&rsquo;est cela, un \u00ab\u00a0jugement ultra-moderne\u00a0\u00bb. J&rsquo;en dis quelques mots puisqu&rsquo;il le faut, mais surtout pour introduire la pi\u00e8ce de r\u00e9sistance du propos, j&rsquo;ai nomm\u00e9 notre \u00ab\u00a0plat du jour\u00a0\u00bb, Derrida, Deleuze &#038; Cie. D&rsquo;abord, le constat \u00e9vident que si j&rsquo;\u00e9tais \u00ab\u00a0ultramoderne\u00a0\u00bb (ou \u00ab\u00a0postmoderne\u00a0\u00bb), je ne voudrais pas d\u00e9construire (d\u00e9structurer) ce monde lui-m\u00eame postmoderne puisque ce monde r\u00e9pondrait \u00e0 mon attente, et d&rsquo;ailleurs je n&rsquo;en aurais pas l&rsquo;id\u00e9e puisqu&rsquo;\u00e9tant postmoderne et \u00ab\u00a0croyant\u00a0\u00bb de la chose, je ne croirais pas une seconde que ce monde f&ucirc;t structur\u00e9 puisque postmoderne, et par d\u00e9finition d\u00e9structur\u00e9.<\/p>\n<\/p>\n<p><p>&raquo; Mais revenons aux r\u00e9alit\u00e9s. Je suis <a href=\"http:\/\/fr.wiktionary.org\/wiki\/contemporain\">contemporain<\/a> (&laquo;<em>Qui est du m\u00eame temps que quelqu&rsquo;un ou quelque chose<\/em>&raquo;) d&rsquo;un univers (un Syst\u00e8me) qui s&rsquo;est d\u00e9velopp\u00e9 en une p\u00e9riode de temps fulgurante, sous la forme d\u00e9sormais affich\u00e9e d&rsquo;un Syst\u00e8me anthropomorphique, selon les descriptions pr\u00e9monitoires des Derrida, Deleuze &#038; Cie, comme s&rsquo;ils \u00e9taient les scribes z\u00e9l\u00e9s et extr\u00eamement accommodants d&rsquo;un d\u00e9veloppement qui nous d\u00e9passe tous, et eux en premier sans aucun doute, &ndash; ils ex\u00e9cutent, c&rsquo;est tout. Etant contemporain sur le tard de cet univers Derrida, Deleuze &#038; Cie, je choisis de me placer en dehors de lui (inconnaissance) pour tenter de le d\u00e9construire. Si cela semble \u00e0 certains la m\u00eame m\u00e9thode que celle de Derrida, Deleuze &#038; Cie, peu me chaut, mais je sais d&rsquo;\u00e9vidence, d&rsquo;intuition et de savoir assur\u00e9s, que cela est <strong>contre leur<\/strong> univers. Ainsi s&rsquo;\u00e9tablissent des syst\u00e8mes antiSyst\u00e8me&#8230;<\/p>\n<\/p>\n<p><p>[&#8230;]<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">&raquo; 3). Le sexe climatique des anges<\/h3>\n<\/p>\n<p><p>&raquo; Le climat ? Parlons du climat, puisque cela se fait et que l&rsquo;on y est souvent invit\u00e9.<\/p>\n<\/p>\n<p><p>&raquo; La question du climat est pour moi le type m\u00eame de la connaissance qui encha&icirc;ne \u00e0 l&rsquo;objet, &ndash; un v\u00e9ritable d\u00e9bat deleuzien. Nul n&rsquo;est s&ucirc;r de rien, les chiffres abondent, auxquels tout le monde fait dire ce que chacun veut, des forces \u00e9normes de pression et d&rsquo;intoxication li\u00e9es au Syst\u00e8me croisent et recroisent dans le d\u00e9bat \u00e0 pleine vapeur, et pas moins chez les climatosceptiques (Mobil Exxon et les p\u00e9troliers, le groupe Murdoch, les partisans de libre-\u00e9change en mode <em>turbo<\/em>, une tr\u00e8s forte majorit\u00e9 des \u00e9lus r\u00e9publicains US si bien qu&rsquo;on peut dire que les climatosceptiques ont la majorit\u00e9 au moins \u00e0 la Chambre des Repr\u00e9sentants du Congr\u00e8s, etc.). La pol\u00e9mique est aussit\u00f4t de la partie et, avec elle, dans un tel cadre, la manipulation, et l&rsquo;on est emport\u00e9 dans ce pi\u00e8ge qui colle comme de la glu, qui est le Syst\u00e8me. Le tour est jou\u00e9, tellement pr\u00e9visible, &ndash; il ne s&rsquo;agit plus du climat mais du Syst\u00e8me, c&rsquo;est-\u00e0-dire du Mal. Voil\u00e0 pour la connaissance dans ce cas ; si je c\u00e9dais \u00e0 descendre dans l&rsquo;ar\u00e8ne, je ne suis s&ucirc;r que d&rsquo;une chose, pour mon compte, &ndash; je serais encha&icirc;n\u00e9 au Syst\u00e8me, broy\u00e9, concass\u00e9, parce qu&rsquo;il est infiniment plus surpuissant que moi. Donc, je refuse cette \u00ab\u00a0connaissance\u00a0\u00bb-l\u00e0 de leurs d\u00e9bats sur le climat.<\/p>\n<\/p>\n<p><p>&raquo; Cela n&rsquo;implique en rien ni l&rsquo;indiff\u00e9rence ni l&rsquo;ignorance, puisqu&rsquo;il est question d&rsquo;inconnaissance. Sur cette question du climat, le savoir me dit ceci&hellip; L&rsquo;effondrement du monde, notamment avec son \u00ab\u00a0eschatologisation\u00a0\u00bb, avec la terrifiante d\u00e9gradation de l&rsquo;environnement et la perception du d\u00e9sordre du climat par rapport \u00e0 notre organisation, avec d&rsquo;autres multiples ph\u00e9nom\u00e8nes chaotiques qui commencent par la crise de notre psychologie (le plus grave), l&rsquo;effondrement du monde n&rsquo;est pas l&rsquo;objet d&rsquo;un d\u00e9bat pour mon compte ; c&rsquo;est un fait \u00e9vident de tous les jours, une <strong>\u00e9vidence<\/strong> colossale et \u00e9crasante que j&rsquo;observe de ma position d&rsquo;inconnaissance, la d\u00e9vastation du monde qui a tout \u00e0 voir avec le d\u00e9sordre de la modernit\u00e9, et rien avec le classement scientifique en degr\u00e9s centigrades dans un sens ou l&rsquo;autre, et en pourcentage de responsabilit\u00e9 humaine ou autre. L&rsquo;\u00e9vidence, c&rsquo;est-\u00e0-dire la v\u00e9rit\u00e9 du monde, cela existe pour l&rsquo;inconnaissance, c&rsquo;est m\u00eame ce qui lui permet de s&rsquo;affirmer comme telle puisque cela fait partie de son savoir.<\/p>\n<\/p>\n<p><p>&raquo; Plus encore, vu de mon observatoire d&rsquo;inconnaissance, j&rsquo;ai deux remarques \u00e0 faire. On verra qu&rsquo;elles n&rsquo;ont nul besoin de la \u00ab\u00a0connaissance\u00a0\u00bb ni de leurs d\u00e9bats sur la \u00ab\u00a0v\u00e9rit\u00e9 scientifique\u00a0\u00bb, &ndash; laquelle est, au vu de l&rsquo;histoire r\u00e9elle, qui ne s&rsquo;interdit pas de remonter au-del\u00e0 de la Renaissance, une aventure sacr\u00e9ment impudente qui prend parfois des allures, elle aussi, de simulacre. (\u00ab\u00a0V\u00e9rit\u00e9 scientifique\u00a0\u00bb, &ndash; doux oxymore, quand tu nous tiens&hellip;)<\/p>\n<\/p>\n<p><p>&raquo; 1). Le d\u00e9bat se fait d&rsquo;abord, dans sa rage pol\u00e9mique la plus extr\u00eame, autour de l&rsquo;id\u00e9e du \u00ab\u00a0r\u00e9chauffement climatique <strong>d&ucirc; aux activit\u00e9s humaines<\/strong>\u00ab\u00a0. Bel exemple de sophisme, que Deleuze ne d\u00e9mentirait pas, &ndash; et ils en sont tous coupables, de ce sophisme, des partisans du r\u00e9chauffement dans ces conditions aux climatosceptiques. Car cet intitul\u00e9 est faux, archi-faux, une imposture, une inversion comme seul notre Syst\u00e8me sait en accoucher&hellip; Le Syst\u00e8me, justement ; le seul intitul\u00e9 qui vaille est bien : d\u00e9bat pour ou contre \u00ab\u00a0le r\u00e9chauffement climatique <strong>d&ucirc; aux activit\u00e9s du Syst\u00e8me<\/strong>\u00ab\u00a0. La diff\u00e9rence est apocalyptique.<\/p>\n<\/p>\n<p><p>&raquo; Tout le d\u00e9bat-pol\u00e9mique sur le climat est compl\u00e8tement subverti par cette imposture s\u00e9mantique. Je suis s&ucirc;r qu&rsquo;elle n&rsquo;a pas \u00e9t\u00e9 voulue, parce qu&rsquo;on fait chez les robots beaucoup moins dans le complot qu&rsquo;on ne croit et que le sens des mots, finalement, on s&rsquo;en fout ; m\u00eame les \u00ab\u00a0institutionnels\u00a0\u00bb n&rsquo;y voient que du feu, de Al Gore (pour) \u00e0 Mobil Exxon (contre), &ndash; sauf qu&rsquo;ils auraient une mauvaise surprise si le pot aux roses leur \u00e9tait r\u00e9v\u00e9l\u00e9, et qu&rsquo;on leur annon\u00e7ait qu&rsquo;ils d\u00e9battent, horreur, pour ou contre \u00ab\u00a0le r\u00e9chauffement climatique <strong>d&ucirc; aux activit\u00e9s du Syst\u00e8me<\/strong>\u00ab\u00a0. Quant aux purs, ceux qui croient vraiment \u00e0 la \u00ab\u00a0v\u00e9rit\u00e9 scientifique\u00a0\u00bb et s&rsquo;\u00e9charpent en son nom, ils ont toute mon affection et toute mon affliction, car ils sont prisonniers de leur \u00ab\u00a0connaissance\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&raquo; (D\u00e9tail \u00ab\u00a0op\u00e9rationnel\u00a0\u00bb : si j&rsquo;ai tendance \u00e0 prendre en compte, sans me battre pour elle, certes, la th\u00e8se des pro-\u00ab\u00a0r\u00e9chauffement climatique&hellip;\u00a0\u00bb, c&rsquo;est d&rsquo;abord parce que c&rsquo;est elle qui me rapproche le plus d&rsquo;une mise en accusation du Syst\u00e8me [parce qu&rsquo;elle fait remonter aux origines du \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-dechainement-de-la-matiere\">d\u00e9cha&icirc;nement de la Mati\u00e8re<\/a>\u00ab\u00a0], &ndash; et alors qu&rsquo;elle n&rsquo;est tout de m\u00eame pas une monstruosit\u00e9 insupportable par rapport \u00e0 la \u00ab\u00a0v\u00e9rit\u00e9 scientifique\u00a0\u00bb, r\u00e9f\u00e9rence immens\u00e9ment vertueuse d\u00e9couverte par le groupe Murdoch autour de 2006, avec la mont\u00e9e m\u00e9diatique des climatosceptiques. On retrouve la ligne de ma pens\u00e9e.)<\/p>\n<\/p>\n<p><p>&raquo; 2). La chose effective et concr\u00e8te qui m&rsquo;importe effectivement dans cette affaire, ce n&rsquo;est ni le r\u00e9chauffement, ni le refroidissement, ni le \u00ab\u00a0tout va tr\u00e8s bien, <em>misses<\/em> la marquise\u00a0\u00bb, etc., tous ces jugements \u00e0 l&#8217;emporte-pi\u00e8ce pour le temps pr\u00e9sent et d\u00e9pendant de chiffres, lesquels sont tordus jusqu&rsquo;\u00e0 ce tout le monde leur fasse dire ce que chacun veut &hellip; La seule chose qui m&rsquo;importe, c&rsquo;est le d\u00e9sordre qu&rsquo;introduit cette pr\u00e9vision ou cette appr\u00e9ciation du d\u00e9r\u00e8glement climatique (voil\u00e0 une expression plus s\u00e9rieuse, &ndash; quoiqu&rsquo;il en soit du climat), d\u00e9sordre qui est <strong>d\u00e9j\u00e0<\/strong> dans les psychologies. Pas besoin de \u00ab\u00a0connaissance\u00a0\u00bb du sujet pour constater cela, l&rsquo;intuition fait l&rsquo;affaire : ce d\u00e9sordre est psychologique et il est d\u00e9j\u00e0 l\u00e0, bien pr\u00e9sent, lancinant&hellip; Confirmation statistique ? (Les statistiques confirment toujours, des ann\u00e9es plus tard, fort pompeusement et \u00e0 prix \u00e9lev\u00e9, l&rsquo;invention du fil \u00e0 couper le beurre.) Voici que <a href=\"http:\/\/www.upi.com\/Top_News\/US\/2011\/07\/11\/Poll-Most-see-disasters-few-climate-turn\/UPI-71691310419193\/print\/#ixzz1RrgFPk1x\">44% des citoyens US<\/a> croient \u00e0 la \u00ab\u00a0th\u00e9orie\u00a0\u00bb du r\u00e9chauffement climatique, contre 51% en 2009 et 71% en 2007  ; la m\u00eame ann\u00e9e que celle des 44% (2011), on nous dit que 77% croient \u00e0 un redoublement des temp\u00eates, de l&rsquo;instabilit\u00e9 climatique par rapport aux tendances admises, donc du d\u00e9sordre. Et d\u00e8s qu&rsquo;il y a une temp\u00eate aujourd&rsquo;hui, g\u00e9missent les climatosceptiques, on l&rsquo;<a href=\"http:\/\/www.telegraph.co.uk\/comment\/columnists\/christopherbooker\/8627584\/The-Phoenix-dust-storm-shows-that-whatever-the-weather-its-always-climate-change.html\">attribue<\/a> au \u00ab\u00a0changement\/r\u00e9chauffement climatique du\/indu aux activit\u00e9s humaines\u00a0\u00bb ; eh oui, et qui t&rsquo;a fait roi ? Voil\u00e0 la deuxi\u00e8me chose tr\u00e8s importante de la pol\u00e9mique du climat : le d\u00e9sordre psychologique est parmi nous, quand on m\u00e9lange la perception du d\u00e9sastre et le \u00ab\u00a0tout va tr\u00e8s bien, <em>misses<\/em> la marquise\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&raquo; Je parle, moi, du Syst\u00e8me et pas du climat, car c&rsquo;est lui, le Syst\u00e8me, qui r\u00e8gne et r\u00e8gle tout dans les conditions que je d\u00e9cris par ses caract\u00e8res (son herm\u00e9tisme, son monopole de surpuissance), et qui constitue les donn\u00e9es essentielles de ma r\u00e9flexion. Si les climatosceptiques l'\u00a0\u00bbemportaient\u00a0\u00bb (hypoth\u00e8se farfelue, que j&rsquo;\u00e9voquais dans <em>dde.crisis<\/em> pour l&rsquo;image d\u00e9velopp\u00e9e, car personne n&#8217;emportera rien dans ce d\u00e9bat), cela ne signifierait pas que le climat est conforme \u00e0 leurs calculs fi\u00e9vreux mais que l&rsquo;\u00e9quilibre au sein du Syst\u00e8me a pench\u00e9 vers eux, c&rsquo;est tout, et cela sans que le Syst\u00e8me ne change rien de sa course, et cette modification de fortune de l&rsquo;\u00e9quilibre interne gr\u00e2ce aux activit\u00e9s m\u00e9diatiques notoirement efficaces et vertueuses du groupe Murdoch, au temps de sa splendeur et maintenant. Je ne participe pas \u00e0 ces d\u00e9bats-l\u00e0, parce que j&rsquo;estime qu&rsquo;une participation serait une marque d&rsquo;all\u00e9geance au Syst\u00e8me, donc une victoire du Syst\u00e8me sur moi, &ndash; outre que ces d\u00e9bats m&rsquo;abaisseraient consid\u00e9rablement parce que ce sont des d\u00e9bats r\u00e9gl\u00e9s par le Syst\u00e8me, pour poursuivre son simulacre type-Derrida, Deleuze &#038; Cie. De l\u00e0 l&rsquo;inconnaissance : je n&rsquo;ai pas besoin de prendre connaissance de ces d\u00e9bats au sein du Syst\u00e8me, et de \u00ab\u00a0me situer\u00a0\u00bb (de me compromettre) par rapport \u00e0 eux, qui n&rsquo;ont aucune r\u00e9alit\u00e9 ontologique (Derrida, Deleuze &#038; Cie, entrepreneurs en destruction d&rsquo;ontologie par d\u00e9finition). Je ne veux pas m&rsquo;exposer sans d\u00e9fense, dans mon humaine faiblesse dont je ne peux \u00eatre tout \u00e0 fait assur\u00e9, au pi\u00e8ge de la s\u00e9duction de la <strong>fascination du Mal<\/strong>, car c&rsquo;est bien cela que repr\u00e9sente le Syst\u00e8me. (Pour \u00e9couter les sir\u00e8nes, rappelle Mattei, Ulysse avait bien pris soin de se faire lier au mat.) &#8230; J&rsquo;ai mes priorit\u00e9s, dont l&rsquo;essentielle est de r\u00e9sister. Je r\u00e9serve mon attention \u00e0 d&rsquo;autres choses plus importantes, qui d\u00e9pendent du savoir et de l&rsquo;intuition haute que privil\u00e9gie l&rsquo;inconnaissance, o&ugrave; l&rsquo;on peut fermement s&rsquo;appuyer ; et enfin c&rsquo;est \u00eatre en dehors, alors que c&rsquo;est d\u00e9sormais et n\u00e9cessairement en dehors du Syst\u00e8me qui tient le monde dans ses griffes que se trouve la v\u00e9rit\u00e9.<\/p>\n<\/p>\n<p><p>&raquo; Je veux refuser absolument l&rsquo;id\u00e9e d&rsquo;une substance du Syst\u00e8me, lui d\u00e9nier absolument la moindre essence et le moindre sens, lui opposer, du dehors, hors de port\u00e9e de sa subversion, une fermet\u00e9 intraitable, qui le fasse hurler de rage, &ndash; et puis, le renvoyer au grand magasin des simulacres, avec ses proches, Derrida, Deleuze &#038; Cie. Cela ne m&#8217;emp\u00eache pas, inconnaissance et savoir aidant justement, de ne pas ignorer \u00e0 qui j&rsquo;ai affaire, et comment&#8230; (On peut se reporter \u00e0 <em>dedefensa.org<\/em> au jour le jour, ci-dessous.) L&rsquo;important est d&rsquo;opposer une fronti\u00e8re \u00e0 l&rsquo;imposture.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">&raquo; 3bis). Le climat, le JSF et Ron Paul<\/h3>\n<\/p>\n<p><p>&raquo; \u00ab\u00a0Et si dans cinq ans nous sommes confront\u00e9s \u00e0 l&rsquo;\u00e9vidence d&rsquo;un refroidissement que restera-t-il de la validit\u00e9 des deux d\u00e9marches, celle du consensus utilitaire et celle de l&rsquo;inconnaissance ?\u00a0\u00bb Je dois avouer que, pour mon compte (l&rsquo;inconnaissance), je ne comprends pas le sens de cette question ; quant au \u00ab\u00a0consensus\u00a0\u00bb dont il est question, je le cherche vainement dans cette basse-cour \u00e9tourdissante de caquetage qu&rsquo;est devenu le commentaire dans notre Syst\u00e8me, et particuli\u00e8rement dans le contexte du \u00ab\u00a0<em>climate change<\/em>\u00ab\u00a0, qui est une abracadabrantesque foire d&#8217;empoigne.<\/p>\n<\/p>\n<p><p>&raquo; L&rsquo;inconnaissance n&rsquo;est absolument pas ignorance et elle n&rsquo;en est en rien une opinion d\u00e9pendant de l&rsquo;\u00e9volution de l&rsquo;objet de cette opinion (ce qui est le cas, au contraire, de la \u00ab\u00a0connaissance\u00a0\u00bb). C&rsquo;est, au contraire, une position permettant l&rsquo;adaptation \u00e0 l&rsquo;\u00e9volution des \u00e9v\u00e9nements, selon le savoir qui est en nous. Je n&rsquo;ignore pas la question du climat ni m\u00eame les diverses hypoth\u00e8ses, et j&rsquo;ai m\u00eame les convictions qu&rsquo;on a vues l\u00e0-dessus. L&rsquo;inconnaissance n&rsquo;implique rien d&rsquo;une position dogmatique d&rsquo;opinion, ce serait \u00e9videmment n&rsquo;y rien entendre ; elle ne procure aucune paralysie en quoi que ce soit, bien au contraire puisqu&rsquo;elle est libre, puisque situ\u00e9e en dehors. Elle ne procurera aucune paralysie si nous avons une p\u00e9riode glaciaire dans 5 ans ou si c&rsquo;est la fin du monde le 12 d\u00e9cembre 2012 comme l&rsquo;annonce le calendrier Maya ; franchement, ces hypoth\u00e8ses n&rsquo;ont pour moi aucun int\u00e9r\u00eat dans ce d\u00e9bat ; le moment venu, je saurais m&rsquo;y adapter, j&rsquo;en ai vu d&rsquo;autres, ou bien je ne le saurais pas si c&rsquo;est mon destin&hellip; (Pour la fin du monde, en effet, c&rsquo;est tout de m\u00eame une exp\u00e9rience tr\u00e8s particuli\u00e8re, y compris pour l'\u00a0\u00bbinconnaissant\u00a0\u00bb.)<\/p>\n<\/p>\n<p><p>&raquo; Je peux, par contre, d\u00e9crire des actions et des \u00e9volutions qui, chez <em>dedefensa.org<\/em>, sont le produit l&rsquo;inconnaissance. L\u00e0, je redescends sur terre car ces exemples sont, comme on dit, \u00ab\u00a0basiques\u00a0\u00bb, et cela pour montrer que l&rsquo;inconnaissance n&rsquo;est en aucun cas une sorte de fuite dans l&rsquo;\u00e9ther de l&rsquo;abstraction en toute \u00ab\u00a0s\u00e9curit\u00e9\u00a0\u00bb&#8230; Je prends deux exemples tr\u00e8s sp\u00e9cifiques, le reste des sujets consid\u00e9r\u00e9s suivant la m\u00eame d\u00e9marche : Ce que nous avons fait sur le JSF (depuis 2002 pour le site) et sur Ron Paul (depuis 2007) ressort de l&rsquo;inconnaissance. Dans le travail sur ces deux sujets, j&rsquo;estime qu&rsquo;il y aurait \u00e0 d\u00e9compte intuitif entre 10% (pour Ron Paul) et 15% (pour le JSF) de \u00ab\u00a0connaissance\u00a0\u00bb (c&rsquo;est-\u00e0-dire des informations venues du sujet et qui m&rsquo;encha&icirc;neraient au sujet si j&rsquo;en restais l\u00e0), le reste \u00e9tant fait d&rsquo;exp\u00e9rience et d&rsquo;intuition qui rel\u00e8vent absolument du savoir, &ndash; y compris la d\u00e9cision de consid\u00e9rer ces sujets comme extr\u00eamement importants, et d&rsquo;int\u00e9r\u00eat universel, cette d\u00e9cision essentiellement dues \u00e0 l&rsquo;intuition&#8230; &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le climate change et dedefensa.org 13 septembre 2017 &ndash; Justement venu en ces temps d&rsquo;ouragans particuli\u00e8rement catastrophiques, un article de ce jour pourrait faire croire \u00e0 des obtus vraiment tr\u00e8s-courts que la publication de cet article incite \u00e0 penser qu&rsquo;il refl\u00e8te la position de dedefensa.org sur la question de la \u00ab\u00a0crise climatique\u00a0\u00bb, et la mienne&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3392,10250,3228,13388,13386,13051,8809,11201,13387],"class_list":["post-77486","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-climatique","tag-climatosceptique","tag-crise","tag-dde-org","tag-deconstructeurs","tag-derrida","tag-geo","tag-inconnaissance","tag-position"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77486"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77486\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}