{"id":77500,"date":"2017-09-21T07:19:10","date_gmt":"2017-09-21T07:19:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/09\/21\/labyrinthe-du-simulacre-de-lonu-a-freeman\/"},"modified":"2017-09-21T07:19:10","modified_gmt":"2017-09-21T07:19:10","slug":"labyrinthe-du-simulacre-de-lonu-a-freeman","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/09\/21\/labyrinthe-du-simulacre-de-lonu-a-freeman\/","title":{"rendered":"Labyrinthe du simulacre, de l&rsquo;ONU \u00e0 Freeman"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Labyrinthe du simulacre, de l&rsquo;ONU \u00e0 Freeman<\/h2>\n<\/p>\n<p><p>21 septembre 2017 &ndash; La<a href=\"https:\/\/sputniknews.com\/us\/201709201057546723-trump-kelly-reaction\/\"> premi\u00e8re image<\/a> qui me vient et me reste \u00e0 l&rsquo;esprit est celle, largement reprise, du g\u00e9n\u00e9ral Kelly, le directeur de cabinet de Trump, t\u00eate baiss\u00e9e, le menton dans ses mains crois\u00e9es, puis une main se cachant le visage pourtant toujours baiss\u00e9, au moment o&ugrave; Trump commence son discours. On l&rsquo;imagine compl\u00e8tement catastroph\u00e9, d\u00e9courag\u00e9, <strong>se r\u00e9p\u00e9tant \u00ab\u00a0Mais qu&rsquo;est-ce qu&rsquo;il est encore en train nous de sortir ?\u00a0\u00bb<\/strong> A c\u00f4t\u00e9 de lui, Melania Trump, le visage ferm\u00e9, imp\u00e9n\u00e9trable, regardant elle aussi son mari, ou bien peut-\u00eatre, &ndash; oui, \u00e0 bien la regarder et pour peu que l&rsquo;on ait l&rsquo;imagination vagabonde, on pourrait voir se peindre sur ce m\u00eame visage une question assez proche, du genre : \u00ab\u00a0Mais qu&rsquo;est-ce qu&rsquo;il raconte, ce type ?\u00a0\u00bb A la tribune, lui, i<strong>l nucl\u00e9arise la Cor\u00e9e du Sud avant de passer \u00e0 l&rsquo;Iran<\/strong>. Netanyahou bondit de joie !<\/p>\n<\/p>\n<p><p>Il y a aussi <a href=\"https:\/\/www.rt.com\/news\/403879-lavrov-us-russia-fix-relations-tillerson\/\">cet article de RT<\/a> qui cite ce jugement de Lavrov \u00e0 propos de l&rsquo;intervention de Trump (&laquo; <em>Un discours remarquable<\/em> &raquo;), en \u00e9voquant une perspective idyllique o&ugrave; les USA et la Russie r\u00e9tabliraient des relations normales parce que Trump a affirm\u00e9 la n\u00e9cessit\u00e9 du respect de toutes les souverainet\u00e9s (de toutes les nations souveraines) dans les relations internationales ; puis martelant des r\u00e9serves colossales et tr\u00e8s inqui\u00e8tes, Lavrov, implicitement tr\u00e8s critique sur les interventions d\u00e9vastatrices de Trump dans les passages de son discours sur les crises nord-cor\u00e9enne et iranienne. (D\u00e9sormais, il semble bien qu&rsquo;il y ait une crise iranienne.) L&rsquo;attitude de Trump est <strong>compl\u00e8tement incoh\u00e9rente \u00e0 maints \u00e9gards<\/strong>, et cela ne peut nous surprendre puisque sa \u00ab\u00a0diplomatie\u00a0\u00bb <strong>est de <a href=\"http:\/\/www.dedefensa.org\/article\/une-journee-dans-la-vie-de-the-donald\">l&rsquo;ordre de la t\u00e9l\u00e9-r\u00e9alit\u00e9<\/a><\/strong> : d&rsquo;un c\u00f4t\u00e9, affirmant le principe intangible de la souverainet\u00e9 des nations dans les relations internationales, de l&rsquo;autre jugeant des comportements nationaux d&rsquo;une mani\u00e8re distordue et compl\u00e8tement intrusive, voire en faisant la promotion du <em>regime change <\/em>dans le cas du Venezuela (et implicitement de la Cor\u00e9e du Nord, et sans doute l&rsquo;Iran), <strong>sans le moindre souci de la souverainet\u00e9 nationale<\/strong>.<\/p>\n<\/p>\n<p><p>Du coup, Macron para&icirc;t excellent lorsqu&rsquo;il prononce son jugement s\u00e9v\u00e8re sur l&rsquo;attitude de Trump vis-\u00e0-vis de l&rsquo;Iran, &ndash; \u00ab\u00a0excellent\u00a0\u00bb lui, c&rsquo;est dire ! Et aussi lors de sa conf\u00e9rence de presse, lorsqu&rsquo;il rapporta des d\u00e9tails de son entretien avec Trump, justement \u00e0 propos de l&rsquo;Iran. Il expose \u00e0 Trump l&rsquo;argument qu&rsquo;il est dangereux sinon absurde de mettre en cause l&rsquo;accord actuel sous pr\u00e9texte qu&rsquo;il n&rsquo;est pas parfait, sans pr\u00e9voir une option de remplacement ; Trump a-t-il une telle option ? interroge Macron ; Trump r\u00e9pond que oui et lui expose son option de remplacement. Et Macron de commenter avec une franchise qui lui fait honneur dans cet instant : &laquo; <em>Je ne l&rsquo;ai pas comprise<\/em> &raquo;, ouvrant par l\u00e0 la voie <strong>\u00e0 l&rsquo;hypoth\u00e8se pas si incoh\u00e9rente que Trump est un esprit incoh\u00e9rent et donc incompr\u00e9hensible<\/strong>.<\/p>\n<\/p>\n<p><p>&hellip;Mais moi-m\u00eame, qualifiant Macron d'\u00a0\u00bbexcellent\u00a0\u00bb alors qu&rsquo;il y a deux jours le site appuyait <a href=\"http:\/\/www.dedefensa.org\/article\/macron-au-microscope\">de commentaires approbateurs<\/a> un portrait incendiaire et furieux de ce m\u00eame Macron, est-ce que je n&rsquo;alimente pas ce constat irr\u00e9sistible de l&rsquo;incoh\u00e9rence, qui vaut d&rsquo;ailleurs dans la relativit\u00e9 extraordinaire qu&rsquo;il expose pour tous les avatars de cette session de l&rsquo;ONU r\u00e9sumant si bien le climat et la psychologie folle de cette \u00e9poque catastrophique ? Qui peut encore pr\u00e9tendre \u00eatre capable de ranger les choses et les actes des hommes, et par cons\u00e9quent \u00e9mettre un jugement durable et solide sur les hommes, d&rsquo;une fa\u00e7on coh\u00e9rente et soutenue, dans ce formidable <a href=\"http:\/\/www.dedefensa.org\/article\/le-tourbillon-crisique-regne\">tourbillon crisique<\/a> ?<\/p>\n<\/p>\n<p><p>Tous les commentateurs commentent et tous les \u00e9ditorialistes \u00e9ditorialisent depuis deux jours <strong>sur ces interventions \u00e0 la tribune de l&rsquo;ONU et sur la situation ainsi cr\u00e9\u00e9e<\/strong>, et moi je reste, bouche b\u00e9e, la plume suspendue. Certes, la faute essentielle, sinon exclusive du point de vue de l&rsquo;op\u00e9rationnalit\u00e9, en revient \u00e0 Trump, qui a expos\u00e9 d&rsquo;une fa\u00e7on symbolique et tonitruante du point de vue de la communication le trouble et le d\u00e9sordre qu&rsquo;il introduit dans les relations internationales, exactement \u00e0 l&rsquo;image de ceux qu&rsquo;ils d\u00e9veloppent dans la politique int\u00e9rieure de Washington D.C. depuis bient\u00f4t deux ans.<\/p>\n<\/p>\n<blockquote>\n<p><p>Mais encore une fois, Trump ne fait que mettre <strong>dans une lumi\u00e8re aveuglante, celle des spots de la t\u00e9l\u00e9-r\u00e9alit\u00e9, une situation qui se d\u00e9veloppe depuis des ann\u00e9es<\/strong> et qu&rsquo;on feint d&rsquo;ignorer, ou qu&rsquo;on n&rsquo;a pas le courage de relever, ou qu&rsquo;on est trop aveugle et d&rsquo;une psychologie trop affaiblie pour s&rsquo;en aviser. Comme l&rsquo;on disait \u00ab\u00a0le fou du roi\u00a0\u00bb, <strong>Trump est \u00ab\u00a0le fou du monde\u00a0\u00bb qui nous fait accepter l&rsquo;\u00e9vidence que le monde est comme ce roi dont un enfant s&rsquo;exclamait \u00ab\u00a0Le roi est nu !\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est pour cette raison que je crois inutile de proposer une appr\u00e9ciation acceptable et raisonnable de la situation du monde, impliquant que cette situation r\u00e9pond elle-m\u00eame \u00e0 des crit\u00e8res identifiables et compr\u00e9hensibles par la raison comme acceptables et raisonnables. C&rsquo;est impossible, tout simplement <strong>parce qu&rsquo;il n&rsquo;y a rien qui soit acceptable et raisonnable, selon l&rsquo;entendement de notre raison courante et selon la logique des dynamiques en cours, dans la situation du monde de notre \u00e9poque catastrophique<\/strong>. On comprend alors le choix, fait d&rsquo;une fa\u00e7on tout \u00e0 fait rationnelle, qui me conduit \u00e0 cette analyse s&rsquo;exprimant dans ces termes du refus d&rsquo;une d\u00e9marche intellectuelle appuy\u00e9e sur une mesure du rangement des choses et des actes et un jugement durable sur les hommes, tout cela avec l&rsquo;instrument de la raison qui se r\u00e9v\u00e8le dans ce cas impuissante et paralys\u00e9e ; on comprend alors ce choix qui fait que ce texte ne figure pas dans une des rubriques du site comme il serait logique qu&rsquo;il soit, mais dans ce <em>Journal.dde-crisis <\/em>qui est d&rsquo;abord comptable de l&rsquo;humeur de celui qui l&rsquo;\u00e9crit.<\/p>\n<\/p>\n<p><p>Enfin, comment mieux ouvrir la perspective comme elle doit l&rsquo;\u00eatre pour terminer justement cette observation sur la folie de l&rsquo;\u00e9poque qu&rsquo;avec ces quelques phrases \u00e0 propos de cette invraisemblable initiative de la cr\u00e9ation d&rsquo;un \u00ab\u00a0comit\u00e9\u00a0\u00bb, &ndash; le <em>Committee To Investigate Russia<\/em>, ou disons le CTR pour rendre compte du s\u00e9rieux de l&rsquo;entreprise, &ndash; organis\u00e9 par une association entre <em>people <\/em>d&rsquo;Hollywood et <em>neocons <\/em>recycl\u00e9s et plus ou moins officiels. <em><a href=\"http:\/\/www.zerohedge.com\/news\/2017-09-20\/we-are-war-morgan-freeman-face-new-committee-investigate-russia\">ZeroHedge.com<\/a><\/em> nous donne un bon r\u00e9sum\u00e9 de l&rsquo;affaire lanc\u00e9e par l&rsquo;acteur et metteur en sc\u00e8ne Rob Reiner, avec les <em>neocons <\/em>David Frum et Max Boot, l&rsquo;ancien directeur du renseignement national (DNI) James Clapper, fameux pour ses d\u00e9positions mensong\u00e8res mais sous serment au Congr\u00e8s, et surtout, pour la sensation et la grotesquerie, la participation tr\u00e8s active de la voie sentencieuse et m\u00e9lodieuse, accompagn\u00e9e du visage de vieux sage un peu retors et \u00e9videmment <em>black<\/em>, de l&rsquo;acteur Norman Freeman.<\/p>\n<\/p>\n<p><p>Cet assortiment abracadabrant pr\u00e9side \u00e0 l&rsquo;encouragement d&rsquo;une \u00ab\u00a0chasse aux sorci\u00e8res\u00a0\u00bb tr\u00e8s hollywoodiennes, sans sorci\u00e8res mais avec des proclamations bombastiques sur l&rsquo;agression russe et les activit\u00e9s guerri\u00e8res russes (&laquo; <em>We are at war with Russia <\/em>&raquo;, r\u00e9v\u00e9lation centrale de Freeman), et tout cela dans une atmosph\u00e8re prompte \u00e0 la d\u00e9nonciation rocambolesque. Hollywood parvenant \u00e0 se rejouer le MacCarthysme compl\u00e8tement inverti, &ndash; ou <strong>la victime de l&rsquo;Inquisition des ann\u00e9es 1940 et 1950 devenue l&rsquo;inquisiteur <em>sexy <\/em>et arros\u00e9 de millions de dollars<\/strong>.<\/p>\n<\/p>\n<p><p>Je ne sais toujours pas si Freeman est dans cette aventure pour la beaut\u00e9 de la cause ou pour son pesant de dollars, mais <a href=\"http:\/\/www.dedefensa.org\/article\/la-doctrine-gerasimov-et-la-folie-antirussiste\">l&rsquo;avis \u00e9mis<\/a> aux premi\u00e8res nouvelles de l&rsquo;intervention (il n&rsquo;\u00e9tait pas encore apparu qu&rsquo;il s&rsquo;agissait d&rsquo;une association bel et bien organis\u00e9e) reste compl\u00e8tement valable : &laquo; [&hellip;L]<em>&lsquo;hyst\u00e9rie comme sagesse, pr\u00e9sent\u00e9e par le visage v\u00e9n\u00e9rable et rayonnant de Freeman, marqu\u00e9 des sillons d&rsquo;une si rude exp\u00e9rience de la vie enfin arriv\u00e9e \u00e0 la lib\u00e9ration du progressisme-soci\u00e9tal (et antiraciste) en vogue \u00e0 Hollywood (\u00ab\u00a0Freeman\u00a0\u00bb le bien-nomm\u00e9 puisque son nom signifie \u00ab\u00a0homme libre\u00a0\u00bb)&#8230; <strong>Le <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">d\u00e9terminisme-narrativiste<\/a> \u00e0 ce point nous conduit \u00e0 d\u00e9ambuler dans un univers hallucinant<\/strong>.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Eh bien \u00e0 l&rsquo;ONU c&rsquo;\u00e9tait pareil, univers hallucinant, lorsque Trump prit d&rsquo;assaut le pupitre, puis ce qui s&rsquo;ensuivit, et tout cela n&rsquo;\u00e9tant en rien accidentel <strong>mais comme une description baroque et assez juste de l&rsquo;\u00e9poque o&ugrave; nous nous d\u00e9battons, emprisonn\u00e9s dans l&rsquo;univers accouch\u00e9 par cette \u00e9poque<\/strong>. Rien \u00e0 faire, cette pens\u00e9e lancinante ne cesse de me revenir : il est impossible, dans ces conditions, de faire &oelig;uvre de commentaire politique comme s&rsquo;il s&rsquo;agissait d&rsquo;une situation objectivement observable pour ce que la raison voudrait y voir. Il y a, dans ce fouillis et dans ce fatras, des forces d&rsquo;une puissance consid\u00e9rable qui sont \u00e0 l&rsquo;&oelig;uvre, qui brouillent tous les rangements qu&rsquo;on pourrait concevoir, qui trompent les logiques, qui attirent les jugements dans des simulacres qui sont des labyrinthes. Le premier \u00e9cueil qui attend le regard de l&rsquo;honn\u00eate homme, c&rsquo;est de comprendre et de mesurer cette forme insaisissable du simulacre dans le labyrinthe, pour tenter de l&rsquo;\u00e9carter, pour tenter de saisir l&rsquo;une ou l&rsquo;autre <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a> qu&rsquo;elle dissimulerait.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Labyrinthe du simulacre, de l&rsquo;ONU \u00e0 Freeman 21 septembre 2017 &ndash; La premi\u00e8re image qui me vient et me reste \u00e0 l&rsquo;esprit est celle, largement reprise, du g\u00e9n\u00e9ral Kelly, le directeur de cabinet de Trump, t\u00eate baiss\u00e9e, le menton dans ses mains crois\u00e9es, puis une main se cachant le visage pourtant toujours baiss\u00e9, au moment&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3299,2651,2773,3970,2830,2617,13184,3349,3004,2730,2639],"class_list":["post-77500","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-coree","tag-du","tag-iran","tag-kelly","tag-lavrov","tag-macron","tag-melania","tag-nord","tag-nucleaire","tag-russie","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77500"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77500\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}