{"id":77521,"date":"2017-10-01T11:50:16","date_gmt":"2017-10-01T11:50:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/10\/01\/de-gaulle-roosevelt-et-lamgot\/"},"modified":"2017-10-01T11:50:16","modified_gmt":"2017-10-01T11:50:16","slug":"de-gaulle-roosevelt-et-lamgot","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/10\/01\/de-gaulle-roosevelt-et-lamgot\/","title":{"rendered":"De Gaulle, Roosevelt et l&rsquo;AMGOT"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">De Gaulle, Roosevelt et l&rsquo;AMGOT<\/h2>\n<\/p>\n<p><p>1<sup>er<\/sup> octobre 2017 &ndash; J&rsquo;aimerais bien que ce soit en signe ironique fait au livre de Philippe Roger, <em>L&rsquo;ennemi am\u00e9ricain<\/em>, qu&rsquo;&Eacute;ric Branca a donn\u00e9 comme titre \u00e0 son livre <em>L&rsquo;ami am\u00e9ricain<\/em>. (*) Le livre de Roger, publi\u00e9 avec grand fracas et grand succ\u00e8s au moment (en 2002) o&ugrave; la France s&rsquo;opposait aux premi\u00e8res actions d\u00e9structurantes US de l&rsquo;\u00e9poque 9\/11(pr\u00e9paration de l&rsquo;invasion de l&rsquo;Irak), constituait une des armes de communication essentielles des proam\u00e9ricanistes fran\u00e7ais soutenus par les influences qu&rsquo;il faut et dont on retrouve la parent\u00e8le de l&rsquo;\u00e9poque, contre de Gaulle certes, dans le livre de Branca. On peut par ailleurs penser que ce livre de Branca fait partie d&rsquo;une r\u00e9action actuelle, ou dirais-je plus prudemment une tentative de r\u00e9action tant est forte la mainmise du Syst\u00e8me sur les psychologies, contre l&rsquo;extraordinaire puissance de l&rsquo;influence et de la r\u00e9f\u00e9rence am\u00e9ricaniste sur la direction politique fran\u00e7aise, \u00e9tal\u00e9e litt\u00e9ralement comme on est beurr\u00e9 sur une tartine, lors des pr\u00e9sidences Sarkozy-Hollande. (On sait ce qu&rsquo;on en pense ici, \u00e0 <em>dedefensa.org<\/em>, d&rsquo;une fa\u00e7on tr\u00e8s g\u00e9n\u00e9rale, il suffit de lire l&rsquo;article \u00ab\u00a0<em><a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">PolitiqueSyst\u00e8me (II)<\/a><\/em>\u00a0\u00bb du <em>Glossaire.dde<\/em>.)<\/p>\n<\/p>\n<p><p>L\u00e0-dessus me vient une autre r\u00e9flexion liminaire, qui va compl\u00e9ter la premi\u00e8re. Il s&rsquo;agit d&rsquo;une observation de Chateaubriand dans un article de 1824 : &laquo; <em>Le public a sans cesse besoin qu&rsquo;on lui remette en m\u00e9moire les choses m\u00eames dont il est tous les jours occup\u00e9. Il lit vite et mal : il est distrait et oublieux<\/em>. &raquo; Cette remarque vaut pour tout ce monde qui est lecteur souvent press\u00e9 lorsqu&rsquo;il s&rsquo;agit de suivre des \u00e9v\u00e9nements courants ou m\u00eame de l&rsquo;historique qui vous sert dans votre quotidien, quoique certes avec des degr\u00e9s selon les lecteurs ; certes (suite), la remarque vaut pour moi comme elle vaut pour tout lecteur, y compris celui de <em>dedefensa.org.<\/em> Elle a jou\u00e9 \u00e0 plein et s&rsquo;est v\u00e9rifi\u00e9e pour ce cas, \u00e0 propos de ma lecture du livre de Branca. Pour autant, je suis loin de l&rsquo;avoir fini puisque j&rsquo;en suis \u00e0 la page 80, juste pass\u00e9 l&rsquo;expos\u00e9 sur l&rsquo;AMGOT (acronyme US pour <em>Allied Military Government of Occupied Territories<\/em>). Mais c&rsquo;est justement ce dont il s&rsquo;agit et dont je souhaite vous entretenir.<\/p>\n<\/p>\n<p><p>(J&rsquo;avertis ici le lecteur que je lui parle moins du livre de Branca que de mon propre comportement de lecteur. Je ne suis pas l\u00e0 pour vous dire que le livre de Branca est du g\u00e9nie pur, ou qu&rsquo;il ne l&rsquo;est pas du tout ; d&rsquo;ailleurs, en juger dans un sens ou l&rsquo;autre \u00e0 la page 80 alors qu&rsquo;il en compte 380, cela serait bien audacieux&#8230; Je parle d&rsquo;un effet de la lecture qui, soudain, illumine une perception et lui donne un sens qu&rsquo;on ne soup\u00e7onnait pas jusqu&rsquo;ici. Il est plus question du lecteur que de l&rsquo;\u00e9crivain, m\u00eame en ayant bien entendu \u00e0 l&rsquo;esprit cette \u00e9vidence que s&rsquo;il n&rsquo;y avait pas l&rsquo;\u00e9crivain il n&rsquo;y aurait pas de lecteur.)<\/p>\n<\/p>\n<p><p>L&rsquo;AMGOT, donc&#8230; C&rsquo;est l&rsquo;acronyme du programme g\u00e9n\u00e9rique que l&rsquo;administration Roosevelt avait d\u00e9cid\u00e9 d&rsquo;appliquer dans les pays europ\u00e9ens et autres soudain priv\u00e9s de leurs cadres de direction et de gestion, et occup\u00e9s par l&rsquo;arm\u00e9e US (par \u00ab\u00a0les arm\u00e9es alli\u00e9es\u00a0\u00bb). On comprend qu&rsquo;il s&rsquo;agit des pays vaincus, puisque vaincus comme ils le sont par une destruction compl\u00e8te et une reddition sans condition, et une haine furieuse par-dessus le march\u00e9, cela signifie qu&rsquo;ils sont compl\u00e8tement d\u00e9structur\u00e9s et qu&rsquo;il importe de leur imposer des structures. Ce sera l&rsquo;AMGOT, et l&rsquo;AMGOT est donc bien la recette pour g\u00e9rer les pays ennemis et vaincus avant qu&rsquo;ils ne se r\u00e9tablissent avec, on l&rsquo;esp\u00e8re fermement, un r\u00e9gime compl\u00e8tement reconnaissant et souriant vis-\u00e0-vis du vainqueur d&rsquo;hier. <strong>C&rsquo;est bien ce traitement que Roosevelt veut appliquer aussi \u00e0 la France, comme si la France \u00e9tait un \u00ab\u00a0pays ennemi et vaincu\u00a0\u00bb par les USA, alors qu&rsquo;elle le fut par l&rsquo;Allemagne nazie<\/strong>.<\/p>\n<\/p>\n<p><p>Il ne s&rsquo;agit pas de croire, contrairement \u00e0 ce qu&rsquo;on pourrait \u00eatre pouss\u00e9 \u00e0 conclure aussit\u00f4t, que Branca apporte des r\u00e9v\u00e9lations sur cette affaire, ni m\u00eame ce qu&rsquo;on pourrait consid\u00e9rer comme une \u00ab\u00a0perception nouvelle\u00a0\u00bb. Tous les d\u00e9tails qu&rsquo;il donne sont en g\u00e9n\u00e9ral connus, et d&rsquo;ailleurs souvent r\u00e9f\u00e9renc\u00e9s. Plut\u00f4t, il s&rsquo;agit du rythme de l&rsquo;expos\u00e9, du r\u00e9cit, <strong>qui fait qu&rsquo;on est conduit \u00e0 donner une place et une importance diff\u00e9rentes \u00e0 l&rsquo;AMGOT, et soudain \u00e0 r\u00e9aliser l&rsquo;ampleur et la profondeur de l&rsquo;infamie de la d\u00e9marche de Roosevelt<\/strong>. Cette perception est bien entendu renforc\u00e9e par les d\u00e9tails que j&rsquo;\u00e9voquais plus haut, mais qui sont concentr\u00e9s en quelques pages (de la page 74 \u00e0 la page 80). Soudain, il nous est rappel\u00e9 que, du c\u00f4t\u00e9 anglo-saxon, il n&rsquo;a pas manqu\u00e9 de voix de haute vol\u00e9e pour d\u00e9noncer la chose ; Eden dans le mode tonitruant chez les Britanniques, et Churchill tout de m\u00eame et indirectement ; surtout, des militaires du c\u00f4t\u00e9 US, et <strong>notamment les trois grands chefs, Eisenhower (**), Marshall et MacArthur, qui \u00e9taient scandalis\u00e9s par les intentions du pr\u00e9sident<\/strong>. (***)<\/p>\n<\/p>\n<p><p>L&rsquo;ensemble de la lecture fait que j&rsquo;ai per\u00e7u, dans cette dynamique, l&rsquo;affaire AMGOT c<strong>omme le point culminant de l&rsquo;affrontement entre Roosevelt et de Gaulle, alors qe cette affaire \u00e9tait jusqu&rsquo;alors plut\u00f4t un \u00e9pisode parmi d&rsquo;autres dans l&rsquo;histoire de leur m\u00e9sentente<\/strong>. C&rsquo;est toujours \u00ab\u00a0l&rsquo;histoire de leur m\u00e9sentente\u00a0\u00bb, mais dans ce cas l&rsquo;AMGOT, qui revient effectivement \u00e0 l&rsquo;asservissement et \u00e0 l&rsquo;humiliation d&rsquo;une grande nation amie affaiblie tragiquement par des \u00e9v\u00e9nements \u00e9pouvantables, s<strong>e r\u00e9v\u00e8le comme un acte de brigandage, une piraterie internationale qui, \u00e0 elle seule, justifie toute l&rsquo;inimiti\u00e9 de De Gaulle pour la politique am\u00e9ricaniste et le syst\u00e8me de l&rsquo;am\u00e9ricanisme<\/strong>, ce que lui reproch\u00e8rent souvent des fractions de la droite, p\u00e9tainistes et h\u00e9ritiers des p\u00e9tainistes en t\u00eate.<\/p>\n<\/p>\n<p><p>(Au reste, les \u00ab\u00a0p\u00e9tainistes\u00a0\u00bb sont, dans ce cas des relations avec Roosevelt, l<strong>es meilleurs amis du pr\u00e9sident US<\/strong>, \u00e0 un point qui est l\u00e0 aussi du domaine de la r\u00e9v\u00e9lation, qui devient quasiment une parent\u00e8le avec les Chambrun [<a href=\"https:\/\/fr.wikipedia.org\/wiki\/Ren%C3%A9_de_Chambrun\">Ren\u00e9 de Chambrun<\/a>, gendre de Laval et de descendance directe du La Fayette de la Guerre d&rsquo;Ind\u00e9pendance am\u00e9ricaine]. Ils sont rejoints par une constellation de personnalit\u00e9s qui ne sont pas directement p\u00e9tainistes, qui ont m\u00eame pr\u00e9tendu entrer \u00ab\u00a0en r\u00e9sistance\u00a0\u00bb, mais qui sont tout de m\u00eame du m\u00eame parti, &ndash; dans ce cas, le \u00ab\u00a0parti de l&rsquo;\u00e9tranger\u00a0\u00bb, toujours tr\u00e8s puissant en France&#8230; Cela va d&rsquo;Alexis L\u00e9ger [St-John Perse] \u00e0 Jean Monnet.)<\/p>\n<\/p>\n<p><p>On comprend combien le cynisme, l&rsquo;arrogance et la tromperie sont une composante essentielle de la \u00ab\u00a0politique lib\u00e9rale\u00a0\u00bb des soi-disant dirigeants progressistes US, de Wilson \u00e0 Obama (mise \u00e0 part l&rsquo;une ou l&rsquo;autre exception heureuse, &ndash; en fait, seulement Carter \u00e0 cet \u00e9gard) ; cette politique qui se couvre inconsciemment,<strong> comme par privil\u00e8ge assur\u00e9<\/strong>, du manteau de la vertu et de l&rsquo;exceptionnalisme pour mieux assurer ses coups en tra&icirc;tre, et qui repr\u00e9sente certes le mieux la tendance au globalisme et le d\u00e9bouch\u00e9 in\u00e9vitable sur le simulacre de la postmodernit\u00e9 et du progressisme-soci\u00e9tal. En un sens, Roosevelt entendait, avec AMGOT, <strong>traiter la France comme ils ont trait\u00e9 l&rsquo;Irak qui s&rsquo;\u00e9tait pourtant battu en leur nom contre l&rsquo;Iran pendant huit ann\u00e9es<\/strong>.<\/p>\n<\/p>\n<p><p>Peut-\u00eatre reste-t-il \u00e0 rechercher la cause initiale de l&rsquo;antipathie de Roosevelt pour de Gaulle (cela va dans ce sens), qui ne craignait pas de toucher jusqu&rsquo;au grotesque d\u00e8s l&rsquo;origine et relevait pour certains d\u00e9tails plus de la psychiatrie que de la politique. (Lors de leur premi\u00e8re rencontre, des officiers du <em>Secret Service <\/em>\u00e9taient dissimul\u00e9s derri\u00e8re diverses tentures, arm\u00e9s de mitraillette. <strong>Sans doute craignait-on que ce coupe-jarret de De Gaulle n&rsquo;agress\u00e2t Roosevelt ou ne le pr&icirc;t en otage<\/strong>.) Je pense et penche simplement pour l&rsquo;influence de ses \u00ab\u00a0amis\u00a0\u00bb fran\u00e7ais (Monnet, Chambrun, etc.) qui, eux, ha\u00efssaient de Gaulle (<strong>surtout Monnet<\/strong>) et purent largement faire leur travail avant que les \u00e9v\u00e9nements n&rsquo;am\u00e8nent les deux hommes (de Gaulle et Roosevelt) \u00e0 devoir se conna&icirc;tre, s&rsquo;arranger ou s&rsquo;affronter, etc. Bateleur \u00e9blouissant, orateur naturellement et presque vertueusement d\u00e9magogique, magicien du verbe, <strong>Roosevelt est de cette m\u00eame esp\u00e8ce qu&rsquo;un Obama, avec la m\u00eame tendance politique vue plus haut, caract\u00e9ris\u00e9e par l&rsquo;arrogance et la s&ucirc;ret\u00e9 de soi<\/strong>, aimant \u00e0 se forger une opinion pr\u00e9jug\u00e9e \u00e0 partir du jugement des autres pour para&icirc;tre assur\u00e9 \u00e0 ses propres yeux, <strong>sans n\u00e9cessit\u00e9 de consulter la r\u00e9alit\u00e9 mais au contraire semblant la ma&icirc;triser par avance<\/strong>.<\/p>\n<\/p>\n<p><p>Ainsi justifierais-je la citation de Chateaubriand faite au d\u00e9but de cette page, mais en la retournant pour lui donner un sens positif. Il est vrai que le lecteur (dans ce cas, le mot est plus appropri\u00e9 que \u00ab\u00a0public\u00a0\u00bb) &laquo; <em>a sans cesse besoin qu&rsquo;on lui remette en m\u00e9moire les choses m\u00eames dont il est tous les jours occup\u00e9&#8230; <\/em>&raquo; (Certes, les rapports entre de Gaulle et Roosevelt ne m&rsquo;occupent pas tous les jours, mais elles sont dans le courant g\u00e9n\u00e9ral de mes r\u00e9flexions, comme je le sugg\u00e8re moi-m\u00eame en faisant le parall\u00e8le entre l&rsquo;AMGOT et l&rsquo;Irak.) Ce rafra&icirc;chissement de la m\u00e9moire n&rsquo;est pas, dans ce cas, pour rattraper une distraction ou un oubli, mais<strong> pour susciter \u00e0 partir des souvenirs enfuis et d&rsquo;un r\u00e9cit nouveau d&rsquo;une chose connue des perspectives in\u00e9dites et remarquables<\/strong>.<\/p>\n<\/p>\n<p><p>J&rsquo;insiste bien sur le r\u00f4le du lecteur dans ce cas : il n&rsquo;est pas assur\u00e9 que Bronca partage la m\u00eame analyse de l&rsquo;importance de l&rsquo;AMGOT, ou de sa signification, etc. Il reste qu&rsquo;il a suscit\u00e9 dans un esprit \u00e9tranger des orientations intuitives et des m\u00e9canismes in\u00e9dits ;<strong> sa mission, dans ce sens, est accomplie<\/strong>.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h2>\n<\/p>\n<p><p>(*) Il faut signaler que c&rsquo;est aussi le titre du livre de Justine Faure, chez Tallandier, en 2004 : <em>L&rsquo;ami am\u00e9ricain &ndash; La Tch\u00e9coslovaquie, enjeu de la diplomatie am\u00e9ricaine<\/em>. <a href=\"https:\/\/sgdl.org\/juridique\/la-minute-juridique-de-la-sgdl-sur-webtv\/762-la-protection-du-titre\">La l\u00e9gislation<\/a> sur la protection (droits d&rsquo;auteur) des titres d'\u00a0\u00bb&oelig;uvres de cr\u00e9ation\u00a0\u00bb est assez complexe pour permettre cette sorte de \u00ab\u00a0doublon\u00a0\u00bb involontaire.<\/p>\n<\/p>\n<p><p>(**) Pour Eisenhower, on voit souvent ces liens d&rsquo;estime avec de Gaulle, notamment lorsque, en ao&ucirc;t 1944, il donne son accord sans en r\u00e9f\u00e9rer \u00e0 Roosevelt pour que la 2<sup>\u00e8me<\/sup> DB fran\u00e7aise soit autoris\u00e9e \u00e0 entrer la premi\u00e8re dans Paris, et non une division US comme primitivement pr\u00e9vu. Eisenhower prend cette d\u00e9cision sans en r\u00e9f\u00e9rer \u00e0 Roosevelt, estimant probablement qu&rsquo;il aurait essuy\u00e9 un refus et que la seule issue \u00e9tait de placer le pr\u00e9sident devant un fait accompli qu&rsquo;il ne pourrait pas d\u00e9cemment d\u00e9noncer.<\/p>\n<\/p>\n<p><p>(***) D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, on peut faire l&rsquo;hypoth\u00e8se que cette r\u00e9action des trois chefs est largement aliment\u00e9e par leur service \u00e0 tous trois, en 1917-1918 en France, et <strong>leur perception de la puissance et de la gloire de l&rsquo;arm\u00e9e fran\u00e7aise et de la France \u00e0 cette \u00e9poque<\/strong>. Il y ainsi la fraternit\u00e9 d&rsquo;armes et le sens que le comportement d&rsquo;une telle puissance collective que celle manifest\u00e9e par la France en 1918 est l&rsquo;indice certain d&rsquo;une souverainet\u00e9 qu&rsquo;il importe absolument de respecter.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De Gaulle, Roosevelt et l&rsquo;AMGOT 1er octobre 2017 &ndash; J&rsquo;aimerais bien que ce soit en signe ironique fait au livre de Philippe Roger, L&rsquo;ennemi am\u00e9ricain, qu&rsquo;&Eacute;ric Branca a donn\u00e9 comme titre \u00e0 son livre L&rsquo;ami am\u00e9ricain. (*) Le livre de Roger, publi\u00e9 avec grand fracas et grand succ\u00e8s au moment (en 2002) o&ugrave; la France&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2769,13451,13450,2875,2744,9465,13452,13311],"class_list":["post-77521","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-americain","tag-branca","tag-chambrun","tag-chateaubriand","tag-eisenhower","tag-eric","tag-lami","tag-monnet"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77521"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77521\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}