{"id":77543,"date":"2017-10-12T12:37:39","date_gmt":"2017-10-12T12:37:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/10\/12\/hollywood-babylon-postmoderne\/"},"modified":"2017-10-12T12:37:39","modified_gmt":"2017-10-12T12:37:39","slug":"hollywood-babylon-postmoderne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/10\/12\/hollywood-babylon-postmoderne\/","title":{"rendered":"<em>Hollywood-Babylon<\/em> postmoderne"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>Hollywood-Babylon<\/em> postmoderne<\/h2>\n<\/p>\n<p><p>12 octobre 2017 &ndash; Je me rappelle, \u00e0 la fin des ann\u00e9es 1950, le bruit sulfureux que produisit l&rsquo;\u00e9dition en France de <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Hollywood_Babylone\">Hollywood-Babylone<\/a><\/em>, le livre-scandale de Kenneth Anger avec nombreuses photos \u00e0 l&rsquo;appui sur le Hollywood d\u00e9prav\u00e9, d\u00e9cadent, parcouru de scandales plus ou moins \u00e9touff\u00e9s, crimes, d\u00e9pravation sexuelle, drogue, etc. Publi\u00e9 par Pauvert \u00e0 Paris, le livre de Anger fut interdit aux USA et une version mise \u00e0 jour ne fut autoris\u00e9e qu&rsquo;en 1975. <em>USA, Land of the Free<\/em>&#8230;<\/p>\n<\/p>\n<p><p>A l&rsquo;\u00e9poque (1958), l&rsquo;on parlait du scandale de la mort de l&rsquo;amant de la star Lana Turner, le gangster de <em>Cosa Nostra<\/em> <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Johnny_Stompanato\">Johnny Stompanato<\/a>, abattu par la fille de l&rsquo;actrice, Cheryl Crane, \u00e2g\u00e9e de 14 ans. Stompanato battait sa m\u00e8re et le tribunal reconnut que Cheryl avait agi en \u00e9tat de l\u00e9gitime d\u00e9fense, \u00ab\u00a0par procuration\u00a0\u00bb si l&rsquo;on veut, ce qui \u00e9tait apr\u00e8s tout une courageuse interpr\u00e9tation de la loi. C&rsquo;\u00e9tait dans la rubrique \u00ab\u00a0faits-divers\u00a0\u00bb, rien d&rsquo;autre sinon le sel qui accompagne les comportements scandaleux des c\u00e9l\u00e9brit\u00e9s, et \u00e9ventuellement une occasion de r\u00e9flexion sociologique et culturelle sur la culture am\u00e9ricaniste, sur la licence ou la d\u00e9cadence des m&oelig;urs, etc. ; dans tous les cas, bien s&ucirc;r, <strong>rien \u00e0 voir avec la politique active, en cours, en aucune fa\u00e7on<\/strong>. Aujourd&rsquo;hui, le scandale Harvey Weinstein n&rsquo;est pas dans la rubrique faits-divers, et <em>Hollywood-Babylone <\/em>devenu <em>Hollywood-Babylon<\/em> postmoderne <strong>est aussit\u00f4t un \u00e9v\u00e9nement tr\u00e8s largement politique, de la plus active des politiques, et qu&rsquo;il importe de reconna&icirc;tre comme tel<\/strong>.<\/p>\n<\/p>\n<p><p>On ne peut dire que l&rsquo;affaire Weinstein a \u00e9t\u00e9 \u00ab\u00a0r\u00e9v\u00e9l\u00e9e\u00a0\u00bb par les articles du New York <em>Times <\/em>et du <em><a href=\"http:\/\/www.francetvinfo.fr\/culture\/cinema\/affaire-harvey-weinstein\/affaire-harvey-weinstein-the-new-yorker-devoile-un-nouvel-enregistrement-compromettant-du-producteur_2414061.html\">New Yorker<\/a><\/em>, puisque, comme l&rsquo;on dit, \u00ab\u00a0tout le monde \u00e9tait au courant\u00a0\u00bb dans le milieu (hollywoodien, je pr\u00e9cise) et que tout le monde \u00ab\u00a0<a href=\"http:\/\/www.francetvinfo.fr\/monde\/usa\/comment-hollywood-a-etouffe-le-scandale-weinstein-pendant-des-annees_2413837.html\">a \u00e9touff\u00e9 l&rsquo;affaire<\/a>\u00a0\u00bb pendant, disons, deux d\u00e9cennies. (Au reste, les \u00e9l\u00e9ments de l&rsquo;article du <em>New-Yorker<\/em>, \u00e9crit par le fils de l&rsquo;acrice Mia Farrow, avaient d&rsquo;abord \u00e9t\u00e9 propos\u00e9s \u00e0 NBC [avec MSNBC, le r\u00e9seau le plus progressiste-soci\u00e9tal aux USA], <a href=\"http:\/\/www.zerohedge.com\/news\/2017-10-11\/how-nbc-killed-ronan-farrows-weinstein-expos%C3%A9\">qui le refusa<\/a> sur l&rsquo;intervention directe de son directeur, grand ami de Weinstein.) <strong>Mais l&rsquo;affaire est devenue \u00ab\u00a0scandale\u00a0\u00bb, et aussit\u00f4t bien plus que cela, quasi-instantan\u00e9ment<\/strong>. Comme je la ressens et l&rsquo;\u00e9value, la rapidit\u00e9 du processus est, sinon une surprise, <strong>sans aucun doute un \u00e9v\u00e9nement qui mesure le changement des temps et l&rsquo;affirmation des facteurs diff\u00e9rents qui importent<\/strong>.<\/p>\n<\/p>\n<p><p>Ainsi donc, d\u00e8s que fut prise la mesure de son ampleur, l&rsquo;affaire quitta aussit\u00f4t le rubrique des faits-divers et devint scndale nationale pour entrer dans le champ de la politique active, <strong>c&rsquo;est-\u00e0-dire de la crise de l&rsquo;am\u00e9ricanisme parvenue \u00e0 son paroxysme depuis la campagne pr\u00e9sidentielle<\/strong>. Nul ne peut oublier que cette campagne USA-2016 fut marqu\u00e9e notamment par des attaques d&rsquo;une puissance consid\u00e9rable contre Trump \u00e0 cause d&rsquo;une phrase de type sexiste, singuli\u00e8rement vulgaire sans nul doute, et sans surprise lorsqu&rsquo;on consid\u00e8re le personnage ; mais cette phrase, qui n&rsquo;attentait pas en quelque fa\u00e7on que ce soit \u00e0 l&rsquo;int\u00e9grit\u00e9 morale et physique d&rsquo;un certain nombre de personnes, nombre assez \u00e9lev\u00e9 sans nul doute lorsqu&rsquo;on se r\u00e9f\u00e8re \u00e0 ce qui nous occupe aujourd&rsquo;hui.<\/p>\n<\/p>\n<p><p>Or le cas de Weinstein, qui est de cette sorte dans une mesure rarement vue, est celui d&rsquo;un homme <strong>qui est l&rsquo;un des principaux soutiens et organisateur de donation du parti d\u00e9mocrate, ami et donateur successivement d&rsquo;Obama et d&rsquo;Hillary Clinton<\/strong>. Ces deux-l\u00e0, Obama et Clinton qui n&rsquo;ignoraient rien du comportement de leur ami Weinstein, sont <a href=\"http:\/\/www.francetvinfo.fr\/culture\/cinema\/affaire-harvey-weinstein\/affaire-harvey-weinstein-barack-obama-hillary-clinton-et-les-democrates-sur-la-defensive_2413925.html\">plut\u00f4t mal pris<\/a> et ils ont bien du mal \u00e0 le cacher ; ce dernier point, qui n&rsquo;est pas vraiment pour me d\u00e9plaire je l&rsquo;avoue \u00e0 cause de l&rsquo;ironie des situations, moi-m\u00eame faisant partie du <em>vulgum pecus<\/em> saoul\u00e9 ces derni\u00e8res ann\u00e9es par les le\u00e7ons de morale et de vertu des personnages en question. Tout cela se passe \u00e0 <strong>Hollywood, principal centre lib\u00e9ral, progressiste-soci\u00e9tal, qui mena constamment la charge contre Trump <\/strong>notamment \u00e0 cause de ses gaudrioles \u00e0 deux balles o&ugrave; il appara&icirc;t d\u00e9sormais comme un amateur, avec Weinstein comme organisateur quasi-divin de cette charge. (Meryl Streep, qui r\u00eave d&rsquo;avoir le scalp de Trump, avait affubl\u00e9 Weinstein, ironiquement je l&rsquo;esp\u00e8re, <strong>du surnom de \u00ab\u00a0<em>God<\/em>\u00a0\u00bb \u00e0 peu pr\u00e8s comme l&rsquo;on dit sardoniquement \u00ab\u00a0<em>devil<\/em>\u00ab\u00a0<\/strong>. Ainsi se retrouve-t-on dans le domaine de l&rsquo;inversion, <a href=\"http:\/\/www.dedefensa.org\/article\/satan-mene-le-bal-usa-2016\">avec la vertu, le sexe et le diabolisme<\/a>, qui semble particuli\u00e8rement marquer les \u00e9lites progressistes-soci\u00e9tales.)<\/p>\n<\/p>\n<p><p>L&rsquo;une des r\u00e9actions les plus puissantes et les plus symboliques caract\u00e9risant ce passage du fait-divers sulfureux \u00e0 la politique est par exemple l&rsquo;\u00e9mission <em>CrossTalk <\/em>de Peter Lavelle, le <a href=\"https:\/\/www.rt.com\/shows\/crosstalk\/406317-weinstein-scandal-hollywood-hypocrisy\/\">10 octobre sur RT<\/a>, avec pour th\u00e8me : &laquo; <em>Hollywood hypocrisy<\/em> &raquo;. Cette hypocrisie-l\u00e0, telle qu&rsquo;on en discute avec v\u00e9h\u00e9mence dans l&rsquo;\u00e9mission n&rsquo;est pas tant celle de Hollywood, ou pas seulement, que celle des d\u00e9mocrates comme ils se sont d\u00e9couverts lors de USA-2016 ; c&rsquo;est donc <strong>l&rsquo;hypocrisie de la vertu progressiste-soci\u00e9tale, du pouvoir de l&rsquo;argent et de la corruption du pouvoir surtout lorsque ces choses tr\u00f4nent sur la vertu postmoderne<\/strong> qu&rsquo;affectionnent jusqu&rsquo;au d\u00e9lire orgasmique si l&rsquo;on peut dire, nos fameux 1%-0,1%, nos \u00ab\u00a0<em>Masters of Universe<\/em>\u00ab\u00a0, hyper-riches, dispensateurs de tant de le\u00e7ons de morale et d&rsquo;\u00e9thique au nom du globalisme et par cons\u00e9quent du Syst\u00e8me. <strong>On en revient toujours l\u00e0 car le Syst\u00e8me est partout pr\u00e9sent<\/strong>&#8230;<\/p>\n<\/p>\n<p><p>Surprise encore et toujours, je l&rsquo;avoue bien que la chose aille dans le sens qu&rsquo;on observe constamment et qui m&rsquo;est si famili\u00e8re (celui de la puissance omnipr\u00e9sente de la communication et des th\u00e8mes soci\u00e9taux), <strong>avec les prolongements politiques qui apparaissent tout aussi rapidement comme pouvant prendre une voie institutionnelle et judiciaire \u00e0 grande signification politique<\/strong>. Des suites judiciaires sont d&rsquo;ores et d\u00e9j\u00e0 <a href=\"http:\/\/www.zerohedge.com\/news\/2017-10-10\/nypd-says-harvey-weinstein-evidence-was-presented-manhattan-da\">en route<\/a>, qui pourraient aussi bien toucher les compagnies o&ugrave; l&rsquo;on \u00e9tait au courant du comportement de \u00ab\u00a0Dieu\u00a0\u00bb (<a href=\"http:\/\/www.breitbart.com\/big-hollywood\/2017\/10\/11\/disney-weinstein-company-could-face-harassment-lawsuits-scandal-widens\/\">Miramax et Disney<\/a> notamment). On signale que <a href=\"http:\/\/www.zerohedge.com\/news\/2017-10-11\/fbi-reportedly-investigating-harvey-weinstein\">le FBI ouvrirait une enqu\u00eate<\/a> et <em>The DailyCaller<\/em> <a href=\"http:\/\/dailycaller.com\/2017\/10\/11\/investigate-hollywood-mr-trump-there-is-only-upside-to-dragging-sex-criminals-into-the-sunlight\/\">lance un appel<\/a> au pr\u00e9sident Trump pour qu&rsquo;il ordonne l&rsquo;ouverture d&rsquo;une enqu\u00eate officielle sp\u00e9ciale embrassant quasiment les agissements et les m&oelig;urs de ce centre de pouvoir et d&rsquo;influence qu&rsquo;est Hollywood. On chuchote \u00e9galement que des t\u00eates pourraient tomber du c\u00f4t\u00e9 des acteurs (genre masculin, style Matt Damon, Russell Crowe, Ben Affleck), qui savaient et n&rsquo;auraient rien dit ou bien qui auraient d\u00e9fendu Weinstein ; et c&rsquo;est <em>TheDuran.com<\/em>, site \u00e9minemment politique comme l&rsquo;on sait, qui <a href=\"http:\/\/theduran.com\/ben-affleck-gets-uncomfortable-when-asked-about-good-friend-harvey-weinstein-video\/\">nous annonce la chose<\/a>.<\/p>\n<\/p>\n<p><p>Une r\u00e9action dite de \u00ab\u00a0<em>damage control<\/em>\u00a0\u00bb (tenter d&rsquo;\u00e9viter des d\u00e9g\u00e2ts trop importants) a \u00e9t\u00e9 d&rsquo;orienter aussit\u00f4t le d\u00e9bat dans le seul sens soci\u00e9tal du f\u00e9minisme, du sort fait aux femmes en g\u00e9n\u00e9ral, sans trop s&rsquo;attarder \u00e0 ce point fondamental que tout cela se passe dans la citadelle incontest\u00e9e du f\u00e9minisme et de toutes les valeurs soci\u00e9tales, dans le chef d&rsquo;un homme qu&rsquo;on ne cessa jamais d&rsquo;encenser puisqu&rsquo;il en \u00e9tait \u00ab\u00a0le Dieu\u00a0\u00bb. La terreur r\u00e9gnait \u00e0 Hollywood sous la loi de \u00ab\u00a0Dieu\u00a0\u00bb, <strong>dans ce lieu \u00e9trange o&ugrave; l&rsquo;on tourne Dieu en d\u00e9rision et o&ugrave; les femmes forc\u00e9es et viol\u00e9es, <a href=\"http:\/\/www.dailymail.co.uk\/news\/article-4142956\/Thousands-women-march-London-against-Donald-Trump.html\">c&rsquo;est-\u00e0-dire les actrices<\/a> de Meryl Streep \u00e0 Madonna, savent o&ugrave; est le Bien (\u00e0 Hollywood-sous-Weinstein) et o&ugrave; l&rsquo;on trouve le Mal (Trump &#038; Cie)<\/strong>.<\/p>\n<\/p>\n<p><p>Mais ce simulacre-l\u00e0 de faire passer le d\u00e9bat du c\u00f4t\u00e9 du f\u00e9minisme, surtout d\u00e9velopp\u00e9 en France, p\u00e8se \u00e0 mon avis de peu de poids \u00e0 c\u00f4t\u00e9 du poids des faits, lorsqu&rsquo;on entend un Antoine de Caunes traiter Weinstein de &laquo; <em><a href=\"http:\/\/www.francetvinfo.fr\/culture\/cinema\/affaire-harvey-weinstein\/affaire-weinstein-antoine-de-caunes-soutient-sa-fille-emma-et-denonce-les-agissements-de-ce-gros-porc-puant_2414433.html\">gros porc puant<\/a> <\/em>&raquo; \u00e0 cause de ce qu&rsquo;il a fait \u00e0 sa fille&#8230; Ou mieux encore, c&rsquo;est-\u00e0-dire pire et plus profond\u00e9ment, lorsqu&rsquo;on entend quelques mots de Pierre Lescure (ex-<em>Canal +<\/em>, comme de Caunes) parler, hier soir sur <em>C Dans l&rsquo;Air<\/em>, de ses contacts avec Weinstein, lorsqu&rsquo;il n\u00e9gociait les films de Miramax&#8230; <strong>Weinstein, \u00ab\u00a0d\u00e9gageait une impression de puissance physique et psychologique incroyablement agressive\u00a0\u00bb<\/strong> dit Lescure sur un tel ton, comme s&rsquo;il s&rsquo;excusait de parler ainsi \u00e0 propos de Hollywood et de sa vertu soci\u00e9tale ; comme si, aussi, il se rappelait une sorte de peur physique qu&rsquo;il \u00e9prouvait \u00e0 \u00ab\u00a0n\u00e9gocier\u00a0\u00bb avec cet homme. (Les photos d\u00e9sormais nombreuses de Harvey Weinstein, en portrait ou en posture compl\u00e8te, font l&rsquo;affaire pour comprendre ce dont Lescure veut parler.) Vous comprenez alors que vous avez affaire, dans le chef de Weinstein, au pr\u00e9dateur-Syst\u00e8me caract\u00e9ris\u00e9 par la force brute (fa\u00e7on \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-lideal-de-puissance-1\">id\u00e9al de puissance<\/a>\u00ab\u00a0), install\u00e9 avec arrogance sur le pouvoir de l&rsquo;argent et sur l&rsquo;arrogance du pouvoir, mais plus encore dans notre situation, <strong>sur la terrorisation de la vertu soci\u00e9tale<\/strong> que repr\u00e9sente Hollywood.<\/p>\n<\/p>\n<p><p>Ainsi passe-t-on finalement, venu du fait-divers sulfureux, \u00e0 des consid\u00e9rations fondamentales sur le ph\u00e9nom\u00e8ne de la puissance et du pouvoir, qui a certes toujours exist\u00e9 mais que le Syst\u00e8me a institu\u00e9 en facteur fondamental de la situation du monde en <strong>l&rsquo;habillant de la cuirasse de la vertu, en une structure quasi-unique du simulacre qui doit mener \u00e0 la destruction du monde<\/strong>. Le cas Weinstein conduit John Whitehead du <em>Rutherford Institute<\/em>, \u00e0 <a href=\"https:\/\/rutherford.org\/publications_resources\/john_whiteheads_commentary\/power_corrupts_a_culture_of_compliance_breeds_despots_and_predators_short\">nous parler<\/a> du pouvoir qui corrompt, et \u00e9videmment du pouvoir absolu qui corrompt absolument. Mais la formule, dont je me suis toujours d\u00e9fi\u00e9, reste \u00e0 mon avis bien trop vague, trop g\u00e9n\u00e9rale, et elle reste une formule que chacun peut s&rsquo;approprier pour s&rsquo;en laver les mains bien plus que la clef d&rsquo;une analyse.<\/p>\n<\/p>\n<blockquote>\n<p><p>Il est essentiel d&rsquo;ajouter que <strong>ce pouvoir absolu \u00e9mane aujourd&rsquo;hui du Syst\u00e8me<\/strong>. S&rsquo;il est install\u00e9 sur l&rsquo;argent bien entendu, il est <strong>fondamentalement manipul\u00e9 par la communication et le discours de terrorisation des \u00ab\u00a0valeurs soci\u00e9tales\u00a0\u00bb<\/strong> qui entretiennent ce que Whitehead d\u00e9signe comme &laquo; <em>une culture de complaisance o&ugrave; personne n&rsquo;ose parler parce que personne ne veut perdre son emploi, ni perdre son argent, ni perdre sa place parmi les \u00e9lites<\/em> &raquo;. C&rsquo;est <strong>\u00e0 cause de cette installation dans sa cuirasse de vertu, ou plus justement de simulacre de vertu<\/strong>, que le pouvoir est devenu absolu tel qu&rsquo;on le constate aujourd&rsquo;hui.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est pour cette raison que je ne consid\u00e8re pas, \u00e0 la diff\u00e9rence de Whitehead, que le \u00ab\u00a0scandale Weinstein\u00a0\u00bb soit un scandale \u00ab\u00a0de plus\u00a0\u00bb, o&ugrave; jouent les habituelles m\u00e9caniques du pouvoir et de l&rsquo;argent. <strong>C&rsquo;est un scandale d&rsquo;un symbolisme fondamental<\/strong>, dans la mesure o&ugrave; Weinstein, un des fondateurs de Miramax si admir\u00e9 pour avoir permis l&rsquo;\u00e9mergence d&rsquo;un \u00ab\u00a0nouvel Hollywood\u00a0\u00bb et favoris\u00e9 tant de cin\u00e9astes ind\u00e9pendants \u00e0 c\u00f4t\u00e9 des <em>blockbusters <\/em>faiseurs de fric, se r\u00e9v\u00e8le \u00e9galement comme un arch\u00e9type du pr\u00e9dateur-Syst\u00e8me, <strong>un &laquo; <em>gros porc puant <\/em>&raquo; comme dit l&rsquo;autre<\/strong>, alors qu&rsquo;il r\u00e9gnait <strong>comme Dieu lui-m\u00eame, comme dit l&rsquo;autre (suite)<\/strong>, au sommet du royaume de la vertu progressiste-soci\u00e9tale.<\/p>\n<\/p>\n<p><p>C&rsquo;est une formidable <strong>description du Simulacre du Syst\u00e8me qui est mise \u00e0 nu<\/strong>. A cette lumi\u00e8re et au-del\u00e0 de la contre-analogie avec le Trump de USA-2016, je crois qu&rsquo;on ne doit plus s&rsquo;\u00e9tonner, si on le constate dans ce sens, que le fait-divers ait pris aussi vite une ampleur nationale sinon globale, et \u00e0 tr\u00e8s forte substance politique.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hollywood-Babylon postmoderne 12 octobre 2017 &ndash; Je me rappelle, \u00e0 la fin des ann\u00e9es 1950, le bruit sulfureux que produisit l&rsquo;\u00e9dition en France de Hollywood-Babylone, le livre-scandale de Kenneth Anger avec nombreuses photos \u00e0 l&rsquo;appui sur le Hollywood d\u00e9prav\u00e9, d\u00e9cadent, parcouru de scandales plus ou moins \u00e9touff\u00e9s, crimes, d\u00e9pravation sexuelle, drogue, etc. Publi\u00e9 par Pauvert&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[13507,934,2631,3009,10996,13508,13505,13504,12533,13506,12538,4644],"class_list":["post-77543","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-caunes","tag-clinton","tag-de","tag-democrates","tag-harvey","tag-lescure","tag-meryl","tag-miramax","tag-progressiste-societal","tag-sleep","tag-usa-2016","tag-weinstein"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77543"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77543\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}