{"id":77572,"date":"2017-10-28T06:30:32","date_gmt":"2017-10-28T06:30:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/10\/28\/qui-ne-dit-mot-consent\/"},"modified":"2017-10-28T06:30:32","modified_gmt":"2017-10-28T06:30:32","slug":"qui-ne-dit-mot-consent","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/10\/28\/qui-ne-dit-mot-consent\/","title":{"rendered":"Qui ne dit mot consent\u2026"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Qui ne dit mot consent&hellip;<\/h2>\n<\/p>\n<p><p>Consentez-vous \u00e0 prendre pour \u00e9poux untel? &Agrave; prendre pour \u00e9pouse une telle? La r\u00e9ponse est toujours oui ou non. Elle concerne la libre volont\u00e9 de chaque personne et la question vient d&rsquo;une tierce qui a autorit\u00e9 pour enregistrer l\u00e9galement le consentement. Consentir \u00e0 l&rsquo;imp\u00f4t est-ce tout \u00e0 fait synonyme d&rsquo;\u00eatre imposable? Pas tout \u00e0 fait bien que dans les deux cas vous n&rsquo;avez pas trop le choix. Je donne mon consentement \u00e9quivaut \u00e0 autoriser, \u00e0 \u00eatre d&rsquo;accord, \u00e0 accepter une proposition qui vous est adress\u00e9e: Je consens \u00e0 vendre mon chat, je consens \u00e0 \u00e9couter vos arguments, mais je n&rsquo;y suis pas oblig\u00e9. L\u00e0, on est d\u00e9j\u00e0 dans un autre registre du consentement. Enfin, tout le monde conna&icirc;t la formule utilis\u00e9e parfois pour culpabiliser ou pousser \u00e0 s&rsquo;exprimer quelqu&rsquo;un qui y r\u00e9pugne par sagesse ou d\u00e9sint\u00e9r\u00eat : &quot;Qui ne dit mot consent&quot;.<\/p>\n<\/p>\n<p><p>Consentir n&rsquo;est pas <em>\u00eatre d&rsquo;accord<\/em>, consentir n&rsquo;est pas <em>accepter<\/em> et encore moins <em>se soumettre<\/em>. Toutefois, l&rsquo;origine du mot fait r\u00e9fl\u00e9chir. &#8211;<em>Con<\/em>-, avec, et <em>sentir<\/em>. Ce qui montre qu&rsquo;on sent avec quelqu&rsquo;un, m\u00eame si, bien s&ucirc;r, on peut (con)sentir \u00e0 sa d\u00e9ch\u00e9ance ou \u00e0 son humiliation tout seul. Qui pr\u00e9tendrait que le consentement \u00e0 s&rsquo;\u00e9pouser est de nature comparable au divorce par consentement mutuel? On voit bien ici que le mot consentir est charg\u00e9 de quelque chose d&rsquo;infiniment subtil et\/ou d&rsquo;infiniment contradictoire. Si je consens \u00e0 \u00e9pouser, mon consentement n&rsquo;est pas celui d&rsquo;une froide raison (il peut l&rsquo;\u00eatre certes mais ce n&rsquo;est pas le sujet), d&rsquo;une d\u00e9cision strictement intellectuelle ou juridique. Quand deux amants d\u00e9cident de s&rsquo;unir, m\u00eame au nom de la loi, c&rsquo;est d&rsquo;abord leur loi \u00e0 eux avant d&rsquo;\u00eatre celle de la Loi. Ce consentement est du c&oelig;ur qui a ses raisons que souvent la raison ignore, emport\u00e9e qu&rsquo;elle est par le <em>consentir<\/em>, le sentir avec, le partage du senti avec une autre personne. Divorcer par consentement mutuel vient de la froide raison de deux personnes raisonnables qui se sont peut-\u00eatre \u00e9pous\u00e9s par consentement mais o&ugrave; il y avait trop de sentir illusoirement partag\u00e9 et qui comprenant que le &ndash;<em>con<\/em>&#8211; \u00e9tait faux ou insuffisant, se s\u00e9parent par manque de sentir. Il y a bien s&ucirc;r une inflexion dans la s\u00e9mantique du mot consentir. Le g\u00e9nie de la langue le souligne en parlant d&rsquo;une vergue qui a <em>consenti<\/em>, qui s&rsquo;est laiss\u00e9 courb\u00e9e, qui a c\u00e9d\u00e9 sous la force du vent. Si bien que dans le domaine \u00e0 la fois clair et obscur du consentement, nos contemporains seraient bien inspir\u00e9s de ne pas se pr\u00e9cipiter. D&rsquo;un un fait divers scabreux, d&rsquo;un homme abusant de son pouvoir pour s\u00e9duire des femmes ou les obliger, on passe \u00e0 la dimension claire-obscure de &quot;consentir&quot;, en g\u00e9n\u00e9ral, \u00e0 un rapport sexuel. Sous quelle forme les petits malins et petites malines qui, outr\u00e9s, s&rsquo;expriment sur la toile ou sur les ondes pourraient-ils nous exposer la nature pr\u00e9cise de ce consentement? Quand deux \u00eatres s&rsquo;attirent suffisamment (et une attirance peut-\u00eatre malsaine, perverse, ambig\u00fce) \u00e0 partir de quel moment chacun sera-t-il conscient de son consentement \u00e0 aller plus loin? Dans le d\u00e9sir sexuel, toute personne moyennement sensible, et \u00e0 plus forte raison toute personne inform\u00e9e, un m\u00e9decin, un psychologue, dont le m\u00e9tier consiste souvent \u00e0 expliquer \u00e0 ceux qui le souhaitent le pourquoi de leurs maladies, ou de leurs maladresses, sait qu&rsquo;il n&rsquo;y a en ce domaine ni de oui radical, ni de non radical, que le d\u00e9sir est influen\u00e7able, contradictoire, labile, et que donc parler de consentement \u00e0 une relation sexuelle &ndash;tout particuli\u00e8rement \u00e0 notre \u00e9poque o&ugrave; chacun se vautre dans le <em>tout est permis<\/em> et se croit malin de <em>faire ce qu&rsquo;il veut<\/em>&ndash;, est r\u00e9ducteur pour ne pas dire absurde. Personne, homme ou femme, n&rsquo;a-t-il jamais regrett\u00e9 un jour ou un an apr\u00e8s avoir couch\u00e9 avec telle ou telle personne alors que sur le moment son &quot;consentement&quot; \u00e9tait indiscutable? Et tous ceux qui ont eu ce regret sont-il aller porter plainte pour &quot;abus&quot; ou pour &quot;viol&quot;, se sont-il battus de verges, se sont-ils suicid\u00e9s? A contrario, combien ne se battent-ils pas la coulpe d&rsquo;avoir refus\u00e9, ou laiss\u00e9 pass\u00e9, une occasion servie sur un plateau par un &quot;consenteur&quot; ou &quot;consentrice&quot; ?<\/p>\n<\/p>\n<p><p>Faudra-t-il un jour demander en bonne et due forme (si on est homme), son consentement dans la langue de Racine \u00e0 une femme avant d&rsquo;avoir l&rsquo;insondable privil\u00e8ge de la p\u00e9n\u00e9trer? Et si cela \u00e9tait si simple, imagine-t-on que ladite femme trouverait la m\u00e9thode \u00e0 son go&ucirc;t ? Le d\u00e9sir ne fait-il pas comme le souligne le g\u00e9nie de la langue plier les volont\u00e9s, effondrer les murailles, favoriser les consentements, c&rsquo;est-\u00e0-dire le <strong><em>sentir ensemble<\/em><\/strong>, comme l&rsquo;intelligence fait comprendre, fait <em>cumprehendere<\/em>, fait prendre l&rsquo;autre avec soi? L&rsquo;intelligence peut convaincre, le d\u00e9sir se contente souvent de vaincre et ce n&rsquo;est pas forc\u00e9ment au d\u00e9triment du vaincu.<\/p>\n<\/p>\n<p><p>Le tragique de l&rsquo;\u00e9poque, c&rsquo;est que beaucoup de femmes (heureusement pas toutes) se laissent guider par des abstractions juridiques et plus beaucoup par le sentiment qui <em>consent<\/em>. J&rsquo;esp\u00e8re ne d\u00e9clencher que la hargne des ignorants en disant que la premi\u00e8re grande erreur de notre temps c&rsquo;est d&rsquo;avoir fait croire qu&rsquo;il y avait, ou plut\u00f4t qu&rsquo;il devait y avoir, \u00e9galit\u00e9 entre l&rsquo;homme et la femme. Le beau concept (chr\u00e9tien) d&rsquo;Egalit\u00e9 de tous les Hommes entre eux, concept de nature d&rsquo;abord spirituelle (aux yeux de Dieu tous les Hommes sont fr\u00e8res et donc \u00e9gaux devant leur cr\u00e9ateur et \u00e9gaux entre eux parce qu&rsquo;\u00e9gaux devant leur cr\u00e9ateur), s&rsquo;est laiss\u00e9 r\u00e9tr\u00e9cir, diminuer, capturer, par le juridique dans la d\u00e9claration des droits de 1789 qui indique que les hommes naissent libres et \u00e9gaux en droit. Il y a deux mots importants : &quot;naissent&quot; on l&rsquo;oublie un peu trop, et surtout, &quot;ils ne sont pas \u00e9gaux en fait, mais en droit&quot;. On est donc descendu d&rsquo;un degr\u00e9 si on mesure \u00e0 partir du spirituel. De plus, \u00e9gaux en droit suppose que le droit est le m\u00eame pour tout le monde. En th\u00e9orie oui, en pratique non et tout le monde le sait au moins depuis La Fontaine. Encore un cran vers en bas. La pr\u00e9somption d&rsquo;innocence deviendra bient\u00f4t de culpabilit\u00e9 si on est homme et la femme redeviendra l&rsquo;ange tomb\u00e9&hellip; malheureusement pourvu d&rsquo;un sexe! Enfin, tout individu non paralys\u00e9 du cerveau se rend vite compte quand m\u00eame qu&rsquo;il y a un abime entre libert\u00e9 et \u00e9galit\u00e9. Si je mets libert\u00e9 au premier plan je ne tiendrai gu\u00e8re compte de ceux que je jugerai inf\u00e9rieur \u00e0 moi et si je mets \u00e9galit\u00e9 au premier plan j&rsquo;aurai tendance \u00e0 niveler un peu trop et \u00e0 bafouer la libert\u00e9, surtout celle de ceux qui ne se sentent absolument pas \u00e9gaux \u00e0 moi, mais sup\u00e9rieurs. Et si \u00e0 toutes ces contradictions et in\u00e9galit\u00e9s, j&rsquo;ajoute celle de la diff\u00e9rence des sexes, je suis bien oblig\u00e9 de reconna&icirc;tre que je dois descendre d&rsquo;un cran encore. Les hommes et les femmes ont des qualit\u00e9s et des d\u00e9fauts qui ne sont pas les m\u00eames et c&rsquo;est d&rsquo;ailleurs pourquoi, ils se mettent ensemble pour essayer courageusement et amoureusement de les compenser. Il est clair qu&rsquo;ils n&rsquo;y arrivent plus, ou de moins en moins, que le consentement \u00e0 ce que l&rsquo;autre soit diff\u00e9rent de moi, n&rsquo;est plus admis. C&rsquo;est ainsi que la guerre des faux \u00e9gaux et des vrais ego s&rsquo;amplifie, et continuera de le faire jusqu&rsquo;aux plus grandes violences, tant que chacune de ces cr\u00e9atures n&rsquo;aura pas la sagesse et la d\u00e9cence de comprendre que dans le consentement de deux \u00e9poux (ou de deux amants, concubins, compagnons, que sais-je) \u00e0 s&rsquo;unir il s&rsquo;agit toujours d&rsquo;une union pour le meilleur et pour le pire. Un pire relativement \u00e0 la destin\u00e9e qui peut \u00eatre terrible, et un meilleur si on est assez g\u00e9n\u00e9reux pour se &quot;consentir&quot;. En tout cas, une chose est s&ucirc;re, le pire sera toujours au rendez-vous si on se pr\u00e9pare d\u00e8s le d\u00e9but \u00e0 balancer son porc ou sa truie pour la simple raison que le porc et la truie se croyaient \u00e9gaux, fait du m\u00eame bois, grandis dans les m\u00eames aspirations, remplis de la m\u00eame sensibilit\u00e9, attir\u00e9s par les m\u00eames plaisirs, \u00e9treints par les m\u00eames joies. L&rsquo;homme et la femme sont des \u00eatres humains semblables, ils ne sont pas \u00e9gaux. Ils m\u00e9ritent chacun le respect \u00e0 condition qu&rsquo;ils en soient capables l&rsquo;un envers l&rsquo;autre. Il y a des veinstein, ils sont l\u00e9gions. Il y a aussi des prostitu\u00e9es d&rsquo;un nombre \u00e0 peu pr\u00e8s \u00e9quivalent qui les aiment pour faire carri\u00e8re et qui, une fois carri\u00e8re faite, les rides venues, les frustrations naturelles de la vie bues jusqu&rsquo;\u00e0 la lie, se vengent. Alors les sorci\u00e8res de la fausse pudeur et de la haine rentr\u00e9e, enfourchent leur balai et sillonnent le ciel m\u00e9diatique pour le plus grands plaisirs des frustr\u00e9s de la terre et des haineuses du ciel.<\/p>\n<\/p>\n<p><p>&quot;Qui dit mot&quot;, ne consent pas \u00e0 accepter la l\u00e9g\u00e8ret\u00e9 inculte de ceux et celles qui glosent sur le consentement dans les relations sexuelles. Honorons les gentils petits cochons et les non moins gentilles petites truies qui leur courent apr\u00e8s et ayons la d\u00e9cence de ne pas lorgner indument dans le lit du voisin parce que dans le n\u00f4tre il ne se passe rien.<\/p>\n<\/p>\n<p><h4>Marc G\u00e9belin<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui ne dit mot consent&hellip; Consentez-vous \u00e0 prendre pour \u00e9poux untel? &Agrave; prendre pour \u00e9pouse une telle? La r\u00e9ponse est toujours oui ou non. Elle concerne la libre volont\u00e9 de chaque personne et la question vient d&rsquo;une tierce qui a autorit\u00e9 pour enregistrer l\u00e9galement le consentement. Consentir \u00e0 l&rsquo;imp\u00f4t est-ce tout \u00e0 fait synonyme d&rsquo;\u00eatre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[11880,13560,2766,11925],"class_list":["post-77572","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-gebelin","tag-homme-femme","tag-relations","tag-societal"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77572"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77572\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}