{"id":77676,"date":"2017-12-24T05:01:00","date_gmt":"2017-12-24T05:01:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2017\/12\/24\/noel-en-goguette\/"},"modified":"2017-12-24T05:01:00","modified_gmt":"2017-12-24T05:01:00","slug":"noel-en-goguette","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2017\/12\/24\/noel-en-goguette\/","title":{"rendered":"No\u00ebl en goguette"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">No\u00ebl en goguette<\/h2>\n<\/p>\n<p><p>Le bon Pape Fran\u00e7ois nous invite \u00e0 toujours plus de transparence en cette \u00e9poque o&ugrave; les chr\u00e9tiens sont appel\u00e9s \u00e0 se fondre dans le relativisme universel. L&rsquo;&oelig;cum\u00e9nisme qu&rsquo;il professe est bas\u00e9 sur les tables de cette loi mondialiste qui dicte la marche de l&rsquo;humanit\u00e9 vers le gouffre de l&rsquo;indistinction. Adepte des grands \u00e9carts, pr\u00eachant l&rsquo;ouverture maximale des fronti\u00e8res, le souverain pontife exhorte ses fid\u00e8les brebis \u00e0 toujours plus de compassion envers les hordes de migrants qui s&rsquo;appr\u00eatent \u00e0 d\u00e9ferler sur les terres infertiles d&rsquo;une vieille Europe d\u00e9pass\u00e9e par les \u00e9v\u00e9nements.<\/p>\n<\/p>\n<p><p>Ap\u00f4tre de la simplicit\u00e9 volontaire, Fran\u00e7ois pr\u00e9tend vouloir nettoyer la Curie romaine afin de reb\u00e2tir une \u00e9glise en ruine et insuffler un regain de vigueur \u00e0 l&rsquo;auguste institution.  Voil\u00e0 pourquoi il s&rsquo;est entour\u00e9 de &laquo; conseillers sp\u00e9ciaux &raquo; qui semblent presque tous appartenir aux milieux de la haute-finance. C&rsquo;est ainsi qu&rsquo;un Peter Sutherland &ndash; pr\u00e9sident de Goldman Sachs et un dirigeant actif du groupe de Bilderberg &ndash; a \u00e9t\u00e9 appoint\u00e9 \u00e0 la <em>Commission international catholique sur les migrations <\/em>(ICMC).  L&rsquo;auguste conseiller de sa Saintet\u00e9 estime qu&rsquo;il serait souhaitable que l&rsquo;Allemagne puisse recevoir 1 million de migrants par an et &hellip; cela pour une p\u00e9riode d&rsquo;au moins 30 ans !<\/p>\n<\/p>\n<p><p>Un autre conseiller, Chris Patten &ndash; grand manitou charg\u00e9 de r\u00e9former le fonctionnement des m\u00e9dias du Vatican &ndash; co-pr\u00e9side <em>l&rsquo;International Crisis Group <\/em>mis sur pied par l&rsquo;ineffable Georges Soros. Disciple d&rsquo;un factice vivre-ensemble, Patten se m\u00e9fie comme de la peste de tout ce qui peut se rapprocher de la &laquo; d\u00e9mocratie directe &raquo; et n&rsquo;h\u00e9site pas \u00e0 faire l&rsquo;\u00e9loge d&rsquo;une immigration qui conforte la th\u00e9ologie du &laquo; Grand Remplacement &raquo; de nos guides spirituels de pacotille. D&rsquo;autre &laquo; conseillers sp\u00e9ciaux &raquo;, proches de l&rsquo;<em>Open Society <\/em>de Soros, ont \u00e9t\u00e9 invit\u00e9s \u00e0 revoir les r\u00e8gles de gouvernance et l&rsquo;administration des finances d&rsquo;une &Eacute;glise qui se positionne, in\u00e9luctablement, aux premi\u00e8res loges des organisations satellites de la gouvernance mondialiste. Voil\u00e0 qui a de quoi ravir les masses de catholiques ti\u00e8des qui ont vot\u00e9 pour Emmanuel Macron, un autre ap\u00f4tre de cette simplicit\u00e9 volontaire impos\u00e9e de force aux gagne-petit.<\/p>\n<\/p>\n<p><p>Adoptant une d\u00e9marche d\u00e9bonnaire face aux m\u00e9dias, le Pape Fran\u00e7ois s&rsquo;active \u00e0 r\u00e9former en profondeur tout ce qui avait \u00e9t\u00e9 \u00e9pargn\u00e9 \u00e0 l&rsquo;\u00e9poque du Concile Vatican II. Sandro Magister &ndash; un journaliste sp\u00e9cialis\u00e9 sur les questions vaticanes &ndash; estime que le Pape gouverne comme un despote l&rsquo;&Eacute;glise et la Curie romaine, tout en cela en porte-\u00e0-faux avec son image de pr\u00e9dicateur progressiste. Malgr\u00e9 tout, certains proches collaborateurs du Souverain pontife soutiennent que le principal int\u00e9ress\u00e9 fait des miracles afin de maintenir l&rsquo;unit\u00e9 entre les fid\u00e8les, histoire d&rsquo;\u00e9viter qu&rsquo;un schisme ne finisse par se produire. Le Pape consolide ses <em>Assises<\/em> en mettant de l&rsquo;<em>aven <\/em>une simplicit\u00e9 volontaire au service de la neutralisation de tout ce qui fondait le <em>magister <\/em>d&rsquo;une institution qui n&rsquo;avait jamais h\u00e9sit\u00e9 \u00e0 s&rsquo;opposer aux princes de ce monde<em>. <\/em>Virtuose de la casuistique, il affirme vouloir lutter pour une plus grande justice sociale et n&rsquo;h\u00e9site pas \u00e0 fustiger la concupiscence des mieux-nantis. Malheureusement, toute cette pr\u00e9dication part en fum\u00e9e lorsque l&rsquo;on examine la feuille de route de ce pontificat qui semble avoir \u00e9t\u00e9 orchestr\u00e9 de but en blanc par les pontes de la conf\u00e9rence de Bilderberg.<\/p>\n<\/p>\n<p><p>Tout le toll\u00e9 qui a \u00e9t\u00e9 provoqu\u00e9 par l&rsquo;installation de la tristement c\u00e9l\u00e8bre &laquo; cr\u00e8che de la mis\u00e9ricorde &raquo;, sur la place Saint-Pierre, traduit bien l&rsquo;\u00e9tat des lieux. Il y a p\u00e9ril en la demeure !<\/p>\n<\/p>\n<p><h4>Patrice-Hans Perrier<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No\u00ebl en goguette Le bon Pape Fran\u00e7ois nous invite \u00e0 toujours plus de transparence en cette \u00e9poque o&ugrave; les chr\u00e9tiens sont appel\u00e9s \u00e0 se fondre dans le relativisme universel. L&rsquo;&oelig;cum\u00e9nisme qu&rsquo;il professe est bas\u00e9 sur les tables de cette loi mondialiste qui dicte la marche de l&rsquo;humanit\u00e9 vers le gouffre de l&rsquo;indistinction. Adepte des grands&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[8780,9535,2653,3232,12606],"class_list":["post-77676","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-catholiques","tag-chris","tag-francois","tag-patten","tag-perrier"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77676"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77676\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}