{"id":77686,"date":"2018-01-01T09:20:07","date_gmt":"2018-01-01T09:20:07","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/01\/notre-schizophrenie-controlee\/"},"modified":"2018-01-01T09:20:07","modified_gmt":"2018-01-01T09:20:07","slug":"notre-schizophrenie-controlee","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/01\/notre-schizophrenie-controlee\/","title":{"rendered":"Notre schizophr\u00e9nie-contr\u00f4l\u00e9e"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Notre schizophr\u00e9nie-contr\u00f4l\u00e9e<\/h2>\n<\/p>\n<p><p>1<sup>er<\/sup> janvier 2018 &ndash; Parlons de l&rsquo;exemple qui a suscit\u00e9 l&rsquo;id\u00e9e du propos g\u00e9n\u00e9ral. Il s&rsquo;agit d&rsquo;une interview tr\u00e8s r\u00e9cente de Ron Paul au Washington <em>Examiner<\/em>, quotidien qui n&rsquo;est certainement ni dissident ni antiSyst\u00e8me, le <a href=\"http:\/\/www.washingtonexaminer.com\/ron-paul-trump-may-be-vulnerable-to-2020-gop-primary-challenge\/article\/2644395\">26 d\u00e9cembre 2017<\/a> ; et Paul de dire sans ambages, r\u00e9pondant \u00e0 une question sur l&rsquo;\u00e9tat de la nation, des USA : &laquo; <em>Nous sommes tout proches de quelque chose qui ressemble \u00e0 ce qui est arriv\u00e9 en 1989 lorsque le syst\u00e8me sovi\u00e9tique s&rsquo;est effondr\u00e9. J&rsquo;esp\u00e8re seulement que notre syst\u00e8me se d\u00e9sint\u00e9grera avec aussi peu de d\u00e9g\u00e2ts que le syst\u00e8me sovi\u00e9tique<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p>R\u00e9ponse aimable (\u00ab\u00a0<em>gracefuly<\/em>\u00a0\u00bb pour \u00ab\u00a0aussi peu de d\u00e9g\u00e2ts\u00a0\u00bb, ce qui vous a un petit air effectivement gracieux) ; mais r\u00e9ponse sans aucun doute tranchante et catastrophiste, qui m\u00e9rite une attention disons m\u00e9tahistorique. Par ailleurs, <strong>l&rsquo;avis de Ron Paul se retrouve chez nombre de commentateurs de qualit\u00e9<\/strong>, dans le camp antiSyst\u00e8me veux-je dire, souvent par des voies diff\u00e9rentes et selon des logiques sp\u00e9cifiques. Malgr\u00e9 sa r\u00e9p\u00e9tition, cet avis garde son aspect sensationnel et dramatique, &ndash; <strong>peut-\u00eatre m\u00eame, \u00e0 cause de la r\u00e9p\u00e9tition<\/strong>&#8230; Au contraire d&rsquo;une r\u00e9p\u00e9tition par imitation et go&ucirc;t du sensationnalisme et de la dramatisation gratuites, on la per\u00e7oit d&rsquo;une fa\u00e7on radicalement diff\u00e9rente, comme un sentiment commun, voire une intuition partag\u00e9e ; <strong>la r\u00e9p\u00e9tition devient alors comme une mar\u00e9e qui monte, comme une \u00e9vidence qui grandit irr\u00e9sistiblement<\/strong>&#8230;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Mais revenons \u00e0 l&rsquo;interview cit\u00e9, qui se poursuit sans vraiment s&rsquo;attarder \u00e0 l&rsquo;affaire de l&rsquo;effondrement proche des USA <strong>comme s&rsquo;il s&rsquo;agissait d&rsquo;une anecdote exotique, d&rsquo;une digression aimable<\/strong>&#8230;. L&rsquo;on passe \u00e0 des questions de pr\u00e9visions politiques, notamment \u00e9lectorales, par rapport au GOP (les r\u00e9publicains du <em>Great Old Party<\/em>) et aux pr\u00e9sidentielles de 2020. Ron Paul r\u00e9pond d&rsquo;une fa\u00e7on classique, en avan\u00e7ant d&rsquo;ailleurs une pr\u00e9vision qu&rsquo;on pourrait juger politiquement int\u00e9ressante : &laquo; <em>Trump sera vuln\u00e9rable lors des primaires<\/em> [de d\u00e9signation du candidat r\u00e9publicain] <em>de 2020<\/em> &raquo;. Justement, cette phrase est exactement celle du titre de l&rsquo;article, comme s&rsquo;il s&rsquo;agissait du plus important dans l&rsquo;entretien : \u00ab\u00a0<em>Ron Paul : Trump may be vulnerable to 2020 GOP primary challenge<\/em>\u00ab\u00a0. Ainsi appara&icirc;t notre-schizophr\u00e9nie, non pas comme maladie de la psychologie <strong>mais comme n\u00e9cessit\u00e9 o&ugrave; se trouvent les esprits disons moins obscurs et plus ouverts que le courant de vivre en m\u00eame temps dans deux mondes diff\u00e9rents<\/strong>, une oreille aux aguets du moindre signe de la catastrophes proche de venir, l&rsquo;autre \u00e9puis\u00e9e mais vaillante de devoir suivre les vanit\u00e9s aveugl\u00e9es d&rsquo;un monde d\u00e9pass\u00e9e qui choisit de faire l&rsquo;autruche avec la vivacit\u00e9 d&rsquo;une taupe.<\/p>\n<\/p>\n<p><p>Car, si l&rsquo;on prend Ron Paul au s\u00e9rieux, comme c&rsquo;est le cas dans cet article o&ugrave; on l&rsquo;interviewe, comment se peut-il faire que l&rsquo;on se concentre et qu&rsquo;on juge comme la plus importante de ses d\u00e9clarations la pr\u00e9vision de possibles difficult\u00e9s de Trump en 2020 d&rsquo;\u00eatre \u00e0 nouveau le candidat r\u00e9publicain, alors que le m\u00eame Ron Paul pr\u00e9voit, avec presque plus d&rsquo;assurance que sa pr\u00e9vision sur les primaires r\u00e9publicaines de 2020, que les USA vont s&rsquo;effondrer assez rapidement (\u00ab\u00a0tout proches\u00a0\u00bb) de la m\u00eame fa\u00e7on que l&rsquo;URSS s&rsquo;est effondr\u00e9e en 1989 ? <strong>Serons-nous encore l\u00e0<\/strong>, je veux dire dans l&rsquo;\u00e9tat actuel des structures branlantes et croulantes, pour voir le pr\u00e9sident Donald J. Trump \u00e9ventuellement mis en difficult\u00e9s durant les primaires de l&rsquo;hiver et du printemps 2020 ? Voyez-vous l&rsquo;incroyable disparit\u00e9 des \u00e9v\u00e8nements en prospective selon Ron Paul, et comment l&rsquo;intervieweur choisit le plus insignifiant, le plus passe-partout, le plus racoleur pour le conformisme parmi les d\u00e9clarations disponibles ?<\/p>\n<\/p>\n<p><p>Je ne vais pas \u00e9piloguer sur l&rsquo;attitude du Washington <em>Examiner<\/em> ni m\u00eame parler de complot et de censure, puisqu&rsquo;il y a eu tout de m\u00eame la question et sa r\u00e9ponse sur l&rsquo;effondrement du Syst\u00e8me. Je crois qu&rsquo;il y a l\u00e0 comme une sorte de r\u00e9flexe-pavlovien du parti des conformistes-Syst\u00e8me, de se conduire vraiment en zombies-Syst\u00e8me, de ne rien voir comme une taupe qui jouerait \u00e0 faire l&rsquo;autruche, bien que le mat\u00e9riel essentiel mais qui leur fait horreur existe tout de m\u00eame pour qui sait lire.<\/p>\n<\/p>\n<p><p>(C&rsquo;est de la \u00ab\u00a0source ouverte\u00a0\u00bb&#8230; Les \u00ab\u00a0sources ouvertes\u00a0\u00bb, &ndash; <a href=\"http:\/\/www.dedefensa.org\/article\/ma-fascination-pour-osint\">OSINT<\/a>, &ndash; valent tous les complots et les documents <em>classified <\/em>du monde et <strong>nous en savons plus, dans nos petites officines<\/strong>, que toutes les \u00ab\u00a0vaches sacr\u00e9es\u00a0\u00bb et expertes du Syst\u00e8me, celles qui ne cessent d&rsquo;aligner leurs prospectives et leurs graphiques sur la reprise, sur la <em>narrative<\/em>, sur les publicistes du <em>Corporate Power<\/em>, sur les monstruosit\u00e9s de Poutine et la suite.)<\/p>\n<\/p>\n<p><p>Non, la chose sur laquelle je veux insister, c&rsquo;est bien notre-schizophr\u00e9nie, \u00ab\u00a0comme n\u00e9cessit\u00e9 o&ugrave; se trouvent les esprits disons moins obscurs et plus ouverts que le courant de vivre en m\u00eame temps dans deux mondes diff\u00e9rents, une oreille aux aguets du moindre signe de la catastrophes proche de venir, l&rsquo;autre \u00e9puis\u00e9e mais vaillante de devoir suivre les vanit\u00e9s aveugl\u00e9es d&rsquo;un monde d\u00e9pass\u00e9e&#8230;\u00a0\u00bb. Nous vivons chaque jour cette curieuse ambigu\u00eft\u00e9 psychologique, o&ugrave; d&rsquo;une part il nous faut nous conduire \u00ab\u00a0normalement\u00a0\u00bb, y compris dans notre discours lorsque le sujet abord\u00e9 y invite, c&rsquo;est-\u00e0-dire nous conduire \u00e0 nos propres yeux comme si effectivement nous \u00e9tions atteint d&rsquo;une pathologie qui nous am\u00e8ne \u00e0 faire une sorte de simulation, \u00e0 accepter le simulacre que nous proposent les autruches-taupes ; o&ugrave; d&rsquo;autre part, \u00e0 la premi\u00e8re occasion venu, nous nous replongeons comme l&rsquo;on s&rsquo;\u00e9l\u00e8ve dans la r\u00e9flexion mi-stup\u00e9faite mi-angoiss\u00e9e mais de toutes les fa\u00e7ons sublime \u00e0 partir de signes nouveaux de ce que nous pr\u00e9voyons comme<strong> in\u00e9luctable, catastrophique et sans-retour, fondant sur nous comme la foudre des dieux de l&rsquo;Olympe<\/strong>.<\/p>\n<\/p>\n<p><p>Cette pens\u00e9e (cette intuition de la catastrophe) para&icirc;trait \u00e0 premi\u00e8re vue assez lourde, tr\u00e8s difficile \u00e0 porter, assur\u00e9ment effrayante, voire paralysante, entreteneuse d&rsquo;angoisse sinon par instants d&rsquo;une certaine panique ; ainsi devrait-on en juger selon la raison qui veut tenir \u00e9gale la balance du jugement. Mais nous ne sommes pas au tribunal et je ne suis pas un t\u00e9moin de l&rsquo;histoire courante, mais une sentinelle d&rsquo;une m\u00e9tahistoire dont la grandeur et la puissance m&rsquo;\u00e9l\u00e8vent et m&rsquo;inspirent autant qu&rsquo;elles pourraient m&rsquo;effrayer en p\u00e9n\u00e9trant par les fissures de moi-m\u00eame que sont mes instants d&rsquo;abandon, \u00e0 la fine pointe du lever ou bien dans un \u00e9clair sombre de la lumi\u00e8re du cr\u00e9puscule. Je ne sais qu&rsquo;une chose d&rsquo;assur\u00e9 : une fois qu&rsquo;elle vous a touch\u00e9 comme un Dieu le fait de sa gr\u00e2ce, &ndash; <strong>cette intuition haute pour dire son v\u00e9ritable nom, &ndash; elle ne vous quitte plus<\/strong>. Ainsi cette lourdeur est-elle bien relative, <strong>une lourdeur incroyable mais l\u00e9g\u00e8re comme une plume<\/strong>, une semeuse de frayeurs terribles que vous ne pouvez vous emp\u00eacher de juger sublimes ; ainsi ce c\u00f4t\u00e9-ci de notre-schizophr\u00e9nie est-il le plus glorieux, le plus superbe, le plus incroyablement grandiose. Nous attendons la chute de notre contre-civilisation, l&rsquo;effondrement du Syst\u00e8me, comme l&rsquo;on guette une r\u00e9v\u00e9lation qui ne peut pas ne pas se manifester.<\/p>\n<\/p>\n<p><p>Le reste, c&rsquo;est le tout-venant, le fait anodin qui nous fait rentrer dans le rang par n\u00e9cessit\u00e9 temporaire, quand je me vois coinc\u00e9 dans une conversation courante (par Dieu bienveillant, c&rsquo;est assez rare jusqu&rsquo;au rarissime), confront\u00e9 \u00e0 des platitudes qui sont \u00e0 des ann\u00e9e-lumi\u00e8res du sentiment dont je vous parlais \u00e0 l&rsquo;instant ; que faire, mon Dieu, sinon marmonner une approbation prudente ou une r\u00e9serve amicale, sans en dire un mot en v\u00e9rit\u00e9. Dans cette sorte de circonstances, certains diraient \u00ab\u00a0dans les d&icirc;ners en ville\u00a0\u00bb, \u00e0 Paris s&rsquo;il vous plait, je me ratatine, je me rapetisse comme la t\u00eate d&rsquo;un de leurs ennemis promptement trait\u00e9e par les Jivaros. Il existe ainsi un oc\u00e9an d&rsquo;une multitude, remarquable par sa m\u00e9diocrit\u00e9 et son refus de l&rsquo;\u00e9norme puissance de la v\u00e9rit\u00e9 catastrophique du monde, et pour survivre je dois parfois tremper le petit bout de mon plus petit doigt de pied dans cette eau ti\u00e9dasse, saum\u00e2tre, putride et puante, et sans vie, etc. (Par Dieu compatissant, cela devient vraiment de plus en plus rare.) A ce moment-l\u00e0, ce c\u00f4t\u00e9-l\u00e0 de ma schizophr\u00e9nie m&rsquo;est absolument insupportable, sa l\u00e9g\u00e8ret\u00e9, son ignorance de l&rsquo;essence et son absence de substance me sont un poids insupportable ; <strong>l&rsquo;insupportable l\u00e9g\u00e8ret\u00e9 du vide, si vous voulez&#8230; Ou, dit autrement mais dit superbement, &laquo; <em>l&rsquo;\u00e9norme poids du rien <\/em>&raquo;<\/strong>.<\/p>\n<\/p>\n<p><p>(Joseph de Maistre, dans une lettre de 1805 \u00e0 son fr\u00e8re Nicolas, \u00e9voquant la vie \u00e0 Chamb\u00e9ry en 1785, lui-m\u00eame le comte Joseph, dans ce temps-l\u00e0 dans l&rsquo;attente des \u00e9v\u00e8nements consid\u00e9rables qu&rsquo;il devinait intuitivement : &laquo; <em>Je me rappelle ces temps o&ugrave;, dans une petite ville de ta connaissance<\/em> [&hellip;] <em>et ne voyant autour de notre cercle \u00e9troit <\/em>[&hellip;] <em>que de petits hommes et de petites choses, je me disais : \u00ab\u00a0Suis-je donc condamn\u00e9 \u00e0 vivre et \u00e0 mourir ici comme une huitre attach\u00e9e \u00e0 son rocher ?\u00a0\u00bb Alors je souffrais beaucoup : j&rsquo;avais la t\u00eate charg\u00e9e, fatigu\u00e9e,<\/em> <strong><em>aplatie<\/em><\/strong> <em>par <strong>l&rsquo;\u00e9norme poids du rien<\/strong><\/em>&hellip; &raquo;)<\/p>\n<\/p>\n<p><p>Contrairement \u00e0 ce que pensent les esprits policiers encore en nombre assez \u00e9lev\u00e9, et que ne pensent pas un nombre croissant d&rsquo;esprits d\u00e9barrass\u00e9s de tous ces embarras, la conscience charg\u00e9e de la vision de la catastrophe qui nous guette est aussi saine, aussi forte, aussi superbe que l&rsquo;air glac\u00e9 des plus hauts sommets. &laquo; <em>Levez-vous vite, orages d\u00e9sir\u00e9s, qui devez emporter Ren\u00e9 dans les espaces d&rsquo;une autre vie !<\/em> &raquo;&#8230; Citer cette phrase \u00e0 mon \u00e2ge repr\u00e9sente une certaine audace, \u00e0 moins que Ren\u00e9 ait voulu parler \u00ab\u00a0d&rsquo;une autre vie\u00a0\u00bb d&rsquo;outre-tombe, d&rsquo;o&ugrave; l&rsquo;on \u00e9crit ses m\u00e9moires sans craindre les importuns et o&ugrave; l&rsquo;on fr\u00e9quente des esprits plus habit\u00e9s par le go&ucirc;t de la libert\u00e9 que par l&rsquo;essorage d\u00e9mocratico-postmoderne qui blanchit la pens\u00e9e aussi bien que l&rsquo;argent sale.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre schizophr\u00e9nie-contr\u00f4l\u00e9e 1er janvier 2018 &ndash; Parlons de l&rsquo;exemple qui a suscit\u00e9 l&rsquo;id\u00e9e du propos g\u00e9n\u00e9ral. Il s&rsquo;agit d&rsquo;une interview tr\u00e8s r\u00e9cente de Ron Paul au Washington Examiner, quotidien qui n&rsquo;est certainement ni dissident ni antiSyst\u00e8me, le 26 d\u00e9cembre 2017 ; et Paul de dire sans ambages, r\u00e9pondant \u00e0 une question sur l&rsquo;\u00e9tat de la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[2631,2651,2803,4595,2711,4596,3140,8735,7716,3310,3014],"class_list":["post-77686","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-de","tag-du","tag-effondrement","tag-joseph","tag-le","tag-maistre","tag-paul","tag-poids","tag-rien","tag-ron","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77686"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77686\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}