{"id":77712,"date":"2018-01-13T15:09:21","date_gmt":"2018-01-13T15:09:21","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/13\/les-drones-antirusses-devoiles-parfakenews\/"},"modified":"2018-01-13T15:09:21","modified_gmt":"2018-01-13T15:09:21","slug":"les-drones-antirusses-devoiles-parfakenews","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/13\/les-drones-antirusses-devoiles-parfakenews\/","title":{"rendered":"Les drones antirusses d\u00e9voil\u00e9s par\u00a0<em>FakeNews<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Les drones antirusses d\u00e9voil\u00e9s par <em>FakeNews<\/em><\/h2>\n<\/p>\n<p><p>Encore une fois, il est excellent pour la sant\u00e9 et pour l&rsquo;humeur de savoir que tout ce qui suit est <em>FakeNews <\/em>et rien que<em> FakeNews <\/em>puisque relay\u00e9s par des r\u00e9seaux compl\u00e8tement <em>Fake <\/em>(Tass en l&rsquo;occurrence, c&rsquo;est dire\/c&rsquo;est pli\u00e9), venant d&rsquo;un pr\u00e9sident-bidon\/gangster douteux et de l&rsquo;un de ses sbires galonn\u00e9s et \u00e9toil\u00e9s, &ndash; respectivement le pr\u00e9sident Poutine et le g\u00e9n\u00e9ral Novikov, chef du d\u00e9veloppement des v\u00e9hicules a\u00e9riens arm\u00e9s sans pilotes (UAV pour<em> Unmanned Armed Vehicles<\/em>) \u00e0 l&rsquo;\u00e9tat-major g\u00e9n\u00e9ral de l&rsquo;arm\u00e9e russe. Cela dit et apr\u00e8s s&rsquo;\u00eatre assur\u00e9 qu&rsquo;on n&rsquo;en croirait pas un seul mot, il faut appr\u00e9cier combien les Russes, apprenant tr\u00e8s vite la technique de la communication \u00ab\u00a0ouverte\u00a0\u00bb (en \u00ab\u00a0source ouverte\u00a0\u00bb), se trouvent aujourd&rsquo;hui \u00e0 des ann\u00e9es-lumi\u00e8re de leurs pr\u00e9d\u00e9cesseurs sovi\u00e9tiques lorsqu&rsquo;il s&rsquo;agit de la description d&rsquo;op\u00e9rations militaires dans le d\u00e9tail. Ils ont l&rsquo;avantage du type \u00ab\u00a0c&rsquo;est pas d&rsquo;jeu\u00a0\u00bb de n&rsquo;avoir qu&rsquo;\u00e0 dire la v\u00e9rit\u00e9 pour d\u00e9velopper leur propagande du type <em>FakeNews<\/em>, avec beaucoup de moyens de renseignement humain et \u00e9lectronique pour substantiver cette v\u00e9rit\u00e9-de-situation. Leurs coll\u00e8gues du Pentagone, eux, se contentent du sc\u00e9nario hollywoodien habituel : lorsqu&rsquo;on leur demande comment il se fait que les terroristes disposent de drones capables de lancer des op\u00e9rations comme celles du 6 janvier contre les deux bases russes de Syrie, ils rigolent et r\u00e9pondent qu&rsquo;on peut trouver tout ce qu&rsquo;on veut \u00ab\u00a0sur le march\u00e9\u00a0\u00bb, comme vous et moi. Rendez-vous donc aux Puces pour fabriquer votre <em>Fake<\/em>drone&#8230;<\/p>\n<\/p>\n<p><p>Effectivement, le 11 janvier on a eu un tr\u00e8s grand nombre d&rsquo;informations venues de la partie russe, sur <a href=\"http:\/\/www.dedefensa.org\/article\/du-drone-a-la-strategie-du-chaos\">cette attaque du 6 janvier<\/a> qui s&rsquo;est termin\u00e9e par un d\u00e9sastre pour les soi-disant \u00ab\u00a0terroristes\u00a0\u00bb. (Sept drones abattus, six intercept\u00e9 \u00e9lectroniquement et pris sous contr\u00f4le, trois terminant leurs vols en <em>crash <\/em>et les trois autres se posant sans encombre sans doute sur la base russe en Syrie de Hmeimim, guid\u00e9s par les contr\u00f4leurs russes.)<\/p>\n<\/p>\n<p><p>La premi\u00e8re \u00ab\u00a0source\u00a0\u00bb est rien moins que Poutine, parlant \u00e0 la presse et donnant des d\u00e9tails extr\u00eamement pr\u00e9cis, et insistant sur le fait que <strong>les aspects rustiques des drones constituaient un montage, un \u00ab\u00a0camouflage\u00a0\u00bb pour faire croire \u00e0 des engins fabriqu\u00e9s d&rsquo;une mani\u00e8re \u00ab\u00a0artisanale\u00a0\u00bb<\/strong>, ce qui n&rsquo;est absolument pas le cas. Quant au but de l&rsquo;attaque, il s&rsquo;agissait \u00e9galement d&rsquo;un montage pour tenter d&rsquo;envenimer les relations entre la Russie et la Turquie, en faisant partir les drones d&rsquo;un point situ\u00e9 dans une zone sous contr\u00f4le turc, donc en esp\u00e9rant que les Russes jugeraient qu&rsquo;il s&rsquo;agissait d&rsquo;une attaque r\u00e9alis\u00e9e par des groupes contr\u00f4l\u00e9s par les Turcs&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>L&rsquo;attaque des UAV contre les bases russes en Syrie \u00e9tait une provocation visant \u00e0 d\u00e9truire des accords en place, a d\u00e9clar\u00e9 le pr\u00e9sident russe Vladimir Poutine lors d&rsquo;une r\u00e9union avec les m\u00e9dias et les agences de presse du pays. \u00ab\u00a0Il s&rsquo;agissait de provocateurs, mais ils n&rsquo;\u00e9taient pas Turcs. Nous savons qui ils sont, qui les a pay\u00e9s pour assurer cette provocation et quelle \u00e9tait la somme r\u00e9elle de la tractation.\u00a0\u00bb \u00ab\u00a0Il n&rsquo;y a \u00e9videmment rien de bon \u00e0 attendre de cette sorte d&rsquo;incident. Le but de l&rsquo;op\u00e9ration \u00e9tait la destruction d&rsquo;accords existants\u00a0\u00bb, a d\u00e9clar\u00e9 M. Poutine.<\/em><\/p>\n<\/p>\n<p><p>&laquo; <em>Il a pr\u00e9cis\u00e9 \u00e0 ce propos que ces actions visaient d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale \u00e0 saper les relations de la Russie avec la Turquie et l&rsquo;Iran. \u00ab\u00a0Nous comprenons parfaitement bien<\/em> [cette man&oelig;uvre] <em>et par cons\u00e9quent nous travaillons ensemble<\/em> [pour en annuler les effets]\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les v\u00e9hicules a\u00e9riens sans pilote utilis\u00e9s dans l&rsquo;attaque des bases russes en Syrie avaient leur apparence modifi\u00e9e pour sembler \u00eatre d&rsquo;une fabrication artisanale mais ils \u00e9taient \u00e9quip\u00e9s de syst\u00e8mes de haute technologie. \u00ab\u00a0Pour ce qui est de ces attaques, elles \u00e9taient assur\u00e9ment bien pr\u00e9par\u00e9es, nous savons quand et o&ugrave; ces v\u00e9hicules sans pilote ont \u00e9t\u00e9 remis aux assaillants, et leur nombre. Ces v\u00e9hicules a\u00e9riens \u00e9taient modifi\u00e9s<\/em> [pour sembler avoir \u00e9t\u00e9 produits de fa\u00e7on artisanale]<em>, &ndash; <strong>je voudrais insister sur ce fait<\/strong>, &ndash; mais il est \u00e9vident que certains \u00e9quipements de haute technologie ont \u00e9t\u00e9 utilis\u00e9s\u00a0\u00bb. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Avec le Major-G\u00e9n\u00e9ral Alexander Novikov, chef de la direction du d\u00e9veloppement des engins guid\u00e9s, notamment des UAV, on a de tr\u00e8s nombreuses pr\u00e9cisions d&rsquo;ordre technique, relay\u00e9es par le r\u00e9seau <em>Fake<\/em>-Tass le 11 janvier. L\u00e0 aussi, l&rsquo;accent est mis, dans le d\u00e9tail le plus pr\u00e9cis, sur l&rsquo;aspect de haute technologie des v\u00e9hicules utilis\u00e9s, jusqu&rsquo;\u00e0 des pr\u00e9cisions sur les explosifs utilis\u00e9s, et l&rsquo;\u00e9vocation des pays d\u00e9veloppant ce type d&rsquo;explosif, <strong>avec mention nominale de l&rsquo;Ukraine<\/strong>, &ndash; ce qui nous ouvre obligeamment la voie \u00e0 des hypoth\u00e8ses passionnantes&#8230; Ci-dessous, une partie importante de l&rsquo;intervention de Novikov telle qu&rsquo;elle est retranscrite :<\/p>\n<\/p>\n<p><p>&laquo; <em>L&rsquo;analyse des drones de terroristes captur\u00e9s en Syrie a montr\u00e9 qu&rsquo;ils ne peuvent pas avoir \u00e9t\u00e9 produits de fa\u00e7on improvis\u00e9e, a d\u00e9clar\u00e9 le chef du d\u00e9veloppement de v\u00e9hicules a\u00e9riens arm\u00e9s sans pilote<\/em> [UAV] <em>\u00e0 l&rsquo;\u00e9tat-major russe, le major-g\u00e9n\u00e9ral Alexander Novikov.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0La conception et la production de drones de cette classe est impossible d&rsquo;une mani\u00e8re improvis\u00e9e. Leur d\u00e9veloppement et leur utilisation impliquent des sp\u00e9cialistes, ayant suivi une formation sp\u00e9ciale dans les pays qui fabriquent et utilisent des syst\u00e8mes avec des v\u00e9hicules a\u00e9riens<\/em> [arm\u00e9s] s<em>ans pilote\u00a0\u00bb, a d\u00e9clar\u00e9 le g\u00e9n\u00e9ral. L&rsquo;assemblage et l&rsquo;utilisation de v\u00e9hicules a\u00e9riens sans pilote est une t\u00e2che d&rsquo;ing\u00e9nierie difficile qui exige \u00ab\u00a0une formation sp\u00e9ciale, un savoir-faire dans divers domaines scientifiques et une exp\u00e9rience pratique dans la cr\u00e9ation de ces dispositifs\u00a0\u00bb, a-t-il d\u00e9clar\u00e9.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Un logiciel sp\u00e9cial est \u00e9galement n\u00e9cessaire pour utiliser ces drones, a not\u00e9 le g\u00e9n\u00e9ral. Pour une utilisation efficace<\/em> [de l&rsquo;engin]<em>, des informations sur les munitions, sur l&#8217;emplacement exact de la cible et des param\u00e8tres tels que l&rsquo;altitude, le vol et la vitesse du vent sont requis. Ces informations ne peuvent \u00eatre obtenues sur Internet, a soulign\u00e9 Novikov<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>De plus, les explosifs des bombes transport\u00e9es par les drones qui ont attaqu\u00e9 les bases de Hmeimim et de Tartous en Syrie ne peuvent pas avoir \u00e9t\u00e9 fabriqu\u00e9s dans des conditions de fortune. Il y a plusieurs endroits o&ugrave; cette substance est fabriqu\u00e9e et l&rsquo;un d&rsquo;entre eux est l&rsquo;Ukraine, selon Novikov<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les drones attaquant des bases russes en Syrie ont \u00e9t\u00e9 lanc\u00e9s depuis la zone de d\u00e9sescalade d&rsquo;Idlib. \u00ab\u00a0L&rsquo;analyse pr\u00e9liminaire a montr\u00e9 que le principal explosif utilis\u00e9 dans les bombes \u00e9tait le t\u00e9tranitrate de penta\u00e9rythritol (\u00e9galement connu sous le nom de PENT, PENTA ou TEN), dont le rendement est beaucoup plus \u00e9lev\u00e9 que celui de l&rsquo;hexog\u00e8ne. Il ne peut pas \u00eatre fabriqu\u00e9 dans des conditions de fortune ou extrait d&rsquo;autres munitions\u00a0\u00bb, a-t-il dit. Novikov a d\u00e9clar\u00e9 que des tests sp\u00e9ciaux \u00e9taient en cours dans le but de trouver le pays d&rsquo;origine<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Les drones utilis\u00e9s par les terroristes portaient des explosifs bourr\u00e9s de roulements \u00e0 billes, selon Novikov. \u00ab\u00a0Les armes des drones m\u00e9ritent l&rsquo;attention : ce sont des engins explosifs<\/em> [sp\u00e9cialement d\u00e9velopp\u00e9s pour cette mission] <em>pesant environ 400 grammes et bourr\u00e9s de composants de frappe &ndash; des roulements \u00e0 billes avec un rayon de frappe allant jusqu&rsquo;\u00e0 50 m\u00e8tres\u00a0\u00bb, a d\u00e9clar\u00e9 le g\u00e9n\u00e9ral<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;arm\u00e9e russe a d\u00e9chiffr\u00e9 les donn\u00e9es de route des drones qui ont attaqu\u00e9 les bases russes \u00e0 Hmeimim et Tartous en Syrie, confirmant qu&rsquo;ils avaient<\/em> [tous] <em>\u00e9t\u00e9 lanc\u00e9s depuis un<\/em> [seul] <em>endroit. \u00ab\u00a0La diapositive montre des donn\u00e9es d\u00e9chiffr\u00e9es des drones captur\u00e9s sur leurs itin\u00e9raires de vol programm\u00e9s et r\u00e9els, et sur les points de largage de munitions. Un des drones \u00e9tait \u00e9quip\u00e9 d&rsquo;une cam\u00e9ra vid\u00e9o et<\/em> [avait pour mission] <em>de contr\u00f4ler et d&rsquo;ajuster les frappes si n\u00e9cessaire\u00a0\u00bb, a d\u00e9clar\u00e9 le g\u00e9n\u00e9ral<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>L\u00e0-dessus, on se doit de reparler de la pr\u00e9sence \u00e0 tr\u00e8s bonne port\u00e9e de la zone de l&rsquo;op\u00e9ration d&rsquo;un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Boeing_P-8_Poseidon\">Boeing P-8A <em>Poseidon<\/em><\/a>, avion tr\u00e8s r\u00e9cent de contr\u00f4le et de surveillance \u00e9lectronique de l&rsquo;US Navy, ayant notamment dans ses sp\u00e9cialit\u00e9s la capacit\u00e9 de surveillance, de contr\u00f4le et de guidage de drones. L&rsquo;avion a crois\u00e9 pendant quatre heures \u00e0 port\u00e9e de l&rsquo;op\u00e9ration, au moment de l&rsquo;op\u00e9ration. <strong>L&rsquo;hypoth\u00e8se \u00e9vidente qu&rsquo;on a d\u00e9j\u00e0 faite ne cesse de se renforcer lorsqu&rsquo;elle est consid\u00e9r\u00e9e dans le cadre des pr\u00e9cisions techniques et politiques qu&rsquo;on ne cesse d&rsquo;obtenir<\/strong>.<\/p>\n<\/p>\n<p><p>Il est \u00e9vident que c&rsquo;est ce que les Russes pensent et veulent faire penser avec les meilleures rasons du monde. <strong>La pr\u00e9cision du G\u00e9n\u00e9ral Novikov sur l&rsquo;Ukraine n&rsquo;est probablement pas innocente<\/strong> : c&rsquo;est un <em>modus operandi <\/em>assez habituel des agences US pour leurs \u00ab\u00a0coups tordus\u00a0\u00bb (<em>dirty tricks<\/em>) d&rsquo;aller chercher du mat\u00e9riel selon des origines diverses, et bien entendu quoi de plus simple que de se fournir chez les amis ukrainiens. Ce qui est int\u00e9ressant si l&rsquo;hypoth\u00e8se est poursuivie, c&rsquo;est la pr\u00e9sence d&rsquo;un P-8A de l&rsquo;US Navy, ce qui signifie que la Navy est partie prenante dans l&rsquo;op\u00e9ration car elle n&rsquo;aurait pas fourni un tel mat\u00e9riel sans savoir pr\u00e9cis\u00e9ment les tenants et les aboutissants de l&rsquo;op\u00e9ration. Un jeu d&rsquo;hypoth\u00e8ses int\u00e9ressant, &ndash; hypoth\u00e8se dans l&rsquo;hypoth\u00e8se si l&rsquo;on suit la fili\u00e8re US, &ndash; serait de savoir qui pr\u00e9cis\u00e9ment a con\u00e7u et lanc\u00e9 cette mission, qui \u00e9tait au courant, si Trump \u00e9tait au courant, etc.<\/p>\n<\/p>\n<p><p>Dans tous les cas, l&rsquo;activit\u00e9 de communication des Russes est remarquable, un v\u00e9ritable exercice en <em><a href=\"http:\/\/www.dedefensa.org\/article\/au-temps-de-gorbatchev-et-de-la-glasnost\">glasnost<\/a><\/em> offensive qui n&rsquo;est, ou n&rsquo;\u00e9tait pas en g\u00e9n\u00e9ral d&rsquo;une pratique courante chez eux. On rapprochera cette attitude de celle de la direction iranienne <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-liran-la-cia-lonuet-macron\">d\u00e9taillant<\/a> ce qui est pr\u00e9sent\u00e9 l\u00e0-bas comme le complot US pour d\u00e9stabiliser le r\u00e9gime, \u00e0 l&rsquo;occasion du mouvement de rue de fin 2017-d\u00e9but 2018. Dans les deux cas, il faut mettre en \u00e9vidence, pour bien mesurer le ph\u00e9nom\u00e8ne, l&rsquo;intervention directe et officielle de personnalit\u00e9s politiques responsables (le ministre de la justice iranien, Poutine) dans ce jeu de d\u00e9voilement des man&oelig;uvres secr\u00e8tes. <strong>Il pourrait bien s&rsquo;agir d&rsquo;une nouvelle approche<\/strong> des pays constamment agress\u00e9s par les USA, consistant \u00e0 <strong>dire tout haut, officiellement et dans le plus grand d\u00e9tail ce que leurs services de renseignement savent des activit\u00e9s subversives contre eux<\/strong>. Cette m\u00e9thode est en g\u00e9n\u00e9ral \u00e9vit\u00e9e, pour ne pas d\u00e9voiler les moyens, les orientations et les capacit\u00e9s de p\u00e9n\u00e9tration des services impliqu\u00e9s.<\/p>\n<\/p>\n<blockquote>\n<p><p>S&rsquo;il s&rsquo;agit bien d&rsquo;une nouvelle tendance, elle correspond au constat qu&rsquo;il est d\u00e9sormais <strong>plus int\u00e9ressant de montrer \u00e0 ciel ouvert les capacit\u00e9s dont on dispose, plut\u00f4t que les dissimuler<\/strong>, en m\u00eame temps que de telles r\u00e9v\u00e9lations contribuent \u00e0 renforcer la perception qu&rsquo;il existe r\u00e9ellement une politique nihiliste de d\u00e9stabilisation \u00e0 l&rsquo;&oelig;uvre, &ndash; pour que nul n&rsquo;en ignore ou pr\u00e9tendent en ignorer. <strong>Si l&rsquo;analyse est bonne, cela marque un durcissement tr\u00e8s net de la \u00ab\u00a0guerre de communication\u00a0\u00bb qui domine aujourd&rsquo;hui tous les affrontements en cours<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>En attendant, les Russes <a href=\"http:\/\/theduran.com\/russia-revenge-mod-jihadis-drone-attack-killed\/\">ont fait le m\u00e9nage<\/a>. Utilisant leur artillerie la plus pr\u00e9cise et la plus puissante (sans doute des batteries <a href=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/thumb\/0\/00\/AlabinoTraining0904-34.jpg\/1200px-AlabinoTraining0904-34.jpg\">2S19 Msta-S<\/a> autopropuls\u00e9es tirant des obus \u00e0 guidage-laser de calibre 152mm), ils ont an\u00e9anti les installations d&rsquo;o&ugrave; avaient \u00e9t\u00e9 lanc\u00e9s les drones. La probabilit\u00e9 est qu&rsquo;une unit\u00e9 des forces sp\u00e9ciales russes effectuant un raid d&rsquo;infiltration a pris en charge le guidage des obus avant de regagner sa base de d\u00e9part. De ce point de vue purement op\u00e9rationnel, <strong>c&rsquo;est aussi un signe du durcissement de la Russie<\/strong> qui s&rsquo;accorde \u00e0 celui qu&rsquo;on observe dans la \u00ab\u00a0guerre de la communication\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Mis en ligne le 13 janvier 2018 \u00e0 16H09<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les drones antirusses d\u00e9voil\u00e9s par FakeNews Encore une fois, il est excellent pour la sant\u00e9 et pour l&rsquo;humeur de savoir que tout ce qui suit est FakeNews et rien que FakeNews puisque relay\u00e9s par des r\u00e9seaux compl\u00e8tement Fake (Tass en l&rsquo;occurrence, c&rsquo;est dire\/c&rsquo;est pli\u00e9), venant d&rsquo;un pr\u00e9sident-bidon\/gangster douteux et de l&rsquo;un de ses sbires galonn\u00e9s&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3015,2631,3283,7554,2645,2622,18032,18030,18031,916,2730,3867,5797,1296],"class_list":["post-77712","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-communication","tag-de","tag-general","tag-glasnost","tag-guerre","tag-la","tag-norikov","tag-p-8a","tag-poseidon","tag-poutine","tag-russie","tag-syrie","tag-uav","tag-ukraine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77712"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77712\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}