{"id":77719,"date":"2018-01-18T06:52:21","date_gmt":"2018-01-18T06:52:21","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/18\/transgenre-contre-lgtbq-russiagate\/"},"modified":"2018-01-18T06:52:21","modified_gmt":"2018-01-18T06:52:21","slug":"transgenre-contre-lgtbq-russiagate","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/18\/transgenre-contre-lgtbq-russiagate\/","title":{"rendered":"Transgenre contre LGTBQ-<em>Russiagate<\/em>"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Transgenre contre LGTBQ-<em>Russiagate<\/em><\/h2>\n<\/p>\n<p><p>Une des plus r\u00e9centes p\u00e9rip\u00e9ties aux USA sous le r\u00e8gne de la folie de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb : l&rsquo;entr\u00e9e de <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Chelsea_Manning\">Chelsea Elizabeth Manning<\/a>, n\u00e9e Bradley Edward Manning, dans la comp\u00e9tition politique. Manning est le plus fameux\/la plus fameuse transgenre de l&rsquo;histoire r\u00e9cente, &ndash; peut-\u00eatre m\u00eame de l&rsquo;histoire plus longue depuis le symbole \u00e9nigmatique qu&rsquo;entretint durant toute sa vie le <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Charles_de_Beaumont,_chevalier_d%27%C3%89on\">Chevalier d&rsquo;Eon<\/a> ?<\/p>\n<\/p>\n<p><p>(Difficile d&rsquo;\u00e9crire grammaticalement avec justesse pour son cas, puisqu&rsquo;une grande partie de sa c\u00e9l\u00e9brit\u00e9 prend place alors qu&rsquo;il s&rsquo;agit de Bradley Edward, et se poursuit aujourd&rsquo;hui alors qu&rsquo;il s&rsquo;agit de Chelsea Elizabeth : le masculin pour le pass\u00e9, le f\u00e9minin pour le pr\u00e9sent ?)<\/p>\n<\/p>\n<p><p> Sa gloire fut d&rsquo;\u00eatre un formidable lanceur d&rsquo;alerte, le premier du genre pour la s\u00e9quence que nous vivons, en passant \u00e0 <em>WikiLeaks <\/em>des centaines de milliers de documents <em>classified <\/em>sur l&rsquo;action US en Irak et en Afghanistan. La suite est bien connue : identifi\u00e9, arr\u00eat\u00e9, Bradley Edward fut condamn\u00e9 \u00e0 une lourde peine (30 ans de prison), tout en subissant un traitement extr\u00eamement rude, sinon \u00ab\u00a0sp\u00e9cial\u00a0\u00bb durant son emprisonnement pendant le proc\u00e8s, puis apr\u00e8s de plus en plus appuy\u00e9. Ayant r\u00e9clam\u00e9 et obtenu l&rsquo;op\u00e9ration \u00ab\u00a0transgenre\u00a0\u00bb, Chelsea Elizabeth fut graci\u00e9e par Obama en janvier 2017 et lib\u00e9r\u00e9e en mai de la m\u00eame ann\u00e9e. Obama calculait ainsi qu&rsquo;il devrait s&rsquo;attirer encore plus de soutien des communaut\u00e9s LGTBQ, ce qui fait partie de son legs historique. Il n&rsquo;ignorait pas que le traitement impos\u00e9 \u00e0 Manning, si la d\u00e9tention \u00e9tait prolong\u00e9e, pouvait conduire \u00e0 la mort, et qu&rsquo;il lui serait alors reproch\u00e9 de n&rsquo;avoir rien fait pour sauver la prisonni\u00e8re.<\/p>\n<\/p>\n<p><p>(D\u00e8s le <a href=\"http:\/\/archive.wikiwix.com\/cache\/?url=http%3A%2F%2Fwww.salon.com%2Fnews%2Fopinion%2Fglenn_greenwald%2F2010%2F12%2F14%2Fmanning%2Findex.html\">16 d\u00e9cembre 2010<\/a>, quelques semaines apr\u00e8s l&rsquo;arrestation de Bradley Edward, Glenn Greenwald protestait contre le traitement qui \u00e9tait inflig\u00e9 \u00e0 Manning. Deux fois en 2016, la deuxi\u00e8me fois en d\u00e9cembre avant d&rsquo;\u00eatre graci\u00e9e, Manning a tent\u00e9 de se suicider. Il ne faisait gu\u00e8re de doute qu&rsquo;une issue fatale \u00e9tait possible sinon probable assez rapidement s&rsquo;il n&rsquo;y avait eu la gr\u00e2ce du pr\u00e9sident sortant.)<\/p>\n<\/p>\n<p><p>Dimanche, Chelsea Elizabeth <a href=\"http:\/\/theduran.com\/chelsea-manning-is-running-for-us-senate-and-the-liberal-left-blame-russia\/\">a annonc\u00e9<\/a> qu&rsquo;elle se pr\u00e9senterait en juin prochain contre le probable candidat d\u00e9mocrate \u00e0 sa propre r\u00e9\u00e9lection, le s\u00e9nateur Ben Cardin, 74 ans, l&rsquo;un des plus fervents interpr\u00e8tes de la Messe dite du <em><a href=\"http:\/\/www.dedefensa.org\/article\/russiagate-simulacre-extreme\">Russiagate<\/a><\/em>. Sur <em>ConsortiumNews<\/em>, <a href=\"https:\/\/consortiumnews.com\/2018\/01\/16\/why-senator-cardin-is-a-fitting-opponent-for-chelsea-manning\/\">Norman Solomon<\/a> trace un portrait impressionnant type-vitriol de Cardin, vieille baderne du s\u00e9rail pass\u00e9 ma&icirc;tre dans l&rsquo;art du simulacre ; Cardin, l&rsquo;un des plus venimeux, des plus z\u00e9l\u00e9s paroissiens du <em>Russiagate<\/em>, qui vient d&rsquo;\u00e9crire un rapport qui repr\u00e9sente un formidable travail d&rsquo;exposition <em>a contrario <\/em>du simulacre antirusse.<\/p>\n<\/p>\n<p><p>D\u00e8s qu&rsquo;elle a annonc\u00e9 sa candidature, Chelsea Elizabeth a \u00e9t\u00e9 d\u00e9nonc\u00e9e par quelques pions (au sens de flics) gravitant autour du parti d\u00e9mocrate et de Cardin <strong>comme n&rsquo;\u00e9tant rien de plus et rien d&rsquo;autre qu&rsquo;un <a href=\"http:\/\/theduran.com\/chelsea-manning-is-running-for-us-senate-and-the-liberal-left-blame-russia\/\">pion du Kremlin<\/a> (au sens de pantin)<\/strong>, un membre du \u00ab\u00a0parti Snowden\u00a0\u00bb qui est n\u00e9cessairement le parti de la trahison selon les services de communication des d\u00e9mocrates et autres officiants de l&rsquo;antirussisme \u00e0 Washington D.C. Au reste, ce n&rsquo;est pas la premi\u00e8re fois que les contradictions fondamentales implicites dans le cas Manning sont mises \u00e0 jour. On a pu voir cela au printemps 2013.<\/p>\n<\/p>\n<p><p>A cette \u00e9poque, Bradley Edward, alors encore homosexuel masculin, fut d\u00e9sign\u00e9 par un coll\u00e8ge de militants comme h\u00e9ros (<em>Grand Marshall<\/em>) de la fameuse <em>Gay Pride<\/em> de San-Francisco de juin 2013. Aussit\u00f4t, la direction, dans la personne de sa pr\u00e9sidente Lisa Williams, qui poss\u00e9dait alors la firme de consultance politique<em> One Source Consulting<\/em> travaillant pour les d\u00e9mocrates, annula la d\u00e9cision et d\u00e9cida la d\u00e9-<em>marshalization <\/em>du soldat-\u00ab\u00a0tra&icirc;tre\u00a0\u00bb Manning. La raison en \u00e9tait \u00e9videmment que cette position et ce personnage <strong>embarrassaient les <em>sponsors<\/em> (le <em>Corporate Power<\/em>, le parti d\u00e9mocrate, etc.) de la manifestation <\/strong>dans la mesure o&ugrave; le soldat Manning \u00e9tait effectivement d\u00e9sign\u00e9 officiellement comme un \u00ab\u00a0tra&icirc;tre\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Nous \u00e9crivions le <a href=\"http:\/\/www.dedefensa.org\/article\/gay-daccord-pride-cest-a-voir\">23 avril 2013<\/a> :  &laquo; <em>L&rsquo;un ou l&rsquo;autre membre de l&rsquo;organisation, ou l&rsquo;un ou l&rsquo;autre militant, avait pris sur lui, ou sur eux s&rsquo;ils sont plusieurs, d&rsquo;instituer le soldat <a href=\"http:\/\/en.wikipedia.org\/wiki\/Bradley_Manning\">Bradley Manning<\/a> comme h\u00e9ros (Grand Marshall) de la Parade. Manning est notoirement homosexuel, en plus d&rsquo;\u00eatre le h\u00e9ros \u00e0 l&rsquo;incroyable courage qui a pass\u00e9 \u00e0 WikiLeaks les centaines de milliers de cables confidentiels des organisations de s\u00e9curit\u00e9 (Pentagone, d\u00e9partement d&rsquo;&Eacute;tat, etc.) du syst\u00e8me de l&rsquo;am\u00e9ricanisme, principal organisme du Syst\u00e8me. Identifi\u00e9 et arr\u00eat\u00e9, Manning subit depuis plus d&rsquo;un an, d&rsquo;une fa\u00e7on absolument arbitraire et m\u00eame totalitaire, \u00e0 l&rsquo;image des pires dictatures, un traitement inhumain et cruel d&rsquo;une barbarie sans pr\u00e9c\u00e9dent. (Nous disons bien \u00ab\u00a0sans pr\u00e9c\u00e9dent\u00a0\u00bb parce que, dans sa sophistication inf\u00e2me, dans sa vindicte aveugle, dans sa haine absolue de tout ce qui n&rsquo;est pas elle, dans sa volont\u00e9 \u00e9galement absolue de d\u00e9shumanisation par la torture, la pression psychologique, l&rsquo;humiliation permanente, dans la dur\u00e9e qu&rsquo;elle imprime \u00e0 toutes ces pratiques, etc., la barbarie moderniste enfant\u00e9e par le Syst\u00e8me et pratiqu\u00e9e dans nombre d&rsquo;organisations de s\u00e9curit\u00e9 des USA est litt\u00e9ralement sans pr\u00e9c\u00e9dent.) Faire de Manning le h\u00e9ros de la Gay Pride, c&rsquo;\u00e9tait l&rsquo;\u00e9vidence m\u00eame selon ce qu&rsquo;on suppose que devrait \u00eatre \u00ab\u00a0l&rsquo;esprit gay\u00a0\u00bb, si la chose existe. Le <a href=\"http:\/\/lgbtweekly.com\/2013\/04\/26\/sf-pridebradley-manning-will-not-be-a-grand-marshal\">26 avril 2013<\/a>, la \u00ab\u00a0president of the Board of SF Pride\u00a0\u00bb, Lisa L Williams, a pris la d\u00e9cision d&rsquo;annuler presto subito cette d\u00e9cision<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>On trouvera tous les d\u00e9tails de cette op\u00e9ration inf\u00e2me dans une chronique absolument furieuse de Glenn Greenwald, dans le Guardian du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2013\/apr\/27\/bradley-manning-sf-gay-pride\">27 avril 2013<\/a>. Greenwald dit non seulement son m\u00e9pris pour cette d\u00e9cision, mais il rajoute les pr\u00e9cisions selon lesquelles la Gay Pride est activement soutenue par l&rsquo;\u00e9l\u00e9ment-clef du Syst\u00e8me dans cette analyse, le Corporate Power&#8230;<\/em> [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; &#8230;<em>L\u00e0-dessus, nous nous tournons vers Justin Raimondo, avec sa chronique d&rsquo;Antiwar.com du <a href=\"http:\/\/original.antiwar.com\/justin\/2013\/04\/28\/imperial-america-and-the-end-of-progressivism\/%E2%80%AC\">29 avril 2013<\/a>. Justin n&rsquo;allait pas rater l&rsquo;\u00e9v\u00e9nement : libertarien de la droite extr\u00eame, antiguerre et isolationniste, et&#8230; homosexuel qui se garde bien d&rsquo;\u00eatre militant au nom de cette seule caract\u00e9ristique. N\u00e9anmoins, il faisait partie de la premi\u00e8re Gay Pride, non autoris\u00e9e, non sponsoris\u00e9e, \u00e0 San Francisco en 1972. A cette \u00e9poque, la Gay Pride pouvait, selon Raimondo, \u00e9prouver une certaine fiert\u00e9 (pride) d&rsquo;\u00eatre, puisqu&rsquo;elle s&rsquo;affichait d&rsquo;abord dissidente et adversaire de l&rsquo;establishment, du National Security State, &ndash; bref, de ce que nous avons coutume de nommer le Syst\u00e8me.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>&#8230; Aujourd&rsquo;hui, constate Raimondo, c&rsquo;est le contraire. Le mouvement gay, c&rsquo;est le Syst\u00e8me m\u00eame ; compl\u00e8tement r\u00e9cup\u00e9r\u00e9, noyaut\u00e9 par les partisans d&rsquo;Obama, devenus quasiment militariste, ce sont les suppl\u00e9tifs des flics du Syst\u00e8me, sinon les flics du Syst\u00e8me eux-m\u00eames<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Si l&rsquo;on prend en compte d&rsquo;un point de vue politique les aspects personnels li\u00e9 \u00e0 son statut soci\u00e9tal, <strong>Manning est un cas politique passionnant<\/strong>. Homosexuel puis transgenre, elle a \u00e9t\u00e9 impliqu\u00e9e dans la s\u00e9quence actuelle par un acte \u00e9clatant, fondamentalement antiSyst\u00e8me, qui la place compl\u00e8tement du c\u00f4t\u00e9 du groupe amalgamant <em>WikiLeaks<\/em>, Snowden et le groupe Greenwald\/<em>The Intercept<\/em>, voire des personnalit\u00e9s comme Oliver Stone. Son calvaire d&rsquo;homosexuel pass\u00e9 transgenre, condamn\u00e9e, subissant un traitement d\u00e9gradant et de torture en prison \u00e9quivalant \u00e0 un emprisonnement \u00e0 Guantanamo, aboutissant \u00e0 deux tentatives de suicide et sauv\u00e9e par une gr\u00e2ce pr\u00e9sidentielle, font d&rsquo;elle <strong>une h\u00e9ro\u00efne de droit et de fait des communaut\u00e9s LGTBQ<\/strong>. Voil\u00e0 qu&rsquo;elle r\u00e9appara&icirc;t aujourd&rsquo;hui effectivement en authentique h\u00e9ro\u00efne de l&rsquo;antiSyst\u00e8me, pr\u00e9tendant jouer un r\u00f4le politique \u00e9minent selon le th\u00e8me de communication officiel de sa candidature que \u00ab\u00a0le Syst\u00e8me ne peut se r\u00e9former de l&rsquo;int\u00e9rieur\u00a0\u00bb, c&rsquo;est-\u00e0-dire selon une tactique d&rsquo;entrisme.<\/p>\n<\/p>\n<p><p>Cette d\u00e9cision, qui aura bien entendu un effet \u00e0 mesure de sa r\u00e9alisation op\u00e9rationnelle, <strong>met puissamment \u00e0 jour les formidables contradictions du bouillonnement actuel de la crise de l&rsquo;am\u00e9ricanisme<\/strong>. On peut en juger selon les v\u00e9ritables positions des diff\u00e9rents acteurs qui ne peuvent ignorer le cas Manning, et surtout, qui ne peuvent certainement pas l&rsquo;enterrer dans <strong>l&rsquo;opprobre terroriste habituel se manifestant sous la forme du lynchage de communication contre tout antiSyst\u00e8me g\u00eanant<\/strong> (\u00ab\u00a0fasciste\u00a0\u00bb, \u00ab\u00a0r\u00e9actionnaire\u00a0\u00bb, etc.).<\/p>\n<\/p>\n<p><p>Dans sa forme organis\u00e9e et institutionnalis\u00e9e aux USA, <strong>le LGTBQ est tr\u00e8s fortement contr\u00f4l\u00e9 par le Syst\u00e8me<\/strong>. Il est compl\u00e8tement annex\u00e9 par le parti d\u00e9mocrate aux USA, il est engag\u00e9 <em>de facto <\/em>dans la compagne de haine antirussiste du <em>Russiagate<\/em> par simple capillarit\u00e9, et par l&rsquo;entrisme d&rsquo;\u00e9l\u00e9ments du Syst\u00e8me (<em>Corporate Power<\/em> et syst\u00e8me artistique [\u00ab\u00a0Art Contemporain\u00a0\u00bb] qui lui est li\u00e9, presseSyst\u00e8me, syst\u00e8me RP-<em>showbusiness<\/em>, Hollywood, etc.). De ce fait et plus largement, le LGTBQ est entra&icirc;n\u00e9 \u00e0 soutenir toutes les options de politique ext\u00e9rieure de la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> qui forme l&rsquo;ossature de la politique am\u00e9ricaniste, &ndash; <strong>tout ce que le soldat Bradley Edward avait d\u00e9nonc\u00e9 en 2010<\/strong> par la formidable \u00ab\u00a0fuite\u00a0\u00bb de documents secrets qu&rsquo;il avait r\u00e9alis\u00e9e.<\/p>\n<\/p>\n<blockquote>\n<p><p>Normalement, Manning, transgenre et lanceur d&rsquo;alerte devenue Chelsea Elizabeth, condamn\u00e9e, emprisonn\u00e9e et tortur\u00e9e par le syst\u00e8me p\u00e9nitentiaire du Pentagone, <strong>devrait \u00eatre une ic\u00f4ne de la gauche des progressistes-soci\u00e9taux et du f\u00e9minisme militant<\/strong>. Ce n&rsquo;est pas le cas. <strong>Nous ne sommes pas dans des temps normaux<\/strong>, dans ces temps o&ugrave; le pouvoir \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, est confront\u00e9 \u00e0 la plus grave crise de dissolution et d&rsquo;effondrement qu&rsquo;on puisse imaginer&#8230;.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La gauche progressistes-soci\u00e9tales est <strong>objectivement proche, tr\u00e8s-proche du syst\u00e8me militaro-industriel<\/strong>, le \u00ab\u00a0Complexe\u00a0\u00bb qui active les guerres dont elle (cette gauche progressiste-soci\u00e9tale) fait son miel ; le Pentagone est le ma&icirc;tre et l&rsquo;un des manipulateurs du Complexe et, en m\u00eame temps, <strong>il hait litt\u00e9ralement Manning<\/strong>&#8230; M\u00eame un Obama, qui garde une position et une influence importantes, <strong>est pris dans une contradiction remarquable avec Manning<\/strong>. Il l&rsquo;a graci\u00e9e selon l&rsquo;\u00e9vidence m\u00eame, parce qu&rsquo;il ne pouvait pas, de fait de son \u00ab\u00a0statut moral\u00a0\u00bbet de ses engagements encore plusmraux, laisser Manning risquer d&rsquo;aller vers la mort sans rien faire pour la sauver. Lib\u00e9r\u00e9e, r\u00e9tablie, et d\u00e9sormais d\u00e9sireuse de faire de l&rsquo;entrisme antiSyst\u00e8me tr\u00e8s voyant en briguant un si\u00e8ge de s\u00e9nateur, Manning devient un fardeau pour Obama dans la mesure o&ugrave; la simple logique des contradictions am\u00e8ne Manning \u00e0 s&rsquo;opposer \u00e0 tout ce qu&rsquo;Obama soutient, y compris le LGTBQ officiel et institutionnalis\u00e9.<\/p>\n<\/p>\n<p><p>Reste \u00e0 voir ce que Manning peut faire, de quel soutien elle peut disposer. De grands efforts vont \u00eatre faits pour an\u00e9antir sa candidature ; sa t\u00e2che ne sera pas facile, et certainement pas d\u00e9nu\u00e9e de risques, m\u00eame pour son int\u00e9grit\u00e9 physique ; d&rsquo;un autre c\u00f4t\u00e9, sa volont\u00e9 de s&rsquo;engager dans cette bataille <strong>montre qu&rsquo;elle a r\u00e9cup\u00e9r\u00e9 de son calvaire et entend tenter de faire payer ses tourmenteurs en reprenant \u00e0 plein son r\u00f4le antiSyst\u00e8me<\/strong>. Il y a l\u00e0 un potentiel pour mettre \u00e0 jour les diverses manigances faites autour du mouvement LGTBQ, notamment et essentiellement la fa\u00e7on dont le Syst\u00e8me a \u00ab\u00a0achet\u00e9\u00a0\u00bb, annex\u00e9 et r\u00e9cup\u00e9r\u00e9 le mouvement. Une candidature Manning r\u00e9ussissant \u00e0 prendre un bon \u00e9lan peut fracturer le mouvement LGTBQ et mettre en danger la bonne marche de la machine progressiste-soci\u00e9tale que le Syst\u00e8me a install\u00e9 pour poursuivre son travail habituel de d\u00e9structuration-dissolution ; elle peut, volontairement ou pas qu&rsquo;importe,<strong> retourner contre le Syst\u00e8me, contre les structures du Syst\u00e8me, ce m\u00eame mouvement de d\u00e9structuration-dissolution<\/strong>. C&rsquo;est l&rsquo;habituelle tactique du \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/resistance-autodestruction-1\">faire<\/a> <em><a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-le-volte-quart-du-maitre-du-faire-aikido\">a\u00efkido<\/a><\/em>\u00ab\u00a0, continuellement reprise pour attaquer le Syst\u00e8me, et qui le sera jusqu&rsquo;\u00e0 ce que le Syst\u00e8me aille jusqu&rsquo;au bout de son autodestruction.<\/p>\n<\/p>\n<p><p>Mis en ligne le 18 janvier 2018 \u00e0 07H53<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transgenre contre LGTBQ-Russiagate Une des plus r\u00e9centes p\u00e9rip\u00e9ties aux USA sous le r\u00e8gne de la folie de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb : l&rsquo;entr\u00e9e de Chelsea Elizabeth Manning, n\u00e9e Bradley Edward Manning, dans la comp\u00e9tition politique. Manning est le plus fameux\/la plus fameuse transgenre de l&rsquo;histoire r\u00e9cente, &ndash; peut-\u00eatre m\u00eame de l&rsquo;histoire plus longue depuis le symbole \u00e9nigmatique qu&rsquo;entretint&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[12375,6018,14837,18040,6125,2651,7865,3969,6944,6615,6208,5623,2904,9681,5491,12160,9887],"class_list":["post-77719","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-aikido","tag-bradley","tag-chelsea","tag-crdin","tag-democrate","tag-du","tag-faire","tag-grace","tag-greenwald","tag-manning","tag-obama","tag-parti","tag-president","tag-senateur","tag-suicide","tag-whistleblower","tag-wikileaks"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77719"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77719\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}