{"id":77736,"date":"2018-01-31T11:32:52","date_gmt":"2018-01-31T11:32:52","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/31\/in-memoriam-robert-parry-lantisysteme\/"},"modified":"2018-01-31T11:32:52","modified_gmt":"2018-01-31T11:32:52","slug":"in-memoriam-robert-parry-lantisysteme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/01\/31\/in-memoriam-robert-parry-lantisysteme\/","title":{"rendered":"<em>In memoriam<\/em>, Robert Parry l&rsquo;antiSyst\u00e8me"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\"><em>In memoriam<\/em>, Robert Parry l&rsquo;antiSyst\u00e8me<\/h2>\n<\/p>\n<p><p>Il y a peu, PhG confiait ses impressions et ses \u00e9motions aux nouvelles concernant deux grands journalistes de l&rsquo;antiSyst\u00e8me, tous deux malades, et chronique de PhG bien entendu marqu\u00e9 par l&rsquo;espoir qu&rsquo;ils nous reviendraient. Si Raimondo continue \u00e0 \u00e9crire et semble se battre avec succ\u00e8s contre la maladie, Robert Parry, lui, a succomb\u00e9. Son dernier article du <a href=\"https:\/\/consortiumnews.com\/2017\/12\/31\/an-apology-and-explanation\/\">28 d\u00e9cembre 2017<\/a>, de son lit d&rsquo;h\u00f4pital, montre qu&rsquo;il est mort sur le champ de sa bataille, sa plume \u00e0 la main.<\/p>\n<\/p>\n<p><p>C&rsquo;est un des tr\u00e8s grands hommes de la libert\u00e9 d&rsquo;au-del\u00e0 des fronti\u00e8res, dans nos temps postmodernes, un des grands hommes de la presse antiSyst\u00e8me, de la bataille contre le Syst\u00e8me, c&rsquo;est bien lui qui vient de succomber et qui m\u00e9rite une pens\u00e9e grave et recueillie. On lui doit un salut, lui Parry, bien entendu ignor\u00e9 des instances officielles qui font la gloire du Syst\u00e8me, et le journaliste <a href=\"https:\/\/www.thenation.com\/authors\/norman-solomon\/\">Norman Solomon<\/a>, \u00e9galement belle plume de l&rsquo;antiSyst\u00e8me et qui travailla avec Parry, s&rsquo;en charge dans le texte ci-dessous.<\/p>\n<\/p>\n<p><p>PhG \u00e9crivait donc le <a href=\"http:\/\/www.dedefensa.org\/article\/leur-bataille-est-la-mienne-et-la-votre\">20 janvier 2018<\/a>, \u00e0 propos des deux hommes, et aujourd&rsquo;hui singuli\u00e8rement, ce texte relu avec une pens\u00e9e couleur d&rsquo;\u00e9ternit\u00e9 pour Parry : &laquo; <em>Je crois peu utile en raison de son \u00e9vidence et un peu d\u00e9plac\u00e9 par rapport au conformisme de cette d\u00e9marche, d&rsquo;observer que je suis, que nous sommes bien entendu de tout c&oelig;ur avec eux, ces deux-l\u00e0 que nous ne connaissons pas, et que nous esp\u00e9rons fermement qu&rsquo;ils pourront retrouver la capacit\u00e9 de poursuivre ce que leur passion les pousse \u00e0 faire ; ces deux-l\u00e0 qui nous pr\u00e9sentent leurs excuses pour ne pas pouvoir poursuivre dans sa compl\u00e9tude, temporairement esp\u00e8rent-ils, un travail qu&rsquo;ils nous offrent, hors de toutes les r\u00e8gles marchandes du Syst\u00e8me&#8230;<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Dans ces circonstances et cette chronologie, ces deux-l\u00e0, vous dis-je, sont comme un symbole unique pour moi, pour nous et pour vous. Ils sont parmi les pionniers de l&rsquo;origine et de l&rsquo;originel, ils sont \u00e0 ma connaissance et \u00e0 mon estime deux parmi les tr\u00e8s rares Founding Fathers de la presse-antiSyst\u00e8me, du journalisme de commentaire sur l&rsquo;internet, du <a href=\"http:\/\/www.dedefensa.org\/article\/notre-samizdat-globalise\">samizdat \u00e9lectronique<\/a> et postmoderne, &ndash; et n\u00e9cessairement, quoiqu&rsquo;ils en veuillent, ainsi anti-postmodernes. Ils sont de la premi\u00e8re g\u00e9n\u00e9ration de la R\u00e9sistance dans sa phase finale<\/em>. [&#8230;]<\/p>\n<\/p>\n<p><p>&raquo; <em>Ah oui, j&rsquo;allais oublier : deux hommes que je mets si proches jusqu&rsquo;\u00e0 en faire des fr\u00e8res que je ne connais pas, qui sont d&rsquo;opinions assez diam\u00e9tralement oppos\u00e9es au point qu&rsquo;on les jugerait irr\u00e9conciliables. Venu de la presseSyst\u00e8me (AP), Parry le d\u00e9mocrate de gauche est nettement de gauche ; venu de l&rsquo;activisme, y compris l&rsquo;activisme-gay \u00e0 ses origines non-subventionn\u00e9es par le Corporate Power, Raimondo le libertarien isolationniste est tr\u00e8s nettement de droite. Cela n&rsquo;a strictement aucune importance lorsque l&rsquo;on parle du Syst\u00e8me. Sans y penser ni le vouloir, ni m\u00eame le r\u00e9aliser malgr\u00e9 la pratique, ni quoi que ce soit de cette sorte enfin, ils font comme l&rsquo;on respire la synth\u00e8se, la fusion et l'\u00a0\u00bbunion sacr\u00e9e\u00a0\u00bb de l&rsquo;antiSyst\u00e8me. Ils font ce que les pi\u00e8tres politiciens \u00e0 pr\u00e9tention antiSyst\u00e8me ne parviennent pas, et n&rsquo;arriveront jamais \u00e0 faire d&rsquo;eux-m\u00eames, sans doute jusqu&rsquo;\u00e0 ce que les \u00e9v\u00e9nements les mettent en \u00e9tat d&rsquo;obligation de le faire ou de dispara&icirc;tre en tant que tels.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ah oui, j&rsquo;allais oublier : deux hommes qui sont Am\u00e9ricains, et malgr\u00e9 tout marqu\u00e9s par l&rsquo;am\u00e9ricanisme, ce qui fait qu&rsquo;en certains domaines qui ne sont pas sans importance je diff\u00e9rerais notablement de l&rsquo;un ou de l&rsquo;autre. Cela n&rsquo;a strictement aucune importance puisque l&rsquo;on parle du Syst\u00e8me. Ce qui importe pour cet instant et pour ces quelques lignes, c&rsquo;est de les saluer dans la bataille qu&rsquo;ils poursuivent dans le secret de leurs personnes attaqu\u00e9es par la maladie, parce que cette bataille ne fait que prolonger celles que nous menons n\u00e9cessairement. C&rsquo;est une proximit\u00e9 qui fait une collectivit\u00e9 fondamentale, tout en conservant dans leur dignit\u00e9 les diff\u00e9rences qui font notre n\u00e9cessaire identit\u00e9<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Voici donc l&rsquo;article de Norman Solomon, le <a href=\"https:\/\/www.thenation.com\/article\/remembering-investigative-journalist-robert-parry\/\">29 janvier 2018<\/a>, dans <em>The Nation<\/em>.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\"><em>In memoriam <\/em>: Robert Parry, journaliste d&rsquo;investigation<\/h2>\n<\/p>\n<p><p>Apr\u00e8s la mort de Robert Parry le 27 janvier, j&rsquo;ai demand\u00e9 \u00e0 un autre journaliste d&rsquo;investigation, Seymour Hersh, quelques mots de commentaires. \u00ab\u00a0J&rsquo;ai rencontr\u00e9 Bob il y a plus de trois d\u00e9cennies quand il a \u00e9t\u00e9 le premier \u00e0 mettre en garde contre le d\u00e9veloppement de l&rsquo;affaire Iran \/ Contra, sans grand succ\u00e8s\u00a0\u00bb, a r\u00e9pondu Hersh. \u00ab\u00a0Il a \u00e9t\u00e9 largement consid\u00e9r\u00e9 au cours des ann\u00e9es qui suivirent comme un critique sp\u00e9cifique des m\u00e9dias grand public en Am\u00e9rique. Ce n&rsquo;\u00e9tait pas le cas. Il \u00e9tait un critique des mauvais reportages, que ce soit dans la Pravda ou dans le New York Times. Il voulait que tous les journalistes, partout, fassent les recherches et les interviews n\u00e9cessaires pour aller au-del\u00e0 de la version officielle accept\u00e9e.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Ce qui a fait de Bob Parry un pionnier du journalisme ind\u00e9pendant a \u00e9galement fait de lui un homme ind\u00e9pendant en rupture avec l&rsquo;establishment m\u00e9diatique. Il a refus\u00e9 de prendre pour parole d&rsquo;Evangile la narrative officielle, que ce soit celle du gouvernements ou celle des organes de presse. Apr\u00e8s avoir \u00e9t\u00e9 acclam\u00e9 et glorifi\u00e9, y compris par un prix Polk, en tant que journaliste de l&rsquo;Associated Press qui avait publi\u00e9 de nombreux scoops sur les sales politiques clandestines des USA en Am\u00e9rique centrale, il a pass\u00e9 trois ans \u00e0 Newsweek o&ugrave; il a vu des r\u00e9dacteurs en chef collaborer avec l&rsquo;administration George H.W. Bush sur ce qui devait \u00eatre publi\u00e9 et sur ce qui devait \u00eatre cach\u00e9 au public. Bob quitta le magazine en 1990 : tr\u00e8s vite, il acquit la r\u00e9putation d&rsquo;un \u00ab\u00a0lanceur d&rsquo;alerte\u00a0\u00bb et ses relations avec les m\u00e9dias traditionnels se g\u00e2t\u00e8rent. Son livre de 1992 <em>Fooling America: How Washington Insiders Twist the Truth and Manufacture the Conventional Wisdom<\/em> citait des noms et ne retenait pas ses coups.<\/p>\n<\/p>\n<p><p>Au milieu des ann\u00e9es 1990, Bob devint directeur de l&rsquo;unit\u00e9 d&rsquo;enqu\u00eate du Nation Institute. Son travail articles pour The Nation en 1996 comprenait des articles sur la CIA et le trafic de drogue par les contras nicaraguayens, le pouvoir financier des fondations de droite, et un expos\u00e9 de sept pages qui reste terrifiant \u00e0 lire plus de 30 ans plus tard, &ndash; un rapport d&rsquo;enqu\u00eate sur les fr\u00e8res Koch.<\/p>\n<\/p>\n<p><p>En 1995, Parry a lanc\u00e9 un espace journalistique unique, <a href=\"https:\/\/consortiumnews.com\">Consortiumnews.com<\/a>, o&ugrave; il a travaill\u00e9 intens\u00e9ment comme \u00e9diteur, r\u00e9dacteur en chef et chroniqueur. Durant les 22 ann\u00e9es suivantes, Parry a supervis\u00e9 l&rsquo;examen du comportement de de l&rsquo;\u00e9lite washingtonienne sur son site. Son travail, qui comprit \u00e9galement l&rsquo;\u00e9dition de six livres, a remport\u00e9 la I.F. Stone Medal de la Fondation Nieman de Harvard pour r\u00e9compenser l&rsquo;ind\u00e9pendance journalistique en 2015 et, l&rsquo;ann\u00e9e derni\u00e8re, le Prix Martha Gellhorn pour le journalisme.<\/p>\n<\/p>\n<p><p>J&rsquo;ai pu voir Bob travailler de pr\u00e8s, en 1996, quand nous avons co-\u00e9crit <a href=\"https:\/\/www.consortiumnews.com\/archive\/powell.html\">une s\u00e9rie<\/a> sur le favori des m\u00e9dias de l&rsquo;\u00e9poque : \u00ab\u00a0Derri\u00e8re la l\u00e9gende de Colin Powell.\u00a0\u00bb Pendant les interviews, Bob \u00e9tait poliment impitoyable. Il avait un z\u00e8le m\u00e9thodique pour labourer des documents, d\u00e9termin\u00e9 \u00e0 \u00ab\u00a0ma&icirc;triser la doc\u00a0\u00bb. Et il \u00e9tait professionnellement g\u00e9n\u00e9reux ; j&rsquo;ai \u00e9crit une toute petite partie des articles, mais il a toujours insist\u00e9 pour que mon nom soit pr\u00e9sent \u00e0 l&rsquo;\u00e9gal du sien comme co-auteur de chacun d&rsquo;eux.<\/p>\n<\/p>\n<p><p>Bob \u00e9tait notoirement non-id\u00e9ologique. Ce qui le motivait \u00e9tait un principe moral de fer et une d\u00e9termination sans faille \u00e0 suivre les faits. Cette d\u00e9votion l&rsquo;a conduit \u00e0 exposer les tromperies mortelles et les machinations sans fin des grandes figures de l&rsquo;\u00e8re Reagan, les Oliver North, Elliott Abrams, Caspar Weinberger. Trois d\u00e9cennies plus tard, la m\u00eame volont\u00e9 de s\u00e9parer les faits de la fiction faussaire le mit en collision frontale avec la narrative conformiste du \u00ab\u00a0Russiagate\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Personne ne savait mieux que Bob Parry comment les agences de renseignement et les principaux m\u00e9dias peuvent cr\u00e9er une fr\u00e9n\u00e9sie prenant des allures diluviennes. &Agrave; partir de la fin de l&rsquo;ann\u00e9e 2016, Bob a \u00e9t\u00e9 prolifique par son travail de d\u00e9mystification du torrent de d\u00e9clarations hyperboliques et faussaires sur la Russie, devenant une inondation catastrophique et omnipr\u00e9sente dans le paysage m\u00e9diatique am\u00e9ricain. Certains sites progressistes sont pass\u00e9s de l&rsquo;habitude de publier souvent ses articles jusqu&rsquo;en 2016, \u00e0 rarement ou ne jamais les passer en 2017.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Depuis quelques ann\u00e9es, les m\u00e9dias traditionnels ont, par une couverture inf\u00e2me des relations am\u00e9ricano-russes, de l&rsquo;Ukraine au Russiagate, \u00e9t\u00e9 absolument les complices du d\u00e9veloppement de cette nouvelle guerre froide et de ses dangers sans pr\u00e9c\u00e9dent\u00a0\u00bb, observe l&rsquo;universitaire sp\u00e9calis\u00e9 dans les affaires russes Stephen F. Cohen, un contributeur de The Nation. \u00ab\u00a0Bob Parry, tr\u00e8s souvent seul, a expos\u00e9 ces malversations, en particulier celles commises par le puissant New York Times et le Washington Post, \u00e9ditant fausse nouvelle apr\u00e8s fausse nouvelle, parfois jour apr\u00e8s jour. Pour cela, il a \u00e9t\u00e9 ostracis\u00e9, insult\u00e9, certainement ignor\u00e9 par les m\u00e9dias traditionnels.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&Agrave; la fin du mois de d\u00e9cembre, une semaine apr\u00e8s que son premier AVC lui eut laiss\u00e9 une vision tr\u00e8s floue, Bob put \u00e9crire ce qui s&rsquo;av\u00e9ra \u00eatre <a href=\"https:\/\/consortiumnews.com\/2017\/12\/31\/an-apology-and-explanation\/\">son dernier article<\/a>, brillant et transcendant, une sorte de cri de c&oelig;ur qui est n&rsquo;est rien moins que son testament. \u00ab\u00a0Les journalistes occidentaux\u00a0\u00bb, \u00e9crivit-il, \u00ab\u00a0consid\u00e8rent d\u00e9sormais comme leur devoir patriotique de cacher des faits essentiels qui, sinon, mineraient la diabolisation de Poutine et de la Russie. Ironiquement, beaucoup de &lsquo;lib\u00e9raux&rsquo; qui se sont forg\u00e9s une vision sceptique lors de la Guerre Froide et des faux pr\u00e9textes de la guerre du Vietnam insistent aujourd&rsquo;hui sur le fait que nous devons tous accepter tout ce que la communaut\u00e9 am\u00e9ricaine du renseignement nous distille comme un article de la Foi.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>&Agrave; la fin d&rsquo;un long hommage qui est apparu le jour apr\u00e8s la mort de son p\u00e8re, Nat Parry <a href=\"https:\/\/consortiumnews.com\/2018\/01\/28\/robert-parrys-legacy-and-the-future-of-consortiumnews\/\">\u00e9crivit<\/a> que, \u00a0\u00bb finalement, Bob \u00e9tait motiv\u00e9 par une inqui\u00e9tude au sujet de l&rsquo;avenir de la vie sur terre. En tant que personne ayant grandi au plus fort de la guerre froide, il avait compris qu&rsquo;il \u00e9tait dangereux de se laisser entra&icirc;ner par les tensions et l&rsquo;hyst\u00e9rie, surtout dans un monde qui contient suffisamment d&rsquo;armes nucl\u00e9aires pour an\u00e9antir la vie sur la plan\u00e8te.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Robert Parry portait haut la torche de la recherche de la v\u00e9rit\u00e9. D\u00e9sormais, d&rsquo;autres devront s&rsquo;en charger.<\/p>\n<\/p>\n<p><h4>Norman Solomon<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In memoriam, Robert Parry l&rsquo;antiSyst\u00e8me Il y a peu, PhG confiait ses impressions et ses \u00e9motions aux nouvelles concernant deux grands journalistes de l&rsquo;antiSyst\u00e8me, tous deux malades, et chronique de PhG bien entendu marqu\u00e9 par l&rsquo;espoir qu&rsquo;ils nous reviendraient. Si Raimondo continue \u00e0 \u00e9crire et semble se battre avec succ\u00e8s contre la maladie, Robert Parry,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[5149,3089,12681,4431,4180,17564,2773,4194,3861,1376,3050],"class_list":["post-77736","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-ap","tag-cohen","tag-consortiumnews","tag-contras","tag-hersh","tag-investigation","tag-iran","tag-nation","tag-newsweek","tag-solomon","tag-the"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77736"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77736\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}