{"id":77754,"date":"2018-02-04T16:01:26","date_gmt":"2018-02-04T16:01:26","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/04\/comment-la-puissanceus-se-dissout\/"},"modified":"2018-02-04T16:01:26","modified_gmt":"2018-02-04T16:01:26","slug":"comment-la-puissanceus-se-dissout","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/04\/comment-la-puissanceus-se-dissout\/","title":{"rendered":"Comment la puissance\u00a0US se dissout"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Comment la puissance US se dissout<\/h2>\n<\/p>\n<p><p>Int\u00e9ressantes remarques d&rsquo;un expert de haut niveau \u00e0 Washington, <a href=\"https:\/\/www.cnas.org\/people\/paul-scharre\">Paul Scharre<\/a>, ancien haut-fonctionnaire du Pentagone, Senior Fellow et Directeur du <em>Technology and National Security Program<\/em>, une des branches du <em>Center for a New American Security<\/em>. On y retrouve toutes les tendances que nous d\u00e9taillons r\u00e9guli\u00e8rement, y compris <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-le-nucleaire-le-jsf-et-le-simulacre\">aujourd&rsquo;hui<\/a>, sur la bureaucratisation entropique, la paralysie du Pentagone dans le processus de modernisation jusqu&rsquo;\u00e0 des processus de r\u00e9gression. Tout cela place la puissance militaire des USA sur la pente d&rsquo;une v\u00e9ritable dissolution, de sa transformation en simulacre.<\/p>\n<\/p>\n<p><p>Scharre parle, d&rsquo;une fa\u00e7on r\u00e9v\u00e9latrice, \u00e0 RT, repris par <em>Sputnik<\/em>-fran\u00e7ais le <a href=\"https:\/\/fr.sputniknews.com\/defense\/201802041035006491-usa-russie-defense\/\">4 mars 2018<\/a> : &laquo; <em>Les forces arm\u00e9es am\u00e9ricaines ne sont pas pr\u00eates \u00e0 parer aux menaces existantes de la part de la Russie et de la Chine, a d\u00e9clar\u00e9 Paul Scharre, collaborateur du Center for a New American Security. P\u00e9kin menace Washington avec ses \u00ab\u00a0centaines de missiles de croisi\u00e8re et ses plus de 1.000 missiles balistiques\u00a0\u00bb et Moscou d\u00e9passe l&rsquo;arm\u00e9e am\u00e9ricaine dans plusieurs types d&rsquo;armements, a indiqu\u00e9 l&rsquo;analyste, cit\u00e9 par la cha&icirc;ne RT<\/em>.<\/p>\n<\/p>\n<p><p>&laquo; \u00ab\u00a0<em>Les &Eacute;tats-Unis sont en retard par rapport \u00e0 la Russie, qui investit beaucoup plus de moyens dans le perfectionnement de son potentiel de frappes de haute pr\u00e9cision \u00e0 grande port\u00e9e et dans la modernisation de ses syst\u00e8mes antia\u00e9riens, ainsi que dans les moyens et m\u00e9thodes de guerre \u00e9lectronique\u00a0\u00bb, a indiqu\u00e9 M. Scharre. Les &Eacute;tats-Unis perdent du terrain en raison de l&rsquo;absence de \u00ab\u00a0souplesse strat\u00e9gique\u00a0\u00bb et de pr\u00e9vision opportune. En outre, la bureaucratisation du syst\u00e8me am\u00e9ricain risque, selon lui, <strong>de reporter \u00e0 des dizaines d&rsquo;ann\u00e9es la mise en exploitation de nouvelles armes<\/strong><\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Pour r\u00e9pondre aux d\u00e9fis actuels, le Pentagone devrait renoncer aux \u00ab\u00a0projets ambitieux\u00a0\u00bb et modifier la structure de financement des d\u00e9veloppements militaires, estime-t-il. Il faudrait consacrer plus de moyens \u00e0 l&rsquo;achat de bombardiers strat\u00e9giques, au d\u00e9veloppement de drones furtifs et aux moyens de guerre \u00e9lectronique<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 04 f\u00e9vrier 2018 \u00e0 15H58<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment la puissance US se dissout Int\u00e9ressantes remarques d&rsquo;un expert de haut niveau \u00e0 Washington, Paul Scharre, ancien haut-fonctionnaire du Pentagone, Senior Fellow et Directeur du Technology and National Security Program, une des branches du Center for a New American Security. On y retrouve toutes les tendances que nous d\u00e9taillons r\u00e9guli\u00e8rement, y compris aujourd&rsquo;hui, sur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[831,2623,5805,18077,3194,2884,2730,18076,5230],"class_list":["post-77754","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-a","tag-bureaucratie","tag-entropie","tag-lagonie","tag-pentagone","tag-russe","tag-russie","tag-scharre","tag-superiorite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77754"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77754\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}