{"id":77756,"date":"2018-02-06T13:43:33","date_gmt":"2018-02-06T13:43:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/06\/neo-totalitarisme-huxley-fait-le-point-en-1957\/"},"modified":"2018-02-06T13:43:33","modified_gmt":"2018-02-06T13:43:33","slug":"neo-totalitarisme-huxley-fait-le-point-en-1957","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/06\/neo-totalitarisme-huxley-fait-le-point-en-1957\/","title":{"rendered":"N\u00e9o-totalitarisme\u00a0: Huxley fait le point en 1957"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">N\u00e9o-totalitarisme : Huxley fait le point en 1957<\/h2>\n<\/p>\n<p><p>Nota : ce texte et long et n&ucirc;ment r\u00e9f\u00e9renc\u00e9. Il appara&icirc;tra pessimiste \u00e0 certains.<\/p>\n<\/p>\n<p><p>On est en 1957. Sputnik fait r\u00eaver les plus conditionn\u00e9s, mais Aldous Huxley rappelle :<\/p>\n<\/p>\n<p><p>&laquo; En 1931, alors que j&rsquo;\u00e9crivais Le Meilleur des Mondes, j&rsquo;\u00e9tais convaincu que le temps ne pressait pas encore. <strong>La soci\u00e9t\u00e9 int\u00e9gralement organis\u00e9e, le syst\u00e8me scientifique des castes, l&rsquo;abolition du libre arbitre par conditionnement m\u00e9thodique, la servitude rendue tol\u00e9rable par des doses r\u00e9guli\u00e8res de bonheur chimiquement provoqu\u00e9, les dogmes orthodoxes enfonc\u00e9s dans les cervelles pendant le -sommeil au moyen des cours de nuit, tout cela approchait<\/strong>; se r\u00e9aliserait bien s&ucirc;r, mais ni de mon vivant, ni m\u00eame du vivant de mes petits-enfants. &raquo;<\/p>\n<\/p>\n<p><p>Il fait un constat apr\u00e8s la guerre, comme Bertrand de Jouvenel :<\/p>\n<\/p>\n<p><p>&laquo; Vingt-sept ans plus tard, dans ce troisi\u00e8me quart du vingti\u00e8me si\u00e8cle apr\u00e8s J-C. et bien longtemps avant la fin du premier si\u00e8cle apr\u00e8s F., <strong>je suis beaucoup moins optimiste que je l&rsquo;\u00e9tais en \u00e9crivant Le Meilleur des Mondes. Les proph\u00e9ties faites en 1931 se r\u00e9alisent bien plus t\u00f4t que je le pensais. L&rsquo;intervalle b\u00e9ni entre trop de d\u00e9sordre et trop d&rsquo;ordre n&rsquo;a pas commenc\u00e9 et rien n&rsquo;indique qu&rsquo;il le fera jamais.<\/strong> En Occident, il est vrai, hommes et femmes jouissent encore dans une appr\u00e9ciable mesure de la libert\u00e9 individuelle, mais m\u00eame dans les pays qui ont une longue tradition de gouvernement d\u00e9mocratique cette libert\u00e9, voire le d\u00e9sir de la poss\u00e9der, paraissent en d\u00e9clin. Dans le reste du monde, elle a d\u00e9j\u00e0 disparu, ou elle est sur le point de le faire. Le cauchemar de l&rsquo;organisation int\u00e9grale que j&rsquo;avais situ\u00e9 dans le septi\u00e8me si\u00e8cle apr\u00e8s F. a surgi de lointains dont l&rsquo;\u00e9loignement rassurait et nous guette maintenant au premier tournant. &raquo;<\/p>\n<\/p>\n<p><p>Le communisme a facilement chut\u00e9 partout finalement mais il a \u00e9t\u00e9 remplac\u00e9 parce que Debord nomme le <strong>spectaculaire int\u00e9gr\u00e9<\/strong>. Tocqueville d\u00e9j\u00e0 disait &laquo; qu&rsquo;en d\u00e9mocratie on laisse le corps pour s&rsquo;attaquer \u00e0 l&rsquo;\u00e2me. &raquo;<\/p>\n<\/p>\n<p><p>Le futur c&rsquo;est la carotte plut\u00f4t que le b\u00e2ton (cf. mes textes sur Tocqueville, Nietzsche ou le film Network) :<\/p>\n<\/p>\n<p><p>&laquo; A la lumi\u00e8re de ce que nous avons r\u00e9cemment appris sur le comportement animal en g\u00e9n\u00e9ral et sur le comportement humain en particulier, <strong>il est devenu \u00e9vident que le contr\u00f4le par r\u00e9pression des attitudes non conformes est moins efficace, au bout du compte, que le contr\u00f4le par renforcement des attitudes satisfaisantes au moyen de r\u00e9compenses et que, dans l&rsquo;ensemble, la terreur en tant que proc\u00e9d\u00e9 de gouvernement rend moins bien que la manipulation non violente du milieu, des pens\u00e9es et des sentiments de l&rsquo;individu<\/strong>. &raquo;<\/p>\n<\/p>\n<p><p>La manipulation est donc \u00e0 l&rsquo;ordre du jour :<\/p>\n<\/p>\n<p><p>&laquo; Pendant ce temps, des forces impersonnelles sur lesquelles nous n&rsquo;avons presque aucun contr\u00f4le semblent nous pousser tous dans la direction du cauchemar de mon anticipation et cette impulsion d\u00e9shumanis\u00e9e est sciemment acc\u00e9l\u00e9r\u00e9e par les repr\u00e9sentants d&rsquo;organisations commerciales et politiques qui ont mis au point nombre de nouvelles techniques pour manipuler, dans l&rsquo;int\u00e9r\u00eat de quelque minorit\u00e9, les pens\u00e9es et les sentiments des masses. &raquo;<\/p>\n<\/p>\n<p><p>La cl\u00e9 du syst\u00e8me est son renforcement par la d\u00e9mographie explosive :<\/p>\n<\/p>\n<p><p>&laquo; De plus, l&rsquo;accroissement annuel lui-m\u00eame s&rsquo;accro&icirc;t : r\u00e9guli\u00e8rement, selon la r\u00e8gle des int\u00e9r\u00eats compos\u00e9s et irr\u00e9guli\u00e8rement aussi, \u00e0 chaque application, par une soci\u00e9t\u00e9 technologiquement retardataire, des principes de la Sant\u00e9 publique. A l&rsquo;heure pr\u00e9sente, cet exc\u00e9dent atteint 43 millions environ pour l&rsquo;ensemble du globe, ce qui signifie que tous les quatre ans l&rsquo;humanit\u00e9 ajoute \u00e0 ses effectifs l&rsquo;\u00e9quivalent de la population actuelle des Etats-Unis &#8211; tous les huit ans et demi l&rsquo;\u00e9quivalent de la population actuelle des Indes. &raquo;<\/p>\n<\/p>\n<p><p>Huxley remet \u00e0 sa place les blablas sur la pseudo-conqu\u00eate spatiale :<\/p>\n<\/p>\n<p><p>&laquo; Une nouvelle \u00e8re est cens\u00e9e avoir commenc\u00e9 le 4 octobre 1957, mais en r\u00e9alit\u00e9, dans l&rsquo;\u00e9tat pr\u00e9sent du monde, <strong>tout notre exub\u00e9rant bavardage post-spoutnik est hors de propos, voire m\u00eame absurde.<\/strong> En ce qui concerne les masses de l&rsquo;humanit\u00e9, l&rsquo;\u00e2ge qui vient ne sera pas celui de l&rsquo;Espace cosmique, mais celui de la surpopulation. &raquo;<\/p>\n<\/p>\n<p><p>Cons\u00e9quence ? Les &laquo; trous \u00e0 merde &raquo; de Donald :<\/p>\n<\/p>\n<p><p>&laquo; Les faits contr\u00f4lables semblent indiquer assez nettement que dans la plupart des pays sous-d\u00e9velopp\u00e9s, le sort de l&rsquo;individu s&rsquo;est d\u00e9t\u00e9rior\u00e9 de fa\u00e7on appr\u00e9ciable au cours du dernier demi-si\u00e8cle.<strong> Les habitants sont plus mal nourris; il existe moins de biens de consommation disponibles par t\u00eate et pratiquement tous les efforts faits pour am\u00e9liorer la situation ont \u00e9t\u00e9 annul\u00e9s par l&rsquo;impitoyable pression d&rsquo;un accroissement continu de la population<\/strong>. &raquo;<\/p>\n<\/p>\n<p><p>Le &laquo; plus froid des monstres froids &raquo; (Nietzsche) va se d\u00e9velopper. Une remarque digne de Jouvenel :<\/p>\n<\/p>\n<p><p>&laquo; Ainsi, des pouvoirs de plus en plus grands sont concentr\u00e9s entre les mains de l&rsquo;ex\u00e9cutif et de ses bureaucrates. <strong>Or, la nature du pouvoir est telle que m\u00eame ceux qui ne l&rsquo;ont pas recherch\u00e9 mais \u00e0 qui il a \u00e9t\u00e9 impos\u00e9, ont tendance \u00e0 y prendre go&ucirc;t&hellip; &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Le Deep State (le &laquo; minotaure &raquo; de Jouvenel) est condamn\u00e9 \u00e0 cro&icirc;tre avec le totalitarisme dans les pays en voie de surpeuplement :<\/p>\n<\/p>\n<p><p>&laquo; Ins\u00e9curit\u00e9 et agitation m\u00e8nent \u00e0 un contr\u00f4le accru exerc\u00e9 par les gouvernements centraux et \u00e0 une extension de leurs pouvoirs. En l&rsquo;absence d&rsquo;une tradition constitutionnelle, ces pouvoirs accrus seront probablement exerc\u00e9s de mani\u00e8re dictatoriale. &raquo;<\/p>\n<\/p>\n<p><p>La surpopulation am\u00e9ricaine menacera la d\u00e9mocratie am\u00e9ricaine (triplement en un si\u00e8cle ! La France a cr&ucirc; de 40% en cinquante ans) :<\/p>\n<\/p>\n<p><p>&laquo; Pour le moment, la surpopulation ne constitue pas pour la libert\u00e9 individuelle des Am\u00e9ricains un danger direct, mais d\u00e9j\u00e0 la menace d&rsquo;une menace. &raquo;<\/p>\n<\/p>\n<p><p>Eug\u00e9niste, proche de Carrel ici, Huxley annonce un d\u00e9clin qualitatif de notre population et de notre intelligence, fait aujourd&rsquo;hui reconnu :<\/p>\n<\/p>\n<p><p>&laquo; Malgr\u00e9 les nouvelles drogues-miracle et des traitements plus efficaces (on peut m\u00eame dire en un certain sens, gr\u00e2ce \u00e0 eux),<strong> la sant\u00e9 physique de la masse ne s&rsquo;am\u00e9liorera pas, au contraire, et un d\u00e9clin de l&rsquo;intelligence moyenne pourrait bien accompagner cette d\u00e9t\u00e9rioration. &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Huxley critique froidement les progr\u00e8s de la m\u00e9decine (ou leur mauvaise gestion) :<\/p>\n<\/p>\n<p><p>&laquo; La mort rapide due \u00e0 la malaria a \u00e9t\u00e9 supprim\u00e9e, mais une existence rendue mis\u00e9rable par la sous-alimentation et le surpeuplement est main- tenant la r\u00e8gle et une mort lente, par inanition, guette un nombre de plus en plus grand d&rsquo;habitants. &raquo;<\/p>\n<\/p>\n<p><p>Huxley ici reprend Bernays sur la mont\u00e9e des \u00e9lites :<\/p>\n<\/p>\n<p><p>&laquo;<strong> Nous voyons donc que la technique moderne a conduit \u00e0 la concentration du pouvoir \u00e9conomique et politique ainsi qu&rsquo;au d\u00e9veloppement d&rsquo;une soci\u00e9t\u00e9 contr\u00f4l\u00e9e (avec f\u00e9rocit\u00e9 dans les Etats totalitaires, courtoisie et discr\u00e9tion dans les d\u00e9mocraties) par les Grosses Affaires et les Gros Gouvernements.<\/strong> &raquo;<\/p>\n<\/p>\n<p><p>Notre auteur cite Fromm :<\/p>\n<\/p>\n<p><p>&laquo; &hellip;Notre soci\u00e9t\u00e9 tend \u00e0 faire de lui un automate qui paie son \u00e9chec sur le plan humain par des maladies mentales toujours plus fr\u00e9quentes et un d\u00e9sespoir qui se dissimule sous une fr\u00e9n\u00e9sie de travail et de pr\u00e9tendu plaisir. &raquo;<\/p>\n<\/p>\n<p><p>Puis Huxley \u00e9value la nullit\u00e9 des hommes modernes et par l\u00e0 se rapproche de Ren\u00e9 Gu\u00e9non (voyez l&rsquo;anonymat dans le r\u00e8gne de la quantit\u00e9) :<\/p>\n<\/p>\n<p><p>&laquo; Ces millions d&rsquo;anormalement normaux vivent sans histoires dans une soci\u00e9t\u00e9 dont ils ne s&rsquo;accommoderaient pas s&rsquo;ils \u00e9taient pleinement humains et s&rsquo;accrochent encore \u00e0 &laquo; l&rsquo;illusion de l&rsquo;individualit\u00e9 &raquo;, mais en fait, ils ont \u00e9t\u00e9 dans une large mesure d\u00e9personnalis\u00e9s. Leur conformit\u00e9 \u00e9volue vers l&rsquo;uniformit\u00e9. &raquo;<\/p>\n<\/p>\n<p><p>Le futur est \u00e0 la termiti\u00e8re :<\/p>\n<\/p>\n<p><p>&laquo; La civilisation este entre autres choses, le processus par lequel les bandes primitives sont transform\u00e9es en un \u00e9quivalent, grossier et m\u00e9canique, des communaut\u00e9s organiques d&rsquo;insectes sociaux. A l&rsquo;heure pr\u00e9sente, les pressions du surpeuplement et de l&rsquo;\u00e9volution technique acc\u00e9l\u00e8rent ce mouvement. La termiti\u00e8re en est arriv\u00e9e \u00e0 repr\u00e9senter un id\u00e9al r\u00e9alisable et m\u00eame, aux yeux de certains, souhaitable. &raquo;<\/p>\n<\/p>\n<p><p>Termiti\u00e8re ? Plus effrayant encore ce passage &ndash; car tous les mots sont rentr\u00e9s dans notre lexique :<\/p>\n<\/p>\n<p><p>&laquo; Ainsi que l&rsquo;a montr\u00e9 Mr. William Whyte dans son remarquable ouvrage, The Organization man, une nouvelle Morale Sociale est en train de remplacer notre syst\u00e8me traditionnel qui donne la premi\u00e8re place \u00e0 l&rsquo;individu. Les mots clefs en sont : &laquo; ajustement &raquo;, &laquo; adaptation &raquo;, &laquo; comportement social ou antisocial &raquo;, &laquo; int\u00e9gration &raquo;, &laquo; acquisition de techniques sociales &raquo;, &laquo; travail d&rsquo;\u00e9quipe &raquo;, &laquo; vie communautaire &raquo;, &laquo; loyalisme communautaire &raquo;, &laquo; dynamique communautaire &raquo;, &laquo; pens\u00e9e communautaire &raquo;, &laquo; activit\u00e9s cr\u00e9atrices communautaires &raquo;&hellip;<\/p>\n<\/p>\n<p><p>Car l&rsquo;ing\u00e9nierie sociale c&rsquo;est la fin du christianisme et m\u00eame du Christ :<\/p>\n<\/p>\n<p><p>&laquo; Selon la Morale Sociale, J\u00e9sus avait compl\u00e8tement tort quand il affirmait que le sabbat a \u00e9t\u00e9 fait pour l&rsquo;homme pour l&rsquo;homme; au contraire, c&rsquo;est l&rsquo;homme qui. a \u00e9t\u00e9 fait pour le sabbat, qui doit sacrifier ses particularit\u00e9s natives et faire semblant d&rsquo;\u00eatre la sorte de bon gar\u00e7on invariablement liant que les organisateurs d&rsquo;activit\u00e9s collectives consid\u00e8rent comme le plus propre \u00e0 leurs fins. &raquo;<\/p>\n<\/p>\n<p><p>En bon patricien britannique (voyez mon livre sur Tolkien, mes essais sur Chesterton), Huxley refuse cet assemblage :<\/p>\n<\/p>\n<p><p>&laquo; Un gouffre immense s\u00e9pare l&rsquo;insecte social du mammif\u00e8re avec son gros cerveau, son instinct gr\u00e9gaire tr\u00e8s mitig\u00e9 et ce gouffre demeurerait, m\u00eame si l&rsquo;\u00e9l\u00e9phant s&rsquo;effor\u00e7ait d&rsquo;imiter la fourmi. Malgr\u00e9 tous leurs efforts, les hommes ne peuvent que cr\u00e9er une organisation et non pas un organisme social. En s&rsquo;acharnant \u00e0 r\u00e9aliser ce dernier, ils parviendront tout juste \u00e0 un despotisme totalitaire. &raquo;<\/p>\n<\/p>\n<p><p>Le futur indolore de la domination est programm\u00e9 :<\/p>\n<\/p>\n<p><p>&laquo; Dans les dictatures plus efficaces de demain, il y aura sans doute beaucoup moins de force d\u00e9ploy\u00e9e. Les sujets des tyrans \u00e0 venir seront enr\u00e9giment\u00e9s sans douleur par un corps d&rsquo;ing\u00e9nieurs sociaux hautement qualifi\u00e9s. &raquo;<\/p>\n<\/p>\n<p><p>Dix ans avant Umberto Eco (voyez mon livre sur Internet), Huxley annonce un nouveau moyen \u00e2ge, pas celui de Gu\u00e9non bien s&ucirc;r, celui de Le Goff plut\u00f4t :<\/p>\n<\/p>\n<p><p>&laquo; Les forces impersonnelles du surpeuplement et de l&rsquo;exc\u00e8s d&rsquo;organisation jointes aux ing\u00e9nieurs sociologues qui essaient de les diriger, nous poussent vers un nouveau syst\u00e8me m\u00e9di\u00e9val. &raquo;<\/p>\n<\/p>\n<p><p>Huxley annonce la propagande \u00e0 venir en occident :<\/p>\n<\/p>\n<p><p>&laquo; La propagande pour une action dict\u00e9e par des impulsions plus basses que l&rsquo;int\u00e9r\u00eat pr\u00e9sente des preuves forg\u00e9es, falsifi\u00e9es, ou tronqu\u00e9es, \u00e9vite les arguments logiques et cherche \u00e0 influencer ses victimes par la simple r\u00e9p\u00e9tition de slogans, la furieuse d\u00e9nonciation de boucs \u00e9missaires \u00e9trangers ou nationaux, et l&rsquo;association machiav\u00e9lique des passions les plus viles aux id\u00e9aux les plus \u00e9lev\u00e9s&hellip; &raquo;<\/p>\n<\/p>\n<p><p>Huxley m\u00e9prise la libert\u00e9 de la presse en rappelant ce simple fait :<\/p>\n<\/p>\n<p><p>&laquo; En ce qui concerne la propagande, les premiers partisans de l&rsquo;instruction obligatoire et d&rsquo;une presse libre ne l&rsquo;envisageaient que sous deux aspects : vraie ou fausse. Ils ne pr\u00e9voyaient pas ce qui, en fait, s&rsquo;est produit- le d\u00e9veloppement d&rsquo;une immense industrie de l&rsquo;information, ne s&rsquo;occupant dans l&rsquo;ensemble ni du vrai, ni du faux, mais de l&rsquo;irr\u00e9el et de l&rsquo;incons\u00e9quent \u00e0 tous les degr\u00e9s. En un mot, ils n&rsquo;avaient pas tenu compte de la fringale de distraction \u00e9prouv\u00e9e par les hommes. &raquo;<\/p>\n<\/p>\n<p><p>On retombe dans le pain et les jeux de Juv\u00e9nal :<\/p>\n<\/p>\n<p><p>&laquo; Pour trouver une situation comparable, f&ucirc;t-ce de loin, \u00e0 celle qui existe actuellement, il nous faut remonter jusqu&rsquo;\u00e0 la Rome imp\u00e9riale, o&ugrave; la populace \u00e9tait maintenue dans la bonne humeur gr\u00e2ce \u00e0 des doses fr\u00e9quentes et gratuites des distractions les plus vari\u00e9es, allant des drames en vers aux combats de gladiateurs, des r\u00e9citations de Virgile aux s\u00e9ances de pugilat, des concerts aux revues militaires et aux ex\u00e9cutions publiques. Mais m\u00eame \u00e0 Rome, il n&rsquo;existait rien de semblable aux distractions ininterrompues fournies par les journaux, les revues, la radio, la t\u00e9l\u00e9vision et le cin\u00e9ma. &raquo;<\/p>\n<\/p>\n<p><p>Une pr\u00e9diction (pr\u00e9diction ou constatation ?) terrible :<\/p>\n<\/p>\n<p><p>&laquo; Une soci\u00e9t\u00e9 dont la plupart des membres passent une grande partie de leur temps, non pas dans l&rsquo;imm\u00e9diat et l&rsquo;avenir pr\u00e9visible, mais quelque part dans les autres mondes incons\u00e9quents du sport, des feuilletons, de la mythologie et de la fantaisie m\u00e9taphysique, aura bien du mal \u00e0 r\u00e9sister aux empi\u00e9tements de ceux qui voudraient la manipuler et la dominer. &raquo;<\/p>\n<\/p>\n<p><p>Le futur est \u00e0 la &laquo; distraction ininterrompue &raquo; qui se m\u00ealera \u00e0 la propagande.<\/p>\n<\/p>\n<p><p>Huxley cite Albert Speer. Apr\u00e8s Hitler on n&rsquo;a pas arr\u00eat\u00e9 le progr\u00e8s.<\/p>\n<\/p>\n<p><p>&laquo; Depuis l&rsquo;\u00e9poque de Hitler, l&rsquo;arsenal des moyens techniques \u00e0 la disposition de l&rsquo;aspirant-dictateur a \u00e9t\u00e9 consid\u00e9rablement d\u00e9velopp\u00e9! En plus de la radio, du haut-parleur, de la cam\u00e9ra de cin\u00e9ma et de la presse rotative, le propagandiste contemporain peut faire usage de la t\u00e9l\u00e9vision pour transmettre non seulement la voix, mais l&rsquo;image de son client et enregistrer le tout sur des bandes magn\u00e9tiques. Gr\u00e2ce aux progr\u00e8s techniques, le Grand Fr\u00e8re peut maintenant \u00eatre omnipr\u00e9sent presque autant que Dieu. D&rsquo;ailleurs, il n&rsquo;y a pas que dans ce domaine que des atouts nouveaux ont \u00e9t\u00e9 apport\u00e9s au jeu du dictateur. Depuis Hitler, des travaux consid\u00e9rables ont \u00e9t\u00e9 faits en psychologie et neurologie appliqu\u00e9es, domaines d&rsquo;\u00e9lection du propagandiste, de l&rsquo;endoctrineur, et du laveur de cerveaux. &raquo;<\/p>\n<\/p>\n<p><p>Puis Huxley compare Hitler \u00e0 Bernays, l&rsquo;inventeur de la cigarette pour les femmes :<\/p>\n<\/p>\n<p><p>&laquo; C&rsquo;est par la manipulation de &laquo; forces cach\u00e9es &raquo; que les experts en publicit\u00e9 vous incitent \u00e0 acheter leurs produits &#8211; une p\u00e2te dentifrice, une marque de cigarettes, un candidat politique &#8211; et c&rsquo;est en faisant appel aux m\u00eames, ainsi qu&rsquo;\u00e0 d&rsquo;autres trop dangereuses pour que s&rsquo;y frotte Madison Avenue, que Hitler a incit\u00e9 les masses allemandes \u00e0 s&rsquo;acheter un F\u00fchrer, une philosophie insane et une Deuxi\u00e8me Guerre mondiale. &raquo;<\/p>\n<\/p>\n<p><p>Apr\u00e8s Hitler, la publicit\u00e9 commerciale. Huxley cite Vance Packard et ajoute :<\/p>\n<\/p>\n<p><p>&laquo; Nous n&rsquo;achetons plus des oranges, mais de la vitalit\u00e9. Nous n&rsquo;achetons plus une voiture, mais du prestige. &raquo; Il en est de m\u00eame pour tout le reste. Avec un dentifrice, nous achetons non plus un simple d\u00e9tersif antiseptique, mais la lib\u00e9ration d&rsquo;une angoisse : celle d&rsquo;\u00eatre sexuellement repoussant. Avec la vodka et le whisky, nous n&rsquo;achetons pas un poison protoplasmique qui, \u00e0 doses faibles, peut d\u00e9primer le syst\u00e8me nerveux de mani\u00e8re utile au point de vue psychologique, nous achetons de l&rsquo;amabilit\u00e9, du liant, la chaleur&hellip; Avec l&rsquo;ouvrage \u00e0 succ\u00e8s du mois, nous acqu\u00e9rons de la culture, l&rsquo;envie de nos voisins moins intellectuels et le respect des raffin\u00e9s. &raquo;<\/p>\n<\/p>\n<p><p>Huxley n&rsquo;est pas tr\u00e8s optimise non plus sur l&rsquo;avenir des enfants mu\u00e9s en de la chair \u00e0 t\u00e9l\u00e9 :<\/p>\n<\/p>\n<p><p>&laquo; Comme on pouvait s&rsquo;y attendre, les jeunes sont extr\u00eamement sensibles \u00e0 la propagande. Ignorants du monde et de ses usages, ils sont absolument sans m\u00e9fiance, leur esprit critique n&rsquo;est pas encore d\u00e9velopp\u00e9, les plus petits n&rsquo;ont pas atteint l&rsquo;\u00e2ge de raison et les plus \u00e2g\u00e9s n&rsquo;ont pas acquis l&rsquo;exp\u00e9rience sur laquelle leur facult\u00e9 de raisonnement nouvellement d\u00e9couverte pourrait s&rsquo;exercer. En Europe, les conscrits \u00e9taient d\u00e9sign\u00e9s sous le nom badin de &laquo; chair \u00e0 canon &raquo;. Leurs petits fr\u00e8res et leurs petites s&oelig;urs sont maintenant devenus de la chair \u00e0 radio et \u00e0 t\u00e9l\u00e9vision. Dans mon enfance, on nous apprenait \u00e0 chanter de petites rengaines sans grand sens ou, dans les familles pieuses, des cantiques. Aujourd&rsquo;hui, les petits gazouillent de la publicit\u00e9 chant\u00e9e. &raquo;<\/p>\n<\/p>\n<p><p>Pas d&rsquo;illusions sur les \u00e9lections et la politique :<\/p>\n<\/p>\n<p><p>&laquo; Les partis mettent leurs candidats et leurs programmes sur le march\u00e9 en utilisant les m\u00eames m\u00e9thodes que le monde des affaires pour vendre ses produits&hellip; Les services de ventes politiques ne font appel qu&rsquo;aux faiblesses de leurs \u00e9lecteurs, jamais \u00e0 leur force latente. Ils se gardent bien d&rsquo;\u00e9duquer les masses et de les mettre en mesure de se gouverner elles-m\u00eames, jugeant tr\u00e8s suffisant de les manipuler et de les exploiter. &raquo;<\/p>\n<\/p>\n<p><p>Sur le lavage de cerveau pratiqu\u00e9 dans notre plan\u00e8te-prison, Huxley rappelle :<\/p>\n<\/p>\n<p><p>&laquo; Si le syst\u00e8me nerveux central du chien peut \u00eatre bris\u00e9, celui d&rsquo;un prisonnier politique aussi. Il s&rsquo;agit seulement d&rsquo;appliquer les doses de tension voulues pendant le temps voulu. A la fin du traitement, l&rsquo;intern\u00e9 sera dans un \u00e9tat de n\u00e9vrose ou d&rsquo;hyst\u00e9rie tel qu&rsquo;il avouera ce que ses ge\u00f4liers voudront. &raquo;<\/p>\n<\/p>\n<p><p>Huxley explique pourquoi notre syst\u00e8me de suggestibilit\u00e9 encourage le somnambulisme puis il rappelle tristement :<\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;efficacit\u00e9 de la propagande politique et religieuse d\u00e9pend des m\u00e9thodes employ\u00e9es et non pas des doctrines enseign\u00e9es. Ces derni\u00e8res peuvent \u00eatre vraies ou fausses, saines ou pernicieuses, peu importe. Si l&rsquo;endoctrinement est bien fait au stade voulu de l&rsquo;\u00e9puisement nerveux, il r\u00e9ussira. &raquo;<\/p>\n<\/p>\n<p><p>Opiomanie ou toxicomanie ? Huxley rappelle ici le fameux soma de son roman :<\/p>\n<\/p>\n<p><p>&laquo; La ration de soma quotidienne \u00e9tait une garantie contre l&rsquo;inqui\u00e9tude personnelle, l&rsquo;agitation sociale et la propagation d&rsquo;id\u00e9es subversives. <strong>Karl Marx d\u00e9clarait que la religion \u00e9tait l&rsquo;opium du peuple, mais dans le Meilleur des Mondes la situation se trouvait renvers\u00e9e : l&rsquo;opium, ou plut\u00f4t le soma, \u00e9tait la religion du peuple.<\/strong> &raquo;<\/p>\n<\/p>\n<p><p>Huxley rappelle nos progr\u00e8s en chimie du cerveau et il proph\u00e9tise l&rsquo;addiction am\u00e9ricaine responsable aujourd&rsquo;hui de dizaines de milliers de morts :<\/p>\n<\/p>\n<p><p>&laquo; &hellip;prenez le cas des barbituriques et des tranquillisants. Aux U.S.A., ces rem\u00e8des peuvent \u00eatre obtenus avec une simple ordonnance de docteur, mais l&rsquo;avidit\u00e9 du public am\u00e9ricain pour quelque chose qui rendra un peu plus supportable la vie dans le milieu urbain et industriel est si grande, que les m\u00e9decins ordonnent actuellement de ces sp\u00e9cialit\u00e9s au rythme de 48 millions de prescriptions par an. &raquo;<\/p>\n<\/p>\n<p><p>On contr\u00f4lera donc l&rsquo;opposition politique par les tranquillisants !<\/p>\n<\/p>\n<p><p>&laquo; Les masses ne risqueront pas de cr\u00e9er la moindre difficult\u00e9 \u00e0 leur ma&icirc;tre. Seulement, dans l&rsquo;\u00e9tat actuel des choses, les tranquillisants peuvent emp\u00eacher certaines personnes de cr\u00e9er assez de difficult\u00e9, non seulement \u00e0 leurs dirigeants, mais \u00e0 elles-m\u00eames. &raquo;<\/p>\n<\/p>\n<p><p>On peut m\u00eame gagner la guerre par les tranquillisants !<\/p>\n<\/p>\n<p><p>&laquo; Lors d&rsquo;une r\u00e9cente conf\u00e9rence sur le m\u00e9probamate, \u00e0 laquelle je participais, un \u00e9minent biochimiste proposa en riant que le gouvernement des U.S.A. envoy\u00e2t gratuitement au peuple sovi\u00e9tique 50 milliards de doses du plus populaire des tranquillisants. La plaisanterie avait son c\u00f4t\u00e9 inqui\u00e9tant. &raquo;<\/p>\n<\/p>\n<p><p>Chez Huxley comme chez La Bo\u00e9tie le fond du probl\u00e8me n&rsquo;est pas la malignit\u00e9 de la science ou des \u00e9lites sinon la m\u00e9diocrit\u00e9 de la nature humaine d\u00e9montr\u00e9e ici par la science&#8230;<\/p>\n<\/p>\n<p><p>&laquo; Les id\u00e9aux de la d\u00e9mocratie et de la libert\u00e9 se heurtent au fait brutal de la suggestibilit\u00e9 humaine. Un cinqui\u00e8me de tous les \u00e9lecteurs peut \u00eatre hypnotis\u00e9 presque en un clin d&rsquo;&oelig;il, un septi\u00e8me soulag\u00e9 de ses souffrances par des piq&ucirc;res d&rsquo;eau, un quart suggestionn\u00e9 avec rapidit\u00e9 et dans l&rsquo;enthousiasme par I&rsquo;hypnop\u00e9die. A toutes ces minorit\u00e9s trop promptes \u00e0 coop\u00e9rer, on doit ajouter les majorit\u00e9s aux r\u00e9actions moins rapides dont la suggestibilit\u00e9 plus mod\u00e9r\u00e9e peut \u00eatre exploit\u00e9e par n&rsquo;importe quel manipulateur connaissant son affaire, pr\u00eat \u00e0 y consacrer le temps et les efforts n\u00e9cessaires. &raquo;<\/p>\n<\/p>\n<p><p>Quant au futur, no comment :<\/p>\n<\/p>\n<p><p>&laquo; La libert\u00e9 individuelle est-elle compatible avec un degr\u00e9 \u00e9lev\u00e9 de suggestibilit\u00e9? Les institutions d\u00e9mocratiques peuvent-elles survivre \u00e0 la subversion exerc\u00e9e du dedans par des sp\u00e9cialistes habiles dans la science et l&rsquo;art d&rsquo;exploiter la suggestibilit\u00e9 \u00e0 la fois des individus et des foules? &raquo;<\/p>\n<\/p>\n<p><p>Il reste que le futur, en 1957, c&rsquo;est aussi, c&rsquo;est surtout cent millions de couillonnes sur Instagram admirant et imitant Kylie Jenner. Huxley :<\/p>\n<\/p>\n<p><p>&laquo; Et l&rsquo;uniformisation des \u00eatres \u00e9tait encore parachev\u00e9e apr\u00e8s la naissance par le conditionnement infantile, l&rsquo;hypnop\u00e9die et l&rsquo;euphorie chimique destin\u00e9e \u00e0 remplacer la satisfaction de se sentir libre et cr\u00e9ateur. <strong>Dans le monde o&ugrave; nous vivons, ainsi qu&rsquo;il a \u00e9t\u00e9 indiqu\u00e9 dans des chapitres pr\u00e9c\u00e9dents, d&rsquo;immenses forces impersonnelles tendent vers l&rsquo;\u00e9tablissement d&rsquo;un pouvoir centralis\u00e9 et d&rsquo;une soci\u00e9t\u00e9 enr\u00e9giment\u00e9e. La standardisation g\u00e9n\u00e9tique est encore impossibl<\/strong>e, mais les Gros Gouvernements et les Grosses Affaires poss\u00e8dent d\u00e9j\u00e0, ou poss\u00e9deront bient\u00f4t, tous les proc\u00e9d\u00e9s pour la manipulation des esprits d\u00e9crits dans Le Meilleur des Mondes, avec bien d&rsquo;autres que mon manque d&rsquo;imagination m&rsquo;a emp\u00each\u00e9 d&rsquo;inventer. &raquo;<\/p>\n<\/p>\n<p><p>Le monde une prison, conclue Hamlet avec Rosencrantz et Guildenstern.<\/p>\n<\/p>\n<p><p>Huxley poursuit cruellement par les banalit\u00e9s d&rsquo;usage sur l&rsquo;\u00e9ducation qui nous rendrait r\u00e9sistant :<\/p>\n<\/p>\n<p><p>&laquo; Si nous voulons \u00e9viter ce genre de tyrannie, il faut que nous commencions sans d\u00e9lai notre \u00e9ducation et celle de nos enfants pour nous rendre aptes \u00e0 \u00eatre libres et \u00e0 nous gouverner nous-m\u00eames. &raquo;<\/p>\n<\/p>\n<p><p>Cette \u00e9ducation (cf. la chasse aux fake news) peut ais\u00e9ment \u00eatre recycl\u00e9e en ce que l&rsquo;on sait !<\/p>\n<\/p>\n<p><p>Il rappelle ce truisme :<\/p>\n<\/p>\n<p><p>&laquo; Les effets d&rsquo;une propagande mensong\u00e8re et pernicieuse ne peuvent \u00eatre neutralis\u00e9s que par une solide pr\u00e9paration \u00e0 l&rsquo;art d&rsquo;analyser ses m\u00e9thodes et de percer \u00e0 jour ses sophismes. &raquo;<\/p>\n<\/p>\n<p><p>Huxley rappelle \u00e0 temps que<strong> personne ne veut de contre-propagande<\/strong> !<\/p>\n<\/p>\n<p><p>&laquo; Et pourtant, nulle part on n&rsquo;enseigne aux enfants une m\u00e9thode syst\u00e9matique pour faire le d\u00e9part entre le vrai et le faux, une affirmation sens\u00e9e et une autre qui ne l&rsquo;est pas. Pourquoi? Parce que leurs a&icirc;n\u00e9s, m\u00eame dans les pays d\u00e9mocratiques, ne veulent pas qu&rsquo;ils re\u00e7oivent ce genre d&rsquo;instruction. Dans ce contexte, <strong>la br\u00e8ve et triste histoire de l&rsquo;Institute for Propaganda Analysis est terriblement r\u00e9v\u00e9latrice. Il avait \u00e9t\u00e9 fond\u00e9 en 1937, alors que la propagande nazie faisait le plus de bruit et de ravages, par Mr. Filene, philanthrope de la Nouvelle-Angleterre<\/strong>. Sous ses auspices, on pratiqua la dissection des m\u00e9thodes de propagande non rationnelle et l&rsquo;on pr\u00e9para plusieurs textes pour l&rsquo;instruction des lyc\u00e9ens et des \u00e9tudiants. Puis vint la guerre, une guerre totale, sur tous les fronts, celui des id\u00e9es au moins autant que celui des corps. <strong>Alors que tous les gouvernements alli\u00e9s se lan\u00e7aient dans \u00ab\u00a0la guerre psychologique\u00a0\u00bb, cette insistance sur la n\u00e9cessit\u00e9 de diss\u00e9quer la propagande sembla quelque peu d\u00e9pourvue de tact. L&rsquo;Institut fut ferm\u00e9 en 1941. &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Huxley rappelle les raisons de cette timidit\u00e9 :<\/p>\n<\/p>\n<p><p>&laquo;<strong> L&rsquo;examen trop critique par trop de citoyens moyens de ce que disent leurs pasteurs et ma&icirc;tres pourrait s&rsquo;av\u00e9rer profond\u00e9ment subversif<\/strong>. Dans sa forme actuelle, l&rsquo;ordre social d\u00e9pend, pour continuer d&rsquo;exister, de l&rsquo;acceptation, sans trop de questions embarrassantes, de la propagande mise en circulation par les autorit\u00e9s et de celle qui est consacr\u00e9e par les traditions locales. &raquo;<\/p>\n<\/p>\n<p><p>Dans son maigre \u00e9nonc\u00e9 des solutions (il n&rsquo;en a pas), Huxley \u00e9voque alors la prison sans barreau (<em>the painless concentration camp<\/em>, expression mise en doute par certains pro-syst\u00e8mes !) :<\/p>\n<\/p>\n<p><p>&laquo;<strong> Il est parfaitement possible qu&rsquo;un homme soit hors de prison sans \u00eatre libre, \u00e0 l&rsquo;abri de toute contrainte mat\u00e9rielle et pourtant captif psychologiquement, oblig\u00e9 de penser, de sentir et d&rsquo;agir comme le veulent les repr\u00e9sentants de l&rsquo;Etat ou de quelque int\u00e9r\u00eat priv\u00e9 \u00e0 l&rsquo;int\u00e9rieur de la nation. &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Huxley recommande de prot\u00e9ger les lieux publics et la t\u00e9l\u00e9vision.<strong> Or on ne peut prot\u00e9ger les lieux publics et la t\u00e9l\u00e9vision qui ne sont l\u00e0 que pour vendre et pour puer : il faut donc les \u00e9viter. Si ton &oelig;il t&rsquo;est objet de tentation&hellip;<\/strong><\/p>\n<\/p>\n<p><p>Il note justement que &laquo; les formes lib\u00e9rales serviront simplement \u00e0 masquer et \u00e0 enjoliver un fond situ\u00e9 aux antipodes du lib\u00e9ralisme &raquo;, et que le futur n&rsquo;est gu\u00e8re plus joyeux que le pr\u00e9sent de Bernays : &laquo; Entre-temps, l&rsquo;oligarchie au pouvoir et son \u00e9lite hautement qualifi\u00e9e de soldats, de policiers, de fabricants de pens\u00e9e, de manipulateurs mentaux m\u00e8nera tout et tout le monde comme bon lui semblera. &raquo;<\/p>\n<\/p>\n<p><p>Sur notre futur monopolistique, Huxley ne se fait gu\u00e8re d&rsquo;illusions (qui s&rsquo;en fait encore ?) :<\/p>\n<\/p>\n<p><p>&laquo; Mais c&rsquo;est un fait historique aujourd&rsquo;hui que les moyens de production sont rapidement centralis\u00e9s et monopolis\u00e9s par les Grosses Affaires et les Gros Gouvernements. Par cons\u00e9quent, si vous avez foi en la d\u00e9mocratie, prenez des mesures pour distribuer les biens aussi largement que possible. &raquo;<\/p>\n<\/p>\n<p><p>Huxley, beaucoup moins m\u00e9chant que ce que pensent pas mal d&rsquo;antisyst\u00e8mes, propose une solution de <em>r\u00e9volution m\u00e9di\u00e9vale<\/em> digne de Chesterton et Belloc :<\/p>\n<\/p>\n<p><p>&laquo; Par cons\u00e9quent, si vous souhaitez \u00e9viter l&rsquo;appauvrissement spirituel des individus et de soci\u00e9t\u00e9s enti\u00e8res, <strong>quittez les grands centres et faites revivre les petites agglom\u00e9rations rurales, ou encore humanisez la ville en cr\u00e9ant \u00e0 l&rsquo;int\u00e9rieur du r\u00e9seau de son organisation m\u00e9canique, les \u00e9quivalents urbains des petits centres ruraux<\/strong> o&ugrave; les individus peuvent se rencontrer et coop\u00e9rer en qualit\u00e9 de personnalit\u00e9s compl\u00e8tes, et non pas comme de simples incarnations de fonctions sp\u00e9cialis\u00e9es. &raquo;<\/p>\n<\/p>\n<p><p>Mais rien n&rsquo;y fait (on est \u00e0 l&rsquo;\u00e9poque du g\u00e9nial Mumford) :<\/p>\n<\/p>\n<p><p>&laquo; Nous savons que, pour la plupart de nos semblables, la vie dans une gigantesque ville moderne est anonyme, atomique, au-dessous du niveau humain, n\u00e9anmoins les villes deviennent de plus en plus d\u00e9mesur\u00e9es et le mode de vie urbano-industriel demeure inchang\u00e9. &raquo;<\/p>\n<\/p>\n<p><p>Huxley, qui finit par citer Dosto\u00efevski et son grand inquisiteur, ne se fait gu\u00e8re d&rsquo;illusions, sondages \u00e0 l&rsquo;appui :<\/p>\n<\/p>\n<p><p>&laquo; Aux U.S.A. &#8211; et l&rsquo;Am\u00e9rique est l&rsquo;image proph\u00e9tique de ce que sera le reste du monde urbano-industriel dans quelques ann\u00e9es d&rsquo;ici &#8211; des sondages r\u00e9cents de l&rsquo;opinion publique ont r\u00e9v\u00e9l\u00e9 que<strong> la majorit\u00e9 des adolescents au-dessous de vingt ans, les votants de demain, ne croient pas aux institutions d\u00e9mocratiques, ne voient pas d&rsquo;inconv\u00e9nient \u00e0 la censure des id\u00e9es impopulaires, ne jugent pas possible le gouvernement du peuple par le peuple et s&rsquo;estimeraient parfaitement satisfaits d&rsquo;\u00eatre gouvern\u00e9s d&rsquo;en haut par une oligarchie d&rsquo;experts assortis<\/strong>, s&rsquo;ils pouvaient continuer \u00e0 vivre dans les conditions auxquelles une p\u00e9riode de grande prosp\u00e9rit\u00e9 les a habitu\u00e9s. &raquo;<\/p>\n<\/p>\n<p><p>Les jeunes sont soumis, les ados sont pires que les autres, comme je l&rsquo;ai constat\u00e9 dans ma jeunesse et comme  le montrera le succ\u00e8s mondial de culture sexe, drogue, rock. Huxley :<\/p>\n<\/p>\n<p><p>&laquo; <strong>Que tant de jeunes spectateurs bien nourris de la t\u00e9l\u00e9vision, dans la plus puissante d\u00e9mocratie du monde, soient si totalement indiff\u00e9rents \u00e0 l&rsquo;id\u00e9e de se gouverner eux-m\u00eames<\/strong>, s&rsquo;int\u00e9ressent si peu \u00e0 la libert\u00e9 d&rsquo;esprit et au droit d&rsquo;opposition est navrant, mais assez peu surprenant. &raquo;<\/p>\n<\/p>\n<p><p>Il \u00e9voque les oiseaux (La Bo\u00e9tie \u00e9voquait les chiens) &hellip;<\/p>\n<\/p>\n<p><p>&laquo; Tout oiseau qui a appris \u00e0 gratter une bonne pitance d&rsquo;insectes et de vers sans \u00eatre oblig\u00e9 de se servir de ses ailes renonce bien vite au privil\u00e8ge du vol et reste d\u00e9finitivement \u00e0 terre. &raquo;<\/p>\n<\/p>\n<p><p>La suite est lyrique !<\/p>\n<\/p>\n<p><p>&laquo; <strong>Le cri de &laquo; Donnez-moi la t\u00e9l\u00e9vision et des saucisses chaudes, mais ne m&rsquo;assommez pas avec les responsabilit\u00e9s de l&rsquo;ind\u00e9pendance &raquo;, fera peut-\u00eatre place, dans des circonstances diff\u00e9rentes \u00e0 celui de &laquo; La libert\u00e9 ou la mort &raquo;<\/strong>.<\/p>\n<\/p>\n<p><p>Et le ma&icirc;tre de conclure :<\/p>\n<\/p>\n<p><p>&laquo; Il semble qu&rsquo;il n&rsquo;y ait aucune raison valable pour qu&rsquo;une dictature parfaitement scientifique soit jamais renvers\u00e9e. &raquo;<\/p>\n<\/p>\n<p><p>Demandez \u00e0 Zuckerberg, \u00e0 la NSA et \u00e0 Monsanto ce qu&rsquo;ils en pensent.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Sources compl\u00e9mentaires<\/h3>\n<\/p>\n<p><p>Huxley &ndash; Le meilleur des mondes ; retour au meilleur des mondes (1957), sur archive.org<\/p>\n<\/p>\n<p><p>Nicolas Bonnal &ndash; Comment les peuples sont devenus jetables ; comment les Fran\u00e7ais sont morts ; la culture comme arme de destruction massive (Amazon.fr)<\/p>\n<\/p>\n<p><p>Umberto Eco &ndash; Vers un nouveau moyen \u00e2ge (1972)<\/p>\n<\/p>\n<p><p>Bertrand de Jouvenel &ndash; Du Pouvoir (Pluriel)<\/p>\n<\/p>\n<p><p>Vince Packard &ndash; Hidden persuaders<\/p>\n<\/p>\n<p><p>Armand Mattelart &ndash; Histoire de l&rsquo;utopie plan\u00e9taire (la D\u00e9couverte)<\/p>\n<\/p>\n<p><p>Chesterton &ndash; What I saw in America (Gutenberg.org)<\/p>\n<\/p>\n<p><p>Shakespeare &ndash; Mesure pour mesure ; Hamlet ; La temp\u00eate (inlibroveritas.net)<\/p>\n<\/p>\n<p><p>La Bo\u00e9tie &ndash; Sur la servitude volontaire (Wikisource)<\/p>\n<\/p>\n<p><p>Tocqueville &ndash; De la d\u00e9mocratie en Am\u00e9rique (classiques.Uqac.ca)<\/p>\n<\/p>\n<p><p>Debord &ndash; Commentaires<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e9o-totalitarisme : Huxley fait le point en 1957 Nota : ce texte et long et n&ucirc;ment r\u00e9f\u00e9renc\u00e9. Il appara&icirc;tra pessimiste \u00e0 certains. On est en 1957. Sputnik fait r\u00eaver les plus conditionn\u00e9s, mais Aldous Huxley rappelle : &laquo; En 1931, alors que j&rsquo;\u00e9crivais Le Meilleur des Mondes, j&rsquo;\u00e9tais convaincu que le temps ne pressait pas&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[15275,16169,8851],"class_list":["post-77756","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-aldous","tag-huxley","tag-totalitarisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77756"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77756\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}