{"id":77767,"date":"2018-02-10T05:54:09","date_gmt":"2018-02-10T05:54:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/10\/jean-luc-melenchon-et-la-tyrannie-liberale\/"},"modified":"2018-02-10T05:54:09","modified_gmt":"2018-02-10T05:54:09","slug":"jean-luc-melenchon-et-la-tyrannie-liberale","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/10\/jean-luc-melenchon-et-la-tyrannie-liberale\/","title":{"rendered":"Jean-Luc M\u00e9lenchon et la tyrannie lib\u00e9rale"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Jean-Luc M\u00e9lenchon et la tyrannie lib\u00e9rale<\/h2>\n<\/p>\n<p><p>&laquo; Nous pensons que la libert\u00e9 c&rsquo;est son exercice. &raquo;<\/p>\n<\/p>\n<p><p>On ne peut que regretter que Jean-Luc M\u00e9lenchon n&rsquo;ait pas \u00e9t\u00e9 pr\u00e9sent au second tour face \u00e0 Macron, en lieu et place de la nullit\u00e9 Marine conseill\u00e9e par le clan Philippot. Mais le FN aura jusqu&rsquo;au bout \u00e9t\u00e9 l&rsquo;alli\u00e9 du pouvoir et des socialistes, en parfait idiot utile depuis quarante ans. On se doute qu&rsquo;il sera d\u00e9congel\u00e9 par le pouvoir et ses sbires pour les prochaines \u00e9lections.<\/p>\n<\/p>\n<p><p>Restons sur M\u00e9lenchon. Face \u00e0 un as pareil, Macron aurait eu du mal \u00e0 s&rsquo;en sortir. Au lieu que l\u00e0 il est en train de nous \u00e9trangler avec le soutien dictatorial de tous les m\u00e9dias et l&rsquo;indiff\u00e9rence d&rsquo;une opinion distraite, h\u00e9b\u00e9t\u00e9e (disait Baudrillard). Je cite des extraits du dernier texte de M\u00e9lenchon, bon par sa qualit\u00e9 philosophique, humaine et \u00e9conomique ;  quant au lib\u00e9ralisme, on sait que dans son jusqu&rsquo;auboutisme il revient toujours \u00e0 un fascisme en pire ; car au moins le fascisme se r\u00e9clame du peuple alors que le lib\u00e9ralisme ne se r\u00e9clame que de son oligarchie aux commandes.<\/p>\n<\/p>\n<p><p>Certes, comme dit Debord, avec son d\u00e9lire ethnique, son culte du sang et du chef <em>le fascisme est trop co&ucirc;teux<\/em>. Alors &laquo; on &raquo; imposa le syst\u00e8me TINA des cerb\u00e8res Thatcher-Merkel-Schauble-Macron : &laquo; il n&rsquo;y pas d&rsquo;alternative. &raquo;<\/p>\n<\/p>\n<p><p>En un mot, Jean-Luc M\u00e9lenchon rappelle la situation ubuesque et scandaleuse de la France actuelle :<\/p>\n<\/p>\n<p><p>&laquo; En France, 32 milliardaires poss\u00e8dent autant que 27 millions de personnes.&raquo;<\/p>\n<\/p>\n<p><p>Et il y en a qui se moquent encore du tiers-monde !<\/p>\n<\/p>\n<p><p>On cite le reste de l&rsquo;extrait :<\/p>\n<\/p>\n<p><p>&laquo; En bout de course, notre \u00e9quation fonctionne. Les recettes des lib\u00e9raux aboutissent \u00e0 des soci\u00e9t\u00e9s tr\u00e8s in\u00e9galitaires o&ugrave; les forts imposent leur int\u00e9r\u00eat particulier aux faibles. En 2017, 82% des richesses produites dans le monde ont \u00e9t\u00e9 capt\u00e9es par le 1% plus riche de la population. En France, 32 milliardaires poss\u00e8dent autant que 27 millions de personnes. Le maintien d&rsquo;un ordre aussi in\u00e9galitaire n\u00e9cessite un contr\u00f4le social toujours plus accru sur ceux en bas de l&rsquo;\u00e9chelle. &raquo;<\/p>\n<\/p>\n<p><p>On ne r\u00e9p\u00e9tera jamais assez que les pauvres ont mieux v\u00e9cu au moyen \u00e2ge qu&rsquo;aux si\u00e8cles lib\u00e9raux auxquels Bruxelles et la mondialisation forc\u00e9e et forcen\u00e9e nous ram\u00e8nent. Pierre Bourdieu ne nous trompait pas quand il nous disait que le syst\u00e8me n\u00e9olib\u00e9ral r\u00eavait d&rsquo;une restauration. Et la chute de l&rsquo;URSS (voyez mon texte) acc\u00e9l\u00e9ra ce retour du refoul\u00e9.<\/p>\n<\/p>\n<p><p>Macron n&rsquo;est pas l\u00e0 pour nous lib\u00e9rer mais pour surveiller :<\/p>\n<\/p>\n<p><p> &laquo; Les mois qui passent ne laissent voir qu&rsquo;une r\u00e9alit\u00e9 au grand jour : <strong>le lib\u00e9ralisme \u00e9conomique n&rsquo;accroit pas la libert\u00e9. Il ne le peut pas. Il la brime. Il ne peut faire autrement.<\/strong> Sur le sujet, la racine est profonde. Mais le contexte donne une violence sp\u00e9ciale \u00e0 ce code g\u00e9n\u00e9tique. Les &laquo; lib\u00e9raux &raquo; agissent comme si la libert\u00e9 n&rsquo;avait d&rsquo;espace qu&rsquo;en dehors de l&rsquo;application des r\u00e8gles toujours trop &laquo; rigides &raquo; pas assez &laquo; flexibles &raquo; et cadenassant toujours les \u00e9nergies qu&rsquo;il faut donc d&rsquo;urgence &laquo; lib\u00e9rer &raquo; de ce carcan. &raquo;<\/p>\n<\/p>\n<p><p>JLM ajoute sur la fin du code du travail :<\/p>\n<\/p>\n<p><p>&laquo; Le code du travail \u00e9tablissait un ensemble de protections pour les individus, contre le travail pr\u00e9caire et mal pay\u00e9. Sans celles-ci, ils seront m\u00e9caniquement davantage expos\u00e9s aux contingences \u00e9conomiques, aux exigences de rentabilit\u00e9 selon les fluctuations impr\u00e9visible du march\u00e9. Ils y seront astreints. Ils seront moins autonomes, donc moins libres.<strong> Quelle est la libert\u00e9 de celui ou celle qui ne sait pas s&rsquo;il aura encore du travail dans un mois ? <\/strong>De celui ou celle dont la seule pr\u00e9occupation est de savoir comment subvenir aux besoins \u00e9l\u00e9mentaires de sa famille avec sa petite paye et son compte dans le rouge le 15 du mois ? &raquo;<\/p>\n<\/p>\n<p><p>Sur la &laquo; dette immonde &raquo; et la soumission \u00e9tatique, JLM remarque :<\/p>\n<\/p>\n<p><p>&laquo; La d\u00e9pense publique qui en est la cons\u00e9quence est donc son ennemi. <strong>&Agrave; cela s&rsquo;ajoutent les cha&icirc;nes de la dette publique. Son paiement doit passer au-dessus de toute autre consid\u00e9ration. <\/strong>En effet les lib\u00e9raux y voient le juste usage de son \u00e9pargne et de sa propri\u00e9t\u00e9 priv\u00e9e, un droit sacr\u00e9 inali\u00e9nable qu&rsquo;ils placent au sommet de la hi\u00e9rarchie des normes. <strong>Naturellement, ce discours est surtout \u00e0 usage de propagande et d&rsquo;habillage de la dictature de l&rsquo;argent. <\/strong>Dans les faits, &laquo; l&rsquo;\u00e9pargne des investisseurs &raquo; adore les placements dans les dettes d&rsquo;&Eacute;tat car seul l&rsquo;&Eacute;tat ne dispara&icirc;t jamais. Les investisseurs adorent les commandes d&rsquo;&Eacute;tat au secteur priv\u00e9 car seul l&rsquo;&Eacute;tat est un acheteur surpuissant et que seule la commande de l&rsquo;&Eacute;tat offre de la visibilit\u00e9 \u00e0 moyen et long terme. &raquo;<\/p>\n<\/p>\n<p><p>Le lib\u00e9ralisme mettra fin comme en Am\u00e9rique \u00e0 la sant\u00e9 et \u00e0 la libert\u00e9 \u00e9ducative :<\/p>\n<\/p>\n<p><p>&laquo; Ainsi dans le domaine de la sant\u00e9. La d\u00e9t\u00e9rioration de l&rsquo;h\u00f4pital public, <strong>les d\u00e9remboursements par la s\u00e9curit\u00e9 sociale conduisent un nombre croissant \u00e0 renoncer \u00e0 des soins pour des raisons financi\u00e8res : entre un quart et un tiers des fran\u00e7ais. Le d\u00e9ni du droit \u00e0 la sant\u00e9 <\/strong>est \u00e0 coup s&ucirc;r une diminution de la libert\u00e9 individuelle \u00e0 proportion des incapacit\u00e9s que la maladie non soign\u00e9e occasionne temporairement ou d\u00e9finitivement. Le m\u00eame m\u00e9canisme se produit dans l&rsquo;\u00e9ducation. <strong>L&rsquo;incessante croisade contre la d\u00e9pense publique a conduit \u00e0 une p\u00e9nurie de places dans nos universit\u00e9s. <\/strong>Davantage de jeunes veulent acc\u00e9der \u00e0 des \u00e9tudes sup\u00e9rieures. L&rsquo;int\u00e9r\u00eat g\u00e9n\u00e9ral serait qu&rsquo;ils puissent le faire. Car cela \u00e9l\u00e8ve le niveau de qualification et donc celui de la production. Mais les universit\u00e9s ont atteint leur capacit\u00e9 maximum. Comme solution, avec l&rsquo;objectif de cr\u00e9er un march\u00e9 du savoir et donc la raret\u00e9 et la concurrence des producteurs de dipl\u00f4mes, raret\u00e9 sans laquelle il n&rsquo;y a pas de march\u00e9,<strong> le gouvernement met fin \u00e0 la libert\u00e9 de choisir ses \u00e9tudes.<\/strong> Pourtant, choisir ses \u00e9tudes, c&rsquo;est choisir sa vie. C&rsquo;est une libert\u00e9 fondamentale que le lib\u00e9ralisme retire aux jeunes gens. &raquo;<\/p>\n<\/p>\n<p><p>Une conclusion logique s&rsquo;impose :<\/p>\n<\/p>\n<p><p>&laquo; La libert\u00e9 des individus est donc est mise en quarantaine pour leur bien. &raquo;<\/p>\n<\/p>\n<p><p>Quant \u00e0 l&rsquo;Europe elle est remise \u00e0 sa place ici :<\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;\u00e9quation lib\u00e9ralisme \u00e9gale moins de libert\u00e9 s&rsquo;applique non seulement aux individus mais aussi aux peuples. Le principe de souverainet\u00e9 populaire signifie la libert\u00e9 des peuples \u00e0 choisir leur destin. Notre r\u00e9gime politique et institutionnel s&rsquo;\u00e9loigne de plus en plus de ce principe. <strong>L&rsquo;Union europ\u00e9enne nous impose des choix dont nous ne voulons pas. Le vote du peuple sur le trait\u00e9 constitutionnel de 2005 a \u00e9t\u00e9 bafou\u00e9,<\/strong> les trait\u00e9s budg\u00e9taires conditionnent les politiques publiques, la gestion de la monnaie est hors de port\u00e9e des peuples. <strong>La pratique du pouvoir d&rsquo;Emmanuel Macron constitue un nouveau raidissement autoritaire. Il suit le mot d&rsquo;ordre de Junker : il n&rsquo;y a pas de d\u00e9mocratie hors des trait\u00e9s europ\u00e9ens.<\/strong> Au niveau europ\u00e9en, il en revient au condominium franco-allemand, camisole de force vou\u00e9e aux int\u00e9r\u00eats des rentiers allemands. &raquo;<\/p>\n<\/p>\n<p><p>Heureusement, <em>Jean-Luc M\u00e9lenchon ne cesse de baisser dans les sondages<\/em>, p\u00e9rorent en se rassurant les garde-chiourmes des m\u00e9dias.<\/p>\n<\/p>\n<p><p>JLM rappelle le r\u00f4le des m\u00e9dias oligarchiques aux ordres : &laquo; Arrive la r\u00e9forme institutionnelle. Une ample campagne de d\u00e9nigrement des parlementaires a d\u00e9j\u00e0 \u00e9t\u00e9 copieusement relay\u00e9e par les m\u00e9dias de l&rsquo;oligarchie fran\u00e7aise. Elle pr\u00e9pare l&rsquo;opinion. &raquo;<\/p>\n<\/p>\n<p><p>Il r\u00e9sume :<\/p>\n<\/p>\n<p><p>&laquo; Une bonne formule dit &laquo; la libert\u00e9 de chacun s&rsquo;arr\u00eate l\u00e0 o&ugrave; commence celle des autres &raquo;. La libert\u00e9 des lib\u00e9raux rend impossible la libert\u00e9 de chacun puisque chacun est alors plac\u00e9 sous l&#8217;empire des plus forts. &raquo;<\/p>\n<\/p>\n<p><p>La libert\u00e9 du pauvre sera combattue \u00e0 coups d&rsquo;euthanasie, de luttes sanguinaires contre les ennemis imp\u00e9riaux, de frappe anti-fake news, sans oublier la flexibilit\u00e9 sociale et l&rsquo;ouverture strat\u00e9gique-humanitaire des fronti\u00e8res&hellip;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jean-Luc M\u00e9lenchon et la tyrannie lib\u00e9rale &laquo; Nous pensons que la libert\u00e9 c&rsquo;est son exercice. &raquo; On ne peut que regretter que Jean-Luc M\u00e9lenchon n&rsquo;ait pas \u00e9t\u00e9 pr\u00e9sent au second tour face \u00e0 Macron, en lieu et place de la nullit\u00e9 Marine conseill\u00e9e par le clan Philippot. Mais le FN aura jusqu&rsquo;au bout \u00e9t\u00e9 l&rsquo;alli\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[398,2687,6553,12986,2711,2617,8315,3314,11402,7833],"class_list":["post-77767","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-europe","tag-france","tag-inegalite","tag-insoumise","tag-le","tag-macron","tag-melenchon","tag-pen","tag-super-riches","tag-tina"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77767"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77767\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}