{"id":77781,"date":"2018-02-17T06:05:25","date_gmt":"2018-02-17T06:05:25","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/17\/genie-de-la-conscience-apocalyptique-en-amerique\/"},"modified":"2018-02-17T06:05:25","modified_gmt":"2018-02-17T06:05:25","slug":"genie-de-la-conscience-apocalyptique-en-amerique","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/17\/genie-de-la-conscience-apocalyptique-en-amerique\/","title":{"rendered":"G\u00e9nie de la conscience apocalyptique en Am\u00e9rique"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">G\u00e9nie de la conscience apocalyptique en Am\u00e9rique<\/h2>\n<\/p>\n<p><p>&laquo; Ces Am\u00e9ricains, ils ont quand m\u00eame Tex Avery. &raquo;<\/p>\n<\/p>\n<p><p>Plus je vieillis, plus je me rends compte que les am\u00e9ricains ont mieux per\u00e7u que nous le contenu apocalyptique de notre\/leur civilisation. Apr\u00e8s tout Schuon est all\u00e9 mourir l\u00e0-bas, avec les indiens sioux de Walsh et de John Ford.<\/p>\n<\/p>\n<p><p>Voyez les Tex Avery dans cette perspective (la t\u00e9l\u00e9 du futur, l&rsquo;automobile du futur&hellip;), et relisez bien s&ucirc;r Edgar Poe ou Lovecraft. Et l\u00e0 je me mets enfin \u00e0 lire au bout de quarante ans de cin\u00e9philie le livre qui inspira le meilleur film <em>am\u00e9ricain <\/em>de Welles, la splendeur des Amberson.<\/p>\n<\/p>\n<p><p>Le g\u00e9nie am\u00e9ricain face au viol automobile du monde ? On connait Mumford et sa fabuleuse <em>histoire de la cit\u00e9 dans l&rsquo;histoire<\/em> qui explique dans sa partie eschatologique que la bagnole a recouvert  &laquo; la plan\u00e8te de d\u00e9tritus urbains &raquo;. Cette partie est reprise par Debord dans la Soci\u00e9t\u00e9 du Spectacle, &sect;174. Nous on a l&rsquo;anar Mirbeau que sa grosse voiture et sa balade en Europe rendent euphorique. Debord encore : &laquo; Le moment pr\u00e9sent est d\u00e9j\u00e0 celui de l&rsquo;autodestruction du milieu urbain. &raquo;<\/p>\n<\/p>\n<p><p>Et le m\u00e9dium Orson Welles, qui vient de d\u00e9crire l&rsquo;entropie m\u00e9diatique am\u00e9ricaine (&laquo; le capital devenu image &raquo;)  adapte Tarkington, un \u00e9crivain ignor\u00e9 dans nos contr\u00e9es, mais cit\u00e9 par Mumford et m\u00eame par Carroll Quigley (p. 1236 de <em>Tragedy and hope<\/em>).<\/p>\n<\/p>\n<p><p>Orson Welles adapte, il est fid\u00e8le au texte, qui vaut bien son Boorstin. Le moment est magique dans le film : la grande transformation de la ville, li\u00e9e \u00e0 l&rsquo;automobile.<\/p>\n<\/p>\n<p><p>Debord encore :<\/p>\n<\/p>\n<p><p>&laquo; La dictature de l&rsquo;automobile, produit-pilote de la premi\u00e8re phase de l&rsquo;abondance marchande, s&rsquo;est inscrite dans le terrain avec la domination de l&rsquo;autoroute, qui disloque les centres anciens et commande une dispersion toujours plus pouss\u00e9e. &raquo;<\/p>\n<\/p>\n<p><p>La discussion sur l&rsquo;automobile dans le livre de Tarkington maintenant. Attention, cette discussion a  lieu dans le film, elle est fondamentale, et la critique de cin\u00e9ma toujours inculte s&rsquo;en est royalement foutue, se contenant du <em>road movie<\/em> pour festival \u00e0 quatre kopecks (il me semble pourtant que la voiture ne porte pas chance dans la <em>Psychose <\/em>d&rsquo;Hitchcock ou le week-end de Godard pas plus que dans le monde de Jacques Tati, mais bon)&hellip;<\/p>\n<\/p>\n<p><p>Tarkington :<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Well, well!\u00a0\u00bb the Major laughed. \u00ab\u00a0You have enough faith in miracles, Eugene&mdash;granting that<strong> trolleys and bicycles and automobiles are miracles. So you think they&rsquo;re to change the face of the land, do you<\/strong>?\u00a0\u00bb<\/p>\n<\/p>\n<p><p>\u00ab\u00a0They&rsquo;re already doing it, Major; and it can&rsquo;t be stopped. Automobiles&mdash;\u00a0\u00bb<\/p>\n<\/p>\n<p><p>At this point he was interrupted. George was the interrupter. He had said nothing since entering the dining room, but now he spoke in a loud and peremptory voice, using the tone of one in authority who checks idle prattle and settles a matter forever.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>George, l&rsquo;insupportable George qui repr\u00e9sente le pass\u00e9, le r\u00e9actionnaire (le personnage qui a dialectiquement raison est toujours &laquo; idiot &raquo; ou antipathique comme je l&rsquo;ai indiqu\u00e9 dans mon livre sur <em>Dosto\u00efevski et la modernit\u00e9 occidentale)<\/em>, mart\u00e8le :<\/p>\n<\/p>\n<p><p>\u00ab\u00a0Automobiles are a useless nuisance,\u00a0\u00bb he said.<\/p>\n<\/p>\n<p><p><strong>\u00ab\u00a0I said all automobiles were a nuisance,\u00a0\u00bb<\/strong> George answered, repeating not only the words but the tone in which he had uttered them. And he added,<strong> \u00ab\u00a0They&rsquo;ll never amount to anything but a nuisance. They had no business to be invented.\u00a0\u00bb<\/strong><\/p>\n<\/p>\n<p><p>Eug\u00e8ne Morgan, l&rsquo;inventeur d&rsquo;automobiles, lui donne alors raison :<\/p>\n<\/p>\n<p><p>&laquo; Again there was a silence, while the Major stared at his grandson, aghast. But Eugene began to laugh cheerfully.<\/p>\n<\/p>\n<p><p>\u00ab\u00a0I&rsquo;m not sure he&rsquo;s wrong about automobiles,\u00a0\u00bb he said.<strong> \u00ab\u00a0With all their speed forward they may be a step backward in civilization&mdash;that is, in spiritual civilization. It may be that they will not add to the beauty of the world, nor to the life of men&rsquo;s souls. I am not sure. But automobiles have come, and they bring a greater change in our life than most of us suspect. They are here, and almost all outward things are going to be different because of what they bring. They are going to alter war, and they are going to alter peace. I think men&rsquo;s minds are going to be changed in subtle ways because of automobile<\/strong>s; just how, though, I could hardly guess. But you can&rsquo;t have the immense outward changes that they will cause without some inward ones, and it may be that George is right, and that <strong>the spiritual alteration will be bad for us.<\/strong> Perhaps, ten or twenty years from now, if we can see the inward change in men by that time, <strong>I shouldn&rsquo;t be able to defend the gasoline engine, but would have to agree with him that automobiles &lsquo;had no business to be invented.&rsquo;<\/strong><\/p>\n<\/p>\n<p><p>Je rappelle Guy Debord :<\/p>\n<\/p>\n<p><p>&laquo; En m\u00eame temps, les moments de r\u00e9organisation inachev\u00e9e du tissu urbain se polarisent passag\u00e8rement autour des &laquo; usines de distribution &raquo; que sont les supermarkets g\u00e9ants \u00e9difi\u00e9s en terrain nu, sur un socle de parking ; et ces temples de la consommation pr\u00e9cipit\u00e9e sont eux-m\u00eames en fuite dans le mouvement centrifuge, qui les repousse \u00e0 mesure qu&rsquo;ils deviennent \u00e0 leur tour des centres secondaires surcharg\u00e9s, parce qu&rsquo;ils ont amen\u00e9 une recomposition partielle de l&rsquo;agglom\u00e9ration.<strong> Mais l&rsquo;organisation technique de la consommation n&rsquo;est qu&rsquo;au premier plan de la dissolution g\u00e9n\u00e9rale qui a conduit ainsi la ville \u00e0 se consommer elle-m\u00eame <\/strong>(La soci\u00e9t\u00e9 du spectacle, &sect;174). &raquo;<\/p>\n<\/p>\n<p><p>Debord pensa justement que l&rsquo;automobile comme la t\u00e9l\u00e9 ont aid\u00e9 le pouvoir totalement ; et notre bonne vieille informatique destin\u00e9e \u00e0 tout contr\u00f4ler et confisquer ?<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est pas termin\u00e9. J&rsquo;ai \u00e9voqu\u00e9 le probl\u00e8me migratoire am\u00e9ricain, quand les Europ\u00e9ens affam\u00e9s, pas &laquo; les gens du tiers-monde &raquo;, d\u00e9rangeaient la civilisation US, celle de Poe, Emerson, Washington Irving. Edward Ross, Madison Grant, Lothrop Stoddard d\u00e9noncent cette invasion, mais aussi notre si ignor\u00e9 Francis Scott Fitzgerald dans Gatsby qui rebaptise Stoddard Godard !<\/p>\n<\/p>\n<p><p>Mais revenons-en aux magnifiques Amberson ; Orson Welles cite ce livre dans son film admirable, pas tout \u00e9videmment. Il \u00e9vite de citer les pages o&ugrave; l&rsquo;on en veut au progr\u00e8s (c&rsquo;est le sujet de ce film et surtout de <strong>ce livre gu\u00e9nonien<\/strong>). Or Tarkington est aussi dur pour les progr\u00e8s industriels et les nouveaux migrants que mettons Lovecraft (lisez en ligne pour rire sa nouvelle <em>The Street<\/em>),  Edgar Poe (<em>Monos et Una<\/em>, <em>Colloque avec une momie<\/em>), Madison Grant (<em>the passing of a great race<\/em>), Lothrop Stoddard, sans oublier Scott Fitzgerald. Pour ces sujets voyez notre livre sur Trump qui recense la traditionnelle et vaine r\u00e9sistance aux invasions migratoires en Am\u00e9rique (d\u00e9couvrez <em>Alien nation <\/em>de Peter Brimelow, jamais traduit bien s&ucirc;r, ou m\u00eame les livres du fr\u00e8re de Paul Auster.<\/p>\n<\/p>\n<p><p>Extraits de la splendeur des Ambersons :<\/p>\n<\/p>\n<p><p>\u00ab\u00a0<strong>But the great change was in the citizenry itself.<\/strong> What was left of the patriotic old-stock generation that had fought the Civil War, and subsequently controlled politics, had become venerable and was little heeded. <strong>The descendants of the pioneers and early settlers were merging into the new crowd, becoming part of it, little to be distinguished from it<\/strong>. What happened to Boston and to Broadway happened in degree to the Midland city; <strong>the old stock became less and less typical,<\/strong> and of the grown people who called the place home, <strong>less than a third had been born in it. There was a German quarter; there was a Jewish quarter; there was a negro quarter<\/strong>&mdash;square miles of it&mdash;called \u00ab\u00a0Bucktown\u00a0\u00bb; there were many Irish neighbourhoods; and there were large settlements of<strong> Italians, and of Hungarians, and of Rumanians, and of Serbians and other Balkan people<\/strong>s.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Le capitalisme n&rsquo;\u00e9tait pas l\u00e0 pour prot\u00e9ger le peuple anglo-am\u00e9ricain. Il \u00e9tait l\u00e0 pour faire du pognon en Am\u00e9rique puis il vampirisa tout le reste du monde ; qu&rsquo;on relise dans cet esprit le Manifeste du parti communiste ou le chapitre VI du Capital I du grand Karl !<\/p>\n<\/p>\n<p><p>L&rsquo;industrie se d\u00e9veloppe avec son lot de migrations (une gr\u00e8ve, un appel d&rsquo;immigr\u00e9s pour casser les salaires, comme dit Ed Ross), de pollution et d&rsquo;endettement (d&rsquo;o&ugrave; les crises \u00e9conomiques \u00e0 r\u00e9p\u00e9tition).<\/p>\n<\/p>\n<p><p><strong>\u00ab\u00a0Prosperity\u00a0\u00bb meant good credit at the bank, black lungs, and housewives&rsquo; Purgatory.<\/strong> The women fought the dirt all they could; but if they let the air into their houses they let in the dirt. <strong>It shortened their lives, and kept them from the happiness of ever seeing anything whit<\/strong>e. And thus, as the city grew, the time came when Lucy, after a hard struggle, had to give up her blue-and-white curtains and her white walls. Indoors, she put everything into dull gray and brown, and outside had the little house painted the dark green nearest to black. Then she knew, of course, that everything was as dirty as ever, but was a little less distressed because it no longer looked so dirty as it was.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Philippe Grasset \u00e9voque dans son &oelig;uvre cette Am\u00e9rique royale et bien s&ucirc;r fran\u00e7aise condamn\u00e9e comme nous tous (\u00e2mes y compris &ndash; voyez Tocqueville) par notre eschatologie d\u00e9mocratique. Tiens un peu d&rsquo;Edgar Poe dont la conscience \u00e9cologiste est ici royale (en doutait-on encore ?) :<\/p>\n<\/p>\n<p><p>&laquo; <strong>Cependant d&rsquo;innombrables cit\u00e9s s&rsquo;\u00e9lev\u00e8rent, \u00e9normes et fumeuses. Les vertes feuilles se recroquevill\u00e8rent devant la chaude haleine des fourneaux. Le beau visage de la Nature fut d\u00e9form\u00e9 comme par les ravages de quelque d\u00e9go&ucirc;tante maladie<\/strong>. &raquo;<\/p>\n<\/p>\n<p><p>Il m&rsquo;est amusant de penser, et douloureux, que le grand cin\u00e9ma am\u00e9ricain, comme la grande litt\u00e9rature am\u00e9ricaine, a \u00e9t\u00e9<strong> aussi sensible que Schuon ou Gu\u00e9non<\/strong>, bien plus que nos romanciers par cons\u00e9quent, \u00e0 l&rsquo;exception surnaturelle de C\u00e9line qui prit conscience du monde moderne en Am\u00e9rique. Il est clair aussi qu&rsquo;il faudrait r\u00e9-enseigner l&rsquo;histoire et la culture de ce grand pays soumis aux distorsions de notre \u00e9ducation moderne&hellip;<\/p>\n<\/p>\n<p><p>Mais bon&hellip;<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Sources<\/h2>\n<\/p>\n<p><p>Howard Philip Lovecraft &ndash; The Street, complete works<\/p>\n<\/p>\n<p><p>Booth Tarkington &ndash; Magnificent Ambersons (Gutenberg.org)<\/p>\n<\/p>\n<p><p>Nicolas Bonnal &ndash; C\u00e9line, le pacifiste enrag\u00e9 ; Trump, de la r\u00e9bellion \u00e0 la trahison (Amazon.fr)<\/p>\n<\/p>\n<p><p>Edgar Poe &ndash; Nouvelles histoires extraordinaires, colloque entre Monos et Una, traduction Charles Baudelaire (ebooksgratuits.com)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>G\u00e9nie de la conscience apocalyptique en Am\u00e9rique &laquo; Ces Am\u00e9ricains, ils ont quand m\u00eame Tex Avery. &raquo; Plus je vieillis, plus je me rends compte que les am\u00e9ricains ont mieux per\u00e7u que nous le contenu apocalyptique de notre\/leur civilisation. Apr\u00e8s tout Schuon est all\u00e9 mourir l\u00e0-bas, avec les indiens sioux de Walsh et de John&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[14142,2604,7548,18111,18113,3902,18112,14132],"class_list":["post-77781","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-amberson","tag-des","tag-eschatologie","tag-lovecraft","tag-orson","tag-poe","tag-splendeur","tag-welles"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77781"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77781\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}