{"id":77792,"date":"2018-02-23T17:45:44","date_gmt":"2018-02-23T17:45:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/23\/deux-su-57-sur-les-plate-bandes-du-pentagone-1\/"},"modified":"2018-02-23T17:45:44","modified_gmt":"2018-02-23T17:45:44","slug":"deux-su-57-sur-les-plate-bandes-du-pentagone-1","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/02\/23\/deux-su-57-sur-les-plate-bandes-du-pentagone-1\/","title":{"rendered":"Deux Su-57 sur les plate-bandes du Pentagone"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Deux Su-57 sur les plate-bandes du Pentagone<\/h2>\n<\/p>\n<p><p>Depuis mercredi et la publication de photos et de vid\u00e9os montrant l&rsquo;arriv\u00e9e de nouveaux avions russes \u00e0 la base de Khmeimim, on se demande si l&rsquo;on n&rsquo;y trouve pas deux Su-57, le nouveau chasseur de combat dit \u00ab\u00a0de 5<sup>\u00e8me<\/sup> g\u00e9n\u00e9ration\u00a0\u00bb, aussi furtif mais plus man&oelig;uvrable que le F-22, avec diverses autres appr\u00e9ciations du m\u00eame genre. Donc, mercredi sont arriv\u00e9s \u00e0 la base de Su-57 arrivant \u00e0 la base de Khmeimim, en Syrie, au moins 4 Su-25 d&rsquo;appui tactique rapproch\u00e9, 4 Su-35 d&rsquo;interdiction a\u00e9rienne et un A-50U de surveillance et de contr\u00f4le de l&rsquo;espace a\u00e9rien ; et puis, deux autres avions, d&rsquo;abord myst\u00e9rieux, bient\u00f4t largement quoiqu&rsquo;encore hypoth\u00e9tiquement identifi\u00e9s comme des Su-57. <em>Spoutnik <\/em>a enqu\u00eat\u00e9 et nous donne un texte assez fourni, sans r\u00e9v\u00e9lation extraordinaire, ni m\u00eame ordinaire d&rsquo;ailleurs ; par contre, le texte lui-m\u00eame, ainsi que l&rsquo;une ou l&rsquo;autre intervention, apparaissent comme une confirmation officieuse mais ferme de la pr\u00e9sence de ces deux avions, deux chasseur de combat Su-57 en phase de mise en condition op\u00e9rationnelle.<\/p>\n<\/p>\n<p><p>Le Pentagone n&rsquo;aime pas qu&rsquo;on vienne pi\u00e9tiner sur ses plate-bandes, surtout qu&rsquo;il lui en reste asez peu qui soient sa propri\u00e9t\u00e9 exclusive. \u00ab\u00a0Ses plates-bandes\u00a0\u00bb, c&rsquo;est d&rsquo;une part le privil\u00e8ge de d\u00e9ployer des avions de combat tr\u00e8s avanc\u00e9s sur les th\u00e9\u00e2tres d&rsquo;op\u00e9ration o&ugrave; leur pr\u00e9sence est peu sinon pas du tout requise, simplement pour en faire l&rsquo;exposition et la promotion et afficher la puissance de l&rsquo;instigateur ; \u00ab\u00a0ses plates-bandes\u00a0\u00bb d&rsquo;autres part, c&rsquo;est la cat\u00e9gorie m\u00eame de cet avion de combat, dit \u00ab\u00a0de 5<sup>\u00e8me<\/sup>-g\u00e9n\u00e9ration\u00a0\u00bb, dont les USA se jugeaient quasiment comme les seuls autoris\u00e9s par d\u00e9cret divin \u00e0 disposer avant encore quelques d\u00e9cennies. Que le Su-57 pr\u00e9tende infirmer ce rangement imp\u00e9ratif du monde, et en Syrie encore, voil\u00e0 des motifs d&rsquo;irritation, &ndash; au Pentagone comme au Ciel.<\/p>\n<\/p>\n<p><p><em>Business Insider <\/em>nous fait bien rire, ce qui est excellent pour la sant\u00e9, en qualifiant la d\u00e9cision ruse de d\u00e9ploiement de &laquo; <em><a href=\"http:\/\/www.businessinsider.com\/russia-looks-to-have-deployed-su-57-to-syria-posing-problem-for-f-22-2018-2\">d\u00e9cision cynique<\/a><\/em> &raquo; dont le but serait, &ndash; tenez-vous bien, vertueux lecteurs, &ndash; de &laquo; <em>stimuler les ventes d&rsquo;armes russes et \u00e0 obtenir des informations pr\u00e9cieuses sur la puissance a\u00e9rienne am\u00e9ricaine avanc\u00e9e dans la r\u00e9gion<\/em> &raquo;. Il faut \u00eatre Russe, c&rsquo;est-\u00e0-dire barbare, immoral et ill\u00e9gal, honte de la civilisation, inculte et pr\u00eat \u00e0 pour le business, prompt \u00e0 la f\u00e9lonie de l&rsquo;espionnage, pour avoir de tels comportements. Le Pentagone ne s&rsquo;en est pas encore remis&#8230;<\/p>\n<\/p>\n<p><p>Les Russes continuent donc, pour ce qui est des usages et des pr\u00e9rogatives, \u00e0 se conduire en Syrie d&rsquo;une part, dans le domaine des armements d&rsquo;autre part, selon des m&oelig;urs et des usages que d\u00e9sapprouve \u00ab\u00a0D.C.-la-folle\u00a0\u00bb parce qu&rsquo;elle ne voit rien qui autorise une telle transgression : transgenre oui, transgression non&#8230; Pout un peu, \u00e9ditos et parlementaires s&rsquo;\u00e9criraient, furieux, paniqu\u00e9s et sur le pied de guerre conform\u00e9ment au climat d&rsquo;hyst\u00e9rie antirussiste qui r\u00e8gne\u00e0 D.C. : \u00ab\u00a0Ces Su-57, c&rsquo;est encore un coup des Russes !\u00a0\u00bb. Que peut-on r\u00e9pliquer \u00e0 cela, nousqui d\u00e9non\u00e7ons sans cesse leurs <em>FakeNews<\/em> ?<\/p>\n<\/p>\n<p><p>Voici donc une adaptation du texte de <em>Sputnik.News<\/em> de ce 23 f\u00e9vrier 2018, rendu quasiment comme s&rsquo;il s&rsquo;agissait de <em>Spoutnik-<\/em>fran\u00e7ais pour l&rsquo;occasion.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Mais que feraient donc 2 Su-57 en Syrie ?<\/h2>\n<\/p>\n<p><p>L&rsquo;apparition de deux chasseurs Su-57 sur la base a\u00e9rienne syrienne de Hmeimim, qui n&rsquo;a pas encore \u00e9t\u00e9 confirm\u00e9e par le minist\u00e8re russe de la D\u00e9fense, suscite n\u00e9anmoins nombre de commentaires des journalistes sp\u00e9cialis\u00e9s dans les questions de d\u00e9fense observateurs de la d\u00e9fense, d&rsquo;analystes et d&rsquo;experts. Mais que pourraient donc faire ces avions en Srie ? Leur d\u00e9ploiement est-il strictement li\u00e9 aux tests ou est-il \u00e9galement destin\u00e9 \u00e0 envoyer un message politique? <em>Spoutnik<\/em> enqu\u00eate.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">D\u00e9tails de d\u00e9ploiement<\/h3>\n<\/p>\n<p><p>Jusqu&rsquo;\u00e0 pr\u00e9sent, le Kremlin et le minist\u00e8re de la D\u00e9fense sont rest\u00e9s muets au sujet d&rsquo;une mission \u00e9ventuelle des Su-57 en Syrie. Mais une simple observation des nouvelles li\u00e9es au Su-57 ces derniers mois semble indiquer que le d\u00e9ploiement est tr\u00e8s probable.<\/p>\n<\/p>\n<p><p>Le 8 f\u00e9vrier, le vice-ministre de la D\u00e9fense, Yuri Borisov <a href=\"https:\/\/sputniknews.com\/military\/201802081061467502-su57-to-start-combat-trials\/\">annon\u00e7ait<\/a> que l&rsquo;arm\u00e9e \u00e9tait pr\u00eate \u00e0 acheter un lot de Su-57 pour les essais de combat, la premi\u00e8re \u00e9tape de ce processus \u00e9tant d\u00e9j\u00e0 achev\u00e9e. Deux semaines auparavant, Boris Obnosov, PDG de Tactical Missiles Corporation, une soci\u00e9t\u00e9 engag\u00e9e dans le d\u00e9veloppement d&rsquo;armes pour cette plate-forme de combat, a confirm\u00e9 que le Su-57 avait commenc\u00e9 les essais en vol avec ses nouvelles armes avanc\u00e9es. Sugg\u00e9rant que les r\u00e9sultats de ce travail seraient appr\u00e9ci\u00e9s &laquo; <em>dans un futur imminent<\/em> &raquo;, Obnosov a ajout\u00e9 que les tirs d&rsquo;essai par le Su-57 des nouvelles armes d\u00e9velopp\u00e9es par les bureaux d&rsquo;\u00e9tudes de Raduga et de Vimpel commenceraient &laquo; <em>bient\u00f4t<\/em> &raquo;.<\/p>\n<\/p>\n<p><p>Vladimir Gutenov, d\u00e9put\u00e9 de la Douma en charge d&rsquo;une commission qui a dans ses comp\u00e9tences l&rsquo;industrie de la d\u00e9fense russe, a d\u00e9clar\u00e9 \u00e0 Spoutnik que s&rsquo;il ne pouvait pas confirmer cat\u00e9goriquement le d\u00e9ploiement des Su-57 en Syrie, il a &laquo; <em>accueilli avec un chaleureux int\u00e9r\u00eat<\/em> &raquo; les informations. Selon le parlementaire, les avions &laquo; <em>doivent \u00eatre test\u00e9s dans des conditions de combat, dans des conditions de possible affrontement<\/em> [avec l&rsquo;ennemi] &raquo;. En outre, a-t-il dit, la pr\u00e9sence des Su-57 enverra sans aucun doute un message politique \u00e0 contenu dissuasif &laquo; <em>pour les a\u00e9ronefs des pays voisins qui volent p\u00e9riodiquement<\/em> &raquo; dans le ciel de ce pays du Moyen-Orient sans y \u00eatre invit\u00e9s.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Ce que disent les experts russes<\/h3>\n<\/p>\n<p><p>Les experts militaires russes ont propos\u00e9 une myriade de raisons possibles pour le d\u00e9ploiement des Su-57 en Syrie.<\/p>\n<\/p>\n<p><p>Par exemple, Andrei Frolov, r\u00e9dacteur en chef d&rsquo;Arms Export, une publication militaire russe, <a href=\"https:\/\/www.rbc.ru\/politics\/22\/02\/2018\/5a8eb0c99a7947e094fcf5be\">a d\u00e9clar\u00e9<\/a> \u00e0 RBC que le d\u00e9ploiement aiderait \u00e0 faire de la publicit\u00e9 pour les avions, en particulier sur le march\u00e9 indien, pour soutenir le programme russo-indien Soukhoi \/ HAL dit-FGFA (Programme de Chasseur de Combat de la 5<sup>\u00e8me<\/sup> G\u00e9n\u00e9ration). &laquo; <em>Lockheed Martin est actif sur le march\u00e9 indien, et il y a \u00e9galement des difficult\u00e9s avec l&rsquo;Inde concernant le projet FGFA. Apr\u00e8s le lancement public du Su-57 l&rsquo;ann\u00e9e derni\u00e8re, son d\u00e9ploiement en Syrie viserait \u00e0 convaincre Indiens que le FGFA est un vrai projet, qui a un prototype qui non seulement vole, mais qui est capable de fonctionner dans une zone de guerre<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Nikolai Antoshkin, colonel (retrait\u00e9), v\u00e9t\u00e9ran sovi\u00e9tique et russe de l&rsquo;aviation militaire, commandant et sp\u00e9cialiste de l&rsquo;entra&icirc;nement au combat, <a href=\"http:\/\/svpressa.ru\/war21\/article\/193803\/\">explique<\/a> que le premier escadron de production de Su-57 devant bient\u00f4t \u00eatre d\u00e9ploy\u00e9 au centre de formation au combat de Lipetsk, &laquo; <em>les combattants, comme pour toute autre arme, sont test\u00e9s principalement au combat : donc, l&rsquo;envoi du Su-57 en Syrie est une solution naturelle<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Soulignant que le Su-57 est un excellent outil qui &laquo; <em>serait utile<\/em> &raquo; dans le cas de &laquo; <em>provocations contre nos forces en Syrie<\/em> &raquo;, Antoshkin a \u00e9galement comment\u00e9 les rumeurs circulant en ligne selon lesquelles l&rsquo;US Air Force aurait suspendu les vols de son F-22 Raptor de la Syrie en raison de l&rsquo;apparition des avions russes dans le pays. D&rsquo;une part, rappelle Antoshkin, le Su-57 est \u00e9quip\u00e9 de jets de vecteurs de pouss\u00e9e 3D, contrairement aux jets de vecteur de pouss\u00e9e 2D du F-22, ce qui signifie une man&oelig;uvrabilit\u00e9 plus \u00e9lev\u00e9e pour l&rsquo;avion russe. &laquo; <em>De plus, ces moteurs permettent \u00e0 notre chasseur d&rsquo;atteindre une vitesse de Mach 2 sans syst\u00e8me de postcombustion. Avec son syst\u00e8me embarqu\u00e9e Belka, le Su-57 peut d\u00e9tecter des avions \u00ab\u00a0furtifs\u00a0\u00bb et suivre simultan\u00e9ment plus de 10 cibles. Enfin, l&rsquo;avion dispos d&rsquo;un excellent ensemble de guerre \u00e9lectronique, et des contre-mesures \u00e9lectroniques tr\u00e8s efficaces contre les syst\u00e8mes de guidage des missiles ennemis<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>En ce qui concerne les armes embarqu\u00e9es, l&rsquo;observateur a rappel\u00e9 que &laquo; <em>le Su-57 dispose de deux grands compartiments d&rsquo;armes internes, qui occupent pratiquement toute la longueur utile de l&rsquo;avion. Chaque compartiment peut transporter jusqu&rsquo;\u00e0 quatre missiles air-air K-77M <\/em>&raquo;, qui ont une port\u00e9e de pr\u00e8s de 200 km et qui constituent l&rsquo;\u00e9quivalent approximatif du missile air-air avanc\u00e9 AIM-120 \u00e0 moyenne port\u00e9e des &Eacute;tats-Unis.<\/p>\n<\/p>\n<p><p>En fin de compte, Antoshkin a soulign\u00e9 que si le d\u00e9ploiement de seulement deux avions ne suffisait pas \u00e0 fournir \u00e0 la Russie un avantage militaire \u00e9crasant sur le th\u00e9\u00e2tre syrien, les adversaires potentiels de la Russie y r\u00e9fl\u00e9chiraient \u00e0 deux fois avant d&rsquo;intervenir &laquo; <em>Je pense que cela donnera \u00e0 nos concurrents g\u00e9opolitiques un argument de poids de plus, de se poser la question de savoir \u00ab\u00a0si le jeu en vaut la chandelle\u00a0\u00bb, d&rsquo;intervenir contre la Russie et les forces russes<\/em>&#8230;. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les observateurs militaires occidentaux r\u00e9agissent<\/h3>\n<\/p>\n<p><p>Les <a href=\"https:\/\/sputniknews.com\/middleeast\/201802221061888802-su-57-footage-pak-fa-syria\/\">photos et les vid\u00e9os<\/a> mis en ligne mercred et montrant ce qui pourrait \u00eatre les deux Su-57 arrivant \u00e0 la base de Hmemeim, en Syrie, avec 4 Su-35, 4 Su-25 et un A-50U de surveillance et de contr\u00f4le de l&rsquo;espace a\u00e9rien a certainement retenu l&rsquo;attention du Pentagone. A Washington, le porte-parole du DoD <a href=\"https:\/\/sputniknews.com\/us\/201802231061916495-pentagon-see-russia-fifth-gen-fighter-threat\/\">s&rsquo;est plaint<\/a> que le d\u00e9ploiement \u00e9tait une indication que la Russie ne respectait pas son &laquo; <em>retrait de force annonc\u00e9 <\/em>&raquo;.<\/p>\n<\/p>\n<p><p>De nombreux observateurs militaires occidentaux se sont montr\u00e9s critiques. Business Insider  a cit\u00e9 des experts affirmant que le d\u00e9ploiement \u00e9tait un &laquo; <em><a href=\"http:\/\/www.businessinsider.com\/russia-looks-to-have-deployed-su-57-to-syria-posing-problem-for-f-22-2018-2\">d\u00e9cision cynique<\/a><\/em> &raquo; visant \u00e0 stimuler les ventes d&rsquo;armes russes et \u00e0 obtenir des informations pr\u00e9cieuses sur la puissance a\u00e9rienne am\u00e9ricaine avanc\u00e9e dans la r\u00e9gion. Popular Mechanic a \u00e9t\u00e9 un peu plus mod\u00e9r\u00e9, <a href=\"https:\/\/www.popularmechanics.com\/military\/a18659251\/russia-su-57-syria-f-22\/\">mettant en \u00e9vidence<\/a> que le d\u00e9ploiement donnera \u00e0 l&rsquo;arm\u00e9e russe l&rsquo;occasion &laquo; <em>d&rsquo;apprendre beaucoup sur la fa\u00e7on dont le chasseur fonctionne dans des conditions moins id\u00e9ales que celles des essais, \u00e0 quel point ses capteurs sont capables de rep\u00e9rer des cibles dans l&rsquo;air et sur le terrain, et combien il est difficile de maintenir des avions de cette sorte \u00e0 des milliers de miles de la m\u00e8re Russie<\/em>. &raquo; Cette publication a aussi insist\u00e9 sur les risques du d\u00e9ploiement, sugg\u00e9rant que les Su-57 pourraient susciter des affrontements avec les F-22 dans l&rsquo;espace a\u00e9rien contr\u00f4l\u00e9 par les Etats-Unis en Syrie et qu&rsquo;ils seraient sous le feu d&rsquo;attaques au ou de drone tant qu&rsquo;ils seraient stationn\u00e9s \u00e0 Hmeimim.<\/p>\n<\/p>\n<p><p>Dave Majumdar, de National Interest, a fait un peu plus d&rsquo;efforts en allant parler \u00e0 un expert militaire russe, Vasily Kashin du Centre pour les Etudes G\u00e9n\u00e9rales Internationales  de Moscou. Selon Kashin, le d\u00e9ploiement des Su-57 revient \u00e0 &laquo; <em>tester<\/em> [l&rsquo;avion] <em><a href=\"http:\/\/nationalinterest.org\/blog\/the-buzz\/russias-su-57-stealth-fighter-syria-%E2%80%9C-testing-actual-war-24611\">dans un environnement de guerre r\u00e9elle<\/a> <\/em>&raquo;, une mesure permettant de pr\u00e9parer une production de l&rsquo;avion en conditions op\u00e9rationnelles.<\/p>\n<\/p>\n<p><p>L&rsquo;avis de Majumdar lui-m\u00eame est que le d\u00e9ploiement aidera probablement l&rsquo;arm\u00e9e russe \u00e0 acqu\u00e9rir de pr\u00e9cieuses donn\u00e9es op\u00e9rationnelles et de performance sur l&rsquo;avionique avanc\u00e9e du Su-57, y compris son radar \u00e0 balayage \u00e9lectronique actif et ses syst\u00e8mes ELINT. M\u00eame &laquo; <em>des missions de combat limit\u00e9es<\/em> &raquo; sont une possibilit\u00e9, \u00e9crit-il.<\/p>\n<\/p>\n<p><h4><em>Spoutnik<\/em><\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deux Su-57 sur les plate-bandes du Pentagone Depuis mercredi et la publication de photos et de vid\u00e9os montrant l&rsquo;arriv\u00e9e de nouveaux avions russes \u00e0 la base de Khmeimim, on se demande si l&rsquo;on n&rsquo;y trouve pas deux Su-57, le nouveau chasseur de combat dit \u00ab\u00a0de 5\u00e8me g\u00e9n\u00e9ration\u00a0\u00bb, aussi furtif mais plus man&oelig;uvrable que le F-22,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2631,249,18140,18023,2622,18141,14251,3411,18139,3867,3519],"class_list":["post-77792","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-de","tag-f-22","tag-futilite","tag-hmeimim","tag-la","tag-majundar","tag-soukhoi","tag-stealth","tag-su-57","tag-syrie","tag-technologie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77792"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77792\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}