{"id":77825,"date":"2018-03-14T06:02:56","date_gmt":"2018-03-14T06:02:56","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/03\/14\/tourbillon-crisique-45\/"},"modified":"2018-03-14T06:02:56","modified_gmt":"2018-03-14T06:02:56","slug":"tourbillon-crisique-45","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/03\/14\/tourbillon-crisique-45\/","title":{"rendered":"Tourbillon crisique-45"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Tourbillon crisique-45<\/h2>\n<\/p>\n<p><p>14 mars 2018 &ndash; La vitesse de l&#8217;embrasement surprend toujours par son acc\u00e9l\u00e9ration chaque fois plus forte. Cette fois, cette acc\u00e9l\u00e9ration tourbillonnante, au c&oelig;ur de <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-tourbillon-crisique\">ce tourbillon crisique<\/a> dont nul ne sait o&ugrave; il m\u00e8ne sinon dans un Trou Noir au-del\u00e0 d&rsquo;o&ugrave; on ne sait rien, <strong>passe tout ce qu&rsquo;on a connu<\/strong>.<\/p>\n<\/p>\n<p><p>Trois situations crisiques permanentes ont <strong>brusquement et parall\u00e8lement \u00e9clat\u00e9 dans un nouveau paroxysme, en une seule journ\u00e9e<\/strong>. Elles para&icirc;traient volontiers coordonn\u00e9es \u00e0 ceux qui y voient le lien des manigances d&rsquo;une organisation rationnelle ; elles nous paraissent beaucoup plus simplement mais irr\u00e9sistiblement jaillir conjointement \u00e0 partir d&rsquo;une tension extr\u00eame que des forces sup\u00e9rieures font peser depuis si longtemps, et en constant <em>crescendo<\/em>, sur la situation g\u00e9n\u00e9rale en \u00e9tablissant ainsi un lien d&rsquo;encha&icirc;nement psychologique. &laquo; <em>Je ne vois aucun terme normal qui puisse satisfaire \u00e0 la description de tout cela <\/em>&raquo;, observe Lavrov.<\/p>\n<\/p>\n<p><p>Il y a la \u00ab\u00a0crise du poison\u00a0\u00bb\/UK (l&rsquo;espion Skripal), qui voit la mont\u00e9e aux extr\u00eames ; hyst\u00e9rique et incontr\u00f4lable du c\u00f4t\u00e9 UK avec ultimatum \u00e0 la Russie, et cette fois avec la Russie proche de ne plus freiner. La Syrie est toujours brandie comme au bord d&rsquo;un nouveau paroxysme, cette fois avec une possibilit\u00e9 d&rsquo;attaque US et l&rsquo;annonce officielle d&rsquo;une riposte russe proche d&rsquo;\u00eatre assur\u00e9e dans ce cas. La \u00ab\u00a0crise du chaos\u00a0\u00bb courante \u00e0 Washington, \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, conna&icirc;t un nouveau paroxysme avec le limogeage de Tillerson puis d&rsquo;un de ses adjoints du d\u00e9partement d&rsquo;&Eacute;tat, et des remous importants dans l&rsquo;\u00e9quipe de s\u00e9curit\u00e9 nationale du Pr\u00e9sident ; elle porte la marque d&rsquo;<strong>un Trump toujours insaisissable, toujours impr\u00e9visible<\/strong>, et cette fois en phase <strong>de <em>turbo-<\/em>activisme<\/strong>&#8230; A Washington m\u00eame, aujiurd&rsquo;hui, dans cette s\u00e9quence, t<strong>out peut se passer<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>Malgr\u00e9 l&rsquo;importance provocatrice qu&rsquo;on accorderait aux agitations d\u00e9mentes de nos directions dont l&rsquo;existence semble se nourrir voracement \u00e0 la rh\u00e9torique la plus extr\u00eame, <strong>l&rsquo;essentielle nouveaut\u00e9 est le durcissement russe<\/strong>. &laquo; <em>On n&rsquo;adresse pas un ultimatum de 24 heures <strong>\u00e0 une puissance nucl\u00e9aire<\/strong><\/em> &raquo;, a dit hier la porte-parole du minist\u00e8re des affaires \u00e9trang\u00e8res, Maria Zakharova. <em><a href=\"http:\/\/theduran.com\/lavrov-simply-dont-normal-terms-left-describe\/\">TheDuran.com<\/a><\/em> observe : &laquo; <strong><em>Il s&rsquo;agit seulement d&rsquo;une sp\u00e9culation (erron\u00e9e, esp\u00e9rons-le !!)<\/em><\/strong><em>, mais en se r\u00e9f\u00e9rant aux discours de Poutine du 1<sup>er<\/sup> mars sur l&rsquo;\u00e9tat de la nation, avec les tests op\u00e9rationnels du missile Kinzhal et les r\u00e9v\u00e9lations faites par le pr\u00e9sident Poutine sur d&rsquo;autres syst\u00e8mes d&rsquo;arme tr\u00e8s avanc\u00e9s, autant qu&rsquo;\u00e0 la situation britannique et d\u00e9sormais qu&rsquo;\u00e0 la situation syrienne, il appara&icirc;t que <strong>la Russie, bien qu&rsquo;elle veuille \u00e9viter l&rsquo;affrontement, semble admettre qu&rsquo;il devient in\u00e9vitable<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<\/blockquote>\n<p><p>La v\u00e9ritable inconnue de cette phase crisique exceptionnelle de paroxysme <strong>reste tout de m\u00eame la situation washingtonienne<\/strong>. Les menaces US contre la Syrie viennent de Haley, \u00e0 l&rsquo;ONU, et l&rsquo;on ne sait \u00e0 qui elle ob\u00e9issait (\u00e0 Tillerson le partant ? A Pompeo qui le remplace ? A Trump lui-m\u00eame ? Ou bien \u00e0 personne, agissant de son propre chef ?). Sur la \u00ab\u00a0crise du poison\u00a0\u00bb\/UK, la position US est incertaine et varie selon la source consult\u00e9e, certains allant jusqu&rsquo;\u00e0 dire que le renvoi de Tillerson a \u00e9t\u00e9 brusqu\u00e9 et rendu tr\u00e8s brutal \u00e0 cause de son soutien affirm\u00e9 \u00e0 100% \u00e0 la th\u00e8se et \u00e0 l&rsquo;action britanniques.<\/p>\n<\/p>\n<p><p>Cette phase dramatique et tragique est \u00e0 l&rsquo;image de Trump, l&rsquo;homme qui a impos\u00e9 cette descente dans le chaos et dans les situations de tous les risques, d&rsquo;affrontement et d&rsquo;effondrement, &ndash; <strong>elle est insaisissable et impr\u00e9visible<\/strong>. Elle est <strong>une r\u00e9p\u00e9tition ou bien elle est la r\u00e9alisation de l&rsquo;acte final de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me<\/strong>. Plus que jamais \u00e0 l&rsquo;extr\u00eame incandescent de ce processus, <strong>nul ne sait<\/strong> s&rsquo;il s&rsquo;agit d&rsquo;une finalit\u00e9 d&rsquo;une part, <strong>nul ne sait<\/strong> la forme que prendra cette finalit\u00e9 si c&rsquo;est le cas d&rsquo;autre part.<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale et \u00e0 cause de plusieurs \u00e9l\u00e9ments, dont l&rsquo;extr\u00eame m\u00e9diocrit\u00e9 de nombre des acteurs humains n&rsquo;est pas le moindre, nous sommes <strong>dans une situation bien plus grave que lors de la crise des missiles de Cuba de 1962<\/strong>. Bien peu de gens, dans le vaste public du monde, le r\u00e9alisent ; peut-\u00eatre, d&rsquo;ailleurs, dans ce climat d&rsquo;inversion totale de la culture, bien peu de gens, dans le vaste public du monde, savent ce que se passa en octobre 1962&#8230;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tourbillon crisique-45 14 mars 2018 &ndash; La vitesse de l&#8217;embrasement surprend toujours par son acc\u00e9l\u00e9ration chaque fois plus forte. Cette fois, cette acc\u00e9l\u00e9ration tourbillonnante, au c&oelig;ur de ce tourbillon crisique dont nul ne sait o&ugrave; il m\u00e8ne sinon dans un Trou Noir au-del\u00e0 d&rsquo;o&ugrave; on ne sait rien, passe tout ce qu&rsquo;on a connu. Trois&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[7178,3228,4470,13231,2631,2651,2830,7834,916,18175,12669,2639,12642],"class_list":["post-77825","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-7178","tag-crise","tag-cuba","tag-d-c-la-folle","tag-de","tag-du","tag-lavrov","tag-poisson","tag-poutine","tag-skripal","tag-tillerson","tag-trump","tag-zakharova"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77825"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77825\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}