{"id":77846,"date":"2018-03-25T06:06:30","date_gmt":"2018-03-25T06:06:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/03\/25\/alfred-hitchcock-et-la-mere-aux-trousses\/"},"modified":"2018-03-25T06:06:30","modified_gmt":"2018-03-25T06:06:30","slug":"alfred-hitchcock-et-la-mere-aux-trousses","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/03\/25\/alfred-hitchcock-et-la-mere-aux-trousses\/","title":{"rendered":"Alfred Hitchcock et la m\u00e8re aux trousses"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Alfred Hitchcock et la m\u00e8re aux trousses<\/h2>\n<\/p>\n<p><p>Hamlet est-il hitchcockien ? Toujours est-il quand le Hamlet de Laurence Olivier, acteur hitchcockien, s&rsquo;explique avec sa m\u00e8re Gertrude, il lui demande d&rsquo;arr\u00eater de coucher avec son beau-p\u00e8re Claudius. <em>Mother, you have my father much offended&hellip;<\/em> Or dans Psychose Norman tue sa m\u00e8re parce qu&rsquo;elle a un amant.<\/p>\n<\/p>\n<p><p> Dans d&rsquo;autres grands films hitchcockiens la m\u00e8re emp\u00eache le fils de devenir un homme. Dans les encha&icirc;n\u00e9s, la m\u00e8re fait empoisonner tuer sa belle-fille soup\u00e7onn\u00e9e d&rsquo;espionnage. Dans les oiseaux la m\u00e8re ne cesse de vouloir mettre M\u00e9lanie \u00e0 la porte. Les moineaux passent par la chemin\u00e9e au moment o&ugrave; elle d\u00e9clare et surtout r\u00e9p\u00e8te que la possible belle-fille ou rivale devrait rentrer pr\u00e9cipitamment \u00e0 San Francisco ! La question demeure : les oiseaux expriment-ils une rage psychologique, les oiseaux sont-ils une mal\u00e9diction et une punition lanc\u00e9e par une peureuse belle-m\u00e8re contre une belle-fille probable ?<\/p>\n<\/p>\n<p><p>Et si on reparle de psychose, ce chef-d&rsquo;&oelig;uvre in\u00e9puisable qu&rsquo;on red\u00e9couvre \u00e0 chaque vision comme Vertigo et les oiseaux,  on ajoutera que le fils Norman d\u00e9clare que le fils un pi\u00e8tre amant&hellip; pour une m\u00e8re !<\/p>\n<\/p>\n<p><p>J&rsquo;\u00e9voque la condition f\u00e9minine chez Alfred Hitchcock et je trouve ces notes dans le l\u00e9gendaire livre de Donald Spoto, <em>the dark side of genius<\/em> :<\/p>\n<\/p>\n<p><p>&laquo; Hitchcock began to make the mothers&rsquo; figure a personal repository of his anger, guilt, resentment and sad yearning.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>On traduit ? Hitchcock commen\u00e7a \u00e0 faire de la figure de la m\u00e8re le r\u00e9ceptacle  de sa col\u00e8re, de sa culpabilit\u00e9 et de sa tristesse.<\/p>\n<\/p>\n<p><p>La m\u00e8re c&rsquo;est donc l&rsquo;ensemble des pressions psychiques qui vous angoissent et vous g\u00e2chent la vie. Et Mother, c&rsquo;est le ma&icirc;tre-mot alors pour comprendre Hamlet, Norman Bates et bien s&ucirc;r Almodovar et ses l\u00e9gions transsexuelles. Par-del\u00e0 le bien et le m\u00e2le&hellip;<\/p>\n<\/p>\n<p><p>La ma&icirc;tresse-phrase de Spoto concerne <em>Notorious<\/em>, les encha&icirc;n\u00e9s ; oublions le McGuffin de l&rsquo;uranium et du nazisme (ils contr\u00f4lent le cobalt dans le l\u00e9gendaire film <em>Gilda<\/em>) pour nous concentrer sur les deux vrais axes du film : la rivalit\u00e9 mim\u00e9tique pour une m\u00eame femme (Claude Rains aime plus Ingrid Bergman que le manipulateur Cary Grant &ndash; dixit Hitchcock) et la haine belle-m\u00e8re\/bru.<\/p>\n<\/p>\n<p><p>La vieille m\u00e8re nazie craint la solitude \u00e0 venir, hait sa bru et pousse le fils faiblard \u00e0 assassiner sa femme espionne, aussi faible et manipul\u00e9e que lui. Et S\u00e9bastien d&rsquo;ailleurs reproche sa jalousie \u00e0 sa m\u00e8re qui est \u00e0 sa broderie, assise sur un fauteuil comme le cadavre de la m\u00e8re Norman, et g\u00e9nialement film\u00e9e de trois-quarts arri\u00e8re. On a les m\u00eames discussions dans les oiseaux et aussi dans psychose. Et si aucune m\u00e8re n&rsquo;existait, et qu&rsquo;elles ne fussent toutes que ce que dit Spoto ; le r\u00e9ceptacle de l&rsquo;angoisse, de la culpabilit\u00e9 et de la rage humaine ?<\/p>\n<\/p>\n<p><p>Dans l&rsquo;inconnu du nord-express, la m\u00e8re de l&rsquo;assassin Bruno, splendidement jou\u00e9 par Robert Walker peint un tableau monstrueux qui est cens\u00e9 repr\u00e9senter le p\u00e8re s\u00e9v\u00e8re et milliardaire.  On trouve ici un personnage exotique, lacustre qui a mis au monde un monstre auquel il a tout pardonn\u00e9. Ce n&rsquo;est pas la m\u00e8re s\u00e9v\u00e8re de Mitch, c&rsquo;est une mis\u00e9rable et une l\u00e2che pour qui tout ce que fait le ch\u00e9rubin rel\u00e8ve du &laquo; joke &raquo;, de la plaisanterie soci\u00e9tale. Cette m\u00e8re petite-bourgeoise et catholique pense d&rsquo;ailleurs repr\u00e9senter saint Fran\u00e7ois d&rsquo;Assise dans un tableau monstrueux ! Cela nous rappelle les observations effray\u00e9es du ma&icirc;tre du cin\u00e9ma sovi\u00e9tique Andrei Tarkovski en visitant ses galeries d&rsquo;art moderne au Vatican&hellip; C&rsquo;est Huysmans qui parle \u00e0 la fin du dix-neuvi\u00e8me si\u00e8cle de &laquo; l&rsquo;effrayant app\u00e9tit de laideur qui d\u00e9shonore l&rsquo;Eglise &raquo;.<\/p>\n<\/p>\n<p><p>Soit la Mother complexe son gentil fils, soit elle soutient le rejeton meurtrier. Dans la mort aux trousses, Hitchcock d\u00e9peint un  fils publiquement humili\u00e9 par sa m\u00e8re joueuse de bridge, et qui ose lui prendre cinquante dollars (toujours pour le bridge) pour lui obtenir des informations \u00e0 la r\u00e9ception du grand h\u00f4tel. Ici reconnaissons avant de dramatiser ou de crier aux phobies que le rapport de Cary Grant \u00e0 sa m\u00e8re est surtout humoristique, d\u00e9cal\u00e9, parodique. Tout l&rsquo;inverse de ce qu&rsquo;il sera dans Frenzy o&ugrave; l&rsquo;assassin joue \u00e0 montrer sa m\u00e8re par la fen\u00eatre de son r\u00e9pugnant appartement.<\/p>\n<\/p>\n<p><p><strong>Chez Hitchcock le surmoi est maternel, pas paternel.<\/strong> M\u00eame la R\u00e9becca d&rsquo;Hitch &ndash; sans compter la gouvernante lesbienne &#8211; est une figure maternelle qui fascine la nouvelle \u00e9pouse et castre le mari-enfant jou\u00e9 par Laurence Olivier, alors Hamlet au cin\u00e9ma (comme on sait Hamlet veut emp\u00eacher sa maman de refaire l&rsquo;amour avec le nouveau p\u00e8re). R\u00e9becca c&rsquo;est la figure d&rsquo;un monde pa\u00efen enfoui p\u00eacheur et lib\u00e9r\u00e9 sexuellement. Une autre mani\u00e8re britannique enracin\u00e9e d&rsquo;exprimer le fameux repaire du ver blanc d\u00e9crit par Bram Stoker et exprim\u00e9 par une Lady ophidienne.<\/p>\n<\/p>\n<p><p>Le combat d&rsquo;Hitchcock n&rsquo;est pas isol\u00e9. Hollywood a exploit\u00e9 alors le th\u00e8me de la r\u00e9volte contre la m\u00e8re. M\u00eame l&rsquo;opus de Ray avec James Dean est ambigu \u00e0 ce sujet : on sent que la bont\u00e9 humanitaire de la m\u00e8re cr\u00e9e un inadapt\u00e9. Rappel d&rsquo;un peu de Nietzsche pour nous aider \u00e0 comprendre le th\u00e8me :<\/p>\n<\/p>\n<p><p>&laquo; I<strong>l y a aujourd&rsquo;hui, presque partout en Europe, une sensibilit\u00e9 et une irritabilit\u00e9 maladives pour la douleur et aussi une intemp\u00e9rance f\u00e2cheuse \u00e0 se plaindre<\/strong>, une f\u00e9minisation qui voudrait se parer de religion et de fatras philosophique, pour se donner plus d&rsquo;\u00e9clat &mdash; il y a un v\u00e9ritable culte de la douleur.&raquo;<\/p>\n<\/p>\n<p><p>Les longues et admirables discussions qui ouvrent les Oiseaux et Psychose (entretiens dans <strong>ce motel<\/strong> dont j&rsquo;ai montr\u00e9 sur mon blog l&rsquo;origine wellesienne &ndash; la soif du mal) posent bien s&ucirc;r le probl\u00e8me maternel. Norman Bates n&rsquo;a pas le droit de vivre \u00e0 cause de Mother. La m\u00e8re dangereuse discute avec M\u00e9lanie pour expliquer le r\u00f4le de son mari d\u00e9funt, et celui de son fils sans qui elle ne sait ce qu&rsquo;elle deviendrait ! C&rsquo;est elle aussi qui envoie M\u00e9lanie chercher les enfants \u00e0 l&rsquo;\u00e9cole, ce qui va pr\u00e9cipiter l&rsquo;attaque sur les ch\u00e9rubins imprudemment sortis de leur abri ! Tout cette sc\u00e8ne semble moins l&rsquo;aveu d&rsquo;une impuissance qu&rsquo;un set-up, un pi\u00e8ge comme on dit pour attraper M\u00e9lanie par les sentiments.<\/p>\n<\/p>\n<p><p>Norman tue et empaille bien les femmes qui lui plaisent, et qui ont sans doute demand\u00e9 au jeune homme de s&rsquo;\u00e9loigner de la m\u00e8re. On sait par Spoto que cette m\u00e8re c&rsquo;est aussi le &laquo; repository &raquo; des col\u00e8res, angoisses et frustrations de la gent masculine non lib\u00e9r\u00e9e, et men\u00e9e \u00e0 la gay attitude explique Almodovar dans <em>los abrazos rotos<\/em> par une m\u00e8re&hellip;divorc\u00e9e. Il explique \u00e0 la s\u00e9duisante fuyarde que les oiseaux empaill\u00e9s ont une<em> dimension passive<\/em> <strong>(I think only birds look well stuffed because they&rsquo;re rather&#8230;  passive, to begin with&#8230; most of them&#8230;)<\/strong><\/p>\n<\/p>\n<p><p>Dans les oiseaux l&rsquo;avocat sarcastique (son sarcasme \u00e9veille l&rsquo;agressivit\u00e9 sexuelle de M\u00e9lanie qui va lui amener des <em>lovebirds<\/em>) montre sa dimension de pauvre h\u00e8re : il vit avec sa m\u00e8re possessive et sa petite s&oelig;ur (la petite Veronica Cartwright qui jouera plus tard dans les sorci\u00e8res d&rsquo;Eastwick la puritaine victime du diable), \u00e0 quelques m\u00e8tres de sa myst\u00e9rieuse ex-fianc\u00e9e qui va servir de confidente et de logeuse \u00e0 la nouvelle \u00e9lue. Le d\u00e9chiqu\u00e8tement final de l&rsquo;h\u00e9ro\u00efne-t\u00eate de linotte par les oiseaux correspond \u00e0 la fois \u00e0 un ch\u00e2timent li\u00e9 \u00e0 la transgression f\u00e9minine (le m\u00e9chant Hitch ch\u00e2tie les voleuses !), \u00e0 la lib\u00e9ration sexuelle, comme dans psychose, et \u00e0 une punition inflig\u00e9e par la m\u00e8re. Ajoutons que pour la m\u00e8re de Mitch le fils g\u00e8re mal la situation et que &laquo; si son p\u00e8re \u00e9tait l\u00e0&hellip; &raquo;. Ce vilain mot est de trop et \u00e9claire Mitch sur la situation psychologique de sa g\u00e9nitrice. Mitch, qui a une bonne trentaine, est du reste sans enfants et sa m\u00e8re semble la grand-m\u00e8re de sa petite s&oelig;ur. P\u00e9rennit\u00e9 du h\u00e9ros hitchcockien sans enfant ou presque&hellip;<\/p>\n<\/p>\n<p><p>L&rsquo;attaque d&rsquo;Hitchcock contre la m\u00e8re est aussi une attaque contre la bourgeoise \u00e2g\u00e9e, poss\u00e9dante, et elle n&rsquo;est pas fortuite. Hitchcock et Bu&ntilde;uel s&rsquo;adoraient&hellip;<\/p>\n<\/p>\n<p><p>Dans l&rsquo;ombre d&rsquo;un doute, son film pr\u00e9f\u00e9r\u00e9, la cible de l&rsquo;assassin jou\u00e9 par Joseph Cotten est la vieille veuve riche. On le relit :<\/p>\n<\/p>\n<p><p>&laquo; Les grandes villes sont remplies de veuves d&rsquo;\u00e2ge m&ucirc;r. Leurs maris ont travaill\u00e9 toute leur vie comme des forcen\u00e9s pour faire fortune, et \u00e0 leur mort ils ont laiss\u00e9 tout leur argent \u00e0 leurs \u00e9pouses stupides. Et qu&rsquo;en font-elles, ces femmes inutiles ? On les voit par milliers dans les meilleurs h\u00f4tels, \u00e0 boire leur argent, \u00e0 manger leur argent, \u00e0 jouer leur argent nuit et jour, empestant leur richesse. Elles sont uniquement fi\u00e8res de leurs bijoux, rien d&rsquo;autre.<\/p>\n<\/p>\n<p><p>Elles sont fan\u00e9es, grasses, avides. [&hellip;] Sont-elles des \u00eatres humains ou des animaux engraiss\u00e9s ? Et qu&rsquo;arrive-t-il \u00e0 un animal quand il devient trop vieux et trop gras ? &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;animal vieux et gras peut devenir fin et lucide, comme la m\u00e8re de Grace Kelly dans la main au collet. Elle pr\u00e9f\u00e9rerait avoir un homme qu&rsquo;un bijou dans son lit ! Mais elle risque de coller aux deux jeunes amants et comme dit Hitch \u00e0 Truffaut, ce sera un final tragique !<\/p>\n<\/p>\n<p><p>Cette inqui\u00e9tude vis-\u00e0-vis de la m\u00e8re se retrouve aussi dans la relation m\u00e8re-fille. On le voit bien dans Marnie et on laisse la parole \u00e0 la docteure Tifenn Brisset :<\/p>\n<\/p>\n<p><p>&laquo; D&rsquo;autres liens montrent la contrainte de l&rsquo;agent, comme les liens familiaux \u00e0 l&rsquo;&oelig;uvre dans Marnie : la jeune femme souffre d&rsquo;importants probl\u00e8mes relationnels avec les hommes mais est totalement d\u00e9vou\u00e9e \u00e0 sa m\u00e8re (Louise Latham), qui ne lui rend pas son amour. &raquo;<\/p>\n<\/p>\n<p><p><strong>Vieille rengaine&hellip; Insistons enfin sur le point essentiel : depuis des d\u00e9cennies on nous bassine avec la figure du p\u00e8re autoritaire de l&rsquo;\u00e9cole de Francfort, figure qu&rsquo;il fallait liquider. Il nous semble important de rappeler que pour le grand cin\u00e9ma cela rel\u00e8ve de la farce : la grande figure aux temps modernes de l&rsquo;Etat-providence c&rsquo;est celle de la m\u00e8re. Ridley Scott s&rsquo;en souvient magnifiquement dans Alien quand l&rsquo;ordinateur tueur est surnomm\u00e9 Mother.<\/strong><\/p>\n<\/p>\n<p><p>Rappelons le prodigieux personnage de Ma dans White Heat de Raoul Walsh. L&rsquo;assassin poss\u00e9d\u00e9 Cody est poss\u00e9d\u00e9 par sa m\u00e8re. Quand il append sa mort (sc\u00e8ne d&rsquo;anthologie comme on dit), il assomme dans le r\u00e9fectoire la moiti\u00e9 des gardiens de la prison ; ici la m\u00e8re devient image de l&rsquo;\u00e2me satanique d&rsquo;un homme. On a cela \u00e0 la fin de psychose, dans une sc\u00e8ne g\u00e9niale et effarante.<\/p>\n<\/p>\n<p><p><strong>La Mother, ce serait la domination terminale de la f\u00e9minit\u00e9 quand il n&rsquo;y a plus d&rsquo;histoire.<\/strong><\/p>\n<\/p>\n<p><p>Un peu de Tocqueville pour nous \u00e9clairer comme \u00e0 son habitude : sur ce devenir maternel, et non paternel, du monde il \u00e9crivait :<\/p>\n<\/p>\n<p><p>&laquo; Au-dessus de ceux-l\u00e0 s&rsquo;\u00e9l\u00e8ve un pouvoir immense et tut\u00e9laire, qui se charge seul d&rsquo;assurer leur jouissance et de veiller sut leur sort. Il est absolu, d\u00e9taill\u00e9, r\u00e9gulier, pr\u00e9voyant et doux. Il ressemblerait \u00e0 la puissance paternelle si, comme elle, il avait pour objet de pr\u00e9parer les hommes \u00e0 l&rsquo;\u00e2ge viril ;<strong> mais il ne cherche, au contraire, qu&rsquo;\u00e0 les fixer irr\u00e9vocablement dans l&rsquo;enfance <\/strong>; il aime que les citoyens se r\u00e9jouissent, pourvu qu&rsquo;ils ne songent qu&rsquo;\u00e0 se r\u00e9jouir. Il travaille volontiers \u00e0 leur bonheur ; mais il veut en \u00eatre l&rsquo;unique agent et le seul arbitre ; il pourvoit \u00e0 leur s\u00e9curit\u00e9, pr\u00e9voit et assure leurs besoins, facilite leurs plaisirs, conduit leurs principales affaires, dirige leur industrie, r\u00e8gle leurs successions, divise leurs h\u00e9ritages,<strong> que ne peut-il leur \u00f4ter enti\u00e8rement le trouble de penser et la peine de vivre ? &raquo;<\/strong><\/p>\n<\/p>\n<p><p>C&rsquo;est le NYT qui r\u00e9cemment faisait l&rsquo;\u00e9loge de ces femmes blanches qui renoncent \u00e0 \u00eatre m\u00e8res pour faire souffler \u00e9cologiquement la plan\u00e8te&hellip; Ah, la MOTHER sans enfants&hellip;<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Sources<\/h2>\n<\/p>\n<p><p>Nicolas Bonnal &ndash; Alfred Hitchcock et la condition f\u00e9minine (Amazon.fr)<\/p>\n<\/p>\n<p><p>Donald Spoto &ndash; The dark side of genius<\/p>\n<\/p>\n<p><p>Tocqueville &ndash; De la d\u00e9mocratie en Am\u00e9rique, II<\/p>\n<\/p>\n<p><p>Tifenn Brisset &ndash; Le cin\u00e9ma d&rsquo;Alfred Hitchcock : une &oelig;uvre du devenir-humain<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alfred Hitchcock et la m\u00e8re aux trousses Hamlet est-il hitchcockien ? Toujours est-il quand le Hamlet de Laurence Olivier, acteur hitchcockien, s&rsquo;explique avec sa m\u00e8re Gertrude, il lui demande d&rsquo;arr\u00eater de coucher avec son beau-p\u00e8re Claudius. Mother, you have my father much offended&hellip; Or dans Psychose Norman tue sa m\u00e8re parce qu&rsquo;elle a un amant.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,2768,18207],"class_list":["post-77846","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-cinema","tag-psycho"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77846"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77846\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}