{"id":77864,"date":"2018-04-05T10:55:05","date_gmt":"2018-04-05T10:55:05","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/04\/05\/tourbillon-crisique-46\/"},"modified":"2018-04-05T10:55:05","modified_gmt":"2018-04-05T10:55:05","slug":"tourbillon-crisique-46","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/04\/05\/tourbillon-crisique-46\/","title":{"rendered":"Tourbillon crisique-46"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Tourbillon crisique-46<\/h2>\n<\/p>\n<p><p>5 avril 2018 &ndash; L&rsquo;h\u00e9g\u00e9monie des &Eacute;tats-Unis d&rsquo;Am\u00e9rique est \u00e0 la fois totale et incontestable, totalitaire et au-dessus de tout argument. Eux seuls agissent avec un z\u00e8le exceptionnel dans le cadre de la seule mission qu&rsquo;il soit d\u00e9sormais possible d&rsquo;ex\u00e9cuter officiellement, la seule qui ait l&rsquo;aval m\u00e9prisant du Syst\u00e8me dont ces m\u00eames &Eacute;tats-Unis d&rsquo;Am\u00e9rique sont <strong>l&rsquo;esclave oblig\u00e9, totalement sous sa d\u00e9pendance<\/strong>. Cette mission, certes, c&rsquo;est <strong>la recherche z\u00e9l\u00e9e, fi\u00e9vreuse, pressante, im-monde et sublime, de l&rsquo;entropisation du monde<\/strong>. Leurs moyens en sont la mesure : \u00e9normes, anarchiques, incroyablement corrupteurs et formidablement gaspill\u00e9s ; leur politique en est l&rsquo;illustration : confuse, absurde, sans aucun sens et dans tous les sens pourvu qu&rsquo;elle brise ; leur communication en est le v\u00e9hicule : simulacre sur simulacre, et m\u00eame simulacre de simulacre, o&ugrave; les mensonges finissent par ne plus signifier que le vide d&rsquo;un cercle vicieux d\u00e9barrass\u00e9 de son contenu, et par cons\u00e9quent se dissolvant par absence de contenu. (Leur simulacre-mensonge comme banc d&rsquo;essai de l&rsquo;entropisation du monde.) <\/p>\n<\/p>\n<p><p>Mais il reste et il y a la direction politique, <strong>humaine-trop-humaine<\/strong>, absolument corrompue et d\u00e9structur\u00e9e qui, brusquement, dans une inversion d&rsquo;elle-m\u00eame inattendue m\u00eame pour elle-m\u00eame, met en cause jusqu&rsquo;\u00e0 la d\u00e9l\u00e9gitimer et \u00e0 la mettre en pi\u00e8ces une si superbe dynamique. Elle s&rsquo;est choisie un pr\u00e9sident si fantasque et si inculte, si changeant et si narcissique, si vide de tout projet et de tout concept, si p\u00e9tulant et avide de propositions-surprises lanc\u00e9es \u00e0 la vitesse d&rsquo;un \u00e9change Borg-McEnroe de Wimbledon-1980, <strong>que ce nomm\u00e9-Trump est enfin parvenu \u00e0 s&rsquo;\u00e9tablir au c&oelig;ur du tourbillon crisique comme le ma&icirc;tre de l&rsquo;inversion et du paradoxe cosmique<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>M\u00eame s&rsquo;il l&rsquo;ignore, il a trouv\u00e9, Trump, sa formule strat\u00e9gique : <strong>il entropise la dynamique d&rsquo;entropisation<\/strong>. Ainsi la surpuissance se trouve-t-elle entra&icirc;n\u00e9e de plus en plus vite au rythme d&rsquo;une valse folle avec son partenaire d\u00e9sormais imp\u00e9ratif-dominant et qui m\u00e8ne le bal, <strong>qui a nom \u00ab\u00a0autodestruction\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Cela, <strong>c&rsquo;est le cadre g\u00e9n\u00e9ral, dans une p\u00e9riode d&rsquo;une bonne grosse semaine, de bonne cuv\u00e9e sans nul doute<\/strong>, entre le championnat des sanctions antirusses qui se poursuit et le man\u00e8ge scintillant des variations de la politique syrienne de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb o&ugrave; les changements d&rsquo;orientation vont \u00e0 la vitesse du m\u00eame \u00e9change Borg-McEnroe dont je parlai plus haut, lorsque le tennis avait encore figure humaine ; et enfin, ceci que j&rsquo;allais oublier, comme autre facteur d&rsquo;excitation des esprits enfi\u00e9vr\u00e9s, les bruits d&rsquo;effondrement financier qui continuent \u00e0 nous interpr\u00e9ter l&rsquo;Ouverture de <em>Tannh&auml;user<\/em>.<\/p>\n<\/p>\n<p><p>Le reste se divise en deux castes. La premi\u00e8re, qui ne la reconna&icirc;trait, se trouve dans les tenants de la servitude volontaire peinturlur\u00e9e aux diverses tendances du jour, qui go&ucirc;tent les d\u00e9lices de l&rsquo;asservissement postmoderne comme on fait rel\u00e2che \u00e0 Capoue, en attendant que le ciel leur tombe sur la t\u00eate. Je parle de ce que l&rsquo;on avait coutume de nommer \u00ab\u00a0civilisation europ\u00e9enne\u00a0\u00bb &#8230;<\/p>\n<\/p>\n<p><p>La civilisation europ\u00e9enne se termine <strong>en fun\u00e8bre et folle farce dansante, comme les rats qui suivent <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_Joueur_de_fl%C3%BBte_de_Hamelin\">le joueur de fl&ucirc;te de Hamelin<\/a><\/strong>, imbue d&rsquo;elle-m\u00eame, insupportable \u00e0 cause de son b\u00e2frement \u00e0 la moraline nietzsch\u00e9enne, presque \u00e9mouvante \u00e0 force de cette intelligence b\u00eatifi\u00e9e jusqu&rsquo;\u00e0 l&rsquo;infantilisation, la civilisation europ\u00e9enne terminale dans une sorte d&rsquo;Alzheimer r\u00e9duite aux acqu\u00eats des enfants trouv\u00e9s et abandonn\u00e9s. <strong>Pauvre Europe dirais-je plein de compassion, en souvenir de la grandeur qu&rsquo;elle fut<\/strong>, comme Bigeard \u00e9crivant \u00e0 ses hommes sur un bout de papier h\u00e9ro\u00efque et froiss\u00e9 l&rsquo;ordre de capitulation de son 6<sup>me<\/sup>Bataillon de Parachutistes Coloniaux \u00e0 Dien Bien-Phu : \u00ab\u00a0<em>Pauvre para, pauvre Six<\/em>\u00ab\u00a0. <\/p>\n<\/p>\n<p><p>Les autres font de la r\u00e9sistance sans illusion ni forfanterie parce qu&rsquo;\u00e0 avoir de si m\u00e9diocres adversaires on se trouve soit m\u00eames un peu \u00e9prouv\u00e9 ; <strong>mais avec un succ\u00e8s grandissant, transformant la technique \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/resistance-autodestruction-1\">faire<\/a> <em><a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-le-volte-quart-du-maitre-du-faire-aikido\">a\u00efkido<\/a><\/em>\u00a0\u00bb en perc\u00e9es \u00e0-la-Patton <\/strong>o&ugrave; \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, totalement accro au Syst\u00e8me qui l&rsquo;aveugle, n&rsquo;y voit que du feu. On a vu et bien vu, par contre, <a href=\"https:\/\/www.rt.com\/news\/423228-syria-separatism-not-tolerated\/\">Erdogan-Rouhani-Poutine<\/a> agir hier de la sorte, jouant avec la Syrie comme s&rsquo;ils en \u00e9taient les ordonnateurs et les organisateurs, &ndash; et ils le sont en v\u00e9rit\u00e9. L\u00e0-dessus, je manquerais \u00e0 mon devoir d&rsquo;oublier <strong>le formidable Xi avec son p\u00e9troyuan<\/strong>, veillant derri\u00e8re ce beau monde, dans la position de <strong>ce verrou cosmique du jeu qu&rsquo;est l&rsquo;arri\u00e8re<\/strong>.<\/p>\n<\/p>\n<p><p>(Je parle en termes de rugby : en rugby, l&rsquo;arri\u00e8re est l&rsquo;homme-clef qui peut briser, en dernier rideau, les plus terribles offensives et pourtant marquer un d\u00e9luge de points qui font la victoire ; et ma nostalgie de rappeler \u00e0 votre m\u00e9moire le titanesque <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Don_Clarke\">Don Clarke<\/a>, 1,88 m\u00e8tre et 110 kilos, avec son \u00ab\u00a0un coup de pied ph\u00e9nom\u00e9nal\u00a0\u00bb et des placages de l\u00e9gende, qui marqua 781 points lors de ses 89 matches avec les <em>All Blacks <\/em>dans les ann\u00e9es 1950-1960.)<\/p>\n<\/p>\n<blockquote>\n<p><p>Soufflez un peu et appr\u00e9ciez un tr\u00e8s court instant, quelques heures ou quelques minutes <strong>de brise l\u00e9g\u00e8re entre deux ouragans crisiques<\/strong>, juste le temps de conclure pour le temps pr\u00e9sent&#8230; L&rsquo;esprit est l\u00e0, qui vous sugg\u00e8re la profonde et irr\u00e9fragable v\u00e9rit\u00e9 : non seulement le <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-tourbillon-crisique\">tourbillon crisique<\/a> r\u00e8gne, mais <strong>il m\u00e9rite d\u00e9sormais, lorsque l&rsquo;occasion le d\u00e9signe, le surnom de \u00ab\u00a0tourbillon cosmique\u00a0\u00bb<\/strong>. Les Temps Exceptionnels approchent.<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Tourbillon crisique-46 5 avril 2018 &ndash; L&rsquo;h\u00e9g\u00e9monie des &Eacute;tats-Unis d&rsquo;Am\u00e9rique est \u00e0 la fois totale et incontestable, totalitaire et au-dessus de tout argument. Eux seuls agissent avec un z\u00e8le exceptionnel dans le cadre de la seule mission qu&rsquo;il soit d\u00e9sormais possible d&rsquo;ex\u00e9cuter officiellement, la seule qui ait l&rsquo;aval m\u00e9prisant du Syst\u00e8me dont ces m\u00eames &Eacute;tats-Unis&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[12375,13098,4243,12703,8294,7979,3737,7865,18223,916,12241,3867,12735,2639],"class_list":["post-77864","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-aikido","tag-borg","tag-clarke","tag-cosmique","tag-crisique","tag-don","tag-erdogan","tag-faire","tag-mcenroe","tag-poutine","tag-rouhani","tag-syrie","tag-tourbillon","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77864"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77864\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}