{"id":77865,"date":"2018-04-06T05:19:47","date_gmt":"2018-04-06T05:19:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/04\/06\/kemerovo-et-les-cercles-de-la-laideur\/"},"modified":"2018-04-06T05:19:47","modified_gmt":"2018-04-06T05:19:47","slug":"kemerovo-et-les-cercles-de-la-laideur","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/04\/06\/kemerovo-et-les-cercles-de-la-laideur\/","title":{"rendered":"Kemerovo et les cercles de la laideur"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Kemerovo et les cercles de la laideur<\/h2>\n<\/p>\n<p><p>Vous avez peut-\u00eatre entendu parler de l&rsquo;\u00e9v\u00e9nement tragique que je vais d\u00e9crire, ou peut-\u00eatre pas. Si vous en avez entendu parler en anglais, il y a de fortes chances que ce que vous avez entendu fasse partie d&rsquo;un travail de sape programm\u00e9 antirusse. Normalement, je serais r\u00e9ticent \u00e0 \u00e9crire \u00e0 ce sujet ; il est g\u00e9n\u00e9ralement pr\u00e9f\u00e9rable de rendre les c\u00e9l\u00e9brations publiques et de garder les trag\u00e9dies priv\u00e9es. Mais dans ce cas, un grand nombre de personnes, \u00e0 diff\u00e9rents niveaux, ont tent\u00e9 de tirer profit de cette trag\u00e9die et d&rsquo;en tirer des b\u00e9n\u00e9fices, g\u00e9n\u00e9rant un gigantesque nuage de fum\u00e9e noire bien plus important que celui g\u00e9n\u00e9r\u00e9 par l&rsquo;\u00e9v\u00e9nement lui-m\u00eame.<\/p>\n<\/p>\n<p><p>Cette trag\u00e9die vraiment effroyable s&rsquo;est d\u00e9roul\u00e9e dimanche dernier, 25 mars, \u00e0 Kemerovo (l&rsquo;accent est mis sur la premi\u00e8re syllabe) r\u00e9gion de Kouzbass, Sib\u00e9rie. Un incendie au centre commercial et de loisirs Winter Cherry a co&ucirc;t\u00e9 la vie \u00e0 64 personnes, dont 41 enfants. Seuls 27 corps ont \u00e9t\u00e9 identifi\u00e9s ; d&rsquo;autres attendent une analyse g\u00e9n\u00e9tique. Le nombre de bless\u00e9s est de 79, dont 12 restent hospitalis\u00e9s ; 67 ont pu sortir et seront trait\u00e9s en ambulatoire. Les familles des victimes et chacun des bless\u00e9s ont re\u00e7u 1 million de roubles du gouvernement r\u00e9gional (17 350 USD). En outre, le principal propri\u00e9taire du centre, l&rsquo;entrepreneur Denis Chtengelov, a promis de verser 3 millions de roubles pour chaque d\u00e9funt. Toutes les victimes seront \u00e9galement suivies par un m\u00e9decin et un psychologue pour les aider jusqu&rsquo;\u00e0 leur gu\u00e9rison.<\/p>\n<\/p>\n<p><p>Les Russes sont habitu\u00e9s \u00e0 la trag\u00e9die. Le climat rigoureux et les longs hivers, accompagn\u00e9s de routes verglac\u00e9es et enneig\u00e9es, de fr\u00e9quentes conditions de voile blanc et autres, provoquent de nombreux accidents dans les transports. Les attaques terroristes ont aussi caus\u00e9 leur part de victimes. Mais cet incident a vraiment \u00e9branl\u00e9 les gens et l&rsquo;effusion de chagrin a touch\u00e9 tout le pays ; d&rsquo;abord, parce que sa cause n&rsquo;\u00e9tait pas la nature ou la guerre &minus; c&rsquo;\u00e9tait un d\u00e9sastre caus\u00e9 par l&rsquo;homme &minus; et deuxi\u00e8mement, parce que tant de victimes \u00e9taient des enfants qui s&rsquo;\u00e9taient pr\u00e9sent\u00e9s l\u00e0 ce dimanche simplement pour une journ\u00e9e de plaisir. Des monuments comm\u00e9moratifs spontan\u00e9s ont \u00e9t\u00e9 \u00e9rig\u00e9s dans tout le pays, de Vladivostok \u00e0 l&rsquo;Est (5400 km de Kemerovo) \u00e0 Saint-P\u00e9tersbourg \u00e0 l&rsquo;Ouest (4100 km) et \u00e0 travers le monde. Avec l&rsquo;effusion de chagrin et de soutien, le respect a \u00e9t\u00e9 rendu aux h\u00e9ros de cette trag\u00e9die, morts et vivants. Tatiana Darsalia, une enseignante d&rsquo;anglais, a conduit sa propre fille hors du b\u00e2timent en flammes, puis elle est revenue en courant pour sauver d&rsquo;autres enfants ; elle n&rsquo;a pas surv\u00e9cu. Dimitri Poloukhine, un cadet du minist\u00e8re des Situations d&rsquo;urgence, a r\u00e9ussi \u00e0 s&#8217;emparer de trois enfants \u00e0 la fois, un gar\u00e7on et deux filles ; il a surv\u00e9cu.<\/p>\n<\/p>\n<p><p>C&rsquo;est donc le c&oelig;ur de la trag\u00e9die, tout cela parfaitement humain et compr\u00e9hensible. Apr\u00e8s beaucoup de chagrin, et beaucoup de soutien de l&rsquo;ext\u00e9rieur, Kemerovo finira par gu\u00e9rir. Mais autour de cette trag\u00e9die, d\u00e8s qu&rsquo;elle s&rsquo;est produite, s&rsquo;est mis en orbite un v\u00e9ritable nuage d&rsquo;ast\u00e9ro\u00efde de laideur humaine : l&rsquo;humanit\u00e9 pr\u00e9datrice sans \u00e2me et bestiale qui tente de tirer un modeste b\u00e9n\u00e9fice personnel ou collectif de la mort de ces enfants. L&rsquo;anglais manque de bons mots pour d\u00e9crire de telles personnes ; tout ce qu&rsquo;il a, c&rsquo;est des vulgaires jurons anglo-saxons et des imitations farfelues de latin, langue morte depuis longtemps. &Eacute;tiqueter simplement de telles personnes ne fonctionnera pas ; au lieu de cela, je lancerais bien en orbite ces d\u00e9chets humains enflamm\u00e9s sur des cercles de laideur. Je les appellerai ainsi, comme Dante Alighieri a vou\u00e9 les p\u00e9cheurs aux cercles de l&rsquo;Enfer. Et peut-\u00eatre m\u00eame leur accorderai-je quelques tourments \u00e9ternels convenablement m\u00e9di\u00e9vaux.<\/p>\n<\/p>\n<p><p>Au centre m\u00eame de cet ensemble de cercles de la laideur peut se trouver un trou noir : le feu pourrait avoir \u00e9t\u00e9 d&rsquo;origine criminelle. (Cela peut aussi \u00eatre d&ucirc; \u00e0 un court-circuit accidentel, l&rsquo;enqu\u00eate n&rsquo;est pas termin\u00e9e.) Mais si c&rsquo;\u00e9tait un incendie criminel, la principale th\u00e9orie est que cela a commenc\u00e9 dans une salle de jeux pour enfants. Il y avait une fosse remplie de blocs de polystyr\u00e8ne et quelqu&rsquo;un (pas encore de suspect) a peut-\u00eatre mis le feu \u00e0 l&rsquo;un d&rsquo;entre eux. Le feu s&rsquo;est alors propag\u00e9 rapidement \u00e0 toute la fosse, les cordes synth\u00e9tiques qui pendaient dessus ont pris feu et il s&rsquo;est \u00e9tendu aux murs et au reste de l&rsquo;espace, et de l\u00e0 \u00e0 toute la structure.<\/p>\n<\/p>\n<p><p>Mais il aurait pu s&rsquo;agir d&rsquo;un petit pyromane stupide jouant avec un briquet qu&rsquo;il a ramass\u00e9 quelque part (probablement un gar\u00e7on). Beaucoup de jeunes gar\u00e7ons sont des pyromanes ; ils finissent g\u00e9n\u00e9ralement par surmonter ce travers si on leur confie la tache de br&ucirc;ler les d\u00e9chets de taille du jardin. Quand j&rsquo;avais environ six ans, je faisais la vaisselle et mon attention a \u00e9t\u00e9 attir\u00e9e par une grille de ventilation au-dessus de l&rsquo;\u00e9vier de la cuisine. J&rsquo;ai donc plac\u00e9 une chaise sur le comptoir de la cuisine, grimp\u00e9 dessus, sorti la grille et regard\u00e9 \u00e0 l&rsquo;int\u00e9rieur. Il faisait sombre \u00e0 l&rsquo;int\u00e9rieur du puits de ventilation, alors j&rsquo;ai trouv\u00e9 une bo&icirc;te d&rsquo;allumettes. Puis, quand la poussi\u00e8re qui tapissait ce conduit de ventilation s&rsquo;est mise \u00e0 flamber, j&rsquo;ai pu observer un magnifique brasier orange monter tout le long de la tour tout en r\u00e9fl\u00e9chissant que la bonne vie pouvait s&rsquo;\u00eatre termin\u00e9e avant m\u00eame qu&rsquo;elle ne commence. Et puis le feu s&rsquo;est \u00e9teint. Mais si l&rsquo;incendie de ce week-end s&rsquo;av\u00e8re avoir \u00e9t\u00e9 un acte pr\u00e9m\u00e9dit\u00e9 d&rsquo;incendie criminel, alors son auteur ne m\u00e9rite pas moins que d&rsquo;\u00eatre coinc\u00e9 dans un trou noir pour toute l&rsquo;\u00e9ternit\u00e9.<\/p>\n<\/p>\n<p><p>Le premier cercle de laideur que nous rencontrons est peupl\u00e9 de tous ceux qui sont responsables de l&rsquo;\u00e9tat d\u00e9plorable de la s\u00e9curit\u00e9 incendie du complexe Winter Cherry. Le syst\u00e8me d&rsquo;alarme incendie automatique \u00e9tait d\u00e9sactiv\u00e9 et ce depuis plusieurs jours. Cette mesure a \u00e9t\u00e9prise \u00e0 la suite de fausses alarmes, et aucune tentative n&rsquo;a \u00e9t\u00e9 faite pour le r\u00e9parer. Apr\u00e8s le d\u00e9but de l&rsquo;incendie, une tentative d&rsquo;activation manuelle s&rsquo;est sold\u00e9e par un \u00e9chec. Le syst\u00e8me de ventilation n&rsquo;a pas \u00e9t\u00e9 arr\u00eat\u00e9 et il a fait circuler de la fum\u00e9e toxique dans tout le b\u00e2timent. Les issues de secours \u00e9taient verrouill\u00e9es ; les couloirs d&rsquo;\u00e9vacuation \u00e9taient rev\u00eatus de mat\u00e9riaux inflammables. Les cages d&rsquo;escaliers n&rsquo;\u00e9taient pas \u00e9tanches \u00e0 la diffusion de la fum\u00e9e et n&rsquo;\u00e9taient pas suffisantes pour pouvoir \u00e9vacuer le b\u00e2timent sans utiliser les ascenseurs et les escaliers m\u00e9caniques, eux-m\u00eames en panne lorsque l&rsquo;\u00e9lectricit\u00e9 a \u00e9t\u00e9 coup\u00e9e. Selon certains rapports, le personnel de s\u00e9curit\u00e9 a \u00e9t\u00e9 soit moins qu&rsquo;utile et m\u00eame contre-productif.<\/p>\n<\/p>\n<p><p>Qui est exactement coupable de cela, et quelle cons\u00e9quence cela aura-t-il ? Ce sera le r\u00e9sultat de l&rsquo;une des enqu\u00eates criminelles les plus approfondies de l&rsquo;histoire russe. Beaucoup de gens sont d\u00e9j\u00e0 s&ucirc;rs d&rsquo;\u00e9coper d&rsquo;une peine de prison ; les r\u00e8glements sur les incendies seront reformul\u00e9s ; non seulement \u00e0 Kemerovo, mais dans tout le pays, les r\u00e8glements sur les incendies et les proc\u00e9dures d&rsquo;inspection seront renforc\u00e9s. De nombreux fonctionnaires au niveau municipal (l&rsquo;une des poches de corruption restantes les plus importantes en Russie) vont soit recevoir une peine d&#8217;emprisonnement, soit \u00eatre licenci\u00e9s, soit se mettre \u00e0 trembler \u00e0 la seule id\u00e9e de toucher un pot-de-vin au lieu de mener \u00e0 bien leur inspection officielle. L&rsquo;enqu\u00eate durera au moins cinq mois ; les proc\u00e8s prendront encore plus de temps. Mais nous pouvons \u00eatre s&ucirc;rs que ce sera minutieux, exhaustif et exemplaire parce que la personne qui l&rsquo;a ordonn\u00e9 et qui va le superviser est Poutine lui-m\u00eame. Lors de l&rsquo;une des \u00e9missions t\u00e9l\u00e9vis\u00e9es, il a fait r\u00e9f\u00e9rence au rapport d&rsquo;inspection de s\u00e9curit\u00e9 incendie pour le b\u00e2timent incendi\u00e9, qui a \u00e9t\u00e9 approuv\u00e9 <em>&laquo; sans commentaires &raquo;<\/em>. Outr\u00e9, il s&rsquo;est tourn\u00e9 vers le chef du comit\u00e9 d&rsquo;enqu\u00eate et a dit : <em>&laquo; Trouvez qui a sign\u00e9 cela et faites-moi conna&icirc;tre son nom &raquo;<\/em>.  &minus; <em>&laquo; Oui, monsieur ! &raquo;<\/em><\/p>\n<\/p>\n<p><p>Ceux qui peuplent ce cercle de la laideur ne m\u00e9ritent pas de tourments \u00e9ternels : tout le poids de la loi administrative et criminelle, exerc\u00e9 sur eux par un Poutine raisonnablement irrit\u00e9 et courrouc\u00e9, suffira amplement, j&rsquo;en suis s&ucirc;r ! Et ici, si je peux me le permettre, appara&icirc;t une lueur d&rsquo;espoir dans cette sombre sitution : il y a une bonne chance que ces 41 enfants ne soient pas morts pour rien. Leur perte donnera l&rsquo;impulsion d&rsquo;une refonte compl\u00e8te de la s\u00e9curit\u00e9 publique et de la gouvernance municipale, rendant beaucoup moins probable la r\u00e9p\u00e9tition d&rsquo;un tel incident.<\/p>\n<\/p>\n<p><p>Le cercle de la laideur suivant est occup\u00e9 par une plan\u00e8te gazeuse g\u00e9ante &minus; une sorte d&rsquo;Uranus de la laideur &minus; avec un grand nombre de satellites semblables \u00e0 des \u00e9trons. Cette boule puante g\u00e9ante de gaz des marais est un Ukrainien du nom de Yevgeny Volnov (de son vrai nom Nikita Kouvikov). Il est tr\u00e8s probablement employ\u00e9 par le minist\u00e8re ukrainien de l&rsquo;information. Peu de temps apr\u00e8s l&rsquo;annonce de l&rsquo;incendie, Volnov a commenc\u00e9 \u00e0 passer des appels \u00e0 la morgue de Kemerovo. Utilisant l&rsquo;identit\u00e9 d&rsquo;un officier du minist\u00e8re russe des Situations d&rsquo;urgence, il a demand\u00e9 aux responsables de la morgue combien de cadavres ils pouvaient accepter et leur a ordonn\u00e9 de se pr\u00e9parer \u00e0 en accepter un grand nombre &minus; des centaines. Bien s&ucirc;r, la fake news que des centaines de cadavres pouvaient \u00eatre en chemin a rapidement fuit\u00e9 hors des morgues. En quelques heures, les gens dans la rue interrogeaient les fonctionnaires et affirmaient qu&rsquo;ils leur mentaient sur le nombre de personnes tu\u00e9es. Les fonctionnaires ont r\u00e9agi en formant des groupes de citoyens b\u00e9n\u00e9voles et en les envoyant directement aux morgues pour effectuer une v\u00e9rification. Les chiffres correspondaient aux rapports officiels et cette tentative ukrainienne de fomenter de l&rsquo;agitation publique en profitant d&rsquo;une trag\u00e9die a \u00e9t\u00e9 contenue.<\/p>\n<\/p>\n<p><p>Mais cela n&rsquo;a pas mis fin \u00e0 l&rsquo;affaire, car maintenant les activistes des m\u00e9dias sociaux ont pris le relais. Diverses c\u00e9l\u00e9brit\u00e9s, dont certaines ont des milliers d&rsquo;adeptes, se sont tourn\u00e9es vers Facebook, Twitter et d&rsquo;autres plateformes de m\u00e9dias sociaux et ont r\u00e9pandu ces mensonges bien au-del\u00e0 des limites de la r\u00e9gion. Un grand nombre de ces personnes ont fait cela plus ou moins sans r\u00e9fl\u00e9chir ; alors que d&rsquo;autres cherchaient simplement \u00e0 accro&icirc;tre leur popularit\u00e9 sur les m\u00e9dias sociaux au d\u00e9triment des victimes de cette trag\u00e9die ; d&rsquo;autres encore, qui se consid\u00e8rent comme des membres de l&rsquo;opposition, ont tent\u00e9 de l&rsquo;exploiter pour saper la confiance du public dans les autorit\u00e9s. Mais alors que la v\u00e9rit\u00e9 peut vous lib\u00e9rer, le mensonge peut facilement devenir une prison auto-fabriqu\u00e9e et ceux qui r\u00e9pandent ces mensonges, involontairement ou avec l&rsquo;intention de nuire, se retrouveront bient\u00f4t au milieu d&rsquo;un fiasco en termes de relations publiques. Il a ensuite \u00e9t\u00e9 soulign\u00e9 que certains d&rsquo;entre eux, des c\u00e9l\u00e9brit\u00e9s en particulier, avaient un si grand nombre d&rsquo;adeptes sur les m\u00e9dias sociaux qu&rsquo;elles pourraient \u00eatre consid\u00e9r\u00e9es comme des organisations m\u00e9diatiques, responsables de la v\u00e9rification des faits et responsables de la diffusion de fausses informations, sp\u00e9cialement dans une p\u00e9riode de crise o&ugrave; cela peut provoquer une panique ou des troubles sociaux. Il faut noter que ce n&rsquo;est qu&rsquo;apr\u00e8s avoir pris conscience des cons\u00e9quences que beaucoup d&rsquo;entre elles ont choisi d&rsquo;\u00e9mettre des r\u00e9tractations publiques et de s&rsquo;excuser.<\/p>\n<\/p>\n<p><p>J&rsquo;ai un v\u00e9ritable d\u00e9sir de tourment m\u00e9di\u00e9val \u00e9ternel pour le m\u00e9chant Volnov et pour tous ceux qui ont fait \u00e9cho \u00e0 ses fausses nouvelles : je les livre \u00e0 l&rsquo;\u00e9ternit\u00e9 de l&rsquo;Ukraine.<\/p>\n<\/p>\n<p><p>En remarque, cette exp\u00e9rience d\u00e9montre quelque chose de particulier sur les m\u00e9dias sociaux. Consid\u00e9rons ces nouvelles plates-formes d&rsquo;accueil telles que AirBNB, ou les diff\u00e9rents syst\u00e8mes de partage de voitures, ou m\u00eame des sites de n\u00e9gociation tels que Ebay. Elles reposent toutes sur le principe que la confiance publique repose sur la r\u00e9putation. D\u00e9truisez le voile de l&rsquo;anonymat, rendez la r\u00e9putation de tout le monde publique, faites en sorte que tout le monde soit facile \u00e0 localiser et \u00e0 identifier instantan\u00e9ment et soudainement le risque dispara&icirc;t et la coop\u00e9ration devient la strat\u00e9gie la moins co&ucirc;teuse. Plus personne ne pourra commander anonymement un taxi et ne pas se trouver au point de rendez-vous. Maintenant, vous pouvez utiliser une application pour smartphone qui vous indique qui est le chauffeur, qui indique au chauffeur qui vous \u00eates, qui permet de n\u00e9gocier le service de transport d\u00e9sir\u00e9, de faire conna&icirc;tre votre emplacement et votre destination. Cela incite automatiquement tout le monde \u00e0 avoir un meilleur comportement.<\/p>\n<\/p>\n<p><p>Les m\u00e9dias sociaux sont exactement le contraire. Il n&rsquo;y a pas de crit\u00e8re pour \u00e9tablir une r\u00e9putation sauf la notori\u00e9t\u00e9 et toute m\u00e9thode pour augmenter cette notori\u00e9t\u00e9 qui \u00e9vite les quelques directives rudimentaires contre le <em>&laquo; discours de haine<\/em>ou l&rsquo;<em>incitation \u00e0 la violence &raquo;<\/em>fonctionne sans autre v\u00e9rification. De plus, il n&rsquo;y a aucune raison de penser que les plateformes des m\u00e9dias sociaux sont r\u00e9ellement int\u00e9ress\u00e9es par la constitution d&rsquo;un groupe social ou quoi que ce soit de ce genre ; tout ce qui les int\u00e9resse c&rsquo;est d&rsquo;obtenir et de e vendre vos donn\u00e9es (et peut-\u00eatre quelques annonces). Certains, comme Facebook, m\u00e9ritent de figurer dans un Cercle de la laideur qui leur serait propre. Que devrions-nous faire de cela ? La r\u00e9ponse, Voltaire l&rsquo;a dite : <em>&laquo; <a href=\"http:\/\/www.dicoperso.com\/term\/adaeaead5e60a85e5e,,xhtml\">&Eacute;crasez l&rsquo;inf\u00e2me !<\/a> &raquo;.<\/em><\/p>\n<\/p>\n<p><p>Le dernier cercle de la laideur est peupl\u00e9 par les porte-parole des m\u00e9dias occidentaux tels que Leonid Berchidsky qui a saisi cette occasion pour \u00e9crire un article particuli\u00e8rement inf\u00e2me pour <em>Bloomberg<\/em>. Apparemment, leur devise est <em>&laquo; faire du foin pendant que le soleil brille &raquo;<\/em>et c&rsquo;est une journ\u00e9e ensoleill\u00e9e pour eux chaque fois qu&rsquo;il y a beaucoup d&rsquo;enfants russes morts. Sa logique est irr\u00e9prochable : voyez les enfants russes morts, donc Poutine est un vil dictateur. Quel tourment \u00e9ternel sugg\u00e9rez-vous aux gens qui utilisent une trag\u00e9die impliquant des enfants morts pour remplir vos yeux et vos oreilles d&rsquo;ordures et votre t\u00eate d&rsquo;id\u00e9es fausses &minus; le tout pour avoir une chance de l\u00e9cher la main de leur ma&icirc;tre ? Je suis s&ucirc;r que vous pouvez imaginer quelque chose de parfaitement m\u00e9di\u00e9val si vous vous concentrez un peu. Allez-y et essayez-le alors ! Ou nous pouvons simplement les condamner tous \u00e0 vivre pour l&rsquo;\u00e9ternit\u00e9 en Ukraine. A votre choix.<\/p>\n<\/p>\n<p><h4>Dimitri Orlov<\/h4>\n<\/p>\n<p><p>(Le 29 mars 2018, <a href=\"http:\/\/cluborlov.blogspot.fr\/2018\/03\/kemerovo-and-circles-of-ugliness.html\">Club Orlov<\/a>&ndash; traduction <em><a href=\"http:\/\/lesakerfrancophone.fr\/kemerovo-et-les-cercles-de-la-laideur\">Le Sakerfrancophone<\/a><\/em>)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kemerovo et les cercles de la laideur Vous avez peut-\u00eatre entendu parler de l&rsquo;\u00e9v\u00e9nement tragique que je vais d\u00e9crire, ou peut-\u00eatre pas. Si vous en avez entendu parler en anglais, il y a de fortes chances que ce que vous avez entendu fasse partie d&rsquo;un travail de sape programm\u00e9 antirusse. Normalement, je serais r\u00e9ticent \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[6045,11258,3858,6508,2668,916],"class_list":["post-77865","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-catastrophe","tag-catastrophes","tag-corruption","tag-incendie","tag-orlov","tag-poutine"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77865"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77865\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}