{"id":77889,"date":"2018-04-18T13:57:10","date_gmt":"2018-04-18T13:57:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/04\/18\/de-limportance-davoir-lair-dangereux\/"},"modified":"2018-04-18T13:57:10","modified_gmt":"2018-04-18T13:57:10","slug":"de-limportance-davoir-lair-dangereux","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/04\/18\/de-limportance-davoir-lair-dangereux\/","title":{"rendered":"De l&rsquo;importance d&rsquo;avoir l&rsquo;air dangereux"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">De l&rsquo;importance d&rsquo;avoir l&rsquo;air dangereux<\/h2>\n<\/p>\n<p><p>C&rsquo;est un travail difficile d&rsquo;\u00eatre un <a href=\"https:\/\/fr.wikipedia.org\/wiki\/H%C3%A9g%C3%A9monie\">h\u00e9g\u00e9mon<\/a>mondial et la seule superpuissance du monde. Vous devez garder la plan\u00e8te enti\u00e8re bien align\u00e9e. Chaque pays a besoin d&rsquo;\u00eatre renseign\u00e9 sur sa place et de s&rsquo;y tenir, par la force s&rsquo;il le faut. De temps en temps un pays ou deux doit \u00eatre conquis ou d\u00e9truit, juste pour tenir les autres inform\u00e9s. De plus, vous devez vous m\u00ealer sans rel\u00e2che de la politique des autres pays, truquer les \u00e9lections afin que seuls les candidats favorables aux &Eacute;tats-Unis puissent gagner, mener des op\u00e9rations de changement de r\u00e9gime et organiser des r\u00e9volutions color\u00e9es. Si vous cessez de le faire, certains pays vont commencer \u00e0 vous ignorer ; le reste r\u00e9alisera rapidement que vous perdez le contr\u00f4le et tous commenceront \u00e0 s&rsquo;\u00e9manciper.<\/p>\n<\/p>\n<p><p>Les &Eacute;tats-Unis sont-ils toujours la plus grande puissance du monde, contr\u00f4lant toute la plan\u00e8te, ou ce moment de l&rsquo;histoire est-il d\u00e9j\u00e0 en train de passer ? Nous entendons constamment parler de la situation g\u00e9opolitique : les relations entre les &Eacute;tats-Unis et les pays de l&rsquo;OTAN d&rsquo;un c\u00f4t\u00e9 et la Russie de l&rsquo;autre vont de mal en pis ; il y a une guerre commerciale en cours avec la Chine ; La Cor\u00e9e du Nord reste un probl\u00e8me insoluble et un embarras. Beaucoup de gens soutiennent que nous sommes tr\u00e8s proches d&rsquo;une guerre mondiale. Mais <em>&laquo; tr\u00e8s proche &raquo;<\/em>signifie-t-il r\u00e9ellement quelque chose ? Il est tout \u00e0 fait possible de rester des heures avec ses orteils suspendus au bord d&rsquo;une falaise et de ne jamais sauter. Le suicide est une grande d\u00e9cision : m\u00eame pour une personne et encore plus pour un grand pays.<\/p>\n<\/p>\n<p><p>Le 1er mars 2018, le pr\u00e9sident Poutine a d\u00e9voil\u00e9 les nouveaux syst\u00e8mes d&rsquo;armement de la Russie contre lesquels les &Eacute;tats-Unis sont sans d\u00e9fense et le resteront dans un avenir pr\u00e9visible. Auparavant, le plan des USA \u00e9tait de cerner la Russie par des bases militaires et des batteries de missiles, puis de lancer une premi\u00e8re frappe pr\u00e9ventive, d\u00e9truisant sa capacit\u00e9 \u00e0 riposter et l&rsquo;obligeant \u00e0 capituler. Ce plan a maintenant \u00e9chou\u00e9 de mani\u00e8re \u00e9vidente et une attaque des &Eacute;tats-Unis et de l&rsquo;OTAN contre la Russie est de nouveau une garantie de suicide. Pire encore, m\u00eame des affrontements militaires limit\u00e9s sont maintenant impensables car la Russie peut d\u00e9sormais infliger des dommages inacceptables aux forces am\u00e9ricaines et de l&rsquo;OTAN, \u00e0 distance et sans mettre en danger ses propres forces. Si la Russie n&rsquo;attaque pas et si les &Eacute;tats-Unis et l&rsquo;OTAN ne peuvent pas attaquer, quelle est la probabilit\u00e9 d&rsquo;une guerre ?<\/p>\n<\/p>\n<p><p>Les nouveaux syst\u00e8mes d&rsquo;armes ont permis \u00e0 la Russie de commencer \u00e0 ignorer les &Eacute;tats-Unis. Il est toujours important de maintenir une posture militaire cr\u00e9dible, mais politiquement, les &Eacute;tats-Unis ne contr\u00f4lent d\u00e9j\u00e0 plus le monde, pas plus que les institutions mondiales sur lesquelles ils se sont appuy\u00e9s. Au lieu de cela, ce que nous voyons est la r\u00e9apparition des &Eacute;tats-nations et m\u00eame des empires. L&rsquo;avenir politique de la Syrie est d\u00e9cid\u00e9 par la Russie, la Turquie et l&rsquo;Iran, sans aucune contribution utile des &Eacute;tats-Unis. De mani\u00e8re significative, alors que la Russie et l&rsquo;Iran sont d\u00e9j\u00e0 ind\u00e9pendants des &Eacute;tats-Unis, la Turquie a \u00e9t\u00e9 un de leurs alli\u00e9s et elle est la deuxi\u00e8me force arm\u00e9e de l&rsquo;OTAN. Le fait que la Turquie ne soit plus d\u00e9sireuse de plaire aux Am\u00e9ricains est assez r\u00e9v\u00e9lateur.<\/p>\n<\/p>\n<p><p>Sauf pendant l&rsquo;\u00e9trange et tumultueux XXe si\u00e8cle au cours duquel les &Eacute;tats-Unis ont bri\u00e8vement domin\u00e9 la sc\u00e8ne mondiale, ces trois pays ont suivi diff\u00e9rents chemins, dont au moins une des d\u00e9nominations contenait le mot <em>&laquo; empire &raquo; <\/em>: l&rsquo;Empire russe, l&rsquo;Empire ottoman et l&rsquo;Empire perse. Des trois, les empires russe et ottoman furent les h\u00e9ritiers du Saint Empire romain germanique, dont la moiti\u00e9 orientale &minus; avec Constantinople, sa capitale &minus; continua \u00e0 exister pendant des si\u00e8cles apr\u00e8s que Rome fut devenue une ruine d\u00e9peupl\u00e9e et qu&rsquo;un \u00e2ge sombre enveloppait l&rsquo;Europe. Apr\u00e8s, Constantinople est tomb\u00e9e aux mains des Turcs et l&rsquo;islam a pris le contr\u00f4le de la r\u00e9gion, le centre du christianisme orthodoxe a, lui, migr\u00e9 vers le nord \u00e0 Moscou. Maintenant, ajoutez la Chine ou l&rsquo;Empire chinois si vous voulez, qui est maintenant align\u00e9 avec la Russie et compl\u00e9tez le tableau : tous les plus grands et les plus anciens empires eurasiens sont revenus sur le devant de la sc\u00e8ne, se parlent et coop\u00e8rent, tandis que le parvenu de l&rsquo;autre c\u00f4t\u00e9 de la plan\u00e8te n&rsquo;est m\u00eame plus invit\u00e9.<\/p>\n<\/p>\n<p><p>Compte tenu de cette situation, que doivent faire les &Eacute;tats-Unis ? Ils ont trois choix. Le premier est de d\u00e9clencher une guerre majeure, commettant ainsi un suicide national (tout en emportant d&rsquo;autres pays avec eux). Ils n&rsquo;ont pas la volont\u00e9 politique de prendre cette d\u00e9cision, bien qu&rsquo;ils puissent lancer une guerre majeure par accident. Le deuxi\u00e8me choix consiste simplement \u00e0 accepter les changements : renoncer \u00e0 essayer de projeter leur pouvoir autour du monde, se retirer dans leurs propres fronti\u00e8res et panser leurs blessures. Ils n&rsquo;ont pas la volont\u00e9 politique de le faire \u00e9galement. La seule issue restante est de pr\u00e9tendre aussi longtemps que possible que tout va toujours bien.<\/p>\n<\/p>\n<p><p>Mais comment est-il possible de pr\u00e9tendre que tout va toujours bien alors que tout s&rsquo;effondre ? La r\u00e9ponse est de commencer \u00e0 faire semblant. Si les &Eacute;tats-Unis r\u00e9ussissent \u00e0 convaincre suffisamment de gens, ici et ailleurs dans le monde, qu&rsquo;ils sont encore dangereux, ils pourront cacher leur affaiblissement croissant pendant un certain temps. Ils ne sont peut-\u00eatre plus capables de r\u00e9aliser aucun de leurs objectifs, mais encore tr\u00e8s capables de meurtres de masse, comme l&rsquo;ont r\u00e9cemment d\u00e9montr\u00e9 les bombardements<em>&laquo; de la coalition &raquo;<\/em>am\u00e9ricaine \u00e0 Mossoul et \u00e0 Raqqa, qui sont maintenant en ruines. Des actes similaires de meurtres de masse ont \u00e9t\u00e9 commis au Y\u00e9men par le proxy arabo-saoudien de l&rsquo;Am\u00e9rique, ainsi que par leur proxy ukrainien dans le Donbass.<\/p>\n<\/p>\n<p><p>Mais m\u00eame les occasions de commettre impun\u00e9ment des meurtres de masse aveugles sont de moins en moins nombreuses, for\u00e7ant les &Eacute;tats-Unis \u00e0 recourir \u00e0 plus d&rsquo;actes de violence de seconde zone. Pour justifier ces actes, les &Eacute;tats-Unis (et une grande partie de l&rsquo;Europe) se ridiculisent aux yeux du reste du monde en utilisant un mur \u00e9labor\u00e9 de non-sens complet. Une des histoires pr\u00e9f\u00e9r\u00e9es a \u00e0 voir avec les armes chimiques r\u00eav\u00e9es comme source d&rsquo;un effroi primordial. Jetez un coup d&rsquo;&oelig;il \u00e0 la r\u00e9cente attaque de missiles des isra\u00e9liens contre la Syrie. Elle \u00e9tait justifi\u00e9e par l&rsquo;utilisation, de toute \u00e9vidence, de fausses s\u00e9quences vid\u00e9o produites par les Casques blancs, un groupe connu pour avoir organis\u00e9 de faux \u00e9v\u00e9nements terroristes. &Agrave; ce stade, ils ne se soucient m\u00eame plus de l&rsquo;apparence de leur produit : cette fois-ci, ils n&rsquo;ont pas pris la peine d&rsquo;expurger le clap initial (utilis\u00e9 pour synchroniser la vid\u00e9o avec le son). Le d\u00e9cor \u00e9tait \u00e9videmment celui d&rsquo;un d\u00e9cor de cin\u00e9ma mais la qualit\u00e9 de la production manquait vraiment \u00e0 l&rsquo;appel. Au lieu de cela, nous avions des acteurs, certains portant des casques blancs, mais aucun \u00e9quipement de protection, d\u00e9versant des seaux d&rsquo;eau sur des enfants frissonnants. Comment cela peut-il pr\u00e9tendre avoir un sens ?<\/p>\n<\/p>\n<p><p>Et puis notez que les missiles (cinq ont \u00e9t\u00e9 abattus par les Syriens, seulement trois sont pass\u00e9s) sont venus d&rsquo;Isra\u00ebl. Pourquoi Isra\u00ebl ? Parce que les Russes avaient averti les &Eacute;tats-Unis qu&rsquo;ils savaient que la provocation par de fausses armes chimiques \u00e9tait organis\u00e9e comme pr\u00e9texte pour lancer une attaque de missiles et qu&rsquo;ils allaient tirer non seulement sur les missiles mais aussi sur ceux qui les lancent. Par cons\u00e9quent, les Am\u00e9ricains ont d\u00e9cid\u00e9 qu&rsquo;il serait trop risqu\u00e9 de lancer l&rsquo;attaque depuis des navires de la marine et ont demand\u00e9 aux Isra\u00e9liens de lancer eux-m\u00eames quelques missiles sur une base a\u00e9rienne \u00e9loign\u00e9e en Syrie, pensant \u00e0 juste titre que les Russes ne riposteraient pas imm\u00e9diatement contre Isra\u00ebl si aucun Russe n&rsquo;\u00e9tait touch\u00e9, sachant qu&rsquo;il n&rsquo;y aurait pas de Russes sur cette base a\u00e9rienne pendant leur attaque. Cela est, d&rsquo;une part, assez path\u00e9tique mais d&rsquo;autre part, cela montre que les Am\u00e9ricains sont encore capables d&rsquo;un minimum de pens\u00e9e rationnelle.<\/p>\n<\/p>\n<p><p>C&rsquo;est une \u00e9trange p\u00e9riode de l&rsquo;histoire que nous traversons. Les &Eacute;tats-Unis mentent sans arr\u00eat (puisque la v\u00e9rit\u00e9 n&rsquo;est pas de leur c\u00f4t\u00e9) tout en pr\u00e9tendant \u00eatre encore dangereux en commettant des meurtres de masse (\u00e0 petite \u00e9chelle, qu&rsquo;ils peuvent \u00eatre s&ucirc;rs de mener en toute impunit\u00e9). Pendant ce temps, le suicide national (via une guerre \u00e0 grande \u00e9chelle) et la d\u00e9cision de terminer tout le projet imp\u00e9rial restent politiquement impossibles. Combien de temps cette p\u00e9riode \u00e9trange et instable de non-sens meurtrier peut-elle persister ? Difficile \u00e0 dire, votre estimation est aussi bonne que la mienne. Mais elle ne peut \u00e9videmment pas durer longtemps. Donnez-lui quelques ann\u00e9es, ou moins.<\/p>\n<\/p>\n<p><h4>Dimitri Orlov<\/h4>\n<\/p>\n<p><p>(Le 10 avril 2018, <a href=\"http:\/\/cluborlov.blogspot.fr\/2018\/04\/the-importance-of-looking-dangerous.html\">Club Orlov<\/a>, &ndash; Traduction <em><a href=\"http:\/\/lesakerfrancophone.fr\/limportance-davoir-lair-dangereux\">Le Sakerfrancophone<\/a><\/em>)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De l&rsquo;importance d&rsquo;avoir l&rsquo;air dangereux C&rsquo;est un travail difficile d&rsquo;\u00eatre un h\u00e9g\u00e9monmondial et la seule superpuissance du monde. Vous devez garder la plan\u00e8te enti\u00e8re bien align\u00e9e. Chaque pays a besoin d&rsquo;\u00eatre renseign\u00e9 sur sa place et de s&rsquo;y tenir, par la force s&rsquo;il le faut. De temps en temps un pays ou deux doit \u00eatre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[2803,3318,8091,2774,2970,18248,2668,15709,3867],"class_list":["post-77889","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-effondrement","tag-force","tag-instabilite","tag-israel","tag-missiles","tag-montrer","tag-orlov","tag-sa","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77889"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77889\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}