{"id":77917,"date":"2018-05-04T10:26:37","date_gmt":"2018-05-04T10:26:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/05\/04\/instantane-de-la-contraction-de-la-puissance-us\/"},"modified":"2018-05-04T10:26:37","modified_gmt":"2018-05-04T10:26:37","slug":"instantane-de-la-contraction-de-la-puissance-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/05\/04\/instantane-de-la-contraction-de-la-puissance-us\/","title":{"rendered":"Instantan\u00e9 de la \u201ccontraction\u201d de la puissance US"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Instantan\u00e9 de la \u00ab\u00a0contraction\u00a0\u00bb de la puissance US<\/h2>\n<\/p>\n<p><p>Le site <em>SouthFront.org <\/em>publie ce <a href=\"https:\/\/southfront.org\/wp-content\/uploads\/2018\/05\/maritime_03_05_2018-1.jpg?x22691\">3 mai 2018<\/a> une carte et une description de la localisation actuelle des dix groupes op\u00e9rationnels de porte-avions de l&rsquo;U.S. Navy. (Un groupe est form\u00e9 autour d&rsquo;un grand porte-avions d&rsquo;attaque, ou CVN [entre 90 000 et 100 000 tonnes, 70-80 a\u00e9ronefs], avec quelque navires d&rsquo;escorte et de soutien, en g\u00e9n\u00e9ral un croiseur, et 3-5 fr\u00e9gates, parfois l&rsquo;un ou l&rsquo;autre navire de soutien logistique, et l&rsquo;un ou l&rsquo;autre sous-marin.)  La situation est particuli\u00e8rement frappante et constitue <strong>une bonne illustration de ce que nous jugerions \u00eatre la \u00ab\u00a0contraction\u00a0\u00bb<\/strong>, &ndash; pour des raisons techniques ou pour des raisons strat\u00e9giques, c&rsquo;est \u00e0 voir, &ndash; du principal instrument naval de projection de force de l&rsquo;US Navy.<\/p>\n<\/p>\n<p><p><em>Southfront.org<\/em>, qui ne dit pas clairement s&rsquo;il a l&rsquo;intention de publier hebdomadairement une telle carte, donne cette explication g\u00e9n\u00e9rale et m\u00e9thodologique : &laquo; <em>Ceci est la nouvelle mise \u00e0 jour de la carte de l&#8217;emplacement des Groupes de porte-avions d&rsquo;attaque de l&rsquo;U.S. Navy, indiquant la localisation approximative de ces groupes d&rsquo;attaque des transporteurs am\u00e9ricains effectu\u00e9e sur une base hebdomadaire. \u00ab\u00a0SouthFront &ndash; Analysis &#038; Intelligence\u00a0\u00bb suit l&rsquo;\u00e9volution de la localisation des groupes de porte-avions en utilisant les informations disponibles en source ouverte. Aucune information classifi\u00e9e n&rsquo;a \u00e9t\u00e9 utilis\u00e9e dans la production de la carte<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, il y a deux sortes de situations de localisation : situation op\u00e9rationnelle (\u00ab\u00a0\u00e0 la mer\u00a0\u00bb) et situation disons de r\u00e9serve ou de contrainte (croisi\u00e8re courte et escale pr\u00e8s du port d&rsquo;attache, immobilisation pour intervention technique). Situation g\u00e9n\u00e9rale actuelle :<\/p>\n<\/p>\n<p><p>&bull; Deux groupes de porte-avions \u00ab\u00a0\u00e0 la mer\u00a0\u00bb : d&rsquo;une part, le groupe du USS <em>Harry S. Truman<\/em>, dont la localisation au 3 mai est le passage du d\u00e9troit de Gibraltar pour entrer en M\u00e9diterran\u00e9e ; d&rsquo;autre part le groupe du USS <em>Abraham Lincoln<\/em>, \u00ab\u00a0au large des c\u00f4tes de Virginie\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&bull; Tous les autres (huit groupes) sont en positions quasi-stationnaires que nous qualifierions \u00ab\u00a0de r\u00e9serve\u00a0\u00bb ou de contrainte : \u00e9volution restreinte ou situation d&rsquo;escale dans un port de passage proche du port d&rsquo;attache, rel\u00e2che dans le port d&rsquo;attache ; ou, d&rsquo;autre part, immobilisation pour entretien y compris cale s\u00e8che, r\u00e9paration, modification, modernisation, etc. Sept groupes se trouvent concentr\u00e9s autour de la masse continentale US, &ndash; huit si l&rsquo;on inclut le USS <em>Abraham Lincoln<\/em>, \u00ab\u00a0\u00e0 la mer\u00a0\u00bb au large de la Virginie, donc pouvant \u00eatre inclus dans \u00ab\u00a0la masse continentale US\u00a0\u00bb. Sur ces huit, cinq se trouvent sur la c\u00f4te Est, trois sur la c\u00f4te Ouest (y compris le USS <em>Theodore Roosevelt <\/em>\u00e0 quai \u00e0 Pearl Harbor). Le USS <em>Ronald Reagan <\/em>se trouve dans son port d&rsquo;attache, \u00e0 Yokosuka, au Japon, o&ugrave; l&rsquo;US Navy dispose par trait\u00e9 d&rsquo;un troisi\u00e8me port d&rsquo;attache pour sa flotte en plus de ses deux ports d&rsquo;attache sur ses c\u00f4tes Est [Norfolk] et Ouest [San Diego].<\/p>\n<\/p>\n<p><p>(On notera que nous parlons bien entendu de cette cat\u00e9gorie des CVN qui sont les grands moyens strat\u00e9giques de l&rsquo;US Navy. Les autres plateformes, essentiellement les porte-h\u00e9licopt\u00e8res avec quelques avions restants \u00e0 d\u00e9collage vertical type <em>Harrier <\/em>aux tr\u00e8s faibles capacit\u00e9s du Corps des Marines n&rsquo;entrent pas dans cette cat\u00e9gorie. On en reparlera si un jour la version du JSF \u00e0 d\u00e9collage vertical F-35B devient une vraie machine op\u00e9rationnelle et non une d\u00e9coration de convenance, ce qui rel\u00e8ve de la science-fiction.) <\/p>\n<\/p>\n<p><p>Faisant l&rsquo;hypoth\u00e8se que cet instantan\u00e9 du d\u00e9ploiement des groupes d&rsquo;attaque de l&rsquo;US Navy repr\u00e9sente une situation courante dans ces temps pourtant intens\u00e9ment crisiques (Syrie, Cor\u00e9e du Nord, etc.), on en tire le constat que le d\u00e9ploiement op\u00e9rationnel actuel de la flotte est <strong>dans une posture extraordinaire de repli<\/strong>, marqu\u00e9 par une sorte de ph\u00e9nom\u00e8ne auquel on pourrait donner le nom de \u00ab\u00a0contraction\u00a0\u00bb. Le <a href=\"http:\/\/www.dedefensa.org\/article\/le-spectre-de-la-contraction\">mot est emprunt\u00e9<\/a> \u00e0 James Howard Kunstler, pour d&rsquo;autres circonstances certes, <strong>mais dans un esprit qui n&rsquo;est pas \u00e0 notre estime fondamentalement diff\u00e9rent<\/strong>. Kunstler parle de l&rsquo;effondrement du Syst\u00e8me, nous faisons l&rsquo;hypoth\u00e8se que ces dispositions de l&rsquo;US Navy correspondent au processus d&rsquo;effondrement de la puissance US, dans sa dimension de projection des forces qui est (qui \u00e9tait) sa strat\u00e9gie centrale dans la situation de l&rsquo;h\u00e9g\u00e9monisme mondial des USA.<\/p>\n<\/p>\n<p><p>Il y a deux options : ou bien le Pentagone estime que le porte-avions n&rsquo;est plus le moyen privil\u00e9gi\u00e9 de la projection des forces, &ndash; ce qui est hautement douteux sinon absurde du point de vue de l&rsquo;US Navy qui continue son programme de grands porte-avions d&rsquo;attaque <a href=\"http:\/\/www.dedefensa.org\/article\/uss-ford-et-f-35-etat-de-la-catastrophe\">malgr\u00e9 d&rsquo;innombrables probl\u00e8mes<\/a> ; <strong>ou bien cette situation r\u00e9pond \u00e0 un r\u00e9flexe r\u00e9el de contraction de l&rsquo;h\u00e9g\u00e9monie US<\/strong>. Dans tous les cas, la r\u00e9partition actuelle des groupes de porte-avion, pour quelque raison que ce soit, <strong>n&rsquo;assure plus du tout la s\u00e9curit\u00e9 des voies de communication<\/strong>, non plus qu&rsquo;elles se situent dans l&rsquo;hypoth\u00e8se d&rsquo;une possibilit\u00e9 de confrontation. Il n&rsquo;y a aucun groupe de porte-avions en mode op\u00e9rationnel dans les mers bordant la Chine, dans l&rsquo;Oc\u00e9an Indien, voire m\u00eame dans l&rsquo;Oc\u00e9an Pacifique, et aucune pr\u00e9sence dans la zone atlantique\/Europe du Nord. La progression du groupe USS <em>Harry S. Truman <\/em>vers la Syrie est pour le moins marqu\u00e9e par une tendance \u00e0 lambiner qui rappelle <a href=\"http:\/\/www.dedefensa.org\/article\/le-porte-avions-volant\">d&rsquo;autres circonstances<\/a>, si effectivement le groupe n&rsquo;en est qu&rsquo;\u00e0 passer le d\u00e9troit de Gibraltar. (On l&rsquo;annon\u00e7ait au large de la Syrie pour la fin avril.)<\/p>\n<\/p>\n<blockquote>\n<p><p>Mais n&rsquo;y a-t-il pas finalement une hypoth\u00e8se strat\u00e9gique op\u00e9rationnelle plus concr\u00e8te, <strong>ce qui serait la repr\u00e9sentation op\u00e9rationnelle du ph\u00e9nom\u00e8ne de contraction<\/strong> ? Nous serions tent\u00e9s d&rsquo;y souscrire. Ce serait alors l&rsquo;id\u00e9e que les avanc\u00e9es technologiques strat\u00e9giques des Russes, annonc\u00e9es par Poutine dans son discours du 1<sup>er<\/sup>mars et que de nombreux signes montrent que les chefs militaires US les ont accept\u00e9es, <strong>repr\u00e9sentent d\u00e9sormais un risque trop grand pour exposer outremer les grands porte-avions d&rsquo;attaque<\/strong>, &ndash; cible r\u00eav\u00e9es pour ces syst\u00e8mes, &ndash; loin de la masse continentale US, hors de la protection d&rsquo;une riposte nucl\u00e9aires strat\u00e9gique instantan\u00e9e que les Russes ne voudraient pas risquer. (L&rsquo;un de ces syst\u00e8mes, le Kh-47M2 <em>Kinzhal<\/em>, est <a href=\"https:\/\/southfront.org\/restoring-strategic-balance-russias-invincible-nuclear-weapons\/\">d&rsquo;ores et d\u00e9j\u00e0<\/a> en service limit\u00e9 sur des avions MiG-31 \u00e9voluant \u00e0 tr\u00e8s haute vitesse et \u00e0 tr\u00e8s haute altitude.) <strong>Cela, c&rsquo;est bien une forme d&rsquo;effondrement de l&rsquo;h\u00e9g\u00e9monisme de la puissance militaire US<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<\/p>\n<p><p>Mis en ligne le 4 mai 2018 \u00e0 10H28<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Instantan\u00e9 de la \u00ab\u00a0contraction\u00a0\u00bb de la puissance US Le site SouthFront.org publie ce 3 mai 2018 une carte et une description de la localisation actuelle des dix groupes op\u00e9rationnels de porte-avions de l&rsquo;U.S. Navy. (Un groupe est form\u00e9 autour d&rsquo;un grand porte-avions d&rsquo;attaque, ou CVN [entre 90 000 et 100 000 tonnes, 70-80 a\u00e9ronefs], avec&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[18281,2631,2803,3318,6625,14029,3319,3704,3375,7437,3866,3611,2671],"class_list":["post-77917","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-continentale","tag-de","tag-effondrement","tag-force","tag-harry","tag-masse","tag-navy","tag-porte-avions","tag-projection","tag-repli","tag-s","tag-truman","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77917"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77917\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}