{"id":77935,"date":"2018-05-12T03:10:47","date_gmt":"2018-05-12T03:10:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/05\/12\/approches-initiatiques-de-la-prisonniere-du-desert\/"},"modified":"2018-05-12T03:10:47","modified_gmt":"2018-05-12T03:10:47","slug":"approches-initiatiques-de-la-prisonniere-du-desert","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/05\/12\/approches-initiatiques-de-la-prisonniere-du-desert\/","title":{"rendered":"Approches initiatiques de la prisonni\u00e8re du d\u00e9sert"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Approches initiatiques de la prisonni\u00e8re du d\u00e9sert<\/h2>\n<\/p>\n<p><p>C&rsquo;est une des plus belles exp\u00e9riences du cin\u00e9ma am\u00e9ricain, une des plus myst\u00e9rieuses, envo&ucirc;tantes, peut-\u00eatre du niveau de 2001 ou du m\u00e9cano de la General.<\/p>\n<\/p>\n<p><p>Ce film de l\u00e9gende, presque onirique, situ\u00e9 dans un espace et une temporalit\u00e9 incertains, est consid\u00e9r\u00e9 comme le plus important ou presque du cin\u00e9ma am\u00e9ricain, et c&rsquo;est justice. Tout en \u00e9tant un western, il d\u00e9passe infiniment le genre, \u00e0 moins qu&rsquo;il ne l&rsquo;accomplisse. N&rsquo;oublions pas que le tiers du film est une lettre lue par Vera Miles ! L&rsquo;aventure est d\u00e9j\u00e0 un r\u00e9cit \u00e9crit.<\/p>\n<\/p>\n<p><p>Infini du cowboy haineux avec un Wayne qui se surpasse, infini de l&rsquo;indien avec ce cruel chef myst\u00e9rieux et m\u00e9taphorique.<\/p>\n<\/p>\n<p><p>La prisonni\u00e8re c&rsquo;est d&rsquo;abord une arriv\u00e9e. On arrive \u00e0 une maison dont on repartira \u00e0 la fin. <\/p>\n<\/p>\n<p><p>La maison est noire au d\u00e9but, quand Martha en sort. Car la maison est une salle de cin\u00e9ma et dans ce film postmoderne on est d\u00e9j\u00e0 dans l&rsquo;apr\u00e8s-cin\u00e9ma. On r\u00e9fl\u00e9chit sur le western, ses indiens, son espace et ses h\u00e9ros, la fronti\u00e8re entre barbare et civilis\u00e9 (ce n&rsquo;est pas qu&rsquo;on ait lu Schuon mais&hellip;). C&rsquo;est un film sur l&rsquo;ouest am\u00e9ricain r\u00e9ifi\u00e9, devenu myst\u00e9rieusement plus myst\u00e9rieux que l&rsquo;orient romantique gr\u00e2ce \u00e0 Hollywood, \u00e0 l&rsquo;industrie des simulacres et \u00e0 des gens comme John Ford. Lieu de vie la maison va devenir lieu de mort et c&rsquo;est pr\u00e8s des tombes que le chef indien recueille la petite fille &#8211; que John Wayne confond avec sa s&oelig;ur a&icirc;n\u00e9e. La tombe devient un athanor, le lieu de naissance ou de renaissance de la gamine \u00e9pargn\u00e9e qui passe alors dans l&rsquo;autre dimension. J&rsquo;ai \u00e9tudi\u00e9 les cimeti\u00e8res de la chevalerie comme lieux d&rsquo;aventures initiatiques ; \u00e0 la m\u00eame \u00e9poque on a le cimeti\u00e8re de Moonfleet, le chef d&rsquo;&oelig;uvre gothique de Fritz Lang qui r\u00e8gle son compte au si\u00e8cle des Lumi\u00e8res et des gentlemen sp\u00e9culateurs.<\/p>\n<\/p>\n<p><p>La prisonni\u00e8re c&rsquo;est ensuite un enl\u00e8vement. Ici une digression.<\/p>\n<\/p>\n<p><p>On a dit que John Wayne est le p\u00e8re de Debbie et que pour cette raison&hellip; Nous ne le croyons pas. Wayne cherche l&rsquo;indien, son <em>match<\/em>, son fr\u00e8re &oelig;dipien (pourquoi ne tuerait-on que son p\u00e8re ?), pas cette enfant. Et la vengeance. Sorti de la soci\u00e9t\u00e9 des blancs civilis\u00e9s (il tue Futterman et ses sbires avec plus de satisfaction que les indiens) il est en lui-m\u00eame une l\u00e9gende, un barbare (le seul non-barbare est le sympathique mexicain qui refuse l&rsquo;argent du sang). Il sera plus respect\u00e9 par les indiens (voyez plus tard Jeremiah Johnson) que par le pasteur-policier Ward Bond qui r\u00eave de lui mettre la main au collet et sait son amour secret pour sa belle-s&oelig;ur. Moins raciste que vengeur, il regrette autant que le m\u00e9tis Martin l&rsquo;assassinat par l&rsquo;arm\u00e9e de la douce et grosse petite indienne qui les suivait gentiment. Son personnage \u00e9voque un OAS, un officier rebelle et extr\u00e9miste, un guerrier sauvage, pas le plouc raciste de la critique d&rsquo;\u00e9lite. Il est autant situ\u00e9 dans la quatri\u00e8me dimension que le Scar qu&rsquo;il poursuit et qui le surnomme Big Shoulder. John Wayne est avant tout un f\u00e9lon \u00e0 l&rsquo;ordre blanc. N&rsquo;oublions pas non plus qu&rsquo;il est le seul \u00e0 voir les corps atrocement mutil\u00e9s de ses gens. Il \u00e9pargne cette peine aux autres et cette sensibilit\u00e9 solitaire nourrit sa rage vengeresse. Notons que son lourd personnage (il porte le mal du monde) est all\u00e9g\u00e9 par son go&ucirc;t pour l&rsquo;humour noir et les sarcasmes, et aussi par le fait jamais soulev\u00e9 que les jeunes ne lui ob\u00e9issent jamais. Enfin il est en d\u00e9finitive moins le protecteur de Martin que le surveill\u00e9 de Martin. Martin sauve son \u00e2me.<\/p>\n<\/p>\n<p><p>Le gentil m\u00e9tis Martin (tout le cin\u00e9ma de Ford est obs\u00e9d\u00e9 par le m\u00e9tissage pr\u00e9sent et \u00e0 venir sur la fin)  la poursuit car lui aussi a \u00e9t\u00e9 victime de la barbarie enfant, et il a \u00e9t\u00e9 \u00e9lev\u00e9 par la famille de Debbie (le fr\u00e8re et la belle-s&oelig;ur amoureuse platonique d&rsquo;Ethan). On a \u00e9voqu\u00e9 le symbolisme des enl\u00e8vements dans notre livre sur le paganisme au cin\u00e9ma. <\/p>\n<\/p>\n<p><p>La Prisonni\u00e8re du d\u00e9sert, plus belle en fran\u00e7ais qu&rsquo;en anglais (the searchers ?), \u00e9voque donc comme telle ch\u00e8vre de monsieur Seguin le combat du jour et de la nuit, de la lumi\u00e8re et des t\u00e9n\u00e8bres. Le jour dans le film (et le livre) ne signifie pas n\u00e9cessairement le blanc et l&rsquo;obscur l&rsquo;indien : le jour ce serait le f\u00e9minin et l&rsquo;obscur le masculin avec son cort\u00e8ge de vices, de viols, de cruaut\u00e9s &ndash; et d&rsquo;enl\u00e8vements. A la fin John Wayne ne rentre pas dans la maison, il reste dehors. Le Yin triomphe et l&rsquo;on peut supposer que l&rsquo;ado Debbie passe d&rsquo;une soci\u00e9t\u00e9 de femmes indiennes \u00e0 une soci\u00e9t\u00e9 de femmes occidentales. Ce serait aussi cela le sujet de ce film infini et \u00e9trange : le triomphe de la f\u00e9minit\u00e9 sur une masculinit\u00e9 barbare et d\u00e9pass\u00e9e, bonne \u00e0 \u00eatre jet\u00e9e aux orties. Remarquons avec plusieurs chercheurs (et non <em>searchers<\/em> !) am\u00e9ricains que la jeune Debbie sort tr\u00e8s pure de son martyre, en bonne sant\u00e9 et m\u00eame \u00e9quilibr\u00e9e ! Rappelons ce qu&rsquo;on disait du Texas o&ugrave;, malgr\u00e9 Monument Valley \u00e0 l&rsquo;entr\u00e9e, est cens\u00e9 se passer l&rsquo;action :<\/p>\n<\/p>\n<p><p>&lsquo;General Phil Sheridan memorably remarked that if he owned hell and Texas, he&rsquo;d live in hell and rent out Texas&hellip;&rsquo;<\/p>\n<\/p>\n<p><p>Car dans le film am\u00e9ricain en g\u00e9n\u00e9ral l&rsquo;espace n&rsquo;est pas un cadeau. D\u00e9sert, neige, glace, chaleur, s\u00e9cheresse, privations, froid, etc. Et le temps qui s&rsquo;\u00e9coule et la pauvre Vera Miles (personnage constamment humili\u00e9 dans le film : elle est cocue et tient m\u00eame des propos racistes et d\u00e9sabus\u00e9s !) qui attend et voit son mariage interrompu de mani\u00e8re ridicule par le retour impromptu de Martin, lamentable de bout en bout avec elle : tout son influx amoureux est parti vers sa s&oelig;ur. Un complexe d&rsquo;Oreste en quelque sorte, bien dans la lign\u00e9e de cette mythologie grecque qui impr\u00e8gne tout le film.<\/p>\n<\/p>\n<p><p>L&rsquo;espace est infini dans le film. Certes l&rsquo;Am\u00e9rique est grande, mais c&rsquo;est surtout parce que l&rsquo;espace est circulaire. On tourne en rond comme dans un cirque, on tourne en rond autour de l&rsquo;axe du monde de Mircea Eliade, on tourne comme on sait toujours autour de Monument Valley, le mont Meru des hindous ou la &laquo; montagne magique &raquo; de John Ford. C&rsquo;est cette impr\u00e9gnation spatiale li\u00e9e au g\u00e9nie des indiens qui donne \u00e0 son cin\u00e9ma, qui donne \u00e0 son film sa port\u00e9e spirituelle incomparable. Et on n&rsquo;invente rien puisque cela est dans le texte :<\/p>\n<\/p>\n<p><p>&lsquo;We&rsquo;ll find just as sure as the turning of the earth.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Autrement dit nous tournerons en rond jusqu&rsquo;\u00e0 la fin du monde, nous tournerons en rond comme le monde. L&rsquo;\u00e9ternel retour si l&rsquo;on veut, ou une circularit\u00e9 ali\u00e9nante, celle que d\u00e9nonce Salomon dans l&rsquo;Eccl\u00e9siaste.<\/p>\n<\/p>\n<p><p>Mais continuons sur l&rsquo;enl\u00e8vement qui dure sept ans, tout un cycle. On a la sensation qu&rsquo;il vire \u00e0 l&rsquo;\u00e9ternit\u00e9, qu&rsquo;on passe dans une autre dimension, o&ugrave; le temps n&rsquo;importe plus (le temps touche l&rsquo;espace dit Gu\u00e9non citant Wagner). Les &laquo; chercheurs &raquo; am\u00e9ricains ont \u00e9voqu\u00e9 ce probl\u00e8me : on imagine que chercher quelqu&rsquo;un durant huit ans (et avec quel argent vol\u00e9, car John Wayne en a vraiment beaucoup !) semble une folie spatio-temporelle. L&rsquo;action durerait huit ans !<\/p>\n<\/p>\n<p><p>C&rsquo;est l\u00e0 qu&rsquo;on entre dans la folie ou dans la po\u00e9sie, la magie de la parabole. On va citer Borges et on va citer Bouvard et P\u00e9cuchet, histoire r\u00e9p\u00e9titive et circulaire, qui se d\u00e9roule pour rien sur des d\u00e9cennies. Borges a la cl\u00e9 comme toujours :<\/p>\n<\/p>\n<p><p>&laquo; C&rsquo;est pourquoi l&rsquo;\u00e9poque de Bouvard et P\u00e9cuchet penche pour l&rsquo;\u00e9ternit\u00e9; pour cette raison, les protagonistes ne meurent pas et ils continueront \u00e0 copier, pr\u00e8s de Caen, leur anachronique Sottisier&hellip; Pour cette raison, l&rsquo;&oelig;uvre regarde, en arri\u00e8re, les paraboles de Voltaire et de Swift et les Orientaux et, \u00e0 partir de l\u00e0, celles de Kafka. &quot;<\/p>\n<\/p>\n<p><p>Mais si le temps est vague dans le film, l&rsquo;espace g\u00e9ographique l&rsquo;est aussi. On ne sait jamais o&ugrave; l&rsquo;on est, entre l&rsquo;Utah, le Texas, l&rsquo;Arizona, les Colorado&hellip; Lisons le critique am\u00e9ricain Buscombe, traduit par les ordinateurs, qui confirme ce que nous \u00e9crivons bien mieux que ses \u00e9pigones Fran\u00e7ais :<\/p>\n<\/p>\n<p><p>&quot;La g\u00e9ographie est \u00e9galement un peu vague&quot; En ce qui concerne l&#8217;emplacement r\u00e9el du film, le voyage d&rsquo;Ethan est circulaire. Au d\u00e9but, nous le voyons sortir de la vall\u00e9e vers la maison de son fr\u00e8re \u00e0 Monument Valley; \u00e0 la fin, la porte des Jorgensen, \u00e9galement \u00e0 Monument Valley, se referme sur lui. Une deuxi\u00e8me unit\u00e9 est all\u00e9e \u00e0 Gunnison dans le Colorado pour filmer des sc\u00e8nes de neige pendant trois jours \u00e0 la fin de f\u00e9vrier 1955. La sc\u00e8ne o&ugrave; Ethan tue le buffle a \u00e9t\u00e9 film\u00e9e peu de temps apr\u00e8s dans le parc national Elk lsland, pr\u00e8s d&rsquo;Edmonton, Alberta, Canada &quot;<\/p>\n<\/p>\n<p><p>Ici tr\u00e8s brillamment ce m\u00eame critique am\u00e9ricain ajoute :<\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;impr\u00e9cision g\u00e9ographique a pour effet d&rsquo;augmenter notre sens des grandes distances qu&rsquo;Ethan et Marty doivent parcourir dans leur recherche, de m\u00eame que l&rsquo;impr\u00e9cision de la dur\u00e9e d\u00e9pens\u00e9e fait peser lourd sur eux &quot;&#8230;<\/p>\n<\/p>\n<p><p>Impr\u00e9cision, extension, vague. On retrouve cette impr\u00e9cision, cet infini dans le portrait moral des personnages que nous allons \u00e9tudier maintenant. Car qui est vraiment bon dans le film ? Ni les indiens, ni les blancs&hellip; Le mexicain et le m\u00e9tis Martin peut-\u00eatre ce qui nous rassurera quand nous aurons dit que m\u00e9tis signifie la sagesse en grec. Autre point de vue de Buscombe :<\/p>\n<\/p>\n<p><p>&laquo;Marty peut \u00eatre gauche, mal \u00e9duqu\u00e9, peu vers\u00e9 dans les affaires du c&oelig;ur; mais il est le centre moral du film, celui qui, tout autour de lui, est pouss\u00e9 par ses pr\u00e9jug\u00e9s, voit clairement que Debbie peut et doit \u00eatre sauv\u00e9e. &raquo;<\/p>\n<\/p>\n<p><p>Et de souligner le message antiraciste de Ford, pr\u00e9sent de toute mani\u00e8re dans presque tous ses derniers opus (la Taverne de l&rsquo;Irlandais, Sergent noir, Liberty Valance, les Cheyennes&hellip;) :<\/p>\n<\/p>\n<p><p>&laquo;Il y a une ironie puissante dans le fait que Marty est la seule personne m\u00e9tisse dans le film, un &laquo;demi-sang &raquo; dans le terme insultant d&rsquo;Ethan; Il vaut la peine de consid\u00e9rer quand des accusations de racisme sont lanc\u00e9es \u00e0 Ford. &quot;<\/p>\n<\/p>\n<p><p>L&rsquo;avenir m\u00e9tis du monde est alors bien visible dans d&rsquo;autres films de cette \u00e9poque : les fils du soleil, Spartacus, Tarass Boulba montrent ces peuples qui bougent et changent de terre. Comme l&rsquo;\u00e9crit quelque part Ignacio Ramonet, le western en tant que &laquo; genre raciste &raquo; fut condamn\u00e9 au moment de Bandoeng, en 1955.<\/p>\n<\/p>\n<p><p>On donne du racisme de Wayne une connotation sinistre, peut-\u00eatre li\u00e9e au combat des ann\u00e9es cinquante contre les restes de comportement sudiste en la mati\u00e8re ! Lui-m\u00eame est un sudiste rebelle, qui est parti avec un myst\u00e9rieux tr\u00e9sor de guerre, et son d\u00e9go&ucirc;t pour Debbie (l&rsquo;assassinerait-il vraiment ?) a aussi une dimension mythologie et symbolique. Le corps souill\u00e9 de la jeune enfant que la critique croit \u00eatre sa fille&hellip; N&rsquo;oublions que ce chevalier errant, sauvage dirait Gu\u00e9non, aime les fant\u00f4mes, pas les \u00eatres en chair. De m\u00eame cette curieuse enfant enlev\u00e9e par un d\u00e9mon n&rsquo;aura pas \u00e9t\u00e9 baptis\u00e9e, le souligne-t-on assez ?<\/p>\n<\/p>\n<p><p>Et Buscombe remarque encore :<\/p>\n<\/p>\n<p><p>&laquo; Le racisme d&rsquo;Ethan est une forme particuli\u00e8rement raciste de racisme &#8230; La souillure de l&rsquo;association avec les Indiens est si grande qu&rsquo;elle surmonte les liens de sang entre lui et sa ni\u00e8ce.<\/p>\n<\/p>\n<p><p>Seule la mort, pense-t-il, peut la purger d&rsquo;une telle contamination &quot;Marty, au contraire, le m\u00e9tis qui n&rsquo;a pas de liens de sang, est celui qui la rach\u00e8te &#8230;&quot;<\/p>\n<\/p>\n<p><p>Cette contamination est bien moins raciale que spirituelle selon nous. Debbie est poss\u00e9d\u00e9e par les d\u00e9mons, pense-t-il.<\/p>\n<\/p>\n<p><p>Mais si ce n&rsquo;\u00e9tait que cela on se dirait que ce film n&rsquo;est qu&rsquo;un cours d&rsquo;\u00e9ducation civique de plus. On est ici face \u00e0 une chef d&rsquo;&oelig;uvre, pas un documentaire p\u00e9dagogique.<\/p>\n<\/p>\n<p><p>Et c&rsquo;est de toute mati\u00e8re le m\u00e9tis Martin qui tue l&rsquo;indien Scar, qui semble avoir bien trait\u00e9 la plus jeune de ses \u00e9pouses (\u00e0 comparer avec les pauvres blanches enlev\u00e9es et devenues folles, qu&rsquo;on retrouve dans les Deux qui cavalent seuls, avec Widmark et James Stewart). Et l&rsquo;enfant a plus peur du p\u00e8re autoritaire Wayne que de Scar,  qui incarne l&rsquo;aventure sauvage, barbare peut-\u00eatre, mais exotique.<\/p>\n<\/p>\n<p><p>Si la dimension symbolique, magique et spatio-temporelle est grandiose, le bilan sociologique est plus modeste ! On ram\u00e8ne l&rsquo;enfant dans la soci\u00e9t\u00e9 des femmes, comme dit Gogol, o&ugrave; elle va \u00eatre reprogramm\u00e9e et reconditionn\u00e9e dans le moule consum\u00e9riste et biblique am\u00e9ricain. Le mariage de Martin promet d&rsquo;\u00eatre chaud et Wayne le maudit s&rsquo;en va lourdement. Le personnage qui incarne l&rsquo;autorit\u00e9 politique et militaire, et m\u00eame religieuse est couvert de ridicule &ndash; comme dans Fort Apache. Ward Bond est humili\u00e9 \u00e0 la m\u00eame \u00e9poque par les gauchistes de Johnny Guitare mais c&rsquo;est de bonne guerre ! Ici il est moqu\u00e9 et mis cul \u00e0 l&rsquo;air par le vieux r\u00e9publicain John Ford et toute sa bande. Le personnage le plus humili\u00e9 et le plus ingrat est celui de Vera Miles qui a des mots terribles contre Debbie. Cette actrice extraordinaire, qui perdit le r\u00f4le de Vertigo pour maternit\u00e9 (elle eut quatre enfants et elle est encore vivante, bravo Vera !) rayonnera trente ans plus tard dans le meilleur \u00e9pisode de la s\u00e9rie militaro-initiatique Magnum (croix de Lorraine, \u00e9pouse fran\u00e7aise, fant\u00f4mes \u00e0 la pelle et onirisme insulaire).<\/p>\n<\/p>\n<p><p>Mais nous fatiguons. Cette &oelig;uvre nous emm\u00e8nerait  aussi loin que l&rsquo;Odyss\u00e9e ou le chant VI de l&rsquo;En\u00e9ide. On laisse un beau mot de la fin \u00e0 un de ces critiques am\u00e9ricains n\u00e9s \u00e0 cheval et au grand air :<\/p>\n<\/p>\n<p><p> &lsquo;All Ford&rsquo;s films are about home: finding it, building it, losing it&hellip;&rsquo;<\/p>\n<\/p>\n<p><p>* Extrait du livre \u00e0 para&icirc;tre de Nicolas Bonnal (les grands westerns am\u00e9ricains : une approche traditionnelle (Editions Avatar)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Approches initiatiques de la prisonni\u00e8re du d\u00e9sert C&rsquo;est une des plus belles exp\u00e9riences du cin\u00e9ma am\u00e9ricain, une des plus myst\u00e9rieuses, envo&ucirc;tantes, peut-\u00eatre du niveau de 2001 ou du m\u00e9cano de la General. Ce film de l\u00e9gende, presque onirique, situ\u00e9 dans un espace et une temporalit\u00e9 incertains, est consid\u00e9r\u00e9 comme le plus important ou presque du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,14428,2651,4244,3961,2622,18292,4400,14328],"class_list":["post-77935","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-desert","tag-du","tag-ford","tag-john","tag-la","tag-prisonniere","tag-wayne","tag-western"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77935"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77935\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}