{"id":77970,"date":"2018-05-30T17:22:49","date_gmt":"2018-05-30T17:22:49","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/05\/30\/les-sanctions-ou-lisolement-emprisonne\/"},"modified":"2018-05-30T17:22:49","modified_gmt":"2018-05-30T17:22:49","slug":"les-sanctions-ou-lisolement-emprisonne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/05\/30\/les-sanctions-ou-lisolement-emprisonne\/","title":{"rendered":"Les sanctions, ou l&rsquo;isolement emprisonn\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Les sanctions, ou l&rsquo;isolement emprisonn\u00e9<\/h2>\n<\/p>\n<p><p>Cela commence \u00e0 se remarquer : aujourd&rsquo;hui, Poutine et Xi tiennent le r\u00f4le que tenaient hier Thatcher et Reagan ; d\u00e9fenseurs du march\u00e9 libre, de la libre concurrence, adversaire des protectionnismes sous-entendu \u00ab\u00a0archa\u00efques\u00a0\u00bb, &ndash; bref, des globalistes comme on le notait dans notre texte du <a href=\"http:\/\/www.dedefensa.org\/article\/poutine-face-a-la-mere-de-toutes-les-crises\">26 mai 2018<\/a>. Cela s&rsquo;est vu, pour Poutine, particuli\u00e8rement au Forum de Saint-Petersbourg (le SPIEF annuel, acronyme de son titre anglais).<\/p>\n<\/p>\n<p><p> &laquo; <em>Au deuxi\u00e8me jour du s\u00e9minaire, le pr\u00e9sident russe Poutine a fait une communication en forme de grave avertissement, et il s&rsquo;agit l\u00e0 d&rsquo;un sujet bien plus s&ucirc;r qui doit retenir toute notre attention. Le paradoxe, \u00e0 ranger exactement au c\u00f4t\u00e9 du paradoxe chinois, est que <strong>Poutine, comme Xi en <a href=\"http:\/\/www.dedefensa.org\/article\/vertigo-suite-chinoise\">d&rsquo;autres<\/a> <\/strong><strong><a href=\"http:\/\/www.dedefensa.org\/article\/the-economist-et-pekin-sur-la-meme-ligne-1\">circonstances<\/a>, s&rsquo;est affirm\u00e9 comme un ardent d\u00e9fenseur du libre-\u00e9change mondial et de la libre concurrence<\/strong>. C&rsquo;est-\u00e0-dire, pour les esprits simples en mati\u00e8re d&rsquo;\u00e9conomie, comme sont les n\u00f4tres ici \u00e0 dedefensa.org, que <strong>Poutine s&rsquo;est fait \u00ab\u00a0ardent d\u00e9fenseur\u00a0\u00bb de ce qu&rsquo;on a coutume de nommer \u00ab\u00a0globalisation\u00a0\u00bb <\/strong>(bien trop rapide cette identification, voir plus loin), toujours <strong>comme Xi et la Chine dans ces m\u00eames \u00ab\u00a0autres circonstances\u00a0\u00bb<\/strong><\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Cette introduction permet surtout de s&rsquo;\u00e9bahir de son contraire, &ndash; \u00e0 savoir qu&rsquo;en cette circonstance comme dans tant d&rsquo;autres, <strong>les USA, ceux de Reagan, sont lanc\u00e9s dans un formidable processus de fermeture, de \u00ab\u00a0protectionnisme\u00a0\u00bb de la plus \u00e9trange des formes<\/strong>. (Parlons moins de Thatcher puisque UK est en train de suivre la voie, \u00e9galement \u00e9trange pour son compte, d&rsquo;une sorte de dissolution, occup\u00e9e \u00e0 monter des fausses attaques chimiques comme succursale d&rsquo;une CIA hallucin\u00e9e par le <em>Russiagate <\/em>et \u00e0 s&rsquo;ab&icirc;mer dans un activisme soci\u00e9tal et multiethnique \u00e9chevel\u00e9s.)<\/p>\n<\/p>\n<p><p>C&rsquo;est \u00e0 cet \u00e9gard, bien entendu, que l&rsquo;interview de l&rsquo;investisseur et financier ind\u00e9pendant Jim Rogers, au m\u00eame SPIEF de la semaine derni\u00e8re, est int\u00e9ressant. Citoyen am\u00e9ricain pur sucre, financier fameux et audacieux, pur produit de Wall Street sans les contraintes des grands \u00e9tablissements, mais r\u00e9sidant \u00e0 Singapour, &ndash; et l&rsquo;on comprend vite pourquoi&#8230; Durant cette interview dont on voit bien que l&rsquo;intervieweur voulait l&rsquo;entra&icirc;ner sur des sujets divers par simple souci d&rsquo;\u00e9largir l&rsquo;information, Rogers ne cesse de revenir \u00e0 un seul sujet : <strong>l&rsquo;enfermement, l&rsquo;isolement, l&rsquo;auto-emprisonnement des USA <\/strong>dans sa folle \u00ab\u00a0politique de la sanction\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>&#8230; Car si nous nous plaignons <strong>\u00e0 juste titre de l'\u00a0\u00bbimp\u00e9rialisme juridique\u00a0\u00bb, ou \u00ab\u00a0h\u00e9g\u00e9monisme juridique\u00a0\u00bb des USA du fait des sanctions <\/strong>d&rsquo;une part, de la positon encore dominante du dollar (pour combien de temps ?), tout cela permettant la p\u00e9nalisation stup\u00e9fiante par les USA de soci\u00e9t\u00e9s \u00e9trang\u00e8res pour leurs contacts avec des pays \u00e9trangers mais \u00ab\u00a0sanctionn\u00e9s\u00a0\u00bb par les USA, <strong>il faut r\u00e9aliser ce paradoxe suicidaire que les USA ont encore plus de raisons de s&rsquo;en plaindre<\/strong>. C&rsquo;est effectivement ce que Rogers ne cesse de r\u00e9p\u00e9ter, absolument accabl\u00e9 par le comportement de son pays&#8230;<\/p>\n<\/p>\n<p><p>La \u00ab\u00a0politique de la sanction\u00a0\u00bb est devenue, aux USA, une sorte de chose-en-soi, d&rsquo;essence bureaucratique et s&rsquo;exer\u00e7ant sur le terrain intraitable de la loi aux USA, <strong>une chose-en-soi, une entit\u00e9 au fonctionnement automatique irr\u00e9sistible et qu&rsquo;on jugerait inarr\u00eatable et dans tous les cas incontr\u00f4lable<\/strong>. Cette entit\u00e9 de force est constitu\u00e9e d&rsquo;un tissu \u00e9pais sinon imp\u00e9n\u00e9trable dont les mailles sont constitu\u00e9es de forces diverses affectant des domaines tr\u00e8s divers (agences, d\u00e9partements, lobbies et groupements d&rsquo;int\u00e9r\u00eats, imp\u00e9ratifs de communication, forces de conformisme, terrorisation de la psychologie, etc.). <strong>L&rsquo;ensemble forme une sorte de prison absolument inviolable<\/strong>, une puissance que rien ne semble pouvoir investir et face \u00e0 laquelle le pouvoir politique semble compl\u00e8tement impuissant : <strong>il en est soit le complice, soit le prisonnier<\/strong>, selon les circonstances et selon le jugement qu&rsquo;on en a. <\/p>\n<\/p>\n<p><p>Ce ph\u00e9nom\u00e8ne, dont les diff\u00e9rents composants se sont d\u00e9velopp\u00e9s ind\u00e9pendamment les uns des autres, &ndash; ce qui a emp\u00each\u00e9 de distinguer la finalit\u00e9 de la dynamique, &ndash; s&rsquo;est soudain constitu\u00e9 en une v\u00e9ritable entit\u00e9, \u00e0 une vitesse extraordinaire et sans que personne ait pu, ni m\u00eame songer s&rsquo;y opposer. <strong>Il semble m\u00eame que fort peu d&rsquo;esprits mesurent la gravit\u00e9 de cette situation<\/strong>, et il faut des entretiens parcellaires de personnages ind\u00e9pendants et hors du circuit washingtonien, et qui exp\u00e9rimentent les effets de cette situation, comme l&rsquo;est un Jim Rogers, pour en prendre conscience.<\/p>\n<\/p>\n<p><p>On a d\u00e9crit ce ph\u00e9nom\u00e8ne de ce point de vue inhabituel des USA, parce <strong>qu&rsquo;il n&rsquo;est nullement habituel de consid\u00e9rer que la \u00ab\u00a0politique de sanction\u00a0\u00bb est un handicap pour les USA<\/strong>. Le jugement courant, normal et d&rsquo;ailleurs aussi bien compr\u00e9hensible que justifi\u00e9, est que cette \u00ab\u00a0politique de la sanction\u00a0\u00bb est vue essentiellement sinon exclusivement comme une arme exceptionnelle aux mains de la politique d&rsquo;h\u00e9g\u00e9monisme des USA, au nom du soi-disant exceptionnalisme de ce pays qui lui permettrait d&rsquo;intervenir unilat\u00e9ralement, ill\u00e9galement, etc., contre des pays tiers, sans aucun respect ni le moindre souci de leurs souverainet\u00e9s. <\/p>\n<\/p>\n<p><p>Mais l&rsquo;attitude et les observations de Rogers nous font r\u00e9aliser pleinement ce que nous devinons plus ou moins \u00e0 mesure que la situation appara&icirc;t dans toute sa structuration. La v\u00e9rit\u00e9-de-situation pourrait bien \u00eatre en effet, que la \u00ab\u00a0politique de sanction\u00a0\u00bb <strong>frappe d&rsquo;abord, et tr\u00e8s durement, les &Eacute;tats-Unis eux-m\u00eames <\/strong>par les imbroglios juridiques qu&rsquo;elle ne cesse de d\u00e9velopper. Peut-\u00eatre m\u00eame pourrait-on avancer l&rsquo;hypoth\u00e8se que cette \u00ab\u00a0politique de la sanction\u00a0\u00bb <strong>frappe les &Eacute;tats-Unis encore plus durement que les autres, ceux qu&rsquo;elle est cens\u00e9e frapper comme les \u00ab\u00a0amis\u00a0\u00bb qu&rsquo;elle frappe par effet indavertant<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>C&rsquo;est certainement l&rsquo;avis de Rogers, qui estime par exemple que l&rsquo;ouverture en cours vers la Cor\u00e9e du Nord, &ndash; qu&rsquo;on imaginerait devenir une \u00ab\u00a0proie\u00a0\u00bb d\u00e9lectable pour le capitalisme am\u00e9ricaniste si le \u00ab\u00a0mod\u00e8le libyen\u00a0\u00bb lui est \u00e9pargn\u00e9, &ndash; <strong>profitera essentiellement aux autres, et d&rsquo;abord aux Russes et aux Chinois<\/strong>, les entrepreneurs US \u00e9tant tous tenus par des contraintes de certaines sanctions qui, m\u00eame en cas de \u00ab\u00a0r\u00e9conciliation\u00a0\u00bb, <strong>resteront bureaucratiquement d&rsquo;application <\/strong>(comme dans le cas de l&rsquo;Iran apr\u00e8s la signature du trait\u00e9 en 2015).<\/p>\n<\/p>\n<\/blockquote>\n<p><p>On <a href=\"http:\/\/www.dedefensa.org\/article\/poutine-face-a-la-mere-de-toutes-les-crises\">a d\u00e9j\u00e0 vu<\/a> comment cette \u00ab\u00a0politique de la sanction\u00a0\u00bb permettait de servir de protectionnisme-qui-ne-dit-pas-son-nom pour les USA, donc comme une sorte d&rsquo;avantage pour les int\u00e9r\u00eats de cette puissance m\u00eame si cette position donne aux USA une position paradoxale d&rsquo;adversaire du libre-\u00e9change (de la \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/globalisation-mondialisation-1\">mondialisation<\/a>\u00a0\u00bb plut\u00f4t que de la \u00ab\u00a0globalisation\u00a0\u00bb). <strong>Mais il s&rsquo;av\u00e8re que ce \u00ab\u00a0protectionnisme\u00a0\u00bb dissimul\u00e9 constitue \u00e9galement un \u00ab\u00a0isolationnisme\u00a0\u00bb qui, lui, travaille contre les int\u00e9r\u00eats des USA<\/strong>. Cet \u00ab\u00a0isolationnisme\u00a0\u00bb n&rsquo;est pas la position historique classique des USA, celui d&rsquo;une puissance forte, s&ucirc;re d&rsquo;elle-m\u00eame et auto-suffisante comme ce pays fut aux XIX\u00e8me et au d\u00e9but du XX\u00e8me si\u00e8cle, <strong>mais celui accidentel et destructeur<\/strong>, d&rsquo;une puissance en d\u00e9clin sinon en cours d&rsquo;effondrement <strong>que ses activit\u00e9s nihilistes isolent de plus en plus du reste du monde <\/strong>alors que les structures \u00ab\u00a0globalis\u00e9es\u00a0\u00bbqyu&rsquo;elle a elle-m\u00eame impos\u00e9es  n\u00e9cessitent une coop\u00e9ration et un commerce intenses \u00e0 tous les acteurs.<\/p>\n<\/p>\n<p><p>Cette prise de conscience que suscitent les constats d&rsquo;un homme d&rsquo;action du secteur financier international qu&rsquo;est Rogers, accentue une situation g\u00e9n\u00e9ral compl\u00e8tement paradoxale o&ugrave; la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politique-Syst\u00e8me<\/a> d\u00e9velopp\u00e9 principalement par les USA, o&ugrave; le comportement hypomaniaque-narcissique des \u00e9lites (\u00e0 l&rsquo;image sinon \u00e0 l&rsquo;exemple de Trump), etc., ont plong\u00e9 les relations internationales d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale dans un d\u00e9sordre complet et dans la plus compl\u00e8te incontr\u00f4labilit\u00e9. Ainsi observe-t-on tous ces points compl\u00e8tement contradictoires :<\/p>\n<\/p>\n<p><p>&bull; La Chine et la Russie, deux pays dot\u00e9s d&rsquo;un gouvernement central fort, tr\u00e8s attentives \u00e0 la souverainet\u00e9, ayant conserv\u00e9 certains aspects de la discipline communiste, sont devenues <strong>les promoteurs les plus z\u00e9l\u00e9s du libre-\u00e9change et de la libre-concurrence<\/strong>.<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;Europe-UE, compl\u00e8tement construite sur le n\u00e9o-lib\u00e9ralisme et la doctrine \u00e9conomiste et commerciale qui va avec, li\u00e9e en position de vassale d&rsquo;une fa\u00e7on ind\u00e9cente, comme jamais vue dans l&rsquo;Histoire \u00e0 ce niveau de puissance, aux USA qui ne cessent de d\u00e9velopper une \u00ab\u00a0politique de sanction\u00a0\u00bb ; laquelle politique <strong>ne cesse de restreindre le commerce et la concurrence et frappe autant sinon plus les alli\u00e9s de l&rsquo;Europe-UE <\/strong>que les cibles que sont l&rsquo;Iran, la Russie, \u00e9ventuellement la Chine, et tant d&rsquo;autres.<\/p>\n<\/p>\n<p><p>&bull; Le pays-souverain, qui se pr\u00e9tend l'\u00a0\u00bbempire du monde\u00a0\u00bb, inventeur et z\u00e9l\u00e9 partisan de la globalisation, imposant partout cette doctrine, qui se contracte en un emprisonnement bureaucratique et l\u00e9gislatif imposant de plus en plus visiblement un isolationnisme qui se r\u00e9duit \u00e0 un isolement <strong>aberrant par rapport \u00e0 ce que sont ses pr\u00e9tentions imp\u00e9riales et h\u00e9g\u00e9monistes<\/strong>.<\/p>\n<\/p>\n<p><p>&bull; Bref, le Syst\u00e8me en action, en pleine surpuissance productrice d&rsquo;autodestruction,<strong>ou comment transformer l&rsquo;or en vil plomb <\/strong>&#8230;<\/p>\n<\/p>\n<p><p>Jim Rogers, investisseur ind\u00e9pendant fameux, install\u00e9 \u00e0 Singapour, est interrog\u00e9 par <em>Sputink<\/em>. L&rsquo;interview, qui a paru le <a href=\"https:\/\/sputniknews.com\/analysis\/201805281064880672-china-iran-russia-spief-trade-investment\/?utm_source=adfox_site_41917&#038;utm_medium=adfox_banner_2537079&#038;utm_campaign=adfox_campaign_626010&#038;ues=1\">28 mai 2018<\/a>, a eu lieu en marge du SPIEF de Saint-Petersbourg, auquel bien s&ucirc;r Rogers participait. Les sources officielles russes disent que tous les recoprds ont \u00e9t\u00e9 battus \u00e0 cette \u00e9dition du SPIEF : 550 contrats pass\u00e9s par les participants pour plus de $38 milliards <\/p>\n<\/p>\n<p><h4><em>dedefensa.org<\/em><\/h4>\n<\/p>\n<p><p>__________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">&laquo; <em>L&rsquo;Am\u00e9rique se ferme de plus en plus<\/em>&#8230; &raquo;<\/h2>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Nous voyons de nouveaux d\u00e9veloppements avec les relations entre les &Eacute;tats-Unis et la Cor\u00e9e du Nord, nous voyons des annonces de politiciens, pour vous en tant qu&rsquo;homme d&rsquo;affaires quel genre d&rsquo;impact cela a-t-il ? Dans une de vos entrevues, vous avez mentionn\u00e9 que vous vouliez faire affaire avec la Cor\u00e9e du Nord, \u00e0 quel point cela est-il possible ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>J&rsquo;aimerais investir en Cor\u00e9e du Nord mais c&rsquo;est impossible pour les Am\u00e9ricains ou pratiquement impossible pour les Am\u00e9ricains. Cela signifie simplement que les Russes, les Chinois et d&rsquo;autres personnes qui peuvent faire des affaires en Cor\u00e9e du Nord vont pouvoir saisir de belles opportunit\u00e9s<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>De quel genre d&rsquo;entreprise s&rsquo;agit-il ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>Tout ce que vous pouvez imaginer. Ils ont besoin de nappes, de savon, d&rsquo;\u00e9lectricit\u00e9, ils ont besoin de tout, tout ce que vous pouvez faire, vous pouvez faire fortune en Cor\u00e9e du Nord<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Il y a une grosse d\u00e9l\u00e9gation am\u00e9ricaine au Forum \u00e9conomique de Saint-P\u00e9tersbourg et les organisateurs nous disent que, contrairement aux pr\u00e9c\u00e9dentes administrations am\u00e9ricaines, cette fois-ci les responsables am\u00e9ricains encouragent les PDG am\u00e9ricains \u00e0 participer \u00e0 l&rsquo;\u00e9v\u00e9nement. Cela signifie-t-il que nous allons voir des changements dans les relations am\u00e9ricano-russes, \u00e0 la fois commerciales et politiques ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>J&rsquo;esp\u00e8re que les relations iront mieux avec la Russie et les &Eacute;tats-Unis. C&rsquo;est de la folie, une folie que la Russie et les &Eacute;tats-Unis ne soient pas amis, ils devraient l&rsquo;\u00eatre et devraient travailler ensemble.<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Quelles sont les principales tendances mondiales que nous voyons sur les march\u00e9s en ce moment ? Quelles sont les grandes choses \u00e0 surveiller ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>Eh bien, malheureusement, je suis un citoyen am\u00e9ricain et je vois que l&rsquo;Am\u00e9rique pousse la Chine et la Russie ensemble, l&rsquo;Am\u00e9rique pousse la Chine et l&rsquo;Iran ensemble, l&rsquo;Am\u00e9rique pousse la Chine, l&rsquo;Iran, la Russie ensemble et cela am\u00e8ne l&rsquo;Am\u00e9rique elle-m\u00eame \u00e0 se retirer de certains pays dans le monde. Je n&rsquo;aime pas particuli\u00e8rement \u00e7a parce que je suis Am\u00e9ricain et que je veux voyager, investir et participer partout, et cela devient de plus en plus difficile pour les Am\u00e9ricains<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Mais il semble que vous passiez beaucoup de temps en Asie et que vous vous concentriez sur l&rsquo;Asie : est-il possible de le faire dans d&rsquo;autres pays d&rsquo;Asie ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>Je vis \u00e0 Singapour, donc je suis s&ucirc;r qu&rsquo;il y a beaucoup d&rsquo;opportunit\u00e9s en Asie, pourtant il y en a de moins en moins pour l&rsquo;Am\u00e9rique parce que l&rsquo;Am\u00e9rique est en train de se quereller avec de plus en plus de pays. C&rsquo;est aussi simple que \u00e7a. Le monde est grand et il reste beaucoup de choses \u00e0 faire, et c&rsquo;est une honte de voir l&rsquo;Am\u00e9rique s&rsquo;interdire d&rsquo;avoir des relations avec tant de pays<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Est-ce principalement \u00e0 cause de la r\u00e9glementation ou y a-t-il autre chose en jeu ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>R\u00e8glements, sanctions, interdictions &ndash; tout ce que vous pouvez imaginer ! Il est pratiquement impossible pour un Am\u00e9ricain de dire le mot Iran, si vous l&rsquo;\u00e9pelez ils vont vous mettre en prison, de m\u00eame pour la Russie, cela devient de plus en plus difficile \u00e0 cause des sanctions. La Chine, ce n&rsquo;est pas encore \u00e0 ce stade mais cela devient de plus en plus difficile. Ce n&rsquo;est vraiment pas bon pour l&rsquo;Am\u00e9rique, ce n&rsquo;est pas bon pour le monde<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Ce n&rsquo;est pas la premi\u00e8re fois que vous participez au forum de Saint-P\u00e9tersbourg, quelles sont les sujets principaux que vous avez not\u00e9s et quelles sont les choses \u00e0 surveiller lors de cet \u00e9v\u00e9nement ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>Ce que j&rsquo;ai remarqu\u00e9 cette ann\u00e9e, peut-\u00eatre parce que je suis Am\u00e9ricain, c&rsquo;est qu&rsquo;on parle beaucoup plus des sanctions, des guerres commerciales et d&rsquo;autres choses de ce genre, des obstacles \u00e0 l&rsquo;\u00e9conomie mondiale. Je n&rsquo;ai pas entendu parler dans ce sens les ann\u00e9es pr\u00e9c\u00e9dentes, peut-\u00eatre parce que cette tendance n&rsquo;existait pas \u00e0 ce point, pas de mani\u00e8re significative dans tous les cas ; m\u00eame l&rsquo;ann\u00e9e derni\u00e8re, tout le monde parlait de s&rsquo;ouvrir de plus en plus, mais maintenant l&rsquo;Am\u00e9rique se ferme de plus en plus<\/em>. &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Cela ne semble-t-il pas \u00e9trange que les &Eacute;tats-Unis d\u00e9veloppent de plus en plus de r\u00e9glementations et plus de restrictions et que d&rsquo;autres pays demandent de plus en plus de libert\u00e9 pour les march\u00e9s ?<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>Bien entendu ! L&rsquo;Am\u00e9rique est para&icirc;t-il \u00ab\u00a0the land of the free\u00a0\u00bb et nous sommes de moins en moins libres, je veux dire, vous en tant que Russe pouvez faire tout ce que vous voulez dans le monde. Je suis emp\u00each\u00e9 de travailler dans de nombreux pays par les Am\u00e9ricains, non par ces pays mais par les Am\u00e9ricains.<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Spoutnik<\/em><\/strong><strong> :<\/strong>&laquo; <em>Y a-t-il une chance d&rsquo;avoir un dialogue avec les politiciens ? M\u00eame ici, il y a des repr\u00e9sentants du gouvernement am\u00e9ricain au forum de cette ann\u00e9e&#8230;<\/em> &raquo;<\/p>\n<\/p>\n<p><p><strong><em>Jim Rogers<\/em><\/strong> : &laquo; <em>J&rsquo;esp\u00e8re qu&rsquo;il y a l&rsquo;un ou l&rsquo;autre qui en parle, qui essaie de dire quelque chose de constructif. Je ne vis plus aux &Eacute;tats-Unis, alors c&rsquo;est plus compliqu\u00e9 pour moi, mais j&rsquo;esp\u00e8re qu&rsquo;on parle de ce ph\u00e9nom\u00e8ne de fermeture et qu&rsquo;on \u00e9coute. Mais jusqu&rsquo;\u00e0 pr\u00e9sent, il me semble que personne n&rsquo;\u00e9coute, et je vous dirais que je suis Am\u00e9ricain et que je n&rsquo;aime pas \u00eatre emp\u00eacher de travailler avec d&rsquo;autres pays par mon propre gouvernement<\/em>. &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les sanctions, ou l&rsquo;isolement emprisonn\u00e9 Cela commence \u00e0 se remarquer : aujourd&rsquo;hui, Poutine et Xi tiennent le r\u00f4le que tenaient hier Thatcher et Reagan ; d\u00e9fenseurs du march\u00e9 libre, de la libre concurrence, adversaire des protectionnismes sous-entendu \u00ab\u00a0archa\u00efques\u00a0\u00bb, &ndash; bref, des globalistes comme on le notait dans notre texte du 26 mai 2018. Cela s&rsquo;est&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[5270,1242,2819,1097,12367,2859,5646,13912],"class_list":["post-77970","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-interview","tag-isolationnisme","tag-jim","tag-protectionnisme","tag-rogers","tag-saint-petersbourg","tag-sanctions","tag-spief"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77970"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77970\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}