{"id":77995,"date":"2018-06-12T17:24:54","date_gmt":"2018-06-12T17:24:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/06\/12\/une-loi-scelerate-pour-le-temps-des-scelerats\/"},"modified":"2018-06-12T17:24:54","modified_gmt":"2018-06-12T17:24:54","slug":"une-loi-scelerate-pour-le-temps-des-scelerats","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/06\/12\/une-loi-scelerate-pour-le-temps-des-scelerats\/","title":{"rendered":"Une \u201cloi sc\u00e9l\u00e9rate\u201d pour le temps des sc\u00e9l\u00e9rats"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">Une \u00ab\u00a0loi sc\u00e9l\u00e9rate\u00a0\u00bb pour le temps des sc\u00e9l\u00e9rats<\/h2>\n<\/p>\n<p><p>On a d\u00e9battu au Parlement, en France, sur la loi commun\u00e9ment d\u00e9sign\u00e9e comme anti-<em>FakeNews<\/em>. La fortune de cette expression en <em>international english<\/em>, &ndash; qui n&rsquo;est pas celui de Shakespeare, &ndash; est telle, puisqu&#8217;employ\u00e9e par ceux qui suivent le train de la <em>FakeInformation<\/em>contre les dissidents qui tentent d&rsquo;endiguer cette mar\u00e9e, qu&rsquo;elle est devenue une sorte d&#8217;embl\u00e8me de notre temps o&ugrave; le mensonge est devenu une <em>narrative <\/em>officielle dont la logique entra&icirc;ne <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-le-determinisme-narrativiste\">un d\u00e9terminisme<\/a>de la n\u00e9gation des <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9s-de-situation<\/a>. On a donc fait une loi contre tout ce qui s&rsquo;\u00e9carte des sentiers battus par la parole convenue. C&rsquo;est une \u00ab\u00a0loi sc\u00e9l\u00e9rate\u00a0\u00bb qui, sans v\u00e9ritable surprise, correspond compl\u00e8tement \u00e0 son temps officiel : nos repr\u00e9sentants officiels, nos gouvernements, constituent \u00ab\u00a0le temps des sc\u00e9l\u00e9rats\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Devant un auditoire quasiment vide et une ministre de la culture venue d&rsquo;une maison d&rsquo;\u00e9dition cr\u00e9\u00e9e par son p\u00e8re pour d\u00e9fendre les paroles de dissidents et qui elle-m\u00eame entend remettre les dissidents dans les <em>Fake-<\/em>chemins, M\u00e9lenchon <a href=\"https:\/\/www.youtube.com\/watch?time_continue=11&#038;v=tY9rtRKo4J4\">a fait un discours<\/a>\u00e0 la fois sur un ton mesur\u00e9 et dans un style peu courant pour sa qualit\u00e9, qui m\u00e9rite largement son audition. M\u00eame s&rsquo;il affirme que cette loi n&rsquo;est pas due \u00e0 une vindicte personnelle du pr\u00e9sident, ce dont nous doutons, M\u00e9lenchon a superbement plaid\u00e9 contre cette \u00ab\u00a0loi sc\u00e9l\u00e9rate\u00a0\u00bb. Depuis il<a href=\"https:\/\/melenchon.fr\/2018\/06\/11\/la-loi-fake-news-etait-une-fake-news\/\">nous a appris<\/a>qu&rsquo;il y avait eu une sorte de coup fourr\u00e9 peut-\u00eatre bien d&ugrave; \u00e0 la g\u00eane grandissante de ce pouvoir devant cette loi et le d\u00e9bat sur la loi ayant pris trop de temps, la loi n&rsquo;avait pu \u00eatre vot\u00e9e dans un tapage m\u00e9diatique soudain r\u00e9duit au silence de la m\u00e9ditation&#8230; On y reviendra&#8230;<\/p>\n<\/p>\n<p><p>&laquo; <em>Grosse agitation m\u00e9diatique et m\u00eame la une du Figaro et du Monde. Mazette ! Puis Pchitttttt ! Plus rien. Certes, la loi a \u00e9t\u00e9 discut\u00e9e. Mais elle n&rsquo;a pas \u00e9t\u00e9 vot\u00e9e. Stupeur ! Les m\u00e9dias qui ont senti le vent du boulet sont rentr\u00e9s dans leur coquille sans un mot, trop contents d&rsquo;avoir \u00e9chapp\u00e9 aux d\u00e9lires des macronistes. Officiellement, conform\u00e9ment aux normes habituelles de la d\u00e9sastreuse organisation des d\u00e9bats \u00e0 l&rsquo;Assembl\u00e9e, le temps aura \u00e9t\u00e9 insuffisant pour aller au bout de la proc\u00e9dure. En effet, il s&rsquo;agissait de la niche parlementaire de la R\u00e9publique en Marche. Ce temps sp\u00e9cial a une organisation sp\u00e9ciale : on ne peut d\u00e9battre au-del\u00e0 d&rsquo;une heure du matin. C&rsquo;est comme \u00e7a que notre proposition de \u00ab\u00a0loi pour le droit de mourir dans la dignit\u00e9\u00a0\u00bba \u00e9t\u00e9 \u00e9vacu\u00e9e. &Agrave; une heure du matin, il restait une foule d&rsquo;amendements. Tout fut clos. Malaise ! &Eacute;trange quand m\u00eame, non ? Sont-ils nuls \u00e0 ce point ? &Ccedil;a parait curieux.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Aussit\u00f4t a fleuri une hypoth\u00e8se. Comme les macronistes ont compris que le toll\u00e9 sur le sujet n&rsquo;allait pas d\u00e9cro&icirc;tre, ils ont eux-m\u00eames organis\u00e9 l&rsquo;impasse. En effet, s&rsquo;ils tenaient tant que \u00e7a \u00e0 ce texte, pourquoi ne pas l&rsquo;avoir mis en premier plut\u00f4t que celui sur l&rsquo;interdiction des portables \u00e0 l&rsquo;\u00e9cole ? Cette organisation des d\u00e9bats aurait donc eu pour objet de permettre l&rsquo;\u00e9limination du texte sans le dire. D&rsquo;o&ugrave; le silence des m\u00e9dias eux-m\u00eames le lendemain de cet exploit grotesque. Conclusion, ils se sont moqu\u00e9s de nous. Moqu\u00e9s du Parlement. Ils nous ont contraints \u00e0 passer une journ\u00e9e et un d\u00e9bat sans objet. Ne reste que le plaisir de les avoir ridiculis\u00e9s dans l&rsquo;argumentation et de les voir d\u00e9truire eux-m\u00eames leur travail initial<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, le ph\u00e9nom\u00e8ne <em>FakeNews<\/em>m\u00e9rite beaucoup de commentaires dans la mesure de son extraordinaire singularit\u00e9. En effet, cette \u00ab\u00a0loi sc\u00e9l\u00e9rate\u00a0\u00bb a au moins, du fait de son ambition inepte et des conditions insens\u00e9s de son fonctionnement, suscit\u00e9 un nombre \u00e9lev\u00e9 de commentaires pour mettre en \u00e9vidence son absurdit\u00e9. Une \u00ab\u00a0loi sc\u00e9l\u00e9rate\u00a0\u00bb pour un \u00ab\u00a0temps des sc\u00e9l\u00e9rats\u00a0\u00bb ? Plus simplement, une loi de notre temps.<\/p>\n<\/p>\n<p><p>Ci-dessous, un texte de Jean Bricmont, publi\u00e9 sur RT le <a href=\"https:\/\/francais.rt.com\/opinions\/51373-anastasie-au-pays-lumieres\">7 juin 2018<\/a>(Docteur en sciences et essayiste belge, Jean Bricmont est professeur \u00e0 l&rsquo;Universit\u00e9 catholique de Louvain. Il est auteur et co-auteur de plusieurs ouvrages dont La r\u00e9publique des censeurs, Impostures intellectuelles [avec Alan Sokal].)<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d;font-size:2em;\">Anastasie au pays des Lumi\u00e8res <\/h2>\n<\/p>\n<blockquote>\n<p><p>La loi sur les fausses informations port\u00e9e par le gouvernement Philippe va loin. Entre la suppression du dialogue et le r\u00e8gne du subjectivisme g\u00e9n\u00e9ralis\u00e9, l&rsquo;essayiste Jean Bricmont estime qu&rsquo;une telle mesure m\u00e8nera \u00e0 un &laquo; totalitarisme de la na\u00efvet\u00e9 &raquo;.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Le gouvernement a d\u00e9cid\u00e9 d&rsquo;introduire une nouvelle loi pour combattre la diffusion de fausses informations (&laquo; fake news &raquo; en franglais).  Il existe d\u00e9j\u00e0 dans la loi sur la presse de 1881 des dispositions r\u00e9primant l&rsquo;insulte, la diffamation et le fait de provoquer des paniques artificielles. Mais aujourd&rsquo;hui le gouvernement veut aller beaucoup plus loin, puisqu&rsquo;il d\u00e9finit les &laquo; fausses informations &raquo; comme une &laquo; all\u00e9gation ou imputation d&rsquo;un fait d\u00e9pourvue d&rsquo;\u00e9l\u00e9ments v\u00e9rifiables de nature \u00e0 la rendre vraisemblable &raquo;. Ce projet va en effet tr\u00e8s loin. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d;font-size:1.25em;\"><strong>Exit<\/strong><\/h3>\n<\/p>\n<p><p>Tout d&rsquo;abord, un sceptique pourrait demander quels sont les &laquo; \u00e9l\u00e9ments v\u00e9rifiables &raquo; prouvant l&rsquo;existence de Dieu, de la vie apr\u00e8s la mort ou de l&rsquo;efficacit\u00e9 des pri\u00e8res. Exit les religions. Qu&rsquo;en est-il des &laquo; \u00e9l\u00e9ments v\u00e9rifiables &raquo; rendant vraisemblable l&rsquo;efficacit\u00e9 de l&rsquo;hom\u00e9opathie, ou les pr\u00e9dictions de l&rsquo;astrologie ? Exit les pseudo-sciences. Bien avant Michel Onfray, de nombreux scientifiques se sont pos\u00e9s des questions sur les &laquo; \u00e9l\u00e9ments v\u00e9rifiables &raquo; qui justifieraient la psychanalyse et, en g\u00e9n\u00e9ral, ils n&rsquo;en ont pas trouv\u00e9s. Faut-il aussi la bannir au nom de la lutte contre les fausses nouvelles ?<\/p>\n<\/p>\n<p><p>Mais que faire alors du plus gros de la philosophie fran\u00e7aise contemporaine dont le plus illustres repr\u00e9sentants (Derrida, Foucault, Althusser, Badiou, Bernard-Henri L\u00e9vy et m\u00eame Bouveresse) ont eu en g\u00e9n\u00e9ral une attitude favorable \u00e0 la psychanalyse et qui, m\u00eame quand ils \u00e9taient critiques vis-\u00e0-vis de celle-ci (Deleuze et Guattari) ne l&rsquo;\u00e9taient pas sur la base d&rsquo;absence \u00e9l\u00e9ments v\u00e9rifiables en sa faveur mais en proposant d&rsquo;autres th\u00e9ories tout aussi peu justifi\u00e9es ?<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est pas tout. Que faire des th\u00e9ories scientifiques qui sont avanc\u00e9es sans s&rsquo;appuyer sur des \u00e9l\u00e9ments v\u00e9rifiables ? On peut penser \u00e0 la th\u00e9orie des cordes en physique ou \u00e0 diverses hypoth\u00e8ses en cosmologie.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d;font-size:1.25em;\"><strong>Impossibilit\u00e9 du dialogue <\/strong><\/h3>\n<\/p>\n<p><p>Finalement, qu&rsquo;en est-il de la presse &laquo; mainstream &raquo; ? Dans toutes les affaires r\u00e9centes (affaire Skripal, usage de gaz en Syrie, &laquo;meurtre&raquo; en Ukraine du journaliste russe Babtchenko, ou encore responsabilit\u00e9 du tir de missile ayant abattu un avion malaisien au-dessus de l&rsquo;Ukraine en juillet 2014), il y a un conflit entre le point de vue dominant en Occident et le point de vue russe ou malaisien ou syrien, lesquels sont partag\u00e9s par une bonne partie du reste du monde.<\/p>\n<\/p>\n<p><p>On en est peut-\u00eatre plus \u00e0 &laquo; v\u00e9rit\u00e9 en de\u00e7\u00e0 des Pyr\u00e9n\u00e9es, erreur au-del\u00e0 &raquo;, mais au moins \u00e0 &laquo; v\u00e9rit\u00e9 d&rsquo;un c\u00f4t\u00e9 de la M\u00e9diterran\u00e9e, erreur de l&rsquo;autre &raquo; ou &laquo; v\u00e9rit\u00e9 en de\u00e7\u00e0 de la fronti\u00e8re russo-polonaise, erreur au-del\u00e0 &raquo; ce qui, en quelques si\u00e8cles, ne nous a pas fait fort avancer vers l&rsquo;universel. La seule fa\u00e7on de r\u00e9soudre nos diff\u00e9rents avec le reste du monde, c&rsquo;est la discussion libre. Comme la loi contre les fausses nouvelles a, semble-t-il, pour but principal de contrer ce que le gouvernement consid\u00e8re comme de la propagande pro-russe, il y a fort \u00e0 craindre qu&rsquo;elle ne fasse que renforcer la fronti\u00e8re mentale &laquo; russo-polonaise &raquo;.<\/p>\n<\/p>\n<p><p>Il a suffi que le journaliste un peu h\u00e9t\u00e9rodoxe Andr\u00e9 Bercoff pose des questions \u00e0 propos du sauvetage providentiel de l&rsquo;enfant suspendu \u00e0 un balcon par Mamadou Gassama pour que le CSA soit saisi, qu&rsquo;il soit mis en accusation par Laurent Joffrin pour &laquo; susciter des doutes &raquo; et quasiment convoqu\u00e9 pour se justifier de l&rsquo;accusation de &laquo; complotisme &raquo; devant son (en principe) confr\u00e8re Jean-Marc Morandini.<\/p>\n<\/p>\n<p><p>D&rsquo;abord il est assez extraordinaire de reprocher \u00e0 un journaliste le fait de poser des questions et d&rsquo;inciter au doute. Ind\u00e9pendamment de cette affaire de sauvetage, il me semblait na\u00efvement que c&rsquo;\u00e9tait justement cela une des fonctions principales du journalisme. Et que la d\u00e9marche rationnelle et scientifique pourrait se r\u00e9sumer ainsi : de m\u00eame qu&rsquo;il vaut mieux avoir dix coupables en libert\u00e9 qu&rsquo;un innocent en prison, il vaut mieux avoir dix doutes excessifs qu&rsquo;un dogme infond\u00e9. <\/p>\n<\/p>\n<p><p>Par ailleurs, il est vrai que ce que les m\u00e9dias dominants appellent les &laquo;th\u00e9ories du complot&raquo;, et qui vont d&rsquo;interrogations l\u00e9gitimes sur les r\u00e9cits m\u00e9diatiques et sur les assertions gouvernementales aux sp\u00e9culations les plus fantaisistes, prolif\u00e8rent sur les r\u00e9seaux sociaux. Mais existe-t-il une seule personne sens\u00e9e qui peut croire que cette fa\u00e7on de traiter monsieur Bercoff va en quoi que ce soit faire reculer cette prolif\u00e9ration ?<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d;font-size:1.25em;\"><strong>Totalitarisme de la na\u00efvet\u00e9<\/strong><\/h3>\n<\/p>\n<p><p>Finalement, la ministre de la culture, madame Fran\u00e7oise Nyssen, souhaite faire de l&rsquo;audiovisuel<strong>public<\/strong>un m\u00e9dia engag\u00e9 qui permettra de combattre les id\u00e9es &laquo; hautement r\u00e9actionnaires &raquo; des Fran\u00e7ais, entre autre concernant la diversit\u00e9. Tout d&rsquo;abord, ce que LREM consid\u00e8re comme r\u00e9actionnaire (d\u00e9fendre les services publics ou la souverainet\u00e9 nationale) est exactement ce qui aurait \u00e9t\u00e9 consid\u00e9r\u00e9 comme progressiste il y a quelques d\u00e9cennies, ce qui fait que le terme m\u00e9riterait d&rsquo;\u00eatre d\u00e9fini. Mais plus fondamentalement, est-il l\u00e9gitime de demander \u00e0 des adultes de payer des imp\u00f4ts ou des redevances pour \u00eatre r\u00e9\u00e9duqu\u00e9s ?<\/p>\n<\/p>\n<p><p>Loin de moi l&rsquo;id\u00e9e que le gouvernement veuille consciemment instaurer un r\u00e9gime totalitaire. Le probl\u00e8me vient plut\u00f4t du subjectivisme g\u00e9n\u00e9ralis\u00e9 de la culture contemporaine o&ugrave; les discours sur les valeurs ont permis de mettre de c\u00f4t\u00e9 les questions touchant aux faits et \u00e0 l&rsquo;objectivit\u00e9. On le voit assez dans la m\u00e9fiance g\u00e9n\u00e9ralis\u00e9e face aux progr\u00e8s scientifiques et techniques. Certes, le droit n&rsquo;a pas le m\u00eame type d&rsquo;objectivit\u00e9 que les sciences naturelles. Mais il cherche \u00e0 \u00e9tablir des r\u00e8gles fond\u00e9es en raison qui permettent de prot\u00e9ger l&rsquo;individu face \u00e0 l&rsquo;arbitraire du pouvoir. Toute la r\u00e9flexion classique sur la libert\u00e9 d&rsquo;expression, remontant au XVIIIe si\u00e8cle, repose sur cette id\u00e9e.<\/p>\n<\/p>\n<p><p>Les gens qui nous parlent sans arr\u00eat de leurs valeurs ne font en r\u00e9alit\u00e9 que mettre en avant leur propre sup\u00e9riorit\u00e9 morale. Et c&rsquo;est bien cela qui est \u00e0 la base de la corruption du droit \u00e0 laquelle on assiste dans l&rsquo;affaire de la loi sur les fausses nouvelles, des r\u00e9actions hyst\u00e9riques face au &laquo; complotisme &raquo; de monsieur Bercoff, et de la bonne conscience de madame Nyssen. A partir du moment o&ugrave; un groupe d&rsquo;individus se persuade qu&rsquo;il incarne le Bien \u00e0 cause de ses &laquo; valeurs &raquo;, il ne per\u00e7oit m\u00eame plus les limites l\u00e9gitimes que l&rsquo;on peut mettre \u00e0 son pouvoir. C&rsquo;est ce qu&rsquo;on pourrait appeler le totalitarisme de la na\u00efvet\u00e9.<\/p>\n<\/p>\n<p><h4>Jean Bricmont<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00ab\u00a0loi sc\u00e9l\u00e9rate\u00a0\u00bb pour le temps des sc\u00e9l\u00e9rats On a d\u00e9battu au Parlement, en France, sur la loi commun\u00e9ment d\u00e9sign\u00e9e comme anti-FakeNews. La fortune de cette expression en international english, &ndash; qui n&rsquo;est pas celui de Shakespeare, &ndash; est telle, puisqu&#8217;employ\u00e9e par ceux qui suivent le train de la FakeInformationcontre les dissidents qui tentent d&rsquo;endiguer&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[9238,3015,12666,3100,9690],"class_list":["post-77995","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-bricmont","tag-communication","tag-fakenews","tag-information","tag-melanchon"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=77995"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/77995\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=77995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=77995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=77995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}