{"id":78024,"date":"2018-06-28T09:00:58","date_gmt":"2018-06-28T09:00:58","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/06\/28\/les-marqueurs-de-leffondrement-de-lempire\/"},"modified":"2018-06-28T09:00:58","modified_gmt":"2018-06-28T09:00:58","slug":"les-marqueurs-de-leffondrement-de-lempire","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/06\/28\/les-marqueurs-de-leffondrement-de-lempire\/","title":{"rendered":"Les marqueurs de l&rsquo;effondrement de l&#8217;empire"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Les marqueurs de l&rsquo;effondrement de l&#8217;empire<\/h2>\n<\/p>\n<p><p>En r\u00e9fl\u00e9chissant \u00e0 l&rsquo;effondrement de l&#8217;empire am\u00e9ricain qui se d\u00e9roule (jusqu&rsquo;\u00e0 pr\u00e9sent) graduellement, l&rsquo;effondrement de l&rsquo;URSS, qui s&rsquo;est produit il y a pr\u00e8s de trente ans, continue d&rsquo;\u00eatre une utile mine d&rsquo;exemples et d&rsquo;analogies. Certains \u00e9v\u00e9nements survenus pendant l&rsquo;effondrement sovi\u00e9tique peuvent servir de panneaux de signalisation utiles dans le contexte am\u00e9ricain, ce qui nous permet de formuler de meilleures hypoth\u00e8ses quant au calendrier des \u00e9v\u00e9nements qui peuvent soudainement transformer un effondrement graduel en sa version acc\u00e9l\u00e9r\u00e9e.<\/p>\n<\/p>\n<p><p>Quand l&rsquo;effondrement sovi\u00e9tique s&rsquo;est produit, la r\u00e9action universelle a \u00e9t\u00e9 \u00ab\u00a0Qui aurait pu le savoir ?\u00a0\u00bb. Eh bien, je le savais. Je me souviens distinctement d&rsquo;une conversation que j&rsquo;avais eue avec un chirurgien au cours de l&rsquo;\u00e9t\u00e9 1990, juste au moment o&ugrave; j&rsquo;allais passer sur le billard pour me faire op\u00e9rer de l&rsquo;appendicite, en attendant l&rsquo;anesth\u00e9sie. Il m&rsquo;a demand\u00e9 ce qu&rsquo;il adviendrait des r\u00e9publiques sovi\u00e9tiques, de l&rsquo;Arm\u00e9nie en particulier. Je lui ai dit qu&rsquo;elles seraient ind\u00e9pendantes en moins d&rsquo;un an. Il avait l&rsquo;air positivement choqu\u00e9. Je ne m&rsquo;\u00e9tais tromp\u00e9 que de deux mois. J&rsquo;esp\u00e8re pouvoir pr\u00e9voir l&rsquo;effondrement am\u00e9ricain avec le m\u00eame degr\u00e9 de pr\u00e9cision.<\/p>\n<\/p>\n<p><p>Je suppose que j&rsquo;\u00e9tais bien plac\u00e9 pour le savoir, et je suis tent\u00e9 de deviner comment j&rsquo;ai r\u00e9ussi cela. Mon domaine d&rsquo;expertise \u00e0 l&rsquo;\u00e9poque \u00e9tait l&rsquo;\u00e9lectronique de mesure et d&rsquo;acquisition de donn\u00e9es pour les exp\u00e9riences de physique des hautes \u00e9nergies, pas la sovi\u00e9tologie. Mais j&rsquo;avais pass\u00e9 l&rsquo;\u00e9t\u00e9 pr\u00e9c\u00e9dent \u00e0 Leningrad, o&ugrave; j&rsquo;avais grandi, et j&rsquo;avais une bonne id\u00e9e de ce qui se passait en URSS. Pendant ce temps, toute la cohue des experts professionnels sur la Russie,  pay\u00e9s pour le faire, qui \u00e9taient install\u00e9s dans divers organismes gouvernementaux \u00e0 Washington ou qui consommaient de l&rsquo;oxyg\u00e8ne dans diverses fondations et universit\u00e9s des &Eacute;tats-Unis, n&rsquo;avaient absolument aucune id\u00e9e de ce \u00e0 quoi on pouvait s&rsquo;attendre.<\/p>\n<\/p>\n<p><p>Je soup\u00e7onne qu&rsquo;il y a un principe l\u00e0-dedans : si votre carri\u00e8re d\u00e9pend de l&rsquo;existence de X, et si X est sur le point de cesser d&rsquo;exister, alors vous ne serez pas tr\u00e8s motiv\u00e9 pour pr\u00e9dire avec pr\u00e9cision sa fin. Inversement, si vous parveniez \u00e0 pr\u00e9dire avec pr\u00e9cision la fin programm\u00e9e de X, alors vous seriez \u00e9galement assez intelligent pour changer de carri\u00e8re \u00e0 l&rsquo;avance, donc vous ne seriez plus un expert sur X et votre opinion sur le sujet serait n\u00e9glig\u00e9e. Les gens penseraient que vous avez quitt\u00e9 un excellent travail et que vous \u00eates maintenant aigri. &Agrave; l&rsquo;heure actuelle, j&rsquo;observe le m\u00eame ph\u00e9nom\u00e8ne \u00e0 l&rsquo;&oelig;uvre chez les experts russes des &Eacute;tats-Unis : ils ne peuvent pas imaginer que les diverses choses qu&rsquo;ils ont pass\u00e9 leur vie \u00e0 \u00e9tudier ont rapidement perdu de leur pertinence. Ou peut-\u00eatre qu&rsquo;ils le peuvent, mais qu&rsquo;ils gardent cette prise de conscience pour eux-m\u00eames, de peur de ne plus \u00eatre invit\u00e9s dans les talk-shows.<\/p>\n<\/p>\n<p><p>Je suppose que puisque l&rsquo;expertise est la possession d&rsquo;un grand savoir sur un sujet tr\u00e8s circonscrit, tout savoir sur rien &ndash; une chose qui n&rsquo;existe pas &ndash; est son accomplissement logique et parfait. Quoi qu&rsquo;il en soit, je pense que nous autres non-experts, arm\u00e9s du recul chronologique acceptable que nous offre l&rsquo;exemple de l&rsquo;effondrement sovi\u00e9tique, nous pouvons \u00e9viter d&rsquo;\u00eatre pareillement aveugl\u00e9s et abasourdis par l&rsquo;exemple am\u00e9ricain. Ce n&rsquo;est pas une question acad\u00e9mique : ceux qui jaugent la situation avec pr\u00e9cision peuvent \u00eatre en mesure de se faufiler et sortir de l&rsquo;enfer \u00e0 l&rsquo;avance, alors que les lumi\u00e8res sont toujours allum\u00e9es, alors que tous les gens ne sont pas encore engourdis dans une sorte de brume mentale plus ou moins nourrie par les drogues, et alors que les fusillades de masse et d&rsquo;autres types de chaos sont toujours consid\u00e9r\u00e9s comme dignes d&rsquo;int\u00e9r\u00eat par les m\u00e9dias.<\/p>\n<\/p>\n<p><p>Ce recul nous permet de rep\u00e9rer certains marqueurs qui se sont manifest\u00e9s \u00e0 ce moment-l\u00e0 de la chute de l&rsquo;URSS et qui se manifestent actuellement pour les USA. Les quatre marqueurs que je vais d\u00e9velopper sont les suivants :<\/p>\n<\/p>\n<p><p>1. Les alli\u00e9s sont ali\u00e9n\u00e9s ;<\/p>\n<\/p>\n<p><p>2. Les inimiti\u00e9s se dissipent ;<\/p>\n<\/p>\n<p><p>3. L&rsquo;id\u00e9ologie devient non pertinente ;<\/p>\n<\/p>\n<p><p>4. La posture militaire devient flasque.<\/p>\n<\/p>\n<p><p>Tout cela est \u00e9vident \u00e0 constater dans l&rsquo;effondrement am\u00e9ricain. Comme pour l&rsquo;effondrement sovi\u00e9tique, il y a une certaine p\u00e9riode d&rsquo;incubation pour chacune de ces tendances, pouvant durer peut-\u00eatre un an ou deux, au cours de laquelle peu de choses semblent se produire, mais quand le moment est venu l&rsquo;\u00e9vidence du ph\u00e9nom\u00e8ne appara&icirc;t en pleine lumi\u00e8re.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">1. Les alliances<\/h3>\n<\/p>\n<p><p>Au fur et \u00e0 mesure que l&rsquo;effondrement sovi\u00e9tique s&rsquo;est d\u00e9roul\u00e9, les anciennes amiti\u00e9s se sont d\u00e9t\u00e9rior\u00e9es, d&rsquo;abord \u00e0 cause d&rsquo;un manque de pertinence puis tournant en une inimiti\u00e9 sinon une hostilit\u00e9 pure et simple. Avant l&rsquo;effondrement, le rideau de fer qui symbolisait l&rsquo;hostilit\u00e9 courait entre l&rsquo;Europe de l&rsquo;Est et de l&rsquo;Ouest ; trois d\u00e9cennies plus tard, il s\u00e9pare la Russie et les pays baltes, la Pologne et l&rsquo;Ukraine. Alors que dans l&rsquo;apr\u00e8s-guerre, les pays du Pacte de Varsovie tiraient de nombreux avantages de leur association avec la Russie et sa puissance industrielle, vers la fin leur adh\u00e9sion au camp sovi\u00e9tique devenait de plus en plus g\u00eanante pour leur propre progr\u00e8s, entravant leur rapprochement puis leur int\u00e9gration des pays prosp\u00e8res et moins troubl\u00e9s plus \u00e0 l&rsquo;ouest, et avec le reste du monde.<\/p>\n<\/p>\n<p><p>On observe ce ph\u00e9nom\u00e8ne entre les USA et l&rsquo;UE, dont le partenariat montre \u00e9galement des signes s\u00e9rieux alors que les USA tentent d&#8217;emp\u00eacher l&rsquo;Europe de s&rsquo;int\u00e9grer au reste de l&rsquo;Eurasie. La menace particuli\u00e8re de sanctions \u00e9conomiques unilat\u00e9rales dans le cadre d&rsquo;un effort futile des USA pour bloquer d&rsquo;autres gazoducs russes vers l&rsquo;Europe et forcer les Europ\u00e9ens \u00e0 se tourner vers une structure th\u00e9orique am\u00e9ricaine de fourniture d&rsquo;un gaz naturel liqu\u00e9fi\u00e9 incertain et sur\u00e9valu\u00e9, a mis en \u00e9vidence le fait que la relation n&rsquo;est plus mutuellement b\u00e9n\u00e9fique. Alors que la Grande-Bretagne se s\u00e9pare de l&rsquo;Europe et joue de ce qu&rsquo;il reste de son habituelle proximit\u00e9 des USA, un nouveau rideau de fer \u00e9merge peu \u00e0 peu : cette fois, il traversera la Manche, s\u00e9parant le monde anglophone de l&rsquo;Eurasie.<\/p>\n<\/p>\n<p><p>Des d\u00e9veloppements similaires sont en cours \u00e0 l&rsquo;Est, affectant la Cor\u00e9e du Sud et le Japon. La volte-face de Trump entre tweets tumultueux et rh\u00e9torique conciliatoire vis-\u00e0-vis de la Cor\u00e9e du Nord a mis \u00e0 nu le vide des garanties de s\u00e9curit\u00e9 am\u00e9ricaines. Ces deux pays voient maintenant la n\u00e9cessit\u00e9 de prendre leurs propres dispositions de s\u00e9curit\u00e9 et de commencer \u00e0 r\u00e9affirmer leur souverainet\u00e9 en mati\u00e8re militaire. Pendant ce temps, pour les &Eacute;tats-Unis, \u00eatre incoh\u00e9rent n&rsquo;est qu&rsquo;une \u00e9tape sur la voie de devenir insignifiant.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">2. Les inimiti\u00e9s<\/h3>\n<\/p>\n<p><p>Pendant toute la p\u00e9riode de la guerre froide, les &Eacute;tats-Unis \u00e9taient l&rsquo;ennemi jur\u00e9 de l&rsquo;Union sovi\u00e9tique, et tout effort de Washington pour donner des conseils ou dicter sa volont\u00e9 se heurtait \u00e0 des aboiements bruyants, synchronis\u00e9s et id\u00e9ologiquement fortifi\u00e9s de Moscou : \u00ab\u00a0Encore l&rsquo;agresseur imp\u00e9rialiste, ne lui pr\u00eatez aucune attention !\u00a0\u00bb. Cette agitation vertueuse a tr\u00e8s bien fonctionn\u00e9 pendant une p\u00e9riode \u00e9tonnamment longue, et a continu\u00e9 de fonctionner pendant que l&rsquo;Union sovi\u00e9tique r\u00e9alisait de nouvelles conqu\u00eates impressionnantes &ndash; dans l&rsquo;espace, la technologie, la science et la m\u00e9decine, dans des projets humanitaires internationaux, etc. Mais lorsque la stagnation s&rsquo;est install\u00e9e, tout cela a commenc\u00e9 \u00e0 para&icirc;tre d\u00e9risoire.<\/p>\n<\/p>\n<p><p>Apr\u00e8s l&rsquo;effondrement sovi\u00e9tique, cette immunit\u00e9 contre la contagion am\u00e9ricaine a disparu. Des \u00ab\u00a0experts\u00a0\u00bb et des \u00ab\u00a0conseillers\u00a0\u00bb occidentaux ont envahi le pays et propos\u00e9 des \u00ab\u00a0r\u00e9formes\u00a0\u00bb telles que le d\u00e9membrement de l&rsquo;URSS en 15 pays distincts (enfermant des millions de personnes du mauvais c\u00f4t\u00e9 par rapport \u00e0 leur nationalit\u00e9 de la fronti\u00e8re nouvellement invent\u00e9e), par le moyen  d&rsquo;une th\u00e9rapie de choc (qui a horriblement appauvri l&rsquo;essentiel de la population russe), de privatisations anarchiques (qui mettaient des biens publics importants entre les mains de quelques oligarques politiquement bien plac\u00e9s, pour la plupart des oligarques juifs) et divers autres projets visant \u00e0 d\u00e9truire la Russie et \u00e0 faire dispara&icirc;tre sa population. Ils auraient probablement r\u00e9ussi s&rsquo;ils n&rsquo;avaient \u00e9t\u00e9 arr\u00eat\u00e9s \u00e0 temps.<\/p>\n<\/p>\n<p><p>Sym\u00e9triquement, les Washingtoniens consid\u00e9raient l&rsquo;URSS comme leur ennemi jur\u00e9. Apr\u00e8s sa disparition, il y a eu un peu de confusion. Le Pentagone a essay\u00e9 de parler de \u00ab\u00a0mafia russe\u00a0\u00bb comme d&rsquo;une menace majeure pour la paix mondiale, mais cela semblait risible. Puis, \u00e0 l&rsquo;occasion de la d\u00e9molition de quelques gratte-ciels \u00e0 New York, peut-\u00eatre en pla\u00e7ant de petites charges nucl\u00e9aires dans le soubassement sous leurs fondations (ce sont les plans de d\u00e9molition qui \u00e9taient enregistr\u00e9s) (*), ils ont fabriqu\u00e9 avec z\u00e8le le concept de \u00ab\u00a0guerre contre le terrorisme\u00a0\u00bb, bombardant divers pays qui n&rsquo;avaient pas de probl\u00e8me de terrorisme avant mais qui en ont aujourd&rsquo;hui \u00e0 profusion. Une fois que ce plan stupide ait \u00e9t\u00e9 mis sur les rails et bien lanc\u00e9 sur la parcours pr\u00e9vu, les Washingtoniens sont retourn\u00e9s \u00e0 leur premier os \u00e0 ronger et ont recommenc\u00e9 \u00e0 harceler la Russie.<\/p>\n<\/p>\n<p><p>Mais d\u00e9sormais flotte une odeur \u00e9trange flotte \u00e0 Washington : l&rsquo;odeur de l&rsquo;\u00e9chec. Les v\u00e9rit\u00e9s commencent \u00e0 fuiter \u00e0 propos de cette campagne pour calomnier la Russie, et elles sont puantes. Pendant ce temps, Trump continue \u00e0 faire du tintamarre \u00e0 propos de l&rsquo;int\u00e9r\u00eat d&rsquo;un rapprochement avec la Russie et un sommet entre Poutine et lui est en cours de pr\u00e9paration. Trump emprunte aussi quelques pratiques \u00e0 la russe : tout comme la Russie a r\u00e9agi aux sanctions occidentales par des contre-sanctions, Trump commence \u00e0 r\u00e9agir aux barri\u00e8res douani\u00e8res occidentales par ses propres barri\u00e8res douani\u00e8res. Nous devrions nous attendre \u00e0 ce que l&rsquo;inimiti\u00e9 am\u00e9ricaine contre la Russie se dissipe pendant quelque temps avant que l&rsquo;attitude am\u00e9ricaine \u00e0 l&rsquo;\u00e9gard de la Russie (et de beaucoup d&rsquo;autres choses) ne devienne insignifiante. Nous devrions \u00e9galement nous attendre, une fois crev\u00e9e la bulle de la fracturation hydraulique du p\u00e9trole de schiste, \u00e0 ce que les &Eacute;tats-Unis deviennent d\u00e9pendants du p\u00e9trole russe et de son gaz naturel liqu\u00e9fi\u00e9, qu&rsquo;ils seront forc\u00e9s de payer avec de l&rsquo;or. (La fracturation hydraulique US implique un processus de combustion en deux phases : la premi\u00e8re phase br&ucirc;le de l&rsquo;argent emprunt\u00e9 pour produire du p\u00e9trole et du gaz, la seconde br&ucirc;le le p\u00e9trole et le gaz.)<\/p>\n<\/p>\n<p><p>D&rsquo;autres inimiti\u00e9s sont aussi sur le d\u00e9clin. Trump vient de signer un document int\u00e9ressant avec Kim Jong-un, pr\u00e9sident de la Cor\u00e9e du Nord. L&rsquo;affaire (si nous l&rsquo;appelons ainsi) est un acte de capitulation tacite. Il a \u00e9t\u00e9 orchestr\u00e9 par la Russie et la Chine. Il affirme ce que la Cor\u00e9e du Nord et la Cor\u00e9e du Sud avaient d\u00e9j\u00e0 accept\u00e9 : la d\u00e9nucl\u00e9arisation \u00e9ventuelle de la p\u00e9ninsule cor\u00e9enne. Tout comme Gorbatchev a consenti \u00e0 la r\u00e9unification de l&rsquo;Allemagne et au retrait des troupes sovi\u00e9tiques de l&rsquo;Allemagne de l&rsquo;Est, Trump s&rsquo;appr\u00eate \u00e0 accepter la r\u00e9unification de la Cor\u00e9e et le retrait des troupes am\u00e9ricaines de la Cor\u00e9e du Sud. Tout comme la chute du mur de Berlin a marqu\u00e9 la fin de l&rsquo;imperium sovi\u00e9tique, le d\u00e9mant\u00e8lement de la zone d\u00e9militaris\u00e9e cor\u00e9enne marquera la fin de l&rsquo;\u00e8re am\u00e9ricaine.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">3. L&rsquo;id\u00e9ologie<\/h3>\n<\/p>\n<p><p>Alors que les &Eacute;tats-Unis n&rsquo;ont jamais rien eu d&rsquo;aussi rigoureux que le dogme communiste de l&rsquo;Union sovi\u00e9tique, leur m\u00e9lange de propagande pro-d\u00e9mocratie, de capitalisme du laissez-faire, de libre-\u00e9change et de domination militaire a \u00e9t\u00e9 puissant pendant un certain temps. Apr\u00e8s avoir cess\u00e9 d&rsquo;\u00eatre la plus grande puissance industrielle du monde, c\u00e9dant la premi\u00e8re place \u00e0 l&rsquo;Allemagne et au Japon, puis \u00e0 la Chine, les &Eacute;tats-Unis accumulent des dettes prodigieuses, confisquant et d\u00e9pensant l&rsquo;\u00e9pargne mondiale tout en d\u00e9fendant le dollar am\u00e9ricain sous la menace de r\u00e9torsion militaire. Il fut pendant un certain temps compris que le privil\u00e8ge exorbitant de l&rsquo;impression mon\u00e9taire sans fin devait \u00eatre d\u00e9fendu avec le sang des soldats am\u00e9ricains. Les &Eacute;tats-Unis se voyaient et se positionnaient comme le pays indispensable, capable de contr\u00f4ler et de dicter des conditions \u00e0 la plan\u00e8te enti\u00e8re, terrorisant ou bloquant divers autres pays selon les besoins. Maintenant, tous ces  <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Schibboleth\">schibboleths<\/a>  id\u00e9ologiques sont en ruines.<\/p>\n<\/p>\n<p><p>La rh\u00e9torique en faveur de la d\u00e9mocratie est toujours utilis\u00e9e consciencieusement par les porte-parole des m\u00e9dias politiques, mais dans la pratique, les &Eacute;tats-Unis ne sont plus une d\u00e9mocratie. Ce pays a \u00e9t\u00e9 transform\u00e9 en un paradis des lobbyistes qui ne sont plus confin\u00e9s dans l&rsquo;arri\u00e8re-cour des pratiques peu glorieuses mais d\u00e9sormais install\u00e9s dans les bureaux du Congr\u00e8s pour r\u00e9diger directement des quantit\u00e9s prodigieuses de lois r\u00e9pondant aux int\u00e9r\u00eats priv\u00e9s des entreprises et des oligarques. Le penchant am\u00e9ricain pour la d\u00e9mocratie n&rsquo;est pas non plus visible dans le soutien que les &Eacute;tats-Unis prodiguent aux dictatures du monde entier ou dans sa tendance croissante \u00e0 promulguer et appliquer des lois extraterritoriales sans le consentement international.<\/p>\n<\/p>\n<p><p>Le capitalisme du laisser-faire est \u00e9galement bien mort, supplant\u00e9 par le capitalisme de copinage nourri par une fusion compl\u00e8te des \u00e9lites de Washington et de Wall Street. L&rsquo;entreprenariat priv\u00e9 n&rsquo;est plus libre mais concentr\u00e9 aux mains d&rsquo;une poign\u00e9e de soci\u00e9t\u00e9s g\u00e9antes, alors qu&rsquo;environ un tiers de la population active aux &Eacute;tats-Unis travaille dans le secteur public. Le d\u00e9partement am\u00e9ricain de la D\u00e9fense est le plus grand employeur du pays et du monde entier. Environ 100 millions d&rsquo;Am\u00e9ricains en \u00e2ge et en capacit\u00e9 de travailler ne travaillent pas. La plupart des autres travaillent dans des emplois de service, ne produisant rien de durable. Un nombre croissant de personnes garde des moyens de subsistance pr\u00e9caires en travaillant de mani\u00e8re sporadique. Tout le syst\u00e8me est aliment\u00e9 &ndash; y compris les parties qui produisent le carburant, comme l&rsquo;industrie de la fracturation hydraulique &ndash; par de la dette. Aucune personne saine d&rsquo;esprit, si on lui demandait de fournir une description r\u00e9aliste du capitalisme, ne fournirait un plan aussi d\u00e9labr\u00e9.<\/p>\n<\/p>\n<p><p>Le libre-\u00e9change \u00e9tait pr\u00f4n\u00e9 jusqu&rsquo;\u00e0 tr\u00e8s r\u00e9cemment, m\u00eame si de nos jours le mouvement est en perte de vitesse. Le commerce sans entraves sur de grandes distances est la condition  <em>sine qua non<\/em>  de tous les empires, y compris l&#8217;empire am\u00e9ricain. Dans le pass\u00e9, des navires de guerre et la menace d&rsquo;une occupation ont \u00e9t\u00e9 utilis\u00e9s pour forcer des pays, comme le Japon, \u00e0 s&rsquo;ouvrir au commerce international. Tout r\u00e9cemment, l&rsquo;administration Obama a \u00e9t\u00e9 tr\u00e8s active dans ses tentatives de faire passer divers partenariats transoc\u00e9aniques, mais aucun n&rsquo;a r\u00e9ussi. Et maintenant, Trump se met \u00e0 d\u00e9truire le libre-\u00e9change en combinant sanctions et barri\u00e8res douani\u00e8res, dans une tentative d\u00e9risoire de faire revivre la grandeur perdue de l&rsquo;Am\u00e9rique en se tournant vers l&rsquo;int\u00e9rieur du pays. En cours de route, les sanctions sur l&rsquo;utilisation du dollar am\u00e9ricain dans le commerce international, en particulier avec les principaux pays exportateurs d&rsquo;\u00e9nergie tels que l&rsquo;Iran et le Venezuela, acc\u00e9l\u00e8rent le processus par lequel le dollar am\u00e9ricain est d\u00e9tr\u00f4n\u00e9 en tant que monnaie de r\u00e9serve mondiale, d\u00e9molissant le privil\u00e8ge exorbitant de l&rsquo;impression mon\u00e9taire sans fin.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">4. Le militarisme<\/h3>\n<\/p>\n<p><p>L&rsquo;effondrement sovi\u00e9tique \u00e9tait dans une certaine mesure d\u00e9j\u00e0 act\u00e9 avec le retrait sovi\u00e9tique de l&rsquo;Afghanistan. Avant cela, il \u00e9tait encore possible de parler du \u00ab\u00a0devoir international\u00a0\u00bb de l&rsquo;Arm\u00e9e rouge pour rendre le monde (ou du moins les parties lib\u00e9r\u00e9es) au socialisme qu&rsquo;il m\u00e9ritait. Apr\u00e8s l&rsquo;Afghanistan, le concept m\u00eame de domination militaire \u00e9tait pulv\u00e9ris\u00e9 et les interventions possibles auparavant, comme en Hongrie en 1956 et en Tch\u00e9coslovaquie en 1968, \u00e9taient devenues impensables. Lorsque l&rsquo;Europe de l&rsquo;Est a connu une r\u00e9bellion en 1989, l&#8217;empire militaire sovi\u00e9tique s&rsquo;est simplement repli\u00e9, abandonnant ses bases et son mat\u00e9riel militaire en se retirant.<\/p>\n<\/p>\n<p><p>Dans le cas des &Eacute;tats-Unis, pour l&rsquo;instant, ils restent capable de faire beaucoup de d\u00e9g\u00e2ts, mais il est devenu clair que la domination militaire de la plan\u00e8te enti\u00e8re n&rsquo;est plus possible pour eux. L&rsquo;arm\u00e9e am\u00e9ricaine est encore \u00e9norme num\u00e9riquement, mais elle est d\u00e9j\u00e0 bien flasque. Elle n&rsquo;est plus capable de d\u00e9ployer une force terrestre d&rsquo;une quelconque envergure o&ugrave; que ce soit et se limite aux bombardements a\u00e9riens, \u00e0 l&rsquo;entra&icirc;nement et \u00e0 l&rsquo;armement de \u00ab\u00a0terroristes mod\u00e9r\u00e9s\u00a0\u00bb et de mercenaires, et au pseudo-contr\u00f4le sans int\u00e9r\u00eat des oc\u00e9ans. Aucune des aventures militaires r\u00e9centes n&rsquo;a abouti \u00e0 quelque chose ressemblant \u00e0 la paix \u00e0 des conditions que les planificateurs am\u00e9ricains avaient initialement envisag\u00e9es ou que l&rsquo;on aurait pu juger souhaitables : l&rsquo;Afghanistan a \u00e9t\u00e9 transform\u00e9 en incubateur de terroristes et en usine de production d&rsquo;h\u00e9ro\u00efne ; l&rsquo;Irak a \u00e9t\u00e9 absorb\u00e9 par un croissant chiite continu qui s&rsquo;\u00e9tend maintenant de l&rsquo;oc\u00e9an Indien \u00e0 la mer M\u00e9diterran\u00e9e.<\/p>\n<\/p>\n<p><p>Les bases militaires am\u00e9ricaines sont toujours pr\u00e9sentes dans le monde entier. Elles \u00e9taient destin\u00e9s \u00e0 projeter le pouvoir am\u00e9ricain sur les deux h\u00e9misph\u00e8res du globe, mais elles ont \u00e9t\u00e9 largement neutralis\u00e9es par l&rsquo;av\u00e8nement de nouvelles armes hypersoniques de pr\u00e9cision \u00e0 longue port\u00e9e, d&rsquo;une puissante technologie de d\u00e9fense a\u00e9rienne et de la puissance paralysante de la guerre \u00e9lectronique. Ces nombreux \u00ab\u00a0<a href=\"https:\/\/en.wikipedia.org\/wiki\/Cooperative_Security_Location\">n\u00e9nuphars<\/a>\u00ab\u00a0, comme on les appelle parfois, sont \u00e0 l&rsquo;oppos\u00e9 de moyens militaires efficaces et productifs : ce sont des cibles inutiles mais co&ucirc;teuses situ\u00e9es dans des endroits difficiles \u00e0 d\u00e9fendre mais faciles \u00e0 attaquer pour des adversaires potentiels. Ces choses ne peuvent \u00eatre utilis\u00e9s que pour faire semblant de combattre, et la s\u00e9rie interminable d&rsquo;exercices d&rsquo;entra&icirc;nement militaire, tels que ceux dans les &Eacute;tats baltes, juste \u00e0 la fronti\u00e8re russe, ou ceux en Cor\u00e9e du Sud, pr\u00e9tendent \u00eatre des provocations mais s&rsquo;av\u00e8rent \u00eatre des parangons d&rsquo;inutilit\u00e9, car attaquer la Russie ou la Cor\u00e9e du Nord serait un geste suicidaire. Ce sont essentiellement des exercices de renforcement de la confiance, et leur intensit\u00e9 croissante t\u00e9moigne d&rsquo;un d\u00e9ficit de confiance prononc\u00e9 et croissant.<\/p>\n<\/p>\n<p><p>Les gens ne se lassent jamais de souligner la taille \u00e9norme du budget militaire am\u00e9ricain, mais ils oublient presque toujours de mentionner que ce que les &Eacute;tats-Unis re\u00e7oivent par unit\u00e9 d&rsquo;argent est dix fois moindre que, par exemple, la Russie. C&rsquo;est un plan d&rsquo;extorsion boursoufl\u00e9 et inefficace qui produit de grandes quantit\u00e9s de catastrophes technologiques &ndash; une \u00e9ponge d&rsquo;argent public sans cesse assoiff\u00e9e. Peu importe combien d&rsquo;argent elle absorbe, cela ne r\u00e9soudra jamais le probl\u00e8me fondamental de l&rsquo;incapacit\u00e9 \u00e0 faire la guerre \u00e0 un adversaire ad\u00e9quatement arm\u00e9 sans subir des dommages inacceptables. Partout dans le monde, les &Eacute;tats-Unis sont maintenant d\u00e9test\u00e9s, mais on les craint de moins en moins : une tendance fatale pour un empire. Par contre l&rsquo;Am\u00e9rique a tr\u00e8s bien r\u00e9ussi \u00e0 militariser ses services de police locaux, de sorte que le moment venu, elle sera pr\u00eate \u00e0 faire la guerre &hellip; contre elle-m\u00eame.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Conclusion<\/h3>\n<\/p>\n<p><p>Cette analyse peut se lire comme une enqu\u00eate historique d\u00e9tach\u00e9e de consid\u00e9rations pratiques et quotidiennes. Mais je crois que cela a un m\u00e9rite pratique. Si les citoyens de l&rsquo;URSS avaient \u00e9t\u00e9 inform\u00e9s, avant les \u00e9v\u00e9nements de 1990, de ce qui allait leur arriver, ils se seraient comport\u00e9s diff\u00e9remment, et beaucoup de trag\u00e9dies personnelles auraient pu \u00eatre \u00e9vit\u00e9es. Une distinction tr\u00e8s utile peut \u00eatre faite entre l&#8217;emp\u00eachement des effondrements (ce qui est futile, tous les empires s&rsquo;effondrent) et l&#8217;emp\u00eachement des sc\u00e9narios les plus d\u00e9favorables, qui deviendra, lorsque l&rsquo;effondrement va s&rsquo;acc\u00e9l\u00e9rer, votre pr\u00e9occupation la plus importante. Votre approche peut impliquer de fuir vers un terrain plus s&ucirc;r, ou de vous pr\u00e9parer \u00e0 survivre l\u00e0 o&ugrave; vous \u00eates. Vous pouvez choisir vos propres marqueurs d&rsquo;effondrement et faire vos propres pr\u00e9dictions sur leur calendrier au lieu de compter sur le mien. Mais, ayant \u00e9t\u00e9 t\u00e9moin d&rsquo;un effondrement, et \u00e9tant t\u00e9moin d&rsquo;un autre, la seule approche que je ne recommanderais vraiment pas, est de ne rien faire et d&rsquo;esp\u00e9rer le meilleur.<\/p>\n<\/p>\n<p><h4>Dimitri Orlov<\/h4>\n<\/p>\n<p><p>(Le 19 juin 2018, <a href=\"http:\/\/cluborlov.blogspot.com\/2018\/06\/imperial-collapse-markers.html\">Club Orlov<\/a>&ndash; Traduit par <a href=\"http:\/\/lesakerfrancophone.fr\/marqueurs-imperiaux-de-leffondrement\">Le Sakerfrancophone<\/a>)<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h3>\n<\/p>\n<p><p>(*) Avant de construire un gratte-ciel \u00e0 Manhattan, les lois locales exigent des architectes de d\u00e9poser un plan de d\u00e9molition \u00e0 utiliser pour d\u00e9manteler la structure plus tard. Le plan d\u00e9pos\u00e9 pour les tours jumelles \u00e9tait une &laquo; d\u00e9molition atomique &raquo; : le placement d&rsquo;une petite charge nucl\u00e9aire de 50 m\u00e8tres dans le roc. L&rsquo;explosion devait cr\u00e9er une cavit\u00e9 de gaz surchauff\u00e9 dans laquelle la tour s&rsquo;effondre et est incin\u00e9r\u00e9e. C&rsquo;est pr\u00e9cis\u00e9ment ce qui semble s&rsquo;\u00eatre pass\u00e9. Si vous regardez les vid\u00e9os, les tours tombent dans des trous dans le sol<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les marqueurs de l&rsquo;effondrement de l&#8217;empire En r\u00e9fl\u00e9chissant \u00e0 l&rsquo;effondrement de l&#8217;empire am\u00e9ricain qui se d\u00e9roule (jusqu&rsquo;\u00e0 pr\u00e9sent) graduellement, l&rsquo;effondrement de l&rsquo;URSS, qui s&rsquo;est produit il y a pr\u00e8s de trente ans, continue d&rsquo;\u00eatre une utile mine d&rsquo;exemples et d&rsquo;analogies. Certains \u00e9v\u00e9nements survenus pendant l&rsquo;effondrement sovi\u00e9tique peuvent servir de panneaux de signalisation utiles dans le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[29],"tags":[10819,18380,2803,5709,2668,963],"class_list":["post-78024","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-dimitri-orlov-1","tag-10819","tag-colapsologie","tag-effondrement","tag-expert","tag-orlov","tag-urss"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78024"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78024\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}