{"id":78034,"date":"2018-07-04T05:56:50","date_gmt":"2018-07-04T05:56:50","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/07\/04\/le-bon-sens-israelien-contre-georges-soros\/"},"modified":"2018-07-04T05:56:50","modified_gmt":"2018-07-04T05:56:50","slug":"le-bon-sens-israelien-contre-georges-soros","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/07\/04\/le-bon-sens-israelien-contre-georges-soros\/","title":{"rendered":"Le bon sens isra\u00e9lien contre Georges Soros"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Le bon sens isra\u00e9lien contre Georges Soros<\/h2>\n<\/p>\n<p><p>Soros en destructeur des d\u00e9mocraties occidentales ?<\/p>\n<\/p>\n<p><p>Ce tr\u00e8s beau texte de Caroline Glick, publi\u00e9 en ao&ucirc;t 2016, fut r\u00e9f\u00e9renc\u00e9 et comment\u00e9 comme il se doit alors par Dedefensa.org. Il renvoie les maniaques des minorit\u00e9s, les antiracistes et les antis\u00e9mites \u00e0 leur niche. <\/p>\n<\/p>\n<p><p>Comme disait un vieux ma&icirc;tre (Lalande, l&rsquo;auteur de mon dico de philosophie pr\u00e9f\u00e9r\u00e9), &laquo; on doit se d\u00e9fendre quand on est attaqu\u00e9, car si on ne le fait pas, on favorise une injustice. &raquo; Et comme disait Nietzsche dans Par-del\u00e0 le bien et le mal, les deux peuples qui ont un avenir en Europe sont les juifs et les russes (&sect;251).  Ils ne l&rsquo;ont que trop montr\u00e9 depuis quand des peuples comme les Fran\u00e7ais ou les Espagnols s&rsquo;affaissent lamentablement dans la danse de Saint-Guy du mondialisme liqu\u00e9fi\u00e9. Les British ou les Italiens ont au moins essay\u00e9&hellip; M\u00eame les Am\u00e9ricains .<\/p>\n<\/p>\n<p><p>Glick commence ainsi :<strong>la menace est globale<\/strong>. Je le sens depuis que Soros a pris pied en Espagne avec le gouvernement de Soros-Sanchez-Podemos, qui ne perd pas une minute pour an\u00e9antir ce pays.<\/p>\n<\/p>\n<p><p>&laquo; OUR WORLD: LA CAMPAGNE DE SOROS DE SOROS DANS LE MONDE<\/p>\n<\/p>\n<p><p>La premi\u00e8re chose que nous voyons est la nature m\u00e9galomaniaque du projet philanthropique de Soros. Aucun coin du globe n&rsquo;est affect\u00e9 par ses efforts. Aucune zone politique n&rsquo;est laiss\u00e9e intacte. &raquo;<\/p>\n<\/p>\n<p><p>Comme une multinationale du crime. La subversion du terme soci\u00e9t\u00e9 ouverte emprunt\u00e9e \u00e0 Henri Bergson (puis seulement \u00e0 Popper) marquait l&rsquo;entropie m\u00e9phitique du K Soros.<\/p>\n<\/p>\n<p><p>Glick ajoute :<\/p>\n<\/p>\n<p><p>&laquo; La notion qui sous-tend la l\u00e9galisation d&rsquo;une immigration sans entraves est que les &Eacute;tats ne devraient pas \u00eatre en mesure de prot\u00e9ger leur identit\u00e9 nationale. &laquo; <\/p>\n<\/p>\n<p><p>Sur la question sexuelle et militaire (la subversion de l&rsquo;un va avec l&rsquo;autre, et r\u00e9ciproquement) :<\/p>\n<\/p>\n<p><p>&laquo; Ils soutiennent non seulement le droit des femmes \u00e0 servir dans les unit\u00e9s de combat, mais aussi les efforts pour forcer les soldats \u00e0 vivre dans des casernes unisexes. En d&rsquo;autres termes, ils soutiennent les efforts visant \u00e0 priver les citoyens des d\u00e9mocraties occidentales du droit de maintenir toute distance entre eux et le rejet par Soros de leurs valeurs les plus intimes &#8211; leur vie sexuelle et leur identit\u00e9 sexuelle. &raquo;<\/p>\n<\/p>\n<p><p>Sur la question de l&rsquo;immigration ill\u00e9gale (je sais, je sais, on est nazi quand on est contre, et on est nazi quand, juif ou isra\u00e9lien, on s&rsquo;y oppose) :<\/p>\n<\/p>\n<p><p>&laquo; Les groupes de Soros sont sur le terrain permettant aux immigrants ill\u00e9gaux d&rsquo;entrer aux &Eacute;tats-Unis et en Europe. Ils ont cherch\u00e9 \u00e0 influencer les d\u00e9cisions de la Cour supr\u00eame des &Eacute;tats-Unis sur l&rsquo;immigration ill\u00e9gale en provenance du Mexique. Ils ont travaill\u00e9 avec des musulmans et d&rsquo;autres groupes pour diaboliser les Am\u00e9ricains et les Europ\u00e9ens qui s&rsquo;opposent aux fronti\u00e8res ouvertes. &raquo;<\/p>\n<\/p>\n<p><p>Glick souligne qu&rsquo;Isra\u00ebl est dans le collimateur de Soros :<\/p>\n<p>&laquo; En Isra\u00ebl \u00e9galement, Soros s&rsquo;oppose aux efforts du gouvernement pour mettre fin au flux d&rsquo;immigration ill\u00e9gale en provenance d&rsquo;Afrique \u00e0 travers la fronti\u00e8re avec l&rsquo;Egypte. &raquo;<\/p>\n<\/p>\n<p><p>Se d\u00e9fendre est raciste. D\u00e9fendre son peuple, son sol, les libert\u00e9s qui vont avec est raciste.<\/p>\n<\/p>\n<p><p>Retenez bien cette constatation magnifique et implacable :<\/p>\n<\/p>\n<p><p>&laquo; S&rsquo;il est raciste pour les Grecs de prot\u00e9ger leur identit\u00e9 nationale en cherchant \u00e0 bloquer l&rsquo;entr\u00e9e de millions de Syriens sur leur territoire, alors cela est raciste pour la Gr\u00e8ce &#8211; ou la France, l&rsquo;Allemagne, la Hongrie, la Su\u00e8de, les &Eacute;tats-Unis ou la Pologne. &raquo;<\/p>\n<\/p>\n<p><p>Caroline Glick termine par un beau rappel des troupes et une constatation non moins implacable :<\/p>\n<\/p>\n<p><p> &laquo; Les peuples de l&rsquo;Occident doivent reconna&icirc;tre les bases communes de toutes les actions de Soros. Ils doivent aussi r\u00e9aliser que la seule r\u00e9ponse \u00e0 ces campagnes pr\u00e9m\u00e9dit\u00e9es de subversion est que les Occidentaux d\u00e9fendent leurs droits nationaux et leur droit individuel \u00e0 la s\u00e9curit\u00e9. Ils doivent soutenir les institutions nationales qui garantissent cette s\u00e9curit\u00e9, conform\u00e9ment \u00e0 la loi, et d\u00e9fendre et d\u00e9fendre leurs valeurs et traditions nationales. &raquo;<\/p>\n<\/p>\n<p><p>Car on n&rsquo;impose ce chaos que par le fascisme.<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Sources<\/h2>\n<\/p>\n<p><p>https:\/\/www.jpost.com\/Opinion\/Our-World-Soross-campaign-of-global-chaos-464770<\/p>\n<\/p>\n<p><p>https:\/\/nicolasbonnal.wordpress.com\/2018\/04\/15\/nietzsche-et-le-conflit-judeo-russe-a-travers-les-siecles\/<\/p>\n<\/p>\n<p><p>https:\/\/www.les4verites.com\/histoire\/notes-politiquement-incorrectes-sur-la-superiorite-des-juifs-a-travers-les-siecles<\/p>\n<\/p>\n<p><p>www.dedefensa.org\/article\/le-jerusalem-post-contre-soros-khaos<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le bon sens isra\u00e9lien contre Georges Soros Soros en destructeur des d\u00e9mocraties occidentales ? Ce tr\u00e8s beau texte de Caroline Glick, publi\u00e9 en ao&ucirc;t 2016, fut r\u00e9f\u00e9renc\u00e9 et comment\u00e9 comme il se doit alors par Dedefensa.org. Il renvoie les maniaques des minorit\u00e9s, les antiracistes et les antis\u00e9mites \u00e0 leur niche. Comme disait un vieux ma&icirc;tre&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[4270,11929,2729,2774,13256,4163],"class_list":["post-78034","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-autodestruction","tag-entropisation","tag-espagne","tag-israel","tag-lgtbq","tag-soros"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78034"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78034\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}