{"id":78057,"date":"2018-07-15T15:07:41","date_gmt":"2018-07-15T15:07:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/07\/15\/etrange-linde-estime-ne-pas-dependre-des-lois-us\/"},"modified":"2018-07-15T15:07:41","modified_gmt":"2018-07-15T15:07:41","slug":"etrange-linde-estime-ne-pas-dependre-des-lois-us","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/07\/15\/etrange-linde-estime-ne-pas-dependre-des-lois-us\/","title":{"rendered":"\u00c9trange\u00a0: l&rsquo;Inde estime ne pas d\u00e9pendre des lois US"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">&Eacute;trange : l&rsquo;Inde estime ne pas d\u00e9pendre des lois US<\/h2>\n<\/p>\n<p><p>Il semble qu&rsquo;une d\u00e9l\u00e9gation du Congr\u00e8s des &Eacute;tats-Unis ait rendu visite il y a quelques semaines aux dirigeants indiens pour leur rappeler aimablement qu&rsquo;il existe une loi, qu&rsquo;eux-m\u00eames ont vot\u00e9e, la loi dite-CAATSA (pour <em>Countering America&rsquo;s Adversaries Through Sanctions Act<\/em>). Les parlementaires US estime que \u00ab\u00a0CAATSA\u00a0\u00bb est ais\u00e9ment prononc\u00e9 et compr\u00e9hensible en <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Langues_en_Inde\">langue <em>hindi<\/em><\/a>, ce qui devrait <strong>suffire \u00e0 convaincre l&rsquo;Inde de ne pas acheter le syst\u00e8me S-400 russe<\/strong>. Le ministre de la d\u00e9fense leur a expliqu\u00e9 (en bon anglais) qu'\u00a0\u00bbil s&rsquo;agit d&rsquo;une l\u00e9gislation US et non d&rsquo;une l\u00e9gislation de l&rsquo;ONU, et encore moins d&rsquo;une loi indienne, <strong>donc qu&rsquo;elle ne s&rsquo;applique en rien \u00e0 l&rsquo;Inde\u00a0\u00bb<\/strong>. Le ministre a confirm\u00e9 que le contrat des S-400 en cours de finalisation devrait \u00eatre solennellement sign\u00e9 par Poutine et le Premier ministre Modi lors de la visite du pr\u00e9sident russe \u00e0 La Nouvelle-Delhi en octobre prochain.<\/p>\n<\/p>\n<blockquote>\n<p><p>Cela fait treize ans que <strong>les USA ont d\u00e9cid\u00e9 que l&rsquo;Inde allait devenir une \u00ab\u00a0grande puissance\u00a0\u00bb, de fa\u00e7on \u00e0 pouvoir renforcer au mieux les int\u00e9r\u00eats strat\u00e9giques US<\/strong>. (<a href=\"http:\/\/www.dedefensa.org\/article\/voulez-vous-devenir-une-grande-puissance\">Mars 2005<\/a> : &laquo; <em>US unveils plans to make India \u00ab\u00a0major world power\u00a0\u00bb<\/em> &raquo;) Il semble qu&rsquo;ils n&rsquo;aient toujours pas lu le mode d&#8217;emploi : chaque fois qu&rsquo;ils croient \u00eatre proche d&rsquo;y parvenir, <strong>ils font grand tapage autour de leur propre <em>modus operandi <\/em><\/strong>(\u00ab\u00a0vous devrez respecter nos  lois chez vous\u00a0\u00bb) et l&rsquo;Inde renvoie la grande alliance strat\u00e9gique <strong>aux calendes grecques<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Membre de l&rsquo;Organisation de Coop\u00e9ration de Shanghai depuis deux mois, ce que les services du d\u00e9partement d&rsquo;&Eacute;tat semble ne pas avoir encore not\u00e9, l&rsquo;Inde para&icirc;t donc d\u00e9cid\u00e9e \u00e0 acheter le S-400. <strong>Cela la placera en conflit direct avec son \u00ab\u00a0alli\u00e9 strat\u00e9gique\u00a0\u00bb<\/strong>. Comme punition, les USA d\u00e9cideront sans doute de ne pas proposer \u00e0 l&rsquo;Inde le F-35\/JSF dont l&rsquo;Inde a d\u00e9j\u00e0 d\u00e9clin\u00e9 l&rsquo;achat \u00e0 deux reprises. RT nous propose <a href=\"https:\/\/francais.rt.com\/international\/52422-inde-tient-tete-sanctions-americaines-compte-acheter-s-400-russie\">quelques mots<\/a> d&rsquo;explications, d&rsquo;abord sur le fait que l&rsquo;Inde est un pays souverain, ensuite sur la circonstance pr\u00e9sente de la m\u00e9sentente USA-Inde, pour refus de la seconde de respecter pour ses propres affaires les lois des premiers.<\/p>\n<\/p>\n<p><p>&laquo; <em>L&rsquo;Inde se consid\u00e8re comme un pays souverain et tient \u00e0 le faire savoir. La ministre indienne de la D\u00e9fense, Nirmala Sitharaman, a d\u00e9clar\u00e9 \u00e0 plusieurs journalistes venus l&rsquo;\u00e9couter dans son bureau de New Delhi, que les sanctions prises unilat\u00e9ralement par les &Eacute;tats-Unis contre la Russie relevaient \u00ab\u00a0du droit am\u00e9ricain et non du droit des Nations unies\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>En l&rsquo;occurrence, les sanctions am\u00e9ricaines, qui pr\u00e9voient de s&rsquo;en prendre aux &Eacute;tats engageant des d\u00e9penses aupr\u00e8s de compagnies d&rsquo;armement russes, pourraient menacer le contrat en passe d&rsquo;\u00eatre pass\u00e9 entre Moscou et New Delhi pour une valeur de 4,87 milliards d&rsquo;euros. L&rsquo;Inde a en effet fait l&rsquo;acquisition de cinq r\u00e9giments de S-400. \u00ab\u00a0Notre relation de d\u00e9fense avec la Russie remonte \u00e0 plusieurs d\u00e9cennies\u00a0\u00bb, a rappel\u00e9 Nirmala Sitharaman pour justifier l&rsquo;attachement de l&rsquo;Inde \u00e0 ce contrat qui est en phase de finalisation.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 15 juillet 2018 \u00e0 15H15<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Eacute;trange : l&rsquo;Inde estime ne pas d\u00e9pendre des lois US Il semble qu&rsquo;une d\u00e9l\u00e9gation du Congr\u00e8s des &Eacute;tats-Unis ait rendu visite il y a quelques semaines aux dirigeants indiens pour leur rappeler aimablement qu&rsquo;il existe une loi, qu&rsquo;eux-m\u00eames ont vot\u00e9e, la loi dite-CAATSA (pour Countering America&rsquo;s Adversaries Through Sanctions Act). Les parlementaires US estime que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[18247,14492,2730,8289,5646,2746],"class_list":["post-78057","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-caatsa","tag-modi","tag-russie","tag-s-400","tag-sanctions","tag-souverainete"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78057"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78057\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}