{"id":78098,"date":"2018-08-07T16:19:20","date_gmt":"2018-08-07T16:19:20","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/08\/07\/rand-paul-a-moscou\/"},"modified":"2018-08-07T16:19:20","modified_gmt":"2018-08-07T16:19:20","slug":"rand-paul-a-moscou","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/08\/07\/rand-paul-a-moscou\/","title":{"rendered":"Rand Paul \u00e0 Moscou"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Rand Paul \u00e0 Moscou<\/h2>\n<\/p>\n<p><p>Le s\u00e9nateur du Kentucky Rand Paul fait donc honneur \u00e0 son p\u00e8re. Ron Paul fut pendant plusieurs d\u00e9cennies un d\u00e9put\u00e9 du Texas \u00e0 la Chambre des Repr\u00e9sentants de Washington o&ugrave; il se singularisa constamment par des positions non-conformistes, contre la position officielle de son parti (r\u00e9publicain), &ndash; lui-m\u00eame \u00e9tant un libertarien hautement proclam\u00e9. Ron Paul fut notamment deux fois candidat \u00e0 la pr\u00e9sidence (2008 et 2012) et <strong>ses tentatives furent loin d&rsquo;\u00eatre ridicules malgr\u00e9 le sabotage syst\u00e9matique de son parti<\/strong>. L&rsquo;ensemble lui permet de <a href=\"http:\/\/www.ronpaulinstitute.org\/\">parler et d&rsquo;\u00e9crire aujourd&rsquo;hui<\/a>, quasiment \u00e0 quatre-vingts ans, comme un vieux sage <strong>qui en sait plus sur la politique de s\u00e9curit\u00e9 nationale que l&rsquo;ensemble du Congr\u00e8s, &ndash; la corruption en moins, certes<\/strong>.<\/p>\n<\/p>\n<p><p>Rand est en train de suivre les traces de son \u00e8re, apr\u00e8s un d\u00e9but h\u00e9sitant. Aujourd&rsquo;hui, il appara&icirc;t au S\u00e9nat comme <strong>un solitaire \u00e0 la puissance paradoxale puisqu&rsquo;il a l&rsquo;unique avantage de dire un nombre non n\u00e9gligeable de v\u00e9rit\u00e9s-de-situation face au d\u00e9cha&icirc;nement de d\u00e9mence de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb<\/strong>. Il s&rsquo;oppose \u00e0 la politique interventionniste US, \u00e0 la politique belliciste de l&rsquo;OTAN, \u00e0 son \u00e9largissement, \u00e0 l&rsquo;hostilit\u00e9 oppos\u00e9e \u00e0 la Russie (<em>Russiagate<\/em>) par quasiment tous les locataires de \u00ab\u00a0la maison des fous\u00a0\u00bb qu&rsquo;est D.C. et son Congr\u00e8s.<\/p>\n<\/p>\n<blockquote>\n<p><p>Rand Paul a donc fait une visite \u00e0 Moscou, invit\u00e9 par la <em>Douma<\/em>, pour des discussions qu&rsquo;il juge absolument n\u00e9cessaires avec ses coll\u00e8gues russes. (Il avait r\u00e9ussi \u00e0 entra&icirc;ner avec lui un s\u00e9nateur de la l\u00e9gislature du Texas, Don Huffines, et le pr\u00e9sident du <em>Cato Institute<\/em>[tendance libertarienne], Peter Goettler.) <strong>Rand Paul a invit\u00e9 ses coll\u00e8gues russes \u00e0 envoyer une d\u00e9l\u00e9gation en visite au Congr\u00e8s<\/strong>, en r\u00e9ciprocit\u00e9 \u00e0 sa propre visite et pour poursuivre le dialogue engag\u00e9. Les Russes ont imm\u00e9diatement accept\u00e9. Il nous semble assur\u00e9 que <strong>cette visite sera pour le moins color\u00e9e et anim\u00e9e<\/strong> : le reste du Congr\u00e8s et la presseSyst\u00e8me parviendront-ils \u00e0 maintenir un <em>blackout <\/em>sur cette visite ? Rand Paul parviendra-t-il \u00e0 les obliger \u00e0 en parler, \u00e9ventuellement \u00e0 en faire une pol\u00e9mique \u00e9difiante ? Cette r\u00e9action, ou absence de r\u00e9action \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, <strong>voil\u00e0 qui repr\u00e9sente sans aucun doute la circonstance la plus int\u00e9ressante de cet \u00e9change<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>Ci-dessous, quelques extraits du texte de Arkadi Savitsky, sur <em>strategic-culture.org<\/em>, le <a href=\"https:\/\/www.strategic-culture.org\/news\/2018\/08\/07\/senator-paul-visits-russia-foster-vital-engagement-between-lawmakers.html\">7 ao&ucirc;t 2018<\/a>&#8230;<\/p>\n<\/p>\n<p><p> &laquo; <em>Donald Trump n&rsquo;est pas le seul politicien am\u00e9ricain \u00e0 s&rsquo;efforcer d&rsquo;am\u00e9liorer ses relations avec Moscou, au m\u00e9pris de tant d&rsquo;opposants qui d\u00e9noncent sa position vis-\u00e0-vis de la Russie. La r\u00e9action hyst\u00e9rique au sommet du pr\u00e9sident des &Eacute;tats-Unis avec le dirigeant russe \u00e0 Helsinki n&#8217;emp\u00eache pas le s\u00e9nateur r\u00e9publicain Rand Paul de faire <a href=\"https:\/\/www.youtube.com\/watch?v=oCiOVeqTQgs\">ce qu&rsquo;il estime \u00eatre juste<\/a>\u00e0 Moscou, \u00e0 la t\u00eate d&rsquo;une d\u00e9l\u00e9gation am\u00e9ricaine, dont le s\u00e9nateur texan Don Huffines. pr\u00e9sident de l&rsquo;Institut Cato, Peter Goettler, afin de stimuler <a href=\"https:\/\/www.paul.senate.gov\/news\/senator-paul-and-chairman-kosachev-agree-us-russia-engagement\">les contacts<\/a>avec les l\u00e9gislateurs russes<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>Lors des pourparlers \u00e0 Moscou le 6 ao&ucirc;t, il a invit\u00e9 une d\u00e9l\u00e9gation de s\u00e9nateurs russes \u00e0 se rendre \u00e0 Washington. \u00ab\u00a0Aujourd&rsquo;hui, j&rsquo;ai rencontr\u00e9 le pr\u00e9sident Kosachev et nous avons convenu de l&rsquo;importance de la poursuite du dialogue. J&rsquo;ai invit\u00e9 la F\u00e9d\u00e9ration de Russie \u00e0 envoyer une d\u00e9l\u00e9gation au Capitole et ils ont accept\u00e9 de franchir cette \u00e9tape importante\u00a0\u00bb, <a href=\"http:\/\/www.rollcall.com\/news\/politics\/sen-rand-paul-invites-top-russians-u-s-claim-no-election-interference\">a d\u00e9clar\u00e9<\/a>M. Paul. Ce sera la premi\u00e8re d\u00e9l\u00e9gation parlementaire russe \u00e0 se rendre \u00e0 Washington depuis pr\u00e8s de trois ans. Le s\u00e9nateur pense que \u00ab\u00a0notre plus gros probl\u00e8me en ce moment c&rsquo;est l&rsquo;absence de dialogue\u00a0\u00bb, <a href=\"https:\/\/nz.news.yahoo.com\/sen-rand-paul-invites-russian-lawmakers-washington-133534385.html\">soulignant<\/a>que \u00ab\u00a0l&rsquo;engagement est essentiel \u00e0 notre s\u00e9curit\u00e9 nationale et \u00e0 la paix dans le monde\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>L&rsquo;ann\u00e9e derni\u00e8re, Rand Paul, qui si\u00e8ge au Comit\u00e9 des relations ext\u00e9rieures, \u00e9tait <a href=\"https:\/\/ivn.us\/2017\/08\/03\/meet-5-lawmakers-voted-against-russia-sanctions-bill\/\">l&rsquo;un des deux s\u00e9nateurs<\/a>qui ont vot\u00e9 contre la loi imposant des sanctions \u00e0 divers pays \u00e9trangers, notamment des sanctions massives contre la Russie. Auparavant, il avait vot\u00e9 contre l&rsquo;adh\u00e9sion \u00e0 l&rsquo;OTAN du Mont\u00e9n\u00e9gro, \u00e0 laquelle Moscou s&rsquo;\u00e9tait \u00e9galement oppos\u00e9. <a href=\"https:\/\/nationalinterest.org\/feature\/why-john-mccain-accusing-rand-paul-working-russia-19808\">Selon le s\u00e9nateur Paul<\/a>, \u00ab\u00a0actuellement, les &Eacute;tats-Unis ont des troupes dans des dizaines de pays et se battent activement en Irak, en Syrie, en Libye et au Y\u00e9men (avec des frappes de drones au Pakistan). En outre, les &Eacute;tats-Unis se sont engag\u00e9s \u00e0 d\u00e9fendre vingt-huit pays au sein de l&rsquo;OTAN. Il est imprudent d&rsquo;\u00e9largir les obligations mon\u00e9taires et militaires des &Eacute;tats-Unis, compte tenu du fardeau de notre dette de 20 000 milliards de dollars.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Contrairement \u00e0 la majorit\u00e9 des l\u00e9gislateurs am\u00e9ricains, Rand Paul a vu les r\u00e9sultats du sommet de Trump-Poutine \u00e0 Helsinki sous un jour positif. L&rsquo;\u00e9v\u00e9nement l&rsquo;a incit\u00e9 \u00e0 prendre la d\u00e9cision de se rendre \u00e0 Moscou et \u00e0 contribuer ainsi au processus de relance progressive d&rsquo;une relation bilat\u00e9rale. Son intention \u00e9tait de \u00ab\u00a0trouver un terrain d&rsquo;entente avec les dirigeants russes et d&rsquo;aider \u00e0 &lsquo;pr\u00e9venir une escalade des tensions inutile'\u00a0\u00bb. Il affirme que \u00ab\u00a0des millions de vies pourraient \u00eatre en jeu\u00a0\u00bb. Le s\u00e9nateur veut am\u00e9liorer \u00ab\u00a0le climat hostile cr\u00e9\u00e9 par les Russophobes\u00a0\u00bb, qui a entra&icirc;n\u00e9 \u00ab\u00a0un vide dans les \u00e9changes culturels, \u00e9ducatifs et m\u00eame l\u00e9gislatifs\u00a0\u00bb.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>Mis en ligne le 7 ao&ucirc;t 2018 \u00e0 16H12<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rand Paul \u00e0 Moscou Le s\u00e9nateur du Kentucky Rand Paul fait donc honneur \u00e0 son p\u00e8re. Ron Paul fut pendant plusieurs d\u00e9cennies un d\u00e9put\u00e9 du Texas \u00e0 la Chambre des Repr\u00e9sentants de Washington o&ugrave; il se singularisa constamment par des positions non-conformistes, contre la position officielle de son parti (r\u00e9publicain), &ndash; lui-m\u00eame \u00e9tant un libertarien&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[21],"tags":[13231,5894,2707,3140,2895,3310,13022,2730],"class_list":["post-78098","post","type-post","status-publish","format-standard","hentry","category-breves-de-crise","tag-d-c-la-folle","tag-dialogue","tag-moscou","tag-paul","tag-rand","tag-ron","tag-russiagate","tag-russie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78098"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78098\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}