{"id":78121,"date":"2018-08-18T18:59:11","date_gmt":"2018-08-18T18:59:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/08\/18\/la-senatrice-sacrilege\/"},"modified":"2018-08-18T18:59:11","modified_gmt":"2018-08-18T18:59:11","slug":"la-senatrice-sacrilege","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/08\/18\/la-senatrice-sacrilege\/","title":{"rendered":"La s\u00e9natrice sacril\u00e8ge"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">La s\u00e9natrice sacril\u00e8ge<\/h2>\n<\/p>\n<p><p>18 ao&ucirc;t 2018 &ndash; Dans ce texte, je fais r\u00e9f\u00e9rence aux deux autres textes du m\u00eame jour, pour \u00e9tablir un lien entre eux deux et constituer ainsi un triangle parfait, compl\u00e8tement isoc\u00e8le, qui figurera la v\u00e9rit\u00e9-de-situation de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me (GCES). <a href=\"http:\/\/www.dedefensa.org\/article\/nationaliser-le-capitalisme-us\">Le premier<\/a>de ces deux textes concerne la s\u00e9natrice Warren et sa proposition de loi de \u00ab\u00a0responsabilisation du capitalisme\u00a0\u00bb ; le second est le <a href=\"http:\/\/www.dedefensa.org\/article\/tc-56-demence-cosmique\">T.C.-56<\/a> sur la \u00ab\u00a0d\u00e9mence cosmique\u00a0\u00bb.<\/p>\n<\/p>\n<p><p>Nous partons sur la s\u00e9natrice du Massachusetts&#8230;  <\/p>\n<\/p>\n<p><p>Elizabeth Warren est une brillante universitaire, venue de Harvard, qui occupa des postes officiels, notamment pour enqu\u00eater sur les conditions du sauvetage de Wall Street apr\u00e8s l&rsquo;effondrement 9\/15 de 2008, avant d&rsquo;\u00eatre \u00e9lue s\u00e9natrice en 2012 (et vice-pr\u00e9sidente de la minorit\u00e9 d\u00e9mocrate au S\u00e9nat depuis 2017), et candidate pr\u00e9f\u00e9r\u00e9e de la base du parti pour les pr\u00e9sidentielles de 2020. Son engagement dans la gauche du parti d\u00e9mocrate est clairement affich\u00e9e et nous trouvons trace d&rsquo;elle sur notre site le <a href=\"http:\/\/www.dedefensa.org\/article\/details-sur-les-700-milliards-pour-sauver-wall-street\">13 ao&ucirc;t 2009<\/a>, alors qu&rsquo;elle d\u00e9nonce la fa\u00e7on dont on a couvert Wall Street effondr\u00e9 de $700 milliards d&rsquo;argent public pour relever les banques. (En fait, il s&rsquo;agit de beaucoup plus, mais c&rsquo;est une autre histoire.) &Eacute;l\u00e9gante, tr\u00e8s comp\u00e9tente, assur\u00e9e d&rsquo;elle-m\u00eame et \u00e9rudite, Warren est la progressiste-type de la C\u00f4te Est (par adoption et par temp\u00e9rament), dans la tradition rooseveltienne (et plut\u00f4t Eleanor que Franklin D.). Petite touche d&rsquo;exotisme bien dans l&rsquo;air du temps d&rsquo;aujourd&rsquo;hui : elle assure avoir du sang cheyenne dans sa g\u00e9n\u00e9alogie, ce que Trump conteste avec v\u00e9h\u00e9mence. (On aura compris qu&rsquo;elle d\u00e9teste Trump.) Comme on peut le voir dans son <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Elizabeth_Warren\">impeccable biographie<\/a> <em>Wikip\u00e9dia<\/em>, parfaitement align\u00e9e et \u00e9l\u00e9gamment hagiographique, cette brillante universitaire-s\u00e9natrice aux tr\u00e8s bons sentiments est un pilier du syst\u00e8me de l&rsquo;am\u00e9ricanisme ; \u00ab\u00a0pilier de gauche\u00a0\u00bb, certes, mais le Syst\u00e8me a besoin de tenir sur ses deux pattes&#8230;<\/p>\n<\/p>\n<p><p>&#8230; <strong>Ce qui rend totalement incroyable sa proposition de loi<\/strong>, dont on a vu qu&rsquo;elle une v\u00e9ritable proposition <strong>de \u00ab\u00a0bolchevisation\u00a0\u00bb du syst\u00e8me de l&rsquo;am\u00e9ricanisme<\/strong>. Il est tout aussi incroyable qu&rsquo;on en discute s\u00e9rieusement, m\u00eame si essentiellement pour la critiquer, <strong>comme s&rsquo;il \u00e9tait pensable qu&rsquo;une telle loi puisse \u00eatre d\u00e9battue<\/strong>, &ndash; ce qu&rsquo;elle sera effectivement m\u00eame si (bis) elle est pourtant l&rsquo;instant promise \u00e0 l&rsquo;\u00e9chec ! Dans <a href=\"http:\/\/www.dedefensa.org\/article\/nationaliser-le-capitalisme-us\">le texte cit\u00e9<\/a> pour la <em>Br\u00e8ves de crise <\/em>r\u00e9f\u00e9renc\u00e9e, autant par exemple que <a href=\"https:\/\/www.lewrockwell.com\/lrc-blog\/elizabeth-warren-is-a-weapon-of-mass-destruction-of-capitalism\/\">dans le texte<\/a> de Michael S. Rozeff, sur <em>LewRockwell.com <\/em>le 17 ao&ucirc;t : &laquo; <em>Elizabeth Warren Is A Weapon of Mass Destruction of Capitalism<\/em> &raquo;, sa proposition est effectivement d\u00e9battue \u00ab\u00a0s\u00e9rieusement\u00a0\u00bb (\u00ab\u00a0comme s&rsquo;il \u00e9tait pensable\u00a0\u00bb&#8230;).<\/p>\n<\/p>\n<p><p>En quoi s&rsquo;agit-il de quelque chose d'\u00a0\u00bbincroyable\u00a0\u00bb ? Je me permets ici de me r\u00e9f\u00e9rer \u00e0 ma longue exp\u00e9rience d&rsquo;un demi-si\u00e8cle, qui implique un int\u00e9r\u00eat actif pour les &Eacute;tats-Unis d&rsquo;Am\u00e9rique, aussi bien dans leur \u00e9volution politique dans le sens le plus large du mot que pour son histoire. L&rsquo;impression qui a toujours domin\u00e9 ma perception est <strong>l&rsquo;incompatibilit\u00e9 absolue de l&rsquo;ontologie am\u00e9ricaniste, et partant de sa psychologie, avec le socialisme, avec le communisme, avec le marxisme<\/strong>, et d&rsquo;un autre c\u00f4t\u00e9 l&rsquo;identification totale avec l&rsquo;individualisme, la propri\u00e9t\u00e9 priv\u00e9e <strong>et le capitalisme<\/strong>.<\/p>\n<\/p>\n<p><p>Le socialisme puis le communisme furent constamment per\u00e7us comme subversion pure de l&rsquo;am\u00e9ricanisme, notamment et tr\u00e8s activement \u00e0 partir de l&rsquo;\u00e9pisode fameux de la premi\u00e8re <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Peur_rouge\">Red Scare<\/a> <\/em>culminant en 1919. Si la finance ou d&rsquo;autres forces du capitalisme am\u00e9ricaniste ont paru parfois soutenir clandestinement des courants de subversion marxiste (notamment durant les ann\u00e9es de guerre civile en Russie, malgr\u00e9 l&rsquo;intervention militaire US contre les bolch\u00e9viques), c&rsquo;est toujours avec des intentions tactiques d&rsquo;obtenir certains avantages de march\u00e9s. Une certaine proximit\u00e9 avec des positions trotskistes de divers groupes, de la finance jusqu&rsquo;aux <em>neocons <\/em>d&rsquo;aujourd&rsquo;hui dont l&rsquo;origine trotskiste est connue, ne concerne gu\u00e8re le marxisme de Trotski, mais son universalisme r\u00e9volutionnaire passant par la \u00ab\u00a0r\u00e9volution permanente\u00a0\u00bb qui rejoint par certains aspects importants les th\u00e8ses du \u00ab\u00a0chaos cr\u00e9ateur\u00a0\u00bb du capitalisme, &ndash; toujours valable pour d&rsquo;autres pays que les USA qu&rsquo;il faut briser pour y installer d&rsquo;importants et lucratifs march\u00e9s \u00e0 s&rsquo;approprier. La semi-p\u00e9n\u00e9tration communiste \u00e0 Hollywood, mise en \u00e9vidence par les grandes auditions inquisitoriales de la commission des activit\u00e9s \u00ab\u00a0non-am\u00e9ricaines\u00a0\u00bb (<em>unamerican<\/em>) de la Chambre dans les ann\u00e9es 1946-1950, imm\u00e9diatement avant McCarthy, fut de l&rsquo;ordre du romantisme et de l&rsquo;exotisme, et sans cons\u00e9quence politique structurelle. Le PC des USA, tr\u00e8s vite interdit et de peu d&rsquo;importance sauf pendant les ann\u00e9es tragiques et quasi-r\u00e9volutionnaires de la Grande D\u00e9pression, fut l&rsquo;objet constant de toutes les attentions du FBI sous la houlette impitoyable de Edgar J. Hoover.<\/p>\n<\/p>\n<p><p>Parmi les personnalit\u00e9s politiques ou proches de la politique qu&rsquo;on pouvait soup\u00e7onner de sympathie pour le communisme, ou dans tous les cas pour le socialisme, il n&rsquo;y en eut gu\u00e8re qui put approcher une position institutionnalis\u00e9e (je veux dire vers les plus hauts niveaux du pouvoir de l&rsquo;am\u00e9ricanisme). On pourrait citer <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Henry_Wallace\">Henry Wallace<\/a>, vice-pr\u00e9sident de Roosevelt, qui fut remplac\u00e9 \u00e0 cette fonction par Truman en 1944 sur intervention du <em>DeepState <\/em>d&rsquo;alors, <strong>ce qui nous fit rater de peu une exp\u00e9rience int\u00e9ressante<\/strong> ; Wallace tenta sans succ\u00e8s une candidature pr\u00e9sidentielle en 1948 avec le parti progressiste soutenu par le PC des USA, puis s&rsquo;en d\u00e9tourna rapidement apr\u00e8s s&rsquo;\u00eatre d\u00e9couvert&#8230; anticommuniste. Ce cas de Wallace est d&rsquo;ailleurs int\u00e9ressant en ce qu&rsquo;il nous montre ce qu&rsquo;est (ce qu&rsquo;\u00e9tait ?) <strong>la limite sacril\u00e8ge de l&rsquo;am\u00e9ricanisme, m\u00eame d&rsquo;ultragauche, vis-\u00e0-vis du socialisme-communisme<\/strong>. Les Am\u00e9ricains ultra-progressistes et pacifistes-globalistes, comme Wallace et notamment du temps de Wallace avec la puissance des USA \u00e0 son pinacle, restaient partisans de l&rsquo;am\u00e9ricanisme comme doctrine propre \u00e0 transformer le monde, et donc partisans d&rsquo;un capitalisme plus ou moins r\u00e9formiste.<\/p>\n<\/p>\n<p><p>On comprend alors combien c&rsquo;est bien <strong>en cela que la situation actuelle est extraordinaire et incroyable<\/strong>, et nous en revenons au cas Warren. Un extrait du commentaire de Rozeff sur elle, apr\u00e8s l&rsquo;annonce de son projet de loi identifi\u00e9e comme clairement anticapitaliste (&laquo; <em>une Arme de Destruction Massive du Capitalisme<\/em> &raquo;), est le suivant : &laquo; <em>Le plan de Warren est socialiste et montre clairement qu&rsquo;elle est une sociale-d\u00e9mocrate. Son plan r\u00e9v\u00e8le qu&rsquo;elle est une Bolch\u00e9vique. Les Bolch\u00e9viques \u00e9taient eux aussi des sociaux-d\u00e9mocrates. Au pouvoir apr\u00e8s la r\u00e9volution russe de 1917, ils devinrent le Parti Communiste<\/em>. [&#8230;] <em>Ayant eu la possibilit\u00e9 de condamner nomm\u00e9ment les \u00ab\u00a0Antifa\u00a0\u00bb <\/em>[ultragauche anti-Trump], <em>Warren refusa. Elle s&rsquo;est elle-m\u00eame alli\u00e9e au groupe \u00ab\u00a0Black Lives Matter\u00a0\u00bb. Si nous nous allons derri\u00e8re l&rsquo;apparence des \u00ab\u00a0Antifa\u00a0\u00bb et de \u00ab\u00a0Black Lives Matter\u00a0\u00bb et appr\u00e9cions les conceptions qu&rsquo;ils \u00e9pousent ou les conceptions que les gens influents et conceptuels parmi eux \u00e9pousent, nous d\u00e9couvrons qu&rsquo;ils sont souvent marxistes et anticapitalistes dans leur orientation<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Tout cela semble bien signifier, par le biais de l&rsquo;exemple d&rsquo;Elizabeth Warren, que le capitalisme n&rsquo;est plus en th\u00e9orie quelque chose d&rsquo;intouchable, que le marxisme n&rsquo;est plus cette chose impie excommuni\u00e9e pour l&rsquo;\u00e9ternit\u00e9. D\u00e9sormais, des personnalit\u00e9s du pouvoir de l&rsquo;am\u00e9ricanisme, \u00e9ventuellement une partie de l&rsquo;aile gauche du \u00ab\u00a0parti unique\u00a0\u00bb (les d\u00e9mocrates), s&rsquo;affichent implicitement sinon explicitement marxistes, et aucune r\u00e9action s\u00e9rieuse n&rsquo;est enregistr\u00e9e, et l&rsquo;on voit m\u00eame le <em>DeepState <\/em>coop\u00e9rer, tous plus ou moins aveugl\u00e9s par ce poison \u00e9pouvantable de l&rsquo;antitrumpisme. M\u00eame les adversaires de cette tendance en discutent implicitement, \u00e0 leur insu quant \u00e0 la signification de la chose, c&rsquo;est-\u00e0-dire <strong>comme s&rsquo;il \u00e9tait \u00ab\u00a0pensable\u00a0\u00bb de concevoir un v\u00e9ritable citoyen am\u00e9ricain et dirigeant de l&rsquo;am\u00e9ricanisme favorable au marxisme et \u00e0 la liquidation du capitalisme<\/strong>. Edgar Jay doit s&rsquo;agiter en un v\u00e9ritable tourbillon crisique dans sa tombe&#8230;<\/p>\n<\/p>\n<blockquote>\n<p><p>De ce que je connais et comprend de l&rsquo;am\u00e9ricanisme, il <strong>s&rsquo;agit d&rsquo;une r\u00e9volution copernicienne qui se dessine sous nos yeux<\/strong>, et une r\u00e9volution dont par d\u00e9finition et par logique ontologique l&rsquo;am\u00e9ricanisme <strong>ne pourra pas<\/strong>se relever, ni se transmuter parce qu&rsquo;on ne transmute pas la \u00ab\u00a0Cit\u00e9 de Dieu\u00a0\u00bb <em>Upon the Hill<\/em>. <strong>Le constat qui s&rsquo;impose est bien celui d&rsquo;une fracture \u00e9pouvantable dans la psychologie am\u00e9ricaniste<\/strong>, qui est le ciment formateur et structurant des &Eacute;tats-Unis d&rsquo;Am\u00e9rique.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>L&rsquo;int\u00e9r\u00eat \u00e0 cet \u00e9gard est bien dans cette fracture-l\u00e0 plut\u00f4t que de savoir si les USA risquent de devenir marxistes, ou sociaux-d\u00e9mocrates \u00e0 la sauce bolch\u00e9vique. L&rsquo;affirmation (qui est la mienne en ce cas) selon laquelle <strong>la psychologie de l&rsquo;am\u00e9ricanisme est mortellement touch\u00e9e alimente largement la th\u00e8se de la pathologie, de la d\u00e9mence, etc.<\/strong> ; je veux dire que, <strong>d&rsquo;un point de vue am\u00e9ricaniste <\/strong>dont tous ces gens d\u00e9pendent \u00e0 l&rsquo;origine, rompre sa propre psychologie am\u00e9ricaniste qui est formative de cet \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-lempire-de-la-communication\">empire de la communication<\/a>\u00a0\u00bb des USA en s&rsquo;ouvrant \u00e0 une conception qui implique la liquidation du capitalisme, ne peut \u00eatre autre chose qu&rsquo;un signe de d\u00e9mence. Bien entendu, cela est largement suffisant pour avancer que, dans de telles conditions, le v\u00e9ritable probl\u00e8me qui se pose aujourd&rsquo;hui aux &Eacute;tats-Unis est de savoir comment ne plus exister, comment \u00ab\u00a0se suicider\u00a0\u00bb comme le pr\u00e9disaient quelques grands anc\u00eatres&#8230;<\/p>\n<\/p>\n<p><p>&#8230; R\u00e9p\u00e9tition du <a href=\"http:\/\/www.dedefensa.org\/article\/tourbillon-crisique-48\">T.C.-48<\/a> comme une sorte de leitmotiv : &laquo; <em>Tous les vrais am\u00e9ricanistes l&rsquo;ont pr\u00e9vu ainsi ; que ce soit leur grand pr\u00e9sident Abraham Lincoln (\u00ab\u00a0Si la destruction devait un jour nous atteindre, nous devrions en \u00eatre nous-m\u00eames les premiers et les ultimes artisans. En tant que nation d&rsquo;hommes libres, nous devons \u00e9ternellement survivre, ou mourir en nous suicidant\u00a0\u00bb) ; que ce soit leur grand po\u00e8te Walt Whitman (\u00ab\u00a0Les &Eacute;tats-Unis sont destin\u00e9s \u00e0 remplacer et \u00e0 surpasser l&rsquo;histoire merveilleuse des temps f\u00e9odaux ou ils constitueront le plus retentissant \u00e9chec que le monde ait jamais connu&hellip;\u00a0\u00bb)<\/em>. &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La s\u00e9natrice sacril\u00e8ge 18 ao&ucirc;t 2018 &ndash; Dans ce texte, je fais r\u00e9f\u00e9rence aux deux autres textes du m\u00eame jour, pour \u00e9tablir un lien entre eux deux et constituer ainsi un triangle parfait, compl\u00e8tement isoc\u00e8le, qui figurera la v\u00e9rit\u00e9-de-situation de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me (GCES). Le premierde ces deux textes concerne la s\u00e9natrice&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[11835,13154,3126,13935,4363,4034,8426,4552,4628,5677,17391,3340,11004,18480,3912,945],"class_list":["post-78121","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-11835","tag-antifa","tag-black","tag-bolchevisme","tag-capitalisme","tag-communisme","tag-elizabeth","tag-henry","tag-live","tag-marxisme","tag-matter","tag-presidentielles","tag-radical","tag-ultra-gauchisme","tag-wallace","tag-warren"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78121"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78121\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}