{"id":78136,"date":"2018-08-26T09:30:57","date_gmt":"2018-08-26T09:30:57","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/08\/26\/flaubert-contre-rastignac-et-la-generation-euro-macron\/"},"modified":"2018-08-26T09:30:57","modified_gmt":"2018-08-26T09:30:57","slug":"flaubert-contre-rastignac-et-la-generation-euro-macron","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/08\/26\/flaubert-contre-rastignac-et-la-generation-euro-macron\/","title":{"rendered":"Flaubert contre Rastignac et la g\u00e9n\u00e9ration euro-Macron"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Flaubert contre Rastignac et la g\u00e9n\u00e9ration euro-Macron<\/h2>\n<\/p>\n<p><p>Des antisyst\u00e8mes espagnols (voyez le site elmanifiesto.com) ont \u00e9voqu\u00e9 les &laquo; macroncitos &raquo;, ces jeunes gens unisexe, BCBG bourgeois, bobos, \u00e9mascul\u00e9s et autres, et qui prennent le pouvoir en occident : on a eu Renzi, Macron, Sanchez, Casado, Rivera, les Trudeau, on en aura bien des milliers d&rsquo;autres. On a eu Medvedev en Russie, connu pour son pro-atlantisme&hellip;<\/p>\n<\/p>\n<p><p>Or ces Rastignac de prisunic ont comme tout \u00e9t\u00e9 cr\u00e9\u00e9s au dix-neuvi\u00e8me si\u00e8cle, et par Balzac encore. Et un qui voyait que tout cela, que toute cette adoration du fric, du cul et du pouvoir nous ferait tomber bien bas \u00e9tait Flaubert.<\/p>\n<\/p>\n<p><p>On cite Flaubert :<\/p>\n<\/p>\n<p><p>&laquo; Les h\u00e9ros pervers de Balzac ont, je crois, tourn\u00e9 la t\u00eate \u00e0 bien des gens. La gr\u00eale g\u00e9n\u00e9ration qui s&rsquo;agite maintenant \u00e0 Paris autour du pouvoir et de la renomm\u00e9e a puis\u00e9, dans ces lectures, l&rsquo;admiration b\u00eate d&rsquo;une certaine immoralit\u00e9 bourgeoise \u00e0 quoi elle s&rsquo;efforce d&rsquo;atteindre. &raquo;<\/p>\n<\/p>\n<p><p>J&rsquo;avais cit\u00e9 ces lignes sulfureuses de Z. Marcas de Balzac :<\/p>\n<\/p>\n<p><p>&laquo; Juste, que personne n&rsquo;est venu chercher, et qui ne serait all\u00e9 chercher personne, \u00e9tait, \u00e0 vingt-cinq ans, un profond politique, un homme d&rsquo;une aptitude merveilleuse \u00e0 saisir les rapports lointains entre les faits pr\u00e9sents et les faits \u00e0 venir. Il m&rsquo;a dit en 1831 ce qui devait arriver et ce qui est arriv\u00e9 : les assassinats, les conspirations, le r\u00e8gne des juifs, la g\u00eane des mouvements de la France, la disette d&rsquo;intelligences dans la sph\u00e8re sup\u00e9rieure, et l&rsquo;abondance de talents dans les bas-fonds o&ugrave; les plus beaux courages s&rsquo;\u00e9teignent sous les cendres du cigare. Que devenir ? &raquo;<\/p>\n<\/p>\n<p><p>Balzac parlait aussi de la soci\u00e9t\u00e9 festive bien avant Muray :<\/p>\n<\/p>\n<p><p>&laquo; Apr\u00e8s nous \u00eatre longtemps promen\u00e9s dans les ruines de Palmyre, nous les oubli\u00e2mes, nous \u00e9tions si jeunes ! Puis vint le carnaval, ce carnaval parisien qui, d\u00e9sormais, effacera l&rsquo;ancien carnaval de Venise, et qui dans quelques ann\u00e9es attirera l&rsquo;Europe \u00e0 Paris, si de malencontreux pr\u00e9fets de police ne s&rsquo;y opposent. On devrait tol\u00e9rer le jeu pendant le carnaval ; mais les niais moralistes qui ont fait supprimer le jeu sont des calculateurs imb\u00e9ciles qui ne r\u00e9tabliront cette plaie n\u00e9cessaire que quand il sera prouv\u00e9 que la France laisse des millions en Allemagne. Ce joyeux carnaval amena, comme chez tous les \u00e9tudiants, une grande mis\u00e8re&hellip; &raquo;<\/p>\n<\/p>\n<p><p>Mais revenons \u00e0 Flaubert.<\/p>\n<\/p>\n<p><p>Notre g\u00e9nie ajoute dans sa correspondance :<\/p>\n<\/p>\n<p><p>&laquo; J&rsquo;ai eu des confidences \u00e0 ce sujet. Ce n&rsquo;est plus Werther ou St&minus;Preux que l&rsquo;on veut \u00eatre, mais Rastignac ou Lucien de Rubempr\u00e9. &raquo;<\/p>\n<\/p>\n<p><p>Ah, le mod\u00e8le mim\u00e9tique ! On pense au Descoings de sciences-po d\u00e9crit par mon amie et condisciple Rapha\u00eblle Bacqu\u00e9 et d\u00e9nonc\u00e9 par Drac dans son \u00e9mission.<\/p>\n<\/p>\n<p><p>Et cela donne sous la plume de Flaubert \u00e9c&oelig;ur\u00e9 :<\/p>\n<\/p>\n<p><p>&laquo; D&rsquo;ailleurs tous ces fameux gaillards pratiques, actifs, qui connaissent les hommes, admirent peu l&rsquo;admiration, visent au solide, font du bruit, se d\u00e9m\u00e8nent comme des gal\u00e9riens, etc., tous ces malins, dis&minus;je, me font piti\u00e9, et au point de vue m\u00eame de leur malice, car je les vois sans cesse tendre la gueule apr\u00e8s l&rsquo;ombre et l\u00e2cher la viande. Ils s&rsquo;enferrent dans leurs mensonges, ils se dupent eux&minus;m\u00eames avec aplomb (c&rsquo;est l&rsquo;histoire de Badinguet se payant \u00e0 lui&minus;m\u00eame des enthousiasmes).<\/p>\n<\/p>\n<p><p>Quand j&rsquo;en aurai vu un seul, un seul de ceux&minus;l\u00e0, avoir gagn\u00e9 par tous les moyens qu&rsquo;ils emploient seulement un million, alors je mettrai chapeau bas.<\/p>\n<\/p>\n<p><p>D&rsquo;ici l\u00e0 qu&rsquo;il me soit permis de les consid\u00e9rer comme des \u00e9piciers fourvoy\u00e9s. &raquo;<\/p>\n<\/p>\n<p><p>Balzac remarquait aussi en grand proph\u00e8te postnapol\u00e9onien : &laquo; vous appartenez \u00e0 cette masse d\u00e9cr\u00e9pite que l&rsquo;int\u00e9r\u00eat rend hideuse, qui tremble, qui se recroqueville et qui veut rapetisser la France parce qu&rsquo;elle se rapetisse. &raquo;<\/p>\n<\/p>\n<p><p>Mais Flaubert conclue justement :<\/p>\n<\/p>\n<p><p>&laquo; Nous allons encore descendre longtemps dans cette latrine. &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flaubert contre Rastignac et la g\u00e9n\u00e9ration euro-Macron Des antisyst\u00e8mes espagnols (voyez le site elmanifiesto.com) ont \u00e9voqu\u00e9 les &laquo; macroncitos &raquo;, ces jeunes gens unisexe, BCBG bourgeois, bobos, \u00e9mascul\u00e9s et autres, et qui prennent le pouvoir en occident : on a eu Renzi, Macron, Sanchez, Casado, Rivera, les Trudeau, on en aura bien des milliers d&rsquo;autres.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[12834,18500,2640,13337],"class_list":["post-78136","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-balzac","tag-bobos","tag-bonnal","tag-flaubert"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78136"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78136\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}