{"id":78161,"date":"2018-09-10T05:18:59","date_gmt":"2018-09-10T05:18:59","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/09\/10\/jesus-palomar-et-la-religion-du-bien\/"},"modified":"2018-09-10T05:18:59","modified_gmt":"2018-09-10T05:18:59","slug":"jesus-palomar-et-la-religion-du-bien","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/09\/10\/jesus-palomar-et-la-religion-du-bien\/","title":{"rendered":"J\u00e9sus Palomar et la religion du bien"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d;font-size:1.65em;font-variant:small-caps;\">J\u00e9sus Palomar et la religion du bien<\/h2>\n<\/p>\n<p><p>On a vu que cette notion \u00e9tait \u00e9voqu\u00e9e par l&rsquo;historien Stanley Payne. Elle remplace tout et justifie n&rsquo;importe quelle barbarie humanitaire, le bolch\u00e9visme l\u00e9gislateur, les invasions et la prochaine guerre mondiale.<\/p>\n<\/p>\n<p><p>Le rite sacrificiel est \u00e0 l&rsquo;origine de la civilisation et, par cons\u00e9quent, pratiquement de toutes les religions. Les plus archa\u00efques ont sacrifi\u00e9 une personne qui a toujours \u00e9t\u00e9 consid\u00e9r\u00e9e coupable. Le rituel a donc rendu la paix \u00e0 une communaut\u00e9 parfois tendue.<\/p>\n<\/p>\n<p><p>Selon <strong>Ren\u00e9 Girard<\/strong>, \u00e9crivain et anthropologue fran\u00e7ais, les critiques ont chang\u00e9 le sc\u00e9nario de ce vieux drame : un sacrifice unique que tout le monde a reconnu comme victime innocente a mis fin \u00e0 tous les sacrifices. Depuis lors, du moins en Occident, il suffisait de le rappeler p\u00e9riodiquement de mani\u00e8re symbolique. Pour Girard, cela supposait une <strong>avanc\u00e9e civilisatrice<\/strong>.<\/p>\n<\/p>\n<p><p>Quand il y a un <strong>seul sacrifice<\/strong> reconnu comme innocent, l&rsquo;Humanit\u00e9 est s&oelig;ur : le fils <em>de Dieu<\/em> enl\u00e8ve le p\u00e9ch\u00e9 du monde, et pas seulement d&rsquo;un groupe, d&rsquo;une communaut\u00e9 ou d&rsquo;une nation. Nous sommes tous innocents parce que nous sommes tous coupables. Cependant, lorsque quelqu&rsquo;un est consid\u00e9r\u00e9 comme une victime innocente en raison de son appartenance \u00e0 un groupe, l&rsquo;humanit\u00e9 est fragment\u00e9e : <strong>certains sont les mauvais et les autres les bons<\/strong>. Au nom du progr\u00e8s, il y a un retour et la politique devient une <strong>religion primitive<\/strong> qui ne le sait pas.<\/p>\n<\/p>\n<p><p><em>Au nom de groupes innocents, les groupes d\u00e9sign\u00e9s coupables doivent \u00eatre sacrifi\u00e9s, m\u00eame symboliquement, sur l&rsquo;autel des m\u00e9dias.<\/em><\/p>\n<\/p>\n<p><p>Les illumin\u00e9s modernes qui cherchent \u00e0 r\u00e9inventer l&rsquo;humanit\u00e9 deviennent \u00e0 leur insu les instincts les plus \u00e9l\u00e9mentaires qui sont \u00e0 l&rsquo;origine de tous les <strong>rituels archa\u00efques<\/strong> : au nom des groupes innocents, les groupes d\u00e9sign\u00e9s comme coupables doivent \u00eatre sacrifi\u00e9s, m\u00eame \u00e0 l&rsquo;autel des m\u00e9dias. Mais qui sont les innocents ?<\/p>\n<\/p>\n<p><p>J&rsquo;ai une amie tr\u00e8s contrari\u00e9e que les m\u00e8res montent dans le bus avec leur enfant dans un chariot, mais elle est tr\u00e8s compr\u00e9hensive avec les aveugles qui viennent avec un chien. Et ce n&rsquo;est pas \u00e0 cause d&rsquo;un amour d\u00e9sint\u00e9ress\u00e9 pour les aveugles, mais pour les chiens.<\/p>\n<\/p>\n<p><p>Il y a quelques semaines, la ville de Ciudad Real a approuv\u00e9 l&rsquo;<strong>arr\u00eat \u00e0 la demande<\/strong> des femmes voyageant seules dans des bus circulant la nuit. Un conseiller de l&rsquo;opposition a appel\u00e9 \u00e0 inclure les personnes \u00e2g\u00e9es et handicap\u00e9es parmi les b\u00e9n\u00e9ficiaires, mais la pl\u00e9ni\u00e8re s&rsquo;y est oppos\u00e9e. La raison implicite de ce refus \u00e9trange est facile \u00e0 deviner : les femmes sont innocentes, mais pas les personnes \u00e2g\u00e9es et les handicap\u00e9s.<\/p>\n<\/p>\n<p><p>La \u00ab\u00a0bont\u00e9\u00a0\u00bb, une nouvelle religion<\/p>\n<\/p>\n<p><p>Les adorateurs de la Terre M\u00e8re, de la bestialit\u00e9, les n\u00e9o-f\u00e9ministes, les lgbetistes, les s\u00e9cessionnistes frustr\u00e9s&#8230; sont les nouveaux innocents de la nouvelle \u00ab\u00a0religion archa\u00efque\u00a0\u00bb, et les autres sont d\u00e9clar\u00e9s ath\u00e9es.<\/p>\n<\/p>\n<p><p>Dans la nouvelle religion, la dialectique gr\u00e9gaire des pers\u00e9cut\u00e9s et des pers\u00e9cuteurs, intensifi\u00e9e par la passion mim\u00e9tique que sugg\u00e9rerait Ren\u00e9 Girard, coupe toute tentative de r\u00e9flexion. La langue est termin\u00e9e et <strong>le motif a expir\u00e9<\/strong>. Le visage triste de la \u00ab\u00a0victime innocente\u00a0\u00bb qui grouille \u00e0 travers les r\u00e9seaux sociaux et la t\u00e9l\u00e9vision est la nouvelle v\u00e9rit\u00e9. Tous ceux qui ont des yeux le verront. Pour r\u00e9pondre aux mots, il faut au moins savoir lire. Pour penser, il faut savoir raisonner un peu. Mais les images parlent \u00e0 tout le monde avec une objectivit\u00e9 \u00e9crasante.<\/p>\n<\/p>\n<p><p>Dans cette tension souterraine, la guerre silencieuse, c&rsquo;est celui qui expose le plus de douleur qui gagne. Et comme le chagrin est inobservable, c&rsquo;est le comportement qui y est associ\u00e9 qui vaut la peine : les yeux humides, les sourcils arqu\u00e9s, les larmes et les larmes. Ce sont les nouvelles armes des groupes de victimes autoproclam\u00e9s. L&rsquo;image est tout, preuve incontestable et fondateur de \u00ab\u00a0nouveaux droits\u00a0\u00bb. Les mots ne comptent d\u00e9j\u00e0 que pour quelques-uns. <strong>Lire ou \u00e9crire est un passe-temps de quatre chats<\/strong>.<\/p>\n<\/p>\n<p><p>Si <strong>Marx<\/strong> vivait \u00e0 notre \u00e9poque, il apprendrait \u00e0 \u00eatre un excellent acteur et un photographe expert. Tant de livres \u00e9crits, et si gros, pour quoi ? La phrase de notre Marx moderne dirait : \u00ab\u00a0g\u00e9missements et pleurs du monde entier, unissez-vous!\u00a0\u00bb <\/p>\n<\/p>\n<p><p>Nous ne voulons plus de raisons, <strong>nous voulons des \u00e9motions. <\/strong>M\u00eame les sensations. Un homme politique appara&icirc;t \u00e0 la t\u00e9l\u00e9vision et b\u00e9atement quelqu&rsquo;un s&rsquo;exclame : &laquo; Il me d\u00e9go&ucirc;te, je ne supporte pas &raquo;, et la r\u00e9flexion est termin\u00e9e. La pens\u00e9e exige des efforts et des arguments peuvent \u00eatre discut\u00e9s ; mais le go&ucirc;t et l&rsquo;odorat sont ais\u00e9s, et les go&ucirc;ts et les odeurs ne sont pas r\u00e9futables. Aujourd&rsquo;hui le d\u00e9go&ucirc;t est structurel, ne d\u00e9pend pas de la personne : jeune ou vieux, beau ou laid. S&rsquo;il n&rsquo;y a pas assez de v\u00e9h\u00e9mence dans le discours entendu, les victimes autoproclam\u00e9s proclament leur d\u00e9go&ucirc;t. Elles sont innocentes comme l&#8217;empathie et la cause et seuls les coupables sont d\u00e9go&ucirc;tants. Mais comme ils survivent apr\u00e8s avoir \u00e9t\u00e9 pr\u00e9alablement \u00e9tiquet\u00e9s coupable par les m\u00e9dias et les d\u00e9fenseurs infatigables des innocents, il n&rsquo;y a pas moyen de sortir du cercle. Nous soutenons le monde \u00e9motionnel et sensible de la petite enfance.<strong>La politique est devenue une affaire d&rsquo;odeurs et de go&ucirc;ts<\/strong> ; et le d\u00e9go&ucirc;t est sa cat\u00e9gorie principale.<\/p>\n<\/p>\n<p><p>Les plantes et les animaux sont innocents. Les homosexuels sont innocents. Toutes les femmes sont innocentes et c&rsquo;est pourquoi elles sont des \u00eatres de lumi\u00e8re incapables de mentir ou de commettre un crime. Cependant, il y a beaucoup de personnes coupables d&rsquo;un certain p\u00e9ch\u00e9 originel. Les culpabilit\u00e9s sont nombreuses et vari\u00e9es : \u00eatre blanc et occidental, \u00eatre n\u00e9 de sexe masculin, \u00eatre h\u00e9t\u00e9rosexuel, aimer les taureaux, c\u00e9l\u00e9brer No\u00ebl ou ne pas assez adorer <strong>Ernesto Che Guevara.<\/strong> Certains sont pittoresques ; d&rsquo;autres, apparemment insignifiants et simples. Tant de choses sont \u00e9galement des p\u00e9ch\u00e9s et personne ne devrait pardonner. La bont\u00e9 nourrit la haine comme l&rsquo;essence le feu et doit toujours identifier les m\u00e9chants qui, \u00e9videmment, sont toujours les autres &#8230; Et ils suscitent beaucoup de d\u00e9go&ucirc;t.<\/p>\n<\/p>\n<p><p>Nous visons \u00e0 \u00e9liminer les fronti\u00e8res et \u00e0 abolir l&rsquo;arm\u00e9e. Le monde est un paradis parce que les gens sont innocents et bons ; mais attention, ne sortez pas du \u00ab\u00a0peuple\u00a0\u00bb agr\u00e9\u00e9. La dissidence est un aveu de culpabilit\u00e9. Si vous le faites, vous serez le farceur du parti ind\u00e9sirable de la r\u00e9union, la personnification du mal, le Hitler ressuscit\u00e9 lui-m\u00eame : en bref, le d\u00e9go&ucirc;t en personne. Vous deviendrez alors le candidat id\u00e9al au sacrifice la\u00efc des temps nouveaux : le lynchage impitoyable dans les r\u00e9seaux sociaux et l&rsquo;accusation publique des m\u00e9dias.<\/p>\n<\/p>\n<p><p>J\u00e9sus Palomar, le 5 septembre 2018<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e9sus Palomar et la religion du bien On a vu que cette notion \u00e9tait \u00e9voqu\u00e9e par l&rsquo;historien Stanley Payne. Elle remplace tout et justifie n&rsquo;importe quelle barbarie humanitaire, le bolch\u00e9visme l\u00e9gislateur, les invasions et la prochaine guerre mondiale. Le rite sacrificiel est \u00e0 l&rsquo;origine de la civilisation et, par cons\u00e9quent, pratiquement de toutes les religions.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,2631,6063,18533,6117,6253,3778,7658],"class_list":["post-78161","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-de","tag-girard","tag-lemotion","tag-originel","tag-peche","tag-religion","tag-rene"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78161"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78161\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}