{"id":78162,"date":"2018-09-10T15:34:37","date_gmt":"2018-09-10T15:34:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/09\/10\/leur-censure-notre-bataille\/"},"modified":"2018-09-10T15:34:37","modified_gmt":"2018-09-10T15:34:37","slug":"leur-censure-notre-bataille","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/09\/10\/leur-censure-notre-bataille\/","title":{"rendered":"Leur censure, notre bataille"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Leur censure, notre bataille<\/h2>\n<\/p>\n<p><p>10 septembre 2018 &ndash; La plus grande d\u00e9monstration de l&rsquo;attaque du 11 septembre (un peu en avance, <em>happy birthday America<\/em>) et de la crise qu&rsquo;elle a ouverte, c&rsquo;est <strong>la confirmation symbolique et \u00e9clatante de l&rsquo;importance fondamental du syst\u00e8me de la communication dans l&rsquo;\u00e9quation de la puissance<\/strong>. La chose \u00e9tait d\u00e9j\u00e0 amorc\u00e9e avec la guerre du Kosovo, la premi\u00e8re guerre \u00ab\u00a0virtualiste\u00a0\u00bb (voir <a href=\"http:\/\/www.dedefensa.org\/article\/la-premiere-guerre-virtualiste\">ceci<\/a> et <a href=\"https:\/\/www.amazon.fr\/FR%C3%89D%C3%89RIC-NIETZSCHE-AU-KOSOVO-retrouv%C3%A9-ebook\/dp\/B073XN62BK\/ref=sr_1_3?s=digital-text&#038;ie=UTF8&#038;qid=1508853948&#038;sr=1-3\">cela<\/a>), mais c&rsquo;est avec 9\/11 qu&rsquo;elle s&rsquo;imposa d\u00e9finitivement. J&rsquo;insiste bien sur ce terme de \u00ab\u00a0d\u00e9finitivement\u00a0\u00bb car en m\u00eame temps que le syst\u00e8me de la communication s&rsquo;imposait et que 9\/11 p\u00e9n\u00e9trait et d\u00e9chiquetait notre <a href=\"http:\/\/www.dedefensa.org\/article\/911-un-trou-creuse-dans-lespace-temps\">espace<\/a>&#8211;<a href=\"http:\/\/www.dedefensa.org\/article\/notes-psychanalytiques-et-metaphysiques-sur-911\">temps<\/a>, commen\u00e7ait notre Grande Crise, &ndash; \u00e0 propos de laquelle j&rsquo;ai sans doute agac\u00e9 quelques lecteurs avec des noms et des acronymes diff\u00e9rents, pour me fixer sur GCES, &ndash; Grande Crise d&rsquo;Effondrement du Syst\u00e8me, nous voil\u00e0, nous y sommes&#8230; Ces trois choses sont absolument mari\u00e9es : le syst\u00e8me de la communication, 9\/11 et la GCES, &ndash; pour mesurer <strong>l&rsquo;enjeu diabolique de cette s\u00e9quence ultime <\/strong>de notre civilisation devenue contre-civilisation.<\/p>\n<\/p>\n<p><p>Or, il se trouve que, dans l&rsquo;\u00e9ditorial d\u00e9sormais mensuel de premi\u00e8re page, &ndash; un des exercices les plus fastidieux que je me sois impos\u00e9 lorsqu&rsquo;il \u00e9tait hebdomadaire, pour finalement lui trouver un sens et un int\u00e9r\u00eat certain avec le rythme mensuel, &ndash; j&rsquo;ai, au nom du site <em>dedefensa.org<\/em>, d\u00e9termin\u00e9 comme th\u00e8me des \u00e9v\u00e9nements du mois l&rsquo;\u00e9tablissement de la censure par les \u00ab\u00a0titans <em>high tech<\/em>\u00a0\u00bb contre le syst\u00e8me de la communication dans sa dimension antiSyst\u00e8me :<\/p>\n<\/p>\n<p><p>&laquo; <em>Ce mois d&rsquo;ao&ucirc;t 2018, nous le consacrerions dans notre analyse globale d&rsquo;abord \u00e0 <strong>l&rsquo;\u00e9clatement du ph\u00e9nom\u00e8ne de la censure des \u00ab\u00a0titans high tech\u00a0\u00bb<\/strong>, tous men\u00e9s par de fringants jeunes gens archi-milliardaires qui s&rsquo;affirment comme totalement soumis au Syst\u00e8me, comme totalement serviles, bien plus que tous leurs ain\u00e9s r\u00e9unis, comme si notre \u00e9poque avait accouch\u00e9 d&rsquo;une g\u00e9n\u00e9ration d'\u00a0\u00bbentrepreneurs\u00a0\u00bb f\u00e9cond\u00e9e par le Syst\u00e8me. <strong>Charme de la jeunesse \u00ab\u00a0qui bouge\u00a0\u00bb, qui \u00ab\u00a0fait postmoderne\u00a0\u00bb&#8230;<\/strong><\/em><strong> &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;un \u00e9v\u00e9nement symbolique et op\u00e9rationnel fondamental parce qu&rsquo;il met \u00e0 nu l&rsquo;ontologie du Syst\u00e8me. L&rsquo;\u00e9v\u00e9nement dit clairement et hautement, officiellement si vous voulez, sinon institutionnellement, <strong>que les employ\u00e9s-Syst\u00e8me abandonnent toute la phras\u00e9ologie id\u00e9ologis\u00e9e <\/strong>sur la d\u00e9mocratie, la libert\u00e9 de parole, l&rsquo;un des aspects fondamentaux du \u00ab\u00a0droitdel&rsquo;hommisme\u00a0\u00bb, tout cela <strong>qui leur donne leur l\u00e9gitimit\u00e9 selon leurs propres param\u00e8tres, dans leur propre syst\u00e8me de valeurs<\/strong>. Il s&rsquo;agit par cons\u00e9quent d&rsquo;un tr\u00e8s grand \u00e9v\u00e9nement, d&rsquo;autant plus grand qu&rsquo;il s&rsquo;attaque \u00e0 la force principale qui s&rsquo;est install\u00e9e avec 9\/11, &ndash; le syst\u00e8me de la communication, ainsi priv\u00e9e de sa fonction et de sa vertu fondamentales de l&rsquo;universalit\u00e9 de son assise qui entend se situer hors de toute id\u00e9ologisation particuli\u00e8re, toujours selon leur propre syst\u00e8me de r\u00e9f\u00e9rences\/de valeurs ici interpr\u00e9t\u00e9 dans ce mode d&rsquo;inversion qui leur est coutumier.<\/p>\n<\/p>\n<p><p>(Je ne dis rien de pr\u00e9cis ni de document\u00e9 \u00e0 propos de l&rsquo;efficacit\u00e9 de la chose [leur censure] parce qu&rsquo;il s&rsquo;agit d&rsquo;un tout autre d\u00e9bat qu&rsquo;on ne peut encore trancher. Tout juste dirais-je que <strong>je doute hautement, vraiment tr\u00e8s hautement de son efficacit\u00e9<\/strong>, comme de toute entreprise de censure \u00e0 ce niveau, sur une telle \u00e9tendue, contre une telle complexit\u00e9 et une telle d\u00e9termination de leurs cibles. Ce doute vaut d&rsquo;autant plus que la censure <strong>porte sur la communication, et non sur le contenu directement<\/strong> : c&rsquo;est leur ultime feuille de vigne qu&rsquo;il n&rsquo;ose \u00f4ter en se faisant v\u00e9ritable et brutal censeur-policier de crainte, en sacrifiant leur dernier reste de vertu selon leurs r\u00e9f\u00e9rences\/leurs valeurs, d&rsquo;appara&icirc;tre nus, comme le roi, et de mettre en pleine lumi\u00e8re sonore et bruyante le rien-du-n\u00e9ant qui les caract\u00e9rise.)<\/p>\n<\/p>\n<p><p> Je veux plut\u00f4t m&rsquo;attacher \u00e0 l&rsquo;affirmation de l&rsquo;importance absolument cruciale de cette bataille, <strong>au point que je la jugerais quasiment d\u00e9cisive<\/strong>. Bien entendu, il y a d&rsquo;autres batailles en cours, bien plus palpables, qu&rsquo;on pourrait m&rsquo;opposer comme argument contre cette \u00e9valuation de la chose ; ce qui se passe en Syrie et autour actuellement, par exemple ; ou bien le tourbillon crisique de \u00ab\u00a0D.C.-la-folle\u00a0\u00bb. Cela se plaide sans aucun doute, pourrait-on juger ; pour mon compte cela n&rsquo;a nul besoin de se plaider parce que je consid\u00e8re ces \u00ab\u00a0autres batailles\u00a0\u00bb, et notamment les deux cit\u00e9es, <strong>comme tr\u00e8s fortement d\u00e9pendantes du syst\u00e8me de la communication, et donc int\u00e9gr\u00e9es dans notre bataille g\u00e9n\u00e9rale<\/strong>.<\/p>\n<\/p>\n<p><p>Par cons\u00e9quent, oui, &ndash; \u00ab\u00a0cette bataille est absolument centrale\u00a0\u00bb. Elle l&rsquo;est d&rsquo;autant plus qu&rsquo;elle doit \u00eatre li\u00e9e, pour \u00eatre bien comprise, \u00e0 un autre \u00e9v\u00e9nement dont la centralit\u00e9 d\u00e9cisive est la raison d&rsquo;\u00eatre. C&rsquo;est ce qui est \u00e9crit dans l&rsquo;\u00e9dito d\u00e9j\u00e0 cit\u00e9, et je vous ferais bien la confidence que cela fut \u00e9crit sans doute en pensant \u00e0 ce texte du <em>Journal-dde.crisis<\/em> :<\/p>\n<\/p>\n<p><p>&laquo;<strong> <em>Censure, leur censure&#8230; Cette bataille est absolument centrale, \u00e0 notre sens plus qu&rsquo;aucune autre<\/em><\/strong><em>. Mais elle (leur censure) est aussi le signe que leur crainte, non leur panique, est immense<\/em>. [&#8230;] <em>Par cons\u00e9quent, en m\u00eame temps que cette attaque de la censure, s&rsquo;impose <strong>le th\u00e8me de leur effondrement sous toutes ses formes<\/strong>, &ndash; la Grande Crise d&rsquo;Effondrement du Syst\u00e8me, &ndash; qui reste et doit \u00eatre de plus en plus, <strong>comme une pression dialectique constante de notre part<\/strong>, le sujet essentiel de la presse et de la communication antiSyst\u00e8me<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;id\u00e9e qu&rsquo;il m&rsquo;importe de d\u00e9velopper est celle qui est contenue dans le membre de phrase \u00ab\u00a0une pression dialectique constante de notre part\u00a0\u00bb, cette pression dialectique \u00e9tant figur\u00e9 dans son contenu <strong>par la pr\u00e9vision de l&rsquo;effondrement du Syst\u00e8me<\/strong>. Comme on l&rsquo;a vu, leur censure porte sur la diffusion, d&rsquo;une fa\u00e7on hypocrite parce qu&rsquo;on ne veut tout de m\u00eame pas passer pour des flics aux mains sales (l&rsquo;encre noire du censeur qui barre le mot d&rsquo;un gros trait bien gras), d&rsquo;une fa\u00e7on quantitative parce qu&rsquo;ils ne peuvent rien comprendre de l&rsquo;importance que peut avoir le contenu quand, par sa qualit\u00e9, il approche la v\u00e9rit\u00e9 (<a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-verite-de-situation-verite\">v\u00e9rit\u00e9-de-situation<\/a>).<strong>Ils sont le simulacre qui se moque de l&rsquo;arch\u00e9type<\/strong>.<\/p>\n<\/p>\n<blockquote>\n<p><p>C&rsquo;est l\u00e0, je crois que nous les tenons. Leur censure ne pouvant pr\u00e9tendre \u00e0 tout \u00e0 fait nous faire taire, nous pouvons continuer \u00e0 d\u00e9velopper notre dialectique \u00e0 notre mesure, <strong>\u00e0 la glisser par des interstices diverses dont le syst\u00e8me de la communication est parcouru comme un gruy\u00e8re par ses trous<\/strong>. L&rsquo;ensemble finit par faire une sorte de \u00ab\u00a0bruit de fond\u00a0\u00bb dont le th\u00e8me est l&rsquo;effondrement, et effectivement le th\u00e8me ne cesse de progresser. (Voyez cela dans <a href=\"http:\/\/www.dedefensa.org\/article\/elevation-de-la-critique-crisique\">l&rsquo;\u00e9l\u00e9vation de la critique<\/a> du bloc-antiSyst\u00e8me.) <strong>Pour contrebattre cela, ils cr\u00e9ent toujours plus de simulacres comme on d\u00e9bite des saucisses, sans pr\u00eater la moindre attention au contenu<\/strong>, au vide qui les habite, \u00e0 l&rsquo;absurdit\u00e9 qui les meut lorsque ces simulacres pr\u00e9tendent incarner des vertus qu&rsquo;ils ne cessent de profaner au travers de <em>narrative <\/em>dont le cr\u00e9dit vaut \u00e0 peu pr\u00e8s celui qu&rsquo;on peut faire aux banques de Wall Street et de la <em>City<\/em>. (<strong>Toujours la quantit\u00e9 pr\u00e9f\u00e9r\u00e9e \u00e0 la qualit\u00e9<\/strong>, cela correspond si bien \u00e0 ce qu&rsquo;ils sont.)<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est cela que j&rsquo;appelle \u00ab\u00a0pression dialectique\u00a0\u00bb exerc\u00e9e par le \u00ab\u00a0bruit de fond\u00a0\u00bb, <strong>les obligeant de plus en plus \u00e0 se justifier, \u00e0 proclamer la sublimit\u00e9 de ces \u00e9normes simulacres gonfl\u00e9s comme des ballons trou\u00e9s-rapi\u00e9c\u00e9s<\/strong>. Cette pression qui les oblige \u00e0 proclamer que le cadavre puant qu&rsquo;ils exaltent est bien vivant, toujours vivant, de plus en plus vivant, attirant ainsi l&rsquo;attention des distraits ou des indiff\u00e9rents sur leur situation effective de cadavre puant, acc\u00e9l\u00e9rant l&rsquo;effondrement.<\/p>\n<\/p>\n<p><p>Il n&rsquo;est pas de bataille plus d\u00e9cisive que celle-l\u00e0, qui parvient \u00e0 convaincre le monstre furieux et pr\u00eat \u00e0 briser le monde qu&rsquo;en v\u00e9rit\u00e9 il est en train de se d\u00e9truire lui-m\u00eame. Cette id\u00e9e que je vous expose ne peut \u00eatre justifi\u00e9e, <strong>elle se justifie d&rsquo;elle-m\u00eame parce qu&rsquo;elle se nourrit d&rsquo;une intuition qui me d\u00e9passe<\/strong>.<\/p>\n<\/p>\n<p><p>J&rsquo;attends donc avec patience que les choses aillent de plus en plus vite.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leur censure, notre bataille 10 septembre 2018 &ndash; La plus grande d\u00e9monstration de l&rsquo;attaque du 11 septembre (un peu en avance, happy birthday America) et de la crise qu&rsquo;elle a ouverte, c&rsquo;est la confirmation symbolique et \u00e9clatante de l&rsquo;importance fondamental du syst\u00e8me de la communication dans l&rsquo;\u00e9quation de la puissance. La chose \u00e9tait d\u00e9j\u00e0 amorc\u00e9e&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[354,370,7894,3015,2631,6365,2803,8555,13053,3085,2622,5579,12812,3965,3014],"class_list":["post-78162","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-354","tag-370","tag-bruit","tag-communication","tag-de","tag-dialectique","tag-effondrement","tag-fond","tag-gces","tag-kosovo","tag-la","tag-pression","tag-quantite","tag-simulacre","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78162"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78162\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}