{"id":78167,"date":"2018-09-13T01:45:30","date_gmt":"2018-09-13T01:45:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/09\/13\/etre-un-homme\/"},"modified":"2018-09-13T01:45:30","modified_gmt":"2018-09-13T01:45:30","slug":"etre-un-homme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/09\/13\/etre-un-homme\/","title":{"rendered":"\u00catre un homme"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">&Ecirc;tre un homme<\/h2>\n<\/p>\n<p><p>Sur le dernier tron\u00e7on du chemin qui conduit jusqu&rsquo;\u00e0 lui, si la saison le permet, les rosiers trouent de leur vivacit\u00e9 les haies de buis et de tro\u00e8ne. Des hortensias \u00e9talent avec prodigalit\u00e9 des tonalit\u00e9s ind\u00e9cises, des cama\u00efeux de rose p\u00e2le au bleu lavande enchantent le marcheur. Des tournesols, plac\u00e9s en bordure de jardins ouvriers, quand ils ne sont pas d\u00e9j\u00e0 d\u00e9garnis et r\u00e9form\u00e9s pour vigueur pass\u00e9e,  pointent leur jaune insolent vers un ciel indolent. Leur or refuse de rouiller,  d\u00e9chire le silence de ce morceau de nature domestiqu\u00e9e qui va entrer en somnolence dans un nouvel automne.<\/p>\n<\/p>\n<p><p>Une tr\u00e8s l\u00e9g\u00e8re brise les fait se dodeliner et caresse les joues de celui qui h\u00e2te maintenant son pas. <\/p>\n<\/p>\n<p><p>Une fronti\u00e8re est nettement dessin\u00e9e.<\/p>\n<\/p>\n<p><p>Le m\u00e9tal rutile sous des rayons encore drus.<\/p>\n<\/p>\n<p><p>Plusieurs haltes sont n\u00e9cessaires pour franchir la multiplicit\u00e9 de la limitation entre le dehors et le dedans, comme autant de couches superpos\u00e9es qui figurent la membrane d&rsquo;une cellule eucaryote. L&rsquo;admission exige que soit d\u00e9pos\u00e9 d\u00e8s le filtre premier le morceau de plastique qui t\u00e9moigne de l&rsquo;identit\u00e9, ce dont on s&rsquo;acquitte avec bonhomie au terme d&rsquo;un long voyage.<\/p>\n<\/p>\n<p><p>L&rsquo;acc\u00e8s est obtenu.<\/p>\n<\/p>\n<p><p>Il d\u00e9bouche sur un espace divis\u00e9 en petites unit\u00e9s, garnies chacune de chaises de jardin moul\u00e9es dans une mauvaise r\u00e9sine blanche, deux ou trois autour d&rsquo;une table minuscule.<\/p>\n<\/p>\n<p><p>Les salutations un peu embrouill\u00e9es par des \u00e9motions diverses et intenses faites, l&rsquo;entretien d\u00e9bute.<\/p>\n<\/p>\n<p><p>Les \u00e9changes sont rapides, les questions enveloppent le visiteur et d\u00e9veloppent les actualit\u00e9s, le temps est bien compt\u00e9. Affable, d\u00e9licat, enjou\u00e9 avec une pointe d&rsquo;humour qui d\u00e9borde quand il dresse pour son usage le portrait de son visiteur par petites touches apport\u00e9es par la substance du dialogue qui efface les murs et \u00e9largit la petite pi\u00e8ce aveugle. Il ne se d\u00e9fait \u00e0 aucun moment de l&rsquo;attention qu&rsquo;il lui porte.<\/p>\n<\/p>\n<p><p>Une grande force spirituelle impr\u00e8gne le moment.<\/p>\n<\/p>\n<p><p>L&rsquo;atmosph\u00e8re est imbib\u00e9e d&rsquo;une bienveillance tranquille, apais\u00e9e.<\/p>\n<\/p>\n<p><p>Un optimisme raisonnable est le germe de cette foi dans un avenir meilleur pour l&rsquo;homme, dans un monde d\u00e9barrass\u00e9 de l&rsquo;oppression, au sein de soci\u00e9t\u00e9s solidement construites sur la justice. Le d\u00e9litement saugrenu de toutes les formes d&rsquo;organisations sociales doit conduire \u00e0 la concr\u00e9tisation de cette id\u00e9e si simple \u00e0 r\u00e9aliser. Les repl\u00e2trages et les mensonges faits pour verrouiller toute pens\u00e9e et toute action sont d&rsquo;une fragilit\u00e9 de plus en plus manifeste.<\/p>\n<\/p>\n<p><p>Parce qu&rsquo;on aurait voulu qu&rsquo;ils ne fussent pas, interrompant \u00e0 l&#8217;emporte-pi\u00e8ce la discussion de plus en plus pr\u00e9cise, les adieux sont maladroits et vite escamot\u00e9s de la m\u00e9moire. Longtemps un apaisement indicible habite le visiteur apr\u00e8s que le visit\u00e9 ne l&rsquo;ait quitt\u00e9, effet de l&rsquo;\u00e9nergie morale irradi\u00e9e et emmagasin\u00e9e pr\u00e9cieusement comme viatique pour le chemin du retour.<\/p>\n<\/p>\n<p><p>Les larmes viennent apr\u00e8s un certain temps, abondantes,  nourries de l&rsquo;impuissance  individuelle et collective \u00e0 lib\u00e9rer le plus vieux prisonnier politique de France.<\/p>\n<\/p>\n<p><p> Georges Ibrahim Abdallah, \u00e9crou num\u00e9ro 2388\/A221, centre p\u00e9nitencier de Lannemezan, 6530,  entamera sa trente cinqui\u00e8me ann\u00e9e de prison en octobre 2018.<\/p>\n<\/p>\n<p><p>Il est l&rsquo;un de ceux qui demeurent d&rsquo;une fid\u00e9lit\u00e9 inflexible \u00e0 leurs motivations politiques d&rsquo;ind\u00e9pendance de tous les pays assujettis \u00e0 l&rsquo;imp\u00e9rialisme et \u00e0 l&rsquo;id\u00e9al communiste de justice sociale et d&rsquo;\u00e9mancipation pour tous les hommes. Toutes ces ann\u00e9es d&rsquo;incarc\u00e9ration n&rsquo;ont en rien att\u00e9nu\u00e9 sa flamme et son d\u00e9sir que son id\u00e9al s&rsquo;atteigne un jour. Au contraire, elles les ont concentr\u00e9s, faisant de lui, d\u00e9tenu depuis des d\u00e9cennies, l&rsquo;Homme, rare, le plus libre et le plus hautement moral qui soit. Toutes ces cl\u00f4tures, foss\u00e9s, barbel\u00e9s, murailles laissent passer jusqu&rsquo;\u00e0 lui les informations d&rsquo;un capitalisme devenu de plus en plus aberrant. Georges reste imperm\u00e9able aux in\u00e9vitables d\u00e9g\u00e9n\u00e9rescences de jugement port\u00e9 sur le devenir de ce mode de production et mode de vie ali\u00e9n\u00e9e. Il est certain que l&rsquo;humanit\u00e9 en triomphera. *<\/p>\n<\/p>\n<p><h4>Badia Benjelloun<\/h4>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Note<\/h3>\n<\/p>\n<p><p>Voici une note biographique pour ceux qui ignoreraient qui est Georges Ibrahim ABDALLAH<\/p>\n<\/p>\n<p><p>Monsieur Georges Ibrahim Abdallah est un prisonnier politique libanais d\u00e9tenu en France depuis 1984. Il avait \u00e9t\u00e9 condamn\u00e9 en 1987 \u00e0 la r\u00e9clusion criminelle \u00e0 perp\u00e9tuit\u00e9 avec une peine de s&ucirc;ret\u00e9 pour complicit\u00e9 d&rsquo;assassinat de l&rsquo;attach\u00e9 militaire de l&rsquo;ambassade am\u00e9ricaine Charles Ray et du diplomate isra\u00e9lien Yacov Barsimentov, abattus \u00e0 Paris en 1982. Ces assassinats ont \u00e9t\u00e9 revendiqu\u00e9s par les Fractions arm\u00e9es r\u00e9volutionnaires libanaises (FARL) et commis dans le cadre de la lutte contre l&rsquo;occupation du Liban par Isra\u00ebl. <\/p>\n<\/p>\n<p><p>Il est lib\u00e9rable depuis 1999. <\/p>\n<\/p>\n<p><p>A chacun des jugements favorables \u00e0 sa lib\u00e9ration, l&rsquo;&Eacute;tat fran\u00e7ais est intervenu pour emp\u00eacher cette lib\u00e9ration. <\/p>\n<\/p>\n<p><p>Le 24 octobre 2018, Georges Ibrahim Abdallah entrera dans sa 35i\u00e8me ann\u00e9e de d\u00e9tention. <\/p>\n<\/p>\n<p><p><strong>Il aurait d&ucirc; \u00eatre lib\u00e9r\u00e9 : <\/strong><\/p>\n<\/p>\n<p><p>&bull; D\u00e8s <strong>1984<\/strong>, comme la France s&rsquo;y \u00e9tait engag\u00e9e aupr\u00e8s du gouvernement alg\u00e9rien ; <\/p>\n<\/p>\n<p><p>&bull; En <strong>1985<\/strong>, lors de l&rsquo;\u00e9change avec Gilles Sydney Peyroles auquel l&rsquo;Etat fran\u00e7ais s&rsquo;\u00e9tait engag\u00e9e ; <\/p>\n<\/p>\n<p><p>&bull; En <strong>1988<\/strong>, s&rsquo;il n&rsquo;avait pas \u00e9t\u00e9 rejug\u00e9 apr\u00e8s son premier proc\u00e8s en juillet 1986 (o&ugrave; a \u00e9t\u00e9 prononc\u00e9s la d\u00e9cision d&rsquo;interdiction du territoire fran\u00e7ais) ; <\/p>\n<\/p>\n<p><p>&bull; En <strong>1994<\/strong>, si la peine applicable aux droits communs pour ce type de d\u00e9lit comme r\u00e9clam\u00e9 par le procureur, conform\u00e9ment au code de proc\u00e9dure p\u00e9nale, avait \u00e9t\u00e9 retenu en mars 1987 lors du second proc\u00e8s. <\/p>\n<\/p>\n<p><p>&bull; En <strong>1999<\/strong>, si la peine de s&ucirc;ret\u00e9 avait \u00e9t\u00e9 strictement appliqu\u00e9e <\/p>\n<\/p>\n<p><p>&bull; En <strong>2003<\/strong>, quand le juge des libert\u00e9s de Pau a \u00e9mis un avis favorable \u00e0 sa lib\u00e9ration conditionnelle, mais que l&rsquo;ex\u00e9cutif a refus\u00e9 de mettre en &oelig;uvre la mesure d&rsquo;expulsion vers son pays d&rsquo;origine et a fait appel pour obtenir le rejet de la demande de mise en libert\u00e9 conditionnelle. <\/p>\n<\/p>\n<p><p>&bull; En <strong>2013<\/strong>, quand le tribunal d&rsquo;application des peines a \u00e9mis un avis favorable en attente d&rsquo;un arr\u00eat\u00e9 d&rsquo;expulsion du minist\u00e8re de l&rsquo;Int\u00e9rieur, mais que l&rsquo;ex\u00e9cutif a refus\u00e9 de mettre en &oelig;uvre et a fait appel. En 2014, 2015 et 2016, les demandes de lib\u00e9ration sont jug\u00e9es, par tous les niveaux judiciaires, irrecevables en l&rsquo;absence de mesure d&rsquo;\u00e9loignement. <\/p>\n<\/p>\n<p><p>Il a plus que doubl\u00e9 la peine incompressible, nous devons permettre les conditions pour que le pouvoir politique lui rende enfin sa libert\u00e9 car la perp\u00e9tuit\u00e9 n&rsquo;existe pas en France. <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Ecirc;tre un homme Sur le dernier tron\u00e7on du chemin qui conduit jusqu&rsquo;\u00e0 lui, si la saison le permet, les rosiers trouent de leur vivacit\u00e9 les haies de buis et de tro\u00e8ne. Des hortensias \u00e9talent avec prodigalit\u00e9 des tonalit\u00e9s ind\u00e9cises, des cama\u00efeux de rose p\u00e2le au bleu lavande enchantent le marcheur. Des tournesols, plac\u00e9s en bordure&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3324,10959,3953,18536,9112,12691,18535,16100,4607,6859],"class_list":["post-78167","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-abdallah","tag-badia","tag-benjelloun","tag-farl","tag-georges","tag-ibrahim","tag-libanais","tag-perpetuite","tag-politique","tag-prisonnier"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78167"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78167\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}