{"id":78224,"date":"2018-10-13T11:26:01","date_gmt":"2018-10-13T11:26:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/13\/roland-barthes-et-la-profonde-alterite-russe-en-1956\/"},"modified":"2018-10-13T11:26:01","modified_gmt":"2018-10-13T11:26:01","slug":"roland-barthes-et-la-profonde-alterite-russe-en-1956","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/13\/roland-barthes-et-la-profonde-alterite-russe-en-1956\/","title":{"rendered":"Roland Barthes et la profonde alt\u00e9rit\u00e9 russe (en 1956)"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Roland Barthes et la profonde alt\u00e9rit\u00e9 russe (en 1956)<\/h2>\n<\/p>\n<p><p>Les d\u00e9lires occidentaux en mati\u00e8re russe n&rsquo;ont h\u00e9las rien de neuf. Relisons le d\u00e9but du journal de Dosto\u00efevski :<\/p>\n<\/p>\n<p><p>&laquo; Quand il s&rsquo;agit de la Russie, une imb\u00e9cillit\u00e9 enfantine s&#8217;empare de ces m\u00eames hommes qui ont invent\u00e9 la poudre et su compter tant d&rsquo;\u00e9toiles dans le ciel qu&rsquo;ils croient vraiment pouvoir les toucher. &raquo;<\/p>\n<\/p>\n<p><p>Dosto\u00efevski ajoute que ces russes extra-terrestres &laquo; tiennent \u00e0 la fois de l&rsquo;Europ\u00e9en et du Barbare. On sait que notre peuple est assez ing\u00e9nieux, mais qu&rsquo;il manque de g\u00e9nie propre ; qu&rsquo;il est tr\u00e8s beau ; qu&rsquo;il vit dans des cabanes de bois nomm\u00e9es isbas, mais que son d\u00e9veloppement intellectuel est retard\u00e9 par les paralysantes gel\u00e9es hivernales. &raquo;<\/p>\n<\/p>\n<p><p>Le russe est rest\u00e9 l&rsquo;\u00eatre inf\u00e9rieur et l&rsquo;automate qu&rsquo;il \u00e9tait chez Custine (lisez mon texte sur lesakerfrancophone.fr) :<\/p>\n<\/p>\n<p><p>&laquo;  On n&rsquo;ignore pas que la Russie encaserne une arm\u00e9e tr\u00e8s nombreuse, mais on se figure que le soldat russe, simple m\u00e9canisme perfectionn\u00e9, bois et ressort, ne pense pas, ne sent pas, ce qui explique son involontaire bravoure dans le combat ; que cet automate sans ind\u00e9pendance est \u00e0 tous les points de vues \u00e0 cent piques au-dessous du troupier fran\u00e7ais&hellip; &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;est que le russe est pire que la lune ; il est inconnaissable :<\/p>\n<\/p>\n<p><p>&laquo; La Russie est ouverte \u00e0 tous les Europ\u00e9ens ; les Russes sont l\u00e0, \u00e0 la port\u00e9e des investigations occidentales, et pourtant le caract\u00e8re d&rsquo;un Russe est peut-\u00eatre plus mal compris en Europe que le caract\u00e8re d&rsquo;un Chinois ou d&rsquo;un Japonais. La Russie est, pour le Vieux Monde, l&rsquo;une des \u00e9nigmes du Sphinx. On trouvera le mouvement perp\u00e9tuel avant d&rsquo;avoir saisi, en Occident, l&rsquo;esprit russe, sa nature et son orientation. &Agrave; ce point de vue l\u00e0 je crois que la Lune est explor\u00e9e presque aussi compl\u00e8tement que la Russie. On sait qu&rsquo;il y a des habitants en Russie, et voil\u00e0 toute la diff\u00e9rence. Mais quels hommes sont ces Russes ? C&rsquo;est un probl\u00e8me, c&rsquo;en est encore un, bien que les Europ\u00e9ens croient l&rsquo;avoir depuis longtemps r\u00e9solu. &raquo;<\/p>\n<\/p>\n<p><p>Si l&rsquo;auteur de l&rsquo;Idiot \u00e9voque la lune, c&rsquo;est pour souligner cette alt\u00e9rit\u00e9 extra-terrestre ; mais un si\u00e8cle plus tard, Barthes \u00e9voquera en riant Mars. C&rsquo;est dans ses Mythologies o&ugrave; Barthes d\u00e9monte les m\u00e9canismes de la pens\u00e9e m\u00e9diocre, social-radicale et petite-bourgeoise fran\u00e7aise qui reprit son envol avec Hollande :<\/p>\n<\/p>\n<p><p>&laquo; Le myst\u00e8re des Soucoupes Volantes a d&rsquo;abord \u00e9t\u00e9 tout terrestre : on supposait que la soucoupe venait de l&rsquo;inconnu sovi\u00e9tique, de ce monde aussi priv\u00e9 d&rsquo;intentions claires qu&rsquo;une autre plan\u00e8te. Et d\u00e9j\u00e0 cette forme du mythe contenait en germe son d\u00e9veloppement plan\u00e9taire ; si la soucoupe d&rsquo;engin sovi\u00e9tique est devenue si facilement engin martien, c&rsquo;est qu&rsquo;en fait la mythologie occidentale attribue au monde communiste l&rsquo;alt\u00e9rit\u00e9 m\u00eame d&rsquo;une plan\u00e8te : l&rsquo;URSS est un monde interm\u00e9diaire entre la Terre et Mars. &raquo;<\/p>\n<\/p>\n<p><p>A l&rsquo;\u00e9poque de Barthes (1954-56 donc) le conflit est-ouest et le d\u00e9lire martien doit aboutir \u00e0 la mondialisation (voyez le classique de Robert Wise The day the earth stood still). Et cela donne sous notre plume acerbe :<\/p>\n<\/p>\n<p><p>&laquo; La grande contestation URSS-USA est donc d\u00e9sormais sentie comme un \u00e9tat coupable, parce qu&rsquo;ici le danger est sans mesure avec le bon droit ; d&rsquo;o&ugrave; le recours mythique \u00e0 un regard c\u00e9leste, assez puissant pour intimider les deux parties. &raquo;<\/p>\n<\/p>\n<p><p>La soucoupe volante c&rsquo;est aussi une arme secr\u00e8te, notion que les russes ont remise \u00e0 la mode r\u00e9cemment (les articles pullulent, y compris les sceptiques). Barthes \u00e9crit :<\/p>\n<\/p>\n<p><p>&laquo; Les analystes de l&rsquo;avenir pourront expliquer les \u00e9l\u00e9ments figuratifs de cette puissance, les th\u00e8mes oniriques qui la composent : la rondeur de l&rsquo;engin, le lisse de son m\u00e9tal, cet \u00e9tat superlatif du monde que serait une mati\u00e8re sans couture : a contrario, nous comprenons mieux tout ce qui dans notre champ perceptif participe au th\u00e8me du Mal : les angles, les plans irr\u00e9guliers, le bruit, le discontinu des surfaces. Tout cela a d\u00e9j\u00e0 \u00e9t\u00e9 minutieusement pos\u00e9 dans les romans d&rsquo;anticipation, dont la psychose martienne ne fait que reprendre \u00e0 la lettre les descriptions. &raquo;<\/p>\n<\/p>\n<p><p>A l&rsquo;\u00e9poque la SF nous rassure. Les martiens ne peuvent \u00eatre que comme nous. Le caustique auteur de S\/Z Seraphita ajoute :<\/p>\n<\/p>\n<p><p>&laquo; Ce qu&rsquo;il y a de plus significatif, c&rsquo;est que Mars est implicitement dou\u00e9e d&rsquo;un d\u00e9terminisme historique calqu\u00e9 sur celui de la Terre. Si les soucoupes sont les v\u00e9hicules de g\u00e9ographes martiens venus observer la configuration de la Terre, comme l&rsquo;a dit tout haut je ne sais quel savant am\u00e9ricain, et comme sans doute beaucoup le pensent tout bas, c&rsquo;est que l&rsquo;histoire de Mars a m&ucirc;ri au m\u00eame rythme que celle de notre monde, et produit des g\u00e9ographes dans le m\u00eame si\u00e8cle o&ugrave; nous avons d\u00e9couvert la g\u00e9ographie et la photographie a\u00e9rienne. La seule avance est celle du v\u00e9hicule lui-m\u00eame, Mars n&rsquo;\u00e9tant ainsi qu&rsquo;une Terre r\u00eav\u00e9e, dou\u00e9e d&rsquo;ailes parfaites comme dans tout r\u00eave d&rsquo;id\u00e9alisation. &raquo;<\/p>\n<\/p>\n<p><p>Barthes conclut logiquement :<\/p>\n<\/p>\n<p><p>&laquo; Probablement que si nous d\u00e9barquions \u00e0 notre tour en Mars telle que nous l&rsquo;avons construite, nous n&rsquo;y trouverions que la Terre elle-m\u00eame, et entre ces deux produits d&rsquo;une m\u00eame Histoire, nous ne saurions d\u00e9m\u00ealer lequel est le n\u00f4tre. Car pour que Mars en soit rendue au savoir g\u00e9ographique, il faut bien qu&rsquo;elle ait eu, elle aussi, son Strabon, son Michelet, son Vidal de La Blache et, de proche en proche, les m\u00eames nations, les m\u00eames guerres, les m\u00eames savants et les m\u00eames hommes que nous. &raquo;<\/p>\n<\/p>\n<p><p>Barthes d\u00e9crit ensuite nos r\u00e9actions dans La croisi\u00e8re du &laquo; Batory &raquo; :<\/p>\n<\/p>\n<p><p>&laquo; Puisqu&rsquo;il y a d\u00e9sormais des voyages bourgeois en Russie sovi\u00e9tique, la grande presse fran\u00e7aise a commenc\u00e9 d&rsquo;\u00e9laborer quelques mythes d&rsquo;assimilation de la r\u00e9alit\u00e9 communiste. MM. Sennep et Macaigne, du Figaro, embarqu\u00e9s sur le Batory, ont fait dans leur journal l&rsquo;essai d&rsquo;un alibi nouveau, l&rsquo;impossibilit\u00e9 de juger un pays comme la Russie en quelques jours. Foin des conclusions h\u00e2tives, d\u00e9clare gravement M. Macaigne, qui se moque beaucoup de ses compagnons de voyage et de leur manie g\u00e9n\u00e9ralisatrice. &raquo;<\/p>\n<\/p>\n<p><p>Notre critique ajoute :<\/p>\n<\/p>\n<p><p>&laquo; Il est assez savoureux de voir un journal qui fait de l&rsquo;antisovi\u00e9tisme \u00e0 longueur d&rsquo;ann\u00e9e sur des ragots mille fois plus improbables qu&rsquo;un s\u00e9jour r\u00e9el en URSS, si court soit-il, traverser une crise d&rsquo;agnosticisme et se draper noblement dans les exigences de l&rsquo;objectivit\u00e9 scientifique, au moment m\u00eame o&ugrave; ses envoy\u00e9s peuvent enfin approcher ce dont ils parlaient si volontiers de loin et d&rsquo;une mani\u00e8re si tranchante. &raquo;<\/p>\n<\/p>\n<p><p>A l&rsquo;\u00e9poque le journaliste du Figaro d\u00e9crit la rue (voyez le d\u00e9lirium durant la coupe du monde de foot) :<\/p>\n<\/p>\n<p><p>&laquo; La rue est devenue tout d&rsquo;un coup un terrain neutre, o&ugrave; l&rsquo;on peut noter, sans pr\u00e9tendre conclure. Mais on devine de quelles notations il s&rsquo;agit. Car cette honn\u00eate r\u00e9serve n&#8217;emp\u00eache nullement le touriste Macaigne de signaler dans la vie imm\u00e9diate quelques accidents disgracieux, propres \u00e0 rappeler la vocation barbare de la Russie sovi\u00e9tique : les locomotives russes font entendre un long meuglement sans rapport avec le sifflet des n\u00f4tres ; le quai des gares est en bois ; les h\u00f4tels sont mal tenus; il y a des inscriptions chinoises sur les wagons (th\u00e8me du p\u00e9ril jaune) ; enfin, fait qui r\u00e9v\u00e8le une civilisation v\u00e9ritablement arri\u00e9r\u00e9e, on ne trouve pas de bistrots en Russie, rien que du jus de poire ! &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;important pour le bourgeois fran\u00e7ais est de rester sup\u00e9rieur :<\/p>\n<\/p>\n<p><p>&laquo; D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, le voyage en URSS sert surtout \u00e0 \u00e9tablir le palmar\u00e8s bourgeois de la civilisation occidentale : la robe parisienne, les locomotives qui sifflent et ne meuglent pas, les bistrots, le jus de poire d\u00e9pass\u00e9, et surtout, le privil\u00e8ge fran\u00e7ais par excellence ; Paris, c&rsquo;est-\u00e0-dire un mixte de grands couturiers et de Folies-Berg\u00e8res ; c&rsquo;est ce tr\u00e9sor inaccessible qui, para&icirc;t-il, fait r\u00eaver les Russes \u00e0 travers les touristes du Batory&hellip; &raquo;<\/p>\n<\/p>\n<p><p>C&rsquo;\u00e9tait avant les oligarques consommateurs&hellip; Et Barthes de conclure :<\/p>\n<\/p>\n<p><p>&laquo; C&rsquo;est donc une fois seulement qu&rsquo;il a \u00e9t\u00e9 illumin\u00e9 par le soleil de la civilisation capitaliste, que le peuple russe peut \u00eatre reconnu spontan\u00e9, affable, g\u00e9n\u00e9reux. Il n&rsquo;y a plus alors que des avantages \u00e0 d\u00e9voiler sa gentillesse d\u00e9bordante : elle signifie toujours une d\u00e9ficience du r\u00e9gime sovi\u00e9tique, une pl\u00e9nitude du bonheur occidental : la reconnaissance &laquo; indescriptible &raquo; de la jeune guide de l&rsquo;intourist pour le m\u00e9decin (de Passy) qui lui offre des bas nylon, signale en fait l&rsquo;arri\u00e9ration \u00e9conomique du r\u00e9gime communiste et la prosp\u00e9rit\u00e9 enviable de la d\u00e9mocratie occidentale. &raquo;<\/p>\n<\/p>\n<p><p>Dans la conclusion Barthes tord le cou \u00e0 la gauche bourgeoise qui bient\u00f4t prendrait le tournant soci\u00e9tal (lui \u00e9crivant pour l&rsquo;Observateur devait s&rsquo;en rendre compte) :<\/p>\n<\/p>\n<p><p><strong>&laquo; On m&rsquo;a demand\u00e9 s&rsquo;il y avait des mythes &laquo;\u00e0 gauche&raquo;. Bien s&ucirc;r, dans la mesure m\u00eame o&ugrave; la gauche n&rsquo;est pas la r\u00e9volution. <\/strong>Le mythe de gauche surgit pr\u00e9cis\u00e9ment au moment o&ugrave; la r\u00e9volutionse transforme en &laquo; gauche &raquo;, c&rsquo;est-\u00e0-dire accepte de semasquer, de voiler son nom, de produire un m\u00e9ta-langage innocentet de se d\u00e9former en &laquo; Nature &raquo;.<\/p>\n<\/p>\n<p><p>Sous le jargon h\u00e9las v\u00e9tuste le m\u00eame propos : on laisse tomber le peuple et on r\u00e9pand des propos russophobes. La russophobie f\u00e9roce remplacera f\u00e9rocement la r\u00e9volte des masses enfouie.<\/p>\n<\/p>\n<p><p>Sources<\/p>\n<\/p>\n<p><p>Roland Barthes &ndash; Mythologies<\/p>\n<\/p>\n<p><p>Dosto\u00efevski &#8211; Journal<\/p>\n<\/p>\n<p><p>Nicolas Bonnal &ndash; Dosto\u00efevski et la modernit\u00e9 occidentale<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Roland Barthes et la profonde alt\u00e9rit\u00e9 russe (en 1956) Les d\u00e9lires occidentaux en mati\u00e8re russe n&rsquo;ont h\u00e9las rien de neuf. Relisons le d\u00e9but du journal de Dosto\u00efevski : &laquo; Quand il s&rsquo;agit de la Russie, une imb\u00e9cillit\u00e9 enfantine s&#8217;empare de ces m\u00eames hommes qui ont invent\u00e9 la poudre et su compter tant d&rsquo;\u00e9toiles dans le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,12334,2607],"class_list":["post-78224","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-dostoievski","tag-russophobie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78224"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78224\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}