{"id":78236,"date":"2018-10-17T10:57:12","date_gmt":"2018-10-17T10:57:12","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/17\/mbsmust-go\/"},"modified":"2018-10-17T10:57:12","modified_gmt":"2018-10-17T10:57:12","slug":"mbsmust-go","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/17\/mbsmust-go\/","title":{"rendered":"\u201c<em>MbS\u00a0<\/em><em>Must Go\u00a0!<\/em>\u201d"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">\u00ab\u00a0[<em><s>Assad<\/s><\/em>] <em>MbS <\/em><em>Must Go !<\/em>\u00ab\u00a0<\/h2>\n<\/p>\n<p><p>Il faut parvenir \u00e0 imaginer comment on serait parvenu \u00e0 imaginer ceci, disons en 2013 lorsque tout le monde s&rsquo;\u00e9poumonerait \u00ab\u00a0<em>Assad Must Go !<\/em>\u00ab\u00a0, qu&rsquo;on en viendrait \u00e0 entendre dans les m\u00eames c\u00e9nacles, de la m\u00eame voix, \u00ab\u00a0<em>MbS <\/em><em>Must Go !<\/em>\u00a0\u00bb (MbS, Mohamed ben Salman, le Jeune Prince brillant et r\u00e9formiste d&rsquo;Arabie Saoudite, chant\u00e9 par tous les organes-Syst\u00e8me il y a encore trois mois) ; et il faut imaginer encore plus, qu&rsquo;on serait parvenu \u00e0 imaginer cette impr\u00e9cation <strong>de la bouche d&rsquo;un Lindsay Graham qui faisait la paire avec McCain pour \u00e9tendre partout l&rsquo;incendie de la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> dont l&rsquo;Arabie fut toujours fermement partie prenante et tant acclam\u00e9e pour cela<\/strong>&#8230; Bref, et pour r\u00e9p\u00e9ter le constat de cette extraordinaire situation, imaginer qu&rsquo;on aurait pu imaginer qu&rsquo;en 2018 le susdit Graham en viendrait, alors qu&rsquo;il disait en 2013 \u00ab\u00a0<em>Assad Must Go !<\/em>\u00ab\u00a0, \u00e0 s&rsquo;\u00e9crier aujourd&rsquo;hui, ou <a href=\"https:\/\/www.youtube.com\/watch?v=ztV5wfwDGRc\">plut\u00f4t hier<\/a> sur <em>FoxNews<\/em> : \u00ab\u00a0<em>MbS<\/em><em>Must Go !<\/em>\u00ab\u00a0&#8230; (Ou plus exactement, mais vous admettrez que c&rsquo;est vraiment la m\u00eame chose : \u00ab\u00a0<em>That guy&rsquo;s got to go !<\/em>\u00ab\u00a0, alors qu&rsquo;Assad est toujours en place&#8230;)<\/p>\n<\/p>\n<p><p>(Nous pensons que, McCain encore vivant, Graham n&rsquo;aurait pas \u00e9t\u00e9 aussi loin. McCain, &ndash; corrompu mais pas plus que les autres, &ndash; \u00e9tait le meneur de la politiqueSyst\u00e8me au Congr\u00e8s, et son extr\u00eame stupidit\u00e9, sa pens\u00e9e de brute primaire [type-Brennan, ex-directeur de la CIA et architecte-en-chef des coups d&rsquo;&Eacute;tat de l&rsquo;&Eacute;tat profond], sa compl\u00e8te na\u00efvet\u00e9 paradoxale [paradoxe d&rsquo;apparence] face aux manipulations dont il \u00e9tait \u00e9videmment l&rsquo;objet, avaient \u00e9tabli sur le Congr\u00e8s <strong>un empire, &ndash; rien de plus solide par les temps actuels, que l&#8217;empire de la sottise,<\/strong>&ndash; auquel un Graham, moins born\u00e9 et plus finaud, n&rsquo;aurait pu r\u00e9sister. McCain parti grim\u00e9 en <a href=\"http:\/\/www.dedefensa.org\/article\/lecons-du-sublime-destinde-saint-john-mccain\">Saint-John-McCain<\/a>, la sottise bien que toujours pr\u00e9sente est aujourd&rsquo;hui sans porte-voix de la communication, ch\u00e2tr\u00e9e en quelque sorte, et Graham retrouve une certaine libert\u00e9 d&rsquo;action.)<\/p>\n<\/p>\n<p><p>C&rsquo;est une r\u00e9volution dans l&rsquo;esprit et dans la lettre, mais il n&rsquo;y a que \u00e7a en ce moment, des r\u00e9volutions. C&rsquo;est le m\u00eame Graham qui, il y a trois semaines, soutenait au S\u00e9nat l&rsquo;homme de Trump pour la Cour Supr\u00eame et d\u00e9non\u00e7ait <a href=\"http:\/\/www.dedefensa.org\/article\/les-quatre-minutes-de-verite-du-senateur-graham\">avec quelle vigueur<\/a> les d\u00e9mocrates-Syst\u00e8me, fauteurs de guerre, <em>neocons<\/em>, etc., dont il \u00e9tait du temps de McCain l&rsquo;alli\u00e9 inconditionnel. Et Graham n&rsquo;est pas une exception tourn\u00e9e folle par rapport aux consignes du Syst\u00e8me, <strong>c&rsquo;est un exemple, un sympt\u00f4me et un symbole du tourbillon crisique qui atteint \u00e0 \u00ab\u00a0D.C.-la-folle\u00a0\u00bb une acc\u00e9l\u00e9ration formidable en m\u00e9langeant toutes les \u00e9tiquettes<\/strong>.<\/p>\n<\/p>\n<p><p>Le colonel Pat Lang avait \u00e9crit, <a href=\"http:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2018\/10\/enemy-of-the-people-ttg.html\">il y a quelques jours<\/a>, avec une r\u00e9elle lucidit\u00e9 : &laquo; <em>Je ne pense pas que Trump puisse esp\u00e9rer que l&rsquo;affaire Khashoggi disparaisse d&rsquo;elle-m\u00eame des gros titres. La r\u00e9pugnance croissante du Congr\u00e8s \u00e0 l&rsquo;\u00e9gard de la guerre au Y\u00e9men continuera de susciter une tension constante, de m\u00eame pour les m\u00e9dias qui ont perdu l&rsquo;un des leurs <\/em>[Khashoggi, collaborateur du Washington <em>Post<\/em>]. <em>Ajoutez \u00e0 cela la blessure encore non gu\u00e9rie du 11-septembre. En mars dernier, un juge de la Cour de district am\u00e9ricaine de Manhattan a d\u00e9clar\u00e9 que les poursuites judiciaires des victimes du 11 septembre contre l&rsquo;Arabie saoudite en vertu de la loi relative \u00e0 la justice contre les terroristes du terrorisme (JASTA) \u00e9taient en cours et seraient poursuivies. C&rsquo;est un tr\u00e8s mauvais moment pour MbS et le reste de la famille royale<\/em>&#8230; &raquo;<\/p>\n<\/p>\n<p><p>Effectivement, que cela plaise ou non \u00e0 Trump qui voudrait tant un arrangement \u00e0 l&rsquo;amiable avec MbS, <strong>le Congr\u00e8s a d\u00e9marr\u00e9 en trombe et il n&rsquo;est pas seulement question de Graham<\/strong>. Encore plus, ce sont les r\u00e9publicains (dont Graham fait partie, certes) qui soutiennent en principe le pr\u00e9sident, <strong>qui sont en pointe dans cette offensive<\/strong>. (Mais ils seront tr\u00e8s probablement soutenus par les d\u00e9mocrates, ce qui donne une id\u00e9e de l&rsquo;importance du Congr\u00e8s dans cette bataille.)<\/p>\n<\/p>\n<p><p><em><a href=\"https:\/\/www.zerohedge.com\/news\/2018-10-16\/republican-senators-threaten-sanctions-against-saudi-arabia\">ZeroHedge.com<\/a> <\/em>rapporte cette \u00e9volution des r\u00e9publicains du S\u00e9nat, c&rsquo;est-\u00e0-dire de l&rsquo;assembl\u00e9e qui d\u00e9tient le pouvoir de d\u00e9cr\u00e9ter des sanctions. Trump pourrait opposer un veto si une telle d\u00e9cision \u00e9tait prise, mais dans une position si d\u00e9licate qu&rsquo;il h\u00e9siterait fortement sans doute avant de le faire : dans une telle hypoth\u00e8se, il semblerait ais\u00e9 de r\u00e9unir les deux-tiers des 2\/3 des voix du S\u00e9nat requises pour repousser le veto et infliger une d\u00e9faite cinglante au pr\u00e9sident. <\/p>\n<\/p>\n<p><p>&laquo; <em>Mais apr\u00e8s avoir appris que le Royaume s&rsquo;appr\u00eatait \u00e0 reconna&icirc;tre son r\u00f4le dans la mort de Khashoggi (narrative officielle : Khashoggi a \u00e9t\u00e9 tu\u00e9 lors d&rsquo;un interrogatoire par des ex\u00e9cuteurs hors de tout contr\u00f4le), les l\u00e9gislateurs r\u00e9publicains intensifient leur discours contre le royaume, avec plusieurs dirigeants r\u00e9publicains au S\u00e9nat affirmant <\/em>[hier] <em>mardi que cette assembl\u00e9e pourrait sanctionner l&rsquo;Arabie saoudite, selon une politique qui devrait largement \u00eatre soutenue par les l\u00e9gislateurs lib\u00e9raux <\/em>[d\u00e9mocrates].<em>Suivant l&rsquo;hypoth\u00e8se selon laquelle les r\u00e9publicains pourraient imposer des sanctions \u00e0 l&rsquo;Arabie saoudite par le biais de la loi Magnitski, la loi controvers\u00e9e adopt\u00e9e pour permettre aux &Eacute;tats-Unis de punir plus facilement les responsables russes pour les violations pr\u00e9sum\u00e9es des droits humains, <\/em>[le chef de la majorit\u00e9 r\u00e9publicaine au S\u00e9nat] <em>Mitch McConnell a ouvert la porte \u00e0 cette possibilit\u00e9, affirmant que \u00ab\u00a0cela pourrait bien \u00eatre la voie choisie\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Je ne peux pas imaginer qu&rsquo;il n&rsquo;y aura pas de r\u00e9action <\/em>[\u00e0 l&rsquo;affaire Khashoggi] <em>mais je pense que nous devons savoir d&rsquo;abord ce qui s&rsquo;est pass\u00e9\u00a0\u00bb, a-t-il d\u00e9clar\u00e9 \u00e0 Bloomberg. \u00ab\u00a0Cela pourrait bien conduire \u00e0 une d\u00e9cision de sanction selon la loi Magnitsky\u00a0\u00bb<\/em>.<\/p>\n<\/p>\n<p><p>&raquo; [Le s\u00e9nateur r\u00e9publicain] <em>Marco Rubio est celui qui exige avec la plus grande fermet\u00e9 que les &Eacute;tats-Unis envisagent de mettre fin aux ventes d&rsquo;armes au Royaume<\/em>. [&#8230;] <em>Lors d&rsquo;une r\u00e9cente interview sur CNN, Rubio a affirm\u00e9 que, si Trump ne punissait pas l&rsquo;Arabie saoudite (en supposant que l&rsquo;assassinat soit confirm\u00e9), \u00ab\u00a0il y aura une tr\u00e8s forte r\u00e9action du Congr\u00e8s\u00a0\u00bb. Rubio a ajout\u00e9 qu&rsquo;il avait d\u00e9j\u00e0 demand\u00e9 l&rsquo;ouverture d&rsquo;une enqu\u00eate dans le cadre de la loi Magnitsky, ce qui signifie que les individus impliqu\u00e9s dans le meurtre seraient sanctionn\u00e9s<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Autre \u00e9l\u00e9ment qui modifie compl\u00e8tement le jeu \u00e0 Washington, brouille les \u00e9tiquettes et accentue la confusion, <strong>l&rsquo;attitude de la presseSyst\u00e8me, et particuli\u00e8rement du Washington <em>Post <\/em>, int\u00e9ress\u00e9 au premier chef dans la mesure o&ugrave; Khashoggi publiait dans ses colonnes<\/strong>. On voit ainsi le colonel Lang, pourtant adversaire de tout ce qui se rattache \u00e0 l&rsquo;<em>establishment<\/em>, <a href=\"http:\/\/turcopolier.typepad.com\/sic_semper_tyrannis\/2018\/10\/httpswwwwashingtonpostcomopinionsglobal-opinionswho-needs-saudi-arabia201810153ebe473c-d0a1-11e8-8c22-fa2ef74bd6d.html\">f\u00e9liciter pour une fois<\/a>le quotidien et son propri\u00e9taire Jeff Bezos, homme class\u00e9 \u00ab\u00a0le plus riche du monde\u00a0\u00bb dans l&rsquo;actuelle comp\u00e9tition, propri\u00e9taire d&rsquo;<em>Amazon.com <\/em>et grand ami de la CIA : &laquo; <em>Encore une fois, je ne suis pas un grand fan de Bezos ou de son blog, mais deux jours de suite, ils ont imprim\u00e9 des avis que je partage. Quelque chose a chang\u00e9 pour lui. Ce jugement est une des marques remarquable d&rsquo;intelligence par rapport au jugement stupide qui triomphe dans les m\u00e9dias am\u00e9ricains, selon lequel l&rsquo;Arabie saoudite est un alli\u00e9 fid\u00e8le et indispensable des &Eacute;tats-Unis au Moyen-Orient. Bezos le conteste et il en est de m\u00eame pour moi<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Le jugement en question porte notamment sur les achats d&rsquo;armes de l&rsquo;Arabie, qui est le principal argument de Trump pour conserver des liens \u00e9troits avec l&rsquo;Arabie et ne pas (trop) r\u00e9agir \u00e0 l&rsquo;affaire Khashoggi. Ainsi le <em>Post <\/em>\u00e9crit-il \u00e0 ce propos dans son <a href=\"https:\/\/www.washingtonpost.com\/opinions\/global-opinions\/who-needs-saudi-arabia\/2018\/10\/15\/3ebe473c-d0a1-11e8-8c22-fa2ef74bd6d6_story.html?noredirect=on&#038;utm_term=.a339b03b5abf\">\u00e9ditorial d&rsquo;hier<\/a>, mettant en \u00e9vidence une des caract\u00e9ristiques des Saoudiens, <strong>qui promettent souvent de passer des commandes mirifiques mais finissent finalement par les r\u00e9duire \u00e0 des proportions beaucoup moins impressionnantes<\/strong>, &ndash; mais aussi, \u00f4 nouveaut\u00e9 inattendue et surprise divine, condamnant au passage <strong>la \u00ab\u00a0campagne sanglante\u00a0\u00bb de l&rsquo;Arabie contre le Y\u00e9men<\/strong> :   <\/p>\n<\/p>\n<p><p>&laquo; <em>En ce qui concerne les ventes d&rsquo;armes, quelqu&rsquo;un devrait informer M. Trump des r\u00e9sultats concrets des promesses qui lui ont \u00e9t\u00e9 faites lors de sa visite \u00e0 Riyad l&rsquo;ann\u00e9e derni\u00e8re. Comme <a href=\"https:\/\/www.brookings.edu\/blog\/order-from-chaos\/2018\/10\/10\/after-khashoggi-us-arms-sales-to-the-saudis-are-essential-leverage\/\">le r\u00e9sume<\/a> Bruce Riedel de la Brookings Institution, \u00ab\u00a0les Saoudiens n&rsquo;ont conclu aucun accord majeur sur les armement avec Washington depuis l&rsquo;arriv\u00e9e de Trump.\u00a0\u00bb Plus encore, une cessation des livraisons de pi\u00e8ces d\u00e9tach\u00e9es et mat\u00e9riels de soutien US \u00e0 l&rsquo;Arabie, une chose \u00e0 laquelle les Russes ne peuvent suppl\u00e9er, clouerait rapidement l&rsquo;aviation saoudienne au sol. Cela aurait l&rsquo;effet bienvenu de faire cesser la campagne sanglante men\u00e9e contre le Y\u00e9men, qu&rsquo;une <a href=\"https:\/\/www.theguardian.com\/world\/2018\/aug\/28\/all-sides-in-yemen-may-be-responsible-for-war-crimes-say-un-experts\">enqu\u00eate de l&rsquo;ONU<\/a> a d\u00e9crite comme probable responsable de crimes de guerre.<\/em> &raquo;<\/p>\n<\/p>\n<p><p>On voit combien on se trouve de plus en plus entrain\u00e9s dans le tourbillon crisique qui implique <strong>une extraordinaire valse des \u00e9tiquettes entre Syst\u00e8me et antiSyst\u00e8me<\/strong>. L&rsquo;affaire Khashoggi a pris comme un incendie prend dans une for\u00eat m\u00e9diterran\u00e9enne frapp\u00e9e par la s\u00e9cheresse, lorsqu&rsquo;une cigarette allum\u00e9e tombe par hasard dans l&rsquo;herbe s\u00e8che. Il est assez <strong>difficile d&rsquo;expliquer l&rsquo;ampleur extraordinaire qu&rsquo;a pris cette affaire en moins d&rsquo;une semaine<\/strong>, balayant tous les pr\u00e9jug\u00e9s colossaux sur la soi-disant indispensabilit\u00e9 de l&rsquo;alliance saoudienne ; mais on voit que cette pente irr\u00e9sistible est maintenant d\u00e9val\u00e9e de tous les c\u00f4t\u00e9s, y compris par les plus bellicistes habituels, et sans prendre garde aux int\u00e9r\u00eats du malheureux Isra\u00ebl et \u00e0 l&rsquo;horreur supr\u00eame de l&rsquo;Iran. <\/p>\n<\/p>\n<p><p>L&rsquo;argument essentiel, et nous pensons qu&rsquo;il s&rsquo;agit bien d&rsquo;un facteur de cette sorte, nous voulons dire de cette sorte d\u00e9risoire, <strong>est l'\u00a0\u00bbimage\u00a0\u00bb de moralit\u00e9, ou de moraline, \u00e0 laquelle tiennent tant les honorables parlementaires<\/strong>. Cela avait \u00e9t\u00e9 imm\u00e9diatement dit par Marco Rubio, l&rsquo;un des plus limit\u00e9s et des plus r\u00e9put\u00e9s-<em>neocons <\/em>parmi les s\u00e9nateurs, montrant par-l\u00e0 que la qualification intellectuelle, la conviction de l&rsquo;engagement, la fermet\u00e9 r\u00e9aliste des int\u00e9r\u00eats de s\u00e9curit\u00e9 nationale, et aussi la reconnaissance pour les donateurs g\u00e9n\u00e9reux, ne d\u00e9passent pas le sort des \u00e9tiquettes qu&rsquo;un peu de vent emporte et qu&rsquo;on peut donc changer \u00e0 volont\u00e9 : &laquo; <em>Le simple fait d&rsquo;\u00eatre alli\u00e9 dans une mission importante, qui restreint l&rsquo;expansion iranienne dans la r\u00e9gion, ne peut nous permettre de n\u00e9gliger ou de nous laver les mains de cela <\/em>[de l&rsquo;assassinat \u00e9ventuel de Khashoggi]<em>.  Cela compromettrait <strong>notre capacit\u00e9 \u00e0 d\u00e9fendre la moralit\u00e9 et les droits de l&rsquo;homme dans le monde entier<\/strong>\u00ab\u00a0<\/em>. &raquo;<\/p>\n<\/p>\n<blockquote>\n<p><p><strong>Nous ne nous plaindrons pas <\/strong>de cette volatilit\u00e9 extraordinaire du jugement, de cette fragilit\u00e9 presque pathologique de la conviction, de cette compl\u00e8te inconsistance de caract\u00e8re, <strong>qui font de guerriers insatiables du Syst\u00e8me, en un tournemain des auxiliaires emport\u00e9s de l&rsquo;antiSyst\u00e8me<\/strong>. (Puisque, d\u00e9cid\u00e9ment, c&rsquo;est de cette fa\u00e7on qu&rsquo;il faut classifier les \u00e9v\u00e9nements en cours entre \u00ab\u00a0D.C.-la-folle\u00a0\u00bb et Ryad, qui sont en train de mettre en grave danger l&rsquo;axe de la politiqueSyst\u00e8me dans la r\u00e9gion, arc-bout\u00e9 notamment sur l&rsquo;alliance USA-Arabie.) <\/p>\n<\/p>\n<\/blockquote>\n<p><p>Quant \u00e0 Trump, il est dans ce cas, \u00e9videmment du c\u00f4t\u00e9 du Syst\u00e8me et de la quincaillerie de la bande du Complexe Militaro-Industriel, avec ses r\u00e9flexes de <em>businessman <\/em>\u00e0 super-courte vue. Qu&rsquo;importe, il n&rsquo;est pas inutile qu&rsquo;il soit dans cette position, il sert au moins \u00e0 entretenir le d\u00e9sordre en tenant <strong>une position qui, pour le moment, exacerbe la vindicte du Congr\u00e8s sans que lui-m\u00eame puisse trop d\u00e9lib\u00e9r\u00e9ment lutter contre elle<\/strong> ; d&rsquo;autre part, c&rsquo;est gr\u00e2ce \u00e0 lui que la possible rupture qui menace a cette ampleur, cette puissance de communication, parce qu&rsquo;il s&rsquo;est jet\u00e9 dans les bras de MbS, guid\u00e9 par son gendre Jared aux bons soins des publicistes isra\u00e9liens&#8230; Tout cela fait d\u00e9sordre et Trump est bien l\u00e0 pour \u00e7a, pour le d\u00e9sordre&#8230;<\/p>\n<\/p>\n<p><p>Mis enb ligne le 17 octobre 2018 \u00e0 11H03<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0[Assad] MbS Must Go !\u00ab\u00a0 Il faut parvenir \u00e0 imaginer comment on serait parvenu \u00e0 imaginer ceci, disons en 2013 lorsque tout le monde s&rsquo;\u00e9poumonerait \u00ab\u00a0Assad Must Go !\u00ab\u00a0, qu&rsquo;on en viendrait \u00e0 entendre dans les m\u00eames c\u00e9nacles, de la m\u00eame voix, \u00ab\u00a0MbS Must Go !\u00a0\u00bb (MbS, Mohamed ben Salman, le Jeune Prince brillant et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3259,3481,3285,10183,3005,6416,2627,5646,3531,2639],"class_list":["post-78236","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arabie","tag-armements","tag-congres","tag-etiquettes","tag-graham","tag-lang","tag-rubio","tag-sanctions","tag-senat","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78236"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78236\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}