{"id":78246,"date":"2018-10-21T15:46:42","date_gmt":"2018-10-21T15:46:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/21\/tc-61-destructuration-et-deconstruction-metahistoriques\/"},"modified":"2018-10-21T15:46:42","modified_gmt":"2018-10-21T15:46:42","slug":"tc-61-destructuration-et-deconstruction-metahistoriques","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/21\/tc-61-destructuration-et-deconstruction-metahistoriques\/","title":{"rendered":"T.C.-61\u00a0: D\u00e9structuration et d\u00e9construction m\u00e9tahistoriques"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">T.C.-61 : D\u00e9structuration et d\u00e9construction m\u00e9tahistoriques<\/h2>\n<\/p>\n<p><p>21 octobre 2018 &ndash; La crise-Khashoggi, car c&rsquo;est bien d&rsquo;une crise qu&rsquo;on peut d\u00e9sormais parler, menace un des axes fondamentaux de <strong>cette chose-USA qui se repr\u00e9sente comme \u00ab\u00a0empire\u00a0\u00bb<\/strong>. Il s&rsquo;agit bien s&ucirc;r de l&rsquo;axe moyen-oriental conduisant \u00e0 ce que Brzezinski nommait en 1979 \u00ab\u00a0l&rsquo;arc de crise\u00a0\u00bb, du Soudan \u00e0 l&rsquo;Inde. <\/p>\n<\/p>\n<p><p><strong>Parall\u00e8lement, dans un sens g\u00e9om\u00e9trique comme dans un sens chronologique<\/strong>, l&rsquo;intention annonc\u00e9e par Trump de sortir du trait\u00e9 INF de 1987, c&rsquo;est-\u00e0-dire de le d\u00e9truire puisqu&rsquo;il ne comporte que deux signataires avec l&rsquo;URSS devenue Russie, menace dans ses effets l&rsquo;autre axe fondamental du m\u00eame \u00ab\u00a0empire\u00a0\u00bb, l&rsquo;axe transatlantique. Cette seconde crise annonce <a href=\"https:\/\/www.rt.com\/news\/441854-russia-denounces-trump-inf\/\">une situation chaotique<\/a> pour la s\u00e9curit\u00e9 europ\u00e9enne.<\/p>\n<\/p>\n<p><p>Chacune de ces deux crises a ses raisons d&rsquo;\u00eatre, ses dynamiques propres, ses \u00ab\u00a0accidents\u00a0\u00bb internes, voire ses desseins et destins sp\u00e9cifiques pour sugg\u00e9rer une explication propre mais qui ne reste que circonstancielle. Dans l&rsquo;\u00e9tat pr\u00e9sent des choses qui ne pr\u00e9juge pas de l&rsquo;avenir et si elles sont prises ensemble comme elles doivent l&rsquo;\u00eatre, leur v\u00e9ritable signification <strong>est celle d&rsquo;une d\u00e9structuration de la forme et de la charpente de s\u00e9curit\u00e9 <\/strong>mises en place et maintenues par les USA durant le deuxi\u00e8me moiti\u00e9 du XX\u00e8me si\u00e8cle pour projeter la protection de leur s\u00e9curit\u00e9 en imposant l&rsquo;ordre du monde qu&rsquo;ils jugeaient n\u00e9cessaire.<\/p>\n<\/p>\n<p><p>Du point de vue de la posture strat\u00e9gique, il s&rsquo;agit de la d\u00e9construction la plus essentielle possible de la forme de la g\u00e9ostrat\u00e9gie du monde, et une d\u00e9construction dont nul ne sait la cause majeure et centrale, ni les cons\u00e9quences fondamentales. On comprend, du fait de leur importance comme de leur correspondance, que <strong>ces deux crises ne peuvent \u00eatre per\u00e7ues que comme les \u00e9l\u00e9ments d&rsquo;une seule et m\u00eame Grande Crise<\/strong>, celle qui institue l&rsquo;Effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<blockquote>\n<p><p>Tout cela se fait \u00e0 deux semaines d&rsquo;une \u00e9lection<em>midterm <\/em>que <strong>certains qualifient de \u00ab\u00a0la plus importante de toute l&rsquo;histoire des USA\u00a0\u00bb<\/strong>. Nul, m\u00eame pas les acteurs de ces \u00e9v\u00e9nements, ne peut dire si le lien qu&rsquo;on est conduit \u00e0 faire entre ces diff\u00e9rents \u00e9v\u00e9nements, &ndash; les deux axes en danger de rupture et les \u00e9lections <em>midterm<\/em>, &ndash; <strong>a \u00e9t\u00e9 voulu et\/ou maniganc\u00e9 par des conceptions et des man&oelig;uvres humaines <\/strong>embrassant tous leurs caract\u00e8res jusqu&rsquo;\u00e0 leur signification commune. Il reste que ce lien, m\u00eame de simple co\u00efncidence, appara&icirc;t aussi brutalement que les \u00e9v\u00e9nements qu&rsquo;il tient ensemble et <strong>qu&rsquo;il est sans aucun doute de l&rsquo;essence m\u00eame des grands \u00e9v\u00e9nements m\u00e9tahistoriques de l&rsquo;histoire du monde<\/strong>.<\/p>\n<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>T.C.-61 : D\u00e9structuration et d\u00e9construction m\u00e9tahistoriques 21 octobre 2018 &ndash; La crise-Khashoggi, car c&rsquo;est bien d&rsquo;une crise qu&rsquo;on peut d\u00e9sormais parler, menace un des axes fondamentaux de cette chose-USA qui se repr\u00e9sente comme \u00ab\u00a0empire\u00a0\u00bb. Il s&rsquo;agit bien s&ucirc;r de l&rsquo;axe moyen-oriental conduisant \u00e0 ce que Brzezinski nommait en 1979 \u00ab\u00a0l&rsquo;arc de crise\u00a0\u00bb, du Soudan \u00e0&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3259,3680,18625,6486,18594,8844,9842,2730,3558,4495,2639],"class_list":["post-78246","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-arabie","tag-axe","tag-charpente","tag-inf","tag-khashoggi","tag-metahistoire","tag-midterm","tag-russie","tag-saoudite","tag-traite","tag-trump"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78246"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78246\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}