{"id":78252,"date":"2018-10-24T02:19:48","date_gmt":"2018-10-24T02:19:48","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/24\/migration-et-delitement-social\/"},"modified":"2018-10-24T02:19:48","modified_gmt":"2018-10-24T02:19:48","slug":"migration-et-delitement-social","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/24\/migration-et-delitement-social\/","title":{"rendered":"Migration et d\u00e9litement social"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Migration et d\u00e9litement social<\/h2>\n<\/p>\n<p><p>Rien de tel que le sentiment d&rsquo;appartenance \u00e0 une communaut\u00e9 positive pour favoriser l&rsquo;\u00e9panouissement de la personnalit\u00e9. Tous les trait\u00e9s de psychologie et de psychologie sociale montrent que se sentir en lien avec son environnement et en connexion avec un groupe renforce la confiance en soi et \u00e9loigne la d\u00e9pression et l&rsquo;instabilit\u00e9 \u00e9motionnelle. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Les Allemands s&rsquo;expatrient quand ils le peuvent<\/h3>\n<\/p>\n<p><p>Une \u00e9tude <a href=\"https:\/\/www.welt.de\/politik\/deutschland\/article138249483\/Deutschlands-Talente-verlassen-in-Scharen-das-Land.html#https:\/\/www.welt.de\/politik\/deutschland\/article138249483\/Deutschlands-Talente-verlassen-in-Scharen-das-Land.html\">publi\u00e9e<\/a> en mars 2015 par le journal Die Welt montrait la propension d&rsquo;une \u00e9lite allemande \u00e9duqu\u00e9e \u00e0 quitter son pays pour travailler ailleurs, principalement en Suisse, aux Usa et en Autriche. Selon le Conseil allemand d&rsquo;experts sur l&rsquo;int\u00e9gration et les migrations, entre 2003 et 2013, un million et demi d&rsquo;Allemands ont \u00e9migr\u00e9 pour faire carri\u00e8re ailleurs. La plupart de ces \u00e9migr\u00e9s, universitaires, m\u00e9decins et \u00e9tudiants finissent par r\u00e9int\u00e9grer leur pays mais le solde migratoire reste n\u00e9gatif depuis les ann\u00e9es soixante. L&rsquo;office des statistiques d\u00e9signe cela sous l&rsquo;appellation &lsquo; mobilit\u00e9 des travailleurs&rsquo;. <a href=\"https:\/\/www.latribune.fr\/actualites\/economie\/union-europeenne\/20150311trib141a5dc06\/les-allemands-quittent-ils-l-allemagne.html#https:\/\/www.latribune.fr\/actualites\/economie\/union-europeenne\/20150311trib141a5dc06\/les-allemands-quittent-ils-l-allem\">Entre 2009 et 20013<\/a>, 710 000 Allemands, plus jeunes et plus dipl\u00f4m\u00e9s que la moyenne ont quitt\u00e9 leur pays alors que 580 000 ont choisi d&rsquo;y retourner. On recense actuellement pr\u00e8s de quatre millions d&rsquo;\u00e9migrants allemands vivant en dehors de la R\u00e9publique f\u00e9d\u00e9rale d&rsquo;Allemagne.<\/p>\n<\/p>\n<p><p>L&rsquo;Allemagne conna&icirc;t un <a href=\"https:\/\/www.leconomiste.eu\/decryptage-economie\/175-le-defi-demographique-de-l-allemagne.html#https:\/\/www.leconomiste.eu\/decryptage-economie\/175-le-defi-demographique-de-l-allemagne.html\">autre probl\u00e8me<\/a> qui affecte sa d\u00e9mographie. Le taux de f\u00e9condit\u00e9 des femmes allemandes 1,37 en 2012 (versus 1,99 pour la France) est l&rsquo;un des plus faibles au niveau europ\u00e9en depuis de nombreuses ann\u00e9es alors que 2 ,1 est requis pour maintenir la population en l&rsquo;\u00e9tat. Ceci a permis de projeter une baisse de la population de 15 millions d&rsquo;habitants, passant de 80,5 \u00e0 66 millions pour l&rsquo;ann\u00e9e 2060. <\/p>\n<\/p>\n<p><p>Le vieillissement inexorable de la population, seulement 22% ont moins de 25 ans, pose des probl\u00e8mes \u00e9conomiques, ceux de la productivit\u00e9 et de l&rsquo;innovation sans compter le poids des retraites et des d\u00e9penses de sant\u00e9 mal assur\u00e9 par une part plus faible de salari\u00e9s.<\/p>\n<\/p>\n<p><p>Cet app\u00e9tit des plus instruits \u00e0 l&rsquo;\u00e9migration et cette tr\u00e8s faible natalit\u00e9 malgr\u00e9 les encouragements financiers de l&rsquo;Etat, cr\u00e8ches en nombre et qualit\u00e9 suffisants, allocations pour les parents qui \u00e9l\u00e8vent leurs enfants, disent les difficult\u00e9s d&rsquo;une soci\u00e9t\u00e9 \u00e0 faire &lsquo;communaut\u00e9&rsquo;. <\/p>\n<\/p>\n<p><p>Le plan Marshall d&rsquo;aide \u00e0 la reconstruction d&rsquo;une Allemagne responsable pour ses besoins d&rsquo;expansion territoriale  d&rsquo;une guerre europ\u00e9enne en 39-45  \u00e9tait assorti d&rsquo;une condition. La nation allemande enferm\u00e9e dans sa partie occidentale allait se fondre dans le projet d&rsquo;une union \u00e9conomique europ\u00e9enne. La culpabilit\u00e9 du d\u00e9sastre nazi a \u00e9t\u00e9 inflig\u00e9e collectivement (et soigneusement entretenue), ses traces persistent encore dans les m\u00e9moires et les fa\u00e7ons d&rsquo;\u00eatre au monde, ce qui n&rsquo;exalte pas l&rsquo;appartenance subjective des citoyens \u00e0 leur histoire r\u00e9cente.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Migrations entrecrois\u00e9es<\/h3>\n<\/p>\n<p><p>L&rsquo;ironie grin\u00e7ante de l&rsquo;histoire veut que l&rsquo;\u00e9tude chiffrant cette fuite des cerveaux allemands a \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9e en 2015 par des anti-immigrationnistes oppos\u00e9s \u00e0 la politique de Merkel d&rsquo;accueil des r\u00e9fugi\u00e9s. Ils ont tordu dans un <a href=\"https:\/\/fr.gatestoneinstitute.org\/9165\/allemands-quittent-allemagne#https:\/\/fr.gatestoneinstitute.org\/9165\/allemands-quittent-allemagne\">contresens absolu<\/a>les faits observ\u00e9s qui s&rsquo;inscrivent dans une tendance ancienne et toujours actuelle absolument ant\u00e9rieure et ind\u00e9pendante de la crise migratoire induite par la guerre de l&rsquo;OTAN en Syrie. <a href=\"https:\/\/www.lesechos.fr\/idees-debats\/cercle\/cercle-164235-migrants-merkel-a-doublement-raison-2052591.php#https:\/\/www.lesechos.fr\/idees-debats\/cercle\/cercle-164235-migrants-merkel-a-doublement-raison-2052591.php\">Angela Merkel,<\/a>physicienne de formation a les yeux riv\u00e9s sur les indicateurs \u00e9conomiques qui montrent la n\u00e9cessit\u00e9 d&rsquo;importer des hommes et des femmes jeunes et en bonne sant\u00e9, &ndash; c&rsquo;est le cas car ils ont r\u00e9ussi \u00e0 braver les difficult\u00e9s de l&rsquo;exode- pour les besoins de l&rsquo;\u00e9conomie allemande pr\u00e9sente et future. Les <a href=\"https:\/\/courrierpologne.fr\/l-allemagne-premiere-destination\/#https:\/\/courrierpologne.fr\/l-allemagne-premiere-destination\/\">Polonais<\/a>arriv\u00e9s en masse ces derni\u00e8res d\u00e9cennies ne suffisent pas \u00e0 combler le d\u00e9ficit en travailleurs qualifi\u00e9s ou non.<\/p>\n<\/p>\n<p><p>L&rsquo;Allemagne impose d&rsquo;une part sa monnaie l&rsquo;euro-deutsche mark dans laquelle empruntent les pays de l&rsquo;UE dont elle garantit la dette \u00e0 condition qu&rsquo;ils perp\u00e9tuent l&rsquo;aust\u00e9rit\u00e9 et qui en absence de relance sont maintenus en asphyxie budg\u00e9taire et \u00e9conomique. D&rsquo;autre part, elle pratique une politique d&rsquo;accueil des r\u00e9fugi\u00e9s devenus \u00ab\u00a0migrants\u00a0\u00bb pour b\u00e9n\u00e9ficier d&rsquo;une main d&rsquo;&oelig;uvre venue au secours d&rsquo;une d\u00e9mographie doublement d\u00e9ficitaire. Elle encourage la r\u00e9bellion des pays du Sud et de l&rsquo;Est atteints par des vagues migratoires issues de guerres livr\u00e9es par l&rsquo;OTAN et de pillages des pays du tiers-monde par les Europ\u00e9ens du Nord dont ils ne se sont jamais sentis partie prenante. L&rsquo;Italie \u00e9tait r\u00e9ticente \u00e0 l&rsquo;intervention en Libye et la Hongrie n&rsquo;a pas eu son mot \u00e0 dire concernant la cr\u00e9ation d&rsquo;une fausse guerre civile en Syrie.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Les Fran\u00e7ais aussi<\/h3>\n<\/p>\n<p><p>Un Fran\u00e7ais sur deux envisage de vivre \u00e0 l&rsquo;\u00e9tranger. Ils <a href=\"https:\/\/voiceofeurope.com\/2018\/10\/shocking-study-reveals-72-per-cent-of-french-youngster-want-to-leave-france\/#https:\/\/voiceofeurope.com\/2018\/10\/shocking-study-reveals-72-per-cent-of-french-youngster-want-to-leave-france\/\">sont 72%<\/a>\u00e0 vouloir le faire quand ils ont entre 18 et 24 ans. En 2000, ils \u00e9taient un million d&rsquo;expatri\u00e9s dans le monde, en 2017, ils sont entre 2 et 2,5 millions. Des jeunes pour la plupart.<\/p>\n<\/p>\n<p><p>Ils cherchent des opportunit\u00e9s de carri\u00e8re, un co&ucirc;t de la vie plus bas, un climat meilleur et une plus grande stabilit\u00e9 politique.<\/p>\n<\/p>\n<p><p>Ni l&rsquo;histoire de Clovis, ni celle de Vercing\u00e9torix ne semblent les attacher \u00e0 leur pays de naissance. Un sondage en 2014 r\u00e9alis\u00e9 par Gallup montrait le <a href=\"https:\/\/www.les-crises.fr\/qui-est-pret-a-se-battre-pour-son-pays\/#https:\/\/www.les-crises.fr\/qui-est-pret-a-se-battre-pour-son-pays\/\">peu d&rsquo;enthousiasme<\/a> des Fran\u00e7ais \u00e0 vouloir se battre pour leur pays et le d\u00e9fendre. A peine 30% d\u00e9clarent \u00eatre pr\u00eats \u00e0 le faire, ce qui illustre que l&rsquo;attachement patriotique et le sentiment d&rsquo;\u00eatre r\u00e9ellement d\u00e9fini par l&rsquo;appartenance \u00e0 la communaut\u00e9 fran\u00e7aise ne sont que des crit\u00e8res faibles d&rsquo;identit\u00e9. Pourtant la France n&rsquo;est pas en guerre apparente permanente, tout est fait pour occulter <a href=\"http:\/\/www.lesutopiques.org\/larmee-francaise-afrique\/#http:\/\/www.lesutopiques.org\/larmee-francaise-afrique\/\">l&rsquo;activit\u00e9 de l&rsquo;arm\u00e9e en Afrique<\/a>avec deux bases officielles et quantit\u00e9 d&rsquo;Opex, comme c&rsquo;est le cas de l&rsquo;entit\u00e9 sioniste o&ugrave; 59% des \u00e9tudiants interrog\u00e9s envisagent de quitter Isra\u00ebl.  <\/p>\n<\/p>\n<p><p><a href=\"https:\/\/www.liberation.fr\/checknews\/2018\/10\/03\/non-91-des-marocains-et-84-des-algeriens-ne-veulent-pas-quitter-leur-pays-pour-venir-en-france-lien-_1682676#https:\/\/www.liberation.fr\/checknews\/2018\/10\/03\/non-91-des-marocains-et-84-des-algeriens-ne\">Interrog\u00e9s de la m\u00eame mani\u00e8re<\/a>, les jeunes Maghr\u00e9bins ne diff\u00e8rent pas des Europ\u00e9ens. En cas d&rsquo;opportunit\u00e9 professionnelle, les Alg\u00e9riens seraient pr\u00eats pour 84% d&rsquo;entre eux \u00e0 quitter leur pays pour une meilleure carri\u00e8re \u00e0 l&rsquo;\u00e9tranger, les Marocains n&rsquo;ont pas de projet d&rsquo;\u00e9migration mais en cas d&rsquo;offre d&#8217;emploi mieux r\u00e9mun\u00e9r\u00e9e, ils rejoindraient l&rsquo;\u00e9tranger \u00e0 91% avec une nette pr\u00e9f\u00e9rence pour le Canada, devant la France, l&rsquo;Allemagne et les Usa. <\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Le salut ailleurs que chez soi<\/h3>\n<\/p>\n<p><p>Les sondages et enqu\u00eates d&rsquo;opinion concernent essentiellement une jeunesse ayant acc\u00e9d\u00e9 \u00e0 une formation universitaire. Ils refl\u00e8tent l&rsquo;\u00e9tat d&rsquo;esprit de ce qui constitue les forces les plus vives d&rsquo;une nation. La &lsquo;globalisation&rsquo; autre nom de la d\u00e9r\u00e9gulation \u00e9conomique et l&rsquo;effacement des fronti\u00e8res aux capitaux et aux marchandises, l&rsquo;impr\u00e9gnation des masses par un individualisme forcen\u00e9 qui a dissip\u00e9 le sentiment d&rsquo;appartenance \u00e0 un groupe, r\u00e9sultat du travail id\u00e9ologique d&rsquo;une <a href=\"https:\/\/www.lexpress.fr\/actualite\/monde\/europe\/margaret-thatcher-en-10-citations_1238445.html#https:\/\/www.lexpress.fr\/actualite\/monde\/europe\/margaret-thatcher-en-10-citations_1238445.html\">Thatcher<\/a>et consorts trouvent ici leur issue. Ceux qui constituaient historiquement l&rsquo;\u00e9lite du pays dans lequel ils sont n\u00e9s et ont \u00e9t\u00e9 \u00e9duqu\u00e9s ne lui t\u00e9moignent pas d&rsquo;attachement particulier et sont pr\u00eats \u00e0 le quitter pour obtenir un confort mat\u00e9riel sup\u00e9rieur. Avec une ampleur qui d\u00e9sorganise certainement les soci\u00e9t\u00e9s d&rsquo;origine et \u00e9galement celles qui absorbent les migrants. Former un m\u00e9decin ou un ing\u00e9nieur repr\u00e9sente un co&ucirc;t et un investissement consid\u00e9rable qui devient une perte pour l&rsquo;un et un gain pour le receveur. Ce d\u00e9litement social s&rsquo;accompagne de conqu\u00eates soci\u00e9tales o&ugrave; toute diff\u00e9rence est combattue au nom d&rsquo;un devoir d&rsquo;\u00e9galitarisme sans substance o&ugrave; les <a href=\"https:\/\/www.lepetitjuriste.fr\/droit-civil\/le-nouveau-statut-juridique-de-lanimal-une-idee-audacieuse-pour-une-reforme-ineffective\/#https:\/\/www.lepetitjuriste.fr\/droit-civil\/le-nouveau-statut-juridique-de-lanimal-une-idee-audacieuse-pour-une-refor\">animaux<\/a>et bient\u00f4t les v\u00e9g\u00e9taux auront les m\u00eames droits qu&rsquo;une personne humaine. <\/p>\n<\/p>\n<p><p>Il s&rsquo;accompagne de perte des marqueurs nationaux comme la langue. Macron restera c\u00e9l\u00e8bre pour avoir pr\u00e9tendu que le fran\u00e7ais avait son socle d\u00e9sormais <a href=\"https:\/\/www.nice-provence.info\/blog\/2018\/10\/19\/avec-macron-francophonie-cacophonie\/#https:\/\/www.nice-provence.info\/blog\/2018\/10\/19\/avec-macron-francophonie-cacophonie\/\">quelque part en Francophonie<\/a>et s&rsquo;affranchit de son territoire de naissance. Un pr\u00e9c\u00e9dent gouvernement en France avait d\u00e9cr\u00e9t\u00e9 que nombre d&rsquo;enseignements dans le sup\u00e9rieur se feraient <a href=\"https:\/\/www.latribune.fr\/opinions\/tribunes\/20130603trib000768129\/des-enseignements-en-anglais-a-l-universite-une-chance-pour-les-etudiants-francais-.html#https:\/\/www.latribune.fr\/opinions\/tribunes\/20130603trib000768129\/des-enseignements-en-anglai\">en anglais<\/a>.<\/p>\n<\/p>\n<p><p>De m\u00eame restera dans la m\u00e9moire des Marocains la proposition d&rsquo;un <a href=\"http:\/\/fr.le360.ma\/politique\/darija-a-lecole-ayouch-traite-ses-detracteurs-de-chiens-174294#http:\/\/fr.le360.ma\/politique\/darija-a-lecole-ayouch-traite-ses-detracteurs-de-chiens-174294\">r\u00e9formateur<\/a>qui souhaitait abolir l&rsquo;enseignement de l&rsquo;arabe et en arabe, langue universelle, par celui en diff\u00e9rents dialectes ou patois, brisant l&rsquo;histoire, la culture et l&rsquo;unit\u00e9 d&rsquo;un pays.<\/p>\n<\/p>\n<p><p>Euthanasier les langues et accepter d&rsquo;\u00e9changer dans un m\u00e9lange inextricable de plusieurs sans qu&rsquo;aucune ne soit ma&icirc;tris\u00e9e participe de la destruction des nations et Etats nations h\u00e9rit\u00e9s d&rsquo;une tradition europ\u00e9enne post\u00e9rieure au trait\u00e9 de Westphalie.<\/p>\n<\/p>\n<p><p>L&rsquo;avion de chasse, l&rsquo;avion cargo et l&rsquo;avion de transport des passagers-touristes ont largement particip\u00e9 \u00e0 l&rsquo;unification d&rsquo;un monde o&ugrave; par exemple le travailleur consommateur ne sait pas qu&rsquo;en prenant un Uber il <a href=\"https:\/\/www.nytimes.com\/2016\/06\/02\/technology\/uber-investment-saudi-arabia.html#https:\/\/www.nytimes.com\/2016\/06\/02\/technology\/uber-investment-saudi-arabia.html\">r\u00e9tribue un fonds<\/a>d&rsquo;investissement s\u00e9oudien et qu&rsquo;il participe \u00e0 faire dispara&icirc;tre les salaires diff\u00e9r\u00e9s comme la retraite et les droits aux soins de sant\u00e9. <\/p>\n<\/p>\n<p><p>Le sentiment d&rsquo;appartenance \u00e0 une communaut\u00e9 &lsquo;positive&rsquo; encourage l&rsquo;expression des id\u00e9es de chacun au sein du groupe qui  d\u00e8s lors s&rsquo;enrichit de points de vue et de perspectives multiples. Parmi les traits qui caract\u00e9risent une communaut\u00e9 de cette sorte, par del\u00e0 les buts partag\u00e9s et le travail en commun pour les atteindre, la non exclusion des minorit\u00e9s qui la composent est essentielle pour sa p\u00e9rennit\u00e9. La communaut\u00e9 encourage ses membres \u00e0 accomplir leurs obligations au lieu de simplement \u00e9dicter des lois et des r\u00e8glements. Elle se fortifie en c\u00e9l\u00e9brant l&rsquo;h\u00e9ritage accumul\u00e9 depuis sa constitution au travers de comm\u00e9morations d&rsquo;\u00e9v\u00e8nements v\u00e9cus en commun et en rappelant les circonstances de sa naissance.<\/p>\n<\/p>\n<p><p>Thatcher a eu raison de si\u00e8cles d&rsquo;h\u00e9ritages et de partages.<\/p>\n<\/p>\n<p><p>C&rsquo;est plut\u00f4t \u00e0 son id\u00e9ologie que les &lsquo;populistes&rsquo; s&rsquo;ils \u00e9taient \u00e9clair\u00e9s de leur histoire devraient s&rsquo;attaquer et non aux effets induits de ce qu&rsquo;il est convenu d&rsquo;appeler le n\u00e9o-lib\u00e9ralisme qui n&rsquo;est rien d&rsquo;autre que le capitalisme rendu \u00e0 son \u00e9tat natif et sauvage.<\/p>\n<\/p>\n<p><p>Une des exceptions notables \u00e0 cette propension \u00e0 aller vivre ailleurs est repr\u00e9sent\u00e9e par les Palestiniens. La volont\u00e9 de retourner chez eux des Palestiniens chass\u00e9s en 1948 et 1967, r\u00e9fugi\u00e9s dans leur propre pays, les pays voisins et ailleurs plus loin dans le monde est ind\u00e9racinable, constitutive de leur &Ecirc;tre.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Migration et d\u00e9litement social Rien de tel que le sentiment d&rsquo;appartenance \u00e0 une communaut\u00e9 positive pour favoriser l&rsquo;\u00e9panouissement de la personnalit\u00e9. Tous les trait\u00e9s de psychologie et de psychologie sociale montrent que se sentir en lien avec son environnement et en connexion avec un groupe renforce la confiance en soi et \u00e9loigne la d\u00e9pression et&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[31],"tags":[3879,13143,4663,3174],"class_list":["post-78252","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-badia-benjelloun-1","tag-individualisme","tag-migrations","tag-patriotisme","tag-thatcher"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78252"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78252\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}