{"id":78259,"date":"2018-10-28T10:10:21","date_gmt":"2018-10-28T10:10:21","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/28\/une-histoire-belge-le-choix-des-belges\/"},"modified":"2018-10-28T10:10:21","modified_gmt":"2018-10-28T10:10:21","slug":"une-histoire-belge-le-choix-des-belges","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/28\/une-histoire-belge-le-choix-des-belges\/","title":{"rendered":"Une histoire belge\u00a0: le choix des Belges"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Une histoire belge : le choix des Belges<\/h2>\n<\/p>\n<p><p>28 octobre 2018 &ndash; La pens\u00e9e m\u00eame de cet article m&rsquo;\u00e9puise absolument, et je ne m&rsquo;y mets, je vous l&rsquo;avoue, qu&rsquo;apr\u00e8s avoir tant repouss\u00e9 l&rsquo;instant de m&rsquo;y mettre : parler du JSF (F-35), de la Belgique, du choix que ce pays vient de nous annoncer (le F-35), du m\u00e9contentement discret mais un peu goguenard des Fran\u00e7ais, du \u00ab\u00a0Je regrette\u00a0\u00bb de Macron, &ndash; tant de m\u00e9diocre bassesse repousse ma plume qui se refuse \u00e0 se tremper d&rsquo;une encre si m\u00e9diocre. Je chancelle sous le poids de leur surhumaine sottise, avec presque de l&rsquo;admiration dans mon exasp\u00e9ration : \u00ab\u00a0Comment peut-on l&rsquo;\u00eatre autant, si longtemps, si compl\u00e8tement, si d\u00e9cid\u00e9ment, si joyeusement, si content-de-soi ?\u00a0\u00bb<\/p>\n<\/p>\n<p><p>Car enfin, comment, aujourd&rsquo;hui, avec tout ce que l&rsquo;on sait hors des virements et donations mensuelles de Lockheed Martin, oui comment peut-on choisir cet incroyable fer \u00e0 repasser et badigeonner sur son fuselage \u00ab\u00a0avion de combat\u00a0\u00bb, cela pour avertir les Russes qu&rsquo;il s&rsquo;agit bien d&rsquo;un combat a\u00e9rien qui s&rsquo;engage ? Comment peut-on croire les Am\u00e9ricains sur leurs promesses alors qu&rsquo;ils se conduisent partout en pirates, faussaires, faux-fr\u00e8res, tra&icirc;tres et parjures, scandaleux escrocs empilant leur montagne de faux talbins (*) ? Le plus fort, non le plus \u00e9clatant et le plus \u00e9vident, c&rsquo;est que les Belges ne sont pas de \u00ab\u00a0mauvais Europ\u00e9ens\u00a0\u00bb, comme les Fran\u00e7ais le laissent entendre parce que ce qu&rsquo;ils ont fait, qui est de faire leur petite commission face aux Yankees de fa\u00e7on \u00e0 ce que se poursuive le tango transatlantique, eh bien il n&rsquo;y a vraiment rien de plus \u00ab\u00a0bon Europ\u00e9en\u00a0\u00bb selon l&rsquo;esprit de Notre-Europe. Tous leurs matamores de l&rsquo;UE ne font pas autrement, et quant au Macron&#8230;<\/p>\n<\/p>\n<p><p>Ces gens sont totalement ferm\u00e9s, aveugles, absolument insensibles \u00e0 la sagesse de l&rsquo;exp\u00e9rience et \u00e0 la mesure du bon sens, zombies postmodernes ouverts \u00e0 toutes les modes subrepticement sataniques qui dissimulent l&rsquo;hyst\u00e9rie derri\u00e8re la gouvernance. Il en faut diablement pour acheter ce fer \u00e0 repasser yankee qui ne fait \u00ab\u00a0vroum-vroum\u00a0\u00bb en l\u00e2chant un peu de vapeur que si les Yanks l&rsquo;autorisent, alors que ces m\u00eames Yanks, sous la direction \u00e9clair\u00e9e du pr\u00e9sident Trump, sont en train de fracasser le trait\u00e9 FNI qui va transformer l&rsquo;Europe en champ de foire nucl\u00e9aire, &ndash; et que les Europ\u00e9ens, voyez-vous, s&rsquo;en aper\u00e7oivent sans que cela ne produise autre chose que des cris d&rsquo;orfraie. (**) Ce qui me terrorise, je l&rsquo;avoue, c&rsquo;est ce d\u00e9versement, cet amoncellement, cette montagne oc\u00e9anique de sottise, tous ces ministres qui semblent croire que la sottise est un art et que l&rsquo;art \u00e7a se respecte par simple g\u00e9nuflexion de bassesse.<\/p>\n<\/p>\n<p><p>Voil\u00e0 pour les Belges&#8230; Quant aux Fran\u00e7ais !<\/p>\n<\/p>\n<p><p>Cela me ram\u00e8ne en 1986-1989,  &ndash; oui, il y a trente ans et plus dans ce monde qui va si vite ! &ndash; selon l&rsquo;histoire de la premi\u00e8re campagne du <em>Rafale <\/em>en Belgique dont j&rsquo;ai d\u00e9j\u00e0 tr\u00e8s-abondamment et diversement parl\u00e9 pour en avoir \u00e9t\u00e9 un commentateur presque-acteur (allez voir le <a href=\"http:\/\/www.dedefensa.org\/article\/notes-sur-le-rafale-et-lexportation-i\">10 octobre 2009<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article\/journalisme-made-in-cia-iii-dia-phg-belgique-et-jsf-rafale-1\">24 octobre 2014<\/a>). A cette \u00e9poque, les Belges \u00e9taient d\u00e9j\u00e0 des Belges mais ils gardaient le go&ucirc;t des frites nationales-souveraines et savaient deviner \u00e0 la fois la bonne affaire et l&rsquo;affaire qui peut vous tricoter une vertu en vous rapportant gros ; et puis, un peu moins \u00e0 la l\u00e8che devant les Yankees, je me rappelle m\u00eame en avoir rencontr\u00e9 certains qui cultivaient un petit coin d&rsquo;audace gaullienne pour une Europe ind\u00e9pendante. C&rsquo;est pour cette raison qu&rsquo;\u00e0 cette \u00e9poque, le <em>Rafale <\/em>\u00e9tait sans concurrent, et parti pour une coop\u00e9ration et des commandes europ\u00e9ennes (belge dans tous les cas) si l&rsquo;on s&rsquo;y prenait avec une certaine habilet\u00e9 dans les m\u00e9andres des influences <em><a href=\"https:\/\/www.universalis.fr\/dictionnaire\/brusselaire\/\">brusselaire<\/a><\/em>.<\/p>\n<\/p>\n<p><p>Les Fran\u00e7ais, autant le gouvernement que Dassault, furent incroyablement mauvais, \u00e0 la fois arrogants et na\u00effs, bousculant tout et n&rsquo;y comprenant rien. Ils se coul\u00e8rent eux-m\u00eames par le fond dans un grand bruit d&rsquo;autosatisfaction parisienne. Croyez-vous que cela leur ait servi de le\u00e7on ? Aux temps actuels de Macron avec Sarko-Hollande en toile de fond, on a suffisamment \u00e0 faire pour s&rsquo;affirmer \u00e0 soi-m\u00eame qu&rsquo;on est excellents et excellemment europ\u00e9ens, d\u00e9crivant avec des clins d&rsquo;yeux entendus les mirifiques march\u00e9s des &Eacute;tats minuscules et p\u00e9troliers. Le go&ucirc;t des mirages p\u00e9troliers fait qu&rsquo;il est plus glorieux de se prendre une veste aux &Eacute;mirats qu&rsquo;\u00e0 Bruxelles, et puis finalement on enfile les deux.<\/p>\n<\/p>\n<p><p>Par des remarques et confidences de vieux amis du temps pass\u00e9 encore dans le circuit (je m&rsquo;en suis extrait, leur quincaillerie me paraissant de plus en plus rouill\u00e9e pour mon propos g\u00e9n\u00e9ral), j&rsquo;ai suivi de loin en loin la \u00ab\u00a0campagne\u00a0\u00bb fran\u00e7aise \u00e0 Bruxelles pour ce march\u00e9, qui semblait ne pouvoir \u00eatre que victorieuse ; mais je rectifie aussit\u00f4t : \u00ab\u00a0qui semblait ne pouvoir \u00eatre que victorieuse\u00a0\u00bb certes, s&rsquo;il y avait eu campagne&#8230; Il y a quelques mois, un ami bruxellois bien au courant de ces choses m&rsquo;interrogeait encore, incr\u00e9dule devant l&rsquo;absence d&rsquo;activit\u00e9 de mes compatriotes (!) dans le grand champ de la communication o&ugrave; tout se d\u00e9cide : \u00ab\u00a0Mais qu&rsquo;est-ce qu&rsquo;attentent les Fran\u00e7ais ? Le terrain leur est compl\u00e8tement favorable\u00a0\u00bb. Je lui r\u00e9pondis, d&rsquo;instinct dirais-je, car je ne sais plus que penser des Fran\u00e7ais, alors et bien plus encore aujourd&rsquo;hui au cr\u00e9puscule des sombres temps pr\u00e9sents : \u00ab\u00a0C&rsquo;est un <em>remake<\/em> de 1986-1989, en pire\u00a0\u00bb&#8230;<\/p>\n<\/p>\n<p><p>J&rsquo;en ai eu des \u00e9chos, ces dix-huit derniers mois, de confidence comme quoi, \u00ab\u00a0&Ccedil;a y est, Dassault va lancer sa campagne d&rsquo;influence, de relations publiques, d&rsquo;actions dans la presse, d&rsquo;interventions aupr\u00e8s de personnalit\u00e9s qui sont contre le JSF\u00a0\u00bb (Il y en a beaucoup, \u00e9norm\u00e9ment, il suffit d&rsquo;entendre les protestations de l&rsquo;opposition au Parlement, apr\u00e8s l&rsquo;intervention du Premier ministre, le nomm\u00e9 Charles Michel, annon\u00e7ant son choix sans y rien comprendre.) Quant aux autorit\u00e9s fran\u00e7aises du temps de Macron, c&rsquo;est \u00ab\u00a0Paris et le d\u00e9sert fran\u00e7ais\u00a0\u00bb qui aurait atteint lui-m\u00eame (Paris) la d\u00e9sertification compl\u00e8te, &ndash; sans doute la crise climatique&#8230; Ainsi ont-ils laiss\u00e9 passer les occasions, assur\u00e9s de leur \u00ab\u00a0excellence\u00a0\u00bb, de leur influence, de leur irr\u00e9sistible suffisance. Pendant ce temps, la machinerie Lockheed-Martin tournait \u00e0 plein r\u00e9gime, semant ses graines de corruption et de m\u00e9sinformation-satisfaction r\u00e9pandant la <em>narrative <\/em>de la miraculeuse transmutation du JSF en F-35. Les Flamands ont jou\u00e9 leur r\u00f4le habituel de porteurs d&rsquo;eau, cette fois sous les couleurs de la <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Nieuw-Vlaamse_Alliantie\">N-VA<\/a>, ces flamboyants et sulfureux nationalistes-souverainistes qui, comme leurs homologues polonais incapables d&rsquo;imaginer autre chose que Charybde et Scylla, croient qu&rsquo;on d\u00e9fend les grands principes souverains en s&rsquo;appuyant sur les Yankees contre les entreprises des pouvoirs europ\u00e9ens.<\/p>\n<\/p>\n<p><p>C&rsquo;est une bien triste histoire, dix fois, cent fois recommenc\u00e9e dans ces sombres temps pr\u00e9sents&#8230; La seule id\u00e9e qui me r\u00e9conforte, c&rsquo;est qu&rsquo;en faisant ce qu&rsquo;ils ont fait, tous, absolument tous, ils ont contribu\u00e9 \u00e0 encore aggraver et acc\u00e9l\u00e9rer la Grande Crise d&rsquo;Effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h3>\n<\/p>\n<p><p>(*) \u00ab\u00a0Billets de banque\u00a0\u00bb en novlangue-Audiard, cf. <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Le_cave_se_rebiffe\">Le cave se rebiffe<\/a>.<\/em><\/p>\n<\/p>\n<p><p>(**) Des diplomates de l&rsquo;UE, dot\u00e9s d&rsquo;une grande vision de l&rsquo;avenir, ont confi\u00e9 \u00e0 <a href=\"https:\/\/www.zerohedge.com\/news\/2018-10-26\/escobar-who-profits-end-mid-range-nuclear-treaty\">P\u00e9p\u00e9 Escobar<\/a> que &laquo; <em>la d\u00e9cision des &Eacute;tats-Unis <\/em>[de quitter le trait\u00e9 FNI]  <em>a \u00e9t\u00e9 un \u00ab\u00a0choc\u00a0\u00bb et \u00ab\u00a0la goutte d&rsquo;eau qui fait d\u00e9border le vase pour l&rsquo;UE, car elle met en p\u00e9ril notre existence m\u00eame et nous soumet \u00e0 la destruction nucl\u00e9aire par des missiles \u00e0 courte port\u00e9e\u00a0\u00bb, qui ne pourraient jamais atteindre les &Eacute;tats-Unis<\/em>. &raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une histoire belge : le choix des Belges 28 octobre 2018 &ndash; La pens\u00e9e m\u00eame de cet article m&rsquo;\u00e9puise absolument, et je ne m&rsquo;y mets, je vous l&rsquo;avoue, qu&rsquo;apr\u00e8s avoir tant repouss\u00e9 l&rsquo;instant de m&rsquo;y mettre : parler du JSF (F-35), de la Belgique, du choix que ce pays vient de nous annoncer (le F-35),&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[25],"tags":[3238,3301,398,2969,250,394,3582,18634,3219,2746],"class_list":["post-78259","post","type-post","status-publish","format-standard","hentry","category-journal-ddecrisis-de-philippe-grasset","tag-charles","tag-dassault","tag-europe","tag-f-35","tag-jsf","tag-lockheed-martin","tag-michel","tag-n-va","tag-rafale","tag-souverainete"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78259"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78259\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}