{"id":78264,"date":"2018-10-31T11:28:54","date_gmt":"2018-10-31T11:28:54","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/31\/brexit-et-belxit-la-belgique-quitte-t-elle-lue\/"},"modified":"2018-10-31T11:28:54","modified_gmt":"2018-10-31T11:28:54","slug":"brexit-et-belxit-la-belgique-quitte-t-elle-lue","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/10\/31\/brexit-et-belxit-la-belgique-quitte-t-elle-lue\/","title":{"rendered":"BREXIT et BELXIT : la Belgique quitte-t-elle l&rsquo;UE ?"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">BREXIT et BELXIT : la Belgique quitte-t-elle l&rsquo;UE ?<\/h2>\n<\/p>\n<p><p>Ces derni\u00e8res d\u00e9cennies et dans le peloton de t\u00eate, tous les gouvernements belges ont confirm\u00e9 leur d\u00e9termination in\u00e9branlable \u00e0 renforcer les capacit\u00e9s de d\u00e9fense europ\u00e9ennes. En d\u00e9cembre 2016 au Conseil europ\u00e9en, la Belgique a mobilis\u00e9 ses forces pour qu&rsquo;un vaste plan visant \u00e0 approfondir la coop\u00e9ration en mati\u00e8re de s\u00e9curit\u00e9 et de d\u00e9fense europ\u00e9enne soit approuv\u00e9. Le rythme s&rsquo;est encore acc\u00e9l\u00e9r\u00e9 en juin 2017 avec la mise en place d&rsquo;un Fonds europ\u00e9en commun de la d\u00e9fense charg\u00e9 de financer les activit\u00e9s conjointes de recherche et d\u00e9veloppement des capacit\u00e9s militaires europ\u00e9ennes.<\/p>\n<\/p>\n<p><p>Ces d\u00e9cisions capitales, embl\u00e9matiques d&rsquo;un cap politique coh\u00e9rent et \u00e9tabli sur la dur\u00e9e font honneur \u00e0 ce pays. La Belgique s&rsquo;oblige sur le plan politique, militaire et financier \u00e0 mettre en commun ses projets de d\u00e9penses en mati\u00e8re de d\u00e9fense afin de mieux recenser les lacunes, d&rsquo;\u00eatre plus coh\u00e9rente et de b\u00e9n\u00e9ficier des \u00e9conomies d&rsquo;\u00e9chelle, dans le cadre d&rsquo;un processus appel\u00e9 &quot;Examen annuel coordonn\u00e9 en mati\u00e8re de d\u00e9fense&quot; (EACD).<\/p>\n<\/p>\n<p><p>La terminologie employ\u00e9e dans ces paragraphes est issue des textes officiels [1]. Ces chantiers ont \u00e9t\u00e9 impuls\u00e9s par la Belgique, promus d&rsquo;une mani\u00e8re militante par ses dirigeants dans les enceintes europ\u00e9ennes et pr\u00e9sent\u00e9s avec conviction face \u00e0 une opinion publique secou\u00e9e par les crises de cr\u00e9dibilit\u00e9 europ\u00e9enne qui se succ\u00e8dent en Europe : du Royaume Uni \u00e0 l&rsquo;Italie, \u00e0 la Hongrie, \u00e0 la Pologne, \u00e0 la Gr\u00e8ce&hellip;<\/p>\n<\/p>\n<p><p>Les mises en sc\u00e8nes m\u00e9diatiques de ces nouveaux syst\u00e8mes europ\u00e9ens dot\u00e9s de comp\u00e9tences aussi sensible que la s\u00e9curit\u00e9 et la d\u00e9fense affectent en effet radicalement posture, ambition et cr\u00e9dibilit\u00e9 du Royaume de Belgique. Pour que la dynamique soit confirm\u00e9e et approfondie, ce pays vient encore de cr\u00e9er avec ses partenaires un cadre permanent de coop\u00e9ration en mati\u00e8re de d\u00e9fense entre les &Eacute;tats membres qui le souhaitent et qui sont en mesure de d\u00e9velopper conjointement des capacit\u00e9s de d\u00e9fense, d&rsquo;investir dans des projets communs ou de mettre sur pied des formations multinationales. Des dizaines de projets sont cens\u00e9s \u00eatre examin\u00e9s par la Belgique et les autres participant \u00e0 cette &quot;Coop\u00e9ration structur\u00e9e permanente&quot; (CSP).<\/p>\n<p>Depuis les premiers pas de l&rsquo;Union europ\u00e9enne \u00e0 Maastricht en 1992 jusqu&rsquo;\u00e0 ces engagements solennels r\u00e9cents, la Belgique a assum\u00e9 avec t\u00e9nacit\u00e9 les responsabilit\u00e9s acquises lorsqu&rsquo;en 1957 elle a jet\u00e9 avec l&rsquo;Allemagne, la France, l&rsquo;Italie, le Luxembourg et les Pays-Bas les bases du projet europ\u00e9en. Elle s&rsquo;est assur\u00e9e depuis 60 ans que le cap initi\u00e9 \u00e0 Six sera maintenu. Une biblioth\u00e8que compl\u00e8te des projets, des espoirs et des d\u00e9cisions en t\u00e9moigne : le domaine de la d\u00e9fense en est la composante la plus concr\u00e8te. Celle-ci est embl\u00e9matique de l&rsquo;ambition des &Eacute;tats fondateurs. Apr\u00e8s des d\u00e9cennies d&rsquo;atermoiements, de convulsions strat\u00e9giques, l&rsquo;Europe a n\u00e9goci\u00e9 son tempo avec l&rsquo;OTAN, sans dommage majeur pour le trait\u00e9 de l&rsquo;Atlantique Nord, sans coup d&rsquo;humeur fatal au lien avec l&rsquo;alli\u00e9 am\u00e9ricain. Elle a inscrit la s\u00e9curit\u00e9 europ\u00e9enne dans des actes fondateurs d&rsquo;une souverainet\u00e9 continentale raisonnable : rester ma&icirc;tres de nos actes, r\u00e9sister aux rivalit\u00e9s entre grandes puissances, apporter l&rsquo;apaisement l\u00e0 o&ugrave; la guerre toujours menace, est un acte de bon sens et de dignit\u00e9.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">L&rsquo;Angleterre reprend la Belgique <\/h3>\n<\/p>\n<p><p>Le Royaume-Uni nous quitte. Encore visible \u00e0 l&rsquo;horizon du Channel, il continuera &ndash; en pente douce d\u00e9sormais &ndash; \u00e0 freiner ce que l&rsquo;Union europ\u00e9enne construit sur ces dossiers depuis des d\u00e9cennies. Processus dont la dramaturgie s&rsquo;inscrit sur le discours ambigu tenu par Londres entre d\u00e9pendance am\u00e9ricaine et entrisme europ\u00e9en, le BREXIT nous rappelle cruellement combien l&rsquo;ambivalence est porteuse de trag\u00e9dies, combien les proclamations atlantiques excessives devant une Europe qui a besoin de tous sont incapacitantes ; combien jouer sur plusieurs tableaux \u00e0 la fois brise plus s&ucirc;rement les liens entre alli\u00e9s qu&rsquo;un chantier politique s\u00e9rieux et des engagements muris.<\/p>\n<\/p>\n<p><p>Tr\u00e8s ancien pratiquant des affaires de s\u00e9curit\u00e9 europ\u00e9enne, je ne compte plus les confidences de ces diplomates belges ent\u00eat\u00e9s mis au pilori par leurs coll\u00e8gues britanniques, de pr\u00e9f\u00e9rence \u00e0 la derni\u00e8re minute, pour bloquer toute dynamique europ\u00e9enne qui ne se rangerait pas sous la banni\u00e8re am\u00e9ricaine. Pas assez puissant pour bloquer tout, le Royaume-Uni n&rsquo;a cess\u00e9 de ralentir, d&rsquo;alourdir, de r\u00e9duire des progr\u00e8s dans ces domaines.<\/p>\n<\/p>\n<p><p>Le Pentagone fait le compte des d\u00e9sastres strat\u00e9giques US depuis 30 ans (Afghanistan, Irak, Libye, Syrie, Y\u00e9men&hellip;). Dans un tel contexte et si elle n&rsquo;est pas pu\u00e9rile (elle amuse beaucoup les industriels am\u00e9ricains qui, gravement, s&rsquo;appuient sur elle pour imposer leurs affaires), la d\u00e9pendance europ\u00e9enne est inqui\u00e9tante : les avertissements virulents de l&rsquo;administration am\u00e9ricain \u00e0 l&rsquo;adresse de tous les &Eacute;tats du monde qui veulent s&rsquo;\u00e9quipent en mat\u00e9riel non-US sont \u00e9difiants. Rien n&rsquo;arr\u00eatera cette logique de l&rsquo;America First &laquo; illib\u00e9rale &raquo; : des alli\u00e9s comme la Turquie, des partenaires strat\u00e9giques comme l&rsquo;Arabie saoudite, l&rsquo;Inde ou l&rsquo;&Eacute;gypte sont aujourd&rsquo;hui menac\u00e9s de lourdes sanctions s&rsquo;ils ne renoncent pas \u00e0 certains \u00e9quipements russes ou autres.<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">L&rsquo;Am\u00e9rique solde ses F-35 et ironise<\/h3>\n<\/p>\n<p><p>C&rsquo;est \u00e0 ce tournant pr\u00e9visible et permis par l&rsquo;ambigu\u00eft\u00e9 de quelques &Eacute;tats engag\u00e9s \u00e0 reculons que la Belgique choisit de dire aux Europ\u00e9ens : &laquo; Nos chantiers depuis 20 ans n&rsquo;ont aucun int\u00e9r\u00eat. Renon\u00e7ons. &raquo;<\/p>\n<\/p>\n<p><p>Sur le programme le plus co&ucirc;teux d&rsquo;\u00e9quipement militaire, le plus structurant en mati\u00e8re technologique, le plus embl\u00e9matique sur le plan politique et strat\u00e9gique &ndash; le choix d&rsquo;un avion de combat &ndash; un pays Fondateur renonce \u00e0 son dossier international cl\u00e9, abandonne les industriels europ\u00e9ens et belges et ach\u00e8te un avion am\u00e9ricain, le F-35. Au bas mot, ce sont 50 ann\u00e9es de d\u00e9pendance totale des &Eacute;tats-Unis &ndash; technologique, militaire, tactique et op\u00e9rationnelle &ndash; qui sont d\u00e9cid\u00e9es. C&rsquo;est la dur\u00e9e de vie moyenne d&rsquo;un syst\u00e8me de cette nature (comme le F-16 command\u00e9 en 1975).<\/p>\n<\/p>\n<p><p>Les mots ont peine \u00e0 d\u00e9crire la reculade op\u00e9r\u00e9e : incarnation de ce que les \u00e9tats-majors et les bureaux d&rsquo;\u00e9tudes d\u00e9signaient alors comme le &laquo; syst\u00e8me de syst\u00e8mes &raquo;, le Joint Strike Fighter (pr\u00e9c\u00e9dent nom du F-35) s&rsquo;inscrit dans une chaine de commandement, de contr\u00f4le, de communication et d&rsquo;intelligence (C3I) dont le c&oelig;ur est am\u00e9ricain &ndash; exclusivement. Sans feu vert US, aucun F-35 dans le monde ne d\u00e9collera pour une mission op\u00e9rationnelle (on peut parier que l&rsquo;exception isra\u00e9lienne ne sera jamais confirm\u00e9e). Les &Eacute;miratis ont fait les frais r\u00e9cemment des interdictions de vol am\u00e9ricaines sur leurs propres F-16 Bloc 60. Leurs Mirages 2000-5 ont d&ucirc; op\u00e9rer seuls sur zones de guerre. On ne dit rien des petites coupures du GPS am\u00e9ricain sur quelques th\u00e9\u00e2tres d&rsquo;op\u00e9ration europ\u00e9ens&hellip;<\/p>\n<\/p>\n<p><p>&laquo; Syst\u00e8me de syst\u00e8me &raquo; a \u00e9t\u00e9 sorti \u00e0 dessein du vocabulaire industriel et militaire am\u00e9ricain, comme me l&rsquo;a rappel\u00e9 ing\u00e9nument un ing\u00e9nieur de Lockheed-Martin : la d\u00e9signation explicite d&rsquo;un chef tous azimuts a \u00e9t\u00e9 comprise comme contre-productive \u00e0 l&rsquo;expansion des march\u00e9s. On en reste \u00e0 int\u00e9gration, interop\u00e9rabilit\u00e9&hellip; qui blessent moins la dignit\u00e9 des clients \u00e0 qui sont pr\u00e9sent\u00e9 des sc\u00e9narios moins frustrants. Les professionnels savent bien de quoi il est question&hellip;<\/p>\n<\/p>\n<p><p>La pr\u00e9tention \u00e0 l&rsquo;ind\u00e9pendance op\u00e9rationnelle belge est sans doute excessive au regard des rapports de force r\u00e9els entre alli\u00e9s. Qu&rsquo;une certaine d\u00e9pendance soit paralysante et extra-europ\u00e9enne alors que l&rsquo;on navigue d\u00e9sormais entre sanctions am\u00e9ricaines multiformes, embargos impos\u00e9s, amendes aux entreprises, extraterritorialit\u00e9 des lois am\u00e9ricaines sur le commerce devrait pourtant interdire de se lier les mains davantage ; que dire du choix fait de prolonger cette paralysie volontaire pendant 50 ans, pas un mois se passant sans que des redistributions de cartes \u00e9conomiques, financi\u00e8res et politiques ne reconfigurent la plan\u00e8te ?<\/p>\n<\/p>\n<p><p>D&rsquo;autres &Eacute;tats membres de l&rsquo;Union europ\u00e9enne ont fait le choix du F-35. Outre le fait que certains s&rsquo;en mordent cruellement les doigts (co&ucirc;t en croissance exponentielle, impasses technologiques, r\u00e9duction en proportion du nombre d&rsquo;avions en commande&hellip;), le processus qui les a conduits est impr\u00e9gn\u00e9 de ce qui m\u00e8ne aujourd&rsquo;hui au BREXIT. Ces pays ont de surcro&icirc;t d\u00e9cid\u00e9 il y a 15 ans (16 ans pour les Pays-Bas). La d\u00e9fense europ\u00e9enne \u00e9tait balbutiante. A l&rsquo;image du Royaume-Uni qui confirme des options connues et hostiles au projet europ\u00e9en, ces pays ont investi dans le complexe industriel am\u00e9ricain de la d\u00e9fense sur une foi quasi religieuse en la sup\u00e9riorit\u00e9 am\u00e9ricaine, pas sur une analyse lucide des atouts technologiques Europ\u00e9ens et Am\u00e9ricains : qui se rappelle le fameux Technological Gap des ann\u00e9es 1990, 2000 et au-del\u00e0 ? Bien des champs op\u00e9rationnels d\u00e9montrent une efficacit\u00e9 op\u00e9rationnelle europ\u00e9enne et des configurations technologiques souples et adapt\u00e9e. Nombre d&rsquo;entreprises europ\u00e9ens ont d\u00e9montr\u00e9 des capacit\u00e9s militaires de tr\u00e8s haut niveau. Elles prouvent au point de le faire dispara&icirc;tre des \u00e9crans politiques, que le Technological Gap euro-am\u00e9ricain \u00e9tait un concept commercial, pas un tableau de comp\u00e9tences que ne rechercheront d&rsquo;ailleurs jamais \u00e0 l&rsquo;identique les deux rives de l&rsquo;Atlantique.<\/p>\n<\/p>\n<p><p>A Bruxelles, la chasse au doute est lanc\u00e9e par ceux qui affichent une expertise sure : &laquo; Le F-35 bien s&ucirc;r ne fonctionne pas, c&rsquo;est une usine \u00e0 gaz mais puisque ce sont les Am\u00e9ricains, il fonctionnera bien un jour !&#8230; &raquo; C&rsquo;est \u00e0 croire que personne ici ne lit les auditions du Congr\u00e8s, les articles de la presse a\u00e9ronautique am\u00e9ricaine et les rapports alarmants du U.S. Government Accountability Office (GAO) dans lesquels le damage control du programme F-35 n&rsquo;a plus qu&rsquo;un nom : vendre, vendre \u00e0 toute vitesse pour \u00e9viter que les tares du syst\u00e8me a\u00e9rien ne soient fatales au programme. <\/p>\n<\/p>\n<p><p>25 ans apr\u00e8s le d\u00e9but du programme d&rsquo;\u00e9tudes, 18 ans apr\u00e8s son lancement, le F-35 est devenu \u00e0 coup de rajouts budg\u00e9taires le programme industriel le plus cher de tous les temps : estim\u00e9 \u00e0 plus d&rsquo;un trillion et demi de dollars, il inonde aujourd&rsquo;hui les bases am\u00e9ricaines de prototype &hellip;fabriqu\u00e9s en s\u00e9rie : une m\u00e9thode imparable (la fameuse technique du &laquo; Concurrency &raquo;) choisie quand l&rsquo;affaire a commenc\u00e9 \u00e0 mal tourner et pour que le programme ne puisse jamais \u00eatre arr\u00eat\u00e9. Le Vice Adm. Mat Winter, patron du programme JSF\/F-35 a reconnu en septembre 2017 (qui a vu cela en Europe ?) que tous les appareils produits recevront tant de modifications et des modifications tellement co&ucirc;teuses avant d&rsquo;\u00eatre certifi\u00e9s d\u00e9finitivement qu&rsquo;il pourrait \u00eatre plus \u00e9conomique de les remplacer par des neufs&hellip; Empilez les g\u00e9n\u00e9rations successives de technologies, on verra bien (&laquo; un jour ! &raquo;) comment les faire fonctionner ensemble ! (Les F-35 ne peuvent toujours pas communiquer avec les F-22 am\u00e9ricains charg\u00e9s de leur protection a\u00e9rienne ; emb\u00eatant &ndash; car cela les Europ\u00e9ens ne le disent (savent) jamais : le F-35 est un avion d&rsquo;appui tactique au sol. Pas un chasseur a\u00e9rien ou un syst\u00e8me omnirole).<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">La Belgique dans un syst\u00e8me d&rsquo;armes europ\u00e9en majeur apr\u00e8s 2068 ?<\/h3>\n<\/p>\n<p><p>Le F-16 fut une &oelig;uvre d&rsquo;art et de ma&icirc;trise des enjeux politiques. Vainqueur \u00e0 l&rsquo;origine d&rsquo;un programme d&rsquo;\u00e9tude de faisabilit\u00e9 pour un d\u00e9monstrateur a\u00e9rien l\u00e9ger (Light Weight Fighter), lanc\u00e9 sous l&rsquo;impulsion d&rsquo;un ancien pilote d&rsquo;essai (John Boyd) et d&rsquo;un ing\u00e9nieur syst\u00e8me fran\u00e7ais (Pierre Sprey) d\u00e9but 1971, il n&rsquo;avait \u00e0 l&rsquo;origine aucune vocation \u00e0 \u00e9quiper l&rsquo;aviation am\u00e9ricaine. Fin 1973 le YF-16 de General Dynamics fut de toute urgence bascul\u00e9 vers un v\u00e9ritable programme d&rsquo;avion de combat et rebaptis\u00e9 pour la cause en ACF (Air Combat Fighter) : les industriels am\u00e9ricains s&rsquo;\u00e9taient avis\u00e9s que plusieurs pays europ\u00e9ens cherchaient \u00e0 renouveler les tristement c\u00e9l\u00e8bres F-104 Starfighter. Le premier YF-16 sortit d&rsquo;usine \u00e0 la fin de l&rsquo;ann\u00e9e. Il fit son vol inaugural le 2 f\u00e9vrier 1974. Un an plus tard soit \u00e0 la mi-1975 (on en est 18 ans pour le F-35), l&rsquo;avion sortait en s\u00e9rie des usines de General Dynamics et en 1979 l&rsquo;USAF recevait ses premiers appareils certifi\u00e9s.<\/p>\n<\/p>\n<p><p>Le F-16 fut l&rsquo;exact inverse du F-35 : mise au point en un temps record, l\u00e9ger, simple, de co&ucirc;t d&rsquo;acquisition et d&rsquo;exploitation abordable et fabriqu\u00e9 sur le continent pour ses clients europ\u00e9ens. Les autorit\u00e9s belges se sont laiss\u00e9 convaincre par les experts (ceux qui ont un peu de &laquo; bouteille &raquo; connaissent bien comment fonctionne un expert) que l&rsquo;Europe aura 30% des composants du F-35 sur le continent. Outre que cela se saurait (l&rsquo;avion vole), on ne peut qu&rsquo;\u00eatre interdit devant la m\u00e9connaissance compl\u00e8te de la gen\u00e8se du F-35 \u00e0 ce niveau de responsabilit\u00e9 politique. La Belgique ne construira pas une miette du F-35 et ne recevra pas une miette de compensation du programme en dehors de quelques engagements de principe : les autres participants au programme bataillent d\u00e9j\u00e0 trop pour avoir leur part promise (et totalement &laquo; contr\u00f4l\u00e9e &raquo; en techno) du processus industriel ou de maintenance. La Belgique en prime voit s&rsquo;\u00e9chapper toute opportunit\u00e9 de participation directe et enti\u00e8re \u00e0 la modernisation des Rafales, Eurofighters ou autres Gripens, l\u00e0 o&ugrave; les b\u00e9n\u00e9fices industriels eussent \u00e9t\u00e9 consid\u00e9rables. <\/p>\n<\/p>\n<p><p>Co&ucirc;t imm\u00e9diat du BELXIT : l&rsquo;ambitieux programme franco-allemand SCAF d&rsquo;avion de combat europ\u00e9en se fera sans Belges. Le paradoxe est que quelle que soit l&rsquo;indignation belge \u00e0 l&rsquo;\u00e9gard de ce panneau d&rsquo;interdiction lev\u00e9 par une ambassadrice lucide, le tabou viendra beaucoup moins s&ucirc;rement de Paris ou de Berlin que des ing\u00e9nieurs am\u00e9ricains de chez Lockheed-Martin ou du Pentagone pour qui l&rsquo;entr\u00e9e dans le &laquo; club ferm\u00e9 &raquo; du F-35 ne saurait \u00eatre compatible avec des passerelles technologiques vers les concurrents europ\u00e9ens !<\/p>\n<\/p>\n<p><p>Le Royaume-Uni en a fait l&rsquo;am\u00e8re exp\u00e9rience deux fois dans son d\u00e9sir de travailler avec Dassault Aviation : deux bureaux d&rsquo;\u00e9tudes conjoints en dix ans, deux \u00e9quipes tri\u00e9es sur le volet et enthousiastes, finalement paralys\u00e9es par les tabous am\u00e9ricains qui emp\u00eachaient toute participation des ing\u00e9nieurs britanniques \u00e0 des concepts s&rsquo;approchant des technologies am\u00e9ricaines dans lesquelles les britanniques \u00e9taient un tant soit peu engag\u00e9s (furtivit\u00e9 sur les avions de chasse et sur le drone FR-UK Telemos, etc.) Deux essais pour rien des deux plus grandes puissances militaires europ\u00e9ennes &ndash; interdites de fian\u00e7ailles par le protecteur d&rsquo;outre atlantique.<\/p>\n<\/p>\n<p><p>Londres est rest\u00e9 otage de cette logique, absent sur le drone franco-italo-allemand MALE (Airbus Defence and Space, Dassault Aviation, Leonardo-Finmeccanica) ; idem pour le NeuRon europ\u00e9en (France, Gr\u00e8ce, Su\u00e8de, Espagne, Italie) pilot\u00e9 par Dassault. Il est des coop\u00e9rations qui ne sont m\u00eame pas envisag\u00e9es&hellip; La file d&rsquo;attente pour participer au programme d&rsquo;avion de combat futur britannique Tempest Concept (MBDA, Leonardo Finmeccanica&hellip;) ne saurait tarder \u00e0 faire l&rsquo;objet de l&rsquo;attention soutenue des conservateurs am\u00e9ricains plus vigilants que jamais sur les quelques secrets technologiques partag\u00e9s avec sa Gracieuse Majest\u00e9.<\/p>\n<\/p>\n<p><p>La Belgique a-t-elle compris le BREXIT ? Vou\u00e9e \u00e0 remplacer le Royaume-Uni autour de la table du Conseil europ\u00e9en lorsqu&rsquo;il faudra verser les contributions au Plan d&rsquo;action D\u00e9fense [2], elle perd d\u00e9finitivement son statut de pays fondateur et la l\u00e9gitimit\u00e9 qui en d\u00e9coule. Regard\u00e9e avec ironie par ses voisins n\u00e9erlandais (plus francs atlantistes depuis le d\u00e9but) ou luxembourgeois (plus riches), elle verra arriver ses premiers &laquo; prototypes &raquo; de F-35 au moment o&ugrave; l&rsquo;Europe de la d\u00e9fense aura c\u00e9d\u00e9 sous les coups de ses inventeurs les plus d\u00e9termin\u00e9s. A moins que, la situation mondiale l&rsquo;imposant, les vrais Europ\u00e9ens marquent le coup, investissent et r\u00e9ussissent \u00e0 maintenir et d\u00e9velopper en commun des capacit\u00e9s industrielles. Mais cela se fera sans le Royaume de Belgique.<\/p>\n<\/p>\n<p><p>&Eacute;conomies d&rsquo;\u00e9chelle, d\u00e9veloppement industriel europ\u00e9en dans le domaine de la d\u00e9fense, etc. a sign\u00e9 encore r\u00e9cemment le gouvernement f\u00e9d\u00e9ral &ndash; sans rire. Les Am\u00e9ricains ne partagent jamais une technologie sensible avec leurs partenaires. Allemands, Fran\u00e7ais&hellip; y sont en Europe aujourd&rsquo;hui oblig\u00e9s et en font publiquement acte politique et de cr\u00e9dibilit\u00e9. C\u00e9cit\u00e9 belge.<\/p>\n<p>Les Anglais avaient \u00e0 composer flegmatiquement avec le &laquo; No &raquo; US. Ils s&rsquo;en vont. Il restera bien une cr\u00e9dibilit\u00e9 belge au Conseil europ\u00e9en pour r\u00e9pliquer \u00e0 la pluie d&rsquo;offensives politico-commerciales am\u00e9ricaines contre l&rsquo;Europe. Taxer les F-35 \u00e0 l&rsquo;importation par exemple&hellip;<\/p>\n<\/p>\n<p><p>BREXIT Soft et BELXIT Hard ? Monnet, Schuman, Paul-Henri Spaak et nos industriels croient r\u00eaver.<\/p>\n<\/p>\n<p><h4>Yves Mollard La Bruy\u00e8re<\/h4>\n<\/p>\n<p><p>(Ancien fonctionnaire europ\u00e9en)<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h2>\n<\/p>\n<p><p>(1) On ne r\u00e9siste pas aux textes officiels. Un exemple suffit pour d\u00e9crire le renoncement aux engagement solennels. Un extrait des Conclusions du Conseil europ\u00e9en sur la s\u00e9curit\u00e9 et la d\u00e9fense de juin 2017 appara&icirc;t en fin d&rsquo;article.<\/p>\n<\/p>\n<p><p>(2) Le plan d&rsquo;action a d\u00e9j\u00e0 pour mission trois programmes : la mise en place un Fonds europ\u00e9en de la d\u00e9fense, les investissements dans le secteur de la d\u00e9fense ; le renforcement du march\u00e9 unique de la d\u00e9fense. L&rsquo;objectif est de renforcer l&rsquo;efficacit\u00e9 au regard des co&ucirc;ts des d\u00e9penses militaires, d&rsquo;am\u00e9liorer la coop\u00e9ration dans le domaine de la d\u00e9fense et de consolider la base industrielle.<\/p>\n<\/p>\n<p><p>&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;&ndash;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Annexe<\/h2>\n<\/p>\n<p><p>Conclusions du Conseil europ\u00e9en sur la s\u00e9curit\u00e9 et la d\u00e9fense, 22\/06\/2017 (extrait) :<\/p>\n<\/p>\n<p><p>7. Le d\u00e9veloppement conjoint de projets capacitaires d\u00e9cid\u00e9s d&rsquo;un commun accord par les &Eacute;tats membres en vue de rem\u00e9dier aux lacunes majeures qui existent et de mettre au point les technologies de demain est primordial si l&rsquo;on veut atteindre le niveau d&rsquo;ambition de l&rsquo;UE approuv\u00e9 par le Conseil europ\u00e9en en d\u00e9cembre 2016. Le Conseil europ\u00e9en accueille avec satisfaction la communication de la Commission relative \u00e0 un Fonds europ\u00e9en de la d\u00e9fense, qui comporte un volet &quot;recherche&quot; et un volet &quot;capacit\u00e9s&quot;, et attend avec int\u00e9r\u00eat sa concr\u00e9tisation rapide. Il appelle \u00e0 la conclusion rapide d&rsquo;un accord sur la proposition relative \u00e0 un programme europ\u00e9en de d\u00e9veloppement industriel dans le domaine de la d\u00e9fense afin que celui-ci soit mis en &oelig;uvre sans tarder, avant que des programmes de plus grande envergure puissent \u00eatre envisag\u00e9s \u00e0 moyen terme. Le Conseil europ\u00e9en appelle les &Eacute;tats membres \u00e0 recenser des projets capacitaires appropri\u00e9s pour le Fonds europ\u00e9en de la d\u00e9fense et pour le programme europ\u00e9en de d\u00e9veloppement industriel dans le domaine de la d\u00e9fense. Le Conseil europ\u00e9en invite les &Eacute;tats membres \u00e0 continuer de travailler sur des options concernant la passation conjointe de march\u00e9s portant sur des capacit\u00e9s dans le cadre du Fonds europ\u00e9en de la d\u00e9fense, sur la base de m\u00e9canismes de financement solides. L&rsquo;objectif est de fournir des capacit\u00e9s, de doter l&rsquo;industrie de d\u00e9fense europ\u00e9enne d&rsquo;une base comp\u00e9titive, innovante et \u00e9quilibr\u00e9e \u00e0 l&rsquo;\u00e9chelle de l&rsquo;UE, y compris par une coop\u00e9ration transnationale et une participation des PME, et de contribuer au renforcement de la coop\u00e9ration europ\u00e9enne en mati\u00e8re de d\u00e9fense, en exploitant les synergies et en mobilisant un soutien de l&rsquo;UE venant s&rsquo;ajouter au financement assur\u00e9 par les &Eacute;tats membres. Le d\u00e9veloppement industriel europ\u00e9en dans le domaine de la d\u00e9fense n\u00e9cessitera \u00e9galement que l&rsquo;UE soutienne les investissements des PME et les investissements interm\u00e9diaires (soci\u00e9t\u00e9s \u00e0 moyenne capitalisation) dans le domaine de la s\u00e9curit\u00e9 et de la d\u00e9fense. &Agrave; cet \u00e9gard, le Conseil europ\u00e9en invite une nouvelle fois la Banque europ\u00e9enne d&rsquo;investissement \u00e0 examiner des mesures en vue de soutenir les investissements dans les activit\u00e9s de recherche et d\u00e9veloppement en mati\u00e8re de d\u00e9fense. (&hellip;)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BREXIT et BELXIT : la Belgique quitte-t-elle l&rsquo;UE ? Ces derni\u00e8res d\u00e9cennies et dans le peloton de t\u00eate, tous les gouvernements belges ont confirm\u00e9 leur d\u00e9termination in\u00e9branlable \u00e0 renforcer les capacit\u00e9s de d\u00e9fense europ\u00e9ennes. En d\u00e9cembre 2016 au Conseil europ\u00e9en, la Belgique a mobilis\u00e9 ses forces pour qu&rsquo;un vaste plan visant \u00e0 approfondir la coop\u00e9ration&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3019,3079,1015,2969,250],"class_list":["post-78264","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-defense","tag-europeenne","tag-f-16","tag-f-35","tag-jsf"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78264"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78264\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}