{"id":78301,"date":"2018-11-13T10:05:45","date_gmt":"2018-11-13T10:05:45","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/11\/13\/heidegger-et-la-destruction-du-monde\/"},"modified":"2018-11-13T10:05:45","modified_gmt":"2018-11-13T10:05:45","slug":"heidegger-et-la-destruction-du-monde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/11\/13\/heidegger-et-la-destruction-du-monde\/","title":{"rendered":"Heidegger et la destruction du monde"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Heidegger et la destruction du monde<\/h2>\n<\/p>\n<p><p>Dans la pens\u00e9e allemande moderne, on note une belle r\u00e9flexion nostalgique sur un pass\u00e9 grec alcyonien ou bien une vision pessimiste par rapport au progr\u00e8s. Au d\u00e9but du vingti\u00e8me si\u00e8cle, le po\u00e8te philosophe Rilke \u00e9voque dans son admirable huiti\u00e8me \u00e9l\u00e9gie cet animal qui voit dans l&rsquo;ouvert \u00e0 plein regard, ce que ne peut plus faire l&rsquo;homme (il n&rsquo;a pas vu les chiens d&rsquo;aujourd&rsquo;hui Rilke), homme qui se tient devant et ne peut plus faire partie du monde. Tout cela est li\u00e9 \u00e0 l&rsquo;involution anthropologique et spirituelle, cons\u00e9quence de l&rsquo;av\u00e8nement d&rsquo;une soci\u00e9t\u00e9 hyper-technique dont l&rsquo;Allemagne, de Bismarck \u00e0 Merkel via l&rsquo;autre, fut et reste la caricature (Metropolis&hellip;). On a vu que Goethe, Schiller et Kleist pressentent ce d\u00e9sastre pendant les ann\u00e9es napol\u00e9oniennes.<\/p>\n<\/p>\n<p><p>Le dernier h\u00e9ritier de cette belle, parfois sulfureuse, \u00e9cole de pens\u00e9e est bien s&ucirc;r Heidegger. Avant de lui donner la parole (il ne jargonne pas toujours !), on rappelle l&rsquo;interview de Lucien Cerise sur le devenir-machin de l&rsquo;homme postmoderne :<\/p>\n<\/p>\n<p><p>&laquo; Si l&rsquo;on poursuit la r\u00e9flexion de Foucault ou Agamben, on arrive au brevetage du vivant, c&rsquo;est-\u00e0-dire \u00e0 sa privatisation, aux Organismes G\u00e9n\u00e9tiquement Modifi\u00e9s, \u00e0 l&rsquo;eug\u00e9nisme et au transhumanisme. Malheureusement, tout cela est d&rsquo;actualit\u00e9. En effet, il existe des volont\u00e9s affirm\u00e9es au sein d&rsquo;organisations supranationales sans l\u00e9gitimit\u00e9 comme l&rsquo;Union europ\u00e9enne ou l&rsquo;Organisation Mondiale de la Sant\u00e9 d&rsquo;en finir avec la biodiversit\u00e9 au moyen de textes \u00e0 pr\u00e9tentions l\u00e9gales tels que le Catalogue des semences autoris\u00e9es, le Certificat d&rsquo;obtention v\u00e9g\u00e9tale ou le Codex Alimentarius. Toutes ces prospectives sont r\u00e9sum\u00e9es par le concept de Gestell, formul\u00e9 par Heidegger, que l&rsquo;on pourrait traduire par le &laquo; dispos\u00e9 &raquo;. Ou encore, au prix d&rsquo;un n\u00e9ologisme, &laquo; l&rsquo;ing\u00e9nier\u00e9 &raquo;. C&rsquo;est vraiment l&rsquo;esprit de l&rsquo;\u00e9poque, la soci\u00e9t\u00e9 liquide, rien ne doit \u00eatre &laquo; en dur &raquo; et rien ne doit durer, il faut pouvoir tout r\u00e9\u00e9crire, tout modifier, tout recomposer \u00e0 chaque instant car tout doit \u00eatre mis \u00e0 disposition, tous les aspects de la vie, y compris les plus intimes, en l&rsquo;occurrence le code g\u00e9n\u00e9tique des \u00eatres vivants, de tous les \u00eatres vivants, de la plante \u00e0 l&rsquo;humain. &raquo;<\/p>\n<\/p>\n<p><p>Si j&rsquo;avais \u00e0 traduire le Gestell je dirais l&rsquo;\u00e9tag\u00e8re. Et on met ce qu&rsquo;on veut sur une \u00e9tag\u00e8re, en attendant de la remplacer. L&rsquo;esprit humain est ainsi reprogramm\u00e9 \u00e0 dessein, et continuellement. Voyez les m\u00e9saventures de l&rsquo;esprit allemand depuis Goethe et Humboldt pour comprendre ce que cela veut dire.<\/p>\n<\/p>\n<p><p>Cerise ajoutait dans son livre :<\/p>\n<\/p>\n<p><p>&laquo; Le Gestell, ou la rationalisation scientifique du vivant, est l&rsquo;outil d\u00e9finitif du pouvoir politique. D\u00e8s lors que le vivant peut \u00eatre int\u00e9gralement quantifi\u00e9, num\u00e9ris\u00e9, explicit\u00e9, chosifi\u00e9, il peut devenir objet d&rsquo;une gestion s\u00e9rielle, production industrielle intrins\u00e8quement docile au pouvoir car programmable et conditionnable d\u00e8s l&rsquo;origine. L&rsquo;ing\u00e9nierie sociale culmine ainsi dans le g\u00e9nie g\u00e9n\u00e9tique (le piratage de l&rsquo;ADN), l&rsquo;eug\u00e9nisme, le clonage, les chim\u00e8res (croisements hybrides de mat\u00e9riel g\u00e9n\u00e9tique humain et animal, autoris\u00e9s au Royaume-Uni depuis mai 2007), et ultimement le transfert de la conscience dans le cyberespace. &raquo;<\/p>\n<\/p>\n<p><p>On en revient donc \u00e0 Heidegger et \u00e0 un de ses textes les plus populaires, celui sur la technique. Ecoutons l&rsquo;oracle, l&rsquo;H\u00e9raclite du si\u00e8cle dernier :<\/p>\n<\/p>\n<p><p>&laquo; Qu&rsquo;est-ce que la technique moderne? Elle aussi est un d\u00e9voilement. C&rsquo;est seulement lorsque nous arr\u00eatons notre regard sur ce trait fondamental que ce qu&rsquo;il y a de nouveau dans la technique moderne  se montre \u00e0 nous. &raquo;<\/p>\n<\/p>\n<p><p>Ce serait la fin de la nature (comme on sait Herbert Marcuse traite aussi du probl\u00e8me dans son Homme unidimensionnel, \u00e9voquant ce lac de montagne qui ne sera plus un lac mais un bassin ludique pour vacanciers motoris\u00e9s) :<\/p>\n<\/p>\n<p><p>&laquo; Le d\u00e9voilement qui r\u00e9git la technique moderne est une pro-vocation (Heraus Jordern) par laquelle la nature est mise en demeure de livrer une \u00e9nergie qui puisse comme telle \u00eatre extraite (herausgefordert) et accumul\u00e9e. Mais ne peut-on en dire autant du vieux moulin \u00e0 vent? Non : ses ailes tournent bien au vent et sont livr\u00e9es directement \u00e0 son souffle. Mais si le moulin \u00e0 vent met \u00e0 notre disposition l&rsquo;\u00e9nergie de l&rsquo;air en mouvement, ce n&rsquo;est pas pour l&rsquo;accumuler. &raquo;<\/p>\n<\/p>\n<p><p>La distinction de Heidegger entre moulin et centrale nous fait ici penser au trop oubli\u00e9 Lewis Mumford, dont nous gagnerions \u00e0 relire technique et civilisation. Ah, ce chapitre sur la pendule&hellip; Mais passons.<\/p>\n<\/p>\n<p><p>La nature est donc l\u00e0 pour \u00eatre extraite, pour produire, reli\u00e9e au syst\u00e8me, \u00e0 la croissance&hellip;<\/p>\n<\/p>\n<p><p>&laquo; Une r\u00e9gion, au contraire, est provoqu\u00e9e \u00e0 l&rsquo;extraction de charbon et de minerais. L&rsquo;\u00e9corce terrestre se d\u00e9voile aujourd&rsquo;hui comme bassin houiller, le sol comme entrep\u00f4t de minerais&hellip; &raquo;<\/p>\n<\/p>\n<p><p>On se souvient que Goethe esp\u00e9rait beaucoup du paysan. &laquo; Cet heureux temps n&rsquo;est plus &raquo;, dirait Hippolyte, car, rappelle Heidegger :<\/p>\n<\/p>\n<p><p>&laquo; Le paysan ne provoque pas la terre cultivable. Quand il s\u00e8me le grain, il confie fa semence aux forces de croissance et il veille \u00e0 ce qu&rsquo;elle prosp\u00e8re. Dans l&rsquo;intervalle, la culture des champs, elle aussi, a \u00e9t\u00e9 prise dans le mouvement aspirant d&rsquo;un mode de culture (Bestellen) d&rsquo;un autre genre, qui requiert (stellt) la nature. Il la requiert au sens de la provocation. L&rsquo;agriculture est aujourd&rsquo;hui une industrie d&rsquo;alimentation motoris\u00e9e. L&rsquo;air est requis pour la fourniture d&rsquo;azote, le sol pour celle de minerais, le minerai par exemple pour celle d&rsquo;uranium, celui-ci pour celle d&rsquo;\u00e9nergie atomique, laquelle peut \u00eatre lib\u00e9r\u00e9e pour des fins de destruction ou pour une utilisation pacifique. &raquo;<\/p>\n<\/p>\n<p><p><strong>Industrie d&rsquo;alimentation motoris\u00e9e<\/strong> : voil\u00e0 qui sonne dur \u00e0 l&rsquo;oreille. Et Heidegger \u00e9crivait avant qu&rsquo;on ne d\u00e9truise l&rsquo;Amazonie ou ce qui restait d&rsquo;Europe, le reste  \u00e9tant transform\u00e9 en parc national pour visiteur, motoris\u00e9 toujours !<\/p>\n<\/p>\n<p><p>Puis viennent les belles, les l\u00e9gendaires phrases sur le Rhin, Rhin motoris\u00e9 et condamn\u00e9 (Tolkien disait que la station-service c&rsquo;\u00e9tait le Mordor, alors&hellip;) :<\/p>\n<\/p>\n<p><p>&laquo; La centrale \u00e9lectrique est mise en place dans le Rhin. Elle le somme (stellt) de livrer sa pression hydraulique, qui somme \u00e0 son tour les turbines de tourner. Ce mouvement fait tourner la machine dont le m\u00e9canisme produit le courant \u00e9lectrique, pour lequel la centrale r\u00e9gionale et son r\u00e9seau sont commis aux fins de transmission&hellip; &raquo;<\/p>\n<\/p>\n<p><p>Heidegger poursuit sur le Rhin, jadis fleuve du po\u00e8te H\u00f6lderlin :<\/p>\n<\/p>\n<p><p>&laquo; &hellip;Le fleuve du Rhin appara&icirc;t, lui aussi, comme quelque chose de commis. La centrale n&rsquo;est pas construite dans le courant du Rhin comme le vieux pont de bois qui depuis des si\u00e8cles unit une rive \u00e0 l&rsquo;autre. C&rsquo;est bien plut\u00f4t le fleuve qui est mur\u00e9 dans la centrale. Ce qu&rsquo;il est aujourd&rsquo;hui comme fleuve, \u00e0 savoir fournisseur de pression hydraulique, il l&rsquo;est de par l&rsquo;essence de la centrale. Afin de voir et de mesurer, ne f&ucirc;t-ce que de loin, l&rsquo;\u00e9l\u00e9ment monstrueux qui domine ici, arr\u00eatons-nous un instant sur l&rsquo;opposition qui appara&icirc;t entre les deux intitul\u00e9s: &laquo; Le Rhin &raquo;, mur\u00e9 dans l&rsquo;usine d&rsquo;\u00e9nergie, et &laquo; Le Rhin &raquo;, titre de cette &oelig;uvre d&rsquo;art qu&rsquo;est un hymne de H\u00f6lderlin. Mais le Rhin, r\u00e9pondra-t-on, demeure, de toute fa\u00e7on le fleuve du paysage. Soit, mais comment le demeure-t-il? Pas autrement que comme un objet pour lequel on passe une commande (bestellbar), l&rsquo;objet d&rsquo;une visite organis\u00e9e par une agence de voyages, laquelle a constitu\u00e9 (bestellt) l\u00e0-bas une industrie des vacances. &raquo;<\/p>\n<\/p>\n<p><p>Car l&rsquo;agence de voyage industrialise le Rhin qu&rsquo;elle vend comme eau non pollu\u00e9e, bouff\u00e9e d&rsquo;air pur, voyage dans le r\u00eave, etc.<\/p>\n<\/p>\n<p><p>On termine par cette froide d\u00e9nonciation :<\/p>\n<\/p>\n<p><p>&laquo; Le d\u00e9voilement qui r\u00e9git compl\u00e8tement la technique moderne a le caract\u00e8re d&rsquo;une interpellation (Stellen) au sens d&rsquo;une provocation. &raquo;<\/p>\n<\/p>\n<p><p>Sources<\/p>\n<\/p>\n<p><p>Heidegger &ndash; la question de la technique<\/p>\n<\/p>\n<p><p>Rilke &ndash; Huiti\u00e8me \u00e9l\u00e9gie de Duino : <strong>MIT allen Augen sieht die Kreatur<\/strong><\/p>\n<\/p>\n<p><p><strong>das Offene&hellip;Dieses hei&szlig;t Schicksal: gegen\u00fcber sein<\/strong><\/p>\n<\/p>\n<p><p><strong>und nichts als das und immer gegen\u00fcber.<\/strong><\/p>\n<\/p>\n<p><p>Lucien Cerise &ndash; Gouverner par le chaos<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heidegger et la destruction du monde Dans la pens\u00e9e allemande moderne, on note une belle r\u00e9flexion nostalgique sur un pass\u00e9 grec alcyonien ou bien une vision pessimiste par rapport au progr\u00e8s. Au d\u00e9but du vingti\u00e8me si\u00e8cle, le po\u00e8te philosophe Rilke \u00e9voque dans son admirable huiti\u00e8me \u00e9l\u00e9gie cet animal qui voit dans l&rsquo;ouvert \u00e0 plein regard,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2748,2640,18680,16061,18681,13181],"class_list":["post-78301","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-allemagne","tag-bonnal","tag-cerise","tag-lucien","tag-rilke","tag-transhumanisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78301"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78301\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}