{"id":78320,"date":"2018-11-24T12:10:16","date_gmt":"2018-11-24T12:10:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2018\/11\/24\/michea-a-propos-des-gilets-jaunes\/"},"modified":"2018-11-24T12:10:16","modified_gmt":"2018-11-24T12:10:16","slug":"michea-a-propos-des-gilets-jaunes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2018\/11\/24\/michea-a-propos-des-gilets-jaunes\/","title":{"rendered":"Mich\u00e9a \u00e0 propos des gilets-jaunes"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Mich\u00e9a \u00e0 propos des gilets-jaunes<\/h2>\n<\/p>\n<p><p>Le philosophe fran\u00e7ais <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Jean-Claude_Mich%C3%A9a\">Jean-Claude Mich\u00e9a<\/a>, c&rsquo;est cet homme de gauche antiSyst\u00e8me de cette sorte exceptionnelle de droite et de gauche qui pourrait faire l&rsquo;union des antiSyst\u00e8me de gauche et de droite (il est un des auteurs favoris d&rsquo;<em><a href=\"https:\/\/collectiflieuxcommuns.fr\/?Gilets-jaunes-la-democratie-en-germe\">&Eacute;l\u00e9ments<\/a> <\/em>comme on le lit dans le <a href=\"http:\/\/www.revue-elements.com\/elements-Populisme--Michea-persiste-et-signe.html\">dernier num\u00e9ro<\/a> de cette revue). Ici, il adresse une lettre \u00e0 ses amis de <em><a href=\"https:\/\/collectiflieuxcommuns.fr\/?Gilets-jaunes-la-democratie-en-germe\">Lieux communs<\/a> <\/em>concernant une analyse de ce site du mouvement des gilets-jaunes. Il apporte son soutien \u00e0 cette analyse et pr\u00e9cise sa position.<\/p>\n<\/p>\n<p><p>Il est \u00e9vident que nous souscrivons sans gu\u00e8re d&rsquo;h\u00e9sitation aux divers points de son analyse, dont certains nous paraissent d&rsquo;un tr\u00e8s grand int\u00e9r\u00eat. La seule remarque que nous devons faire, nous qui sommes loin du champ de bataille (ou sur une de ses annexes puisqu&rsquo;il s&rsquo;av\u00e8re qu&rsquo;il y a du gilet-jaune en Wallonie, Belgique francophone), porte sur le \u00ab\u00a0climat\u00a0\u00bb, l'\u00a0\u00bbatmosph\u00e8re\u00a0\u00bb qui entoure cet \u00e9v\u00e9nement. Sans s&rsquo;attarder essentiellement \u00e0 ce point, le texte de Mich\u00e9a nous para&icirc;t d\u00e9gager une tonalit\u00e9 un peu trop pessimiste sur l&rsquo;attitude des divers cliques-Syst\u00e8me vis-\u00e0-vis des gilets-jaunes (presseSyst\u00e8me, monde politique, <em>talk-shows <\/em>permanents, etc.).<\/p>\n<\/p>\n<p><p>L&rsquo;impression que nous en recueillons, qu&rsquo;on trouve dans les textes de notre site sur le ph\u00e9nom\u00e8ne, sur \u00ab\u00a0<a href=\"http:\/\/www.dedefensa.org\/article\/resilience-de-letrange-evenement\">l&rsquo;\u00e9trange-\u00e9v\u00e9nement<\/a>\u00a0\u00bb selon PhG, c&rsquo;est une certaine confusion, une r\u00e9elle incompr\u00e9hension sinon une sid\u00e9ration, et m\u00eame une certaine bienveillance dans les r\u00e9actions d&rsquo;un certain nombre d&rsquo;institutions (y compris -Syst\u00e8me) du monde de la communication, m\u00e9dias et politique m\u00eal\u00e9s. Il ne fait aucun doute que ces attitudes, si elles existent comme nous les percevons, viennent autant de la confusion que de l&rsquo;incompr\u00e9hension, et sont explicables notamment par la puissance d&rsquo;un \u00e9v\u00e8nement qui nous d\u00e9passe tous et en \u00e9crasent certains. <\/p>\n<\/p>\n<p><p>On admettra que cette divergence, &ndash; qui tient pour notre part \u00e0 la perception que nous avons, avec toutes les r\u00e9serves qu&rsquo;on peut faire sans vraiment nous bouleverser, &ndash; est plut\u00f4t encourageante et ne concerne rien quant au fond de cette affaire. Par cons\u00e9quent, la lecture de la lettre de Mich\u00e9a est roborative et \u00e0 recommander. La lettre vient du <em>blog <\/em>dit <em>Les Amis de Bartleby<\/em>, elle est dat\u00e9e <a href=\"https:\/\/lesamisdebartleby.wordpress.com\/2018\/11\/22\/jean-claude-michea-une-lettre-a-propos-du-mouvement-des-gilets-jaunes%E2%80%89\/amp\/?__twitter_impression=true\">du 21 novembre<\/a>. <\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>______________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Une lettre \u00e0 propos des Gilets jaunes<\/h2>\n<\/p>\n<p><p>Chers Amis,<\/p>\n<\/p>\n<p><p>Juste ces quelques mots tr\u00e8s brefs et donc tr\u00e8s lapidaires &ndash; car ici, on est un peu d\u00e9bord\u00e9s par la pr\u00e9paration de l&rsquo;hiver (bois \u00e0 couper, plantes et arbres \u00e0 pailler etc.). Je suis \u00e9videmment d&rsquo;accord avec l&rsquo;ensemble de vos remarques, ainsi qu&rsquo;avec la plupart des th\u00e8ses <a href=\"https:\/\/collectiflieuxcommuns.fr\/?Gilets-jaunes-la-democratie-en-germe\">de Lieux communs<\/a>(seule la derni\u00e8re phrase me para&icirc;t un peu faible en raison de son &laquo;occidentalisme&raquo;&thinsp;: il existe aussi, bien entendu, une v\u00e9ritable culture de l&rsquo;\u00e9mancipation populaire en Asie, en Afrique ou en Am\u00e9rique latine&thinsp;!). <\/p>\n<\/p>\n<p><p>Le mouvement des &laquo;gilets jaunes&raquo; (bel exemple, au passage, de cette inventivit\u00e9 populaire que j&rsquo;annon\u00e7ais dans <em>Les Myst\u00e8res de la gauche<\/em>) est, d&rsquo;une certaine mani\u00e8re, l&rsquo;exact contraire de &laquo;Nuit Debout&raquo;. Ce dernier mouvement, en simplifiant, \u00e9tait en effet d&rsquo;abord une tentative &ndash; d&rsquo;ailleurs encourag\u00e9e par une grande partie de la presse bourgeoise &ndash; des &laquo;10%&raquo; (autrement dit, ceux qui sont pr\u00e9pos\u00e9s &ndash; ou se pr\u00e9parent \u00e0 l&rsquo;\u00eatre &ndash; \u00e0 l&rsquo;encadrement technique, politique et &laquo;culturel&raquo; du capitalisme moderne), pour d\u00e9samorcer la critique radicale du Syst\u00e8me, en dirigeant toute l&rsquo;attention politique sur le seul pouvoir (certes d\u00e9cisif) de Wall Street et des fameux &laquo;1%&raquo;. Une r\u00e9volte, par cons\u00e9quent, de ces urbains hypermobiles et surdipl\u00f4m\u00e9s (m\u00eame si une fraction minoritaire de ces nouvelles classes moyennes commence \u00e0 conna&icirc;tre, ici ou l\u00e0, une certaine &laquo;pr\u00e9carisation&raquo;) et qui constituent, depuis l&rsquo;\u00e8re Mitterrand, le principal vivier dans lequel se recrutent les cadres de la gauche et de l&rsquo;extr\u00eame gauche lib\u00e9rales (et, notamment, de ses secteurs les plus ouvertement contre-r\u00e9volutionnaires et antipopulaires&thinsp;: <em>Regards, Politis,<\/em> NP\u00a0\u00bbA\u00a0\u00bb, Universit\u00e9 Paris VIII, etc.). Ici, au contraire, ce sont bien ceux d&rsquo;en bas (tels que les analysait Christophe Guilluy &ndash; d&rsquo;ailleurs curieusement absent, jusqu&rsquo;ici, de tous les talk-shows t\u00e9l\u00e9vis\u00e9s, au profit, entre autres comiques, du r\u00e9formiste sous-keyn\u00e9sien Besancenot), qui se r\u00e9voltent, avec d\u00e9j\u00e0 suffisamment de conscience r\u00e9volutionnaire pour refuser d&rsquo;avoir encore \u00e0 choisir entre exploiteurs de gauche et exploiteurs de droite (c&rsquo;est d&rsquo;ailleurs ainsi que Podemos avait commenc\u00e9 en 2011, avant que les Cl\u00e9mentine Autain et les Beno&icirc;t Hamon du cru ne r\u00e9ussissent \u00e0 enterrer ce mouvement prometteur en le coupant progressivement de ses bases populaires). <\/p>\n<\/p>\n<p><p>Quant \u00e0 l&rsquo;argument des &laquo;\u00e9cologistes&raquo; de cour &ndash; ceux qui pr\u00e9parent cette &laquo;transition \u00e9nerg\u00e9tique&raquo; qui consiste avant tout, comme Guillaume Pitron l&rsquo;a bien montr\u00e9 dans <em>La Guerre des m\u00e9taux rares, <\/em>\u00e0 <em>d\u00e9localiser la pollution des pays occidentaux dans les pays du Sud, <\/em>selon lequel ce mouvement spontan\u00e9 ne serait port\u00e9 que par &laquo;une id\u00e9ologie de la bagnole&raquo; et par &laquo;des gars qui fument des clopes et roulent en diesel&raquo;, il est aussi absurde qu&rsquo;immonde&thinsp;: il est clair, en effet, que la plupart des Gilets jaunes n&rsquo;\u00e9prouvent aucun plaisir \u00e0 devoir prendre leur voiture pour aller travailler chaque jour \u00e0 50 km de chez eux, \u00e0 aller faire leurs courses au seul centre commercial existant dans leur r\u00e9gion et g\u00e9n\u00e9ralement situ\u00e9 en pleine nature \u00e0 20 km, ou encore \u00e0 se rendre chez le seul m\u00e9decin qui n&rsquo;a pas encore pris sa retraite et dont le cabinet se trouve \u00e0 10 km de leur lieu d&rsquo;habitation. (J&#8217;emprunte tous ces exemples \u00e0 mon exp\u00e9rience landaise&thinsp;! J&rsquo;ai m\u00eame un voisin, qui vit avec 600 &euro; par mois et qui doit calculer le jour du mois o&ugrave; il peut encore aller faire ses courses \u00e0 Mont-de-Marsan, sans tomber en panne, en fonction de la quantit\u00e9 de diesel &ndash; cette essence des pauvres &ndash; qu&rsquo;il a encore les moyens de s&rsquo;acheter&thinsp;!) Gageons qu&rsquo;ils sont au contraire les premiers \u00e0 avoir compris que le vrai probl\u00e8me, c&rsquo;\u00e9tait justement que la mise en &oelig;uvre syst\u00e9matique, depuis maintenant 40 ans, du programme lib\u00e9ral par les successifs gouvernements de gauche et de droite, a progressivement transform\u00e9 leur village ou leur quartier en d\u00e9sert m\u00e9dical, d\u00e9pourvu du moindre commerce de premi\u00e8re n\u00e9cessit\u00e9, et o&ugrave; la premi\u00e8re entreprise encore capable de leur offrir un vague emploi mal r\u00e9mun\u00e9r\u00e9 se trouve d\u00e9sormais \u00e0 des dizaines de kilom\u00e8tres (s&rsquo;il existe des &laquo;plans banlieues&raquo; &ndash; et c&rsquo;est tant mieux &ndash; il n&rsquo;y a \u00e9videmment jamais eu rien de tel pour ces villages et ces communes &ndash; o&ugrave; vit pourtant la majorit\u00e9 de la population fran\u00e7aise &ndash; officiellement promis \u00e0 l&rsquo;extinction par le &laquo;sens de l&rsquo;histoire&raquo; et la &laquo;construction europ\u00e9enne&raquo; !). <\/p>\n<\/p>\n<p><p>Ce n&rsquo;est donc \u00e9videmment pas la voiture en tant que telle &ndash; comme &laquo; signe &raquo; de leur pr\u00e9tendue int\u00e9gration dans le monde de la consommation (ce ne sont pas des Lyonnais ou des Parisiens !) &ndash; que les Gilets jaunes d\u00e9fendent aujourd&rsquo;hui. C&rsquo;est simplement que leur voiture diesel achet\u00e9e d&rsquo;occasion (et que la Commission europ\u00e9enne essaye d\u00e9j\u00e0 de leur enlever en inventant sans cesse de nouvelles normes de &laquo; contr\u00f4le technique &raquo;) repr\u00e9sente leur ultime possibilit\u00e9 de survivre, c&rsquo;est-\u00e0-dire d&rsquo;avoir encore un toit, un emploi et de quoi se nourrir, eux et leur famille, dans le syst\u00e8me capitaliste tel qu&rsquo;il est devenu, et tel qu&rsquo;il profite de plus en plus aux gagnants de la mondialisation. Et dire que c&rsquo;est d&rsquo;abord cette <em>gauche k\u00e9ros\u00e8ne<\/em> &ndash; celle qui navigue d&rsquo;a\u00e9roport en a\u00e9roport pour porter dans les universit\u00e9s du monde entier (et dans tous les &laquo;Festival de Cannes&raquo;) la bonne parole &laquo;\u00e9cologique&raquo; et &laquo;associative&raquo; qui ose leur faire la le\u00e7on sur ce point ! D\u00e9cid\u00e9ment, ceux qui ne connaissent rien d&rsquo;autre que leurs pauvres palais m\u00e9tropolitains n&rsquo;auront jamais le centi\u00e8me de la d\u00e9cence qu&rsquo;on peut encore rencontrer dans les chaumi\u00e8res (et l\u00e0 encore, c&rsquo;est mon exp\u00e9rience landaise qui parle !).<\/p>\n<\/p>\n<p><p>La seule question que je me pose est donc de savoir jusqu&rsquo;o&ugrave; un tel mouvement r\u00e9volutionnaire (mouvement qui n&rsquo;est pas sans rapport, dans sa naissance, son programme rassembleur et son mode de d\u00e9veloppement, avec la grande r\u00e9volte du Midi de 1907) peut aller dans les tristes conditions politiques qui sont les n\u00f4tres. Car n&rsquo;oublions pas qu&rsquo;il a devant lui un gouvernement thatch\u00e9rien de gauche (le principal conseiller de Macron est d&rsquo;ailleurs Mathieu Laine &ndash; un homme d&rsquo;affaires de la City de Londres et qui est, en France, le pr\u00e9facier des &oelig;uvres de la sorci\u00e8re Maggie), c&rsquo;est-\u00e0-dire un gouvernement cynique et impavide, qui est clairement pr\u00eat &ndash; c&rsquo;est sa grande diff\u00e9rence avec tous ses pr\u00e9d\u00e9cesseurs &ndash; \u00e0 aller jusqu&rsquo;aux pires extr\u00e9mit\u00e9s pinochetistes (comme Maggie avec les mineurs gallois ou les gr\u00e9vistes de la faim irlandais) pour imposer sa &laquo;soci\u00e9t\u00e9 de croissance &raquo; et ce pouvoir antid\u00e9mocratique des juges, aujourd&rsquo;hui triomphant, qui en est le corollaire oblig\u00e9. Et, bien s&ucirc;r, sans avoir quoi que ce soit \u00e0 craindre, sur ce plan, du servile personnel m\u00e9diatique fran\u00e7ais. Faut-il rappeler, en effet, qu&rsquo;on compte d\u00e9j\u00e0 <em>3 morts,<\/em> des centaines de bless\u00e9s, dont certains dans un \u00e9tat tr\u00e8s critique. Or, si ma m\u00e9moire est bonne, c&rsquo;est bien \u00e0 Mai 68 qu&rsquo;il faut remonter pour retrouver un bilan humain comparable lors de manifestations populaires, du moins sur le sol m\u00e9tropolitain. Et pour autant, l&rsquo;\u00e9cho m\u00e9diatique donn\u00e9 \u00e0 ce fait effarant est-il, du moins pour l&rsquo;instant, \u00e0 la hauteur d&rsquo;un tel drame ? Et qu&rsquo;auraient d&rsquo;ailleurs dit les chiens de garde de France Info si ce bilan (provisoire) avait \u00e9t\u00e9 l&rsquo;&oelig;uvre, par exemple, d&rsquo;un Vladimir Poutine ou d&rsquo;un Donald Trump&thinsp;? <\/p>\n<\/p>\n<p><p>Enfin, <em>last but not the least,<\/em> on ne doit surtout pas oublier que si le mouvement des Gilets jaunes gagnait encore de l&rsquo;ampleur (ou s&rsquo;il conservait, comme c&rsquo;est toujours le cas, le soutien de la grande majorit\u00e9 de la population), l&rsquo;&Eacute;tat benallo-macronien n&rsquo;h\u00e9sitera pas un seul instant \u00e0 envoyer partout son <em>Black Bloc <\/em>et ses &laquo; <em>antifas<\/em> &raquo; (telle la fameuse &laquo; brigade rouge &raquo; de la grande \u00e9poque) pour le discr\u00e9diter par tous les moyens, ou l&rsquo;orienter vers des impasses politiques suicidaires (on a d\u00e9j\u00e0 vu, par exemple, comment l&rsquo;&Eacute;tat macronien avait proc\u00e9d\u00e9 pour couper en tr\u00e8s peu de temps l&rsquo;exp\u00e9rience zadiste de Notre-Dame-des-Landes de ses soutiens populaires originels). Mais m\u00eame si ce courageux mouvement se voyait provisoirement bris\u00e9 par le PMA &ndash; le Parti des m\u00e9dias et de l&rsquo;argent (<em>PMA pour tous<\/em>, telle est, en somme, la devise de nos M. Thiers d&rsquo;aujourd&rsquo;hui !), cela voudra dire, au pire, qu&rsquo;il n&rsquo;est qu&rsquo;une r\u00e9p\u00e9tition g\u00e9n\u00e9rale et le d\u00e9but d&rsquo;un long combat \u00e0 venir. Car la col\u00e8re de ceux d&rsquo;en bas (soutenus, je dois \u00e0 nouveau le marteler, par 75% de la population &ndash; et donc logiquement stigmatis\u00e9, \u00e0 ce titre, par 95% des chiens de garde m\u00e9diatiques) ne retombera plus, tout simplement parce que ceux d&rsquo;en bas n&rsquo;en peuvent plus et ne veulent plus. Le peuple est donc d\u00e9finitivement en marche ! Et \u00e0 moins d&rsquo;en \u00e9lire un autre (selon le v&oelig;u d&rsquo;&Eacute;ric Fassin, cet agent d&rsquo;influence particuli\u00e8rement actif de la trop c\u00e9l\u00e8bre <em>French American Fondation<\/em>), il n&rsquo;est pas pr\u00e8s de rentrer dans le rang. Que les Versaillais de gauche et de droite (pour reprendre la formule des proscrits de la Commune r\u00e9fugi\u00e9s \u00e0 Londres) se le tiennent pour dit !<\/p>\n<\/p>\n<p><p>Tr\u00e8s amicalement,<\/p>\n<\/p>\n<p><h4>Jean-Claude Mich\u00e9a<\/h4><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mich\u00e9a \u00e0 propos des gilets-jaunes Le philosophe fran\u00e7ais Jean-Claude Mich\u00e9a, c&rsquo;est cet homme de gauche antiSyst\u00e8me de cette sorte exceptionnelle de droite et de gauche qui pourrait faire l&rsquo;union des antiSyst\u00e8me de gauche et de droite (il est un des auteurs favoris d&rsquo;&Eacute;l\u00e9ments comme on le lit dans le dernier num\u00e9ro de cette revue). Ici,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[4646,18713,14212,3186,18697,5425,18712],"class_list":["post-78320","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-antisysteme","tag-debout","tag-elements","tag-gauche","tag-gilets-jaune","tag-jaune","tag-nuits"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78320"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78320\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}