{"id":78411,"date":"2019-01-14T06:32:41","date_gmt":"2019-01-14T06:32:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/01\/14\/marx-la-republique-et-son-regne-des-banquiers\/"},"modified":"2019-01-14T06:32:41","modified_gmt":"2019-01-14T06:32:41","slug":"marx-la-republique-et-son-regne-des-banquiers","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/01\/14\/marx-la-republique-et-son-regne-des-banquiers\/","title":{"rendered":"Marx, la r\u00e9publique et son r\u00e8gne des banquiers"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Marx, la r\u00e9publique et son r\u00e8gne des banquiers<\/h2>\n<\/p>\n<p><p>Oh, ce pr\u00e9sent permanent : alors que l&rsquo;\u00e9lite mondialis\u00e9e \u00e9crase en France le peuple sous son talon de fer au nom de la r\u00e9publique, du lib\u00e9ralisme et des banquiers &ndash; surtout des banquiers -, j&rsquo;invite \u00e0 relire le bel essai de Marx sur la Lutte des classes en France, qui r\u00e9conciliera un peu plus populistes de droite et de gauche. La sc\u00e8ne se passe dans les ann\u00e9es 1840 puis sous la seconde r\u00e9publique. On commence : <\/p>\n<\/p>\n<p><p>&laquo; Apr\u00e8s la r\u00e9volution de Juillet, lorsque le banquier lib\u00e9ral Laffitte conduisit en triomphe son comp\u00e8re le duc d&rsquo;Orl\u00e9ans \u00e0 l&rsquo;H\u00f4tel de ville, il laissa \u00e9chapper ces mots : &laquo; Maintenant, le r\u00e8gne des banquiers va commencer. &raquo; Laffitte venait de trahir le secret de la r\u00e9volution. &raquo;<\/p>\n<\/p>\n<p><p>Et c&rsquo;\u00e9tait en 1830&hellip; Apr\u00e8s, c&rsquo;est le r\u00e8gne prototypique de Louis-Philippe&hellip; Marx :<\/p>\n<\/p>\n<p><p>&laquo; Ce n&rsquo;est pas la bourgeoisie fran\u00e7aise qui r\u00e9gnait sous Louis-Philippe, mais une fraction de celle-ci : banquiers, rois de la Bourse, rois des chemins de fer, propri\u00e9taires de mines de charbon et de fer, propri\u00e9taires de for\u00eats et la partie de la propri\u00e9t\u00e9 fonci\u00e8re ralli\u00e9e \u00e0 eux, ce que l&rsquo;on appelle l&rsquo;aristocratie financi\u00e8re. Install\u00e9e sur le tr\u00f4ne, elle dictait les lois aux Chambres, distribuait les charges publiques, depuis les minist\u00e8res jusqu&rsquo;aux bureaux de tabac. &raquo;<\/p>\n<\/p>\n<p><p>On se croirait sous Jospin-DSK, Sarkozy-Jupp\u00e9, au moment des grandes privatisations qui marqu\u00e8rent cette Restauration dont a parl\u00e9 Pierre Bourdieu. On continue sur les innombrables malversations de cette \u00e9poque qui inspira ses Mis\u00e9rables \u00e0 Victor Hugo :<\/p>\n<\/p>\n<p><p>&laquo; En outre, les sommes \u00e9normes passant ainsi entre les mains de l&rsquo;&Eacute;tat laissaient place \u00e0 des contrats de livraison frauduleux, \u00e0 des corruptions, \u00e0 des malversations et \u00e0 des escroqueries de toute esp\u00e8ce. <strong>Le pillage de l&rsquo;&Eacute;tat en grand, tel qu&rsquo;il se pratiquait au moyen des emprunts, se renouvelait en d\u00e9tail dans les travaux publics. <\/strong>Les relations entre la Chambre et le gouvernement se trouvaient multipli\u00e9es sous forme de relations entre les diff\u00e9rentes administrations et les diff\u00e9rents entrepreneurs.<\/p>\n<\/p>\n<p><p><strong>De m\u00eame que les d\u00e9penses publiques en g\u00e9n\u00e9ral et les emprunts publics, la classe dominante exploitait aussi les constructions de lignes de chemin de fer. &raquo;<\/strong><\/p>\n<\/p>\n<p><p>On comprend nos travaux et infrastructures&hellip;Tiens, Karl Marx parle de Rothschild, ce compte fait baron :<\/p>\n<\/p>\n<p><p>&laquo; Par contre, la moindre r\u00e9forme financi\u00e8re \u00e9chouait devant l&rsquo;influence des banquiers, telle, par exemple, la r\u00e9forme postale. <strong>Rothschild protesta, l&rsquo;&Eacute;tat avait-il le droit d&rsquo;amoindrir des sources de revenu qui lui servaient \u00e0 payer les int\u00e9r\u00eats de sa dette sans cesse croissante? &raquo;<\/strong><\/p>\n<\/p>\n<p><p>On parle souvent des 1% qui contr\u00f4lent ce pays. Du temps de Marx ils sont d\u00e9j\u00e0 l\u00e0 :<\/p>\n<\/p>\n<p><p>&laquo; <strong>La monarchie de Juillet n&rsquo;\u00e9tait qu&rsquo;une soci\u00e9t\u00e9 par actions fond\u00e9e pour l&rsquo;exploitation de la richesse nationale fran\u00e7aise dont les dividendes \u00e9taient partag\u00e9s entre les ministres, les Chambres, 240 000 \u00e9lecteurs et leur s\u00e9quelle. Louis-Philippe \u00e9tait le directeur de cette soci\u00e9t\u00e9 : Robert Macaire sur le tr\u00f4ne. <\/strong>Le commerce, l&rsquo;industrie, l&rsquo;agriculture, la navigation, les int\u00e9r\u00eats de la bourgeoisie industrielle ne pouvaient \u00eatre que menac\u00e9s et l\u00e9s\u00e9s sans cesse par ce syst\u00e8me. Aussi, celle-ci avait-elle inscrit sur son drapeau, pendant les journ\u00e9es de Juillet : Gouvernement \u00e0 bon march\u00e9. &raquo;<\/p>\n<\/p>\n<p><p>La crapulerie immorale se d\u00e9cha&icirc;ne, c&rsquo;est la boh\u00eame double V et le lumpenprol\u00e9tariat aux commandes, toute la descente aux affaires (on ne citera pas nos scandales&hellip;) :<\/p>\n<\/p>\n<p><p>&laquo; C&rsquo;est notamment aux sommets de la soci\u00e9t\u00e9 bourgeoise que l&rsquo;assouvissement des convoitises les plus malsaines et les plus d\u00e9r\u00e9gl\u00e9es se d\u00e9cha&icirc;nait, et entrait \u00e0 chaque instant en conflit avec les lois bourgeoises elles-m\u00eames, car c&rsquo;est l\u00e0 o&ugrave; la jouissance devient crapuleuse, l\u00e0 o&ugrave; l&rsquo;or, la boue et le sang s&rsquo;entrem\u00ealent que tout naturellement la richesse provenant du jeu cherche sa satisfaction.<strong>L&rsquo;aristocratie financi\u00e8re, dans son mode de gain comme dans ses jouissances, n&rsquo;est pas autre chose que la r\u00e9surrection du lumpenprol\u00e9tariat dans les sommets de la soci\u00e9t\u00e9 bourgeoise. &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Depuis la &laquo; crise &raquo; de 2008 nous sommes recouverts de dette, comme tous nos voisins europ\u00e9ens &ndash; et du coup bien soumis. La dette est la base de ce type de gouvernement. Marx :<\/p>\n<\/p>\n<p><p><strong>&laquo; L&rsquo;endettement de l&rsquo;&Eacute;tat \u00e9tait, bien au contraire, d&rsquo;un int\u00e9r\u00eat direct pour la fraction de la bourgeoisie qui gouvernait<\/strong>et l\u00e9gif\u00e9rait au moyen des Chambres. C&rsquo;\u00e9tait pr\u00e9cis\u00e9ment le d\u00e9ficit de l&rsquo;&Eacute;tat, qui \u00e9tait l&rsquo;objet m\u00eame de ses sp\u00e9culations et le poste principal de son enrichissement. A la fin de chaque ann\u00e9e, nouveau d\u00e9ficit. Au bout de quatre ou cinq ans, nouvel emprunt. <strong>Or, chaque nouvel emprunt fournissait \u00e0 l&rsquo;aristocratie une nouvelle occasion de ran\u00e7onner l&rsquo;&Eacute;tat, qui, maintenu artificiellement au bord de la banqueroute, \u00e9tait oblig\u00e9 de traiter avec les banquiers dans les conditions les plus d\u00e9favorables<\/strong>. Chaque nouvel emprunt \u00e9tait une nouvelle occasion, de d\u00e9valiser le public qui place ses capitaux en rentes sur l&rsquo;&Eacute;tat, au moyen d&rsquo;op\u00e9rations de Bourse, au secret desquelles gouvernement et majorit\u00e9 de la Chambre \u00e9taient initi\u00e9s. &raquo;<\/p>\n<\/p>\n<p><p>Puis Marx se d\u00e9foule d&rsquo;une mani\u00e8re qui le m\u00e8nerait l\u00e9gitimement en prison de nos jours :<\/p>\n<\/p>\n<p><p>&laquo; La bourgeoisie industrielle voyait ses int\u00e9r\u00eats menac\u00e9s, la petite bourgeoisie \u00e9tait moralement indign\u00e9e, l&rsquo;imagination populaire s&rsquo;insurgeait, Paris \u00e9tait inond\u00e9 de pamphlets : &laquo; La dynastie Rothschild &raquo; &laquo; Les Juifs, rois de l&rsquo;\u00e9poque &raquo;, etc., o&ugrave; l&rsquo;on d\u00e9non\u00e7ait, fl\u00e9trissait avec plus ou moins d&rsquo;esprit, la domination de l&rsquo;aristocratie financi\u00e8re. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;auteur ajoute :<\/p>\n<\/p>\n<p><p>&laquo; Rien pour la gloire! La paix partout et toujours La guerre fait baisser le cours du 3 et du 4 %. Voil\u00e0 ce qu&rsquo;avait \u00e9crit sur son drapeau la France des Juifs de la Bourse.<strong>Aussi, sa politique \u00e9trang\u00e8re sombra-t-elle dans une s\u00e9rie d&rsquo;humiliations du sentiment national fran\u00e7ais&hellip; &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Oui, la diplomatie de Louis-Philippe fut une honte. Mais ne parlons pas de celle du successeur Bonaparte (Crim\u00e9e et ch\u00e2timent, Chine-Indochine, puis Mexique et enfin Sedan)&hellip;<\/p>\n<\/p>\n<p><p>Le pouvoir aux abois invoque toujours la r\u00e9publique en France. Mais pour Marx la r\u00e9publique est surtout un gouvernement de bourgeois au profit des plus riches ; il note :<\/p>\n<\/p>\n<p><p>&laquo; La R\u00e9publique ne rencontra aucune r\u00e9sistance pas plus au dehors qu&rsquo;au dedans. C&rsquo;est ce qui la d\u00e9sarma. <strong>Sa t\u00e2che ne fut plus de transformer r\u00e9volutionnairement le monde; elle ne consista plus qu&rsquo;\u00e0 s&rsquo;adapter aux conditions de la soci\u00e9t\u00e9 bourgeoise.<\/strong>Rien ne t\u00e9moigne plus \u00e9loquemment du fanatisme avec lequel le Gouvernement provisoire s&#8217;employa \u00e0 cette t\u00e2che que les mesures financi\u00e8res prises par lui. &raquo;<\/p>\n<\/p>\n<p><p>La r\u00e9publique aurait d&ucirc; r\u00e9agir contre les banquiers et les financiers. Marx :<\/p>\n<\/p>\n<p><p>&laquo; Le cr\u00e9dit public et le cr\u00e9dit priv\u00e9 \u00e9taient naturellement \u00e9branl\u00e9s. Le cr\u00e9dit public repose sur la croyance que l&rsquo;&Eacute;tat se laisse exploiter par les Juifs de la Finance. <strong>Mais l&rsquo;ancien &Eacute;tat avait disparu et la r\u00e9volution \u00e9tait dirig\u00e9e avant tout contre l&rsquo;aristocratie financi\u00e8re. <\/strong>Les oscillations de la derni\u00e8re crise commerciale en Europe n&rsquo;avaient pas encore cess\u00e9. Les banqueroutes succ\u00e9daient encore aux banqueroutes. &raquo;<\/p>\n<\/p>\n<p><p>Bien entendu l&rsquo;\u00e9pargnant de cette \u00e9poque est destin\u00e9 \u00e0 \u00eatre plum\u00e9 :<\/p>\n<\/p>\n<p><p>&laquo; Le petit bourgeois, d\u00e9j\u00e0 bien assez r\u00e9duit \u00e0 la mis\u00e8re, en fut irrit\u00e9 contre la R\u00e9publique. Ayant re\u00e7u \u00e0 la place de son livret de caisse d&rsquo;\u00e9pargne, des bons du Tr\u00e9sor, il fut contraint d&rsquo;aller les vendre \u00e0 la Bourse et de se livrer ainsi directement aux mains des Juifs de la Bourse contre lesquels il avait fait la r\u00e9volution de F\u00e9vrier. &raquo;<\/p>\n<\/p>\n<p><p>L&rsquo;argent est divinis\u00e9 (ce que C\u00e9line arriv\u00e9 \u00e0 New York remarquera) :<\/p>\n<\/p>\n<p><p>&laquo; L&rsquo;aristocratie financi\u00e8re qui r\u00e9gnait sous la monarchie de Juillet avait dans la Banque son &Eacute;glise \u00e9piscopale. De m\u00eame que la Bourse r\u00e9git le cr\u00e9dit public, la Banque gouverne le cr\u00e9dit commercial. Directement menac\u00e9e par la r\u00e9volution de F\u00e9vrier, non seulement dans sa domination, mais dans son existence, la Banque s&rsquo;appliqua, d\u00e8s le d\u00e9but, \u00e0 discr\u00e9diter la R\u00e9publique en g\u00e9n\u00e9ralisant la fermeture du cr\u00e9dit. &raquo;<\/p>\n<\/p>\n<p><p>Le gouvernement r\u00e9publicain loin de soumettre la banque s&rsquo;y soumet gentiment (comme en 2008 &ndash; voyez Lucien Cerise) :<\/p>\n<\/p>\n<p><p>&laquo; Le Gouvernement provisoire pouvait, sans recourir \u00e0 la violence de fa\u00e7on l\u00e9gale, acculer la Banque \u00e0 la banqueroute; il n&rsquo;avait qu&rsquo;\u00e0 observer une attitude passive et \u00e0 abandonner la Banque \u00e0 son propre sort. La banqueroute de la Banque, c&rsquo;\u00e9tait le d\u00e9luge balayant en un clin d&rsquo;&oelig;il du sol fran\u00e7ais l&rsquo;aristocratie financi\u00e8re, le plus puissant et le plus dangereux ennemi de la R\u00e9publique, le pi\u00e9destal d&rsquo;or de la monarchie de Juillet. Une fois la Banque en faillite, la bourgeoisie \u00e9tait oblig\u00e9e de consid\u00e9rer elle-m\u00eame comme une derni\u00e8re tentative de sauvetage d\u00e9sesp\u00e9r\u00e9e la cr\u00e9ation par le gouvernement d&rsquo;une banque nationale et la subordination du cr\u00e9dit national au contr\u00f4le de la nation. &raquo;<\/p>\n<\/p>\n<p><p>Mais le gouvernement provisoire dirig\u00e9 par l&rsquo;\u00e2non Lamartine choisit la voie contraire. On commence \u00e0 brader la France :<\/p>\n<\/p>\n<p><p>&laquo; Le Gouvernement provisoire, au contraire, donna cours forc\u00e9 aux billets de banque. Il fit mieux. Il transforma toutes les banques de province en succursales de la Banque de France, lui permettant de jeter son r\u00e9seau sur le pays tout entier. Plus tard, il engagea aupr\u00e8s d&rsquo;elle les for\u00eats domaniales en garantie de l&#8217;emprunt qu&rsquo;il contracta envers elle. C&rsquo;est ainsi que la r\u00e9volution de F\u00e9vrier consolida et \u00e9largit directement la bancocratie qu&rsquo;elle devait renverser. &raquo;<\/p>\n<\/p>\n<p><p>Puis on choisira Fould comme ministre des finances :<\/p>\n<\/p>\n<p><p>&laquo; Louis-Philippe n&rsquo;avait jamais os\u00e9 faire d&rsquo;un v\u00e9ritable loup-cervier un ministre des Finances. De m\u00eame que sa royaut\u00e9 \u00e9tait le nom id\u00e9al pour la domination de la haute bourgeoisie, les int\u00e9r\u00eats privil\u00e9gi\u00e9s devaient dans ses minist\u00e8res porter des noms d&rsquo;une id\u00e9ologie d\u00e9sint\u00e9ress\u00e9e. <strong>La R\u00e9publique bourgeoise poussa partout au premier plan ce que les diverses monarchies, l\u00e9gitimiste comme orl\u00e9aniste, tenaient cach\u00e9 \u00e0 l&rsquo;arri\u00e8re-plan. Elle fit descendre sur la terre ce que celles-ci avaient divinis\u00e9.<\/strong>Elle mit les noms propres bourgeois des int\u00e9r\u00eats de classe dominants \u00e0 la place de leurs noms de saints. &raquo;<\/p>\n<\/p>\n<p><p>Conclusion \u00e0 graver dans les c&oelig;urs quand on vous parle de r\u00e9v\u00e9rer, diviniser et prot\u00e9ger la r\u00e9publique dans la guerre et le sang :<\/p>\n<\/p>\n<p><p>&laquo; <strong>Toute notre exposition a montr\u00e9 que la R\u00e9publique, d\u00e8s le premier jour de son existence, n&rsquo;a pas renvers\u00e9, mais, au contraire, constitu\u00e9 l&rsquo;aristocratie financi\u00e8re.<\/strong>Mais les concessions qu&rsquo;on lui faisait \u00e9taient un destin auquel on se soumettait sans qu&rsquo;on veuille le faire na&icirc;tre. Avec Fould, l&rsquo;initiative gouvernementale revint \u00e0 l&rsquo;aristocratie financi\u00e8re. &raquo;<\/p>\n<\/p>\n<p><p>Avec ces gars de la bourse, la dette explose. Marx encore :<\/p>\n<\/p>\n<p><p>&laquo; Donc, sans bouleversement complet de l&rsquo;&Eacute;tat fran\u00e7ais, pas de bouleversement du budget public fran\u00e7ais. <strong>Avec ce budget public, n\u00e9cessit\u00e9 de l&rsquo;endettement de l&rsquo;&Eacute;tat, et, avec l&rsquo;endettement de l&rsquo;&Eacute;tat, n\u00e9cessit\u00e9 de la domination du commerce, des dettes publiques, des cr\u00e9anciers de l&rsquo;&Eacute;tat, des banquiers, des marchands d&rsquo;argent, des loups-cerviers. <\/strong>Une fraction seulement du parti de l&rsquo;ordre participait directement au renversement de l&rsquo;aristocratie financi\u00e8re : les fabricants. &raquo;<\/p>\n<\/p>\n<p><p>Les bonnes vieilles m\u00e9thodes de notre pr\u00e9sent permanent :<\/p>\n<\/p>\n<p><p>&laquo; Sous Fould, l&rsquo;aristocratie financi\u00e8re, \u00e0 c\u00f4t\u00e9 des autres fractions bourgeoises qui la jalousaient, n&rsquo;\u00e9tala point, naturellement, autant de corruption cynique que sous Louis-Philippe. Mais, d&rsquo;abord, le syst\u00e8me restait le m\u00eame, augmentation constante des dettes, dissimulation du d\u00e9ficit. <strong>Puis, avec le temps, l&rsquo;escroquerie boursi\u00e8re d&rsquo;autrefois se manifesta avec plus de cynisme. <\/strong>&raquo;<\/p>\n<\/p>\n<p><p>Mais Marx parle aussi du peuple \u00e9crabouill\u00e9 d&rsquo;imp\u00f4ts alors que le riche passe au travers :<\/p>\n<\/p>\n<p><p>&laquo; Le paysan, lorsqu&rsquo;il \u00e9voque le diable, lui donne les traits du porteur de contrainte. <strong>D\u00e8s le moment o&ugrave; Montalembert fit de l&rsquo;imp\u00f4t un dieu, le paysan devint impie, ath\u00e9e et se jeta dans les bras du diable, du socialisme.<\/strong>La religion de l&rsquo;ordre s&rsquo;\u00e9tait moqu\u00e9e de lui, les j\u00e9suites s&rsquo;\u00e9taient moqu\u00e9s de lui, Bonaparte s&rsquo;\u00e9tait moqu\u00e9 de lui. &raquo;<\/p>\n<\/p>\n<p><p>Marx ajoute encore sur le fisc fran\u00e7ais :<\/p>\n<\/p>\n<p><p><strong>&laquo; La haine populaire contre l&rsquo;imp\u00f4t sur les boissons s&rsquo;explique par le fait qu&rsquo;il r\u00e9unit en lui tous les c\u00f4t\u00e9s odieux du syst\u00e8me fiscal fran\u00e7ais.<\/strong>Son mode de perception est odieux, son mode de r\u00e9partition est aristocratique, car, les pourcentages d&rsquo;imp\u00f4t \u00e9tant les m\u00eames pour les vins les plus ordinaires et pour les plus fins, <strong>il augmente donc en proportion g\u00e9om\u00e9trique dans la mesure o&ugrave; diminue la fortune des consommateurs, c&rsquo;est un imp\u00f4t progressif \u00e0 rebours. &raquo;<\/strong><\/p>\n<\/p>\n<p><p>Et que faire pour calmer tous ces m\u00e9contents ? Les mitrailler, car, comme dit Flaubert dans son Dictionnaire des id\u00e9es re\u00e7ues, c&rsquo;est le seul moyen de faire taire des ouvriers&hellip; <\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Sources <\/h2>\n<\/p>\n<p><p>Marx, <em><a href=\"http:\/\/classiques.uqac.ca\/classiques\/Marx_karl\/luttes_de_classes_france\/luttes_classes_france.pdf\">Luttes des classes en France<\/a><\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marx, la r\u00e9publique et son r\u00e8gne des banquiers Oh, ce pr\u00e9sent permanent : alors que l&rsquo;\u00e9lite mondialis\u00e9e \u00e9crase en France le peuple sous son talon de fer au nom de la r\u00e9publique, du lib\u00e9ralisme et des banquiers &ndash; surtout des banquiers -, j&rsquo;invite \u00e0 relire le bel essai de Marx sur la Lutte des classes&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[27],"tags":[2640,18347,18802,3716,15202],"class_list":["post-78411","post","type-post","status-publish","format-standard","hentry","category-les-carnets-de-nicolas-bonnal-1","tag-bonnal","tag-bourgeoisie","tag-proletariat","tag-siecle","tag-xixeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78411"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78411\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}