{"id":78422,"date":"2019-01-20T15:36:11","date_gmt":"2019-01-20T15:36:11","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/01\/20\/des-lgtbq-a-gabbard-une-feconde-agitation\/"},"modified":"2019-01-20T15:36:11","modified_gmt":"2019-01-20T15:36:11","slug":"des-lgtbq-a-gabbard-une-feconde-agitation","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/01\/20\/des-lgtbq-a-gabbard-une-feconde-agitation\/","title":{"rendered":"Des LGTBQ \u00e0 Gabbard, une f\u00e9conde agitation"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Des LGTBQ \u00e0 Gabbard, une f\u00e9conde agitation<\/h2>\n<\/p>\n<p><p>On a vu hier, avec le cas de Chris Hedges <a href=\"http:\/\/www.dedefensa.org\/article\/le-dilemme-barnum-trump\">face \u00e0 Barnum-Trump<\/a>, les contradictions consid\u00e9rables de la gauche qui s&rsquo;affiche antiSyst\u00e8me, par rapport aux activit\u00e9s et aux choix du Syst\u00e8me. (Le cas de Hedges est celui des USA mais le processus est largement partag\u00e9, &ndash; globalisation oblige, &ndash; par les gauches des pays du bloc-BAO.) Ces contradictions apparaissent en pleine lumi\u00e8re <strong>au c&oelig;ur de la n\u00e9buleuse LGTBQ-\u00e9largie US, regroupant tous les mouvements soci\u00e9taux et communautaristes <\/strong>(f\u00e9minisme, antiracisme, anti-antis\u00e9mitisme, multiculturalisme, homosexualit\u00e9, transgenrisme, etc.) pr\u00e9tendant lutter contre l&rsquo;ordre \u00e9tabli, et \u00e9ventuellement contre le Syst\u00e8me pouyr l&rsquo;affichage (r\u00e9f\u00e9rence antiSyst\u00e8me). <\/p>\n<\/p>\n<p><p>Selon cette logique d\u00e9vastatrice et autodestructrice, <strong>une cassure tr\u00e8s grave est mise \u00e0 jour avec la <em>Women&rsquo;s March<\/em> de Washington D.C.<\/strong>, version 2019 d&rsquo;un \u00e9v\u00e9nement embl\u00e9matique et consid\u00e9rable du f\u00e9minisme anti-Trump aux USA depuis 2017. La cause se trouve dans les positions de certaines des cr\u00e9ateurs et organisateurs de cette \u00ab\u00a0Marche\u00a0\u00bb annuelle, <strong>des Africains-Am\u00e9ricains proches de Louis Farrakhan, leader de <em>The Nation of Islam (NOI) <\/em><\/strong>et de l&rsquo;activisme musulman avec des racines d&rsquo;un \u00ab\u00a0nationalisme noir\u00a0\u00bb (Malcolm X) dans la communaut\u00e9 africaine-am\u00e9ricaine ; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Louis_Farrakhan\">Farrakhan<\/a> (grand ami de Kadhafi jusqu&rsquo;\u00e0 sa mort en 2011, entra&icirc;nant la rupture Farrakhan-Obama) est connu pour <strong>son hostilit\u00e9 affich\u00e9e \u00e0 Isra\u00ebl, identifi\u00e9 par ses adversaires comme de l&rsquo;antis\u00e9mitisme manifeste<\/strong>.<\/p>\n<\/p>\n<p><p>Ainsi observe-t-on une grave division aujourd&rsquo;hui expos\u00e9e en plein jour du f\u00e9minisme US, progressiste, multiculturaliste et antiraciste bien entendu, mais aussi truff\u00e9es de progressistes pro-Isra\u00ebl, veillant \u00e0 d\u00e9busquer tout ce qui pourrait se rapprocher de l&rsquo;antis\u00e9mitisme. Ainsi y a-t-il eu <a href=\"https:\/\/sputniknews.com\/us\/201901191071637808-women-march-celebrities-attendance\/\">diverses d\u00e9fections<\/a> importantes au sein du mouvement f\u00e9ministe pour la <em>Women&rsquo;s March<\/em>, dans divers hauts-lieux du genre, notamment \u00e0 Hollywood o&ugrave; l&rsquo;on a le cuir sensible sur le chapitre de la bonne conduite pro-isra\u00e9lienne. D&rsquo;autre part, plus de la moiti\u00e9 des 500 sponsors de la <em>Women&rsquo;s March <\/em>ont retir\u00e9 leur soutien, &ndash; autre signe de la puissance de l&rsquo;influence isra\u00e9lienne et des institutions et fortunes juives qui lui sont associ\u00e9es aux USA.<\/p>\n<\/p>\n<p><p>Hier, la <em>Women&rsquo;s March<\/em>, qui a tout de m\u00eame eu lieu, a \u00e9t\u00e9 marqu\u00e9 <a href=\"https:\/\/www.rt.com\/usa\/449215-laura-loomer-womens-march\/\">par un incident<\/a>, caus\u00e9 par une activiste de ce qu&rsquo;on nomme l&rsquo;<em>Alt-Right<\/em> (extr\u00eame-droite, tendance Bannon), <a href=\"https:\/\/en.wikipedia.org\/wiki\/Laura_Loomer\">Laura Loomer<\/a>, elle-m\u00eame juive et pro-isra\u00e9lienne, s&#8217;emparant du micro de l&rsquo;estrade officielle pour d\u00e9noncer une \u00ab\u00a0marche nazie\u00a0\u00bb. L&rsquo;incident a mis en \u00e9vidence la situation embarrassante de la manifestation et du mouvement f\u00e9ministe activiste actuellement aux USA, et la fa\u00e7on dont les adversaires politiques du mouvement peuvent en profiter.<\/p>\n<\/p>\n<p><p>Vendredi, avant la <em>Women&rsquo;s March<\/em>, l&rsquo;une des co-pr\u00e9sidentes du mouvement, l&rsquo;Africaine-Am\u00e9ricaine Tamilka Mallory, proche de Farrakhan, <strong>avait refus\u00e9 lors d&rsquo;une interview de reconna&icirc;tre le droit \u00e0 l&rsquo;existence sp\u00e9cifiquement d&rsquo;Isra\u00ebl<\/strong>, se contentant d&rsquo;affirmer que \u00ab\u00a0n&rsquo;importe qui a le droit d&rsquo;exister\u00a0\u00bb, et notamment les Palestiniens qui connaissent \u00ab\u00a0une tr\u00e8s grave crise\u00a0\u00bb. Un texte de <em><a href=\"https:\/\/www.breitbart.com\/podcast\/2019\/01\/18\/womens-march-co-chair-tamika-mallory-refuses-to-acknowledge-israels-right-to-exist\/\">Breitbart.com<\/a> <\/em>rapporte quelques d\u00e9tails de l&rsquo;interview par Margaret Hoover sur PBS  (\u00e9mission <em>Firing Line<\/em>), qui montre une Mallory extr\u00eamement camp\u00e9e sur sa position. <\/p>\n<\/p>\n<p><p>&laquo; <em>Pressed by host Margaret Hoover on whether she believes Israel has the right to exist, Mallory said, \u00ab\u00a0I have said many times that I feel everyone has a right to exist.\u00a0\u00bb \u00ab\u00a0I feel everyone has a right to exist. I just don&rsquo;t feel that anyone has a right to exist at the disposal of another group,\u00a0\u00bb she added.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0In your view, does that include Israelis in Israel?\u00a0\u00bb Hoover followed up.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0I believe that all people have the right to exist and that Palestinians are also suffering with a great crisis, and that there are other Jewish scholars who will sit here and say the same,\u00a0\u00bb an annoyed Mallory replied, before ordering Hoover to \u00ab\u00a0move on\u00a0\u00bb from her question.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Hoover, expressing dissatisfaction with Mallory&rsquo;s dodging of the question, noted that \u00ab\u00a0scholarly knowledge\u00a0\u00bb isn&rsquo;t required to understand Israel&rsquo;s right to exist. <\/em><em>\u00ab\u00a0Again, I believe everyone has the right to exist,\u00a0\u00bb the Women&rsquo;s March co-leader shot back<\/em>&hellip; &raquo;<\/p>\n<\/p>\n<p><p>Cette s\u00e9quence de l&rsquo;affaire a commenc\u00e9 \u00e0 la suite d&rsquo;une interview de Louis Farrakhan lundi dans le m\u00e9dia <em>The View<\/em>. Mallory a d\u00e9fendu certaines d\u00e9clarations de Farrakhan jug\u00e9es racistes et antis\u00e9mites, ce qui a conduit \u00e0 la crise actuelle. Sur cette question et sur Farrakhan, Mallory a r\u00e9pondu lors de l&rsquo;interview de vendredi : &laquo; <em>\u00ab\u00a0I didn&rsquo;t call him <\/em>[Farrakhan] <em>the greatest of all time because of his rhetoric. I called him the greatest of all time because of what he&rsquo;s done in black communities,\u00a0\u00bb the embattled organizer replied when asked about her describing Farrakhan as the \u00ab\u00a0GOAT,\u00a0\u00bb an acronym for the \u00ab\u00a0Greatest of all Time.\u00a0\u00bb <\/em>&raquo;<\/p>\n<\/p>\n<p><p>La fracture a \u00e9t\u00e9 marqu\u00e9e d&rsquo;une fa\u00e7on significative par une intervention de la parlementaire d\u00e9mocrate Debbie Wasserman Schultz retirant son soutien \u00e0 la <em>Women&rsquo;s March<\/em>. Wasserman Shultz a tous les arguments pour parler comme elle le fait : juive bien entendu, ancienne pr\u00e9sidente du parti d\u00e9mocrate, tr\u00e8s proche d&rsquo;Hillary Clinton, corrompue jusqu&rsquo;\u00e0 la moelle, etc. Elle se pose sans aucun doute en porte-parole de la faction pro-isra\u00e9lienne du mouvement f\u00e9ministe\/soci\u00e9tal-progressiste <strong>et son attaque est tr\u00e8s virulente, tr\u00e8s pr\u00e9cise et tranchante<\/strong> ; tout cela montre que l&rsquo;incident est extr\u00eamement grave et <strong>peut conduire \u00e0 une scission de type politique du puissant mouvement f\u00e9ministe US<\/strong>.<\/p>\n<\/p>\n<p><p>On notera dans l&rsquo;argumentaire de Wasserman Schultz des arguments qui, derri\u00e8re leur aspect pol\u00e9mique, tendent \u00e0 rejeter l&rsquo;autre fraction, repr\u00e9sentant essentiellement les minorit\u00e9s de couleur par leur proximit\u00e9 de Farrakhan, vers le camp anti-globaliste des populistes (&laquo; <em>Avec l&rsquo;antis\u00e9mitisme et le nationalisme blanc en plein d\u00e9veloppement aux USA et globalement, <\/em>[leur proximit\u00e9 de] <em>Louis Farrakhan est extr\u00eamement pr\u00e9occupante <\/em>&raquo;). <\/p>\n<\/p>\n<p><p>&laquo; <em>In a Friday opinion-editorial, Rep. Debbie Wasserman Schultz (D-FL) <\/em><em><a href=\"https:\/\/www.breitbart.com\/politics\/2019\/01\/18\/debbie-wasserman-schultz-cuts-ties-with-womens-march-over-anti-semitism\/\">announced<\/a><\/em><em>that she can no longer support the Women&rsquo;s March on Washington due to its leadership&rsquo;s refusal to \u00ab\u00a0repudiate anti-Semitism and all forms of bigotry.\u00a0\u00bb \u00ab\u00a0I am not alone,\u00a0\u00bb the Florida Democrat wrote in USA Today of her disassociation from the group. \u00ab\u00a0Teresa Shook, who <\/em><em><a href=\"https:\/\/www.washingtonpost.com\/news\/local\/wp\/2017\/01\/31\/the-woman-who-started-the-womens-march-with-a-facebook-post-reflects-it-was-mind-boggling\/?utm_term=.d6b0ddfcff6b\" target=\"_blank\">launched<\/a><\/em><em>the movement with her viral Facebook post, has <\/em><em><a href=\"https:\/\/redirect.viglink.com\/?format=go&#038;jsonp=vglnk_15477405670109&#038;key=0de604de366e10157cd309534403dfb2&#038;libId=jr0srsfz0101k4gd000DLbj0oqwdq&#038;loc=https%3A%2F%2Fwww.thedailybeast.com%2Fa-record-number-of-women-were-just-elected-but-the-womens-march-is-imploding&#038;v=1&#038;out=https%3A%2F%2Fwww.facebook.com%2FTeresaShookOfficial%2Fposts%2F2368957223146495&#038;ref=https%3A%2F%2Fwww.google.com%2F&#038;title=A%20Record%20Number%20of%20Women%20Were%20Just%20Elected%2C%20but%20the%20Women%E2%80%99s%20March%20Is%20Imploding&#038;txt=Facebook%20post\" target=\"_blank\">publicly called<\/a><\/em><em>for the co-chairs to resign, writing that Bob Bland, Linda Sarsour, Carmen Perez and Tamika Mallory &lsquo;have allowed anti-Semitism, anti-LBGTQIA sentiment and hateful, racist rhetoric to become a part of the platform&rsquo; of the march.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>\u00ab\u00a0Since that first march, I witnessed a disturbing spike in hatred aimed at Jewish homes, schools and synagogues in my own community. And with anti-Semitism and white nationalism apparently on the upswing in America and globally, the <a href=\"https:\/\/www.jpost.com\/American-Politics\/Womens-March-leaders-refuse-to-condemn-Farrakhan-after-antisemitic-speech-544074\" target=\"_blank\">associations<\/a><\/em><em>that Sarsour, Perez and Mallory have had with Nation of Islam (NOI) leader Louis Farrakhan have been most troubling,\u00a0\u00bb she <a href=\"https:\/\/www.breitbart.com\/politics\/2019\/01\/18\/debbie-wasserman-schultz-cuts-ties-with-womens-march-over-anti-semitism\/\">continued<\/a>. <\/em>&raquo;<\/p>\n<\/p>\n<p><p>Cette affaire est presque une crise au c&oelig;ur de l&rsquo;alliance entre les minorit\u00e9s de couleur et les LGTBQ (auxquels ces minorit\u00e9s avaient \u00e9t\u00e9 incorpor\u00e9es) qui forment le front essentiel de l&rsquo;opposition anti-Trump et les troupes de combat du parti d\u00e9mocrate pour conqu\u00e9rir une majorit\u00e9 \u00e9lectorale puissante pour les d\u00e9cennies \u00e0 venir. C&rsquo;est un enjeu extr\u00eamement puissant, qui fait s&rsquo;interroger sur la solidit\u00e9 de la reconversion de ce qu&rsquo;on nomma <em><a href=\"https:\/\/en.wikipedia.org\/wiki\/Rainbow_Coalition_(Fred_Hampton)\">The Rainbow Coalition<\/a> <\/em>dans les ann\u00e9es 1970, assemblant des groupes de minorit\u00e9s de couleur, des groupes socialisants de gauche, avec un soutien actif d&rsquo;organisations progressistes juives.<\/p>\n<\/p>\n<blockquote>\n<p><p>L&rsquo;arc en ciel devint l&rsquo;insigne \u00e9galement des LGBTQ et l&rsquo;association entre les deux, &ndash; les minorit\u00e9s de couleur et les mouvements soci\u00e9taux, &ndash; semblait au d\u00e9part prometteuse. Aujourd&rsquo;hui appara&icirc;t <strong>la possibilit\u00e9 d&rsquo;une fracture grave qui, d\u00e9laissant le simple aspect soci\u00e9tal, d\u00e9bouche sur l&rsquo;aspect politique fondamental<\/strong>. En effet, derri\u00e8re un affrontement caract\u00e9ris\u00e9e par l&rsquo;argument de l&rsquo;opposition \u00e0 l&rsquo;antis\u00e9mitisme pour les uns, par l&rsquo;argument de la d\u00e9nonciation de la politique d&rsquo;Isra\u00ebl pour les autres, <strong>se profilent des positions plus larges, &ndash; pour ou contre la <a href=\"http:\/\/www.dedefensa.org\/article\/glossairedde-politiquesysteme-ii\">politiqueSyst\u00e8me<\/a> belliciste et imp\u00e9rialiste <\/strong>soutenue par l&rsquo;<em>establishment <\/em>washingtonien, mais particuli\u00e8rement par les d\u00e9mocrates.<\/p>\n<\/p>\n<\/blockquote>\n<p><p>C&rsquo;est l\u00e0 qu&rsquo;intervient l&rsquo;engagement pour <strong>les pr\u00e9sidentielles de 2020 <a href=\"http:\/\/www.dedefensa.org\/article\/gabbard-2020-dc-la-folle-devient-fou\">de Tulsi Gabbard<\/a><\/strong>&#8230;<\/p>\n<\/p>\n<p><p>Dans un article <a href=\"https:\/\/tomluongo.me\/2019\/01\/18\/pelosi-fiddles-while-the-democrats-burn\/\">du 18 janvier<\/a>, Tom Luongo examine l&rsquo;affrontement entre la <em>Speaker <\/em>de la Chambre Pelosi et Trump, \u00e0 propos du \u00ab\u00a0Mur\u00a0\u00bb sur la fronti\u00e8re mexicaine, et du <em>shutdown <\/em>du gouvernement qui a suivi le refus de la Chambre de financer ce Mur. Pelosi, \u00e0 pr\u00e8s de 80 ans, repr\u00e9sente la structure ossifi\u00e9e du parti d\u00e9mocrate qui a cru retrouver sa jeunesse et sa verdeur avec les LGTBQ. Dans la bataille qu&rsquo;elle a engag\u00e9e contre Trump, avec l&rsquo;objectif de le faire perdre en 2020, sinon de le faire tomber avant, <strong>Pelosi a \u00e9pous\u00e9 \u00e0 fond tous les aspects de la politiqueSyst\u00e8me, belliciste, etc.,<\/strong>et son maximalisme se retrouve peut-\u00eatre dans l&rsquo;affrontement en train d&rsquo;appara&icirc;tre dans le rassemblement LGTBQ-\u00e9largi qui craque \u00e9ventuellement \u00e0 cause d&rsquo;Isra\u00ebl, donc aussi \u00e0 cause de la politiqueSyst\u00e8me que m\u00e8ne ce pays avec l&rsquo;accord sinon, l&rsquo;exhortation du <em>DeepState de Washington <\/em>; mais son maximalisme, dans le sens contraire, au sein d&rsquo;un parti d\u00e9mocrate en lambeaux, pousse \u00e0 des rebellions&#8230; <strong><em>Enter Tulsi<\/em><\/strong><em>.<\/em><\/p>\n<\/p>\n<p><p>&laquo; <em>As I said, appearance of strength is all that matters in politics at this level. <\/em><em>Pelosi cannot afford to look at all weak during a government shutdown she started to oppose Trump and regain the White House in 2020. So, while Pelosi is focused on being the establishment&rsquo;s mouthpiece for taking down Trump to regain control over the vast government machinery, rebellions are happening within her own party.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Enter Tulsi Gabbard. Gabbard has real promise as the anti-war\/anti-empire insurrectionist within the Democrats. <\/em><em>She is a leftist version of Ron Paul in that she&rsquo;s hated by everyone who thinks they are someone.<\/em><em>Because nothing unites the DNC and the RNC like the threat of peace getting an audience on the national stage.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>When \u00ab\u00a0anti-incumbent\u00a0\u00bb is the watchword of the day, Gabbard throwing her hat into the 2020 Presidential race is a big deal. <\/em><em>Gabbard will get support from anti-war Republicans, Independents and Libertarians. They will cross party lines to vote for her in primaries, hurting the anointed ones.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>She will successfully fund-raise on ending useless and counter-productive engagements in the Middle East. With her part of the Presidential conversation it forces her opposition to adopt her positions while simultaneously supporting Trump&rsquo;s struggle against his own staff<\/em>. [&#8230;] <em>She&rsquo;s everything the current Democratic party isn&rsquo;t: attractive, conscientious, brave and committed to peace<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Luongo, qui identifie justement en Gabbard \u00ab\u00a0un Ron Paul de gauche\u00a0\u00bb, pense qu&rsquo;elle aura le soutien des r\u00e9publicains anti-guerre, des ind\u00e9pendants et des libertariens&#8230; Et pourquoi n&rsquo;aurait-elle pas le soutien de la faction des LGTBQ-\u00e9largis, &ndash; les minorit\u00e9s de couleur, &ndash; qui est en train d&rsquo;appara&icirc;tre comme proche de Farrakhan jusqu&rsquo;\u00e0 \u00e9pouser les th\u00e8ses anti-isra\u00e9liennes de <em>The Nation Of Islam<\/em>, lesquelles reviennent objectivement \u00e0 s&rsquo;opposer \u00e0 la politiqueSyst\u00e8me et donc \u00e0 <strong>se trouver \u00e9ventuellement \u00e0 l&rsquo;aise avec une \u00ab\u00a0candidate de la paix\u00a0\u00bb, &ndash; qui plus est une femme, dite \u00ab\u00a0de gauche\u00a0\u00bb venue d&rsquo;une minorit\u00e9<\/strong> ? Les Africains-Am\u00e9ricains, quant \u00e0 eux, ne feraient que <strong>renouer avec la politique sur la fin de sa vie de l&rsquo;ic\u00f4ne Martin Luther King<\/strong>, si souvent d\u00e9form\u00e9e par le Syst\u00e8me pour les besoins de la cause, lorsque, &ndash; et sans doute est-ce l\u00e0 la raison de son \u00e9limination d&rsquo;avril 1968, &ndash; il s&rsquo;opposa avec une virulence extr\u00eame \u00e0 la guerre du Vietnam, au syst\u00e8me du complexe militaro-industriel, etc., bref \u00e0 la politiqueSyst\u00e8me d\u00e9j\u00e0 en cours&#8230;<\/p>\n<\/p>\n<p><p>Mis en ligne le 20 janvier 2019 \u00e0 15H45 <\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Des LGTBQ \u00e0 Gabbard, une f\u00e9conde agitation On a vu hier, avec le cas de Chris Hedges face \u00e0 Barnum-Trump, les contradictions consid\u00e9rables de la gauche qui s&rsquo;affiche antiSyst\u00e8me, par rapport aux activit\u00e9s et aux choix du Syst\u00e8me. (Le cas de Hedges est celui des USA mais le processus est largement partag\u00e9, &ndash; globalisation oblige,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3334,2631,17392,3837,2750,3186,2774,3581,5649,18817,18819,3140,6140,3310,8124,18816,4387,2832,13580,18818],"class_list":["post-78422","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisemitisme","tag-de","tag-farrakhan","tag-feminisme","tag-gabbard","tag-gauche","tag-israel","tag-louis","tag-luongo","tag-mallory","tag-march","tag-paul","tag-pelosi","tag-ron","tag-schultz","tag-tamilka","tag-tony","tag-tulsi","tag-wasserman","tag-womens"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78422"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78422\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}