{"id":78440,"date":"2019-01-28T16:55:35","date_gmt":"2019-01-28T16:55:35","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/01\/28\/rien-ni-davos-nechappent-a-la-crise\/"},"modified":"2019-01-28T16:55:35","modified_gmt":"2019-01-28T16:55:35","slug":"rien-ni-davos-nechappent-a-la-crise","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/01\/28\/rien-ni-davos-nechappent-a-la-crise\/","title":{"rendered":"Rien ni Davos n&rsquo;\u00e9chappent \u00e0 la crise"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepgreen\" style=\"color:#75714d; font-size:1.65em; font-variant:small-caps\">Rien ni Davos n&rsquo;\u00e9chappent \u00e0 la crise<\/h2>\n<\/p>\n<p><p>Ce texte (avec ses annexes) nous a paru int\u00e9ressant parce qu&rsquo;il aborde deux situations diff\u00e9rentes, mais simplement et tr\u00e8s largement pour renforcer notre perception de l&rsquo;universalit\u00e9 de la crise, et pour observer la similitude des composants. Il y est question de la grande rencontre annuelle quasiment en-cours (sans nous) de Davos, en Suisse, d&rsquo;une part ; et, d&rsquo;autre part, comme compl\u00e9ment, de la situation en Suisse. Il s&rsquo;agit d&rsquo;une approche \u00e9conomique, mais on se trouve n\u00e9cessairement entra&icirc;n\u00e9 dans les domaines politiques et plus g\u00e9n\u00e9raux, avec tous les \u00e9l\u00e9ments de la Grande Crise d&rsquo;Effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>On observe trois th\u00e8mes de r\u00e9flexion, ou de simples constats retir\u00e9s aussi bien des rencontres fastueuses de Davos que de la situation suisse, qui rejoignent ce que nous voyons r\u00e9guli\u00e8rement dans toutes les situations que nous abordons :<\/p>\n<\/p>\n<p><p>&bull; La n\u00e9cessit\u00e9 de poursuivre ou de retrouver (retrouver plut\u00f4t, avec nos meilleurs v&oelig;ux) une forte croissance et l&rsquo;\u00e9vidence que cette croissance se paie d&rsquo;une destruction acc\u00e9l\u00e9r\u00e9e de l&rsquo;environnement. A Davos, on veut les deux : une forte croissance, une formidable d\u00e9fense de l&rsquo;environnement ; et l&rsquo;on a le contraire : une croissance faiblarde et l&rsquo;acc\u00e9l\u00e9ration de la destruction de l&rsquo;environnement.<\/p>\n<\/p>\n<p><p>(&hellip; Pour autant, l&rsquo;enthousiasme ne manque pas \u00e0 Davos pour des \u00ab\u00a0vedettes m\u00e9diatiques\u00a0\u00bb de lutte contre la destruction de l&rsquo;environnement, dans tous les cas de faire savoir qu&rsquo;on y croit dans ce festival du simulacre, et de montrer qu&rsquo;on semble si acif ; cela permet aux Lagarde &#038; Cie en mission permanente depuis pr\u00e8s d&rsquo;un si\u00e8cle de <em>damage control <\/em>de se faire voir en compagnie d&rsquo;une jeune Su\u00e9doise qui est \u00e0 Davos avec sa pancarte contre la destruction de l&rsquo;environnement et qui est acclam\u00e9e par tous ceux qui en portent la responsabilit\u00e9 : &laquo; <em>Greta Thunberg, \u00e2g\u00e9e de 16 ans, est instrumentalis\u00e9e par les m\u00e9dias de complaisance comme \u00ab\u00a0vedette de Davos\u00a0\u00bb pour son engagement politique concernant le r\u00e9chauffement climatique. Cela rappelle les cas historiques de sacrifices d&rsquo;enfants pour une cause religieuse, estime Wolfgang Prabel, politicien de l&rsquo;Alternative pour l&rsquo;Allemagne, sur <a href=\"http:\/\/www.prabelsblog.de\/2019\/01\/eine-kranke-wird-verheizt\/\">son site internet<\/a><\/em>. [Traduction <a href=\"https:\/\/lesobservateurs.ch\/2019\/01\/27\/greta-thunberg-laissez-cette-jeune-fille-en-paix-debut-de-demystification\/\">en fran\u00e7ais<\/a>.]&raquo;)<\/p>\n<\/p>\n<p><p>&bull; Un deuxi\u00e8me th\u00e8me que l&rsquo;on trouve de plus en plus r\u00e9pandu comme nous l&rsquo;avons d\u00e9j\u00e0 not\u00e9, c&rsquo;est l&rsquo;explication <a href=\"http:\/\/www.dedefensa.org\/article\/extra-ordinaire-folie-ordinaire\">de la folie<\/a> des dirigeants Syst\u00e8me, au lieu des habituelles descriptions de complots, d&rsquo;entreprises concert\u00e9es, etc. (Notons bien que le terme \u00ab\u00a0folie\u00a0\u00bb est pris dans un sens g\u00e9n\u00e9ral, et certainement pas dans un sens m\u00e9dical o&ugrave; il n&rsquo;a pas sa place ; nous avons d\u00e9j\u00e0 indiqu\u00e9 dans le texte r\u00e9f\u00e9renc\u00e9 que l&rsquo;image de la \u00ab\u00a0folie\u00a0\u00bb est employ\u00e9e, pour notre cas, pour indiquer essentiellement le comportement maniaco-d\u00e9pressif.)<\/p>\n<\/p>\n<p><p>&bull; Un troisi\u00e8me th\u00e8me est le rejet du souverainisme (surtout) et du populisme. L&rsquo;auteur montre bien que seul le souverainisme peut permettre de retrouver l&rsquo;\u00e9quilibre, qui est un param\u00e8tre aussi important, sinon plus, que la croissance. C&rsquo;est rejeter l&rsquo;aspect quantitatif pour le qualitatif, et s&rsquo;orienter vers la trinit\u00e9 principielle que nous recommandons (ordre, harmonie, \u00e9quilibre)&hellip; &laquo; <em>Une croissance qui ne respecte pas l&rsquo;\u00e9quilibre est une mauvaise croissance. Et \u00e7a c&rsquo;est une loi de la nature, un principe premier et incontournable de toute philosophie des syst\u00e8mes.  Tout syst\u00e8me, tout \u00e9l\u00e9ment organis\u00e9, que ce soit une chaudi\u00e8re ou un corps humain a besoin d&rsquo;\u00e9quilibre, et poss\u00e8de pour cette raison un moyen de r\u00e9guler ses \u00e9quilibres internes ; sans soupape de s&ucirc;ret\u00e9 une chaudi\u00e8re est vou\u00e9e \u00e0 sa perte, de m\u00eame qu&rsquo;un corps humain qui n&rsquo;aurait pas de syst\u00e8mes pour r\u00e9guler sa temp\u00e9rature, sa pression sanguine, et ainsi de suite, selon le principe de l&rsquo;hom\u00e9ostasie, et il en va exactement de m\u00eame avec les corps \u00e9conomiques<\/em>. &raquo;<\/p>\n<\/p>\n<p><p>Nous avons un tableau de la Suisse qui montre que ce pays, que l&rsquo;on juge en g\u00e9n\u00e9ral comme \u00ab\u00a0en-dehors du monde\u00a0\u00bb et prot\u00e9g\u00e9 en quelque sorte, ne l&rsquo;est pas tant que \u00e7a. La Suisse est bien dans le monde et dans notre monde&hellip; Nul n&rsquo;\u00e9chappe \u00e0 la crise, bien entendu, et la Suisse en souffre come les autres. Le Syst\u00e8me r\u00e8gne, <em>Delenda Est Systemum.<\/em><\/p>\n<\/p>\n<p><p>Le texte de Michel Piccand est publi\u00e9 ce <a href=\"https:\/\/lesobservateurs.ch\/2019\/01\/27\/greta-thunberg-les-contradictions-insurmontables-de-davos\/\">26 janvier 2019<\/a> sur l&rsquo;excellent site suisse <em><a href=\"https:\/\/lesobservateurs.ch\/\">LesObservateurs.ch<\/a><\/em>.<\/p>\n<\/p>\n<p><h4><em>dde.org<\/em><\/h4>\n<\/p>\n<p><p>_________________________<\/p>\n<\/p>\n<\/p>\n<p><h2 class=\"titleset_a.deepgreen\" style=\"color:#75714d; font-size:2em\">Davos, contradictions insurmontables <\/h2>\n<\/p>\n<p><p>La pr\u00e9sence \u00e0 Davos de la jeune activiste \u00e9cologiste su\u00e9doise, Greta Thunberg, aura eu le m\u00e9rite de mettre en lumi\u00e8re les contradictions insurmontables de la pens\u00e9e politique dominante du monde actuel. Trois tendances majeures sont ressorties des d\u00e9clarations de tous bords. 1) La croissance \u00e9conomique est en train de dangereusement s&rsquo;affaiblir. 2) La consommation doit \u00eatre imm\u00e9diatement r\u00e9duite pour pr\u00e9server le climat. 3) Le plus grand danger politique actuel est le populisme et les souverainistes.<\/p>\n<\/p>\n<p><p>Pas besoin d&rsquo;\u00eatre un g\u00e9nie pour comprendre que la proposition num\u00e9ro 1 est en contradiction majeure avec la num\u00e9ro 2. On ne peut pas se battre pour soutenir la croissance \u00e0 tout prix et demander en m\u00eame temps de r\u00e9duire la consommation. C&rsquo;est parfaitement antinomique dans la situation actuelle. Ainsi lorsque la directrice du FMI Christine Lagarde croise Greta Thunberg \u00e0 Davos et lui dit son admiration pour ce que fait la jeune Su\u00e9doise c&rsquo;est une pure posture davosienne, tout le monde aime tout le monde (sauf les souverainistes) et se serre la main \u00e0 Davos, pour \u00eatre vu devant les t\u00e9l\u00e9visions du monde entier.<\/p>\n<\/p>\n<p><p>Ce qu&rsquo;il faut retenir de Davos c&rsquo;est que la pens\u00e9e g\u00e9n\u00e9rale est devenue litt\u00e9ralement schizophr\u00e9nique (coup\u00e9e en deux) et les pens\u00e9es partisanes compl\u00e8tement min\u00e9es par des processus mentaux de  refoulement. Les Verts portent en \u00e9g\u00e9rie la petite Greta, mais ne disent rien de ce qui se passerait si l&rsquo;on arr\u00eate imm\u00e9diatement et de mani\u00e8re drastique toute \u00e9mission de co2, dont les cons\u00e9quences seraient un effondrement brutal de toutes nos \u00e9conomies, le chaos voir la guerre avec de par le monde les pertes d&#8217;emploi de centaines de millions de personnes, des entreprises et des Etats qui seraient accul\u00e9s \u00e0 la banqueroute.<\/p>\n<\/p>\n<p><p>Le FMI lagardien et n\u00e9o-lib\u00e9ral ne fait pas mieux en d\u00e9fendant un accroissement continuel et maximum de  la croissance mais en passant sous silence que tous les probl\u00e8mes \u00e9conomiques actuels sont pr\u00e9cis\u00e9ment le fruit de ce principe hallucinant de croissance perp\u00e9tuelle. Nous sommes ici dans un monde o&ugrave; le d\u00e9lire est roi, o&ugrave; toutes les parties, chacune \u00e0 leur tour,  ne veulent ni tout voir, ni tout dire, ni tout entendre, mais qui invraisemblablement s&rsquo;entendent pour faire du souverainisme le bouc \u00e9missaire, alors que ce sont eux les responsables de cette situation actuelle catastrophique. Et c&rsquo;est pourquoi il est important du point de vue helv\u00e9tique de remettre ici un tant soit peu les points sur les i.<\/p>\n<\/p>\n<p><p>Depuis la fin de la seconde guerre mondiale l&rsquo;\u00e9conomie plan\u00e9taire a produit plus de richesses qu&rsquo;\u00e0 nulle autre \u00e9poque de l&rsquo;histoire mais paradoxalement s&rsquo;est retrouv\u00e9e plus endett\u00e9e qu&rsquo;elle ne l&rsquo;avait jamais \u00e9t\u00e9. Comment imaginer que plus un homme travaille et s&rsquo;enrichit et plus il devienne endett\u00e9 ? Que plus il am\u00e9liore son cadre de vie et plus il le d\u00e9truit ? Difficile \u00e0 penser n&rsquo;est-ce pas ? Cette petite all\u00e9gorie pour montrer que toute croissance n&rsquo;est pas forc\u00e9ment bonne \u00e0 prendre et que la question est infiniment plus subtile qu&rsquo;il n&rsquo;y para&icirc;t.<\/p>\n<\/p>\n<p><p>La croissance est importante pour l&rsquo;homme mais la croissance n&rsquo;est qu&rsquo;un des param\u00e8tres, un autre \u00e9l\u00e9ment tout aussi important \u00e0 prendre en compte c&rsquo;est l&rsquo;\u00e9quilibre. Une croissance qui ne respecte pas l&rsquo;\u00e9quilibre est une mauvaise croissance. Et \u00e7a c&rsquo;est une loi de la nature, un principe premier et incontournable de toute philosophie des syst\u00e8mes.  Tout syst\u00e8me, tout \u00e9l\u00e9ment organis\u00e9, que ce soit une chaudi\u00e8re ou un corps humain a besoin d&rsquo;\u00e9quilibre, et poss\u00e8de pour cette raison un moyen de r\u00e9guler ses \u00e9quilibres internes ; sans soupape de s&ucirc;ret\u00e9 une chaudi\u00e8re est vou\u00e9e \u00e0 sa perte, de m\u00eame qu&rsquo;un corps humain qui n&rsquo;aurait pas de syst\u00e8mes pour r\u00e9guler sa temp\u00e9rature, sa pression sanguine, et ainsi de suite, selon le principe de l&rsquo;hom\u00e9ostasie, et il en va exactement de m\u00eame avec les corps \u00e9conomiques. Et c&rsquo;est bien ici en ce qui concerne les Verts et le n\u00e9o-lib\u00e9ralisme lagardien du FMI que le b\u00e2t blesse.<\/p>\n<\/p>\n<p><p>Car faut-il le rappeler, le principe premier du souverainisme en \u00e9conomie est pr\u00e9cis\u00e9ment de mettre  l&rsquo;accent sur l&rsquo;\u00e9quilibre avant la croissance. Que la pr\u00e9servation des \u00e9quilibres internes nationaux est au fondement de  l&rsquo;approche \u00e9conomique souverainiste. Que le principe de s&ucirc;ret\u00e9 et de pr\u00e9servation des \u00e9quilibres internes fut de toujours la premi\u00e8re pr\u00e9occupation de la Suisse, du moins jusqu&rsquo;\u00e0 ce changement de mod\u00e8le qui nous fut impos\u00e9 en 2002 par l&rsquo;introduction de la libre-circulation des personnes, et qui fit passer notre pays d&rsquo;un principe de croissance certes limit\u00e9e mais qualitative \u00e0 un principe de croissance quantitative sans frein dont chacun peut d\u00e9sormais mesurer les effets d\u00e9sastreux et la perte en qualit\u00e9 de vie.<\/p>\n<\/p>\n<p><p>Faut-il rappeler que ce sont les Verts et tous les supp\u00f4ts du n\u00e9o-lib\u00e9ralisme lagardien du FMI (PLR, PDC, PS) qui nous ont impos\u00e9 la suppression de notre principal syst\u00e8me de r\u00e9gulation interne, ce contingentement migratoire qui faisait pour nous office de soupape de s&ucirc;ret\u00e9, le moyen de r\u00e9gulation le plus efficace que nous avions trouv\u00e9 pour maintenir l&rsquo;\u00e9quilibre de notre d\u00e9mographie, de notre \u00e9conomie et de tout notre syst\u00e8me, y compris la production de nos d\u00e9chets. Faut-il rappeler que ce principal instrument de r\u00e9gulation qu&rsquo;est le contingentement migratoire nous est d\u00e9sormais confisqu\u00e9 par le viol de notre constitution et par le vol de nos votes du 9 f\u00e9vrier.<\/p>\n<\/p>\n<p><p>Il y a des jours o&ugrave; l&rsquo;on commence \u00e0 \u00eatre fatigu\u00e9 de tant de sornettes et de tant d&rsquo;idiotie, de tant d&rsquo;irresponsabilit\u00e9. Depuis 1848 le principe premier de la Suisse fut toujours d&rsquo;assurer son \u00e9quilibre et son ind\u00e9pendance sur le long terme, depuis toujours ce fut sa vertu, certes avec ses hauts et ses bas, mais avec une qualit\u00e9 certaine qui avait montr\u00e9 sa redoutable efficacit\u00e9. On se demande donc ce qui s&rsquo;est pass\u00e9 dans la t\u00eate de ces gens, ce qu&rsquo;ils ont \u00e9tudi\u00e9 ?<\/p>\n<\/p>\n<p><p>Il est constant dans la litt\u00e9rature \u00e9conomique qu&rsquo;on ne peut rapporter \u00e0 aucune loi certaine que la croissance puisse \u00eatre toujours continue, alors que l&rsquo;on peut \u00eatre certain qu&rsquo;il est prudent et judicieux de pr\u00e9server ses instruments d&rsquo;\u00e9quilibre, de pr\u00e9server des marges d&rsquo;\u00e9quilibre, autrement dit de pr\u00e9server \u00e0 la Suisse des marges pour absorber d&rsquo;\u00e9ventuels chocs dans le futur et donc une vraie capacit\u00e9 de r\u00e9silience. Ils ont tout jet\u00e9 avec la libre circulation des personnes en supprimant notre seule soupape de s&ucirc;ret\u00e9. C&rsquo;est tout simplement inconscient et ignoble.<\/p>\n<\/p>\n<p><p>Les Verts se sont rang\u00e9s derri\u00e8re leur nouvelle \u00e9g\u00e9rie su\u00e9doise mais le contenu de Davos est d\u00e9sesp\u00e9r\u00e9ment vide et ne servira \u00e0 rien, il n&rsquo;apporte aucune solution. Tous ces v&oelig;ux pieux n&rsquo;auront pas plus d&rsquo;effets que le sable qui roule au bord de l&rsquo;oc\u00e9an, tout simplement parce qu&rsquo;au-del\u00e0 des enfermements dogmatiques dans lesquels les uns et les autres se sont enferm\u00e9s, ils n&#8217;emp\u00eacheront jamais les r\u00e9alit\u00e9s premi\u00e8res de continuer d&rsquo;exister, et parmi celles-ci qu&rsquo;aucun syst\u00e8me quel qu&rsquo;il soit ne peut survivre sans \u00e9quilibre et sans instrument de r\u00e9gulation.<\/p>\n<\/p>\n<p><p>Ceux qui pr\u00e9tendent en Suisse nous apporter des solutions sont les m\u00eames que ceux qui nous ont impos\u00e9 une croissance imma&icirc;tris\u00e9e, les m\u00eames que ceux qui nous privent de notre principal instrument de r\u00e9gulation, les m\u00eames qui nous imposent de mani\u00e8re dogmatique que nos fronti\u00e8res seraient inutiles. Comme si les corps humains n&rsquo;avaient eux-m\u00eames pas de fronti\u00e8re avec l&rsquo;ext\u00e9rieur, comme si les chaudi\u00e8res \u00e9taient des \u00eatres immat\u00e9riels sans parois autour pour structurer leur fonctionnement. Ils nous expliquent que le monde est comme un grand bateau dans lequel tout probl\u00e8me de l&rsquo;un serait celui de l&rsquo;autre. Oui, sauf que tout navire a des portes de cloisonnement, pour emp\u00eacher qu&rsquo;une voie d&rsquo;eau dans un compartiment ne se r\u00e9pande dans toute la cale et fasse sombrer le b\u00e2timent. Sauf que toutes les constructions d&rsquo;importance ont aujourd&rsquo;hui des portes coupe-feu.<\/p>\n<\/p>\n<p><p>Il n&rsquo;y a plus rien \u00e0 attendre en Suisse de la bande des quatre (PLR, PDC, PS, Verts) de personnes qui de part et d&rsquo;autre refoulent une partie des probl\u00e8mes, pensent avec des id\u00e9aux na\u00effs et pr\u00e9con\u00e7us pour les uns, les autres avec des aveuglements conceptuels d\u00e9pass\u00e9s en \u00e9conomie et dont ils montrent aujourd&rsquo;hui la faillite et la vacuit\u00e9. Ensemble ils d\u00e9signent le souverainisme comme le bouc \u00e9missaire alors m\u00eame qu&rsquo;ils sont incapables de voir que les solutions qui s&rsquo;imposent naturellement par le bon sens dans le peuple, comme la consommation de produits locaux, sont en r\u00e9alit\u00e9 des solutions toutes droit inspir\u00e9es du nationalisme \u00e9conomique et du souverainisme et des principes d&rsquo;autarcie&hellip;<\/p>\n<\/p>\n<p><p>C&rsquo;est \u00e0 pleurer de b\u00eatise, et ici sans que l&rsquo;on ne puisse plus rien esp\u00e9rer de la bande des quatre, ils ont d\u00e9pass\u00e9 le stade o&ugrave; l&rsquo;on peut encore les prendre au s\u00e9rieux. Et \u00e7a ce n&rsquo;est plus un secret pour personne. Il suffit de regarder Gen\u00e8ve qui ne sait d\u00e9j\u00e0 plus o&ugrave; enterrer ses d\u00e9chets non incin\u00e9rables mais dont la majorit\u00e9 politique forme le v&oelig;u (Verts y compris) de faire venir encore 100&rsquo;000 habitants de plus dans la d\u00e9cennie qui arrive [1], de constater que de Sierre \u00e0 Gen\u00e8ve on cache le probl\u00e8me des m\u00e9taux lourds dans le lac [2],  pour conclure que celui qui ne comprend pas doit avoir un sacr\u00e9 probl\u00e8me mental.<\/p>\n<\/p>\n<p><p>Je propose que Davos et nos \u00e9minents politiciens et politiciennes de la bande des quatre figurent d\u00e9sormais dans le manuel international de diagnostic mental, on devrait s&ucirc;rement arriver \u00e0 leur trouver une entr\u00e9e. De m\u00eame pour tous ceux qui apr\u00e8s ce qui vient d&rsquo;\u00eatre dit pensent encore qu&rsquo;ils commettraient un crime irr\u00e9parable s&rsquo;ils \u00e9lisaient des souverainistes aux prochaines \u00e9lections. Parce qu&rsquo;\u00e0 un certain moment il faut peut-\u00eatre commencer \u00e0 ouvrir un peu les yeux. Dans sa libert\u00e9 il faut commencer \u00e0 choisir entre promettre des cancers d\u00e8s cinquante ans \u00e0 vos enfants et petits enfants ou apporter votre voix aux souverainistes qui sont les seuls \u00e0 vouloir et pouvoir r\u00e9introduire de l&rsquo;\u00e9quilibre dans notre pays.<\/p>\n<\/p>\n<p><p>Ce n&rsquo;est ni Greta, ni les Verts et leurs associ\u00e9s opportunistes de la bande des quatre qui r\u00e9introduiront les instruments de r\u00e9gulation de l&rsquo;\u00e9quilibre dans notre pays, car ce sont eux, le PLR, le PDC, le PS et les Verts qui vous les ont enlev\u00e9s, en violant toutes nos institutions.<\/p>\n<\/p>\n<p><p>Et \u00e7a, c&rsquo;est juste la r\u00e9alit\u00e9.<\/p>\n<\/p>\n<p><h4>Michel Piccand<\/h4>\n<\/p>\n<p><p>N.B. Les probl\u00e8mes pos\u00e9s par une croissance non ma&icirc;tris\u00e9e (d\u00e9s\u00e9quilibr\u00e9e) sont connus depuis plus de 50  ans. Le rapport sur les limites de la croissance connu sous le nom de &laquo; Rapport Meadows &raquo; a \u00e9t\u00e9 publi\u00e9 par le MIT en 1970 (voir sur <em><a href=\"https:\/\/fr.wikipedia.org\/wiki\/Les_Limites_%C3%A0_la_croissance\">Wikip\u00e9dia<\/a><\/em>). Quoique l&rsquo;on puisse penser de ce rapport il faudrait \u00eatre fou pour le rejeter sans autre consid\u00e9ration. La loi sur les rendements d\u00e9croissants sur laquelle le rapport notamment s&rsquo;appuie est une r\u00e9alit\u00e9 parfaitement connue, loi qui se traduit aussi par le ph\u00e9nom\u00e8ne dit de d\u00e9s\u00e9conomies d&rsquo;\u00e9chelle, soit en bref que la diminution du co&ucirc;t par unit\u00e9 (\u00e9conomie d&rsquo;\u00e9chelle) \u00e0 un moment s&rsquo;arr\u00eate voir m\u00eame peut s&rsquo;inverser et se traduire par des co&ucirc;ts suppl\u00e9mentaires et croissants, ph\u00e9nom\u00e8ne qui est exactement en train de se produire en Suisse et qui a \u00e9t\u00e9 induit par l&rsquo;augmentation d\u00e9mographique massive lib\u00e9r\u00e9e par la libre circulation des personnes, augmentation des co&ucirc;ts (financiers, sociaux et \u00e9cologiques) d\u00e9montr\u00e9e dans l&rsquo;essai &laquo; La croissance \u00e9conomique de la Suisse, un drame politique cach\u00e9 &raquo; et qui au mieux, \u00e0 terme, ne peut se traduire que par une croissance stationnaire extr\u00eamement co&ucirc;teuse qui <em>in fine<\/em> am\u00e8nera \u00e0 un appauvrissement g\u00e9n\u00e9ral de la Suisse et de sa population et dans des conditions \u00e9cologiques qu&rsquo;on n&rsquo;ose m\u00eame pas imaginer. En <a href=\"https:\/\/mouvement-9fevrier.org\/la-croissance-economique-de-la-suisse-un-drame-politique-cache\/?fbclid=IwAR3KC-uAsKUvGsd_umeXPm-snEI4TBy46DCQYA7WbBmMhp17oWY6vbNjk58\">lecture libre ici<\/a>.<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepgreen\" style=\"color:#75714d; font-size:1.25em\">Notes<\/h2>\n<\/p>\n<p><p>[1] Concept de l&rsquo;am\u00e9nagement cantonal. Plan directeur cantonal Gen\u00e8ve 2030 | Adopt\u00e9 par le Grand Conseil le 20 septembre 2013, p.5.<\/p>\n<\/p>\n<p><p>[2] Extrait d&rsquo;un article \u00e0 para&icirc;tre courant 2019. \u00ab\u00a0Contamination au mercure, le pdc et les pro-europ\u00e9ens impliqu\u00e9s. Non au syndrome de minamata.\u00a0\u00bb<\/p>\n<\/p>\n<p><p>En 1970 la CIPEL, Commission internationale pour la protection des eaux du L\u00e9man, mesurait la teneur en mercure dans les s\u00e9diments du Rh\u00f4ne, 400 ppb au Bouveret &#8211; soit 8 fois la teneur naturelle qui est de 50 ppb &#8211; 690 ppb \u00e0 Monthey, 1&rsquo;820 \u00e0 Gampel.<\/p>\n<\/p>\n<p><p>Dix ans plus tard en 1980 les taux avaient explos\u00e9s, 520 ppb au Bouveret, 1&rsquo;690 \u00e0 Monthey, 5&rsquo;180 \u00e0 Aproz et 25&rsquo;300 \u00e0 Gampel ! Oui 25&rsquo;300 ppb !<\/p>\n<\/p>\n<p><p>Il n&rsquo;y a ici pas besoin d&rsquo;avoir fait de longues \u00e9tudes pour comprendre qu&rsquo;en 1980 d\u00e9j\u00e0 il y avait un probl\u00e8me, que nous \u00e9tions face \u00e0 une contamination majeure, 25&rsquo;300 ppb \u00e0 Gampel c&rsquo;est plus de 500 fois le taux naturel.<\/p>\n<\/p>\n<p><p>On rappellera que le mercure est un des \u00e9l\u00e9ments les plus toxiques qui soit et que les effets de sa contamination ne se gu\u00e9rissent pas. Les professionnels faiblement expos\u00e9s mais de mani\u00e8re chronique peuvent d\u00e9j\u00e0 subir des atteintes irr\u00e9versibles \u00e0 leur syst\u00e8me nerveux. Des \u00e9tudes ont montr\u00e9 que les dentistes surexpos\u00e9s (les amalgames dentaires contiennent du mercure) pouvaient pr\u00e9senter jusqu&rsquo;\u00e0 3 fois plus de probl\u00e8mes de m\u00e9moire et 10 fois plus de maladies r\u00e9nales qu&rsquo;une population t\u00e9moin. Les contaminations plus \u00e9lev\u00e9es ou massives d\u00e9truisent litt\u00e9ralement la vie humaine, elles provoquent des malformations cong\u00e9nitales (syndrome de minamata) et des baisses de la f\u00e9condit\u00e9, de graves troubles gastriques et on en passe, certains pensent qu&rsquo;elle pourrait \u00eatre \u00e0 l&rsquo;origine de d\u00e9g\u00e9n\u00e9rescence comme la maladie d&rsquo;Alzheimer, \u00e0 l&rsquo;origine de syndromes de fatigue chronique, fibromyalgies, et tout ce que l&rsquo;on n&rsquo;a pas encore identifi\u00e9 comme des troubles de l&rsquo;humeur agressive ou suicidaires qui sont d\u00e9sormais suspect\u00e9s. Le mercure est un m\u00e9tal neurotoxique. Un neurotoxique permanent. Le mercure c&rsquo;est la mort du vivant. Un m\u00e9tal lourd d&rsquo;autant plus redoutable qu&rsquo;il peut passer de l&rsquo;eau \u00e0 la terre avant de passer dans la nourriture et l&rsquo;\u00eatre humain et ne cesse d&rsquo;\u00eatre un danger que lorsqu&rsquo;il est captur\u00e9 et confin\u00e9, d\u00e9finitivement isol\u00e9 et stock\u00e9.<\/p>\n<\/p>\n<p><p>En 1975 on trouvait au milieu du lac des brochets avec 1&rsquo;100 ppb ! La teneur moyenne en mercure des brochets dans le L\u00e9man \u00e9tait entre 5 et 10 fois sup\u00e9rieure \u00e0 celle du lac de Z\u00fcrich.<\/p>\n<\/p>\n<p><p>Personne ne peut garantir que ce mercure ne ressortira pas un jour \u00e0 Gen\u00e8ve et Lausanne, on dit qu&rsquo;il faut soixante ans \u00e0 une mol\u00e9cule d&rsquo;eau qui entre au Bouveret pour ressortir \u00e0 Gen\u00e8ve. Et que dit le PDC au bout du lac pendant ce temps-l\u00e0, il porte en \u00e9tendard le slogan \u00e9lectoral d&rsquo;une croissance &laquo; Que Du Bonheur &raquo;. C&rsquo;est ind\u00e9cent, c&rsquo;est litt\u00e9ralement obsc\u00e8ne. Pendant que des centaines de familles dans le Haut-Valais \u00e0 la source de la pollution vivent dans l&rsquo;angoisse avec une \u00e9p\u00e9e de Damocl\u00e8s sur leur t\u00eate. Nous ne voulons plus de ces partis qui ne cessent de s&rsquo;attribuer des m\u00e9rites avant les \u00e9lections et qui imposent l&rsquo;omerta sur leurs responsabilit\u00e9s. Nous ne voulons plus de leurs pratiques politiques. Cela doit maintenant s&rsquo;arr\u00eater. La main gauche qui dit qu&rsquo;elle ne sait pas ce que fait la main droite cela doit s&rsquo;arr\u00eater, la main du Valais c&rsquo;est la m\u00eame que la main de Gen\u00e8ve, c&rsquo;est le m\u00eame parti qui suit les m\u00eames politiques.<\/p>\n<\/p>\n<p><p>_____________<\/p>\n<\/p>\n<p><p>Comme d\u00e9j\u00e0 dit et redit, lorsque l&rsquo;homme m\u00e9prise les \u00e9quilibres il finit toujours par en payer le prix sous une forme ou sous une autre, que ces d\u00e9s\u00e9quilibres soient politiques, \u00e9conomiques, d\u00e9mographiques, \u00e9cologiques, sociaux, ou tout simplement biologiques. C&rsquo;est l\u00e0 une v\u00e9rit\u00e9 premi\u00e8re incontournable.<\/p>\n<\/p>\n<p><p>Donc stop \u00e0 la croissance \u00e9conomique et d\u00e9mographique immod\u00e9r\u00e9e dans notre pays. Oui, \u00e0 l&rsquo;\u00e9quilibre et \u00e0 la r\u00e9gulation.<\/p>\n<\/p>\n<p><p>Et \u00e7a, seuls les souverainistes ont la volont\u00e9 et la capacit\u00e9 de le mettre en place rapidement et aujourd&rsquo;hui, par la r\u00e9introduction de contingents migratoires, seul outil v\u00e9ritablement efficace pour contr\u00f4ler les \u00e9quilibres dans notre pays.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rien ni Davos n&rsquo;\u00e9chappent \u00e0 la crise Ce texte (avec ses annexes) nous a paru int\u00e9ressant parce qu&rsquo;il aborde deux situations diff\u00e9rentes, mais simplement et tr\u00e8s largement pour renforcer notre perception de l&rsquo;universalit\u00e9 de la crise, et pour observer la similitude des composants. Il y est question de la grande rencontre annuelle quasiment en-cours (sans&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[15428,3244,18842,4020,18844,3582,18843,6220],"class_list":["post-78440","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-croissance","tag-davos","tag-dirigeants-systeme","tag-folie","tag-lesobservateurs-ch","tag-michel","tag-piccand","tag-suisse"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78440"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78440\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}