{"id":78452,"date":"2019-02-05T10:30:33","date_gmt":"2019-02-05T10:30:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/05\/coup-detat-a-litalienne\/"},"modified":"2019-02-05T10:30:33","modified_gmt":"2019-02-05T10:30:33","slug":"coup-detat-a-litalienne","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2019\/02\/05\/coup-detat-a-litalienne\/","title":{"rendered":"Coup d&rsquo;\u00c9tat \u00e0 l&rsquo;italienne"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Coup d&rsquo;&Eacute;tat \u00e0 l&rsquo;italienne<\/h2>\n<\/p>\n<p><p>5 f\u00e9vrier 2019 &ndash; Les Italiens semblent avoir r\u00e9alis\u00e9 avec une certaine discr\u00e9tion, mais tout de m\u00eame en prenant garde de le faire savoir, <strong>un v\u00e9ritable \u00ab\u00a0coup d&rsquo;Etat\u00a0\u00bb au c&oelig;ur de cette forteresse de bureaucratie et de conformisme d&rsquo;une id\u00e9ologie radicalis\u00e9e qu&rsquo;est l&rsquo;Union Europ\u00e9enne<\/strong>. Il s&rsquo;agirait, dans le cadre de la crise v\u00e9n\u00e9zu\u00e9lienne, du blocage par une menace de veto annonc\u00e9 lors d&rsquo;une r\u00e9union des ministres des affaires \u00e9trang\u00e8res, contre une reconnaissance par l&rsquo;UE \u00ab\u00a0unanime\u00a0\u00bb du \u00ab\u00a0pr\u00e9sident par int\u00e9rim\u00a0\u00bb Juan Guaido \u00e0 la place du pr\u00e9sident Maduro.<\/p>\n<\/p>\n<p><p>Diverses indications sur la position italienne sp\u00e9cifique dans cette affaire ont \u00e9t\u00e9 donn\u00e9es hier 4 f\u00e9vrier \u00e0 l&rsquo;agence Reuters. Mais c&rsquo;est surtout RT.com qui est concern\u00e9, par des confidences venues directement d&rsquo;un des deux partis de la coalition populiste, le M5S (Mouvement 5 Etoiles), qui a manifestement voulu \u00eatre identifi\u00e9 comme tel dans les informations qu&rsquo;il a donn\u00e9es aux r\u00e9seau russe. Voici ce <a href=\"https:\/\/francais.rt.com\/international\/58770-italie-aurait-fait-capoter-declaration-ue-visant-reconnaitre-legitimite-guaido\">qu&rsquo;en dit RT.com<\/a> :<\/p>\n<\/p>\n<p><p>&laquo; <em>Rome a-t-il fait d\u00e9railler une d\u00e9claration de l&rsquo;Union europ\u00e9enne (UE), cens\u00e9e reconna&icirc;tre Juan Guaido comme dirigeant par int\u00e9rim du Venezuela si le pr\u00e9sident Nicolas Maduro n&rsquo;organisait pas des \u00e9lections pr\u00e9sidentielles anticip\u00e9es ? C&rsquo;est ce qu&rsquo;une source au sein du Mouvement 5 \u00e9toiles, parti dirig\u00e9 Luigi Di Maio, l&rsquo;un des deux vice-pr\u00e9sidents du Conseil des ministres et ministre du D\u00e9veloppement \u00e9conomique, du travail et des politiques sociales, <a href=\"https:\/\/www.rt.com\/news\/450594-source-italy-regects-guaido\/?utm_source=browser&#038;utm_medium=aplication_chrome&#038;utm_campaign=chrome\">a fait savoir \u00e0 RT<\/a>.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Selon cette m\u00eame source, l&rsquo;Italie aurait annonc\u00e9 son veto lors d&rsquo;une r\u00e9union informelle des ministres des Affaires \u00e9trang\u00e8res de l&rsquo;UE qui s&rsquo;est tenue le 31 janvier en Roumanie. A travers cette d\u00e9claration, qui devait \u00eatre prononc\u00e9e par le chef de la diplomatie europ\u00e9enne, Federica Mogherini, l&rsquo;UE reconnaissait Juan Guaido comme pr\u00e9sident par int\u00e9rim si des \u00e9lections pr\u00e9sidentielles anticip\u00e9es n&rsquo;\u00e9taient pas organis\u00e9es.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Ce 4 f\u00e9vrier, des sources diplomatiques ont affirm\u00e9 \u00e0 l&rsquo;agence de presse Reuters que l&rsquo;Italie s&rsquo;\u00e9tait oppos\u00e9e ce m\u00eame jour \u00e0 une d\u00e9claration commune de l&rsquo;Union europ\u00e9enne visant \u00e0 reconna&icirc;tre Juan Guaido comme \u00ab\u00a0pr\u00e9sident par int\u00e9rim\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Le Parlement europ\u00e9en a \u00e9t\u00e9 le premier organe europ\u00e9en <a href=\"https:\/\/francais.rt.com\/international\/58614-venezuela-parlement-europeen-reconnait-opposant-juan-guaido-president-legitime\">\u00e0 reconna&icirc;tre l&rsquo;opposant<\/a> \u00ab\u00a0en tant que seul pr\u00e9sident par int\u00e9rim l\u00e9gitime du pays jusqu&rsquo;\u00e0 ce que de nouvelles \u00e9lections pr\u00e9sidentielles libres, transparentes et cr\u00e9dibles puissent \u00eatre convoqu\u00e9es pour r\u00e9tablir la d\u00e9mocratie\u00a0\u00bb.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il avait exhort\u00e9 l&rsquo;UE \u00e0 faire de m\u00eame, mais ses efforts ont \u00e9t\u00e9 suspendus en raison de discordes internes. Ce 4 f\u00e9vrier, plusieurs pays europ\u00e9ens, dont le Royaume-Uni, la France, l&rsquo;Allemagne, l&rsquo;Espagne ou encore l&rsquo;Autriche ont finalement reconnu &ndash; s\u00e9par\u00e9ment &ndash; Juan Guaido en tant que pr\u00e9sident par int\u00e9rim (ou pr\u00e9sident \u00ab\u00a0<a href=\"https:\/\/francais.rt.com\/international\/58763-venezuela-royaume-uni-espagne-reconnaissent-juan-guaido-president-interim\">en charge<\/a>\u00a0\u00bb dans le cas de la France) du Venezuela<\/em>. &raquo; <\/p>\n<\/p>\n<p><p> Comme on le voit, il s&rsquo;agit d&rsquo;une affaire qui secoue notablement le monde transatlantique, avec notamment et sans v\u00e9ritable surprise l&rsquo;habituel rassemblement des pays europ\u00e9ens les plus marquants derri\u00e8re les USA, mais aussi <strong>avec l&rsquo;agr\u00e9able surprise de ce qui serait l&rsquo;attitude tr\u00e8s ind\u00e9pendante prise par le gouvernement italien<\/strong>. L&rsquo;\u00e9v\u00e9nement v\u00e9n\u00e9zu\u00e9lien d\u00e9passe donc tr\u00e8s largement le cadre r\u00e9gional et envoie une onde de choc dans tous les domaines des relations internationales, \u00e0 la suite de l&rsquo;initiative am\u00e9ricaniste imm\u00e9diate, <strong>ce que Wayne Madsen nomme (voir ci-apr\u00e8s) \u00ab\u00a0la boite de Pandore de Pompeo\u00a0\u00bb<\/strong>.<\/p>\n<\/p>\n<p><p>Bien entendu, personne parmi les grands moralistes de l&rsquo;UE ne s&rsquo;attarde sur l&rsquo;aspect totalement ill\u00e9gal, ill\u00e9gitime, faussaire, etc., de cette \u00ab\u00a0reconnaissance\u00a0\u00bb d&rsquo;un \u00ab\u00a0pr\u00e9sident par int\u00e9rim\u00a0\u00bb faite en pleine lumi\u00e8re, dans une atmosph\u00e8re d&rsquo;un cynisme consomm\u00e9 du genre dont le secr\u00e9taire d&rsquo;&Eacute;tat Pompeo semble avoir le secret. On imagine ce que pourraient \u00eatre les cons\u00e9quences d&rsquo;une telle pseudo-jurisprudence, l&rsquo;accentuation exponentiel du d\u00e9sordre que cela implique si l&rsquo;on devait consid\u00e9rer la chose comme une sorte de nouvelle \u00ab\u00a0l\u00e9galit\u00e9\u00a0\u00bb internationale.<\/p>\n<\/p>\n<p><p>Wayne Madsen donc, s&rsquo;y essaie&hellip; Madsen est un dissident antiSyst\u00e8me mais plut\u00f4t de gauche, et un adversaire sans concession de Trump malgr\u00e9 les aspects parfois\/souvent antiSyst\u00e8me de l&rsquo;action de Trump. Il imagine ce que <strong>pourraient devenir les affaires internationales \u00e0 partir de la rocambolesque, de l&rsquo;abracadabrantesque \u00ab\u00a0<a href=\"https:\/\/www.strategic-culture.org\/news\/2019\/02\/01\/pompeo-pandora-box.html\">jurisprudence Maduro-Guaido<\/a>\u00ab\u00a0<\/strong>, &ndash; laquelle, de plus, est affirm\u00e9e comme telle pr\u00e8s de neuf mois apr\u00e8s que Maduro ait \u00e9t\u00e9 r\u00e9\u00e9lu, comme si le monde si sensible du Droit International avait pu vivre dans l&rsquo;innocence et l&rsquo;inconscience avec ce cancer de l&rsquo;\u00e9pouvantable et scandaleuse \u00e9lection de Maduro fich\u00e9 en son flanc absolument vertueux&hellip; (Question de Lavrov : &laquo; <em>C&rsquo;est incroyable que l&rsquo;Union europ\u00e9enne marche de nouveau dans les pas des Etats-Unis et commence \u00e0 lancer des ultimatums, insistant sur le fait que la r\u00e9\u00e9lection du pr\u00e9sident Maduro pour un second mandat n&rsquo;ait pas \u00e9t\u00e9 l\u00e9gitime<\/em> [&#8230;] <em>Mais s&rsquo;ils affirment que l&rsquo;\u00e9lection n&rsquo;a pas \u00e9t\u00e9 l\u00e9gitime, <strong>pourquoi n&rsquo;ont-ils rien dit depuis mai 2018<\/strong><\/em><strong> <em>?<\/em><\/strong> &raquo;)<\/p>\n<\/p>\n<p><p>Voici un extrait du texte de Wayne Madsen : &laquo; <em>Pompeo a v\u00e9ritablement ouvert la \u00ab\u00a0bo&icirc;te de Pandore\u00a0\u00bb avec son initiative ouvrant le d\u00e9fil\u00e9 de reconnaissance internationale de Guaido comme nouveau pr\u00e9sident (\u00ab\u00a0par int\u00e9rim\u00a0\u00bb) du Venezuela, dans un acte de compl\u00e8te usurpation antid\u00e9mocratique du pouvoir. Qu&rsquo;il s&rsquo;agisse de la bo&icirc;te de Pandore de Pompeo ou de la \u00ab\u00a0doctrine Trump\u00a0\u00bb, ceux qui se pr\u00e9cipitent pour soutenir Guaido pourraient bien voir la situation se retourner contre eux. Bolsonaro, qui a \u00e9t\u00e9 \u00e9lu pr\u00e9sident du Br\u00e9sil uniquement parce que l&rsquo;ancien pr\u00e9sident Luiz Inacio Lula da Silva, beaucoup plus populaire, est toujours en prison \u00e0 la suite d&rsquo;un proc\u00e8s politique bas\u00e9 sur des accusations fabriqu\u00e9es de toutes pi\u00e8ces ; nombre de pays pourraient finalement estimer que Lula, bien qu&#8217;emprisonn\u00e9, est le pr\u00e9sident l\u00e9gitime du Br\u00e9sil, et le reconna&icirc;tre comme tel \u00e0 la place de Bolsonaro.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Il en va de m\u00eame pour le Colombien Duque, qui a remport\u00e9 son \u00e9lection en 2018 en raison de l&rsquo;intimidation des \u00e9lecteurs par des cartels de la drogue et de puissants oligarques. Le candidat de gauche d\u00e9fait, Gustavo Petro, pourrait \u00eatre reconnu comme pr\u00e9sident de la Colombie par d&rsquo;autres nations. Le pr\u00e9sident p\u00e9ruvien, Martin Vizcarra, n&rsquo;est devenu pr\u00e9sident qu&rsquo;apr\u00e8s la d\u00e9mission de celui dont il \u00e9tait le vice-pr\u00e9sident, Pedro Pablo Kuczynski, \u00e0 cause du scandale de corruption Odebrecht qui a secou\u00e9 toute l&rsquo;Am\u00e9rique latine. Vizcarra pourrait facilement \u00e0 son tour se voir contest\u00e9 comme pr\u00e9sident du P\u00e9rou, lui aussi \u00e9tant impliqu\u00e9 dans le scandale Odebrecht. Des nations du monde entier, d\u00e9go&ucirc;t\u00e9es qu&rsquo;un tel criminel soit install\u00e9 au palais pr\u00e9sidentiel \u00e0 Lima, pourraient se tourner vers le vice-pr\u00e9sident de Vizcarra, Mercedes Araoz.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Quant au pr\u00e9sident de l&rsquo;Argentine, Mauricio Macri, qui soutient Guaido, sa victoire \u00e0 l&rsquo;arrach\u00e9 et largement marqu\u00e9e d&rsquo;accusations de fraude de 2015 sur Daniel Scioli, pourrait \u00eatre contest\u00e9e par des nations progressistes, lui pr\u00e9f\u00e9rant finalement Scioli \u00e0 la pr\u00e9sidence de l&rsquo;Argentine. Et ainsi de suite pour nombre de dirigeants qui ont reconnu Guaido comme pr\u00e9sident du Venezuela. Peut-\u00eatre m\u00eame qu&rsquo;un groupe de nations pourrait annoncer qu&rsquo;elles ne traiteraient plus d\u00e9sormais qu&rsquo;avec le chef de l&rsquo;opposition travailliste Jeremy Corbyn comme Premier ministre britannique.<\/em><\/p>\n<\/p>\n<p><p>&raquo; <em>Et un groupe de pays pourrait toujours proclamer qu&rsquo;ils croient que Donald Trump a \u00e9t\u00e9 \u00e9lu ill\u00e9galement \u00e0 la pr\u00e9sidence des &Eacute;tats-Unis et annoncer qu&rsquo;ils reconnaissent Hillary Clinton en tant que pr\u00e9sidente par int\u00e9rim des &Eacute;tats-Unis. En effet, l&rsquo;ouverture de la bo&icirc;te de Pandore par Pompeo laisse entrevoir des possibilit\u00e9s int\u00e9ressantes<\/em>. &raquo;<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\"><em>Forza, Italia !<\/em><\/h3>\n<\/p>\n<p><p>On se doute qu&rsquo;il y a beaucoup de choses \u00e0 dire dans le domaine g\u00e9n\u00e9ral des relations internationales \u00e0 propos de cette affaire v\u00e9n\u00e9zu\u00e9lienne mais on se doute \u00e9galement que toutes ces choses nous ram\u00e8nent <strong>\u00e0 une seule observation, \u00e0 un seul constat, \u00e0 une conclusion sempiternelle<\/strong>, avec pour en faire la synth\u00e8se toujours le m\u00eame mot r\u00e9p\u00e9t\u00e9 et r\u00e9p\u00e9t\u00e9 pour <strong>caract\u00e9riser l&rsquo;\u00e9tat de ces relations : d\u00e9sordre, d\u00e9sordre, d\u00e9sordre<\/strong>&hellip;<\/p>\n<\/p>\n<p><p>Pourtant et pour autant, l&rsquo;\u00e9v\u00e9nement qui nous para&icirc;t le plus int\u00e9ressant, &ndash; tant il est vrai que le constat du d\u00e9sordre, fut-il rocambolesque et abracadabrantesque, ne parvient plus \u00e0 vraiment nous \u00e9mouvoir ni \u00e0 susciter un commentaire \u00e0 chaque fois d&rsquo;un int\u00e9r\u00eat extr\u00eame, &ndash; est bien <strong>le cas sp\u00e9cifique de cette attitude de l&rsquo;Italie dans les d\u00e9lib\u00e9rations de l&rsquo;UE<\/strong>. Il s&rsquo;agit l\u00e0 d&rsquo;un \u00e9v\u00e9nement important et, surtout, d&rsquo;un \u00e9v\u00e9nement nouveau.<\/p>\n<\/p>\n<p><p>L&rsquo;affaire v\u00e9n\u00e9zu\u00e9lienne, d\u00e8s lors que les USA ont \u00ab\u00a0reconnu\u00a0\u00bb un nouveau pr\u00e9sident \u00e0 la place du pr\u00e9sident l\u00e9gal, est devenue une affaire de c&oelig;ur et d&rsquo;\u00e2me pour l&rsquo;UE, quelque chose d&rsquo;essentiel. Elle est entr\u00e9e dans la confr\u00e9rie des grandes dynamiques transatlantiques, de la partie <strong>des non-dits imp\u00e9ratifs<\/strong>, qui caract\u00e9rise ce qu&rsquo;il y a de plus extraordinaire dans l&rsquo;alignement de l&rsquo;UE sur les USA. <strong>C&rsquo;est le domaine de la servilit\u00e9 comme raison d&rsquo;\u00eatre selon l&rsquo;UE, plut\u00f4t que la \u00ab\u00a0servilit\u00e9 volontaire\u00a0\u00bb<\/strong>, car la volont\u00e9 est une denr\u00e9e inconnue dans l&rsquo;UE &hellip; (S&rsquo;il faut des qualificatifs, on proposerait bien le duo \u00ab\u00a0servilit\u00e9 arrogante et besogneuse\u00a0\u00bb, &ndash; <strong>\u00ab\u00a0servilit\u00e9 arrogante\u00a0\u00bb pour Macron, \u00ab\u00a0servilit\u00e9 besogneuse\u00a0\u00bb pour Merkel<\/strong>.)`<\/p>\n<\/p>\n<p><p>Cela concerne ces grandes affaires sans queue ni t\u00eate, lanc\u00e9es \u00e0 partir de <em>narrative<\/em>, essentiellement sinon exclusivement par les USA devenus \u00ab\u00a0D.C.-la-folle\u00a0\u00bb, et que l&rsquo;UE se doit de suivre aveugl\u00e9ment, m\u00eame si c&rsquo;est contre son int\u00e9r\u00eat, et l&rsquo;on dirait m\u00eame : surtout si c&rsquo;est contre son int\u00e9r\u00eat. Les sanctions contre la Russie sont le meilleur exemple de cette sorte d&rsquo;activit\u00e9 parano-schizophr\u00e9nique et maniaco-d\u00e9pressive ; mais quoi, l&rsquo;UE doit suivre, et \u00e0 l&rsquo;unanimit\u00e9. Il y a parfois des grognements, mais tout le monde suit, d&rsquo;autant que les deux grands leaders France-Allemagne ont tout de suite d\u00e9clar\u00e9 <strong>qu&rsquo;ils d\u00e9fendaient une Europe ind\u00e9pendante et souveraine et que, pour cette raison, il fallait absolument suivre, yeux ferm\u00e9s et nez bouch\u00e9s, la trace des USA, fussent-ils les USA du ha\u00efssable Trump<\/strong>. La bureaucratie-UE fait le reste, charg\u00e9 de mettre des verrous partout o&ugrave; il se doit.<\/p>\n<\/p>\n<p><p>C&rsquo;est de cette sorte que l&rsquo;affaire v\u00e9n\u00e9zu\u00e9lienne \u00e9tait devenue en quelques jours, et donc tout devait aller comme sur des roulettes comme on en a d\u00e9crit le mod\u00e8le, avec une d\u00e9cision unanime de l&rsquo;UE pour adouber le nouveau pr\u00e9sident l\u00e9galement non-\u00e9lu et donc compl\u00e8tement ill\u00e9gitimement l\u00e9gitime. Pourtant, ce ne fut pas le cas, et la surprise dut \u00eatre aussi terrifiante qu&rsquo;une explosion nucl\u00e9aire ! L&rsquo;on mesure combien cette transgression du non-dit sacr\u00e9 et proam\u00e9ricaniste constituerait une r\u00e9volution copernicienne.<\/p>\n<\/p>\n<p><p>Les Italiens se seraient donc dress\u00e9s et auraient dit :  nous ne marchons pas et ne voulons pas d&rsquo;une position commune de l&rsquo;UE qui nous engagerait, et nous ferons usage si n\u00e9cessaire de notre droit de veto pour interdire cette position commune. <strong>Ce dut \u00eatre un beau tintamarre, car il y a tout lieu de croire que tout s&rsquo;est ainsi pass\u00e9<\/strong>, mais finalement l&rsquo;on c\u00e9da et l&rsquo;on abandonna l&rsquo;id\u00e9e d&rsquo;une reconnaissance de Guaido par l&rsquo;UE. Que ce soit le M5S qui ait fuit\u00e9 cette affaire sp\u00e9cifiquement vers RT.com n&rsquo;est pas exempt de signification. On peut interpr\u00e9ter les deux aspects tels qu&rsquo;ils nous ont \u00e9t\u00e9 restitu\u00e9s de cette fa\u00e7on :<\/p>\n<\/p>\n<p><p>&bull; Des deux composants du gouvernement populiste, l&rsquo;intervention de M5S serait logique dans la mesure o&ugrave; ce parti est \u00e0 gauche (la <em>Liga <\/em>\u00e0 droite), soit plus proche de Maduro et du bolivarisme v\u00e9n\u00e9zu\u00e9lien.<\/p>\n<\/p>\n<p><p>&bull; La fuite vers RT.com, l\u00e0 aussi de fa\u00e7on sp\u00e9cifique o&ugrave; la source s&rsquo;identifie elle-m\u00eame, constituerait un acte de d\u00e9fiance vis-\u00e0-vis de la presseSyst\u00e8me italienne et europ\u00e9enne et une reconnaissance du r\u00f4le de RT aupr\u00e8s des antiSyst\u00e8me, comme le seul r\u00e9seau \u00e0 grande diffusion qui ne soit pas sous le contr\u00f4le des forces oligarchiques au service du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>En fait de jurisprudence, celle que l&rsquo;Italie aurait impos\u00e9e au c&oelig;ur des r\u00e8gles non-\u00e9crites les plus sacr\u00e9es de l&rsquo;UE<strong>est d&rsquo;une immense importance, certainement plus importantes que l&rsquo;acte d\u00e9lictueux des USA par rapport au Venezuela<\/strong>. Elle ouvrirait une br\u00e8che dans une forteresse psychologique et bureaucratique qu&rsquo;on jugeait inexpugnable jusqu&rsquo;alors, sous l&rsquo;influence qu&rsquo;on jugeait \u00eatre de fer des Franco-Allemands. <strong>Tout cela est brusquement \u00e9branl\u00e9 jusqu&rsquo;au tr\u00e9fonds, et il s&rsquo;agirait bien d&rsquo;une sorte de coup d&rsquo;&Eacute;tat<\/strong>, &ndash; sans tambour ni trompette, que personne ne signalera, pour ceux qui s&rsquo;en sont aper\u00e7us, &ndash; mais pourtant bien plus important que nombre d&rsquo;affirmations bombastiques dont l&rsquo;UE est coutumi\u00e8re lorsqu&rsquo;il s&rsquo;agit des droits de l&rsquo;homme et de toute cette sorte de choses.<\/p>\n<\/p>\n<p><p>Bien entendu, nulle surprise que cela vienne du gouvernement populiste italien, que l&rsquo;UE et ses partisans ne cessent de maudire davantage chaque jour. <strong>L&rsquo;antagonisme entre la France et l&rsquo;Italie, d\u00e9j\u00e0 bien aliment\u00e9, n&rsquo;en sera que plus exacerb\u00e9<\/strong>. Ce qu&rsquo;on craignait de ce gouvernement populiste Italie, c&rsquo;\u00e9tait essentiellement des actions internes de la sorte qu&rsquo;il a jusqu&rsquo;ici d\u00e9velopp\u00e9es (rassemblement des populismes notamment). Par contre, l&rsquo;on n&rsquo;attendait gu\u00e8re d&rsquo;action de ce gouvernement sur la politique ext\u00e9rieure de l&rsquo;UE de strict alignement sur le Syst\u00e8me, via les USA et les r\u00e9flexes transatlantiques. <\/p>\n<\/p>\n<p><p><strong>Mauvaise surprise<\/strong>pour le Syst\u00e8me, caract\u00e9ristique d&rsquo;une \u00e9poque nouvelle.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coup d&rsquo;&Eacute;tat \u00e0 l&rsquo;italienne 5 f\u00e9vrier 2019 &ndash; Les Italiens semblent avoir r\u00e9alis\u00e9 avec une certaine discr\u00e9tion, mais tout de m\u00eame en prenant garde de le faire savoir, un v\u00e9ritable \u00ab\u00a0coup d&rsquo;Etat\u00a0\u00bb au c&oelig;ur de cette forteresse de bureaucratie et de conformisme d&rsquo;une id\u00e9ologie radicalis\u00e9e qu&rsquo;est l&rsquo;Union Europ\u00e9enne. Il s&rsquo;agirait, dans le cadre de la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[4609,2631,3870,18853,18851,11992,3029,2904,2609,3305,18852,6552],"class_list":["post-78452","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-bureaucratique","tag-de","tag-droit","tag-guaido","tag-interim","tag-maduro","tag-par","tag-president","tag-ue","tag-venezuela","tag-verrouillage","tag-veto"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=78452"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/78452\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=78452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=78452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=78452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}